{"id":4576,"date":"2026-04-27T13:57:09","date_gmt":"2026-04-27T13:57:09","guid":{"rendered":"https:\/\/estadimallorcasonmoix.es\/?page_id=4576"},"modified":"2026-07-06T07:39:28","modified_gmt":"2026-07-06T07:39:28","slug":"mallorca-son-moix-stadium","status":"publish","type":"page","link":"https:\/\/estadimallorcasonmoix.es\/en\/","title":{"rendered":"Mallorca Son Moix Stadium"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4576\" class=\"elementor elementor-4576 elementor-4574\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-41d74dc e-con-full e-flex e-con e-parent\" data-id=\"41d74dc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6a09a1b elementor-widget__width-initial elementor-widget elementor-widget-jet-listing-grid\" data-id=\"6a09a1b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns&quot;:&quot;1&quot;}\" data-widget_type=\"jet-listing-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-listing-grid jet-listing\"><div class=\"jet-listing-grid__slider\" data-slider_options=\"{&quot;autoplaySpeed&quot;:3000,&quot;autoplay&quot;:true,&quot;pauseOnHover&quot;:true,&quot;infinite&quot;:true,&quot;centerMode&quot;:false,&quot;speed&quot;:500,&quot;arrows&quot;:true,&quot;dots&quot;:true,&quot;slidesToScroll&quot;:1,&quot;prevArrow&quot;:&quot;\\u003Cdiv class=\\u0027jet-listing-grid__slider-icon prev-arrow \\u0027 role=\\u0027button\\u0027 aria-label=\\u0027Previous\\u0027\\u003E\\u003Csvg width=\\u0027180\\u0027 height=\\u0027180\\u0027 viewBox=\\u00270 0 180 180\\u0027 fill=\\u0027none\\u0027 xmlns=\\u0027http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\u0027\\u003E\\u003Cpath d=\\u0027M119 47.3166C119 48.185 118.668 48.9532 118.003 49.6212L78.8385 89L118.003 128.379C118.668 129.047 119 129.815 119 130.683C119 131.552 118.668 132.32 118.003 132.988L113.021 137.998C112.356 138.666 111.592 139 110.729 139C109.865 139 109.101 138.666 108.436 137.998L61.9966 91.3046C61.3322 90.6366 61 89.8684 61 89C61 88.1316 61.3322 87.3634 61.9966 86.6954L108.436 40.002C109.101 39.334 109.865 39 110.729 39C111.592 39 112.356 39.334 113.021 40.002L118.003 45.012C118.668 45.68 119 46.4482 119 47.3166Z\\u0027 fill=\\u0027black\\u0027\\\/\\u003E\\u003C\\\/svg\\u003E\\u003C\\\/div\\u003E&quot;,&quot;nextArrow&quot;:&quot;\\u003Cdiv class=\\u0027jet-listing-grid__slider-icon next-arrow \\u0027 role=\\u0027button\\u0027 aria-label=\\u0027Next\\u0027\\u003E\\u003Csvg width=\\u0027180\\u0027 height=\\u0027180\\u0027 viewBox=\\u00270 0 180 180\\u0027 fill=\\u0027none\\u0027 xmlns=\\u0027http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\u0027\\u003E\\u003Cpath d=\\u0027M119 47.3166C119 48.185 118.668 48.9532 118.003 49.6212L78.8385 89L118.003 128.379C118.668 129.047 119 129.815 119 130.683C119 131.552 118.668 132.32 118.003 132.988L113.021 137.998C112.356 138.666 111.592 139 110.729 139C109.865 139 109.101 138.666 108.436 137.998L61.9966 91.3046C61.3322 90.6366 61 89.8684 61 89C61 88.1316 61.3322 87.3634 61.9966 86.6954L108.436 40.002C109.101 39.334 109.865 39 110.729 39C111.592 39 112.356 39.334 113.021 40.002L118.003 45.012C118.668 45.68 119 46.4482 119 47.3166Z\\u0027 fill=\\u0027black\\u0027\\\/\\u003E\\u003C\\\/svg\\u003E\\u003C\\\/div\\u003E&quot;,&quot;rtl&quot;:false,&quot;itemsCount&quot;:4,&quot;fade&quot;:false,&quot;slidesToShow&quot;:{&quot;desktop&quot;:1,&quot;tablet&quot;:1,&quot;mobile&quot;:1}}\" dir=\"ltr\"><div class=\"jet-listing-grid__items grid-col-desk-1 grid-col-tablet-1 grid-col-mobile-1 jet-listing-grid--4913 grid-collapse-gap\" data-queried-id=\"4576|WP_Post\" data-nav=\"{&quot;enabled&quot;:false,&quot;type&quot;:null,&quot;more_el&quot;:null,&quot;query&quot;:[],&quot;widget_settings&quot;:{&quot;lisitng_id&quot;:4913,&quot;posts_num&quot;:11,&quot;columns&quot;:1,&quot;columns_tablet&quot;:1,&quot;columns_mobile&quot;:1,&quot;column_min_width&quot;:240,&quot;column_min_width_tablet&quot;:240,&quot;column_min_width_mobile&quot;:240,&quot;inline_columns_css&quot;:false,&quot;is_archive_template&quot;:&quot;&quot;,&quot;post_status&quot;:[&quot;publish&quot;],&quot;use_random_posts_num&quot;:&quot;&quot;,&quot;max_posts_num&quot;:9,&quot;not_found_message&quot;:&quot;No data was found&quot;,&quot;is_masonry&quot;:false,&quot;equal_columns_height&quot;:&quot;&quot;,&quot;use_load_more&quot;:&quot;&quot;,&quot;load_more_id&quot;:&quot;&quot;,&quot;load_more_type&quot;:&quot;click&quot;,&quot;load_more_offset&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;use_custom_post_types&quot;:&quot;&quot;,&quot;custom_post_types&quot;:[],&quot;hide_widget_if&quot;:&quot;&quot;,&quot;carousel_enabled&quot;:&quot;yes&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;arrows&quot;:&quot;true&quot;,&quot;arrow_icon&quot;:&quot;fa fa-angle-left&quot;,&quot;dots&quot;:&quot;true&quot;,&quot;autoplay&quot;:&quot;true&quot;,&quot;pause_on_hover&quot;:&quot;true&quot;,&quot;autoplay_speed&quot;:3000,&quot;infinite&quot;:&quot;true&quot;,&quot;center_mode&quot;:&quot;&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500,&quot;inject_alternative_items&quot;:&quot;&quot;,&quot;injection_items&quot;:[],&quot;scroll_slider_enabled&quot;:&quot;&quot;,&quot;scroll_slider_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;custom_query&quot;:false,&quot;custom_query_id&quot;:&quot;&quot;,&quot;_element_id&quot;:&quot;&quot;,&quot;collapse_first_last_gap&quot;:&quot;true&quot;,&quot;list_tag_selection&quot;:&quot;&quot;,&quot;list_items_wrapper_tag&quot;:&quot;div&quot;,&quot;list_item_tag&quot;:&quot;div&quot;,&quot;empty_items_wrapper_tag&quot;:&quot;div&quot;}}\" data-page=\"1\" data-pages=\"1\" data-listing-source=\"posts\" data-listing-id=\"4913\" data-query-id=\"\"><div class=\"jet-listing-grid__item jet-listing-dynamic-post-5144\" data-post-id=\"5144\"  ><style type=\"text\/css\">.jet-listing-dynamic-post-5144 .elementor-element.elementor-element-54b942f:not(.elementor-motion-effects-element-type-background), .jet-listing-dynamic-post-5144 .elementor-element.elementor-element-54b942f > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-image:url(\"https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2026\/07\/Estadi-Hero_Trofeu-Ciutat-de-Palma-2400x1000px_EN.jpg\");}@media(max-width:1024px){.jet-listing-dynamic-post-5144 .elementor-element.elementor-element-54b942f:not(.elementor-motion-effects-element-type-background), .jet-listing-dynamic-post-5144 .elementor-element.elementor-element-54b942f > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-image:url(\"https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2026\/07\/Estadi-Hero_Trofeu-Ciutat-de-Palma-1080x1200px_EN.jpg\");}}@media(max-width:767px){.jet-listing-dynamic-post-5144 .elementor-element.elementor-element-54b942f:not(.elementor-motion-effects-element-type-background), .jet-listing-dynamic-post-5144 .elementor-element.elementor-element-54b942f > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-image:url(\"https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2026\/07\/Estadi-Hero_Trofeu-Ciutat-de-Palma-1080x1200px_EN.jpg\");}}<\/style>\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"4913\" class=\"elementor elementor-4913\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<a class=\"elementor-element elementor-element-54b942f e-con-full e-flex e-con e-parent\" data-id=\"54b942f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/www.rcdmallorca.es\/en\/news\/el-paris-saint-germain-rival-de-lujo-en-el-48o-trofeu-ciutat-de-palma\" target=\"_blank\">\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-5143\" data-post-id=\"5143\"  ><style type=\"text\/css\">.jet-listing-dynamic-post-5143 .elementor-element.elementor-element-54b942f:not(.elementor-motion-effects-element-type-background), .jet-listing-dynamic-post-5143 .elementor-element.elementor-element-54b942f > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-image:url(\"https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2026\/07\/Estadi_Hero-Isla-Race-2400x1000px_EN.jpg\");}@media(max-width:1024px){.jet-listing-dynamic-post-5143 .elementor-element.elementor-element-54b942f:not(.elementor-motion-effects-element-type-background), .jet-listing-dynamic-post-5143 .elementor-element.elementor-element-54b942f > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-image:url(\"https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2026\/07\/Estadi_Hero-Isla-Race-1080x1200px_EN.jpg\");}}@media(max-width:767px){.jet-listing-dynamic-post-5143 .elementor-element.elementor-element-54b942f:not(.elementor-motion-effects-element-type-background), .jet-listing-dynamic-post-5143 .elementor-element.elementor-element-54b942f > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-image:url(\"https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2026\/07\/Estadi_Hero-Isla-Race-1080x1200px_EN.jpg\");}}<\/style>\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"4913\" class=\"elementor elementor-4913\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<a class=\"elementor-element elementor-element-54b942f e-con-full e-flex e-con e-parent\" data-id=\"54b942f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/islarace.es\" target=\"_blank\">\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-4981\" data-post-id=\"4981\"  ><style type=\"text\/css\">.jet-listing-dynamic-post-4981 .elementor-element.elementor-element-54b942f:not(.elementor-motion-effects-element-type-background), .jet-listing-dynamic-post-4981 .elementor-element.elementor-element-54b942f > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-image:url(\"https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2026\/03\/Estadi_Hero-MFP-2400x1000px_EN.jpg\");}@media(max-width:1024px){.jet-listing-dynamic-post-4981 .elementor-element.elementor-element-54b942f:not(.elementor-motion-effects-element-type-background), .jet-listing-dynamic-post-4981 .elementor-element.elementor-element-54b942f > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-image:url(\"https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2026\/03\/Estadi_Hero-MFP-1080x1200px_EN.jpg\");}}@media(max-width:767px){.jet-listing-dynamic-post-4981 .elementor-element.elementor-element-54b942f:not(.elementor-motion-effects-element-type-background), .jet-listing-dynamic-post-4981 .elementor-element.elementor-element-54b942f > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-image:url(\"https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2026\/03\/Estadi_Hero-MFP-1080x1200px_EN.jpg\");}}<\/style>\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"4913\" class=\"elementor elementor-4913\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<a class=\"elementor-element elementor-element-54b942f e-con-full e-flex e-con e-parent\" data-id=\"54b942f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/mallorcafootballpark.com\/ca\/\" target=\"_blank\">\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-4996\" data-post-id=\"4996\"  ><style type=\"text\/css\">.jet-listing-dynamic-post-4996 .elementor-element.elementor-element-54b942f:not(.elementor-motion-effects-element-type-background), .jet-listing-dynamic-post-4996 .elementor-element.elementor-element-54b942f > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-image:url(\"https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2026\/03\/Estadi_Hero-Tour-2400x1000px_EN.jpg\");}@media(max-width:1024px){.jet-listing-dynamic-post-4996 .elementor-element.elementor-element-54b942f:not(.elementor-motion-effects-element-type-background), .jet-listing-dynamic-post-4996 .elementor-element.elementor-element-54b942f > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-image:url(\"https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2026\/03\/Estadi_Hero-Tour-1080x1200px_EN.jpg\");}}@media(max-width:767px){.jet-listing-dynamic-post-4996 .elementor-element.elementor-element-54b942f:not(.elementor-motion-effects-element-type-background), .jet-listing-dynamic-post-4996 .elementor-element.elementor-element-54b942f > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-image:url(\"https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2026\/03\/Estadi_Hero-Tour-1080x1200px_EN.jpg\");}}<\/style>\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"4913\" class=\"elementor elementor-4913\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<a class=\"elementor-element elementor-element-54b942f e-con-full e-flex e-con e-parent\" data-id=\"54b942f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/www.rcdmallorca.es\/ca\/museu-tour\" target=\"_blank\">\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cb033aa e-flex e-con-boxed e-con e-parent\" data-id=\"cb033aa\" data-element_type=\"container\" data-e-type=\"container\" id=\"particles-js\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5184738 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"5184738\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">UPCOMING EVENTS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a1e51b elementor-invisible elementor-widget elementor-widget-jet-listing-grid\" data-id=\"5a1e51b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns&quot;:&quot;4&quot;,&quot;columns_laptop&quot;:&quot;3&quot;,&quot;columns_tablet&quot;:&quot;2&quot;,&quot;columns_mobile&quot;:&quot;1&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"jet-listing-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-listing-grid jet-listing\"><div class=\"jet-listing-grid__slider\" data-slider_options=\"{&quot;autoplaySpeed&quot;:5000,&quot;autoplay&quot;:false,&quot;pauseOnHover&quot;:true,&quot;infinite&quot;:true,&quot;centerMode&quot;:false,&quot;speed&quot;:500,&quot;arrows&quot;:false,&quot;dots&quot;:true,&quot;slidesToScroll&quot;:1,&quot;prevArrow&quot;:&quot;\\u003Cdiv class=\\u0027jet-listing-grid__slider-icon prev-arrow \\u0027 role=\\u0027button\\u0027 aria-label=\\u0027Previous\\u0027\\u003E\\u003Csvg width=\\u0027180\\u0027 height=\\u0027180\\u0027 viewBox=\\u00270 0 180 180\\u0027 fill=\\u0027none\\u0027 xmlns=\\u0027http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\u0027\\u003E\\u003Cpath d=\\u0027M119 47.3166C119 48.185 118.668 48.9532 118.003 49.6212L78.8385 89L118.003 128.379C118.668 129.047 119 129.815 119 130.683C119 131.552 118.668 132.32 118.003 132.988L113.021 137.998C112.356 138.666 111.592 139 110.729 139C109.865 139 109.101 138.666 108.436 137.998L61.9966 91.3046C61.3322 90.6366 61 89.8684 61 89C61 88.1316 61.3322 87.3634 61.9966 86.6954L108.436 40.002C109.101 39.334 109.865 39 110.729 39C111.592 39 112.356 39.334 113.021 40.002L118.003 45.012C118.668 45.68 119 46.4482 119 47.3166Z\\u0027 fill=\\u0027black\\u0027\\\/\\u003E\\u003C\\\/svg\\u003E\\u003C\\\/div\\u003E&quot;,&quot;nextArrow&quot;:&quot;\\u003Cdiv class=\\u0027jet-listing-grid__slider-icon next-arrow \\u0027 role=\\u0027button\\u0027 aria-label=\\u0027Next\\u0027\\u003E\\u003Csvg width=\\u0027180\\u0027 height=\\u0027180\\u0027 viewBox=\\u00270 0 180 180\\u0027 fill=\\u0027none\\u0027 xmlns=\\u0027http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\u0027\\u003E\\u003Cpath d=\\u0027M119 47.3166C119 48.185 118.668 48.9532 118.003 49.6212L78.8385 89L118.003 128.379C118.668 129.047 119 129.815 119 130.683C119 131.552 118.668 132.32 118.003 132.988L113.021 137.998C112.356 138.666 111.592 139 110.729 139C109.865 139 109.101 138.666 108.436 137.998L61.9966 91.3046C61.3322 90.6366 61 89.8684 61 89C61 88.1316 61.3322 87.3634 61.9966 86.6954L108.436 40.002C109.101 39.334 109.865 39 110.729 39C111.592 39 112.356 39.334 113.021 40.002L118.003 45.012C118.668 45.68 119 46.4482 119 47.3166Z\\u0027 fill=\\u0027black\\u0027\\\/\\u003E\\u003C\\\/svg\\u003E\\u003C\\\/div\\u003E&quot;,&quot;rtl&quot;:false,&quot;itemsCount&quot;:2,&quot;fade&quot;:false,&quot;slidesToShow&quot;:{&quot;desktop&quot;:4,&quot;tablet&quot;:2,&quot;mobile&quot;:1}}\" dir=\"ltr\"><div class=\"jet-listing-grid__items grid-col-desk-4 grid-col-tablet-2 grid-col-mobile-1 jet-listing-grid--136 jet-equal-columns__wrapper\" data-queried-id=\"4576|WP_Post\" data-nav=\"{&quot;enabled&quot;:false,&quot;type&quot;:null,&quot;more_el&quot;:null,&quot;query&quot;:[],&quot;widget_settings&quot;:{&quot;lisitng_id&quot;:136,&quot;posts_num&quot;:4,&quot;columns&quot;:4,&quot;columns_tablet&quot;:2,&quot;columns_mobile&quot;:1,&quot;column_min_width&quot;:240,&quot;column_min_width_tablet&quot;:240,&quot;column_min_width_mobile&quot;:240,&quot;inline_columns_css&quot;:false,&quot;is_archive_template&quot;:&quot;&quot;,&quot;post_status&quot;:[&quot;publish&quot;],&quot;use_random_posts_num&quot;:&quot;&quot;,&quot;max_posts_num&quot;:9,&quot;not_found_message&quot;:&quot;No data was found&quot;,&quot;is_masonry&quot;:false,&quot;equal_columns_height&quot;:&quot;yes&quot;,&quot;use_load_more&quot;:&quot;&quot;,&quot;load_more_id&quot;:&quot;&quot;,&quot;load_more_type&quot;:&quot;click&quot;,&quot;load_more_offset&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;use_custom_post_types&quot;:&quot;yes&quot;,&quot;custom_post_types&quot;:[&quot;eventos&quot;],&quot;hide_widget_if&quot;:&quot;&quot;,&quot;carousel_enabled&quot;:&quot;yes&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;arrows&quot;:&quot;true&quot;,&quot;arrow_icon&quot;:&quot;fa fa-angle-left&quot;,&quot;dots&quot;:&quot;true&quot;,&quot;autoplay&quot;:&quot;true&quot;,&quot;pause_on_hover&quot;:&quot;true&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;true&quot;,&quot;center_mode&quot;:&quot;&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500,&quot;inject_alternative_items&quot;:&quot;&quot;,&quot;injection_items&quot;:[],&quot;scroll_slider_enabled&quot;:&quot;&quot;,&quot;scroll_slider_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;custom_query&quot;:false,&quot;custom_query_id&quot;:&quot;&quot;,&quot;_element_id&quot;:&quot;&quot;,&quot;collapse_first_last_gap&quot;:false,&quot;list_tag_selection&quot;:&quot;&quot;,&quot;list_items_wrapper_tag&quot;:&quot;div&quot;,&quot;list_item_tag&quot;:&quot;div&quot;,&quot;empty_items_wrapper_tag&quot;:&quot;div&quot;}}\" data-page=\"1\" data-pages=\"1\" data-listing-source=\"posts\" data-listing-id=\"136\" data-query-id=\"\"><div class=\"jet-listing-grid__item jet-listing-dynamic-post-5102 jet-equal-columns\" data-post-id=\"5102\"  >\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"1407\" class=\"elementor elementor-1407 elementor-136\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<div class=\"elementor-element elementor-element-334b2c8 e-flex e-con-boxed e-con e-parent\" data-id=\"334b2c8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-31ce626 e-con-full e-flex e-con e-child\" data-id=\"31ce626\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-04b27de elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"04b27de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"625\" src=\"https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2026\/07\/Estadi-Tarjeta_Trofeu-Ciutat-de-Palma-1000x625px.jpg\" class=\"attachment-full size-full wp-image-5100\" alt=\"\" srcset=\"https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2026\/07\/Estadi-Tarjeta_Trofeu-Ciutat-de-Palma-1000x625px.jpg 1000w, https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2026\/07\/Estadi-Tarjeta_Trofeu-Ciutat-de-Palma-1000x625px-300x188.jpg 300w, https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2026\/07\/Estadi-Tarjeta_Trofeu-Ciutat-de-Palma-1000x625px-768x480.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d9278b0 e-con-full e-flex e-con e-child\" data-id=\"d9278b0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cfcd169 evento-fecha elementor-widget elementor-widget-heading\" data-id=\"cfcd169\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Wednesday, 5th August, 2026, 8pm<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7533d8d elementor-widget elementor-widget-heading\" data-id=\"7533d8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">RCD Mallorca vs Paris Saint-Germain confirmed as out opposition for the 48\u00ba Trofeu Ciutat de Palma<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fdd9de elementor-widget elementor-widget-heading\" data-id=\"4fdd9de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">\r\nReigning European champions Paris Saint-Germain (PSG) will face RCD Mallorca\r\n<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1fdd28 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"e1fdd28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.rcdmallorca.es\/en\/entradas\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ticketing<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-5113 jet-equal-columns\" data-post-id=\"5113\"  >\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"1407\" class=\"elementor elementor-1407 elementor-136\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<div class=\"elementor-element elementor-element-334b2c8 e-flex e-con-boxed e-con e-parent\" data-id=\"334b2c8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-31ce626 e-con-full e-flex e-con e-child\" data-id=\"31ce626\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-04b27de elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"04b27de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1000\" height=\"625\" src=\"https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2026\/06\/ESTADI_Banner-web-Isla-Race_EN-1.jpg\" class=\"attachment-full size-full wp-image-5108\" alt=\"\" srcset=\"https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2026\/06\/ESTADI_Banner-web-Isla-Race_EN-1.jpg 1000w, https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2026\/06\/ESTADI_Banner-web-Isla-Race_EN-1-300x188.jpg 300w, https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2026\/06\/ESTADI_Banner-web-Isla-Race_EN-1-768x480.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d9278b0 e-con-full e-flex e-con e-child\" data-id=\"d9278b0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cfcd169 evento-fecha elementor-widget elementor-widget-heading\" data-id=\"cfcd169\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">19 and 20th of September<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7533d8d elementor-widget elementor-widget-heading\" data-id=\"7533d8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Isla Race Estadi Mallorca Son Moix<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fdd9de elementor-widget elementor-widget-heading\" data-id=\"4fdd9de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Go beyond your limits in this hybrid obstacle race in an incredible setting<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1fdd28 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"e1fdd28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/islarace.es\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Register from July 4<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43d3e41 elementor-align-center elementor-mobile-align-justify elementor-invisible elementor-widget elementor-widget-button\" data-id=\"43d3e41\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/estadimallorcasonmoix.es\/en\/calendar\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">VIEW ALL EVENTS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9a51cbc particles-js e-flex e-con-boxed e-con e-parent\" data-id=\"9a51cbc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-14f08e9 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"14f08e9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-8f5fc1b e-con-full e-flex e-con e-child\" data-id=\"8f5fc1b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b618001 elementor-widget elementor-widget-image\" data-id=\"b618001\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"58\" src=\"https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2026\/03\/FOOTBALLPARK-COBRANDING-RGB_HORIZONTAL-ROJO-CONESCUDO-1-300x58.png\" class=\"attachment-medium size-medium wp-image-3870\" alt=\"\" srcset=\"https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2026\/03\/FOOTBALLPARK-COBRANDING-RGB_HORIZONTAL-ROJO-CONESCUDO-1-300x58.png 300w, https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2026\/03\/FOOTBALLPARK-COBRANDING-RGB_HORIZONTAL-ROJO-CONESCUDO-1-1024x199.png 1024w, https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2026\/03\/FOOTBALLPARK-COBRANDING-RGB_HORIZONTAL-ROJO-CONESCUDO-1-768x149.png 768w, https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2026\/03\/FOOTBALLPARK-COBRANDING-RGB_HORIZONTAL-ROJO-CONESCUDO-1-1536x298.png 1536w, https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2026\/03\/FOOTBALLPARK-COBRANDING-RGB_HORIZONTAL-ROJO-CONESCUDO-1-2048x398.png 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ece66d elementor-widget elementor-widget-text-editor\" data-id=\"8ece66d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Football as you&#8217;ve never played it before<\/p><p>Discover a unique space where football is experienced in a whole new way. Over 1,500 m\u00b2 of interactive experiences, games, and technology in a covered environment designed for all audiences. A place to enjoy, compete, learn, and share the passion for sport in the heart of Estadi Mallorca Son Moix.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40cad13 elementor-widget elementor-widget-button\" data-id=\"40cad13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/mallorcafootballpark.com\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">BUY YOUR TICKETS NOW!<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f87dde7 e-con-full e-flex e-con e-child\" data-id=\"f87dde7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_scale_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_scale_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:2,&quot;sizes&quot;:[]},&quot;background_motion_fx_scale_direction&quot;:&quot;out-in&quot;,&quot;background_motion_fx_scale_range&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:20,&quot;end&quot;:80}},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-478d9e0 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"478d9e0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-db78e60 e-con-full e-flex e-con e-child\" data-id=\"db78e60\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_scale_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_scale_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:2,&quot;sizes&quot;:[]},&quot;background_motion_fx_scale_direction&quot;:&quot;out-in&quot;,&quot;background_motion_fx_scale_range&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:20,&quot;end&quot;:80}},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-330c017 e-con-full e-flex e-con e-child\" data-id=\"330c017\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-70ea262 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"70ea262\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"388\" height=\"512\" viewBox=\"0 0 388 512\" fill=\"none\"><path d=\"M363.158 344.23C367.708 340.909 371.288 338.118 374.534 334.796C377.779 331.474 380.585 327.773 383.376 322.51C385.257 318.991 386.304 315.23 387.927 311.59C382.466 312.697 377.006 314.123 372.258 317.247C372.85 315.943 373.229 314.653 373.563 313.349C373.957 311.726 374.154 310.164 374.078 308.602C374.215 308.465 374.336 308.283 374.473 308.146C375.064 307.373 375.58 306.721 376.293 306.19C377.658 305.083 379.023 303.975 380.191 302.61C381.814 302.61 383.058 302.413 384.028 301.958C385.136 301.503 385.909 300.729 386.44 299.683C386.895 298.773 387.032 297.999 386.956 297.408C386.819 296.437 386.106 295.845 385.136 295.845C384.362 295.785 383.376 296.103 382.406 296.756C380.722 297.802 380.191 299.091 379.615 300.654C378.902 302.671 377.142 303.9 375.519 305.143C374.867 305.659 374.351 306.19 373.896 306.827C373.244 303.247 374.291 298.955 375.262 294.996C375.656 293.312 376.035 291.553 376.49 289.794C374.215 291.098 372.334 292.782 370.378 294.48C371.545 292.463 372.516 290.385 373.366 288.231C374.791 284.849 375.777 281.345 376.429 277.826C377.142 274.125 377.658 270.546 378.841 266.966C374.609 269.575 370.711 272.366 367.268 275.945C367.587 274.323 367.723 272.76 367.663 271.137C367.663 270.622 367.663 270.167 367.602 269.636C368.512 268.786 369.285 267.876 370.014 266.906C370.742 265.935 371.318 264.949 371.834 263.842C372.683 263.902 373.457 263.644 374.169 263.129C374.882 262.537 375.535 261.703 375.792 260.656C376.05 259.61 375.929 258.579 375.535 257.729C375.14 256.88 374.427 256.228 373.517 256.045C372.547 255.848 371.637 256.045 370.787 256.637C370.074 257.153 369.483 258.063 369.225 259.109C368.967 260.156 369.028 261.187 369.422 262.037C369.68 262.628 370.074 263.083 370.59 263.402C370.135 264.373 369.619 265.283 368.967 266.193C368.512 266.845 367.996 267.421 367.405 268.013C367.208 266.708 366.889 265.343 366.434 264.039C365.721 261.824 365.585 259.428 365.782 257.077C365.979 254.21 366.828 251.48 367.541 248.629C365.13 249.933 362.991 251.419 360.913 253.179C358.835 254.938 356.939 256.88 355.316 259.034C354.603 256.364 353.238 254.605 351.539 253.437C349.78 252.208 347.702 251.677 345.563 251.556C347.186 247.855 348.809 244.275 350.508 240.696C351.357 238.815 352.192 236.919 352.586 236.085C354.467 231.929 354.406 228.744 353.754 224.315C352.783 218.339 347.126 209.951 340.482 201.624C337.16 197.392 333.52 193.175 330.214 189.262C327.089 185.622 324.238 182.3 322.144 179.57C320.976 178.068 319.611 176.248 317.988 174.959C316.305 173.533 314.348 172.684 312.073 173.139C309.859 173.533 308.236 175.475 308.433 177.75C308.569 179.434 309.859 180.738 311.618 180.875C311.755 182.497 311.557 183.863 311.026 185.167C309.661 188.868 306.142 191.022 302.32 191.537C299.727 191.856 296.921 191.537 294.327 190.764C293.28 190.506 292.31 190.051 291.263 189.596C288.275 188.17 285.348 185.956 282.739 183.347C279.038 179.57 275.974 174.959 274.29 170.606C273.062 167.481 272.41 164.175 272.667 160.793C272.865 157.865 273.714 154.938 275.534 152.01C276.384 150.645 278.067 150.509 279.629 150.448C281.51 150.387 283.27 150.312 284.058 148.37C284.574 147.066 284.316 145.64 283.406 144.533C282.435 143.228 280.812 142.455 279.174 142.394C279.629 142.136 280.024 141.878 280.342 141.545C280.797 141.09 281.055 140.635 281.252 140.043C281.45 139.527 281.51 138.936 281.389 138.36C281.252 137.586 280.934 136.858 280.221 136.221C280.737 134.537 281.268 132.778 282.435 131.534C283.406 130.487 284.058 129.577 284.453 128.804H284.847C285.894 128.804 287.062 128.607 288.032 128.152C289.079 127.636 289.989 126.847 290.368 125.74C290.565 125.346 290.687 124.83 290.687 124.238C290.687 123.526 290.944 122.737 291.278 121.903C291.93 120.538 292.962 119.172 294.145 118.065C295.116 117.216 296.101 116.503 297.133 116.109C298.104 115.714 299.09 115.654 299.924 115.911C300.697 116.23 301.486 116.882 302.062 117.989C301.092 119.809 301.607 122.085 303.291 123.253C305.308 124.678 307.978 123.965 309.009 121.69C310.571 118.369 309.722 114.349 307.508 111.346C307.963 109.981 308.675 108.934 309.464 108.1C310.177 108.419 310.89 108.616 311.679 108.616C314.545 108.616 316.821 106.28 316.821 103.474C316.821 102.109 316.365 100.941 315.516 100.031H315.653C318.443 100.031 320.794 97.7557 320.794 94.889C320.794 93.3874 320.082 91.9616 319.035 91.0515C321.902 90.7937 324.177 88.3214 324.177 85.394C324.177 82.8003 322.417 80.5859 319.945 79.9336C322.933 79.4179 325.148 76.8091 325.148 73.7604C325.148 70.3173 322.357 67.5113 318.898 67.5113C318.246 67.5113 317.731 67.572 317.139 67.7085C319.217 66.6619 320.643 64.5233 320.643 61.9903C320.643 58.4714 317.776 55.5592 314.212 55.5592C313.044 55.5592 311.937 55.8777 310.966 56.4692C311.739 55.4227 312.134 54.1941 312.134 52.829C312.134 49.3859 309.343 46.5799 305.885 46.5799C304.459 46.5799 303.154 47.035 302.108 47.8843V47.49C302.108 44.1683 299.378 41.4381 296.056 41.4381C294.433 41.4381 292.931 42.151 291.824 43.2582C291.627 43.3947 291.506 43.5767 291.369 43.7132C291.309 43.5767 291.308 43.4554 291.233 43.3189C290.641 41.0437 288.563 39.3601 286.091 39.3601C284.589 39.3601 283.224 39.9517 282.253 40.9224C282.117 41.1196 281.996 41.2409 281.859 41.4381C281.207 39.2236 279.129 37.6007 276.717 37.6007C275.216 37.6007 273.926 38.1922 272.94 39.1629C272.804 39.2994 272.683 39.4208 272.622 39.5573V39.2994C272.622 36.4328 270.286 34.0969 267.359 34.0969C265.281 34.0969 263.461 35.3255 262.611 37.1456C262.672 36.9485 262.672 36.6906 262.672 36.4934C262.672 33.6267 260.336 31.2909 257.469 31.2909C255.968 31.2909 254.679 31.8825 253.693 32.8532C253.556 30.123 251.281 27.9085 248.551 27.9085C247.125 27.9085 245.821 28.5001 244.911 29.4101C244.258 30.123 243.743 30.9724 243.545 31.9431V31.6853C243.545 28.8944 241.27 26.6799 238.54 26.6799C237.175 26.6799 235.946 27.2715 235.021 28.1057C234.627 28.5001 234.308 28.9551 234.111 29.4708C233.793 27.59 232.428 26.0884 230.592 25.4969C230.137 25.3603 229.682 25.2997 229.167 25.2997C227.801 25.2997 226.573 25.8912 225.663 26.8013C225.344 27.1198 225.011 27.5142 224.813 27.9085C224.358 25.694 222.341 23.9346 220.005 23.9346C218.64 23.9346 217.412 24.5261 216.486 25.4362C216.229 25.694 215.971 26.0277 215.773 26.3463C215.061 24.5261 213.362 23.2975 211.345 23.2975C208.675 23.2975 206.536 25.512 206.597 28.1057C205.171 28.1057 203.867 27.8478 202.562 27.3321C203.078 26.1642 203.412 24.7991 203.412 23.4341C203.412 18.7472 199.969 14.7885 195.479 14.0756V9.19161H201.197V6.06707H195.479V0H192.491V6.11257H186.773V9.23711H192.491V14.1211C188.001 14.834 184.558 18.8079 184.558 23.4796C184.558 24.8446 184.877 26.2097 185.408 27.3777C184.103 27.8934 182.814 28.1512 181.373 28.1512C181.434 25.5575 179.295 23.3431 176.626 23.3431C174.608 23.3431 172.925 24.5716 172.197 26.3918C172 26.0732 171.742 25.7395 171.484 25.4817C170.574 24.5716 169.345 23.9801 167.965 23.9801C165.629 23.9801 163.612 25.7395 163.157 27.954C162.96 27.5597 162.641 27.1805 162.307 26.8468C161.397 25.9367 160.169 25.3452 158.789 25.3452C158.47 25.3452 158.136 25.4059 157.818 25.4817C155.801 25.8761 154.238 27.4383 153.844 29.5163C153.647 29.0006 153.328 28.5456 152.934 28.1512C152.024 27.3018 150.795 26.7254 149.415 26.7254C146.685 26.7254 144.41 28.9399 144.41 31.7308V31.9886C144.212 31.0179 143.697 30.1685 143.044 29.4556C142.134 28.5456 140.83 27.954 139.404 27.954C136.674 27.954 134.399 30.1685 134.262 32.8987C133.292 31.928 131.987 31.3364 130.486 31.3364C127.619 31.3364 125.283 33.6722 125.283 36.5389C125.283 36.7361 125.283 36.994 125.344 37.1911C124.494 35.371 122.674 34.1424 120.596 34.1424C117.669 34.1424 115.333 36.4783 115.333 39.3449V39.6028C115.272 39.4663 115.136 39.3449 115.015 39.2084C114.044 38.2377 112.739 37.6462 111.238 37.6462C108.826 37.6462 106.748 39.2691 106.096 41.4836C105.96 41.2864 105.838 41.1651 105.702 40.9679C104.731 39.9972 103.366 39.4056 101.864 39.4056C99.2706 39.4056 97.0561 41.2864 96.6011 43.7587C96.4646 43.5616 96.2826 43.4402 96.146 43.3037C95.0388 42.1965 93.5524 41.4836 91.9143 41.4836C88.5925 41.4836 85.8624 44.2138 85.8624 47.5355C85.8624 47.672 85.8624 47.7933 85.923 47.9298C84.8158 47.0805 83.5114 46.6254 82.0856 46.6254C78.6426 46.6254 75.8365 49.4163 75.8365 52.8745C75.8365 54.2396 76.2309 55.4682 77.0044 56.5148C76.0337 55.9232 74.9265 55.6047 73.7586 55.6047C70.179 55.6047 67.3275 58.5321 67.3275 62.0358C67.3275 64.5688 68.7532 66.7226 70.8312 67.754C70.2397 67.6175 69.724 67.5568 69.0717 67.5568C65.6287 67.5568 62.8227 70.3477 62.8227 73.8059C62.8227 76.8698 65.0371 79.4634 68.0252 79.9791C65.6135 80.6314 63.7934 82.8458 63.7934 85.4395C63.7934 88.3669 66.0685 90.8392 68.9352 91.0971C67.8887 92.0071 67.1758 93.4329 67.1758 94.9345C67.1758 97.8012 69.5116 100.076 72.3176 100.076H72.4541C71.6047 100.986 71.1497 102.154 71.1497 103.519C71.1497 106.31 73.4249 108.661 76.2916 108.661C77.0651 108.661 77.8538 108.464 78.506 108.146C79.2796 108.919 79.9318 109.905 80.3868 111.209C79.2796 112.635 78.5667 114.334 78.3089 116.154C78.1117 117.974 78.1117 120.052 78.9004 121.751C79.8711 124.026 82.6013 124.739 84.6186 123.313C86.3022 122.145 86.8331 119.87 85.8472 118.05C86.4387 116.943 87.2123 116.291 87.9858 115.972C88.8352 115.714 89.806 115.775 90.7767 116.169C91.8233 116.564 92.794 117.276 93.7647 118.126H93.7041C94.9326 119.172 95.9185 120.538 96.5707 121.827C96.9651 122.676 97.2229 123.586 97.2229 124.299C97.2229 124.891 97.3595 125.406 97.4808 125.801C97.9358 126.908 98.8459 127.681 99.8925 128.212C100.863 128.667 102.031 128.865 103.078 128.865H103.533C103.927 129.638 104.579 130.548 105.55 131.595C106.779 132.823 107.234 134.583 107.764 136.282C107.052 136.934 106.718 137.647 106.597 138.42C106.46 139.012 106.536 139.588 106.733 140.104C106.93 140.695 107.249 141.15 107.643 141.605C107.962 141.924 108.356 142.197 108.811 142.455C107.188 142.515 105.565 143.304 104.519 144.593C103.669 145.701 103.351 147.126 103.866 148.431C104.716 150.387 106.46 150.448 108.356 150.509C109.918 150.57 111.541 150.706 112.451 152.071C114.211 154.998 115.121 157.926 115.318 160.853C115.515 164.236 114.863 167.557 113.695 170.667C112.011 175.02 108.948 179.646 105.171 183.408C102.577 186.001 99.5739 188.216 96.5859 189.717C95.6152 190.172 94.5686 190.567 93.5979 190.825C91.0042 191.598 88.1982 191.932 85.6652 191.598C81.7671 191.082 78.324 188.929 76.8831 185.228C76.4281 183.923 76.1702 182.558 76.2916 180.935C78.1117 180.799 79.3403 179.509 79.5374 177.811C79.7346 175.535 78.0358 173.579 75.8365 173.2C73.622 172.745 71.6806 173.594 69.9818 175.02C68.3589 176.324 66.9331 178.144 65.8259 179.631C63.6872 182.361 60.8205 185.683 57.696 189.323C50.734 197.513 42.5435 207.145 37.8567 215.335C35.9 218.657 34.6108 221.767 34.2164 224.375C33.6249 227.955 33.5036 230.685 34.4136 233.734C31.6228 236.464 29.5296 239.391 28.4982 243.229C27.6488 246.217 27.5275 249.599 28.1797 253.497C26.1624 249.539 23.6901 246.278 20.5049 243.092C19.8526 248.158 19.3976 253.239 19.3369 258.305C18.6847 257.198 17.9719 256.091 17.3196 255.12C16.2731 253.695 15.2417 252.329 14.1951 251.086C14.5136 250.767 14.7866 250.433 14.908 249.978C15.3023 249.129 15.363 248.098 14.9687 247.051C14.6501 246.08 13.8614 245.292 13.012 244.912C12.1626 244.457 11.1312 244.321 10.1453 244.655C9.1746 244.973 8.46172 245.701 8.06736 246.611C7.673 247.521 7.61233 248.568 8.00669 249.539C8.40105 250.509 9.11393 251.298 9.96332 251.753C10.8734 252.208 11.8441 252.269 12.83 251.95C12.9665 251.95 13.0272 251.89 13.0879 251.814C14.1951 253.042 15.2265 254.407 16.2124 255.848C17.3196 257.35 18.2904 259.094 19.2763 260.914L19.3369 260.975C19.3369 262.598 19.3976 264.297 19.5341 265.98C18.4269 263.963 17.0011 262.082 15.4389 260.323C12.5722 257.138 9.18977 254.802 5.54953 252.527C5.41302 258.442 5.86805 264.236 7.68817 269.954C9.31111 275.415 12.0413 280.875 16.2731 286.411C15.4237 291.932 15.2265 297.468 15.9546 302.989C16.3489 305.522 16.8646 308.055 17.5775 310.604C16.7281 309.178 15.818 307.737 14.908 306.372C12.9514 303.444 10.8734 300.775 8.59823 298.439C9.18977 297.848 9.56896 297.074 9.56896 296.225C9.56896 295.375 9.1746 294.541 8.52239 294.01C7.93085 293.419 7.1573 293.1 6.24724 293.1C5.33718 293.1 4.56363 293.419 3.91142 294.01C3.31988 294.602 3.00136 295.375 3.00136 296.225C3.00136 297.074 3.39572 297.848 3.97209 298.439C4.56363 299.031 5.39785 299.349 6.30791 299.349C6.70227 299.349 7.08146 299.289 7.47582 299.152C9.75098 301.427 11.9048 304.157 13.8462 307.085C15.8029 310.012 17.623 313.137 19.2459 316.246C18.1387 315.139 16.9708 314.032 15.8029 313C11.0554 308.966 5.91355 305.841 0.074 303.566C-0.244521 307.661 0.468359 311.18 2.15197 314.942C3.65357 318.385 5.85288 321.828 8.32521 325.468C10.1453 328.001 12.2233 330.079 14.3771 332.172C17.0466 334.842 19.7161 337.435 21.5969 341.015C20.3683 340.62 19.0639 340.363 17.8202 340.044C19.6403 343.108 21.2632 346.096 22.5677 349.403C23.7356 352.193 24.6456 355.121 25.4344 358.245C26.0259 360.52 26.3444 363.129 26.6023 365.723C25.3737 365.207 24.1906 364.616 23.0227 363.903C21.7941 363.19 20.5504 362.341 19.3218 361.43C19.8375 359.808 19.8375 358.306 19.519 357.077C19.1246 355.576 18.2145 354.484 16.986 354.089C16.4703 353.953 16.0152 353.892 15.5602 353.892C14.7866 353.953 14.1344 354.211 13.5429 354.666C12.9514 355.06 12.4963 355.712 12.2385 356.349C12.102 356.744 12.102 357.123 12.102 357.578C12.2385 359.08 13.0727 360.369 14.2406 361.218C15.4692 362.068 16.9708 362.447 18.3966 362.325C19.701 363.296 21.0661 364.206 22.3705 364.995C23.7962 365.844 25.2372 366.557 26.7236 367.073C26.8601 368.241 26.9208 369.409 27.118 370.516C26.8601 370.455 26.6629 370.379 26.4051 370.319C21.5211 368.635 12.4205 366.163 7.09663 366.8C7.94602 367.71 8.85608 368.362 9.82681 369.136C12.4963 371.092 15.0293 372.912 17.1073 375.445C21.0812 380.193 25.1765 384.607 29.5903 388.641C32.2598 391.053 34.99 393.389 37.8415 395.527C39.601 396.832 41.4211 398.121 43.3019 399.304C45.4405 401.716 47.3971 404.446 49.0201 407.373C50.643 410.361 51.9474 413.486 52.7968 416.611C53.0547 417.323 53.2519 418.036 53.5097 418.749C49.4751 417.976 45.577 416.337 42.0581 414.138C42.2553 413.622 42.1188 412.97 41.8609 412.455C41.1481 411.15 39.4493 410.498 38.0842 410.832C38.0235 410.832 37.887 410.892 37.8263 410.892C36.4613 411.347 35.8697 412.712 36.5978 414.017C36.8556 414.533 37.3106 414.988 37.8263 415.245C38.5999 415.7 39.51 415.837 40.3593 415.64C40.6779 415.579 41.0116 415.443 41.3301 415.185C45.1675 417.657 49.5206 419.417 54.0709 420.19C54.5866 421.358 55.2388 422.465 55.9517 423.512C56.7253 424.558 57.6353 425.529 58.6819 426.378C53.3429 425.726 48.1555 426.378 42.8772 427.349C44.5608 428.851 46.2596 430.277 47.8218 431.839C49.1263 433.067 50.4307 434.433 51.7958 436.131C55.4967 440.484 61.4121 445.49 68.5105 446.855C73.0002 447.704 77.9448 447.113 83.0715 444.125C87.1061 450.495 91.4592 456.866 96.5252 463.236C102.835 471.305 110.252 479.359 119.474 487.368C127.407 495.498 144.243 509.861 157.712 508.754C158.682 508.693 159.592 508.557 160.502 508.36C166.297 506.858 171.029 502.308 170.71 495.937C172.015 499.32 173.956 502.369 176.504 504.841C180.933 509.27 187.107 512 193.871 512C200.636 512 206.749 509.27 211.238 504.841C213.711 502.369 215.728 499.32 216.957 495.937C216.638 502.308 221.386 506.858 227.225 508.36C228.272 508.618 229.364 508.754 230.471 508.815C243.864 509.467 260.382 495.361 268.178 487.353C277.415 479.359 284.756 471.351 291.066 463.357C294.251 459.398 297.178 455.364 299.848 451.329C308.175 453.407 315.85 451.39 322.539 447.431C329.501 443.336 335.537 437.087 340.285 431.308C340.346 431.308 340.346 431.247 340.346 431.247L340.998 430.474L340.285 430.277L339.966 430.216C336.463 429.564 332.807 429.503 328.97 430.155C326.103 430.61 323.176 431.46 320.127 432.688C322.857 430.095 325.33 427.091 327.544 423.588C330.016 422.996 332.489 422.359 334.885 421.449C336.705 420.797 338.525 420.084 340.285 419.234C340.74 418.977 341.195 418.779 341.65 418.522C342.044 419.113 342.621 419.492 343.334 419.75C344.38 420.069 345.472 420.008 346.458 419.75C347.884 419.295 349.052 418.249 349.128 416.762C349.128 415.913 348.733 415.139 347.96 414.548C346.458 413.38 344.122 413.501 342.621 414.608C341.711 415.261 341.058 416.171 341.195 417.339C340.937 417.475 340.603 417.596 340.285 417.794C338.404 418.704 336.447 419.553 334.43 420.266C332.474 420.979 330.456 421.57 328.454 422.025C329.304 420.66 330.077 419.159 330.866 417.596C332.686 413.895 334.385 409.982 336.068 406.145C336.66 404.78 337.236 403.415 337.828 402.11C338.677 402.05 339.511 401.974 340.3 401.913C344.138 401.397 347.975 400.032 351.752 397.757C356.438 394.89 361.11 390.734 365.66 385.213C368.451 381.831 371.257 378.843 374.048 375.916C375.019 374.808 376.005 373.777 376.976 372.73C371.06 372.412 365.858 373.246 360.397 375.597C360.594 374.687 360.716 373.777 360.716 373.003C362.217 371.32 363.764 369.682 365.403 368.059C366.828 366.694 368.269 365.389 369.756 364.221C370.15 364.479 370.605 364.676 371.121 364.737C372.88 365.056 374.822 364.024 375.413 362.265C376.005 360.445 374.761 358.685 372.941 358.367C371.121 358.048 369.164 359.08 368.648 360.839C368.391 361.688 368.451 362.523 368.846 363.251C367.42 364.479 365.979 365.723 364.493 367.149C363.188 368.377 361.899 369.742 360.594 371.244C360.397 370.015 360.079 368.908 359.745 367.862C359.487 366.891 359.229 366.041 359.093 365.192C358.501 359.671 363.188 352.254 366.176 347.507C366.828 346.536 367.283 345.944 368.133 345.171C365.342 345.368 362.794 346.141 360.139 347.309C360.989 346.202 361.899 345.095 363.006 344.261L363.158 344.23ZM276.945 52.9352C276.884 52.6773 276.884 52.5408 276.884 52.4195C276.823 51.3729 276.748 50.3415 276.49 49.2949C282.011 50.5235 287.016 52.6167 291.248 55.4075C294.115 57.2276 296.587 59.3814 298.725 61.7173C304.247 67.7692 307.174 75.2468 306.522 82.9823C306.385 85.1968 305.93 87.4113 305.293 89.5499C303.534 89.0949 301.774 88.382 301.198 87.7298C298.725 84.8025 295.222 83.3009 291.248 82.5273C289.231 82.133 287.016 81.9358 284.817 81.8144C284.68 79.3421 284.362 76.8091 282.739 73.8211C280.464 73.3054 278.188 73.0475 275.913 72.9717C276.368 71.2122 276.687 69.5286 276.884 67.8298C277.476 63.2795 277.339 58.5927 276.945 52.9352ZM96.6921 75.4288V75.4895C91.171 79.3876 88.5622 81.4049 81.4789 79.5848C81.7974 73.0779 84.6641 66.8439 89.3509 61.7021C91.4289 59.3663 93.9012 57.2731 96.6921 55.453C100.985 52.6622 105.99 50.5084 111.587 49.2798C111.329 50.3263 111.268 51.3577 111.192 52.4043C111.192 52.5408 111.192 52.6622 111.132 52.92C110.737 58.5776 110.616 63.2644 111.192 67.8147C111.329 69.1191 111.587 70.4083 111.845 71.7734C106.126 70.2718 101.318 72.092 96.6921 75.4137V75.4288ZM340.467 263.796C340.603 263.402 340.725 263.083 340.922 262.689C341.119 265.283 342.151 268.028 343.789 272.442C342.742 272.381 341.65 272.578 340.467 272.76C340.073 272.821 339.693 272.897 339.299 273.018C338.647 273.155 337.934 273.276 337.221 273.337C338.192 270.091 339.299 266.906 340.467 263.781V263.796ZM209.904 34.0666C211.587 34.3244 213.347 34.7188 215.167 35.2952C219.323 36.5238 222.842 37.4338 226.421 38.0254C227.786 38.2225 229.212 38.4197 230.653 38.5411C232.989 38.7382 235.4 38.8596 238.131 38.8596C242.362 38.8596 245.805 39.5725 248.475 41.3319C251.084 43.0155 253.025 45.685 254.133 49.5831C255.043 52.6318 255.498 55.635 255.558 58.6837C255.164 58.6231 254.785 58.6231 254.451 58.5472C246.837 57.8343 246.003 51.6611 240.406 49.7045C237.812 48.7944 234.035 48.7337 230.653 49.0523C229.682 49.1888 228.772 49.3101 227.862 49.4466C224.025 50.1595 221.355 48.7337 217.715 47.49C215.303 46.7164 212.831 45.9277 210.237 45.2755C209.267 41.1196 207.901 37.2821 206.081 34.0211C206.021 33.8846 205.884 33.7026 205.823 33.5661C207.249 33.7026 208.614 33.8239 209.919 34.0211L209.904 34.0666ZM133.944 49.6135C135.051 45.7154 137.008 43.0459 139.601 41.3622C142.271 39.6028 145.714 38.8899 149.946 38.8899C152.873 38.8899 155.467 38.7534 157.878 38.4956C159.183 38.359 160.411 38.2377 161.655 38.0405C165.235 37.449 168.739 36.5389 172.91 35.3103C174.73 34.7188 176.489 34.3396 178.173 34.0818C179.796 33.8239 181.495 33.6874 183.239 33.4902C182.465 35.7047 181.874 38.3742 181.419 40.8314C180.964 42.9093 180.569 44.7901 180.19 45.776C180.054 45.9732 179.993 46.2311 179.872 46.4283C175.579 48.5062 172.712 52.5408 168.162 53.8452C166.342 54.3609 164.067 53.5267 161.458 53.193C160.29 52.9959 159.122 52.9959 157.878 53.0565C152.615 53.5116 147.155 56.3024 144.03 60.337C140.132 65.403 137.144 67.4962 133.959 68.7247C133.186 65.9946 132.73 63.2037 132.594 60.3977C132.457 56.8788 132.852 53.2385 133.959 49.5983L133.944 49.6135ZM40.3745 356.455C40.3138 356.971 40.238 357.366 40.238 357.76C39.5251 356.198 38.8122 354.772 37.9629 353.407C37.1893 352.178 36.3399 350.995 35.4298 349.964C35.8849 349.448 36.2034 348.735 36.2034 347.825C37.0528 347.764 37.5685 347.628 37.9629 347.431C37.9629 347.886 38.0994 348.341 38.2207 348.796C38.6151 349.645 39.3886 350.419 40.4352 350.813C40.4959 351.784 40.4959 352.77 40.4959 353.74C40.4352 354.651 40.4352 355.561 40.3593 356.471L40.3745 356.455ZM357.182 311.529C356.332 313.743 355.817 316.018 355.68 318.354C353.86 316.018 352.04 313.607 350.341 311.135C348.839 308.92 347.55 306.842 346.504 304.885L345.851 303.718L345.336 304.946C343.516 309.694 342.272 314.76 341.696 319.901C341.18 324.846 341.301 329.851 342.211 334.66C342.803 338.103 344.092 341.364 345.988 344.276C347.747 347.006 350.023 349.478 352.874 351.754C352.556 352.072 352.161 352.345 351.828 352.664C348.9 355.394 346.564 358.715 344.805 362.811C344.805 361.582 344.805 360.338 344.744 359.11C344.684 357.032 344.547 355.015 344.289 352.997C344.684 352.8 345.063 352.542 345.336 352.148C345.791 351.556 346.109 350.646 346.109 349.736C346.109 348.826 345.791 347.916 345.336 347.325C344.168 345.899 342.211 345.899 340.983 347.264C340.785 347.522 340.664 347.78 340.467 348.037C340.27 348.492 340.148 349.084 340.148 349.66C340.148 350.176 340.285 350.768 340.467 351.223C340.664 351.541 340.785 351.814 341.058 352.072C341.574 352.724 342.287 353.119 343.076 353.179C343.273 355.136 343.47 357.153 343.531 359.095V361.112C343.334 360.202 343.076 359.292 342.818 358.442C342.166 356.562 341.453 354.666 340.482 352.921C340.224 352.406 339.966 351.814 339.633 351.298C338.662 349.676 337.615 348.113 336.387 346.551C333.717 358.063 329.622 369.045 324.359 379.389C324.42 384.394 324.95 389.005 326.24 392.721C327.605 396.559 329.819 399.35 333.262 400.593C325.845 404.37 319.733 409.118 314.985 414.836C314.788 413.41 314.788 412.045 314.849 410.68C314.909 408.921 315.167 407.161 315.501 405.477C316.35 405.477 317.185 405.22 317.776 404.628C318.292 404.112 318.625 403.324 318.823 402.216C318.823 401.822 318.823 401.443 318.762 401.048C318.701 400.336 318.368 399.744 317.988 399.289C317.533 398.773 316.942 398.515 316.365 398.379C316.168 398.379 315.971 398.379 315.713 398.44C314.94 398.5 314.288 398.955 313.757 399.608C313.302 400.26 312.983 401.033 312.907 401.943C312.907 402.793 313.104 403.703 313.559 404.355C313.757 404.613 314.015 404.871 314.333 405.068C313.939 406.888 313.681 408.769 313.559 410.589C313.499 412.409 313.559 414.229 313.878 416.11C312.452 417.93 311.148 419.887 309.904 421.904C310.162 418.324 310.041 415.079 309.51 412.151C309.115 409.618 308.402 407.343 307.432 405.326C303.458 410.27 299.105 414.942 294.494 419.31C294.63 421.98 295.009 424.255 295.54 426.333L292.492 421.191C292.097 421.585 291.718 421.904 291.263 422.298C274.23 437.572 253.48 448.887 230.668 454.803C218.959 457.851 206.673 459.49 194.053 459.49C181.434 459.49 169.467 457.927 157.894 454.939C134.808 449.024 113.938 437.648 96.7073 422.162C89.6239 415.852 83.117 408.829 77.3988 401.23C77.2016 408.39 77.5353 415.276 78.4454 421.646C78.051 420.933 77.596 420.145 77.0803 419.371C74.6686 415.534 72.0749 411.893 68.8291 408.708C69.2841 405.978 69.3448 403.051 68.8291 400.32C69.1476 400.123 69.4206 399.926 69.6026 399.608C70.452 398.44 70.3155 396.68 69.2841 395.634C68.1769 394.587 66.5539 394.663 65.6439 395.891C64.7945 397.12 64.931 398.819 65.9624 399.85C66.4174 400.305 67.0089 400.563 67.5853 400.624C67.9797 402.899 67.9797 405.371 67.7218 407.646C65.5073 405.69 63.1109 404.006 60.4413 402.58C58.5606 401.61 56.5432 400.76 54.3894 400.047C54.5259 398.364 54.3894 396.665 53.9344 394.981C55.2995 393.874 56.2702 391.993 56.9831 389.521C57.6353 387.049 58.0297 383.924 58.151 380.36C58.3482 375.157 58.0904 370.213 57.4988 365.404C54.6321 357.927 52.357 350.191 50.734 342.259C49.2324 344.079 47.9432 346.49 46.8359 349.418C45.668 352.603 44.758 356.38 44.1058 360.869C43.5142 359.823 42.9378 358.791 42.4221 357.745C42.1643 357.29 41.9064 356.835 41.7093 356.44C41.7093 355.53 41.7699 354.62 41.7699 353.71V350.98C43.135 350.98 44.1058 350.131 44.5608 349.099C44.8793 348.25 44.9551 347.279 44.6215 346.43C44.2271 345.322 43.2564 344.412 41.6334 344.352C40.5869 344.352 39.7526 344.61 39.1611 345.065C39.2218 344.867 39.2976 344.61 39.4189 344.352C40.329 341.682 41.4969 338.831 42.6648 335.827C44.6821 330.822 46.7601 325.62 48.0645 321.009C47.928 318.476 47.8673 315.867 47.8673 313.273C47.8673 310.224 48.0038 307.1 48.1252 304.036C47.9887 303.581 47.8673 303.126 47.6702 302.732C46.3051 299.289 44.3484 296.619 41.6183 294.147C40.511 297.529 39.3431 300.851 38.0994 304.218C38.0387 304.355 38.0387 304.476 37.9629 304.612C36.8556 307.676 35.7484 310.725 34.717 313.85C34.1254 315.806 33.6097 317.748 33.094 319.765C32.3811 312.606 31.1374 306.372 29.2566 301.23C32.0475 299.349 35.3085 296.422 37.9629 293.813L40.1773 291.599C43.044 288.474 45.3192 285.228 46.8814 282.104C48.2465 279.373 49.0959 276.583 49.4144 273.655C49.6116 272.29 49.6116 270.864 49.551 269.363C50.5217 272.154 51.3711 275.081 52.1598 278.008C59.3796 249.205 75.1843 223.708 96.7073 204.46C113.938 188.989 134.808 177.598 157.894 171.683C169.467 168.695 181.631 167.133 194.053 167.133C206.476 167.133 218.959 168.756 230.668 171.819C253.495 177.735 274.23 189.05 291.263 204.324C312.847 223.572 328.651 249.129 335.871 277.932C336.008 277.417 336.19 276.886 336.326 276.431C337.1 281.77 338.404 286.047 340.482 289.627C340.876 290.218 341.195 290.795 341.589 291.386C344.653 295.679 349.067 298.803 355.377 301.594C355.316 304.976 355.892 308.359 357.197 311.408V311.468L357.182 311.529Z\" fill=\"black\"><\/path><path d=\"M200.151 30.8812C198.012 31.852 198.467 34.1271 200.287 35.3102C202.426 36.6753 203.73 41.3621 204.519 46.1703C205.293 50.9177 205.566 55.8624 205.687 58.001C205.945 62.0356 206.005 66.1916 205.823 69.9077C205.687 73.1535 205.368 76.0809 204.853 78.3561C204.595 79.2661 204.337 80.1155 204.003 80.8284C203.29 82.6485 202.835 83.9529 204.853 85.9702C204.989 86.1067 205.171 86.2281 205.308 86.3646C205.763 86.6831 206.218 86.8803 206.733 86.8803C207.188 86.8803 207.704 86.6224 208.235 86.1067C208.432 85.9702 208.554 85.7882 208.69 85.591C209.6 84.4231 210.313 82.4665 210.768 79.8728C211.223 77.2033 211.481 73.8209 211.42 69.8015C211.42 64.3411 211.162 57.8949 210.192 51.661C209.221 45.427 207.659 39.3751 204.989 34.749C204.398 33.7024 203.685 32.4738 202.851 31.6245C202.077 30.9116 201.167 30.5172 200.181 30.9116L200.151 30.8812Z\" fill=\"#FFE200\"><\/path><path d=\"M219.975 113.135C219.125 113.59 217.245 115.092 217.108 115.547C217.108 115.092 215.606 113.408 214.772 112.68C207.81 112.089 200.924 111.831 194.023 111.831C187.122 111.831 180.175 112.089 173.349 112.68C172.5 113.333 170.938 115.092 170.938 115.547C170.801 115.031 168.92 113.59 168.01 113.135C153.51 114.637 139.268 117.428 125.48 121.463C124.707 121.66 123.857 122.828 123.918 123.419C123.918 124.071 125.419 123.419 126.512 123.161C127.937 122.843 127.422 124.132 128.134 124.329C128.59 124.39 129.181 124.329 130.546 123.935C130.607 124.39 129.636 124.648 128.863 125.497C127.952 126.544 127.558 127.772 129.575 127.636C131.138 127.575 131.714 127.12 132.306 127.378C133.352 127.772 132.503 128.349 134.323 127.894C154.026 123.283 174.047 120.932 194.008 120.932C217.214 120.932 240.497 124.117 263.187 130.366C261.367 127.636 265.144 127.241 267.086 127.954C268.056 128.349 272.88 130.821 276.323 130.366C279.766 129.911 278.598 128.485 276.717 127.317C274.381 125.891 271.378 125.436 270.665 125.497C268.906 125.634 261.504 123.677 261.822 122.448C265.205 123.358 268.784 124.466 272.227 124.587C255.513 118.793 237.888 115.031 219.944 113.135H219.975Z\" fill=\"#FFE200\"><\/path><path d=\"M176.671 69.7708C176.61 73.8054 176.868 77.1877 177.323 79.8421C177.839 82.4358 178.491 84.3924 179.401 85.5603C179.538 85.7575 179.72 85.9547 179.856 86.076C180.372 86.5917 180.903 86.8496 181.358 86.8496C181.874 86.8496 182.329 86.6524 182.784 86.3339C182.92 86.1973 183.102 86.076 183.239 85.9395C185.256 83.9222 184.801 82.6178 184.088 80.7977C183.77 80.0848 183.497 79.2354 183.239 78.3253C182.723 76.0502 182.389 73.1228 182.268 69.8769C182.071 66.176 182.131 62.0049 182.405 57.9703C182.541 55.8317 182.799 50.887 183.572 46.1395C184.225 42.3021 185.135 38.6012 186.56 36.5232C187.668 34.9609 190.079 30.2135 185.65 31.5786C185.332 32.0336 184.998 32.5493 184.74 33.1408C183.83 35.2795 183.178 38.3433 182.662 41.0735C182.207 43.2122 181.813 45.1688 181.358 46.276C179.341 50.8263 178.173 54.0722 177.46 57.5304C176.808 60.9128 176.686 64.5531 176.686 69.7556L176.671 69.7708Z\" fill=\"#FFE200\"><\/path><path d=\"M193.128 76.005C190.656 75.5499 188.836 73.4113 188.836 70.8631C188.836 68.0723 191.05 65.7213 193.78 65.6C190.914 65.4634 188.638 63.0669 188.638 60.2003C188.638 57.3336 190.853 54.9978 193.644 54.8006C191.05 54.5427 188.957 52.3889 188.957 49.7346C188.957 47.2622 190.777 45.1843 193.189 44.7292C191.232 44.4107 189.67 42.9091 189.215 41.0283C186.485 42.1356 185.059 44.9264 184.604 47.6566C184.012 51.8884 183.754 56.105 183.633 58.0616C183.436 62.0962 183.375 66.1915 183.497 69.8317C183.633 73.0169 183.952 75.8836 184.467 78.0223C184.664 78.9323 184.983 79.6452 185.241 80.3581C185.954 82.3147 186.545 83.7405 185.104 85.6971C185.817 85.4393 186.606 85.2421 187.379 85.1814C187.698 83.5585 188.487 82.2541 189.518 81.344C189.457 81.0861 189.457 80.8283 189.457 80.5704C189.457 78.356 191.02 76.4752 193.098 76.0201L193.128 76.005Z\" fill=\"#FFE200\"><\/path><path d=\"M203.594 78.0224C204.11 75.8838 204.443 73.0171 204.565 69.8319C204.701 66.1917 204.625 62.0964 204.428 58.0618C204.292 55.9231 203.973 50.9785 203.199 46.3523C203.063 45.3816 202.881 44.3957 202.684 43.4856C202.229 41.2105 200.803 40.0426 198.907 38.7988C199.423 41.529 197.678 44.1985 194.872 44.7142C197.284 45.1693 199.104 47.2472 199.104 49.7196C199.104 52.3891 197.026 54.5277 194.417 54.7856C197.208 54.9827 199.423 57.3186 199.423 60.1853C199.423 63.0519 197.148 65.4484 194.281 65.5849C197.011 65.7215 199.226 68.0573 199.226 70.8481C199.226 73.3811 197.405 75.5349 194.933 75.99C197.011 76.445 198.573 78.3258 198.573 80.5403C198.573 80.7981 198.573 81.056 198.513 81.3138C199.559 82.2239 200.333 83.5283 200.651 85.1512C201.501 85.2119 202.274 85.4091 202.987 85.7428C201.486 83.7862 202.016 82.2997 202.79 80.3431C203.048 79.6302 203.382 78.9173 203.564 78.0073L203.594 78.0224Z\" fill=\"#FFE200\"><\/path><path d=\"M95.3876 112.423C95.1298 112.741 94.5382 112.68 94.3411 112.286C93.2945 110.527 92.0659 109.419 90.7008 108.843C89.3357 108.267 87.91 108.191 86.469 108.585C85.0433 108.904 83.6782 109.692 82.5709 110.8C81.0693 112.165 79.9773 114.121 79.7043 116.26C79.6436 116.851 79.5677 117.428 79.5677 118.141C79.5677 119.187 79.7043 120.279 80.0835 121.189C80.4778 121.963 81.0542 122.555 81.9642 122.691C82.1007 122.691 82.2828 122.752 82.4193 122.752C83.0108 122.752 83.5265 122.555 83.9815 122.236C84.3759 121.978 84.6337 121.644 84.8309 121.265C85.0281 120.871 85.1495 120.416 85.1495 119.961C85.1495 119.445 85.0129 118.914 84.6944 118.459C84.5579 118.323 84.5579 117.944 84.6338 117.807C85.4073 116.123 86.4539 115.138 87.6825 114.758C88.7897 114.364 90.0941 114.44 91.3227 114.956C92.2934 115.274 93.2793 115.926 94.1135 116.639C95.5393 117.807 96.328 119.824 98.2088 118.065C98.8004 117.549 99.2554 116.897 99.5132 116.184C99.9076 115.335 101.076 115.79 100.681 116.639C100.363 117.549 99.7711 118.323 99.1189 118.975C96.5859 120.992 98.6032 120.992 98.6032 124.238C98.6032 124.633 98.6638 124.951 98.8004 125.285C99.5739 127.302 102.896 128.015 104.776 127.241C132.473 116.123 163.233 110.527 193.993 110.527C224.753 110.527 255.437 116.123 283.133 127.241C284.953 128.015 288.336 127.302 289.109 125.285C291.445 120.477 281.176 121.129 277.733 118.778C276.11 118.004 274.548 116.76 273.304 114.88C273.107 114.561 273.244 114.03 273.623 113.97C275.125 113.515 275.959 112.468 276.353 111.376C276.55 110.663 276.611 109.95 276.55 109.237C276.414 108.524 276.156 107.872 275.701 107.281C275.049 106.31 273.881 105.658 272.379 105.658C271.469 105.658 270.696 105.916 270.043 106.31C269.452 106.704 268.997 107.22 268.618 107.872C268.299 108.524 268.102 109.237 268.102 109.95C268.102 110.724 268.36 111.512 268.815 112.225C269.012 112.544 268.815 113.075 268.42 113.135C263.536 114.637 259.441 114.819 255.877 113.727C252.297 112.68 249.249 110.284 246.382 106.446C246.063 105.991 246.64 105.279 247.231 105.536C250.28 107.099 252.889 106.507 254.572 105.081C255.482 104.308 256.135 103.322 256.529 102.215C256.984 101.107 257.121 99.9395 256.923 98.893C256.666 96.9363 255.3 95.192 252.692 94.6005C252.434 94.5398 252.176 94.2061 252.176 93.9483C252.373 91.7338 251.584 90.1109 250.356 89.0036C249.643 88.4121 248.854 88.0329 248.02 87.8357C247.11 87.6385 246.2 87.6385 245.35 87.8357C243.727 88.2908 242.287 89.398 241.513 91.476C241.452 91.7338 241.058 91.931 240.8 91.8703C238.131 91.2181 236.189 92.1888 235.082 93.7511C234.43 94.7218 234.035 95.9656 233.975 97.1942C233.914 98.4228 234.111 99.6665 234.688 100.774C235.658 102.791 237.812 104.277 241.255 104.02C241.847 103.959 242.165 104.869 241.65 105.188C238.07 107.523 233.656 108.691 229.288 108.115C225.511 107.599 221.81 105.703 218.883 102.063C218.564 101.669 218.822 101.016 219.338 101.016C221.219 100.88 222.387 99.7879 222.917 98.4834C223.115 97.8919 223.175 97.2548 223.175 96.6026C223.175 95.9504 222.978 95.3741 222.72 94.7825C222.129 93.4781 220.9 92.5074 219.019 92.5074C217.457 92.5074 216.289 93.2202 215.637 94.191C215.182 94.7825 214.924 95.4196 214.863 96.1476C214.727 96.8605 214.803 97.5734 215 98.2256C215.394 99.3935 216.304 100.44 217.791 100.819C218.306 101.016 218.382 101.729 217.927 101.987C213.377 104.717 209.145 106.082 205.247 105.627C201.349 105.233 197.769 102.958 194.584 98.3469C194.19 97.8312 194.979 97.0425 195.494 97.4369C196.268 98.1497 197.512 98.4834 198.877 98.4834C199.923 98.4834 201.015 98.2862 202.001 97.8312C202.972 97.4369 203.882 96.8605 204.534 96.0111C205.308 95.101 205.763 93.8725 205.763 92.3102C205.763 90.7479 205.111 89.1856 204.079 88.0784C203.033 87.0318 201.668 86.3948 200.045 86.4555C199.787 86.4555 199.453 86.1369 199.453 85.8639C199.256 84.4988 198.74 83.4523 198.027 82.6787C197.254 84.1045 195.813 85.0904 194.053 85.151C195.282 90.217 195.221 89.8379 200.621 91.0664C198.088 91.0058 195.676 91.1271 193.993 93.0837C192.309 91.1271 189.897 91.0058 187.364 91.0664C192.764 89.8379 192.703 90.217 193.932 85.151C192.173 85.0904 190.747 84.1045 189.958 82.6787C189.245 83.4523 188.73 84.4988 188.532 85.8639C188.532 86.1218 188.214 86.4555 187.941 86.4555C186.439 86.3948 184.953 86.9712 183.846 87.8812C182.875 88.7306 182.283 89.8985 182.344 91.2029C182.344 92.113 182.799 92.8866 183.451 93.5388C183.77 93.7966 184.164 94.0545 184.558 94.191C184.953 94.3882 185.332 94.4488 185.726 94.3882C186.242 94.3882 186.834 94.191 187.289 93.6753C187.683 93.2202 188.517 93.6753 188.335 94.2668C188.199 95.0404 188.274 95.7684 188.532 96.3448C188.73 96.8605 189.124 97.3155 189.503 97.6492C189.958 97.9071 190.413 98.1042 190.929 98.1042C191.384 98.1042 191.9 97.9677 192.355 97.5885C192.87 97.1942 193.583 97.9829 193.265 98.4986C190.079 103.049 186.5 105.263 182.602 105.718C178.704 106.113 174.472 104.672 169.982 102.018C169.527 101.76 169.588 101.047 170.119 100.85C171.545 100.455 172.455 99.4238 172.849 98.2559C173.107 97.6037 173.167 96.8908 173.046 96.1779C172.925 95.4651 172.652 94.8129 172.273 94.2213C171.56 93.2506 170.452 92.5377 168.89 92.5377C167.009 92.5377 165.766 93.5084 165.113 94.8128C164.856 95.4044 164.719 95.9808 164.719 96.633C164.658 97.2852 164.78 97.9374 164.977 98.5138C165.493 99.8182 166.661 100.925 168.557 101.047C169.012 101.047 169.33 101.699 169.012 102.093C166.084 105.734 162.383 107.614 158.606 108.145C154.253 108.737 149.824 107.554 146.184 105.218C145.729 104.899 145.987 103.989 146.639 104.05C150.022 104.368 152.16 102.943 153.207 100.925C153.798 99.8182 154.056 98.4531 153.98 97.2245C153.844 95.9201 153.465 94.6915 152.812 93.7056C151.705 92.1433 149.764 91.2333 147.155 91.8855C146.897 91.9462 146.503 91.749 146.442 91.4911C145.668 89.4132 144.228 88.3059 142.605 87.8509C141.755 87.6537 140.845 87.6537 139.935 87.8509C139.086 88.0481 138.312 88.4424 137.599 89.0188C136.371 90.126 135.582 91.749 135.779 93.9635C135.779 94.2213 135.521 94.555 135.263 94.6157C132.67 95.1314 131.365 96.8908 131.032 98.8475C130.834 99.894 130.971 101.062 131.35 102.169C131.745 103.216 132.397 104.247 133.231 105.036C134.915 106.537 137.523 107.114 140.648 105.627C141.164 105.37 141.755 106.082 141.422 106.537C138.555 110.314 135.506 112.711 131.927 113.757C128.347 114.865 124.312 114.667 119.383 113.166C118.989 113.105 118.867 112.574 119.064 112.256C119.519 111.543 119.717 110.754 119.717 109.981C119.717 109.268 119.58 108.555 119.201 107.903C118.882 107.25 118.427 106.735 117.775 106.34C117.184 105.946 116.41 105.688 115.5 105.688C113.998 105.688 112.83 106.34 112.118 107.311C111.723 107.903 111.465 108.54 111.344 109.268C111.283 109.981 111.283 110.693 111.541 111.406C111.936 112.514 112.77 113.545 114.271 114C114.59 114.061 114.787 114.592 114.59 114.91C113.361 116.791 111.799 118.035 110.161 118.808C108.144 119.779 106.005 120.113 104.048 120.037C103.533 120.037 103.199 119.445 103.533 119.066C104.579 117.762 105.156 116.139 105.156 114.576C105.156 113.803 105.019 113.075 104.761 112.438C104.443 111.785 104.048 111.209 103.533 110.754C102.683 110.163 101.652 109.783 100.211 109.783C99.1037 109.723 98.2543 109.981 97.4808 110.436C96.7072 110.891 95.9792 111.603 95.3421 112.453L95.3876 112.423Z\" fill=\"#FFE200\"><\/path><path d=\"M197.739 39.7995C197.739 37.7822 196.055 36.0986 194.038 36.0986C192.021 36.0986 190.337 37.7822 190.337 39.7995C190.337 41.8168 192.021 43.5763 194.038 43.5763C196.055 43.5763 197.739 41.8927 197.739 39.7995Z\" fill=\"#FFE200\"><\/path><path d=\"M160.472 491.387C159.956 492.555 160.214 493.86 161.064 494.77C161.716 495.422 162.565 495.741 163.339 496.074C162.034 498.744 160.153 499.972 157.09 499.654C153.768 499.259 151.174 497.773 149.551 495.68C148.702 494.633 148.126 493.465 147.792 492.237C147.473 491.008 147.337 489.704 147.473 488.399C147.792 485.609 149.293 482.802 152.024 480.664C155.012 478.252 161.003 476.311 166.387 474.491C168.526 473.778 170.619 473.126 172.303 472.473C174.836 471.503 176.08 469.607 176.277 467.862C176.413 466.694 176.019 465.39 174.972 464.677C174.062 464.086 172.697 464.086 170.938 465.132C167.161 467.347 163.657 468.712 160.017 470.077C158.136 470.85 156.119 471.578 154.102 472.488C149.491 474.566 145.653 477.949 143.242 481.923C140.314 486.731 139.146 492.646 141.482 497.849C142.787 500.716 145.001 503.309 148.444 505.387C152.084 507.662 156.513 508.117 160.351 507.147C163.475 506.297 166.524 504.477 168.223 501.686C170.179 498.562 170.301 493.299 167.631 490.508C165.553 488.369 161.716 488.49 160.472 491.418V491.387Z\" fill=\"#FFE200\"><\/path><path d=\"M233.96 472.458C231.942 471.548 229.925 470.835 228.044 470.046C224.404 468.681 220.885 467.316 217.123 465.102C214.651 463.676 211.663 463.6 208.736 463.676C210.692 465.815 211.921 468.165 214.135 470.243C215.045 471.154 215.895 471.866 216.729 472.519C218.231 473.565 219.914 474.02 221.613 474.597C227.073 476.356 233.125 478.298 236.053 480.649C238.783 482.787 240.284 485.593 240.603 488.384C240.861 490.978 240.148 493.587 238.525 495.664C236.902 497.742 234.293 499.244 230.987 499.638C227.923 499.957 226.042 498.728 224.738 496.059C225.511 495.74 226.361 495.407 227.013 494.754C227.862 493.844 228.12 492.54 227.604 491.372C226.376 488.445 222.538 488.323 220.445 490.462C217.776 493.253 217.912 498.531 219.854 501.641C221.537 504.431 224.601 506.251 227.726 507.101C231.563 508.072 235.977 507.617 239.632 505.341C243.075 503.264 245.29 500.655 246.594 497.803C248.93 492.601 247.762 486.685 244.835 481.877C242.423 477.918 238.586 474.536 233.975 472.443L233.96 472.458Z\" fill=\"#FFE200\"><\/path><path d=\"M219.52 489.567C220.369 488.718 221.34 488.202 222.311 487.944C223.357 487.687 224.328 487.687 225.299 487.884C226.148 488.142 226.922 488.597 227.574 489.188C228.09 489.704 228.484 490.295 228.742 490.948C229.06 491.66 229.197 492.51 229.06 493.359C228.924 494.209 228.545 494.982 227.892 495.695C227.498 496.014 227.043 496.408 226.467 496.742C226.861 497.333 227.377 497.712 227.892 497.97C228.742 498.425 229.713 498.486 230.759 498.425C233.747 498.031 236.022 496.742 237.524 494.922C238.237 494.011 238.752 493.041 239.025 491.933C239.344 490.826 239.42 489.719 239.283 488.551C239.025 486.079 237.721 483.606 235.249 481.665C232.519 479.45 226.542 477.57 221.203 475.81C220.43 475.552 219.702 475.355 219.323 475.219C217.958 474.764 216.987 474.248 216.001 473.596C215.091 472.944 214.242 472.17 213.21 471.184C212.164 470.138 211.193 469.106 210.222 467.999L210.161 467.938C209.449 467.741 208.66 467.544 207.947 467.347C207.628 467.286 207.355 467.15 207.037 467.089C208.599 468.06 210.086 469.227 211.39 470.532C215.819 474.885 218.61 480.998 218.61 487.702C218.61 488.87 218.549 490.113 218.352 491.281C218.67 490.629 219.065 490.053 219.52 489.598V489.567Z\" fill=\"#FFE200\"><\/path><path d=\"M210.541 474.612C206.187 473.247 201.759 472.018 197.269 471.29C194.084 470.699 195.646 471.882 194.144 474.475C192.84 476.751 191.475 479.086 189.988 481.498C188.82 483.455 187.577 485.396 186.287 487.353C185.893 488.005 185.772 488.46 186.424 488.854C187.334 489.37 188.563 489.446 189.549 489.507C195.145 490.022 200.469 492.753 205.156 495.816C206.46 496.59 208.796 498.547 210.101 498.683C210.753 498.82 211.329 498.486 212.118 497.576H212.057C212.77 496.529 213.68 495.559 214.272 494.451C215.834 491.66 213.62 489.385 211.284 488.081C205.945 485.093 200.227 482.818 194.372 481.195C193.522 480.937 193.856 479.693 194.69 479.966C199.954 481.468 205.095 483.409 209.904 485.882C212.694 487.307 214.454 484.38 214.97 482.105C215.682 478.722 213.923 475.674 210.541 474.627V474.612Z\" fill=\"#FFE200\"><\/path><path d=\"M194.675 466.679C194.736 467.65 195.07 469.667 196.101 469.804C200.393 470.395 204.625 471.487 208.781 472.731C209.373 472.928 210.01 472.928 210.404 472.337C210.541 472.14 210.662 471.563 210.465 471.366C206.491 467.468 201.167 464.996 195.252 464.662C195.252 464.662 195.231 464.682 195.191 464.723C194.675 465.041 194.599 465.951 194.675 466.679Z\" fill=\"#FFE200\"><\/path><path d=\"M204.625 497.105C199.165 494.769 196.829 499.062 192.597 500.882C189.078 502.383 184.983 503.293 181.221 503.157C181.737 504.325 182.587 505.371 183.633 506.282L184.027 505.766C184.543 504.992 185.59 505.766 185.074 506.479L184.619 507.07C184.938 507.328 185.211 507.525 185.529 507.722C185.787 507.465 185.923 507.07 185.984 506.676C186.181 505.826 187.41 506.084 187.213 506.934C187.152 507.449 186.955 507.98 186.621 508.435C187.076 508.693 187.531 508.951 188.047 509.148C188.305 508.632 188.502 508.102 188.563 507.525C188.699 506.615 189.988 506.812 189.791 507.722C189.731 508.435 189.473 509.088 189.2 509.679C189.913 509.998 190.625 510.271 191.278 510.453C191.535 509.679 191.672 508.951 191.596 508.238C191.535 507.328 192.825 507.267 192.901 508.102C192.901 508.951 192.84 509.785 192.582 510.635C193.037 510.695 193.553 510.695 194.008 510.695H194.523C194.721 509.725 194.781 508.739 194.842 507.768C194.842 506.858 196.071 506.919 196.071 507.829C196.071 508.739 196.01 509.709 195.813 510.619C196.662 510.559 197.496 510.422 198.346 510.301C198.406 509.194 198.406 508.086 198.285 506.979C198.224 506.069 199.453 505.933 199.589 506.843C199.65 507.889 199.65 508.921 199.65 509.967C200.363 509.77 201.152 509.573 201.865 509.315C201.865 508.147 201.804 506.903 201.546 505.735C201.349 504.886 202.653 504.628 202.775 505.538C203.033 506.585 203.093 507.677 203.169 508.784C203.882 508.466 204.671 508.132 205.308 507.738C205.368 506.63 205.505 505.66 205.171 504.613C204.974 503.703 206.218 503.385 206.4 504.295C206.658 505.265 206.658 506.175 206.658 506.964C207.31 506.509 207.826 505.66 207.704 504.886C207.644 504.689 207.568 504.492 207.507 504.234C207.113 503.384 208.281 502.869 208.614 503.718C208.614 503.718 208.634 503.764 208.675 503.855C208.933 503.202 209.13 502.55 209.069 501.898C209.009 499.684 206.476 497.863 204.58 497.09L204.625 497.105Z\" fill=\"#FFE200\"><\/path><path d=\"M186.105 501.458C189.291 500.943 195.145 499.244 196.829 496.119C197.542 494.891 197.026 492.798 195.661 492.282C192.537 491.053 188.32 490.204 184.862 490.598C183.633 490.735 182.526 491.19 181.358 491.372C180.964 491.433 180.584 491.508 180.19 491.508C178.112 491.645 175.958 490.796 174.472 489.37C173.82 488.718 174.669 487.808 175.321 488.46C176.626 489.688 178.446 490.341 180.129 490.28C180.584 490.28 180.979 490.219 181.358 490.083C182.526 489.825 183.633 489.112 184.346 488.005C185.969 485.593 187.471 483.197 188.896 480.846C190.322 478.51 191.763 476.159 193.128 473.823C194.493 471.351 194.69 467.847 192.081 466.209C191.945 466.148 191.884 466.072 191.763 466.072C190.853 465.617 187.865 465.617 188.381 467.301C188.699 468.469 190.064 469.121 190.337 470.486C190.474 471.335 190.277 472.17 189.685 473.535C188.123 476.917 186.242 480.163 184.225 483.288C183.709 484.061 182.662 483.348 183.178 482.575C185.195 479.526 187.015 476.401 188.517 473.019C188.972 471.912 189.169 471.26 189.033 470.744C188.896 469.97 187.926 468.863 187.273 468.332C185.514 467.104 183.299 467.559 181.358 468.59C179.856 469.364 178.491 470.471 177.581 471.381C173.349 475.537 170.756 481.27 170.756 487.641C170.756 491.539 171.726 495.255 173.486 498.44C175.048 500.973 178.233 501.762 181.358 501.822C183.042 501.883 184.74 501.686 186.105 501.428V501.458ZM178.946 479.162C179.598 478.191 180.311 477.281 180.903 476.295C181.039 476.098 181.221 475.84 181.358 475.643C181.813 474.87 182.268 474.141 182.723 473.429C183.178 472.655 184.285 473.292 183.77 474.081C183.178 475.052 182.602 476.037 182.01 477.008C181.752 477.327 181.555 477.6 181.358 477.918C180.903 478.57 180.448 479.223 179.993 479.875C179.401 480.648 178.37 479.875 178.946 479.162Z\" fill=\"#FFE200\"><\/path><path d=\"M174.851 472.534C174.26 472.989 173.547 473.383 172.773 473.641C171.014 474.293 168.936 475.006 166.797 475.719C161.534 477.478 155.618 479.42 152.812 481.634C150.34 483.591 149.036 486.063 148.778 488.52C148.641 489.688 148.717 490.796 149.036 491.903C149.294 493.01 149.809 493.981 150.537 494.891C152.812 497.758 157.818 499.183 159.638 495.027C159.319 494.512 159.122 493.92 158.986 493.344C158.849 492.494 158.986 491.66 159.304 490.932C159.562 490.28 159.956 489.704 160.472 489.173C161.124 488.581 161.898 488.126 162.747 487.868C163.718 487.671 164.704 487.671 165.735 487.929C166.706 488.187 167.692 488.703 168.526 489.552C168.981 490.007 169.376 490.598 169.694 491.236C169.497 490.068 169.436 488.824 169.436 487.656C169.436 481.938 171.454 476.675 174.836 472.503L174.851 472.534Z\" fill=\"#FFE200\"><\/path><path d=\"M199.165 459.459C197.481 459.459 195.722 459.52 194.023 459.52C192.461 459.52 190.838 459.52 189.276 459.459C186.94 459.398 185.12 462.326 187.455 464.267C189.533 463.676 191.748 463.357 194.023 463.357C199.165 463.357 204.428 465.041 209.373 466.421C207.75 463.888 202.35 459.338 199.165 459.459Z\" fill=\"#FFE200\"><\/path><path d=\"M153.586 471.29C155.664 470.38 157.681 469.667 159.638 468.878C163.217 467.513 166.661 466.148 170.361 463.994C170.619 463.858 170.877 463.737 171.135 463.6C171.529 462.751 171.59 461.977 171.332 461.188C169.967 461.249 168.86 461.386 167.95 461.507C165.811 461.765 164.962 461.704 164.765 459.368C164.704 458.853 164.704 458.2 164.628 457.351C163.718 457.745 162.869 458.064 162.216 458.398C161.367 458.853 160.654 459.308 160.078 459.763C159.941 459.899 159.623 459.899 159.426 459.823C157.469 458.974 155.33 458.2 153.176 457.806C151.099 457.351 148.945 457.214 146.867 457.487C146.351 457.624 145.957 456.972 146.275 456.517C146.73 455.804 147.246 455.091 147.837 454.378C148.035 454.12 148.232 453.862 148.49 453.605C148.095 453.665 147.716 453.741 147.322 453.862C146.351 454.06 145.502 454.317 144.592 454.636C144.076 454.772 143.621 454.181 143.879 453.726L145.244 451.254C144.076 451.314 142.908 451.511 141.801 451.769C140.375 452.027 138.873 452.482 137.448 453.074C136.993 453.271 136.401 452.679 136.674 452.224L138.297 448.448L138.16 448.387C136.401 448.705 134.642 449.1 132.897 449.494C132.442 449.555 132.048 449.1 132.184 448.645L132.958 446.112C132.761 445.975 132.564 445.915 132.366 445.793C130.683 446.9 129.121 447.613 127.68 448.008C126.375 448.265 125.147 448.265 124.161 447.81C123.114 447.355 122.341 446.445 121.886 445.08C121.491 443.912 121.37 442.289 121.567 440.196C121.506 440.196 121.431 440.136 121.37 440.136L119.413 441.759C119.019 442.077 118.367 441.759 118.367 441.304L118.169 438.24C118.033 438.103 117.912 438.043 117.775 437.982C117.381 438.3 116.926 438.695 116.471 439.089C116.334 439.226 116.213 439.286 116.152 439.347C115.834 439.665 115.181 439.408 115.106 438.953C115.045 438.103 115.045 437.33 115.106 436.617C114.453 437.072 113.801 437.466 113.028 437.724C112.633 437.86 112.178 437.587 112.178 437.208C112.118 436.238 112.042 435.252 112.118 434.342C111.92 434.144 111.663 434.023 111.465 433.887C110.692 434.281 109.903 434.539 109.13 434.539C108.219 434.599 107.309 434.402 106.521 433.947C105.747 433.492 105.095 432.901 104.64 432.066C104.048 431.02 103.73 429.791 103.927 428.29C100.878 425.878 97.951 423.406 95.0843 420.812C94.9478 421.525 94.7658 422.177 94.4927 422.89C93.5827 425.878 92.2783 428.35 90.5947 430.959C89.1689 433.037 87.9858 435.054 87.0758 437.39C86.3022 439.271 84.8613 442.593 85.5742 444.61C86.1657 446.37 88.3043 446.43 89.6694 445.657C90.261 444.094 90.898 442.608 91.4896 441.106C92.2631 439.347 92.9911 437.724 93.704 436.222C94.0984 435.373 95.2056 435.965 94.8113 436.738C94.0984 438.3 93.3855 439.923 92.6726 441.546C92.0204 443.23 91.3075 444.929 90.6553 446.552C90.3368 447.462 90.4581 449.342 90.9132 450.192C91.3075 451.102 92.0811 451.496 93.0518 451.299C94.1591 451.041 95.0691 450.389 95.4635 449.418C95.9792 448.053 96.51 446.749 97.0864 445.52C97.6021 444.155 98.1937 442.79 98.8459 441.364C99.1644 440.515 100.347 441.046 100.014 441.88C99.4222 443.184 98.8459 444.549 98.2543 445.975C97.6628 447.401 97.0864 448.842 96.4949 450.268C95.9792 451.436 95.782 452.937 96.0399 454.242C96.237 455.288 96.8134 456.198 97.7235 456.835C98.77 457.487 100.256 456.244 100.59 455.334C100.909 454.424 101.182 453.514 101.5 452.603L102.152 450.647C102.471 449.797 103.715 450.192 103.381 451.041L102.668 453.059C102.41 453.908 102.077 454.818 101.758 455.728C101.303 457.093 101.167 458.519 101.364 459.884C101.622 461.113 102.137 462.356 103.047 463.327C103.7 464.101 104.276 464.829 105.262 464.374C105.914 464.116 106.49 463.524 106.688 462.948C107.461 460.809 108.25 458.519 108.963 456.32C109.418 455.015 109.812 453.787 110.131 452.998C110.388 452.148 111.632 452.543 111.299 453.392C110.844 454.757 110.525 455.728 110.191 456.714C109.418 458.928 108.69 461.067 107.916 463.342C107.4 464.768 107.4 466.072 107.719 466.922C108.113 467.892 108.887 468.347 109.858 468.287C111.162 468.15 112.451 467.119 112.588 465.814C112.724 464.586 112.906 463.084 113.24 461.461C113.634 459.505 114.15 457.305 114.742 454.894C114.999 454.044 116.243 454.378 115.97 455.212C115.379 457.548 114.863 459.763 114.469 461.719C114.15 463.539 113.877 465.162 113.816 466.527C113.756 467.498 113.877 468.15 114.211 468.484C114.529 468.939 115.06 469 115.576 468.803C116.622 468.484 117.199 467.437 117.714 466.467C118.488 464.965 119.14 463.281 119.671 461.461C120.263 459.247 120.778 456.911 121.173 454.242C121.309 453.392 122.538 453.589 122.401 454.439C122.007 457.169 121.491 459.581 120.9 461.78C120.308 463.737 119.671 465.481 118.822 467.043C117.851 468.924 118.23 472.898 121.097 470.623C122.978 469.197 125.071 465.481 126.299 463.281C126.618 462.629 126.952 462.114 127.149 461.856C127.604 461.082 128.711 461.719 128.195 462.508C127.998 462.826 127.74 463.281 127.422 463.934C126.315 465.814 124.692 468.818 122.811 470.698C121.643 472.003 119.823 474.217 120.217 476.038C120.414 476.948 121.127 477.463 122.037 477.463C123.721 477.524 124.965 475.901 125.814 474.597C126.982 472.64 128.286 470.896 129.591 469.136C131.017 467.255 132.457 465.435 133.883 463.676C134.475 463.024 135.445 463.812 134.854 464.525C133.352 466.285 131.927 468.105 130.622 469.925C129.318 471.548 128.089 473.307 126.921 475.188C126.148 476.356 124.843 477.403 124.449 478.707C124.055 479.875 124.13 480.785 124.449 481.437C124.707 482.029 125.298 482.347 125.951 482.287C127.058 482.15 128.089 481.119 128.681 480.269C130.501 477.676 132.382 475.203 134.399 472.731C136.356 470.319 138.494 467.983 140.648 465.708C141.3 465.056 142.21 465.966 141.558 466.618C139.419 468.833 137.326 471.169 135.385 473.58C133.368 475.916 131.547 478.464 129.727 480.997C129.212 481.847 128.559 482.423 127.968 482.817C127.194 484.638 127.452 486.716 128.226 488.02C128.544 488.414 128.878 488.733 129.196 488.991C131.077 489.961 132.579 486.579 133.034 485.411C134.202 482.544 135.764 480.072 137.584 477.933C139.465 475.856 141.619 474.035 143.955 472.412C144.212 472.215 144.47 472.018 144.865 472.549C145.183 473.065 144.925 473.262 144.667 473.459C142.453 475.021 140.314 476.781 138.555 478.798C136.795 480.876 135.309 483.151 134.262 485.881C133.61 487.565 131.927 489.203 133.671 490.887C133.989 491.205 134.444 491.478 134.899 491.6C135.354 491.797 135.87 491.797 136.401 491.736C137.448 491.6 138.479 490.826 139.131 489.142C139.526 486.473 140.557 483.743 142.059 481.27C144.652 477.114 148.626 473.535 153.51 471.32L153.586 471.29Z\" fill=\"#FFE200\"><\/path><path d=\"M267.055 453.483C261.595 450.753 255.68 449.054 251.19 447.886H251.129C251.387 448.66 251.19 449.388 251.19 450.222C251.129 450.616 250.674 450.935 250.28 450.738C249.309 450.283 248.521 449.828 247.747 449.373C248.141 450.222 248.399 451.132 248.596 452.239C248.657 452.694 248.278 453.089 247.823 452.952C246.518 452.694 245.229 452.3 243.985 451.906C243.728 451.845 242.939 451.314 242.681 451.253C243.394 451.966 244.638 453.074 245.548 453.923C245.942 454.317 245.411 455.152 244.895 454.97C242.817 454.257 241.255 453.407 239.435 452.437C240.148 453.802 241.195 455.303 242.165 456.532C242.484 457.047 241.771 457.836 241.255 457.442C239.374 456.213 237.554 454.848 235.795 453.407C235.537 453.468 235.279 453.604 235.021 453.665C235.416 454.712 235.871 455.743 236.326 456.729C236.584 457.321 235.673 457.897 235.279 457.442C234.43 456.395 233.596 455.364 232.867 454.257C231.639 454.575 230.395 454.909 229.167 455.227C230.334 456.456 231.578 457.639 232.807 458.746C233.52 459.338 232.67 460.309 231.957 459.717C230.456 458.413 229.091 457.048 227.801 455.561C226.831 455.819 225.845 456.016 224.935 456.213L228.378 459.99C228.969 460.642 228.059 461.492 227.407 460.839L223.433 456.547C222.129 456.805 220.764 457.063 219.399 457.321C219.914 457.715 220.445 458.17 221.022 458.549C222.326 459.52 223.615 460.43 225.056 461.34C225.83 461.795 225.117 462.902 224.343 462.447C222.917 461.537 221.552 460.566 220.248 459.58C219.399 458.928 218.564 458.276 217.776 457.563C216.805 457.76 215.758 457.882 214.788 458.018C215.637 459.58 216.547 460.946 217.654 462.174C219.08 463.797 220.642 465.162 222.462 466.269C222.66 466.406 222.857 466.527 223.054 466.664C224.874 467.513 226.694 468.165 228.514 468.878C230.471 469.652 232.412 470.38 234.49 471.29C239.374 473.504 243.333 477.084 245.942 481.24C247.565 483.909 248.612 486.837 248.991 489.688C249.249 491.963 249.051 494.239 248.475 496.453C249.188 497.166 250.432 496.65 251.205 496.135C252.707 495.088 253.875 492.692 254.527 490.159C255.3 487.17 255.437 483.909 254.785 482.089C253.025 477.478 250.295 473.762 246.716 471.032C243.136 468.241 238.722 466.285 233.58 465.056C232.67 464.859 232.989 463.63 233.838 463.827C239.177 465.056 243.788 467.073 247.489 470.001C251.266 472.928 254.117 476.765 255.938 481.634C256.256 482.484 256.393 483.652 256.453 484.88C256.453 485.593 256.848 486.245 257.56 486.64C258.865 487.489 259.578 485.472 259.775 484.501C260.548 480.209 259.32 476.174 257.045 472.867C254.117 468.438 249.309 465.132 244.88 463.63C243.97 463.372 244.425 462.129 245.275 462.462C249.961 464.025 254.967 467.528 258.152 472.155C260.685 475.992 262.05 480.603 260.822 485.548C260.624 486.321 260.564 486.852 261.019 487.626C261.216 488.081 261.671 488.475 262.187 488.338C264.522 487.883 264.977 483.727 265.175 481.968C265.432 480.148 265.569 478.267 265.569 476.31C265.508 473.838 265.175 471.366 264.007 469.348C262.323 466.163 257.181 463.691 253.086 461.613C251.857 461.021 250.674 460.445 249.704 459.854C248.93 459.459 249.506 458.291 250.295 458.746C251.266 459.338 252.434 459.853 253.678 460.506C257.909 462.584 263.233 465.253 265.19 468.757C266.418 470.971 266.813 473.641 266.873 476.295C266.873 478.252 266.676 480.269 266.418 482.15C266.282 483.652 267.465 484.289 268.633 483.318C270.514 481.756 271.757 478.768 272.273 475.643C272.789 472.2 272.531 468.56 271.363 466.482C269.998 463.949 268.041 461.871 265.645 460.111C263.233 458.428 260.382 456.987 257.257 455.758C256.408 455.44 256.863 454.257 257.712 454.59C260.897 455.819 263.885 457.32 266.358 459.141C268.951 460.961 271.045 463.175 272.531 465.905C273.441 467.589 273.896 470.259 273.76 472.989C273.76 473.702 273.502 474.096 274.215 474.612C274.988 475.203 275.898 475.522 276.748 474.748C277.203 474.293 277.597 473.58 277.915 472.792C278.628 470.714 278.826 467.908 278.568 465.966C277.915 460.566 272.91 456.471 267.055 453.483Z\" fill=\"#FFE200\"><\/path><path d=\"M281.1 455.167C279.22 453.028 276.55 451.072 272.91 449.449C271.09 448.6 269.27 447.432 267.51 446.264C266.54 445.611 265.554 445.035 264.583 444.307C263.612 443.594 262.96 443.139 261.656 443.139C261.003 443.139 260.745 443.336 260.882 443.989C261.079 444.641 261.656 445.414 261.989 446.067C261.14 446.067 260.488 446.006 259.653 445.748C258.607 445.49 257.575 445.156 257.378 445.809C256.923 446.855 259.198 448.857 260.245 449.191C262.717 450.101 265.25 451.148 267.662 452.376C273.835 455.501 279.114 459.915 279.887 465.83C279.948 466.679 280.024 467.65 279.948 468.697C280.918 469.47 281.176 469.804 282.284 468.757C283.785 467.256 285.074 464.662 284.619 462.448C284.028 459.854 282.996 457.382 281.1 455.167Z\" fill=\"#FFE200\"><\/path><path d=\"M298.467 436.117C297.952 433.902 297.163 431.763 295.995 430.065C294.888 428.502 293.386 427.471 291.506 427.334C290.99 427.334 290.459 427.395 289.883 427.532C289.17 427.668 288.517 428.047 288.26 428.76C287.865 429.67 288.396 431.172 289.109 431.748C290.671 432.977 292.097 434.615 293.401 436.359C294.964 438.498 296.329 440.712 297.102 442.472C297.3 442.866 297.497 443.321 297.694 443.837C299.12 444.231 298.998 443.973 298.998 442.669C298.998 442.472 298.998 442.214 299.059 441.956C299.12 440.333 298.922 438.179 298.467 436.101V436.117Z\" fill=\"#FFE200\"><\/path><path d=\"M292.355 437.163C291.187 435.479 289.761 433.917 288.32 432.81C287.471 432.097 286.44 431.702 285.454 431.763C284.604 431.899 283.77 432.279 283.042 433.189C282.648 433.644 282.451 434.159 282.526 434.69C282.587 435.919 284.286 437.36 285.059 438.133C287.85 441.061 290.717 444.049 293.189 447.689C293.902 448.796 294.691 450.359 295.009 451.921C295.859 452.239 296.966 452.573 297.421 451.526C297.618 451.011 297.679 450.298 297.679 449.509C297.542 447.295 296.632 444.564 295.919 443.078C295.146 441.319 293.902 439.18 292.34 437.163H292.355Z\" fill=\"#FFE200\"><\/path><path d=\"M284.149 439.043C283.558 438.391 282.921 437.815 282.648 437.481C282.056 436.829 281.146 436.253 280.236 436.055C279.584 435.919 278.932 435.995 278.355 436.51C277.703 437.102 276.732 437.678 276.672 438.725C276.414 440.803 277.976 441.516 279.402 442.82C280.509 443.867 281.616 444.898 282.784 445.884C284.801 447.643 286.561 449.524 287.926 451.799C288.639 453.104 289.23 454.469 289.61 456.031C289.746 456.683 289.867 457.26 290.838 457.396C292.855 457.533 294.023 455.182 293.963 453.438C293.902 451.678 292.992 449.737 292.082 448.432C289.67 444.853 286.879 441.925 284.149 439.074V439.043Z\" fill=\"#FFE200\"><\/path><path d=\"M281.95 446.84C280.782 445.869 279.675 444.762 278.507 443.715C277.4 442.668 276.292 441.576 275.064 440.53C274.093 439.756 272.728 438.968 271.621 438.77C271.166 438.71 270.453 438.573 270.256 439.165C270.059 439.878 270.514 441.121 270.65 441.895C269.543 441.637 266.873 440.075 267.268 442.411C267.723 445.338 271.044 447.158 273.441 448.265C277.278 449.949 280.069 452.042 282.086 454.378C284.104 456.714 285.272 459.383 285.863 462.174C285.924 462.568 286 463.023 286 463.403H286.515C287.107 463.403 287.562 463.205 287.941 462.948C288.336 462.629 288.593 462.174 288.791 461.522C288.851 461.067 288.927 460.612 288.927 460.02C288.791 457.032 288.017 454.499 286.849 452.406C285.621 450.267 283.922 448.432 281.965 446.809L281.95 446.84Z\" fill=\"#FFE200\"><\/path><path d=\"M350.933 230.7C350.28 229.017 348.855 229.138 347.414 229.654C345.396 232.703 343.455 236.024 341.62 239.543C339.739 243.183 337.979 247.021 336.478 250.995C336.159 251.844 334.976 251.389 335.31 250.54C336.811 246.505 338.632 242.607 340.512 238.967C342.393 235.327 344.41 231.944 346.488 228.82C347.717 226.863 348.248 224.785 347.596 222.51C347.277 221.342 346.488 220.235 345.184 220.038C344.926 220.553 344.592 221.084 344.274 221.539C342.196 224.209 340.315 226.939 338.419 229.669C336.599 232.46 334.84 235.266 333.217 238.193C332.762 238.967 331.594 238.39 332.11 237.541C333.732 234.614 335.553 231.747 337.373 228.956C339.253 226.165 341.21 223.435 343.227 220.766C344.077 219.719 344.592 218.551 344.653 217.323C344.79 214.79 341.862 211.347 339.906 214.077C337.494 217.459 335.098 221.039 332.747 224.603C330.214 228.501 327.741 232.475 325.33 236.57C324.875 237.344 323.767 236.707 324.222 235.918C326.695 231.823 329.167 227.788 331.7 223.951C334.172 220.113 336.645 216.413 339.178 212.894C339.633 212.241 339.951 211.589 339.891 210.679C339.891 210.163 339.754 209.708 339.496 209.314C338.723 208.207 337.085 207.949 336.25 208.996C333.52 212.241 331.184 215.502 328.909 218.748C326.573 222.131 324.359 225.634 322.023 229.214C321.568 229.988 320.461 229.275 320.976 228.562C323.312 224.922 325.527 221.479 327.863 218.035C330.274 214.517 332.807 211.149 335.659 207.691C336.372 206.781 336.174 205.552 335.795 204.642C335.598 204.385 335.401 204.127 335.28 203.93C334.051 202.564 332.944 202.428 331.836 203.732C327.544 208.161 322.736 213.227 318.246 220.644C317.791 221.418 316.684 220.781 317.2 219.992C321.75 212.454 326.634 207.373 330.926 202.822C331.836 201.912 332.686 201.321 332.489 199.895C332.352 198.848 331.836 198.014 331.124 197.362C329.698 196.194 329.046 195.997 327.741 197.362C325.527 199.637 323.388 202.307 321.234 205.234C319.096 208.222 316.942 211.407 314.727 214.79C314.591 215.047 314.409 215.305 313.878 214.987C313.362 214.668 313.484 214.395 313.681 214.077C315.895 210.694 318.034 207.448 320.188 204.521C322.402 201.533 324.617 198.803 326.816 196.528C327.923 195.36 328.575 194.45 327.665 192.887C325.982 190.218 324.541 191.917 323.054 193.6C320.84 196.073 318.701 198.606 316.623 201.336C314.545 204.127 312.528 207.054 310.571 210.179C310.374 210.436 310.253 210.694 309.661 210.376C309.146 210.057 309.343 209.784 309.464 209.526C311.481 206.341 313.499 203.353 315.577 200.623C317.715 197.832 319.869 195.223 322.084 192.751C323.13 191.583 323.646 190.734 323.707 190.021C323.843 189.429 323.509 188.853 322.994 188.261C321.765 186.896 318.959 184.03 317.533 187.215C316.168 190.203 314.212 192.554 311.937 194.298C309.404 196.255 306.476 197.544 303.412 198.196C296.132 199.758 288.715 196.634 282.936 192.478C277.021 188.185 271.166 182.134 267.586 175.247C264.462 169.271 262.839 162.309 264.522 155.681C253.526 160.231 243.318 162.507 233.504 162.764C226.224 162.962 217.578 161.991 210.101 159.579C200.151 156.394 187.804 156.394 177.854 159.579C170.377 161.991 161.792 162.962 154.451 162.764C144.637 162.507 134.429 160.231 123.433 155.681C125.116 162.309 123.493 169.271 120.445 175.247C116.804 182.134 110.95 188.185 105.034 192.478C99.2402 196.634 91.8384 199.758 84.5579 198.196C81.5092 197.544 78.5818 196.24 76.0337 194.298C73.7585 192.539 71.8019 190.203 70.4368 187.215C69.011 184.03 66.205 186.896 64.9764 188.261C64.4607 188.853 64.1271 189.429 64.2636 190.021C64.3242 190.734 64.8551 191.583 65.8865 192.751C68.101 195.223 70.2396 197.817 72.3934 200.623C74.4714 203.353 76.4887 206.341 78.506 209.526C78.6425 209.784 78.8245 210.042 78.3088 210.376C77.7173 210.694 77.596 210.436 77.3988 210.179C75.4421 207.054 73.4248 204.127 71.3469 201.336C69.2689 198.606 67.1151 196.073 64.9158 193.6C63.4142 191.917 61.9884 190.218 60.3048 192.887C59.3947 194.45 60.047 195.36 61.1542 196.528C63.3687 198.803 65.5832 201.533 67.7825 204.521C69.9211 207.448 72.1356 210.694 74.2894 214.077C74.4866 214.395 74.6079 214.668 74.0922 214.987C73.5765 215.305 73.3793 215.047 73.2428 214.79C71.0283 211.407 68.8897 208.222 66.7359 205.234C64.5973 202.307 62.4434 199.637 60.229 197.362C58.9245 195.997 58.2723 196.194 56.8466 197.362C56.1337 198.014 55.618 198.864 55.4815 199.895C55.2843 201.321 56.1337 201.912 57.0438 202.822C61.3362 207.373 66.205 212.439 70.7705 219.992C71.2862 220.766 70.179 221.418 69.7239 220.644C65.2343 213.227 60.4261 208.161 56.1337 203.732C55.0265 202.428 53.9192 202.564 52.6906 203.93C52.5541 204.127 52.3721 204.385 52.1749 204.642C51.7806 205.552 51.5834 206.781 52.3114 207.691C55.1781 211.134 57.7111 214.517 60.1076 218.035C62.4434 221.479 64.6579 224.922 66.9937 228.562C67.5094 229.275 66.4022 229.988 65.9472 229.214C63.6114 225.634 61.3969 222.131 59.0611 218.748C56.7859 215.502 54.4501 212.241 51.7199 208.996C50.8705 207.949 49.2476 208.222 48.474 209.314C48.2162 209.708 48.0797 210.163 48.0797 210.679C48.019 211.589 48.3375 212.241 48.7925 212.894C51.3255 216.413 53.7979 220.113 56.2702 223.951C58.8032 227.788 61.2755 231.823 63.7479 235.918C64.2029 236.692 63.0957 237.344 62.6406 236.57C60.229 232.475 57.7566 228.501 55.2236 224.603C52.8878 221.023 50.4762 217.444 48.0645 214.077C46.1079 211.347 43.1805 214.79 43.317 217.323C43.3777 218.551 43.9692 219.734 44.7428 220.766C46.7601 223.435 48.7167 226.165 50.5975 228.956C52.4783 231.747 54.2377 234.614 55.8607 237.541C56.3764 238.39 55.2085 238.967 54.7534 238.193C53.1305 235.266 51.371 232.475 49.5509 229.669C47.6701 226.939 45.7742 224.209 43.6962 221.539C43.3777 221.084 43.044 220.568 42.7861 220.038C41.4817 220.235 40.7082 221.342 40.3745 222.51C39.7223 224.785 40.238 226.863 41.4817 228.82C43.5597 231.944 45.577 235.327 47.4578 238.967C49.3386 242.607 51.1587 246.505 52.6603 250.54C52.9788 251.389 51.8109 251.844 51.4924 250.995C49.9908 247.021 48.2465 243.199 46.3505 239.543C44.5304 236.024 42.5738 232.718 40.5565 229.654C39.1307 229.138 37.6898 229.002 37.0376 230.7C35.7332 234.144 37.2348 237.132 38.6605 240.195C43.8024 251.45 49.0656 262.826 52.7058 275.566C69.4206 213.273 126.512 167.178 193.932 167.178C261.352 167.178 318.459 213.288 335.158 275.566C338.798 262.826 344.062 251.45 349.203 240.195C350.629 237.147 352.131 234.144 350.826 230.7H350.933Z\" fill=\"#FFE200\"><\/path><path d=\"M283.694 191.431C289.155 195.405 296.314 198.454 303.2 196.952C306.067 196.3 308.857 195.132 311.193 193.312C313.332 191.628 315.167 189.474 316.396 186.684C317.366 184.606 317.761 181.936 317.366 179.661C317.169 178.69 316.911 177.78 316.396 177.067C315.622 175.642 313.529 174.337 311.845 174.731C310.48 175.05 309.57 176.294 309.707 177.659C309.843 179.479 311.33 179.676 312.755 179.615C313.013 181.693 313.013 183.65 312.24 185.592C310.677 189.823 306.779 192.296 302.426 192.811C299.696 193.206 296.708 192.872 293.978 192.038C289.685 190.733 285.454 187.882 281.889 184.242C277.991 180.404 274.867 175.596 273.107 171.106C271.803 167.785 271.151 164.342 271.348 160.762C271.606 157.637 272.516 154.452 274.396 151.404C275.625 149.386 277.642 149.326 279.538 149.265C281.04 149.204 282.405 149.128 282.86 147.961C283.254 147.05 282.996 146.08 282.405 145.367C281.631 144.32 280.327 143.744 279.023 143.683C272.713 143.486 267.905 149.144 266.206 154.68C264.189 161.111 265.554 168.664 268.739 174.701C272.243 181.405 277.976 187.321 283.694 191.477V191.431Z\" fill=\"#FFE200\"><\/path><path d=\"M233.565 161.52C242.726 161.262 252.419 159.184 262.702 155.013C264.007 154.498 265.175 153.648 265.766 152.283C266.873 149.75 268.496 147.399 270.574 145.579C253.48 152.147 230.774 155.984 207.113 157.031C215.637 160.216 224.343 161.778 233.58 161.52H233.565Z\" fill=\"#FFE200\"><\/path><path d=\"M76.8527 193.312C79.1885 195.132 81.9945 196.3 84.8461 196.952C91.7322 198.454 98.8913 195.39 104.352 191.431C110.07 187.275 115.803 181.36 119.307 174.656C122.492 168.604 123.918 161.066 121.84 154.635C120.156 149.114 115.333 143.456 109.023 143.638C107.795 143.699 106.414 144.29 105.641 145.322C105.049 146.035 104.792 147.005 105.186 147.915C105.641 149.083 107.006 149.144 108.508 149.22C110.388 149.28 112.406 149.356 113.649 151.358C115.53 154.407 116.44 157.607 116.698 160.717C116.895 164.296 116.243 167.74 114.939 171.061C113.255 175.551 110.055 180.359 106.157 184.196C102.577 187.837 98.3605 190.703 94.068 191.993C91.3378 192.842 88.3498 193.161 85.6196 192.766C81.2665 192.25 77.3684 189.778 75.8061 185.546C75.0933 183.59 75.0326 181.648 75.2904 179.57C76.7162 179.631 78.2178 179.434 78.3391 177.614C78.4756 176.249 77.5656 175.02 76.2005 174.686C74.5169 174.292 72.4237 175.596 71.6502 177.022C71.1345 177.735 70.8766 178.645 70.6795 179.616C70.2851 181.891 70.6795 184.56 71.6502 186.638C72.8788 189.429 74.7141 191.583 76.8527 193.267V193.312Z\" fill=\"#FFE200\"><\/path><path d=\"M125.298 155.014H125.359C135.627 159.17 145.32 161.263 154.496 161.521C155.8 161.657 161.716 161.384 164.643 160.095C167.828 158.73 165.493 155.939 163.02 155.666C146.048 153.846 130.182 150.464 117.502 145.595C119.58 147.415 121.203 149.751 122.31 152.299C122.902 153.603 123.994 154.513 125.298 155.029V155.014Z\" fill=\"#FFE200\"><\/path><path d=\"M287.987 109.753C286.561 109.753 285.257 110.345 284.286 111.255C283.376 112.226 282.724 113.53 282.724 114.956C282.724 117.883 285.135 120.219 287.987 120.219C289.488 120.219 290.778 119.628 291.688 118.718C292.658 117.747 293.25 116.442 293.25 114.941C293.25 112.074 290.914 109.738 287.987 109.738V109.753Z\" fill=\"#FFE200\"><\/path><path d=\"M276.156 141.363C277.46 141.818 278.689 141.423 279.402 140.65C279.66 140.392 279.918 140.058 280.054 139.679C280.115 139.361 280.191 138.966 280.115 138.572C279.978 137.601 279.144 136.615 277.324 136.039C250.204 126.878 222.114 122.251 194.023 122.251C165.933 122.251 137.842 126.862 110.722 136.039C108.902 136.63 108.053 137.601 107.931 138.572C107.871 138.966 107.931 139.345 107.992 139.679C108.129 140.073 108.386 140.392 108.644 140.65C109.357 141.423 110.601 141.818 111.89 141.363C141.346 132.065 167.677 127.378 194.008 127.378C220.339 127.378 246.67 132.065 276.126 141.363H276.156Z\" fill=\"#FFE200\"><\/path><path d=\"M188.957 100.077C188.957 98.5751 187.728 97.4072 186.227 97.4072C184.725 97.4072 183.557 98.5751 183.557 100.077C183.557 101.578 184.725 102.807 186.227 102.807C187.728 102.807 188.957 101.578 188.957 100.077Z\" fill=\"#FFE200\"><\/path><path d=\"M194.038 83.877C195.858 83.877 197.36 82.3754 197.36 80.5552C197.36 78.7351 195.858 77.1729 194.038 77.1729C192.218 77.1729 190.716 78.6745 190.716 80.5552C190.716 82.436 192.218 83.877 194.038 83.877Z\" fill=\"#FFE200\"><\/path><path d=\"M198.133 60.2155C198.133 57.9404 196.313 56.0596 194.038 56.0596C191.763 56.0596 189.943 57.9404 189.943 60.2155C189.943 62.4907 191.763 64.3108 194.038 64.3108C196.313 64.3108 198.133 62.4907 198.133 60.2155Z\" fill=\"#FFE200\"><\/path><path d=\"M197.8 49.75C197.8 47.672 196.116 45.9126 194.023 45.9126C191.93 45.9126 190.246 47.672 190.246 49.75C190.246 51.828 191.93 53.5268 194.023 53.5268C196.116 53.5268 197.8 51.8432 197.8 49.75Z\" fill=\"#FFE200\"><\/path><path d=\"M190.064 70.8784C190.064 73.017 191.884 74.8523 194.038 74.8523C196.192 74.8523 197.997 73.0322 197.997 70.8784C197.997 68.7245 196.177 66.8438 194.038 66.8438C191.899 66.8438 190.064 68.6639 190.064 70.8784Z\" fill=\"#FFE200\"><\/path><path d=\"M194.038 31.6701C198.528 31.6701 202.168 27.9692 202.168 23.4796C202.168 18.99 198.528 15.2891 194.038 15.2891C189.548 15.2891 185.908 18.9293 185.908 23.4796C185.908 28.0299 189.548 31.6701 194.038 31.6701Z\" fill=\"#FFE200\"><\/path><path d=\"M253.92 86.1522C253.92 88.1088 255.482 89.7318 257.424 89.7318C258.395 89.7318 259.305 89.3374 259.957 88.6852C260.609 88.033 261.003 87.1229 261.003 86.1522C261.003 84.1956 259.38 82.6333 257.424 82.6333C255.467 82.6333 253.92 84.1956 253.92 86.1522Z\" fill=\"#FFE200\"><\/path><path d=\"M266.464 72.6985C267.571 72.6985 268.542 72.2435 269.194 71.5913C269.907 70.8784 270.362 69.9077 270.362 68.8004C270.362 66.6618 268.602 64.9023 266.464 64.9023C265.417 64.9023 264.446 65.3574 263.734 66.0703C263.021 66.7831 262.566 67.7539 262.566 68.8004C262.566 70.9391 264.325 72.6985 266.464 72.6985Z\" fill=\"#FFE200\"><\/path><path d=\"M258.925 77.9623C258.925 79.9796 260.609 81.6632 262.702 81.6632C263.749 81.6632 264.659 81.2689 265.296 80.556C266.009 79.9038 266.403 78.9937 266.403 77.9623C266.403 75.8843 264.719 74.1855 262.702 74.1855C261.656 74.1855 260.685 74.5799 260.033 75.2928C259.32 75.945 258.925 76.9157 258.925 77.9623Z\" fill=\"#FFE200\"><\/path><path d=\"M267.177 63.3405C268.284 63.3405 269.255 62.8855 269.968 62.2333C270.681 61.5204 271.075 60.5496 271.075 59.4424C271.075 57.3038 269.315 55.605 267.177 55.605C266.13 55.605 265.159 55.9993 264.447 56.7122C263.734 57.4251 263.339 58.3958 263.339 59.4424C263.339 61.581 265.099 63.3405 267.177 63.3405Z\" fill=\"#FFE200\"><\/path><path d=\"M266.464 53.5113C267.571 53.5113 268.542 53.0563 269.255 52.3434C270.028 51.6305 270.423 50.6598 270.423 49.5525C270.423 47.3381 268.663 45.5786 266.464 45.5786C265.357 45.5786 264.386 46.0336 263.673 46.7465C262.96 47.4594 262.505 48.4301 262.505 49.5374C262.505 51.7519 264.264 53.5113 266.479 53.5113H266.464Z\" fill=\"#FFE200\"><\/path><path d=\"M267.374 43.3041C269.588 43.3041 271.348 41.5447 271.348 39.3454C271.348 37.146 269.588 35.4473 267.374 35.4473C265.159 35.4473 263.476 37.2067 263.476 39.3454C263.476 41.484 265.235 43.3041 267.374 43.3041Z\" fill=\"#FFE200\"><\/path><path d=\"M257.5 40.5133C259.638 40.5133 261.398 38.6932 261.398 36.5394C261.398 34.3856 259.638 32.5654 257.5 32.5654C255.361 32.5654 253.526 34.3856 253.526 36.5394C253.526 38.6932 255.285 40.5133 257.5 40.5133Z\" fill=\"#FFE200\"><\/path><path d=\"M248.581 36.9938C249.628 36.9938 250.598 36.5388 251.311 35.8259C252.024 35.1737 252.479 34.203 252.479 33.0957C252.479 30.9571 250.72 29.2583 248.581 29.2583C247.534 29.2583 246.564 29.6527 245.851 30.3655C245.138 31.0784 244.683 32.0492 244.683 33.0957C244.683 35.2344 246.442 36.9938 248.581 36.9938Z\" fill=\"#FFE200\"><\/path><path d=\"M238.571 35.4321C239.617 35.4321 240.527 34.9771 241.24 34.3249C241.892 33.612 242.287 32.7019 242.287 31.716C242.287 29.6381 240.664 28.0151 238.586 28.0151C237.615 28.0151 236.629 28.4095 235.992 29.0617C235.34 29.7746 234.885 30.6846 234.885 31.7312C234.885 33.7485 236.568 35.4321 238.586 35.4321H238.571Z\" fill=\"#FFE200\"><\/path><path d=\"M229.212 34.0669C230.259 34.0669 231.169 33.6118 231.821 32.9596C232.534 32.3074 232.928 31.3367 232.928 30.366C232.928 28.288 231.244 26.665 229.227 26.665C228.181 26.665 227.271 27.0594 226.633 27.7116C225.921 28.4245 225.526 29.3346 225.526 30.3811C225.526 32.3984 227.21 34.082 229.227 34.082L229.212 34.0669Z\" fill=\"#FFE200\"><\/path><path d=\"M220.036 32.5803C221.006 32.5803 221.916 32.1859 222.569 31.5337C223.221 30.8208 223.676 29.9108 223.676 28.94C223.676 26.9227 221.992 25.2998 220.036 25.2998C218.989 25.2998 218.079 25.6942 217.442 26.3464C216.79 27.0593 216.335 27.9693 216.335 28.9552C216.335 30.9725 218.018 32.5955 220.036 32.5955V32.5803Z\" fill=\"#FFE200\"><\/path><path d=\"M211.39 31.5336C213.271 31.5336 214.833 29.9713 214.833 28.0905C214.833 26.2097 213.271 24.6475 211.39 24.6475C209.509 24.6475 207.886 26.2097 207.886 28.0905C207.886 29.9713 209.448 31.5336 211.39 31.5336Z\" fill=\"#FFE200\"><\/path><path d=\"M276.747 47.1412C277.855 47.1412 278.886 46.6862 279.614 45.9126H279.675C280.388 45.1998 280.843 44.1532 280.843 43.046C280.843 40.7708 279.023 38.9507 276.747 38.9507C275.64 38.9507 274.609 39.4057 273.881 40.1186C273.107 40.8921 272.652 41.878 272.652 43.046C272.652 45.2604 274.472 47.1412 276.747 47.1412Z\" fill=\"#FFE200\"><\/path><path d=\"M286.106 48.9005C287.213 48.9005 288.245 48.3848 288.973 47.6719C289.746 46.959 290.201 45.9125 290.201 44.8052C290.201 42.5301 288.32 40.71 286.106 40.71C284.938 40.71 283.967 41.165 283.179 41.8779C282.466 42.6514 282.011 43.6373 282.011 44.8052C282.011 47.0197 283.831 48.9005 286.106 48.9005Z\" fill=\"#FFE200\"><\/path><path d=\"M296.056 52.2831C297.36 52.2831 298.589 51.6915 299.438 50.8573C300.288 50.0079 300.803 48.84 300.803 47.5356C300.803 44.9419 298.665 42.7881 296.056 42.7881C294.751 42.7881 293.584 43.3038 292.734 44.1532C291.885 45.0632 291.308 46.2311 291.308 47.5356C291.308 50.1292 293.447 52.2831 296.056 52.2831Z\" fill=\"#FFE200\"><\/path><path d=\"M305.869 57.8642C307.235 57.8642 308.463 57.2726 309.388 56.3626C310.314 55.4525 310.89 54.2239 310.89 52.8588C310.89 50.1287 308.615 47.8535 305.885 47.8535C304.52 47.8535 303.291 48.4451 302.366 49.3551C301.456 50.2652 300.864 51.4938 300.864 52.874C300.864 55.6042 303.139 57.8793 305.869 57.8793V57.8642Z\" fill=\"#FFE200\"><\/path><path d=\"M309.054 62.0354C309.054 64.9021 311.39 67.2379 314.196 67.2379C317.002 67.2379 319.399 64.9021 319.399 62.0354C319.399 59.1687 317.063 56.8936 314.196 56.8936C311.33 56.8936 309.054 59.2294 309.054 62.0354Z\" fill=\"#FFE200\"><\/path><path d=\"M313.878 73.8056C313.878 76.5358 316.092 78.811 318.883 78.811C321.674 78.811 323.828 76.5358 323.828 73.8056C323.828 71.0754 321.613 68.8003 318.883 68.8003C316.153 68.8003 313.878 71.0754 313.878 73.8056Z\" fill=\"#FFE200\"><\/path><path d=\"M322.842 85.4397C322.842 83.028 320.885 81.0107 318.489 81.0107C316.092 81.0107 314.06 83.028 314.06 85.4397C314.06 87.8514 316.077 89.8687 318.489 89.8687C320.901 89.8687 322.842 87.8514 322.842 85.4397Z\" fill=\"#FFE200\"><\/path><path d=\"M319.46 94.9346C319.46 92.8566 317.776 91.0972 315.622 91.0972C313.468 91.0972 311.785 92.8566 311.785 94.9346C311.785 97.0126 313.544 98.772 315.622 98.772C317.7 98.772 319.46 97.0884 319.46 94.9346Z\" fill=\"#FFE200\"><\/path><path d=\"M311.663 107.357C313.802 107.357 315.562 105.598 315.562 103.52C315.562 101.442 313.802 99.6216 311.663 99.6216C309.525 99.6216 307.826 101.381 307.826 103.52C307.826 105.658 309.585 107.357 311.663 107.357Z\" fill=\"#FFE200\"><\/path><path d=\"M272.258 64.7055C271.864 68.4064 270.953 71.986 269.528 75.2319C267.965 78.7356 266.145 82.1938 264.067 85.3032C262.111 88.2912 259.911 91.0214 257.697 93.0994C257.303 93.5544 257.045 93.8729 257.105 94.2673C257.166 94.7223 257.5 95.3139 258.152 96.1481C258.349 96.3453 258.546 96.5425 258.743 96.6638C259.456 97.1188 260.306 96.9823 261.276 96.4059C262.384 95.6931 263.552 94.4493 264.72 92.9629C267.192 89.7777 269.664 85.288 271.484 81.3293C273.82 76.3846 275.064 72.0922 275.64 67.6784C276.232 62.6124 275.959 57.5312 275.64 52.4652C275.443 50.3266 275.322 47.5812 273.107 47.2627C272.516 47.202 272.258 47.7784 272.137 48.5671C272 49.6137 272.137 50.9788 272.273 51.8888C272.728 56.1206 272.789 60.4737 272.273 64.7055H272.258Z\" fill=\"#FFE200\"><\/path><path d=\"M258.152 44.6082C257.56 43.956 256.923 43.501 256.195 43.501C254.633 43.5616 254.436 44.4717 254.314 45.3818C254.117 46.7469 254.967 47.8541 255.361 49.2799C256.468 53.0566 256.923 56.7575 256.787 60.4584C256.59 64.1593 255.877 67.7996 254.572 71.455C253.859 73.533 252.949 75.3531 251.903 77.1125C250.796 78.872 249.628 80.5556 248.46 82.2544C247.352 83.756 247.034 84.666 247.231 85.1211C247.428 85.5761 248.081 85.834 249.051 86.0918C251.842 86.744 252.949 84.8632 254.117 82.8459C254.436 82.3302 254.769 81.7387 255.164 81.1623C258.743 75.8991 260.821 70.4994 261.595 65.0997C262.444 59.3057 261.853 53.5268 260.033 48.0664C259.714 47.0199 259.062 45.5941 258.152 44.6234V44.6082Z\" fill=\"#FFE200\"><\/path><path d=\"M130.637 89.7318C132.594 89.7318 134.156 88.1088 134.156 86.1522C134.156 84.1956 132.594 82.6333 130.637 82.6333C128.681 82.6333 127.058 84.1956 127.058 86.1522C127.058 87.1229 127.452 88.033 128.104 88.6852C128.756 89.3374 129.666 89.7318 130.637 89.7318Z\" fill=\"#FFE200\"><\/path><path d=\"M121.597 72.6985C123.736 72.6985 125.495 70.9391 125.495 68.8004C125.495 67.7539 125.04 66.7831 124.327 66.0703C123.615 65.3574 122.644 64.9023 121.597 64.9023C119.459 64.9023 117.699 66.6618 117.699 68.8004C117.699 69.9077 118.154 70.8784 118.867 71.5913C119.519 72.2435 120.49 72.6985 121.597 72.6985Z\" fill=\"#FFE200\"><\/path><path d=\"M125.374 81.6632C127.452 81.6632 129.151 79.9796 129.151 77.9623C129.151 76.9157 128.757 75.945 128.044 75.2928C127.391 74.5799 126.421 74.1855 125.374 74.1855C123.357 74.1855 121.673 75.8692 121.673 77.9623C121.673 79.0089 122.068 79.9189 122.78 80.556C123.433 81.2689 124.343 81.6632 125.374 81.6632Z\" fill=\"#FFE200\"><\/path><path d=\"M124.722 59.4268C124.722 58.3802 124.328 57.4095 123.615 56.6966C122.902 55.9837 121.931 55.5894 120.885 55.5894C118.746 55.5894 116.986 57.273 116.986 59.4268C116.986 60.534 117.381 61.5047 118.094 62.2176C118.807 62.8698 119.777 63.3249 120.885 63.3249C122.963 63.3249 124.722 61.5654 124.722 59.4268Z\" fill=\"#FFE200\"><\/path><path d=\"M121.597 45.5786C119.383 45.5786 117.623 47.3381 117.623 49.5525C117.623 50.6598 118.018 51.6305 118.791 52.3434C119.504 53.0563 120.475 53.5113 121.582 53.5113C123.797 53.5113 125.541 51.7519 125.541 49.5374C125.541 48.4301 125.086 47.4594 124.373 46.7465C123.66 46.0336 122.689 45.5786 121.582 45.5786H121.597Z\" fill=\"#FFE200\"><\/path><path d=\"M120.687 43.3041C122.826 43.3041 124.585 41.5447 124.585 39.3454C124.585 37.146 122.826 35.4473 120.687 35.4473C118.549 35.4473 116.713 37.2067 116.713 39.3454C116.713 41.484 118.473 43.3041 120.687 43.3041Z\" fill=\"#FFE200\"><\/path><path d=\"M130.562 40.5133C132.776 40.5133 134.52 38.6932 134.52 36.5394C134.52 34.3856 132.761 32.5654 130.562 32.5654C128.362 32.5654 126.663 34.3856 126.663 36.5394C126.663 38.6932 128.423 40.5133 130.562 40.5133Z\" fill=\"#FFE200\"><\/path><path d=\"M139.48 36.9938C141.619 36.9938 143.378 35.2344 143.378 33.0957C143.378 32.0492 142.923 31.0784 142.21 30.3655C141.497 29.6527 140.527 29.2583 139.48 29.2583C137.341 29.2583 135.582 30.9419 135.582 33.0957C135.582 34.203 136.037 35.1737 136.75 35.8259C137.463 36.5388 138.434 36.9938 139.48 36.9938Z\" fill=\"#FFE200\"><\/path><path d=\"M149.491 35.4321C151.508 35.4321 153.192 33.7485 153.192 31.7312C153.192 30.6846 152.737 29.7746 152.084 29.0617C151.432 28.4095 150.461 28.0151 149.491 28.0151C147.413 28.0151 145.79 29.6381 145.79 31.716C145.79 32.6868 146.184 33.5968 146.897 34.3249C147.549 34.9771 148.459 35.4321 149.491 35.4321Z\" fill=\"#FFE200\"><\/path><path d=\"M158.849 34.0664C160.866 34.0664 162.55 32.3828 162.55 30.3655C162.55 29.3189 162.156 28.4089 161.443 27.696C160.791 27.0438 159.881 26.6494 158.849 26.6494C156.832 26.6494 155.148 28.2724 155.148 30.3503C155.148 31.3211 155.543 32.307 156.255 32.944C156.908 33.5962 157.818 34.0512 158.849 34.0512V34.0664Z\" fill=\"#FFE200\"><\/path><path d=\"M168.026 32.5798C170.043 32.5798 171.727 30.9569 171.727 28.9396C171.727 27.9689 171.272 27.0588 170.619 26.3307C169.967 25.6785 169.057 25.2842 168.01 25.2842C166.054 25.2842 164.37 26.9071 164.37 28.9244C164.37 29.8952 164.825 30.8052 165.477 31.5181C166.13 32.1703 167.04 32.5647 168.01 32.5647L168.026 32.5798Z\" fill=\"#FFE200\"><\/path><path d=\"M176.671 31.5336C178.628 31.5336 180.19 29.9713 180.19 28.0905C180.19 26.2097 178.628 24.6475 176.671 24.6475C174.714 24.6475 173.228 26.2097 173.228 28.0905C173.228 29.9713 174.79 31.5336 176.671 31.5336Z\" fill=\"#FFE200\"><\/path><path d=\"M108.462 45.9126C109.175 46.6862 110.222 47.1412 111.329 47.1412C113.604 47.1412 115.424 45.2604 115.424 43.046C115.424 41.878 114.969 40.9073 114.195 40.1186C113.483 39.4057 112.436 38.9507 111.329 38.9507C109.054 38.9507 107.234 40.7708 107.234 43.046C107.234 44.1532 107.689 45.1846 108.401 45.9126H108.462Z\" fill=\"#FFE200\"><\/path><path d=\"M101.955 48.9005C104.23 48.9005 106.05 47.0197 106.05 44.8052C106.05 43.6373 105.595 42.6666 104.882 41.8779C104.109 41.165 103.123 40.71 101.955 40.71C99.7407 40.71 97.8599 42.5301 97.8599 44.8052C97.8599 45.9125 98.3149 46.9439 99.0884 47.6719C99.8013 48.3848 100.848 48.9005 101.955 48.9005Z\" fill=\"#FFE200\"><\/path><path d=\"M92.0052 52.2831C94.5988 52.2831 96.7527 50.1444 96.7527 47.5356C96.7527 46.2311 96.1611 45.0632 95.3269 44.1532C94.4775 43.3038 93.3096 42.7881 92.0052 42.7881C89.4115 42.7881 87.2577 44.9267 87.2577 47.5356C87.2577 48.84 87.7734 50.0079 88.6228 50.8573C89.4722 51.7067 90.7008 52.2831 92.0052 52.2831Z\" fill=\"#FFE200\"><\/path><path d=\"M82.1918 57.8647C84.9219 57.8647 87.1971 55.5895 87.1971 52.8594C87.1971 51.4943 86.6056 50.2505 85.6955 49.3405C84.7854 48.4304 83.5569 47.8389 82.1766 47.8389C79.4464 47.8389 77.1713 50.114 77.1713 52.8442C77.1713 54.2093 77.7628 55.4379 78.6729 56.3479C79.5829 57.258 80.8115 57.8495 82.1766 57.8495L82.1918 57.8647Z\" fill=\"#FFE200\"><\/path><path d=\"M73.8646 67.2379C76.6555 67.2379 79.0065 64.9021 79.0065 62.0354C79.0065 59.1687 76.6706 56.8936 73.8646 56.8936C71.0586 56.8936 68.6621 59.2294 68.6621 62.0354C68.6621 64.8414 70.9979 67.2379 73.8646 67.2379Z\" fill=\"#FFE200\"><\/path><path d=\"M69.1931 78.811C71.9839 78.811 74.1984 76.5358 74.1984 73.8056C74.1984 71.0754 71.9839 68.8003 69.1931 68.8003C66.4022 68.8003 64.2484 71.0754 64.2484 73.8056C64.2484 76.5358 66.4629 78.811 69.1931 78.811Z\" fill=\"#FFE200\"><\/path><path d=\"M74.0012 85.4397C74.0012 83.028 71.9839 81.0107 69.5722 81.0107C67.1606 81.0107 65.2191 83.028 65.2191 85.4397C65.2191 87.8514 67.1758 89.8687 69.5722 89.8687C71.9687 89.8687 74.0012 87.8514 74.0012 85.4397Z\" fill=\"#FFE200\"><\/path><path d=\"M72.439 98.772C74.517 98.772 76.2764 97.0884 76.2764 94.9346C76.2764 92.7808 74.517 91.0972 72.439 91.0972C70.361 91.0972 68.6016 92.8566 68.6016 94.9346C68.6016 97.0126 70.2852 98.772 72.439 98.772Z\" fill=\"#FFE200\"><\/path><path d=\"M72.4995 103.52C72.4995 105.598 74.259 107.357 76.3976 107.357C78.5362 107.357 80.235 105.598 80.235 103.52C80.235 101.442 78.4756 99.6216 76.3976 99.6216C74.3196 99.6216 72.4995 101.381 72.4995 103.52Z\" fill=\"#FFE200\"><\/path><path d=\"M112.421 52.4797C112.102 57.5457 111.829 62.6269 112.421 67.6929C113.012 72.1219 114.241 76.3992 116.577 81.3438C118.397 85.3026 120.869 89.7922 123.342 92.9774C124.51 94.479 125.677 95.7076 126.785 96.4205C127.755 97.012 128.605 97.1334 129.318 96.6783C129.515 96.5418 129.712 96.3598 129.909 96.1626C130.561 95.3133 130.88 94.7369 130.956 94.2819C131.016 93.8875 130.759 93.569 130.364 93.1139C128.15 91.036 125.935 88.3058 123.994 85.3178C121.916 82.1932 120.096 78.7502 118.533 75.2464C117.108 72.0005 116.198 68.421 115.803 64.7201C115.288 60.4883 115.348 56.1352 115.803 51.9034C115.94 50.9933 116.061 49.6282 115.94 48.5816C115.803 47.8081 115.545 47.2166 114.969 47.2772C112.755 47.5958 112.633 50.3411 112.436 52.4797H112.421Z\" fill=\"#FFE200\"><\/path><path d=\"M132.912 81.1472C133.307 81.7387 133.625 82.3151 133.959 82.8308C135.127 84.8481 136.234 86.7289 139.025 86.0767C139.996 85.8188 140.648 85.561 140.845 85.1059C141.042 84.6509 140.709 83.7409 139.617 82.2393C138.449 80.5556 137.281 78.8569 136.234 77.0974C135.127 75.338 134.217 73.5178 133.504 71.4399C132.2 67.7996 131.487 64.1594 131.29 60.4433C131.153 56.7424 131.608 53.0263 132.715 49.2647C133.11 47.839 133.944 46.7317 133.762 45.3666C133.625 44.4566 133.443 43.5465 131.881 43.4858C131.168 43.4858 130.516 43.9409 129.924 44.5931C129.014 45.5638 128.362 47.0047 128.044 48.0361C126.224 53.4965 125.632 59.2906 126.481 65.0694C127.255 70.4691 129.348 75.8688 132.912 81.132V81.1472Z\" fill=\"#FFE200\"><\/path><path d=\"M78.4149 68.4059C73.8039 74.6549 74.259 82.6483 76.2004 89.7923C77.884 95.7683 80.9479 101.502 84.6488 106.765C85.0432 107.281 85.5589 107.478 86.1504 107.356C87.197 107.099 88.2891 107.038 89.3356 107.159C90.185 107.296 90.3822 106.386 89.9878 105.794C87.652 102.67 85.5589 99.2872 83.9359 95.7835C81.9793 91.6882 80.69 87.3958 80.2957 83.0427C79.6435 75.3072 82.5102 67.8295 87.7734 61.6562C84.5275 63.082 81.0086 64.8415 78.4149 68.421V68.4059Z\" fill=\"#FFE200\"><\/path><path d=\"M298.134 54.9526C297.224 54.4369 296.314 53.9818 295.343 53.5268C293.978 52.8746 292.021 54.4369 293.523 55.4834C294.691 56.3328 295.798 57.2429 296.905 58.2136C298.407 59.5787 301.258 56.7879 298.134 54.9677V54.9526Z\" fill=\"#FFE200\"><\/path><path d=\"M304.11 95.7842C301.896 100.592 298.771 105.082 295.525 109.117C294.297 110.618 293.902 112.241 294.16 113.409C294.357 114.001 294.752 114.516 295.389 114.577C296.299 114.577 297.603 113.925 299.09 112.165C304.747 105.598 309.555 97.9228 311.83 89.7929C313.651 83.0888 313.711 76.2027 310.92 69.4986C309.04 65.009 306.309 61.3687 303.048 58.4413C301.168 56.8791 299.014 60.125 300.318 61.6872C305.581 67.8605 308.387 75.3381 307.735 83.013C307.341 87.3661 306.052 91.6586 304.095 95.7538L304.11 95.7842Z\" fill=\"#FFE200\"><\/path><path d=\"M194.038 459.52C274.533 459.52 340.209 393.844 340.209 313.288C340.209 232.733 274.533 167.178 194.038 167.178C113.543 167.178 47.8521 232.854 47.8521 313.288C47.8521 393.723 113.528 459.52 194.023 459.52H194.038Z\" fill=\"#ED1B24\"><\/path><path d=\"M194.038 113.924C193.977 114.637 191.702 117.504 191.05 117.822H193.067C193.522 117.504 193.841 117.17 194.038 116.715C194.235 117.17 194.554 117.489 195.009 117.822H197.026C196.374 117.504 194.099 114.637 194.038 113.924Z\" fill=\"black\"><\/path><path d=\"M194.038 103.064C193.977 103.717 191.702 106.052 191.05 106.31H193.067C193.522 106.052 193.841 105.795 194.038 105.4C194.235 105.795 194.554 106.052 195.009 106.31H197.026C196.374 106.052 194.099 103.717 194.038 103.064Z\" fill=\"black\"><\/path><path d=\"M156.255 119.127L155.345 119.9C151.189 123.677 146.048 124.587 139.935 122.827L138.706 122.433L139.753 121.72C142.089 119.961 144.561 118.929 147.094 118.535C149.627 118.08 152.297 118.217 155.027 118.854L156.255 119.111V119.127Z\" fill=\"black\"><\/path><path d=\"M169.846 104.884C169.846 105.4 167.828 107.675 167.252 108.009L169.269 107.751C169.664 107.493 169.921 107.235 170.179 106.902C170.437 107.159 170.832 107.417 171.226 107.554L173.243 107.357C172.591 107.22 170.058 105.4 169.861 104.884H169.846Z\" fill=\"black\"><\/path><path d=\"M144.607 107.873C144.667 108.464 142.923 111.118 142.392 111.513L144.349 111.058C144.743 110.739 145.001 110.406 145.123 110.011C145.441 110.269 145.835 110.466 146.29 110.603L148.247 110.148C147.595 110.087 144.804 108.388 144.607 107.873Z\" fill=\"black\"><\/path><path d=\"M117.563 114.956C117.623 115.547 116.137 118.338 115.606 118.732L117.487 118.141C117.805 117.822 118.078 117.489 118.2 117.094C118.518 117.352 118.913 117.489 119.368 117.61L121.324 117.018C120.672 116.958 117.805 115.456 117.548 114.94L117.563 114.956Z\" fill=\"black\"><\/path><path d=\"M153.449 119.839C151.311 119.445 149.293 119.445 147.337 119.779C145.32 120.097 143.439 120.825 141.619 121.993C146.169 123.04 150.143 122.312 153.449 119.855V119.839Z\" fill=\"#ED1B24\"><\/path><path d=\"M231.806 119.127L232.716 119.9C236.948 123.677 242.013 124.587 248.126 122.827L249.355 122.433L248.308 121.72C245.972 119.961 243.5 118.929 240.967 118.535C238.434 118.08 235.764 118.217 233.034 118.854L231.806 119.111V119.127Z\" fill=\"black\"><\/path><path d=\"M218.215 104.884C218.215 105.4 220.233 107.675 220.809 108.009L218.792 107.751C218.397 107.493 218.14 107.235 217.882 106.902C217.624 107.159 217.23 107.417 216.835 107.554L214.818 107.357C215.47 107.22 218.003 105.4 218.2 104.884H218.215Z\" fill=\"black\"><\/path><path d=\"M243.454 107.873C243.394 108.464 245.138 111.118 245.669 111.513L243.712 111.058C243.394 110.739 243.121 110.406 242.939 110.011C242.62 110.269 242.226 110.466 241.771 110.603L239.814 110.148C240.466 110.087 243.257 108.388 243.454 107.873Z\" fill=\"black\"><\/path><path d=\"M270.498 114.956C270.438 115.547 271.924 118.338 272.455 118.732L270.574 118.141C270.256 117.822 269.983 117.489 269.861 117.094C269.543 117.352 269.148 117.489 268.693 117.61L266.737 117.018C267.389 116.958 270.256 115.456 270.514 114.94L270.498 114.956Z\" fill=\"black\"><\/path><path d=\"M234.612 119.839C236.75 119.445 238.768 119.445 240.724 119.779C242.741 120.097 244.622 120.825 246.442 121.993C241.892 123.04 237.918 122.312 234.612 119.855V119.839Z\" fill=\"#ED1B24\"><\/path><path d=\"M247.095 93.4331C246.898 99.1513 247.034 97.6649 252.1 100.319C249.688 99.6064 247.292 99.1513 245.138 100.577C243.97 98.2413 241.695 97.4525 239.223 96.8762C244.941 97.0733 244.365 98.4384 247.095 93.4331Z\" fill=\"black\"><\/path><path d=\"M140.967 93.4331C141.164 99.1513 141.027 97.6649 135.961 100.319C138.373 99.6064 140.769 99.1513 142.923 100.577C144.091 98.2413 146.366 97.4525 148.839 96.8762C143.12 97.0733 143.697 98.4384 140.967 93.4331Z\" fill=\"black\"><\/path><path d=\"M148.581 63.0675C146.048 66.1921 142.074 66.7078 140.845 70.4845C140.254 72.1681 141.695 73.5484 143.06 73.9276C144.622 74.4433 145.396 72.1075 147.094 71.5159C146.381 72.3653 145.866 73.5332 146.321 74.1854C146.836 73.4119 147.291 72.881 148.596 72.5625C146.518 75.5505 147.428 76.0814 148.99 75.8842C149.9 75.8235 150.492 74.9742 151.584 74.4585C151.523 74.7163 148.657 77.3858 150.992 77.583C151.508 77.6437 153.207 76.8701 153.662 76.4151C153.525 77.4617 151.902 77.8408 153.465 78.6902C154.314 79.2059 155.346 78.2352 156.134 77.9167C154.253 80.5104 155.164 81.0412 156.331 80.6469C157.181 80.3283 157.894 79.4183 159.259 79.4183C158.485 80.0705 157.833 80.1918 157.833 81.0412C157.894 83.7714 160.427 83.5742 161.868 83.3164C160.821 84.0899 161.868 87.2145 162.323 87.2903C164.992 87.6088 165.644 86.8353 168.117 86.1224C171.696 85.0151 172.409 80.207 172.348 74.0338C172.288 68.6341 171.636 63.113 170.726 61.4143C169.618 61.0957 167.025 62.5822 167.025 64.1444C166.827 63.4316 166.372 62.84 165.978 62.84C165.129 62.9007 164.294 64.1444 163.566 64.463C160.958 65.6309 163.172 62.1271 163.172 61.93C159.532 61.7934 159.532 66.9353 159.532 61.6114C156.999 61.2171 155.3 66.4196 155.497 61.8693C153.874 60.4435 152.631 61.8086 151.66 62.9765C150.947 63.8866 150.295 64.6601 150.234 64.2809C150.098 63.5074 150.553 62.1423 150.431 61.7479C150.173 61.0351 148.808 62.8552 148.611 63.113L148.581 63.0675Z\" fill=\"#ED1B24\"><\/path><path d=\"M220.233 59.0472C220.551 61.383 220.233 62.4903 219.914 63.734C218.231 69.1337 220.688 74.1997 220.506 79.6601C222.584 80.8887 222.387 78.8107 223.039 77.1271C224.267 71.7274 229.348 85.4541 235.127 79.6601C237.008 77.1878 240.588 74.5182 244.289 74.8519C249.173 77.84 247.019 63.9919 245.654 63.279C245.138 63.0211 244.031 63.6734 244.031 63.4762C243.894 62.3083 243.439 61.5196 242.802 61.5196C241.634 61.2617 241.179 62.1111 240.921 63.3397C240.785 64.1891 239.875 63.5975 239.951 61.7774C239.298 62.3689 238.843 63.5975 238.586 63.7947C238.07 64.1891 238.722 63.7947 238.191 62.2324C237.736 60.7308 237.145 59.8966 236.568 62.4296C236.174 64.0525 234.232 66.7221 231.229 64.9626C229.864 64.1132 229.606 60.0179 227.453 59.5629C226.345 59.3657 227.195 60.7308 226.285 60.6095C226.027 60.5488 225.83 59.8359 225.314 59.4416C224.404 58.7894 225.708 59.7601 223.099 56.3777C220.824 53.5869 219.975 57.5456 220.233 59.0472Z\" fill=\"#ED1B24\"><\/path><path d=\"M273.881 97.6042C272.516 97.7407 271.606 98.3777 271.272 99.6215C270.559 102.488 275.367 101.699 278.234 101.305C282.845 100.714 282.466 104.627 285.12 103.717C286.682 103.201 285.833 97.0127 287.85 95.0712C288.897 94.1005 291.354 93.0539 291.748 92.0073C292.522 89.9293 291.035 88.1092 288.047 87.3205C286.819 87.0627 286.622 85.7582 284.801 85.8947C282.39 86.0313 281.616 87.9727 280.448 89.7928C279.538 91.1579 278.568 92.523 276.929 93.1752C274.912 93.9488 274.715 96.1026 273.881 97.6042Z\" fill=\"#ED1B24\"><\/path><path d=\"M110.934 94.0852C113.801 97.9226 117.639 100.911 120.096 100.713C122.113 100.395 123.16 97.9833 121.977 95.3744C119.504 89.7169 114.817 88.0333 114.696 81.587C110.995 79.9034 106.824 81.1927 102.41 83.4071C97.0105 87.3811 91.808 89.9747 82.6467 89.004C83.8146 93.0993 85.6954 96.9974 87.9099 100.577C90.4429 100.638 92.263 99.5304 92.6574 97.3917C92.9152 96.2845 93.8253 94.2065 95.5848 94.2065C94.3562 95.1166 93.3703 97.4524 94.614 97.9833C96.7527 98.954 97.8599 92.9173 99.8165 92.4622C99.3008 93.6302 97.0864 96.5575 99.4222 96.5575C101.242 96.239 101.106 92.9173 103.002 93.1145C103.26 94.161 102.744 96.6334 104.23 96.5575C106.308 96.0418 105.656 93.0538 106.961 93.0538C106.642 96.0418 110.009 95.5261 110.934 94.1004V94.0852Z\" fill=\"#ED1B24\"><\/path><path d=\"M235.977 135.447C237.539 136.221 240.269 136.357 242.408 136.297C246.443 136.16 244.031 138.83 246.564 138.83C250.72 138.83 253.844 143.714 250.007 145.595C249.097 146.05 247.535 145.989 245.851 145.989C244.349 146.444 248.9 148.325 244.622 148.977C242.999 149.235 238.313 147.87 238.313 150.736C238.313 152.359 233.429 153.33 232.064 153.527C219.899 155.211 206.9 156.06 194.023 156.06C185.635 156.06 177.187 155.666 168.981 155.014C166.19 154.756 166.115 152.541 163.384 151.829C161.883 151.434 159.941 151.631 157.924 151.434C153.434 150.979 153.95 147.657 149.855 148.31C146.215 148.901 142.635 146.489 143.227 144.669C143.621 143.623 145.896 143.046 149.278 142.713C146.867 141.742 147.519 142.121 144.925 142.061C141.877 142 141.088 141.469 141.937 140.559C142.65 139.846 147.276 139.588 144.212 138.997C139.601 138.087 147.731 135.933 148.566 135.554C151.887 134.128 154.739 132.035 158.379 131.458C170.468 129.578 182.238 128.667 194.008 128.667C203.821 128.667 213.65 129.32 223.6 130.624C227.953 131.14 232.124 133.551 235.962 135.432L235.977 135.447Z\" fill=\"#ED1B24\"><\/path><path d=\"M227.847 190.264C221.734 188.58 215.485 187.336 209.054 186.563C208.144 186.426 207.173 186.365 206.263 186.244V229.032C202.305 228.441 198.194 228.122 194.038 228.122C189.882 228.122 185.787 228.441 181.813 229.032V186.244C117.184 192.493 66.3264 247.173 66.3264 313.304C66.3264 379.435 120.035 437.239 187.213 440.879V427.289C127.452 423.709 79.856 373.899 79.856 313.304C79.856 259.398 117.639 214.077 168.026 202.185V232.233C145.077 239.65 126.284 256.486 116.395 278.206L128.484 284.258C131.153 278.342 134.535 272.806 138.631 267.877V358.852C130.956 349.418 125.556 338.103 123.357 325.62L110.161 328.411C117.32 368.211 152.236 398.637 194.038 398.637C199.104 398.637 204.185 398.182 209.054 397.272C215.622 396.104 221.932 394.147 227.847 391.614C258.076 378.419 279.281 348.311 279.281 313.319C279.281 287.504 267.647 264.297 249.431 248.689V213.637C284.407 233.203 308.205 270.531 308.205 313.319C308.205 364.495 274.321 407.935 227.832 422.435C221.78 424.316 215.47 425.681 209.039 426.53C206.309 426.925 203.639 427.183 200.849 427.304V440.894C203.639 440.697 206.309 440.5 209.039 440.181C215.47 439.408 221.719 438.164 227.832 436.48C281.859 421.586 321.72 371.972 321.72 313.319C321.72 254.666 281.859 205.189 227.832 190.294L227.847 190.264ZM220.036 202.155C222.705 202.807 225.299 203.52 227.832 204.294C230.501 205.143 233.095 206.053 235.628 207.085V239.012C233.095 237.587 230.486 236.282 227.832 235.114C225.299 234.007 222.69 233.036 220.036 232.187V202.14V202.155ZM265.751 313.289C265.751 340.606 250.341 364.404 227.847 376.553C221.992 379.677 215.683 382.013 209.054 383.439C204.17 384.486 199.165 385.062 194.038 385.062C178.567 385.062 164.188 380.057 152.418 371.669V255.014C157.226 251.571 162.429 248.705 168.026 246.49V303.976H181.813V242.653C185.787 242.001 189.882 241.606 194.038 241.606C198.194 241.606 202.289 242.001 206.263 242.653V352.543H220.051V246.49C222.72 247.597 225.314 248.765 227.847 250.13C230.577 251.632 233.186 253.255 235.643 255.014V304.309H249.431V267.831C259.638 280.253 265.751 296.058 265.751 313.289Z\" fill=\"#FFE200\"><\/path><path d=\"M54.2377 416.277C54.8899 418.75 55.8606 420.888 57.165 422.708C58.4694 424.468 60.153 425.894 62.231 426.864C63.9146 427.259 65.6134 427.774 67.2363 428.366C71.9232 430.247 76.2763 433.174 80.8873 437.072C79.3857 435.191 77.8992 433.371 76.337 431.612C73.7433 428.624 70.9373 425.696 68.2677 422.83C67.9492 422.511 67.6762 422.178 67.4184 421.859C65.9926 421.601 64.6882 421.085 63.3231 420.433C61.958 419.72 60.5929 418.871 59.1671 417.9C58.4543 417.385 59.1671 416.338 59.88 416.854C61.2451 417.764 62.5495 418.613 63.9146 419.265C64.5668 419.584 65.219 419.918 65.9319 420.115C65.3404 419.523 64.8854 418.886 64.3697 418.295C63.2017 416.732 62.1552 415.307 61.1844 413.805C60.6687 413.092 61.7001 412.379 62.231 413.092C63.2017 414.518 64.2483 416.019 65.4162 417.521C66.5841 419.023 67.8886 420.509 69.193 421.95C71.8625 424.817 74.532 427.668 77.2622 430.793C79.0216 432.81 80.7659 434.827 82.404 436.966C81.0996 433.72 80.1289 430.262 79.3402 426.622C78.6273 424.544 77.4594 422.329 76.0184 420.115C71.6653 413.229 67.0392 407.571 59.8345 403.794C55.7392 401.58 50.9918 400.154 45.3949 399.562C47.215 401.777 48.838 404.173 50.2789 406.782C51.9625 409.831 53.3428 413.092 54.2528 416.277H54.2377Z\" fill=\"#00844B\"><\/path><path d=\"M38.8879 243.517C38.7514 244.29 38.5694 245.018 38.175 245.792C38.7666 245.534 39.2823 245.473 39.798 245.473C39.4795 244.821 39.1458 244.169 38.8879 243.517Z\" fill=\"#00844B\"><\/path><path d=\"M36.6128 258.669C35.5055 259.579 34.6561 260.626 34.0039 261.794C33.291 262.962 32.836 264.266 32.5023 265.631C33.3517 269.332 33.8067 273.109 33.9281 276.886C34.4438 274.474 35.1567 272.199 35.9454 269.924C36.2639 269.074 37.5077 269.469 37.174 270.379C36.2639 272.851 35.4903 275.521 34.9595 278.114C36.3246 275.521 37.9475 273.367 39.5705 271.486C40.2833 270.713 41.0721 269.924 41.7849 269.211C43.7416 267.33 45.7589 265.829 47.761 264.463C46.1381 260.11 44.3786 255.879 42.5585 251.723C42.3006 252.117 42.0428 252.496 41.7849 252.83C40.4198 254.908 38.7969 256.864 36.5824 258.685L36.6128 258.669ZM40.9659 262.234C41.2844 262.097 41.5574 261.915 41.8153 261.779C42.331 261.324 42.7253 260.808 43.1804 260.217C43.4989 260.535 43.6354 261.187 43.6354 261.9C43.6354 264.115 42.9832 264.433 41.8153 264.949C41.3602 265.146 40.7687 265.404 40.1317 265.798C40.071 264.297 39.6766 262.674 40.981 262.219L40.9659 262.234Z\" fill=\"#00844B\"><\/path><path d=\"M45.9105 428.123C46.9571 429.033 47.9278 429.943 48.8986 430.914C50.203 432.142 51.5681 433.583 52.9938 435.267C56.4976 439.498 62.1551 444.307 68.9199 445.611C73.1517 446.385 77.7626 445.869 82.5708 443.017C82.4343 442.76 82.2523 442.502 82.1158 442.244C82.0551 442.244 81.9186 442.183 81.8579 442.183C78.612 440.682 75.6847 439.392 72.6966 439.316H72.4995C71.8472 439.316 71.1344 439.377 70.4822 439.514C69.1171 439.771 67.9492 439.969 66.9026 440.105C65.856 440.166 64.946 440.166 64.1724 440.045C63.8539 439.984 63.5202 439.908 63.6567 439.271C63.7932 438.679 64.1117 438.679 64.3696 438.755C65.0825 438.892 65.8712 438.892 66.8419 438.816C67.6913 438.755 68.662 438.619 69.7693 438.361C69.0564 438.103 68.3435 437.845 67.6306 437.451C66.0684 436.738 64.3847 435.828 62.5646 434.66C62.3068 434.463 62.0489 434.266 62.3675 433.75C62.7618 433.234 63.0197 433.431 63.2775 433.553C65.037 434.721 66.6599 435.631 68.2222 436.344C69.7238 437.056 71.2102 437.572 72.6511 438.027C75.897 438.088 78.9609 439.453 82.4039 441.015C82.5405 441.076 82.6618 441.152 82.7983 441.152L83.1168 440.757C77.3986 435.555 72.3174 431.778 66.7357 429.639C60.1075 426.97 52.9483 426.97 45.9257 428.138L45.9105 428.123Z\" fill=\"#00844B\"><\/path><path d=\"M48.0492 394.299C46.7448 392.995 45.2584 391.705 43.6202 390.462C42.1186 390.204 40.6929 390.067 39.1913 390.265C38.3419 390.401 38.1447 389.157 39.0548 389.036C39.9648 388.899 40.8142 388.839 41.5271 388.899C41.2086 388.642 40.8749 388.384 40.5564 388.187C39.7828 387.595 38.9941 387.019 38.2206 386.503C36.719 386.184 35.1718 385.593 33.4731 384.88C31.8501 384.167 30.0907 383.318 28.2099 382.286C27.3605 381.892 27.952 380.785 28.8014 381.179C30.6822 382.15 32.381 383.06 34.0039 383.712C34.459 383.97 34.9747 384.167 35.4297 384.304C35.0353 384.046 34.6561 383.712 34.3225 383.394C32.2445 381.771 30.2879 380.148 28.2706 378.388C27.5577 377.797 28.4071 376.826 29.0441 377.418C31.1221 379.177 33.0787 380.8 35.096 382.423C37.1133 384.046 39.1913 385.669 41.2693 387.17C43.9994 389.051 46.5324 391.068 48.9441 393.344C50.6277 394.967 52.0686 396.665 53.1759 398.288C52.9787 395.695 52.1293 393.086 50.5822 390.492C48.3071 386.594 44.9853 383.272 41.5423 380.345C36.8555 376.31 31.7288 373.519 26.1319 371.502C21.2479 369.743 16.0606 368.711 10.6609 368.059L10.7216 368.12C13.4517 370.137 16.0606 372.018 18.2599 374.687C22.158 379.374 26.2533 383.727 30.5457 387.686C34.7775 391.584 39.252 395.103 43.9994 398.212C47.0481 398.41 49.8542 398.865 52.4478 399.578C51.3406 397.757 49.8542 395.998 48.0189 394.314L48.0492 394.299Z\" fill=\"#00844B\"><\/path><path d=\"M38.5544 412.06C37.8415 412.257 37.5078 412.773 37.8415 413.425C38.2965 414.199 39.4037 414.593 40.1773 414.396C40.8902 414.259 41.2239 413.683 40.8902 413.031C40.4958 412.257 39.3886 411.863 38.5544 412.06Z\" fill=\"#00844B\"><\/path><path d=\"M68.6016 398.925C69.6481 397.423 67.7522 395.224 66.6449 396.71C66.1899 397.363 66.2506 398.394 66.8421 398.986C67.3578 399.501 68.1465 399.501 68.6016 398.925Z\" fill=\"#00844B\"><\/path><path d=\"M33.0333 357.305C34.2012 358.989 35.3084 360.809 36.2792 362.826C37.0527 364.389 37.7049 366.012 38.3571 367.771C39.5857 364.252 40.7688 361.856 39.0094 358.079C37.3257 354.378 34.9747 350.859 31.926 348.068C28.8015 345.277 25.0399 343.184 20.611 341.956C21.8395 344.231 22.9468 346.506 23.9327 348.918C25.1006 351.784 26.0107 354.712 26.86 357.897C27.5123 360.627 27.8308 363.691 28.0886 366.74C28.2858 368.165 28.4071 369.606 28.6043 371.032C31.471 372.2 34.2619 373.626 36.8555 375.324C36.992 373.959 37.1134 372.655 37.3712 371.426C37.5078 370.577 37.7656 370.198 37.5078 369.348C36.7949 367.21 36.0062 365.253 35.0961 363.372C34.186 361.492 33.1395 359.671 31.9716 358.033C31.4558 357.32 32.4266 356.608 33.0181 357.32L33.0333 357.305Z\" fill=\"#00844B\"><\/path><path d=\"M50.203 387.61C50.4002 384.288 50.1423 381.179 49.5508 378.054C48.7773 374.353 47.4728 370.713 45.7134 366.936C44.409 364.145 42.9225 361.415 41.4816 358.685C41.2844 361.415 41.0266 364.343 39.8587 367.391C39.343 368.756 38.8879 370.182 38.6301 371.684C38.3722 373.11 38.175 374.55 38.175 376.113C39.6008 377.083 41.0417 378.191 42.4068 379.359C43.2562 380.071 44.0298 380.784 44.8185 381.497C44.8792 379.874 44.682 378.373 44.3028 376.947C43.8478 375.188 43.1349 373.504 42.1641 371.805C41.7091 371.032 42.8164 370.379 43.2714 371.214C44.2421 372.973 45.0915 374.732 45.5465 376.613C46.0622 378.494 46.1987 380.451 46.0016 382.665C47.6245 384.288 49.0654 385.911 50.2334 387.61H50.203Z\" fill=\"#00844B\"><\/path><path d=\"M45.1219 362.826C45.7135 363.994 46.2899 365.162 46.8814 366.406C48.565 370.107 49.8694 373.626 50.6581 377.205C50.7947 375.249 50.916 373.231 51.0525 371.35C51.2497 367.847 51.371 364.464 51.4469 361.143C51.4469 360.233 52.7513 360.233 52.7513 361.143C52.6906 364.525 52.5541 367.968 52.2963 371.411C52.1598 374.536 51.9019 377.721 51.6441 380.845C51.3862 383.636 51.644 386.503 51.3862 389.294C52.2356 390.659 53.0091 392.16 53.5248 393.723C54.4956 392.752 55.2084 391.25 55.7393 389.233C56.3915 386.821 56.7859 383.773 56.9072 380.33C57.1651 373.049 56.5129 366.284 55.345 359.52C53.6613 354.454 52.2204 349.251 51.1132 343.912C49.9453 345.535 48.9745 347.492 48.0645 349.888C46.7601 353.331 45.7893 357.684 45.1371 362.826H45.1219Z\" fill=\"#00844B\"><\/path><path d=\"M15.4084 331.232C18.3965 334.159 21.3845 337.147 23.4018 341.439C23.4018 341.5 23.4625 341.5 23.4625 341.576C26.1927 342.547 28.6043 343.912 30.743 345.474C29.3779 342.744 27.7549 339.953 25.9955 337.223C23.781 333.704 21.4452 330.261 19.1094 326.878C19.1094 326.878 19.1094 326.818 19.0487 326.818C17.5471 326.302 16.0607 325.513 14.5591 324.603C12.9968 323.633 11.4345 322.389 9.87224 321.024C9.22003 320.432 10.0088 319.461 10.7216 320.114C12.2232 321.342 13.7097 322.525 15.2719 323.496C16.182 324.088 17.0921 324.603 18.0021 324.998C17.4864 324.224 16.9555 323.375 16.3792 322.586C15.4691 321.282 14.4984 319.992 13.3911 318.749C12.7996 318.096 13.7097 317.247 14.3619 317.899C15.4691 319.204 16.5005 320.508 17.4106 321.797C20.7323 326.348 24.0389 331.747 27.1027 336.555C29.3779 340.196 31.4558 343.836 33.1546 347.476C33.6703 347.931 34.1254 348.447 34.5804 348.978C35.3539 348.068 35.0961 346.05 33.9282 342.926C31.9109 337.405 28.7257 331.808 25.859 326.666C23.326 322.176 19.5492 317.763 15.0596 313.925C10.9036 310.346 6.15616 307.358 1.40868 305.34C1.27217 308.328 2.06089 311.316 3.42598 314.38C4.92758 317.763 7.06622 321.145 9.53855 324.725C11.2222 327.197 13.3153 329.214 15.3933 331.232H15.4084Z\" fill=\"#00844B\"><\/path><path d=\"M41.6183 345.671C40.4504 345.611 39.7375 346.066 39.4796 346.642C38.7061 348.144 40.1925 349.691 41.6941 349.691C42.5435 349.752 43.1199 349.236 43.3777 348.584C43.6356 348.068 43.6356 347.416 43.4384 346.9C43.2412 346.248 42.589 345.671 41.6183 345.671Z\" fill=\"#00844B\"><\/path><path d=\"M16.7128 355.287C16.4549 355.151 16.1213 355.151 15.8027 355.151C15.287 355.212 14.832 355.348 14.4376 355.667C14.0433 355.924 13.7248 356.319 13.5883 356.713C13.5276 356.971 13.5276 357.168 13.5276 357.426C13.5883 358.533 14.2405 359.504 15.1505 360.156C16.0606 360.808 17.1678 361.127 18.2751 361.066C18.6694 359.641 18.7301 358.336 18.4722 357.365C18.2144 356.258 17.5622 355.545 16.7128 355.287Z\" fill=\"#00844B\"><\/path><path d=\"M20.8687 300.077C23.9933 305.734 26.3898 311.453 28.2099 317.307C29.6357 322.115 30.7429 326.999 31.5923 331.944C31.653 329.472 31.9108 327.136 32.2445 324.861V324.542C31.5923 314.789 30.1059 306.599 27.497 300.228C25.4797 295.087 22.3552 290.157 17.6077 287.093C16.8341 292.356 16.637 297.559 17.3498 302.761C18.0021 307.645 19.3671 312.454 21.5058 317.262C23.0074 320.583 25.2067 322.919 26.9662 326.105C28.1947 328.319 29.3778 330.397 30.3485 332.278C29.575 327.333 28.4678 322.525 26.9662 317.717C25.146 311.923 22.8102 306.265 19.7463 300.744C19.2913 299.971 20.4592 299.318 20.8536 300.092L20.8687 300.077Z\" fill=\"#00844B\"><\/path><path d=\"M47.8521 313.288C47.8521 311.726 47.8521 310.164 47.9128 308.601C47.655 306.645 47.1393 304.825 46.487 303.202C45.4405 300.472 43.954 298.257 42.1946 296.437C41.2845 299.228 40.3138 301.958 39.3279 304.628C38.16 307.873 36.9921 311.134 35.9455 314.244C33.8069 321.069 32.7603 328.031 32.821 335.251C32.8816 338.376 34.7776 341.106 35.6118 344.033C36.0669 339.999 36.6584 335.964 37.2954 332.066C38.069 327.379 38.9791 322.829 40.0256 318.339C39.8284 317.232 39.7071 316.064 39.6313 314.896C39.6313 313.728 39.6919 312.484 39.8284 311.195C39.965 310.285 41.1935 310.422 41.1329 311.332C40.9357 312.56 40.875 313.743 40.9357 314.911C40.9357 315.503 40.9964 316.079 41.0722 316.671C41.3907 316.352 41.7244 315.897 41.9823 315.442C42.4373 314.669 42.8316 313.758 43.1502 312.651C43.2867 312.393 43.3473 312.06 43.9996 312.257C44.5911 312.454 44.5153 312.773 44.3939 313.03C44.0754 314.198 43.6204 315.245 43.0895 316.094C42.5738 316.944 41.9823 317.657 41.33 318.233C40.2835 322.844 39.3127 327.591 38.5392 332.278C37.7656 336.889 37.1741 341.576 36.7191 346.46C37.8263 346.263 37.8263 344.898 38.1448 343.988C39.1156 341.257 40.2835 338.33 41.4666 335.403C44.1361 328.699 46.9269 321.676 47.837 316.352V313.303L47.8521 313.288Z\" fill=\"#00844B\"><\/path><path d=\"M16.0607 283.696C18.1387 286.684 21.0054 287.731 23.4019 290.582C21.9761 286.426 20.4745 282.255 18.5937 278.297C16.2579 273.231 13.4519 268.483 9.81166 264.448C9.61448 264.191 9.35663 263.933 9.87233 263.538C10.3274 263.083 10.5245 263.341 10.7217 263.599C14.4985 267.755 17.35 272.578 19.7617 277.781C20.8082 279.995 21.7183 282.21 22.6283 284.546C21.2633 279.282 20.4139 274.338 19.9588 269.651C18.7303 266.466 16.9101 263.675 14.6198 261.127C12.4053 258.715 9.81166 256.576 6.94497 254.756C6.8843 259.64 7.46067 264.57 9.02294 269.575C10.4487 274.262 12.7239 278.934 16.0456 283.681L16.0607 283.696Z\" fill=\"#00844B\"><\/path><path d=\"M27.315 295.663C27.7093 292.933 27.9065 290.142 28.0279 287.336C28.1644 283.635 28.0279 279.798 27.77 275.96C27.5122 272.578 25.6314 268.619 23.9326 264.964C23.2804 263.735 22.704 262.431 22.1731 261.263C22.0366 260.944 21.9153 260.671 22.4917 260.414C23.068 260.156 23.2045 260.474 23.341 260.732C23.7961 261.9 24.4483 263.144 25.0247 264.433C25.6769 265.798 26.3291 267.163 26.9054 268.528C26.7689 267.36 26.6476 266.253 26.5111 265.085C26.0561 262.355 25.5404 259.564 24.9488 256.758C24.8881 256.44 24.7516 256.106 25.4038 255.985C26.0561 255.924 26.1167 256.182 26.1774 256.5C26.7689 259.367 27.3453 262.158 27.7397 264.888C28.0582 267.3 28.3312 269.635 28.5132 271.971C28.6497 273.336 28.9076 274.58 28.9683 275.869C29.2261 279.707 29.3626 283.605 29.2261 287.382C29.1654 291.083 28.7711 294.799 28.1189 298.378C28.3767 298.894 28.5739 299.485 28.7711 300.001C29.7418 299.349 30.1968 297.21 30.849 293.949C31.0462 293.039 31.2434 291.993 31.4406 290.885C33.3214 282.498 33.0029 273.261 31.0462 264.934C29.3626 257.653 26.2381 250.888 21.5513 245.822C20.6412 252.981 20.3227 260.459 21.0962 268.574C21.9456 277.735 24.1601 286.911 27.2695 295.618L27.315 295.663Z\" fill=\"#00844B\"><\/path><path d=\"M6.4443 297.999C7.03584 297.999 7.49087 297.802 7.87006 297.483C8.18859 297.165 8.4616 296.71 8.4616 296.179C8.4616 295.648 8.20375 295.208 7.87006 294.875C7.4757 294.556 6.96 294.359 6.36846 294.359C5.85276 294.359 5.3219 294.556 4.9427 294.875C4.62418 295.193 4.427 295.648 4.427 296.179C4.427 296.71 4.62418 297.15 5.01854 297.483C5.33706 297.802 5.86793 297.999 6.4443 297.999Z\" fill=\"#00844B\"><\/path><path d=\"M38.4329 247.02C37.0678 247.612 35.6421 248.78 35.1112 249.296C33.3518 251.116 32.0625 252.739 31.2131 254.24C29.7115 256.713 30.1666 257.425 30.9553 259.837C31.4103 258.866 31.7288 257.759 32.0625 256.713C32.9726 253.785 34.5955 252.481 37.1285 250.539C37.3864 250.342 37.6442 250.084 37.8414 249.948C38.5543 249.432 39.343 250.403 38.6149 250.918C38.3571 251.176 38.0992 251.374 37.9021 251.51C35.5662 253.33 34.004 254.498 33.2911 257.031C33.0332 257.88 32.7754 258.791 32.4417 259.503C32.1839 260.277 31.8502 260.929 31.471 261.46C31.6075 261.976 31.7895 262.567 31.926 263.144C32.1839 262.431 32.5175 261.779 32.8967 261.126C33.6096 259.822 34.5804 258.715 35.8241 257.683C38.3571 255.666 40.0559 253.254 41.6182 250.858C41.2996 249.629 41.1025 247.673 40.1166 246.884C39.798 246.565 39.1458 246.687 38.4329 247.02Z\" fill=\"#00844B\"><\/path><path d=\"M40.5717 272.32C38.0387 275.187 35.6877 278.752 33.8676 283.499C33.8676 283.499 33.8069 283.56 33.8069 283.636C33.6097 286.169 33.2912 288.777 32.6997 291.25C32.9575 291.053 33.2154 290.734 33.549 290.476C34.3984 289.505 35.3085 288.398 35.6877 287.609C37.1135 285.334 38.2965 283.711 39.6616 281.755C39.6616 281.694 39.7981 281.497 40.511 280.526C41.0267 279.813 42.0733 280.526 41.5576 281.3C41.4211 281.436 41.2391 281.755 40.7082 282.468C39.3431 284.424 38.1752 286.047 36.8101 288.322C36.3551 289.096 35.3843 290.34 34.4743 291.31C33.3064 292.539 32.457 292.539 32.1385 294.238C31.8199 295.739 31.5469 297.029 31.2891 298.136C34.2771 295.8 36.9466 293.328 39.2824 290.795C42.0733 287.746 44.2878 284.621 45.7135 281.633C47.0179 279.04 47.8522 276.294 48.1859 273.564C48.5044 271.092 48.383 268.62 47.7915 266.026C45.3192 267.709 42.8468 269.727 40.5717 272.336V272.32Z\" fill=\"#00844B\"><\/path><path d=\"M10.661 250.539C11.2526 250.858 11.9654 250.934 12.5418 250.736C13.194 250.479 13.649 250.024 13.9069 249.432C14.1647 248.841 14.1647 248.203 13.9069 247.475C13.649 246.823 13.194 246.308 12.6025 245.974C12.0109 245.716 11.2981 245.579 10.7217 245.837C10.0695 246.035 9.61445 246.49 9.3566 247.066C9.09875 247.657 9.09875 248.37 9.3566 249.023C9.55378 249.735 10.0695 250.251 10.661 250.524V250.539Z\" fill=\"#00844B\"><\/path><path d=\"M30.6974 245.914C31.4103 242.986 32.4569 240.195 33.7613 237.526C34.1556 236.677 35.3236 237.268 34.9292 238.042C33.6248 240.711 32.654 243.441 31.9412 246.232C31.4255 248.31 30.9704 250.464 30.7126 252.603C31.6226 251.298 32.7905 249.872 34.2315 248.371C36.1881 246.414 38.0689 245.246 37.6139 241.803C37.356 240.18 36.6431 237.647 34.8837 235.099C32.745 237.374 30.7884 240.362 29.8784 243.487C29.1655 246.081 28.9683 249.084 29.484 252.466C29.7418 250.252 30.1362 248.037 30.7126 245.898L30.6974 245.914Z\" fill=\"#00844B\"><\/path><path d=\"M83.6934 410.301C83.5569 409.906 83.7541 409.588 84.0877 409.451C82.2069 407.313 80.4475 405.159 78.688 402.884C78.5515 409.846 78.8852 416.474 79.856 422.587C80.766 428.183 82.2676 433.704 84.6034 438.846C85.7714 437.284 86.0292 436.571 86.8786 434.812C87.1971 432.339 87.3336 429.67 87.1364 426.879C86.8786 421.419 85.7107 415.625 83.6934 410.301Z\" fill=\"#00844B\"><\/path><path d=\"M85.2404 410.756C87.0605 415.958 88.1677 421.555 88.4256 426.879C88.4863 428.639 88.4863 430.322 88.4256 432.021C89.1992 430.792 89.4722 429.685 89.6542 428.184C90.1092 425.393 90.1699 421.419 89.9727 416.611C89.9727 416.353 90.0334 416.156 90.1699 416.095C88.4863 414.335 86.8482 412.576 85.2252 410.756H85.2404Z\" fill=\"#00844B\"><\/path><path d=\"M91.0344 427.926C91.9445 426.242 92.718 424.483 93.3702 422.526C93.6281 421.677 93.8253 420.767 94.0831 419.796C93.1124 418.946 92.2023 418.036 91.2923 417.202C91.4895 421.555 91.3529 425.196 91.0344 427.926Z\" fill=\"#00844B\"><\/path><path d=\"M373.244 318.157C368.299 321.342 364.204 326.742 361.474 332.005C361.277 332.4 361.155 332.46 361.155 332.855C361.216 334.675 361.095 336.495 360.761 338.315C362.778 336.176 364.856 334.083 366.934 332.005C367.071 330.959 367.192 329.988 367.45 329.017C367.708 327.971 368.042 326.879 368.497 325.832C368.815 324.861 369.998 325.377 369.665 326.226C369.27 327.334 368.952 328.304 368.694 329.351C368.633 329.745 368.497 330.2 368.436 330.58C371.303 327.849 374.291 325.18 377.279 322.51C377.992 321.919 378.78 322.905 378.128 323.481C375.064 326.151 372.076 328.82 369.149 331.611C369.467 331.611 369.801 331.611 370.12 331.672C370.893 331.672 371.743 331.732 372.531 331.808C373.441 331.869 373.305 333.173 372.395 333.037C371.682 332.976 370.893 332.9 370.059 332.9H367.844C365.236 335.433 362.703 338.042 360.23 340.833C359.457 343.7 358.152 346.551 356.453 349.221C356.969 348.902 357.5 348.629 358.016 348.311C359.244 346.49 360.609 344.61 362.445 343.245C366.934 339.862 370.514 337.132 373.623 333.886C376.809 330.701 379.539 327.061 382.269 321.919C383.695 319.249 384.408 315.67 385.97 313.395C380.964 314.502 377.188 315.609 373.229 318.142L373.244 318.157Z\" fill=\"#00844B\"><\/path><path d=\"M374.473 292.736C369.589 296.71 365.312 300.806 362.187 305.098C358.805 309.785 356.787 314.79 356.984 320.114C358.607 322.647 359.775 325.256 360.428 327.986C360.488 325.969 360.488 324.012 360.625 322.268C360.822 319.674 361.14 317.323 361.671 315.306C362.323 313.228 363.097 311.605 364.007 310.3C364.917 308.996 366.024 308.025 367.132 307.252C367.905 306.736 368.633 307.767 367.905 308.298C366.798 309.011 365.888 309.921 365.038 311.089C364.189 312.257 363.476 313.759 362.9 315.64C362.763 316.095 362.703 316.55 362.581 317.065C363.097 316.474 363.628 315.958 364.144 315.503C365.251 314.532 366.358 313.683 367.587 312.909C368.3 312.454 369.012 313.501 368.239 314.017C367.132 314.729 366.024 315.518 364.993 316.428C364.022 317.399 363.036 318.385 362.202 319.477C362.066 320.387 362.005 321.358 361.944 322.404C361.808 324.422 361.747 326.56 361.747 328.911C364.417 324.361 367.268 321.115 370.332 318.703C371.181 316.747 371.955 314.866 372.41 313.046C372.804 311.226 373.062 309.148 372.668 307.328C371.955 303.354 373.062 298.879 374.033 294.784C374.23 294.071 374.351 293.419 374.488 292.767L374.473 292.736Z\" fill=\"#00844B\"><\/path><path d=\"M353.663 352.815C349.173 356.592 346.246 361.794 344.501 367.316C344.441 367.316 344.441 367.376 344.441 367.376C344.896 375.567 342.621 383.439 340.148 390.856C342.363 387.155 344.501 383.06 346.519 378.828L346.913 378.054H346.852C346.989 377.084 347.049 376.173 347.049 375.263C346.989 374.353 346.852 373.443 346.731 372.594C346.534 371.744 347.778 371.487 347.96 372.336C348.142 373.185 348.217 374.095 348.278 375.006C350.159 370.713 351.979 366.36 353.617 362.189C353.936 361.339 355.119 361.794 354.785 362.644C353.162 366.876 351.342 371.229 349.446 375.521C349.643 375.385 349.765 375.203 349.962 375.066C351.008 374.293 352.04 373.565 353.086 372.928C353.86 372.533 354.391 373.64 353.738 374.035C352.692 374.626 351.721 375.339 350.75 376.052C349.446 377.099 348.339 377.933 347.687 379.374C346.382 382.165 345.017 384.834 343.591 387.367C346.124 384.698 349.052 382.225 352.176 380.087C354.391 378.661 356.666 377.357 359.002 376.249C360.17 372.928 359.396 370.395 358.744 368.256C358.425 367.209 358.152 366.299 358.031 365.329C357.379 359.413 362.126 351.875 365.251 346.93C361.095 348.098 356.924 350.115 353.678 352.846L353.663 352.815Z\" fill=\"#00844B\"><\/path><path d=\"M371.803 262.568C372.319 262.704 372.911 262.507 373.366 262.173C373.957 261.718 374.336 261.127 374.534 260.353C374.731 259.58 374.67 258.851 374.397 258.336C374.139 257.82 373.745 257.426 373.168 257.289C372.653 257.153 372.061 257.289 371.546 257.684C371.03 258.078 370.635 258.654 370.438 259.443C370.241 260.156 370.302 260.945 370.575 261.521C370.833 262.037 371.288 262.431 371.803 262.568Z\" fill=\"#00844B\"><\/path><path d=\"M345.214 272.578C346.64 272.776 348.005 273.488 349.446 274.793C349.507 273.17 349.765 271.471 350.159 269.848C350.296 269.135 350.478 268.483 350.751 267.77C350.356 266.405 349.901 265.101 349.446 263.872C348.93 262.568 348.4 261.4 347.763 260.368C347.247 259.595 348.354 258.943 348.809 259.716C349.522 260.823 350.114 262.052 350.629 263.356C350.948 264.13 351.221 264.979 351.479 265.829C352.252 263.948 353.238 262.189 354.345 260.49C353.83 257.502 352.525 255.682 350.826 254.514C349.264 253.406 347.308 252.951 345.366 252.83C343.091 256.986 342.12 259.458 342.181 261.991C342.242 264.661 343.349 267.452 345.245 272.457V272.594L345.214 272.578Z\" fill=\"#00844B\"><\/path><path d=\"M354.315 288.838C355.089 290.067 355.938 291.311 356.909 292.479C357.045 292.084 357.167 291.705 357.303 291.371C355.999 285.911 355.741 281.224 356.393 275.764C356.651 273.807 357.045 271.79 357.5 269.788C357.106 268.878 356.727 267.968 356.393 267.058C356.135 266.087 355.938 265.04 355.877 263.933C355.817 263.023 357.106 263.023 357.182 263.933C357.182 264.843 357.379 265.814 357.637 266.663C357.773 267.058 357.895 267.513 358.092 267.892C358.805 265.359 359.775 262.826 360.958 260.278C361.353 259.504 362.521 260.02 362.126 260.869C361.019 263.144 360.17 265.419 359.457 267.755C359.518 267.619 359.654 267.497 359.775 267.361C360.367 266.769 360.943 266.193 361.338 265.541C361.853 264.767 362.9 265.48 362.445 266.254C361.929 266.967 361.338 267.619 360.685 268.271C360.094 268.863 359.457 269.378 358.805 269.894C358.289 271.911 357.895 273.929 357.697 275.946C357.561 277.053 357.44 278.16 357.379 279.268C357.697 278.949 358.092 278.555 358.425 278.221C359.017 277.508 359.593 276.856 359.851 276.401C360.306 275.551 361.413 276.143 361.019 276.992C360.625 277.584 360.048 278.297 359.336 279.07C358.623 279.844 357.834 280.693 357.379 281.482C357.379 284.076 357.697 286.685 358.152 289.278C360.23 284.849 362.703 281.088 365.494 277.902C366.146 275.627 366.464 273.413 366.404 271.198C366.343 268.923 365.949 266.648 365.236 264.434C364.462 262.022 364.265 259.489 364.523 256.956C364.659 255.136 365.039 253.179 365.494 251.298C364.189 252.208 362.9 253.118 361.717 254.165C356.833 258.26 352.874 263.857 351.372 270.167C349.871 276.143 350.599 282.65 354.3 288.823L354.315 288.838Z\" fill=\"#00844B\"><\/path><path d=\"M355.422 300.274C355.422 299.759 355.483 299.228 355.483 298.712C353.602 296.498 351.782 294.222 350.022 291.947H348.066C347.414 291.947 346.761 291.887 346.049 291.75C345.139 291.614 345.336 290.385 346.185 290.521C346.837 290.582 347.489 290.658 348.142 290.658C348.46 290.719 348.733 290.719 349.052 290.719C348.4 289.869 347.823 289.035 347.232 288.246C346.185 286.821 345.154 285.455 344.183 284.015C342.56 283.878 340.998 283.559 339.572 282.847C338.723 282.452 339.314 281.284 340.088 281.679C341.058 282.134 342.105 282.452 343.212 282.649C341.908 280.89 340.679 279.07 339.511 277.31C338.996 276.537 340.027 275.809 340.558 276.598C341.726 278.281 342.894 279.98 344.077 281.664C344.016 281.072 343.88 280.435 343.819 279.843C343.622 278.615 343.364 277.432 343.106 276.203C342.909 275.293 344.153 275.035 344.335 275.885C344.592 277.113 344.85 278.418 345.047 279.661C345.305 281.027 345.503 282.452 345.639 283.893C346.488 285.061 347.398 286.305 348.233 287.473C348.748 288.125 349.203 288.838 349.734 289.49C349.734 289.232 349.795 288.974 349.795 288.777C349.856 287.928 349.856 287.094 349.856 286.305C349.856 285.395 351.16 285.395 351.16 286.305C351.16 287.154 351.16 287.988 351.099 288.838C351.039 289.551 350.963 290.203 350.842 290.916C352.464 292.994 354.087 295.011 355.786 297.028C355.983 295.982 356.181 294.95 356.499 293.904H356.438C355.271 292.478 354.163 290.977 353.314 289.475C350.781 285.243 349.537 280.89 349.416 276.598C346.291 272.957 343.364 273.534 339.602 274.262C338.889 274.398 338.177 274.52 337.388 274.656C338.237 281.482 339.86 286.623 342.727 290.658C345.518 294.693 349.613 297.681 355.468 300.274H355.422Z\" fill=\"#00844B\"><\/path><path d=\"M356.651 300.73C356.514 303.854 356.909 306.979 357.879 309.83C358.592 308.329 359.442 306.842 360.473 305.34L360.412 305.28C360.155 303.778 359.957 302.61 360.352 301.124C361.52 296.437 363.218 292.145 365.296 287.989C366.267 286.169 367.253 284.288 368.345 282.528C368.482 281.679 368.603 281.027 368.664 280.39C368.8 279.737 368.8 279.161 368.861 278.372C368.861 277.462 370.089 277.523 370.089 278.433C370.089 278.827 370.089 279.282 370.029 279.662C370.742 278.494 371.53 277.326 372.243 276.219C372.44 275.961 372.562 275.703 373.093 276.021C373.684 276.34 373.487 276.613 373.29 276.931C370.878 280.632 368.482 284.606 366.464 288.565C366.146 289.157 365.873 289.733 365.615 290.325L365.676 290.264C366.388 289.748 367.177 289.217 367.951 288.838C368.724 288.444 369.316 289.551 368.542 290.006C367.769 290.324 367.117 290.78 366.404 291.31C365.751 291.826 365.099 292.418 364.447 293.07C364.386 293.07 364.386 293.131 364.386 293.131C363.218 295.8 362.308 298.53 361.595 301.458C361.338 302.307 361.338 303.081 361.459 303.93C363.082 301.791 364.963 299.698 367.056 297.62C367.056 297.62 367.117 297.559 367.117 297.484C369.194 294.359 370.893 291.113 372.183 287.792C373.608 284.409 374.594 281.027 375.246 277.584C375.701 275.051 376.02 272.442 376.672 269.848C373.35 272.063 370.302 274.535 367.511 277.584C364.128 281.224 361.262 285.577 359.184 290.127C357.682 293.373 356.772 297.089 356.651 300.73Z\" fill=\"#00844B\"><\/path><path d=\"M385.333 299.167C385.591 298.576 386.243 297.15 385.136 297.089C384.62 297.089 383.907 297.347 383.058 297.802C381.753 298.652 381.374 299.759 380.843 301.124C380.843 301.185 380.782 301.26 380.782 301.321C381.95 301.321 382.86 301.124 383.573 300.805C384.347 300.487 384.938 299.895 385.333 299.183V299.167Z\" fill=\"#00844B\"><\/path><path d=\"M354.573 318.946C352.616 316.474 350.872 314.138 349.31 311.863C348.081 310.043 347.035 308.344 346.124 306.721C344.562 310.953 343.455 315.503 343 320.054C342.484 324.862 342.606 329.746 343.455 334.493C344.107 337.739 345.275 340.803 347.095 343.654C348.597 345.99 350.538 348.205 352.95 350.161C352.556 344.898 351.721 339.696 350.538 334.554C349.568 333.962 348.718 333.325 347.808 332.537C346.898 331.687 345.988 330.716 345.139 329.609C344.547 328.896 345.594 328.108 346.109 328.836C346.959 329.882 347.793 330.792 348.703 331.566C349.158 332.021 349.613 332.339 350.068 332.734C349.158 329.23 348.111 325.848 346.944 322.389C346.686 321.54 347.854 321.161 348.172 321.995C349.279 325.241 350.311 328.563 351.16 331.884C351.418 330.777 351.615 329.609 351.676 328.502C351.676 327.592 352.98 327.653 352.904 328.563C352.844 330.443 352.389 332.339 351.676 334.16C352.904 339.423 353.754 344.822 354.148 350.283C361.171 340.727 362.081 328.502 354.543 318.946H354.573Z\" fill=\"#00844B\"><\/path><path d=\"M337.6 398.591C341.18 397.029 344.562 395.406 347.869 393.192C348.066 392.282 348.324 391.372 348.718 390.522C349.112 389.612 349.628 388.702 350.22 387.853C350.417 387.595 350.614 387.337 351.13 387.716C351.645 388.035 351.448 388.308 351.266 388.565C350.675 389.339 350.22 390.188 349.901 391.038C349.704 391.356 349.583 391.69 349.507 392.084C353.739 389.021 357.576 385.577 361.277 381.937C361.929 381.346 362.839 382.195 362.187 382.847C358.349 386.624 354.512 390.006 350.675 392.797C347.156 395.33 343.394 397.605 339.299 399.304C339.102 399.82 338.844 400.275 338.647 400.806C342.878 400.548 347.095 399.183 351.266 396.65C355.877 393.92 360.427 389.824 364.856 384.425C367.905 380.784 371.166 377.341 374.351 373.898C366.874 373.838 359.138 376.947 352.889 381.118C346.003 385.805 340.27 392.115 337.615 398.606L337.6 398.591Z\" fill=\"#00844B\"><\/path><path d=\"M372.91 359.58C371.743 359.383 370.377 360.035 370.044 361.203C369.649 362.31 370.438 363.281 371.545 363.478C372.653 363.675 374.018 363.023 374.412 361.855C374.731 360.748 374.018 359.838 372.91 359.58Z\" fill=\"#00844B\"><\/path><path d=\"M344.365 348.144C343.713 347.37 342.681 347.37 341.953 348.144C341.635 348.538 341.438 349.054 341.438 349.706C341.438 350.297 341.635 350.874 342.029 351.268C342.681 352.042 343.652 352.315 344.365 351.405C344.684 351.01 344.881 350.434 344.881 349.782C344.881 349.13 344.684 348.553 344.365 348.159V348.144Z\" fill=\"#00844B\"><\/path><path d=\"M333.444 399.304C332.595 397.621 332.019 395.406 331.624 392.797C331.169 389.551 331.033 385.714 331.306 381.543C331.503 378.221 331.897 374.914 332.474 371.471C333.065 368.028 333.899 364.509 335.082 361.006C335.34 360.096 336.584 360.49 336.25 361.4C335.143 364.843 334.294 368.286 333.717 371.669C333.126 375.051 332.807 378.373 332.61 381.619V381.679C332.807 381.361 332.929 381.027 333.126 380.769C333.839 379.662 334.552 378.555 335.401 377.523C335.993 376.871 336.963 377.66 336.372 378.373C335.598 379.343 334.87 380.329 334.233 381.437C333.581 382.483 333.004 383.575 332.474 384.758C332.413 387.686 332.534 390.355 332.868 392.691C333.187 395.027 333.839 397.636 335.143 399.714C336.705 399.001 337.873 393.54 338.586 391.523C342.029 381.315 345.214 370.258 341.574 358.822C340.861 356.486 339.815 354.211 338.526 351.996C337.813 350.692 336.963 349.402 335.993 348.159C333.581 357.972 330.198 367.406 325.921 376.386L325.663 376.841C325.603 382.635 326.058 388.277 327.483 392.312C328.651 395.755 330.547 398.227 333.46 399.334L333.444 399.304Z\" fill=\"#00844B\"><\/path><path d=\"M307.765 434.296C311.011 430.398 314.333 428.441 315.501 423.239C315.819 421.677 315.956 420.19 315.895 418.628C315.834 417.657 317.063 417.521 317.124 418.491C317.26 420.175 317.124 421.874 316.729 423.497C316.593 424.149 316.411 424.801 316.214 425.378C317.518 424.012 318.747 422.647 319.915 421.222C321.932 418.749 323.752 416.156 325.254 413.092C325.709 412.318 326.816 412.895 326.421 413.683C324.799 416.808 322.978 419.477 320.961 422.01C320.188 422.92 319.459 423.83 318.625 424.68C319.596 424.164 320.506 423.633 321.416 423.254C322.19 422.86 322.781 423.967 321.932 424.361C320.764 424.953 319.52 425.59 318.352 426.318C314.454 428.654 311.648 431.657 308.736 435.161C307.234 436.981 305.809 438.862 304.504 440.879C309.707 438.998 314.318 436.389 318.413 432.749C322.842 428.851 326.664 423.709 329.925 417.081C331.745 413.243 333.429 409.467 335.128 405.629C335.901 403.748 336.751 401.852 337.6 399.972C320.43 407.449 309.191 419.993 304.899 438.073C305.809 436.768 306.719 435.54 307.765 434.296Z\" fill=\"#00844B\"><\/path><path d=\"M315.562 404.188C316.077 404.188 316.532 404.052 316.866 403.733C317.185 403.415 317.458 402.884 317.579 402.11C317.579 401.853 317.579 401.519 317.518 401.261C317.458 400.806 317.26 400.412 317.063 400.154C316.805 399.896 316.548 399.699 316.214 399.699H315.956C315.501 399.759 315.107 400.017 314.788 400.412C314.47 400.806 314.272 401.382 314.197 402.035C314.197 402.626 314.333 403.202 314.652 403.658C314.849 403.976 315.167 404.173 315.562 404.173V404.188Z\" fill=\"#00844B\"><\/path><path d=\"M347.429 415.504C346.322 414.73 344.638 414.851 343.531 415.64C342.302 416.55 342.424 417.976 343.986 418.507C344.699 418.765 345.548 418.704 346.322 418.507C347.687 418.112 348.794 416.626 347.429 415.519V415.504Z\" fill=\"#00844B\"><\/path><path d=\"M315.88 436.374C312.24 438.968 308.205 440.985 303.852 442.486C302.805 443.397 301.971 444.564 301.319 445.808C300.864 446.718 300.409 447.689 300.015 448.857C303.261 448.72 306.779 447.75 310.617 446.187C313.347 444.109 315.956 441.758 318.231 439.165C318.883 438.452 319.793 439.301 319.202 440.014C317.837 441.576 316.335 443.002 314.773 444.443C317.897 442.941 321.204 441.197 324.783 439.241C325.557 438.786 326.209 439.893 325.375 440.348C321.143 442.684 317.245 444.701 313.605 446.324C315.031 446.46 316.472 446.718 317.958 447.37C318.474 447.568 318.474 447.886 318.155 448.341C319.52 447.75 320.825 447.113 322.053 446.324C328.621 442.486 334.278 436.768 338.829 431.308C331.548 430.14 321.856 432.081 315.88 436.374Z\" fill=\"#00844B\"><\/path><path d=\"M311.785 447.492H310.875C307.098 448.993 303.655 449.903 300.409 450.161C306.582 451.663 312.376 450.813 317.639 448.599C317.579 448.538 317.503 448.538 317.442 448.462C315.622 447.689 313.665 447.613 311.785 447.492Z\" fill=\"#00844B\"><\/path><path d=\"M303.079 440.348C303.473 438.468 303.928 436.648 304.444 434.888C302.942 432.931 301.85 429.291 301.198 426.895C300.94 425.787 299.12 424.559 298.073 424.028C297.3 423.634 297.815 422.526 298.665 422.921C299.636 423.376 300.546 424.028 301.334 424.877C301.592 423.77 301.926 422.663 302.305 421.632C302.821 420.13 303.473 418.704 304.383 417.476C304.975 416.763 306.006 417.536 305.43 418.249C304.58 419.356 304.004 420.661 303.473 422.026C303.018 423.391 302.624 424.817 302.366 426.182C302.821 428.715 303.731 431.126 304.975 433.144C305.945 430.216 307.053 427.426 308.418 424.756C309.009 420.069 308.933 415.974 308.281 412.394C307.963 410.256 307.371 408.238 306.597 406.479C303.215 410.574 299.575 414.472 295.737 418.188C295.995 426.576 298.665 431.642 301.395 437.042C301.987 438.088 302.502 439.181 303.079 440.364V440.348Z\" fill=\"#00844B\"><\/path><path d=\"M200.151 30.8812C198.012 31.852 198.467 34.1271 200.287 35.3102C202.426 36.6753 203.73 41.3621 204.519 46.1703C205.293 50.9177 205.566 55.8624 205.687 58.001C205.945 62.0356 206.005 66.1916 205.823 69.9077C205.687 73.1535 205.368 76.0809 204.853 78.3561C204.595 79.2661 204.337 80.1155 204.003 80.8284C203.29 82.6485 202.835 83.9529 204.853 85.9702C204.989 86.1067 205.171 86.2281 205.308 86.3646C205.763 86.6831 206.218 86.8803 206.733 86.8803C207.188 86.8803 207.704 86.6224 208.235 86.1067C208.432 85.9702 208.554 85.7882 208.69 85.591C209.6 84.4231 210.313 82.4665 210.768 79.8728C211.223 77.2033 211.481 73.8209 211.42 69.8015C211.42 64.3411 211.162 57.8949 210.192 51.661C209.221 45.427 207.659 39.3751 204.989 34.749C204.398 33.7024 203.685 32.4738 202.851 31.6245C202.077 30.9116 201.167 30.5172 200.181 30.9116L200.151 30.8812Z\" fill=\"#FFE200\"><\/path><path d=\"M219.975 113.135C219.125 113.59 217.245 115.092 217.108 115.547C217.108 115.092 215.606 113.408 214.772 112.68C207.81 112.089 200.924 111.831 194.023 111.831C187.122 111.831 180.175 112.089 173.349 112.68C172.5 113.333 170.938 115.092 170.938 115.547C170.801 115.031 168.92 113.59 168.01 113.135C153.51 114.637 139.268 117.428 125.48 121.463C124.707 121.66 123.857 122.828 123.918 123.419C123.918 124.071 125.419 123.419 126.512 123.161C127.937 122.843 127.422 124.132 128.134 124.329C128.59 124.39 129.181 124.329 130.546 123.935C130.607 124.39 129.636 124.648 128.863 125.497C127.952 126.544 127.558 127.772 129.575 127.636C131.138 127.575 131.714 127.12 132.306 127.378C133.352 127.772 132.503 128.349 134.323 127.894C154.026 123.283 174.047 120.932 194.008 120.932C217.214 120.932 240.497 124.117 263.187 130.366C261.367 127.636 265.144 127.241 267.086 127.954C268.056 128.349 272.88 130.821 276.323 130.366C279.766 129.911 278.598 128.485 276.717 127.317C274.381 125.891 271.378 125.436 270.665 125.497C268.906 125.634 261.504 123.677 261.822 122.448C265.205 123.358 268.784 124.466 272.227 124.587C255.513 118.793 237.888 115.031 219.944 113.135H219.975Z\" fill=\"#FFE200\"><\/path><path d=\"M176.671 69.7708C176.61 73.8054 176.868 77.1877 177.323 79.8421C177.839 82.4358 178.491 84.3924 179.401 85.5603C179.538 85.7575 179.72 85.9547 179.856 86.076C180.372 86.5917 180.903 86.8496 181.358 86.8496C181.874 86.8496 182.329 86.6524 182.784 86.3339C182.92 86.1973 183.102 86.076 183.239 85.9395C185.256 83.9222 184.801 82.6178 184.088 80.7977C183.77 80.0848 183.497 79.2354 183.239 78.3253C182.723 76.0502 182.389 73.1228 182.268 69.8769C182.071 66.176 182.131 62.0049 182.405 57.9703C182.541 55.8317 182.799 50.887 183.572 46.1395C184.225 42.3021 185.135 38.6012 186.56 36.5232C187.668 34.9609 190.079 30.2135 185.65 31.5786C185.332 32.0336 184.998 32.5493 184.74 33.1408C183.83 35.2795 183.178 38.3433 182.662 41.0735C182.207 43.2122 181.813 45.1688 181.358 46.276C179.341 50.8263 178.173 54.0722 177.46 57.5304C176.808 60.9128 176.686 64.5531 176.686 69.7556L176.671 69.7708Z\" fill=\"#FFE200\"><\/path><path d=\"M193.128 76.005C190.656 75.5499 188.836 73.4113 188.836 70.8631C188.836 68.0723 191.05 65.7213 193.78 65.6C190.914 65.4634 188.638 63.0669 188.638 60.2003C188.638 57.3336 190.853 54.9978 193.644 54.8006C191.05 54.5427 188.957 52.3889 188.957 49.7346C188.957 47.2622 190.777 45.1843 193.189 44.7292C191.232 44.4107 189.67 42.9091 189.215 41.0283C186.485 42.1356 185.059 44.9264 184.604 47.6566C184.012 51.8884 183.754 56.105 183.633 58.0616C183.436 62.0962 183.375 66.1915 183.497 69.8317C183.633 73.0169 183.952 75.8836 184.467 78.0223C184.664 78.9323 184.983 79.6452 185.241 80.3581C185.954 82.3147 186.545 83.7405 185.104 85.6971C185.817 85.4393 186.606 85.2421 187.379 85.1814C187.698 83.5585 188.487 82.2541 189.518 81.344C189.457 81.0861 189.457 80.8283 189.457 80.5704C189.457 78.356 191.02 76.4752 193.098 76.0201L193.128 76.005Z\" fill=\"#FFE200\"><\/path><path d=\"M203.594 78.0224C204.11 75.8838 204.443 73.0171 204.565 69.8319C204.701 66.1917 204.625 62.0964 204.428 58.0618C204.292 55.9231 203.973 50.9785 203.199 46.3523C203.063 45.3816 202.881 44.3957 202.684 43.4856C202.229 41.2105 200.803 40.0426 198.907 38.7988C199.423 41.529 197.678 44.1985 194.872 44.7142C197.284 45.1693 199.104 47.2472 199.104 49.7196C199.104 52.3891 197.026 54.5277 194.417 54.7856C197.208 54.9827 199.423 57.3186 199.423 60.1853C199.423 63.0519 197.148 65.4484 194.281 65.5849C197.011 65.7215 199.226 68.0573 199.226 70.8481C199.226 73.3811 197.405 75.5349 194.933 75.99C197.011 76.445 198.573 78.3258 198.573 80.5403C198.573 80.7981 198.573 81.056 198.513 81.3138C199.559 82.2239 200.333 83.5283 200.651 85.1512C201.501 85.2119 202.274 85.4091 202.987 85.7428C201.486 83.7862 202.016 82.2997 202.79 80.3431C203.048 79.6302 203.382 78.9173 203.564 78.0073L203.594 78.0224Z\" fill=\"#FFE200\"><\/path><path d=\"M95.3876 112.423C95.1298 112.741 94.5382 112.68 94.3411 112.286C93.2945 110.527 92.0659 109.419 90.7008 108.843C89.3357 108.267 87.91 108.191 86.469 108.585C85.0433 108.904 83.6782 109.692 82.5709 110.8C81.0693 112.165 79.9773 114.121 79.7043 116.26C79.6436 116.851 79.5677 117.428 79.5677 118.141C79.5677 119.187 79.7043 120.279 80.0835 121.189C80.4778 121.963 81.0542 122.555 81.9642 122.691C82.1007 122.691 82.2828 122.752 82.4193 122.752C83.0108 122.752 83.5265 122.555 83.9815 122.236C84.3759 121.978 84.6337 121.644 84.8309 121.265C85.0281 120.871 85.1495 120.416 85.1495 119.961C85.1495 119.445 85.0129 118.914 84.6944 118.459C84.5579 118.323 84.5579 117.944 84.6338 117.807C85.4073 116.123 86.4539 115.138 87.6825 114.758C88.7897 114.364 90.0941 114.44 91.3227 114.956C92.2934 115.274 93.2793 115.926 94.1135 116.639C95.5393 117.807 96.328 119.824 98.2088 118.065C98.8004 117.549 99.2554 116.897 99.5132 116.184C99.9076 115.335 101.076 115.79 100.681 116.639C100.363 117.549 99.7711 118.323 99.1189 118.975C96.5859 120.992 98.6032 120.992 98.6032 124.238C98.6032 124.633 98.6638 124.951 98.8004 125.285C99.5739 127.302 102.896 128.015 104.776 127.241C132.473 116.123 163.233 110.527 193.993 110.527C224.753 110.527 255.437 116.123 283.133 127.241C284.953 128.015 288.336 127.302 289.109 125.285C291.445 120.477 281.176 121.129 277.733 118.778C276.11 118.004 274.548 116.76 273.304 114.88C273.107 114.561 273.244 114.03 273.623 113.97C275.125 113.515 275.959 112.468 276.353 111.376C276.55 110.663 276.611 109.95 276.55 109.237C276.414 108.524 276.156 107.872 275.701 107.281C275.049 106.31 273.881 105.658 272.379 105.658C271.469 105.658 270.696 105.916 270.043 106.31C269.452 106.704 268.997 107.22 268.618 107.872C268.299 108.524 268.102 109.237 268.102 109.95C268.102 110.724 268.36 111.512 268.815 112.225C269.012 112.544 268.815 113.075 268.42 113.135C263.536 114.637 259.441 114.819 255.877 113.727C252.297 112.68 249.249 110.284 246.382 106.446C246.063 105.991 246.64 105.279 247.231 105.536C250.28 107.099 252.889 106.507 254.572 105.081C255.482 104.308 256.135 103.322 256.529 102.215C256.984 101.107 257.121 99.9395 256.923 98.893C256.666 96.9363 255.3 95.192 252.692 94.6005C252.434 94.5398 252.176 94.2061 252.176 93.9483C252.373 91.7338 251.584 90.1109 250.356 89.0036C249.643 88.4121 248.854 88.0329 248.02 87.8357C247.11 87.6385 246.2 87.6385 245.35 87.8357C243.727 88.2908 242.287 89.398 241.513 91.476C241.452 91.7338 241.058 91.931 240.8 91.8703C238.131 91.2181 236.189 92.1888 235.082 93.7511C234.43 94.7218 234.035 95.9656 233.975 97.1942C233.914 98.4228 234.111 99.6665 234.688 100.774C235.658 102.791 237.812 104.277 241.255 104.02C241.847 103.959 242.165 104.869 241.65 105.188C238.07 107.523 233.656 108.691 229.288 108.115C225.511 107.599 221.81 105.703 218.883 102.063C218.564 101.669 218.822 101.016 219.338 101.016C221.219 100.88 222.387 99.7879 222.917 98.4834C223.115 97.8919 223.175 97.2548 223.175 96.6026C223.175 95.9504 222.978 95.3741 222.72 94.7825C222.129 93.4781 220.9 92.5074 219.019 92.5074C217.457 92.5074 216.289 93.2202 215.637 94.191C215.182 94.7825 214.924 95.4196 214.863 96.1476C214.727 96.8605 214.803 97.5734 215 98.2256C215.394 99.3935 216.304 100.44 217.791 100.819C218.306 101.016 218.382 101.729 217.927 101.987C213.377 104.717 209.145 106.082 205.247 105.627C201.349 105.233 197.769 102.958 194.584 98.3469C194.19 97.8312 194.979 97.0425 195.494 97.4369C196.268 98.1497 197.512 98.4834 198.877 98.4834C199.923 98.4834 201.015 98.2862 202.001 97.8312C202.972 97.4369 203.882 96.8605 204.534 96.0111C205.308 95.101 205.763 93.8725 205.763 92.3102C205.763 90.7479 205.111 89.1856 204.079 88.0784C203.033 87.0318 201.668 86.3948 200.045 86.4555C199.787 86.4555 199.453 86.1369 199.453 85.8639C199.256 84.4988 198.74 83.4523 198.027 82.6787C197.254 84.1045 195.813 85.0904 194.053 85.151C195.282 90.217 195.221 89.8379 200.621 91.0664C198.088 91.0058 195.676 91.1271 193.993 93.0837C192.309 91.1271 189.897 91.0058 187.364 91.0664C192.764 89.8379 192.703 90.217 193.932 85.151C192.173 85.0904 190.747 84.1045 189.958 82.6787C189.245 83.4523 188.73 84.4988 188.532 85.8639C188.532 86.1218 188.214 86.4555 187.941 86.4555C186.439 86.3948 184.953 86.9712 183.846 87.8812C182.875 88.7306 182.283 89.8985 182.344 91.2029C182.344 92.113 182.799 92.8866 183.451 93.5388C183.77 93.7966 184.164 94.0545 184.558 94.191C184.953 94.3882 185.332 94.4488 185.726 94.3882C186.242 94.3882 186.834 94.191 187.289 93.6753C187.683 93.2202 188.517 93.6753 188.335 94.2668C188.199 95.0404 188.274 95.7684 188.532 96.3448C188.73 96.8605 189.124 97.3155 189.503 97.6492C189.958 97.9071 190.413 98.1042 190.929 98.1042C191.384 98.1042 191.9 97.9677 192.355 97.5885C192.87 97.1942 193.583 97.9829 193.265 98.4986C190.079 103.049 186.5 105.263 182.602 105.718C178.704 106.113 174.472 104.672 169.982 102.018C169.527 101.76 169.588 101.047 170.119 100.85C171.545 100.455 172.455 99.4238 172.849 98.2559C173.107 97.6037 173.167 96.8908 173.046 96.1779C172.925 95.4651 172.652 94.8129 172.273 94.2213C171.56 93.2506 170.452 92.5377 168.89 92.5377C167.009 92.5377 165.766 93.5084 165.113 94.8128C164.856 95.4044 164.719 95.9808 164.719 96.633C164.658 97.2852 164.78 97.9374 164.977 98.5138C165.493 99.8182 166.661 100.925 168.557 101.047C169.012 101.047 169.33 101.699 169.012 102.093C166.084 105.734 162.383 107.614 158.606 108.145C154.253 108.737 149.824 107.554 146.184 105.218C145.729 104.899 145.987 103.989 146.639 104.05C150.022 104.368 152.16 102.943 153.207 100.925C153.798 99.8182 154.056 98.4531 153.98 97.2245C153.844 95.9201 153.465 94.6915 152.812 93.7056C151.705 92.1433 149.764 91.2333 147.155 91.8855C146.897 91.9462 146.503 91.749 146.442 91.4911C145.668 89.4132 144.228 88.3059 142.605 87.8509C141.755 87.6537 140.845 87.6537 139.935 87.8509C139.086 88.0481 138.312 88.4424 137.599 89.0188C136.371 90.126 135.582 91.749 135.779 93.9635C135.779 94.2213 135.521 94.555 135.263 94.6157C132.67 95.1314 131.365 96.8908 131.032 98.8475C130.834 99.894 130.971 101.062 131.35 102.169C131.745 103.216 132.397 104.247 133.231 105.036C134.915 106.537 137.523 107.114 140.648 105.627C141.164 105.37 141.755 106.082 141.422 106.537C138.555 110.314 135.506 112.711 131.927 113.757C128.347 114.865 124.312 114.667 119.383 113.166C118.989 113.105 118.867 112.574 119.064 112.256C119.519 111.543 119.717 110.754 119.717 109.981C119.717 109.268 119.58 108.555 119.201 107.903C118.882 107.25 118.427 106.735 117.775 106.34C117.184 105.946 116.41 105.688 115.5 105.688C113.998 105.688 112.83 106.34 112.118 107.311C111.723 107.903 111.465 108.54 111.344 109.268C111.283 109.981 111.283 110.693 111.541 111.406C111.936 112.514 112.77 113.545 114.271 114C114.59 114.061 114.787 114.592 114.59 114.91C113.361 116.791 111.799 118.035 110.161 118.808C108.144 119.779 106.005 120.113 104.048 120.037C103.533 120.037 103.199 119.445 103.533 119.066C104.579 117.762 105.156 116.139 105.156 114.576C105.156 113.803 105.019 113.075 104.761 112.438C104.443 111.785 104.048 111.209 103.533 110.754C102.683 110.163 101.652 109.783 100.211 109.783C99.1037 109.723 98.2543 109.981 97.4808 110.436C96.7072 110.891 95.9792 111.603 95.3421 112.453L95.3876 112.423Z\" fill=\"#FFE200\"><\/path><path d=\"M197.739 39.7995C197.739 37.7822 196.055 36.0986 194.038 36.0986C192.021 36.0986 190.337 37.7822 190.337 39.7995C190.337 41.8168 192.021 43.5763 194.038 43.5763C196.055 43.5763 197.739 41.8927 197.739 39.7995Z\" fill=\"#FFE200\"><\/path><path d=\"M160.472 491.387C159.956 492.555 160.214 493.86 161.064 494.77C161.716 495.422 162.565 495.741 163.339 496.074C162.034 498.744 160.153 499.972 157.09 499.654C153.768 499.259 151.174 497.773 149.551 495.68C148.702 494.633 148.126 493.465 147.792 492.237C147.473 491.008 147.337 489.704 147.473 488.399C147.792 485.609 149.293 482.802 152.024 480.664C155.012 478.252 161.003 476.311 166.387 474.491C168.526 473.778 170.619 473.126 172.303 472.473C174.836 471.503 176.08 469.607 176.277 467.862C176.413 466.694 176.019 465.39 174.972 464.677C174.062 464.086 172.697 464.086 170.938 465.132C167.161 467.347 163.657 468.712 160.017 470.077C158.136 470.85 156.119 471.578 154.102 472.488C149.491 474.566 145.653 477.949 143.242 481.923C140.314 486.731 139.146 492.646 141.482 497.849C142.787 500.716 145.001 503.309 148.444 505.387C152.084 507.662 156.513 508.117 160.351 507.147C163.475 506.297 166.524 504.477 168.223 501.686C170.179 498.562 170.301 493.299 167.631 490.508C165.553 488.369 161.716 488.49 160.472 491.418V491.387Z\" fill=\"#FFE200\"><\/path><path d=\"M233.96 472.458C231.942 471.548 229.925 470.835 228.044 470.046C224.404 468.681 220.885 467.316 217.123 465.102C214.651 463.676 211.663 463.6 208.736 463.676C210.692 465.815 211.921 468.165 214.135 470.243C215.045 471.154 215.895 471.866 216.729 472.519C218.231 473.565 219.914 474.02 221.613 474.597C227.073 476.356 233.125 478.298 236.053 480.649C238.783 482.787 240.284 485.593 240.603 488.384C240.861 490.978 240.148 493.587 238.525 495.664C236.902 497.742 234.293 499.244 230.987 499.638C227.923 499.957 226.042 498.728 224.738 496.059C225.511 495.74 226.361 495.407 227.013 494.754C227.862 493.844 228.12 492.54 227.604 491.372C226.376 488.445 222.538 488.323 220.445 490.462C217.776 493.253 217.912 498.531 219.854 501.641C221.537 504.431 224.601 506.251 227.726 507.101C231.563 508.072 235.977 507.617 239.632 505.341C243.075 503.264 245.29 500.655 246.594 497.803C248.93 492.601 247.762 486.685 244.835 481.877C242.423 477.918 238.586 474.536 233.975 472.443L233.96 472.458Z\" fill=\"#FFE200\"><\/path><path d=\"M219.52 489.567C220.369 488.718 221.34 488.202 222.311 487.944C223.357 487.687 224.328 487.687 225.299 487.884C226.148 488.142 226.922 488.597 227.574 489.188C228.09 489.704 228.484 490.295 228.742 490.948C229.06 491.66 229.197 492.51 229.06 493.359C228.924 494.209 228.545 494.982 227.892 495.695C227.498 496.014 227.043 496.408 226.467 496.742C226.861 497.333 227.377 497.712 227.892 497.97C228.742 498.425 229.713 498.486 230.759 498.425C233.747 498.031 236.022 496.742 237.524 494.922C238.237 494.011 238.752 493.041 239.025 491.933C239.344 490.826 239.42 489.719 239.283 488.551C239.025 486.079 237.721 483.606 235.249 481.665C232.519 479.45 226.542 477.57 221.203 475.81C220.43 475.552 219.702 475.355 219.323 475.219C217.958 474.764 216.987 474.248 216.001 473.596C215.091 472.944 214.242 472.17 213.21 471.184C212.164 470.138 211.193 469.106 210.222 467.999L210.161 467.938C209.449 467.741 208.66 467.544 207.947 467.347C207.628 467.286 207.355 467.15 207.037 467.089C208.599 468.06 210.086 469.227 211.39 470.532C215.819 474.885 218.61 480.998 218.61 487.702C218.61 488.87 218.549 490.113 218.352 491.281C218.67 490.629 219.065 490.053 219.52 489.598V489.567Z\" fill=\"#FFE200\"><\/path><path d=\"M210.541 474.612C206.187 473.247 201.759 472.018 197.269 471.29C194.084 470.699 195.646 471.882 194.144 474.475C192.84 476.751 191.475 479.086 189.988 481.498C188.82 483.455 187.577 485.396 186.287 487.353C185.893 488.005 185.772 488.46 186.424 488.854C187.334 489.37 188.563 489.446 189.549 489.507C195.145 490.022 200.469 492.753 205.156 495.816C206.46 496.59 208.796 498.547 210.101 498.683C210.753 498.82 211.329 498.486 212.118 497.576H212.057C212.77 496.529 213.68 495.559 214.272 494.451C215.834 491.66 213.62 489.385 211.284 488.081C205.945 485.093 200.227 482.818 194.372 481.195C193.522 480.937 193.856 479.693 194.69 479.966C199.954 481.468 205.095 483.409 209.904 485.882C212.694 487.307 214.454 484.38 214.97 482.105C215.682 478.722 213.923 475.674 210.541 474.627V474.612Z\" fill=\"#FFE200\"><\/path><path d=\"M194.675 466.679C194.736 467.65 195.07 469.667 196.101 469.804C200.393 470.395 204.625 471.487 208.781 472.731C209.373 472.928 210.01 472.928 210.404 472.337C210.541 472.14 210.662 471.563 210.465 471.366C206.491 467.468 201.167 464.996 195.252 464.662C195.252 464.662 195.231 464.682 195.191 464.723C194.675 465.041 194.599 465.951 194.675 466.679Z\" fill=\"#FFE200\"><\/path><path d=\"M204.625 497.105C199.165 494.769 196.829 499.062 192.597 500.882C189.078 502.383 184.983 503.293 181.221 503.157C181.737 504.325 182.587 505.371 183.633 506.282L184.027 505.766C184.543 504.992 185.59 505.766 185.074 506.479L184.619 507.07C184.938 507.328 185.211 507.525 185.529 507.722C185.787 507.465 185.923 507.07 185.984 506.676C186.181 505.826 187.41 506.084 187.213 506.934C187.152 507.449 186.955 507.98 186.621 508.435C187.076 508.693 187.531 508.951 188.047 509.148C188.305 508.632 188.502 508.102 188.563 507.525C188.699 506.615 189.988 506.812 189.791 507.722C189.731 508.435 189.473 509.088 189.2 509.679C189.913 509.998 190.625 510.271 191.278 510.453C191.535 509.679 191.672 508.951 191.596 508.238C191.535 507.328 192.825 507.267 192.901 508.102C192.901 508.951 192.84 509.785 192.582 510.635C193.037 510.695 193.553 510.695 194.008 510.695H194.523C194.721 509.725 194.781 508.739 194.842 507.768C194.842 506.858 196.071 506.919 196.071 507.829C196.071 508.739 196.01 509.709 195.813 510.619C196.662 510.559 197.496 510.422 198.346 510.301C198.406 509.194 198.406 508.086 198.285 506.979C198.224 506.069 199.453 505.933 199.589 506.843C199.65 507.889 199.65 508.921 199.65 509.967C200.363 509.77 201.152 509.573 201.865 509.315C201.865 508.147 201.804 506.903 201.546 505.735C201.349 504.886 202.653 504.628 202.775 505.538C203.033 506.585 203.093 507.677 203.169 508.784C203.882 508.466 204.671 508.132 205.308 507.738C205.368 506.63 205.505 505.66 205.171 504.613C204.974 503.703 206.218 503.385 206.4 504.295C206.658 505.265 206.658 506.175 206.658 506.964C207.31 506.509 207.826 505.66 207.704 504.886C207.644 504.689 207.568 504.492 207.507 504.234C207.113 503.384 208.281 502.869 208.614 503.718C208.614 503.718 208.634 503.764 208.675 503.855C208.933 503.202 209.13 502.55 209.069 501.898C209.009 499.684 206.476 497.863 204.58 497.09L204.625 497.105Z\" fill=\"#FFE200\"><\/path><path d=\"M186.105 501.458C189.291 500.943 195.145 499.244 196.829 496.119C197.542 494.891 197.026 492.798 195.661 492.282C192.537 491.053 188.32 490.204 184.862 490.598C183.633 490.735 182.526 491.19 181.358 491.372C180.964 491.433 180.584 491.508 180.19 491.508C178.112 491.645 175.958 490.796 174.472 489.37C173.82 488.718 174.669 487.808 175.321 488.46C176.626 489.688 178.446 490.341 180.129 490.28C180.584 490.28 180.979 490.219 181.358 490.083C182.526 489.825 183.633 489.112 184.346 488.005C185.969 485.593 187.471 483.197 188.896 480.846C190.322 478.51 191.763 476.159 193.128 473.823C194.493 471.351 194.69 467.847 192.081 466.209C191.945 466.148 191.884 466.072 191.763 466.072C190.853 465.617 187.865 465.617 188.381 467.301C188.699 468.469 190.064 469.121 190.337 470.486C190.474 471.335 190.277 472.17 189.685 473.535C188.123 476.917 186.242 480.163 184.225 483.288C183.709 484.061 182.662 483.348 183.178 482.575C185.195 479.526 187.015 476.401 188.517 473.019C188.972 471.912 189.169 471.26 189.033 470.744C188.896 469.97 187.926 468.863 187.273 468.332C185.514 467.104 183.299 467.559 181.358 468.59C179.856 469.364 178.491 470.471 177.581 471.381C173.349 475.537 170.756 481.27 170.756 487.641C170.756 491.539 171.726 495.255 173.486 498.44C175.048 500.973 178.233 501.762 181.358 501.822C183.042 501.883 184.74 501.686 186.105 501.428V501.458ZM178.946 479.162C179.598 478.191 180.311 477.281 180.903 476.295C181.039 476.098 181.221 475.84 181.358 475.643C181.813 474.87 182.268 474.141 182.723 473.429C183.178 472.655 184.285 473.292 183.77 474.081C183.178 475.052 182.602 476.037 182.01 477.008C181.752 477.327 181.555 477.6 181.358 477.918C180.903 478.57 180.448 479.223 179.993 479.875C179.401 480.648 178.37 479.875 178.946 479.162Z\" fill=\"#FFE200\"><\/path><path d=\"M174.851 472.534C174.26 472.989 173.547 473.383 172.773 473.641C171.014 474.293 168.936 475.006 166.797 475.719C161.534 477.478 155.618 479.42 152.812 481.634C150.34 483.591 149.036 486.063 148.778 488.52C148.641 489.688 148.717 490.796 149.036 491.903C149.294 493.01 149.809 493.981 150.537 494.891C152.812 497.758 157.818 499.183 159.638 495.027C159.319 494.512 159.122 493.92 158.986 493.344C158.849 492.494 158.986 491.66 159.304 490.932C159.562 490.28 159.956 489.704 160.472 489.173C161.124 488.581 161.898 488.126 162.747 487.868C163.718 487.671 164.704 487.671 165.735 487.929C166.706 488.187 167.692 488.703 168.526 489.552C168.981 490.007 169.376 490.598 169.694 491.236C169.497 490.068 169.436 488.824 169.436 487.656C169.436 481.938 171.454 476.675 174.836 472.503L174.851 472.534Z\" fill=\"#FFE200\"><\/path><path d=\"M199.165 459.459C197.481 459.459 195.722 459.52 194.023 459.52C192.461 459.52 190.838 459.52 189.276 459.459C186.94 459.398 185.12 462.326 187.455 464.267C189.533 463.676 191.748 463.357 194.023 463.357C199.165 463.357 204.428 465.041 209.373 466.421C207.75 463.888 202.35 459.338 199.165 459.459Z\" fill=\"#FFE200\"><\/path><path d=\"M153.586 471.29C155.664 470.38 157.681 469.667 159.638 468.878C163.217 467.513 166.661 466.148 170.361 463.994C170.619 463.858 170.877 463.737 171.135 463.6C171.529 462.751 171.59 461.977 171.332 461.188C169.967 461.249 168.86 461.386 167.95 461.507C165.811 461.765 164.962 461.704 164.765 459.368C164.704 458.853 164.704 458.2 164.628 457.351C163.718 457.745 162.869 458.064 162.216 458.398C161.367 458.853 160.654 459.308 160.078 459.763C159.941 459.899 159.623 459.899 159.426 459.823C157.469 458.974 155.33 458.2 153.176 457.806C151.099 457.351 148.945 457.214 146.867 457.487C146.351 457.624 145.957 456.972 146.275 456.517C146.73 455.804 147.246 455.091 147.837 454.378C148.035 454.12 148.232 453.862 148.49 453.605C148.095 453.665 147.716 453.741 147.322 453.862C146.351 454.06 145.502 454.317 144.592 454.636C144.076 454.772 143.621 454.181 143.879 453.726L145.244 451.254C144.076 451.314 142.908 451.511 141.801 451.769C140.375 452.027 138.873 452.482 137.448 453.074C136.993 453.271 136.401 452.679 136.674 452.224L138.297 448.448L138.16 448.387C136.401 448.705 134.642 449.1 132.897 449.494C132.442 449.555 132.048 449.1 132.184 448.645L132.958 446.112C132.761 445.975 132.564 445.915 132.366 445.793C130.683 446.9 129.121 447.613 127.68 448.008C126.375 448.265 125.147 448.265 124.161 447.81C123.114 447.355 122.341 446.445 121.886 445.08C121.491 443.912 121.37 442.289 121.567 440.196C121.506 440.196 121.431 440.136 121.37 440.136L119.413 441.759C119.019 442.077 118.367 441.759 118.367 441.304L118.169 438.24C118.033 438.103 117.912 438.043 117.775 437.982C117.381 438.3 116.926 438.695 116.471 439.089C116.334 439.226 116.213 439.286 116.152 439.347C115.834 439.665 115.181 439.408 115.106 438.953C115.045 438.103 115.045 437.33 115.106 436.617C114.453 437.072 113.801 437.466 113.028 437.724C112.633 437.86 112.178 437.587 112.178 437.208C112.118 436.238 112.042 435.252 112.118 434.342C111.92 434.144 111.663 434.023 111.465 433.887C110.692 434.281 109.903 434.539 109.13 434.539C108.219 434.599 107.309 434.402 106.521 433.947C105.747 433.492 105.095 432.901 104.64 432.066C104.048 431.02 103.73 429.791 103.927 428.29C100.878 425.878 97.951 423.406 95.0843 420.812C94.9478 421.525 94.7658 422.177 94.4927 422.89C93.5827 425.878 92.2783 428.35 90.5947 430.959C89.1689 433.037 87.9858 435.054 87.0758 437.39C86.3022 439.271 84.8613 442.593 85.5742 444.61C86.1657 446.37 88.3043 446.43 89.6694 445.657C90.261 444.094 90.898 442.608 91.4896 441.106C92.2631 439.347 92.9911 437.724 93.704 436.222C94.0984 435.373 95.2056 435.965 94.8113 436.738C94.0984 438.3 93.3855 439.923 92.6726 441.546C92.0204 443.23 91.3075 444.929 90.6553 446.552C90.3368 447.462 90.4581 449.342 90.9132 450.192C91.3075 451.102 92.0811 451.496 93.0518 451.299C94.1591 451.041 95.0691 450.389 95.4635 449.418C95.9792 448.053 96.51 446.749 97.0864 445.52C97.6021 444.155 98.1937 442.79 98.8459 441.364C99.1644 440.515 100.347 441.046 100.014 441.88C99.4222 443.184 98.8459 444.549 98.2543 445.975C97.6628 447.401 97.0864 448.842 96.4949 450.268C95.9792 451.436 95.782 452.937 96.0399 454.242C96.237 455.288 96.8134 456.198 97.7235 456.835C98.77 457.487 100.256 456.244 100.59 455.334C100.909 454.424 101.182 453.514 101.5 452.603L102.152 450.647C102.471 449.797 103.715 450.192 103.381 451.041L102.668 453.059C102.41 453.908 102.077 454.818 101.758 455.728C101.303 457.093 101.167 458.519 101.364 459.884C101.622 461.113 102.137 462.356 103.047 463.327C103.7 464.101 104.276 464.829 105.262 464.374C105.914 464.116 106.49 463.524 106.688 462.948C107.461 460.809 108.25 458.519 108.963 456.32C109.418 455.015 109.812 453.787 110.131 452.998C110.388 452.148 111.632 452.543 111.299 453.392C110.844 454.757 110.525 455.728 110.191 456.714C109.418 458.928 108.69 461.067 107.916 463.342C107.4 464.768 107.4 466.072 107.719 466.922C108.113 467.892 108.887 468.347 109.858 468.287C111.162 468.15 112.451 467.119 112.588 465.814C112.724 464.586 112.906 463.084 113.24 461.461C113.634 459.505 114.15 457.305 114.742 454.894C114.999 454.044 116.243 454.378 115.97 455.212C115.379 457.548 114.863 459.763 114.469 461.719C114.15 463.539 113.877 465.162 113.816 466.527C113.756 467.498 113.877 468.15 114.211 468.484C114.529 468.939 115.06 469 115.576 468.803C116.622 468.484 117.199 467.437 117.714 466.467C118.488 464.965 119.14 463.281 119.671 461.461C120.263 459.247 120.778 456.911 121.173 454.242C121.309 453.392 122.538 453.589 122.401 454.439C122.007 457.169 121.491 459.581 120.9 461.78C120.308 463.737 119.671 465.481 118.822 467.043C117.851 468.924 118.23 472.898 121.097 470.623C122.978 469.197 125.071 465.481 126.299 463.281C126.618 462.629 126.952 462.114 127.149 461.856C127.604 461.082 128.711 461.719 128.195 462.508C127.998 462.826 127.74 463.281 127.422 463.934C126.315 465.814 124.692 468.818 122.811 470.698C121.643 472.003 119.823 474.217 120.217 476.038C120.414 476.948 121.127 477.463 122.037 477.463C123.721 477.524 124.965 475.901 125.814 474.597C126.982 472.64 128.286 470.896 129.591 469.136C131.017 467.255 132.457 465.435 133.883 463.676C134.475 463.024 135.445 463.812 134.854 464.525C133.352 466.285 131.927 468.105 130.622 469.925C129.318 471.548 128.089 473.307 126.921 475.188C126.148 476.356 124.843 477.403 124.449 478.707C124.055 479.875 124.13 480.785 124.449 481.437C124.707 482.029 125.298 482.347 125.951 482.287C127.058 482.15 128.089 481.119 128.681 480.269C130.501 477.676 132.382 475.203 134.399 472.731C136.356 470.319 138.494 467.983 140.648 465.708C141.3 465.056 142.21 465.966 141.558 466.618C139.419 468.833 137.326 471.169 135.385 473.58C133.368 475.916 131.547 478.464 129.727 480.997C129.212 481.847 128.559 482.423 127.968 482.817C127.194 484.638 127.452 486.716 128.226 488.02C128.544 488.414 128.878 488.733 129.196 488.991C131.077 489.961 132.579 486.579 133.034 485.411C134.202 482.544 135.764 480.072 137.584 477.933C139.465 475.856 141.619 474.035 143.955 472.412C144.212 472.215 144.47 472.018 144.865 472.549C145.183 473.065 144.925 473.262 144.667 473.459C142.453 475.021 140.314 476.781 138.555 478.798C136.795 480.876 135.309 483.151 134.262 485.881C133.61 487.565 131.927 489.203 133.671 490.887C133.989 491.205 134.444 491.478 134.899 491.6C135.354 491.797 135.87 491.797 136.401 491.736C137.448 491.6 138.479 490.826 139.131 489.142C139.526 486.473 140.557 483.743 142.059 481.27C144.652 477.114 148.626 473.535 153.51 471.32L153.586 471.29Z\" fill=\"#FFE200\"><\/path><path d=\"M267.055 453.483C261.595 450.753 255.68 449.054 251.19 447.886H251.129C251.387 448.66 251.19 449.388 251.19 450.222C251.129 450.616 250.674 450.935 250.28 450.738C249.309 450.283 248.521 449.828 247.747 449.373C248.141 450.222 248.399 451.132 248.596 452.239C248.657 452.694 248.278 453.089 247.823 452.952C246.518 452.694 245.229 452.3 243.985 451.906C243.728 451.845 242.939 451.314 242.681 451.253C243.394 451.966 244.638 453.074 245.548 453.923C245.942 454.317 245.411 455.152 244.895 454.97C242.817 454.257 241.255 453.407 239.435 452.437C240.148 453.802 241.195 455.303 242.165 456.532C242.484 457.047 241.771 457.836 241.255 457.442C239.374 456.213 237.554 454.848 235.795 453.407C235.537 453.468 235.279 453.604 235.021 453.665C235.416 454.712 235.871 455.743 236.326 456.729C236.584 457.321 235.673 457.897 235.279 457.442C234.43 456.395 233.596 455.364 232.867 454.257C231.639 454.575 230.395 454.909 229.167 455.227C230.334 456.456 231.578 457.639 232.807 458.746C233.52 459.338 232.67 460.309 231.957 459.717C230.456 458.413 229.091 457.048 227.801 455.561C226.831 455.819 225.845 456.016 224.935 456.213L228.378 459.99C228.969 460.642 228.059 461.492 227.407 460.839L223.433 456.547C222.129 456.805 220.764 457.063 219.399 457.321C219.914 457.715 220.445 458.17 221.022 458.549C222.326 459.52 223.615 460.43 225.056 461.34C225.83 461.795 225.117 462.902 224.343 462.447C222.917 461.537 221.552 460.566 220.248 459.58C219.399 458.928 218.564 458.276 217.776 457.563C216.805 457.76 215.758 457.882 214.788 458.018C215.637 459.58 216.547 460.946 217.654 462.174C219.08 463.797 220.642 465.162 222.462 466.269C222.66 466.406 222.857 466.527 223.054 466.664C224.874 467.513 226.694 468.165 228.514 468.878C230.471 469.652 232.412 470.38 234.49 471.29C239.374 473.504 243.333 477.084 245.942 481.24C247.565 483.909 248.612 486.837 248.991 489.688C249.249 491.963 249.051 494.239 248.475 496.453C249.188 497.166 250.432 496.65 251.205 496.135C252.707 495.088 253.875 492.692 254.527 490.159C255.3 487.17 255.437 483.909 254.785 482.089C253.025 477.478 250.295 473.762 246.716 471.032C243.136 468.241 238.722 466.285 233.58 465.056C232.67 464.859 232.989 463.63 233.838 463.827C239.177 465.056 243.788 467.073 247.489 470.001C251.266 472.928 254.117 476.765 255.938 481.634C256.256 482.484 256.393 483.652 256.453 484.88C256.453 485.593 256.848 486.245 257.56 486.64C258.865 487.489 259.578 485.472 259.775 484.501C260.548 480.209 259.32 476.174 257.045 472.867C254.117 468.438 249.309 465.132 244.88 463.63C243.97 463.372 244.425 462.129 245.275 462.462C249.961 464.025 254.967 467.528 258.152 472.155C260.685 475.992 262.05 480.603 260.822 485.548C260.624 486.321 260.564 486.852 261.019 487.626C261.216 488.081 261.671 488.475 262.187 488.338C264.522 487.883 264.977 483.727 265.175 481.968C265.432 480.148 265.569 478.267 265.569 476.31C265.508 473.838 265.175 471.366 264.007 469.348C262.323 466.163 257.181 463.691 253.086 461.613C251.857 461.021 250.674 460.445 249.704 459.854C248.93 459.459 249.506 458.291 250.295 458.746C251.266 459.338 252.434 459.853 253.678 460.506C257.909 462.584 263.233 465.253 265.19 468.757C266.418 470.971 266.813 473.641 266.873 476.295C266.873 478.252 266.676 480.269 266.418 482.15C266.282 483.652 267.465 484.289 268.633 483.318C270.514 481.756 271.757 478.768 272.273 475.643C272.789 472.2 272.531 468.56 271.363 466.482C269.998 463.949 268.041 461.871 265.645 460.111C263.233 458.428 260.382 456.987 257.257 455.758C256.408 455.44 256.863 454.257 257.712 454.59C260.897 455.819 263.885 457.32 266.358 459.141C268.951 460.961 271.045 463.175 272.531 465.905C273.441 467.589 273.896 470.259 273.76 472.989C273.76 473.702 273.502 474.096 274.215 474.612C274.988 475.203 275.898 475.522 276.748 474.748C277.203 474.293 277.597 473.58 277.915 472.792C278.628 470.714 278.826 467.908 278.568 465.966C277.915 460.566 272.91 456.471 267.055 453.483Z\" fill=\"#FFE200\"><\/path><path d=\"M281.1 455.167C279.22 453.028 276.55 451.072 272.91 449.449C271.09 448.6 269.27 447.432 267.51 446.264C266.54 445.611 265.554 445.035 264.583 444.307C263.612 443.594 262.96 443.139 261.656 443.139C261.003 443.139 260.745 443.336 260.882 443.989C261.079 444.641 261.656 445.414 261.989 446.067C261.14 446.067 260.488 446.006 259.653 445.748C258.607 445.49 257.575 445.156 257.378 445.809C256.923 446.855 259.198 448.857 260.245 449.191C262.717 450.101 265.25 451.148 267.662 452.376C273.835 455.501 279.114 459.915 279.887 465.83C279.948 466.679 280.024 467.65 279.948 468.697C280.918 469.47 281.176 469.804 282.284 468.757C283.785 467.256 285.074 464.662 284.619 462.448C284.028 459.854 282.996 457.382 281.1 455.167Z\" fill=\"#FFE200\"><\/path><path d=\"M298.467 436.117C297.952 433.902 297.163 431.763 295.995 430.065C294.888 428.502 293.386 427.471 291.506 427.334C290.99 427.334 290.459 427.395 289.883 427.532C289.17 427.668 288.517 428.047 288.26 428.76C287.865 429.67 288.396 431.172 289.109 431.748C290.671 432.977 292.097 434.615 293.401 436.359C294.964 438.498 296.329 440.712 297.102 442.472C297.3 442.866 297.497 443.321 297.694 443.837C299.12 444.231 298.998 443.973 298.998 442.669C298.998 442.472 298.998 442.214 299.059 441.956C299.12 440.333 298.922 438.179 298.467 436.101V436.117Z\" fill=\"#FFE200\"><\/path><path d=\"M292.355 437.163C291.187 435.479 289.761 433.917 288.32 432.81C287.471 432.097 286.44 431.702 285.454 431.763C284.604 431.899 283.77 432.279 283.042 433.189C282.648 433.644 282.451 434.159 282.526 434.69C282.587 435.919 284.286 437.36 285.059 438.133C287.85 441.061 290.717 444.049 293.189 447.689C293.902 448.796 294.691 450.359 295.009 451.921C295.859 452.239 296.966 452.573 297.421 451.526C297.618 451.011 297.679 450.298 297.679 449.509C297.542 447.295 296.632 444.564 295.919 443.078C295.146 441.319 293.902 439.18 292.34 437.163H292.355Z\" fill=\"#FFE200\"><\/path><path d=\"M284.149 439.043C283.558 438.391 282.921 437.815 282.648 437.481C282.056 436.829 281.146 436.253 280.236 436.055C279.584 435.919 278.932 435.995 278.355 436.51C277.703 437.102 276.732 437.678 276.672 438.725C276.414 440.803 277.976 441.516 279.402 442.82C280.509 443.867 281.616 444.898 282.784 445.884C284.801 447.643 286.561 449.524 287.926 451.799C288.639 453.104 289.23 454.469 289.61 456.031C289.746 456.683 289.867 457.26 290.838 457.396C292.855 457.533 294.023 455.182 293.963 453.438C293.902 451.678 292.992 449.737 292.082 448.432C289.67 444.853 286.879 441.925 284.149 439.074V439.043Z\" fill=\"#FFE200\"><\/path><path d=\"M281.95 446.84C280.782 445.869 279.675 444.762 278.507 443.715C277.4 442.668 276.292 441.576 275.064 440.53C274.093 439.756 272.728 438.968 271.621 438.77C271.166 438.71 270.453 438.573 270.256 439.165C270.059 439.878 270.514 441.121 270.65 441.895C269.543 441.637 266.873 440.075 267.268 442.411C267.723 445.338 271.044 447.158 273.441 448.265C277.278 449.949 280.069 452.042 282.086 454.378C284.104 456.714 285.272 459.383 285.863 462.174C285.924 462.568 286 463.023 286 463.403H286.515C287.107 463.403 287.562 463.205 287.941 462.948C288.336 462.629 288.593 462.174 288.791 461.522C288.851 461.067 288.927 460.612 288.927 460.02C288.791 457.032 288.017 454.499 286.849 452.406C285.621 450.267 283.922 448.432 281.965 446.809L281.95 446.84Z\" fill=\"#FFE200\"><\/path><path d=\"M350.933 230.7C350.28 229.017 348.855 229.138 347.414 229.654C345.396 232.703 343.455 236.024 341.62 239.543C339.739 243.183 337.979 247.021 336.478 250.995C336.159 251.844 334.976 251.389 335.31 250.54C336.811 246.505 338.632 242.607 340.512 238.967C342.393 235.327 344.41 231.944 346.488 228.82C347.717 226.863 348.248 224.785 347.596 222.51C347.277 221.342 346.488 220.235 345.184 220.038C344.926 220.553 344.592 221.084 344.274 221.539C342.196 224.209 340.315 226.939 338.419 229.669C336.599 232.46 334.84 235.266 333.217 238.193C332.762 238.967 331.594 238.39 332.11 237.541C333.732 234.614 335.553 231.747 337.373 228.956C339.253 226.165 341.21 223.435 343.227 220.766C344.077 219.719 344.592 218.551 344.653 217.323C344.79 214.79 341.862 211.347 339.906 214.077C337.494 217.459 335.098 221.039 332.747 224.603C330.214 228.501 327.741 232.475 325.33 236.57C324.875 237.344 323.767 236.707 324.222 235.918C326.695 231.823 329.167 227.788 331.7 223.951C334.172 220.113 336.645 216.413 339.178 212.894C339.633 212.241 339.951 211.589 339.891 210.679C339.891 210.163 339.754 209.708 339.496 209.314C338.723 208.207 337.085 207.949 336.25 208.996C333.52 212.241 331.184 215.502 328.909 218.748C326.573 222.131 324.359 225.634 322.023 229.214C321.568 229.988 320.461 229.275 320.976 228.562C323.312 224.922 325.527 221.479 327.863 218.035C330.274 214.517 332.807 211.149 335.659 207.691C336.372 206.781 336.174 205.552 335.795 204.642C335.598 204.385 335.401 204.127 335.28 203.93C334.051 202.564 332.944 202.428 331.836 203.732C327.544 208.161 322.736 213.227 318.246 220.644C317.791 221.418 316.684 220.781 317.2 219.992C321.75 212.454 326.634 207.373 330.926 202.822C331.836 201.912 332.686 201.321 332.489 199.895C332.352 198.848 331.836 198.014 331.124 197.362C329.698 196.194 329.046 195.997 327.741 197.362C325.527 199.637 323.388 202.307 321.234 205.234C319.096 208.222 316.942 211.407 314.727 214.79C314.591 215.047 314.409 215.305 313.878 214.987C313.362 214.668 313.484 214.395 313.681 214.077C315.895 210.694 318.034 207.448 320.188 204.521C322.402 201.533 324.617 198.803 326.816 196.528C327.923 195.36 328.575 194.45 327.665 192.887C325.982 190.218 324.541 191.917 323.054 193.6C320.84 196.073 318.701 198.606 316.623 201.336C314.545 204.127 312.528 207.054 310.571 210.179C310.374 210.436 310.253 210.694 309.661 210.376C309.146 210.057 309.343 209.784 309.464 209.526C311.481 206.341 313.499 203.353 315.577 200.623C317.715 197.832 319.869 195.223 322.084 192.751C323.13 191.583 323.646 190.734 323.707 190.021C323.843 189.429 323.509 188.853 322.994 188.261C321.765 186.896 318.959 184.03 317.533 187.215C316.168 190.203 314.212 192.554 311.937 194.298C309.404 196.255 306.476 197.544 303.412 198.196C296.132 199.758 288.715 196.634 282.936 192.478C277.021 188.185 271.166 182.134 267.586 175.247C264.462 169.271 262.839 162.309 264.522 155.681C253.526 160.231 243.318 162.507 233.504 162.764C226.224 162.962 217.578 161.991 210.101 159.579C200.151 156.394 187.804 156.394 177.854 159.579C170.377 161.991 161.792 162.962 154.451 162.764C144.637 162.507 134.429 160.231 123.433 155.681C125.116 162.309 123.493 169.271 120.445 175.247C116.804 182.134 110.95 188.185 105.034 192.478C99.2402 196.634 91.8384 199.758 84.5579 198.196C81.5092 197.544 78.5818 196.24 76.0337 194.298C73.7585 192.539 71.8019 190.203 70.4368 187.215C69.011 184.03 66.205 186.896 64.9764 188.261C64.4607 188.853 64.1271 189.429 64.2636 190.021C64.3242 190.734 64.8551 191.583 65.8865 192.751C68.101 195.223 70.2396 197.817 72.3934 200.623C74.4714 203.353 76.4887 206.341 78.506 209.526C78.6425 209.784 78.8245 210.042 78.3088 210.376C77.7173 210.694 77.596 210.436 77.3988 210.179C75.4421 207.054 73.4248 204.127 71.3469 201.336C69.2689 198.606 67.1151 196.073 64.9158 193.6C63.4142 191.917 61.9884 190.218 60.3048 192.887C59.3947 194.45 60.047 195.36 61.1542 196.528C63.3687 198.803 65.5832 201.533 67.7825 204.521C69.9211 207.448 72.1356 210.694 74.2894 214.077C74.4866 214.395 74.6079 214.668 74.0922 214.987C73.5765 215.305 73.3793 215.047 73.2428 214.79C71.0283 211.407 68.8897 208.222 66.7359 205.234C64.5973 202.307 62.4434 199.637 60.229 197.362C58.9245 195.997 58.2723 196.194 56.8466 197.362C56.1337 198.014 55.618 198.864 55.4815 199.895C55.2843 201.321 56.1337 201.912 57.0438 202.822C61.3362 207.373 66.205 212.439 70.7705 219.992C71.2862 220.766 70.179 221.418 69.7239 220.644C65.2343 213.227 60.4261 208.161 56.1337 203.732C55.0265 202.428 53.9192 202.564 52.6906 203.93C52.5541 204.127 52.3721 204.385 52.1749 204.642C51.7806 205.552 51.5834 206.781 52.3114 207.691C55.1781 211.134 57.7111 214.517 60.1076 218.035C62.4434 221.479 64.6579 224.922 66.9937 228.562C67.5094 229.275 66.4022 229.988 65.9472 229.214C63.6114 225.634 61.3969 222.131 59.0611 218.748C56.7859 215.502 54.4501 212.241 51.7199 208.996C50.8705 207.949 49.2476 208.222 48.474 209.314C48.2162 209.708 48.0797 210.163 48.0797 210.679C48.019 211.589 48.3375 212.241 48.7925 212.894C51.3255 216.413 53.7979 220.113 56.2702 223.951C58.8032 227.788 61.2755 231.823 63.7479 235.918C64.2029 236.692 63.0957 237.344 62.6406 236.57C60.229 232.475 57.7566 228.501 55.2236 224.603C52.8878 221.023 50.4762 217.444 48.0645 214.077C46.1079 211.347 43.1805 214.79 43.317 217.323C43.3777 218.551 43.9692 219.734 44.7428 220.766C46.7601 223.435 48.7167 226.165 50.5975 228.956C52.4783 231.747 54.2377 234.614 55.8607 237.541C56.3764 238.39 55.2085 238.967 54.7534 238.193C53.1305 235.266 51.371 232.475 49.5509 229.669C47.6701 226.939 45.7742 224.209 43.6962 221.539C43.3777 221.084 43.044 220.568 42.7861 220.038C41.4817 220.235 40.7082 221.342 40.3745 222.51C39.7223 224.785 40.238 226.863 41.4817 228.82C43.5597 231.944 45.577 235.327 47.4578 238.967C49.3386 242.607 51.1587 246.505 52.6603 250.54C52.9788 251.389 51.8109 251.844 51.4924 250.995C49.9908 247.021 48.2465 243.199 46.3505 239.543C44.5304 236.024 42.5738 232.718 40.5565 229.654C39.1307 229.138 37.6898 229.002 37.0376 230.7C35.7332 234.144 37.2348 237.132 38.6605 240.195C43.8024 251.45 49.0656 262.826 52.7058 275.566C69.4206 213.273 126.512 167.178 193.932 167.178C261.352 167.178 318.459 213.288 335.158 275.566C338.798 262.826 344.062 251.45 349.203 240.195C350.629 237.147 352.131 234.144 350.826 230.7H350.933Z\" fill=\"#FFE200\"><\/path><path d=\"M283.694 191.431C289.155 195.405 296.314 198.454 303.2 196.952C306.067 196.3 308.857 195.132 311.193 193.312C313.332 191.628 315.167 189.474 316.396 186.684C317.366 184.606 317.761 181.936 317.366 179.661C317.169 178.69 316.911 177.78 316.396 177.067C315.622 175.642 313.529 174.337 311.845 174.731C310.48 175.05 309.57 176.294 309.707 177.659C309.843 179.479 311.33 179.676 312.755 179.615C313.013 181.693 313.013 183.65 312.24 185.592C310.677 189.823 306.779 192.296 302.426 192.811C299.696 193.206 296.708 192.872 293.978 192.038C289.685 190.733 285.454 187.882 281.889 184.242C277.991 180.404 274.867 175.596 273.107 171.106C271.803 167.785 271.151 164.342 271.348 160.762C271.606 157.637 272.516 154.452 274.396 151.404C275.625 149.386 277.642 149.326 279.538 149.265C281.04 149.204 282.405 149.128 282.86 147.961C283.254 147.05 282.996 146.08 282.405 145.367C281.631 144.32 280.327 143.744 279.023 143.683C272.713 143.486 267.905 149.144 266.206 154.68C264.189 161.111 265.554 168.664 268.739 174.701C272.243 181.405 277.976 187.321 283.694 191.477V191.431Z\" fill=\"#FFE200\"><\/path><path d=\"M233.565 161.52C242.726 161.262 252.419 159.184 262.702 155.013C264.007 154.498 265.175 153.648 265.766 152.283C266.873 149.75 268.496 147.399 270.574 145.579C253.48 152.147 230.774 155.984 207.113 157.031C215.637 160.216 224.343 161.778 233.58 161.52H233.565Z\" fill=\"#FFE200\"><\/path><path d=\"M76.8527 193.312C79.1885 195.132 81.9945 196.3 84.8461 196.952C91.7322 198.454 98.8913 195.39 104.352 191.431C110.07 187.275 115.803 181.36 119.307 174.656C122.492 168.604 123.918 161.066 121.84 154.635C120.156 149.114 115.333 143.456 109.023 143.638C107.795 143.699 106.414 144.29 105.641 145.322C105.049 146.035 104.792 147.005 105.186 147.915C105.641 149.083 107.006 149.144 108.508 149.22C110.388 149.28 112.406 149.356 113.649 151.358C115.53 154.407 116.44 157.607 116.698 160.717C116.895 164.296 116.243 167.74 114.939 171.061C113.255 175.551 110.055 180.359 106.157 184.196C102.577 187.837 98.3605 190.703 94.068 191.993C91.3378 192.842 88.3498 193.161 85.6196 192.766C81.2665 192.25 77.3684 189.778 75.8061 185.546C75.0933 183.59 75.0326 181.648 75.2904 179.57C76.7162 179.631 78.2178 179.434 78.3391 177.614C78.4756 176.249 77.5656 175.02 76.2005 174.686C74.5169 174.292 72.4237 175.596 71.6502 177.022C71.1345 177.735 70.8766 178.645 70.6795 179.616C70.2851 181.891 70.6795 184.56 71.6502 186.638C72.8788 189.429 74.7141 191.583 76.8527 193.267V193.312Z\" fill=\"#FFE200\"><\/path><path d=\"M125.298 155.014H125.359C135.627 159.17 145.32 161.263 154.496 161.521C155.8 161.657 161.716 161.384 164.643 160.095C167.828 158.73 165.493 155.939 163.02 155.666C146.048 153.846 130.182 150.464 117.502 145.595C119.58 147.415 121.203 149.751 122.31 152.299C122.902 153.603 123.994 154.513 125.298 155.029V155.014Z\" fill=\"#FFE200\"><\/path><path d=\"M287.987 109.753C286.561 109.753 285.257 110.345 284.286 111.255C283.376 112.226 282.724 113.53 282.724 114.956C282.724 117.883 285.135 120.219 287.987 120.219C289.488 120.219 290.778 119.628 291.688 118.718C292.658 117.747 293.25 116.442 293.25 114.941C293.25 112.074 290.914 109.738 287.987 109.738V109.753Z\" fill=\"#FFE200\"><\/path><path d=\"M276.156 141.363C277.46 141.818 278.689 141.423 279.402 140.65C279.66 140.392 279.918 140.058 280.054 139.679C280.115 139.361 280.191 138.966 280.115 138.572C279.978 137.601 279.144 136.615 277.324 136.039C250.204 126.878 222.114 122.251 194.023 122.251C165.933 122.251 137.842 126.862 110.722 136.039C108.902 136.63 108.053 137.601 107.931 138.572C107.871 138.966 107.931 139.345 107.992 139.679C108.129 140.073 108.386 140.392 108.644 140.65C109.357 141.423 110.601 141.818 111.89 141.363C141.346 132.065 167.677 127.378 194.008 127.378C220.339 127.378 246.67 132.065 276.126 141.363H276.156Z\" fill=\"#FFE200\"><\/path><path d=\"M188.957 100.077C188.957 98.5751 187.728 97.4072 186.227 97.4072C184.725 97.4072 183.557 98.5751 183.557 100.077C183.557 101.578 184.725 102.807 186.227 102.807C187.728 102.807 188.957 101.578 188.957 100.077Z\" fill=\"#FFE200\"><\/path><path d=\"M194.038 83.877C195.858 83.877 197.36 82.3754 197.36 80.5552C197.36 78.7351 195.858 77.1729 194.038 77.1729C192.218 77.1729 190.716 78.6745 190.716 80.5552C190.716 82.436 192.218 83.877 194.038 83.877Z\" fill=\"#FFE200\"><\/path><path d=\"M198.133 60.2155C198.133 57.9404 196.313 56.0596 194.038 56.0596C191.763 56.0596 189.943 57.9404 189.943 60.2155C189.943 62.4907 191.763 64.3108 194.038 64.3108C196.313 64.3108 198.133 62.4907 198.133 60.2155Z\" fill=\"#FFE200\"><\/path><path d=\"M197.8 49.75C197.8 47.672 196.116 45.9126 194.023 45.9126C191.93 45.9126 190.246 47.672 190.246 49.75C190.246 51.828 191.93 53.5268 194.023 53.5268C196.116 53.5268 197.8 51.8432 197.8 49.75Z\" fill=\"#FFE200\"><\/path><path d=\"M190.064 70.8784C190.064 73.017 191.884 74.8523 194.038 74.8523C196.192 74.8523 197.997 73.0322 197.997 70.8784C197.997 68.7245 196.177 66.8438 194.038 66.8438C191.899 66.8438 190.064 68.6639 190.064 70.8784Z\" fill=\"#FFE200\"><\/path><path d=\"M194.038 31.6701C198.528 31.6701 202.168 27.9692 202.168 23.4796C202.168 18.99 198.528 15.2891 194.038 15.2891C189.548 15.2891 185.908 18.9293 185.908 23.4796C185.908 28.0299 189.548 31.6701 194.038 31.6701Z\" fill=\"#FFE200\"><\/path><path d=\"M253.92 86.1522C253.92 88.1088 255.482 89.7318 257.424 89.7318C258.395 89.7318 259.305 89.3374 259.957 88.6852C260.609 88.033 261.003 87.1229 261.003 86.1522C261.003 84.1956 259.38 82.6333 257.424 82.6333C255.467 82.6333 253.92 84.1956 253.92 86.1522Z\" fill=\"#FFE200\"><\/path><path d=\"M266.464 72.6985C267.571 72.6985 268.542 72.2435 269.194 71.5913C269.907 70.8784 270.362 69.9077 270.362 68.8004C270.362 66.6618 268.602 64.9023 266.464 64.9023C265.417 64.9023 264.446 65.3574 263.734 66.0703C263.021 66.7831 262.566 67.7539 262.566 68.8004C262.566 70.9391 264.325 72.6985 266.464 72.6985Z\" fill=\"#FFE200\"><\/path><path d=\"M258.925 77.9623C258.925 79.9796 260.609 81.6632 262.702 81.6632C263.749 81.6632 264.659 81.2689 265.296 80.556C266.009 79.9038 266.403 78.9937 266.403 77.9623C266.403 75.8843 264.719 74.1855 262.702 74.1855C261.656 74.1855 260.685 74.5799 260.033 75.2928C259.32 75.945 258.925 76.9157 258.925 77.9623Z\" fill=\"#FFE200\"><\/path><path d=\"M267.177 63.3405C268.284 63.3405 269.255 62.8855 269.968 62.2333C270.681 61.5204 271.075 60.5496 271.075 59.4424C271.075 57.3038 269.315 55.605 267.177 55.605C266.13 55.605 265.159 55.9993 264.447 56.7122C263.734 57.4251 263.339 58.3958 263.339 59.4424C263.339 61.581 265.099 63.3405 267.177 63.3405Z\" fill=\"#FFE200\"><\/path><path d=\"M266.464 53.5113C267.571 53.5113 268.542 53.0563 269.255 52.3434C270.028 51.6305 270.423 50.6598 270.423 49.5525C270.423 47.3381 268.663 45.5786 266.464 45.5786C265.357 45.5786 264.386 46.0336 263.673 46.7465C262.96 47.4594 262.505 48.4301 262.505 49.5374C262.505 51.7519 264.264 53.5113 266.479 53.5113H266.464Z\" fill=\"#FFE200\"><\/path><path d=\"M267.374 43.3041C269.588 43.3041 271.348 41.5447 271.348 39.3454C271.348 37.146 269.588 35.4473 267.374 35.4473C265.159 35.4473 263.476 37.2067 263.476 39.3454C263.476 41.484 265.235 43.3041 267.374 43.3041Z\" fill=\"#FFE200\"><\/path><path d=\"M257.5 40.5133C259.638 40.5133 261.398 38.6932 261.398 36.5394C261.398 34.3856 259.638 32.5654 257.5 32.5654C255.361 32.5654 253.526 34.3856 253.526 36.5394C253.526 38.6932 255.285 40.5133 257.5 40.5133Z\" fill=\"#FFE200\"><\/path><path d=\"M248.581 36.9938C249.628 36.9938 250.598 36.5388 251.311 35.8259C252.024 35.1737 252.479 34.203 252.479 33.0957C252.479 30.9571 250.72 29.2583 248.581 29.2583C247.534 29.2583 246.564 29.6527 245.851 30.3655C245.138 31.0784 244.683 32.0492 244.683 33.0957C244.683 35.2344 246.442 36.9938 248.581 36.9938Z\" fill=\"#FFE200\"><\/path><path d=\"M238.571 35.4321C239.617 35.4321 240.527 34.9771 241.24 34.3249C241.892 33.612 242.287 32.7019 242.287 31.716C242.287 29.6381 240.664 28.0151 238.586 28.0151C237.615 28.0151 236.629 28.4095 235.992 29.0617C235.34 29.7746 234.885 30.6846 234.885 31.7312C234.885 33.7485 236.568 35.4321 238.586 35.4321H238.571Z\" fill=\"#FFE200\"><\/path><path d=\"M229.212 34.0669C230.259 34.0669 231.169 33.6118 231.821 32.9596C232.534 32.3074 232.928 31.3367 232.928 30.366C232.928 28.288 231.244 26.665 229.227 26.665C228.181 26.665 227.271 27.0594 226.633 27.7116C225.921 28.4245 225.526 29.3346 225.526 30.3811C225.526 32.3984 227.21 34.082 229.227 34.082L229.212 34.0669Z\" fill=\"#FFE200\"><\/path><path d=\"M220.036 32.5803C221.006 32.5803 221.916 32.1859 222.569 31.5337C223.221 30.8208 223.676 29.9108 223.676 28.94C223.676 26.9227 221.992 25.2998 220.036 25.2998C218.989 25.2998 218.079 25.6942 217.442 26.3464C216.79 27.0593 216.335 27.9693 216.335 28.9552C216.335 30.9725 218.018 32.5955 220.036 32.5955V32.5803Z\" fill=\"#FFE200\"><\/path><path d=\"M211.39 31.5336C213.271 31.5336 214.833 29.9713 214.833 28.0905C214.833 26.2097 213.271 24.6475 211.39 24.6475C209.509 24.6475 207.886 26.2097 207.886 28.0905C207.886 29.9713 209.448 31.5336 211.39 31.5336Z\" fill=\"#FFE200\"><\/path><path d=\"M276.747 47.1412C277.855 47.1412 278.886 46.6862 279.614 45.9126H279.675C280.388 45.1998 280.843 44.1532 280.843 43.046C280.843 40.7708 279.023 38.9507 276.747 38.9507C275.64 38.9507 274.609 39.4057 273.881 40.1186C273.107 40.8921 272.652 41.878 272.652 43.046C272.652 45.2604 274.472 47.1412 276.747 47.1412Z\" fill=\"#FFE200\"><\/path><path d=\"M286.106 48.9005C287.213 48.9005 288.245 48.3848 288.973 47.6719C289.746 46.959 290.201 45.9125 290.201 44.8052C290.201 42.5301 288.32 40.71 286.106 40.71C284.938 40.71 283.967 41.165 283.179 41.8779C282.466 42.6514 282.011 43.6373 282.011 44.8052C282.011 47.0197 283.831 48.9005 286.106 48.9005Z\" fill=\"#FFE200\"><\/path><path d=\"M296.056 52.2831C297.36 52.2831 298.589 51.6915 299.438 50.8573C300.288 50.0079 300.803 48.84 300.803 47.5356C300.803 44.9419 298.665 42.7881 296.056 42.7881C294.751 42.7881 293.584 43.3038 292.734 44.1532C291.885 45.0632 291.308 46.2311 291.308 47.5356C291.308 50.1292 293.447 52.2831 296.056 52.2831Z\" fill=\"#FFE200\"><\/path><path d=\"M305.869 57.8642C307.235 57.8642 308.463 57.2726 309.388 56.3626C310.314 55.4525 310.89 54.2239 310.89 52.8588C310.89 50.1287 308.615 47.8535 305.885 47.8535C304.52 47.8535 303.291 48.4451 302.366 49.3551C301.456 50.2652 300.864 51.4938 300.864 52.874C300.864 55.6042 303.139 57.8793 305.869 57.8793V57.8642Z\" fill=\"#FFE200\"><\/path><path d=\"M309.054 62.0354C309.054 64.9021 311.39 67.2379 314.196 67.2379C317.002 67.2379 319.399 64.9021 319.399 62.0354C319.399 59.1687 317.063 56.8936 314.196 56.8936C311.33 56.8936 309.054 59.2294 309.054 62.0354Z\" fill=\"#FFE200\"><\/path><path d=\"M313.878 73.8056C313.878 76.5358 316.092 78.811 318.883 78.811C321.674 78.811 323.828 76.5358 323.828 73.8056C323.828 71.0754 321.613 68.8003 318.883 68.8003C316.153 68.8003 313.878 71.0754 313.878 73.8056Z\" fill=\"#FFE200\"><\/path><path d=\"M322.842 85.4397C322.842 83.028 320.885 81.0107 318.489 81.0107C316.092 81.0107 314.06 83.028 314.06 85.4397C314.06 87.8514 316.077 89.8687 318.489 89.8687C320.901 89.8687 322.842 87.8514 322.842 85.4397Z\" fill=\"#FFE200\"><\/path><path d=\"M319.46 94.9346C319.46 92.8566 317.776 91.0972 315.622 91.0972C313.468 91.0972 311.785 92.8566 311.785 94.9346C311.785 97.0126 313.544 98.772 315.622 98.772C317.7 98.772 319.46 97.0884 319.46 94.9346Z\" fill=\"#FFE200\"><\/path><path d=\"M311.663 107.357C313.802 107.357 315.562 105.598 315.562 103.52C315.562 101.442 313.802 99.6216 311.663 99.6216C309.525 99.6216 307.826 101.381 307.826 103.52C307.826 105.658 309.585 107.357 311.663 107.357Z\" fill=\"#FFE200\"><\/path><path d=\"M272.258 64.7055C271.864 68.4064 270.953 71.986 269.528 75.2319C267.965 78.7356 266.145 82.1938 264.067 85.3032C262.111 88.2912 259.911 91.0214 257.697 93.0994C257.303 93.5544 257.045 93.8729 257.105 94.2673C257.166 94.7223 257.5 95.3139 258.152 96.1481C258.349 96.3453 258.546 96.5425 258.743 96.6638C259.456 97.1188 260.306 96.9823 261.276 96.4059C262.384 95.6931 263.552 94.4493 264.72 92.9629C267.192 89.7777 269.664 85.288 271.484 81.3293C273.82 76.3846 275.064 72.0922 275.64 67.6784C276.232 62.6124 275.959 57.5312 275.64 52.4652C275.443 50.3266 275.322 47.5812 273.107 47.2627C272.516 47.202 272.258 47.7784 272.137 48.5671C272 49.6137 272.137 50.9788 272.273 51.8888C272.728 56.1206 272.789 60.4737 272.273 64.7055H272.258Z\" fill=\"#FFE200\"><\/path><path d=\"M258.152 44.6082C257.56 43.956 256.923 43.501 256.195 43.501C254.633 43.5616 254.436 44.4717 254.314 45.3818C254.117 46.7469 254.967 47.8541 255.361 49.2799C256.468 53.0566 256.923 56.7575 256.787 60.4584C256.59 64.1593 255.877 67.7996 254.572 71.455C253.859 73.533 252.949 75.3531 251.903 77.1125C250.796 78.872 249.628 80.5556 248.46 82.2544C247.352 83.756 247.034 84.666 247.231 85.1211C247.428 85.5761 248.081 85.834 249.051 86.0918C251.842 86.744 252.949 84.8632 254.117 82.8459C254.436 82.3302 254.769 81.7387 255.164 81.1623C258.743 75.8991 260.821 70.4994 261.595 65.0997C262.444 59.3057 261.853 53.5268 260.033 48.0664C259.714 47.0199 259.062 45.5941 258.152 44.6234V44.6082Z\" fill=\"#FFE200\"><\/path><path d=\"M130.637 89.7318C132.594 89.7318 134.156 88.1088 134.156 86.1522C134.156 84.1956 132.594 82.6333 130.637 82.6333C128.681 82.6333 127.058 84.1956 127.058 86.1522C127.058 87.1229 127.452 88.033 128.104 88.6852C128.756 89.3374 129.666 89.7318 130.637 89.7318Z\" fill=\"#FFE200\"><\/path><path d=\"M121.597 72.6985C123.736 72.6985 125.495 70.9391 125.495 68.8004C125.495 67.7539 125.04 66.7831 124.327 66.0703C123.615 65.3574 122.644 64.9023 121.597 64.9023C119.459 64.9023 117.699 66.6618 117.699 68.8004C117.699 69.9077 118.154 70.8784 118.867 71.5913C119.519 72.2435 120.49 72.6985 121.597 72.6985Z\" fill=\"#FFE200\"><\/path><path d=\"M125.374 81.6632C127.452 81.6632 129.151 79.9796 129.151 77.9623C129.151 76.9157 128.757 75.945 128.044 75.2928C127.391 74.5799 126.421 74.1855 125.374 74.1855C123.357 74.1855 121.673 75.8692 121.673 77.9623C121.673 79.0089 122.068 79.9189 122.78 80.556C123.433 81.2689 124.343 81.6632 125.374 81.6632Z\" fill=\"#FFE200\"><\/path><path d=\"M124.722 59.4268C124.722 58.3802 124.328 57.4095 123.615 56.6966C122.902 55.9837 121.931 55.5894 120.885 55.5894C118.746 55.5894 116.986 57.273 116.986 59.4268C116.986 60.534 117.381 61.5047 118.094 62.2176C118.807 62.8698 119.777 63.3249 120.885 63.3249C122.963 63.3249 124.722 61.5654 124.722 59.4268Z\" fill=\"#FFE200\"><\/path><path d=\"M121.597 45.5786C119.383 45.5786 117.623 47.3381 117.623 49.5525C117.623 50.6598 118.018 51.6305 118.791 52.3434C119.504 53.0563 120.475 53.5113 121.582 53.5113C123.797 53.5113 125.541 51.7519 125.541 49.5374C125.541 48.4301 125.086 47.4594 124.373 46.7465C123.66 46.0336 122.689 45.5786 121.582 45.5786H121.597Z\" fill=\"#FFE200\"><\/path><path d=\"M120.687 43.3041C122.826 43.3041 124.585 41.5447 124.585 39.3454C124.585 37.146 122.826 35.4473 120.687 35.4473C118.549 35.4473 116.713 37.2067 116.713 39.3454C116.713 41.484 118.473 43.3041 120.687 43.3041Z\" fill=\"#FFE200\"><\/path><path d=\"M130.562 40.5133C132.776 40.5133 134.52 38.6932 134.52 36.5394C134.52 34.3856 132.761 32.5654 130.562 32.5654C128.362 32.5654 126.663 34.3856 126.663 36.5394C126.663 38.6932 128.423 40.5133 130.562 40.5133Z\" fill=\"#FFE200\"><\/path><path d=\"M139.48 36.9938C141.619 36.9938 143.378 35.2344 143.378 33.0957C143.378 32.0492 142.923 31.0784 142.21 30.3655C141.497 29.6527 140.527 29.2583 139.48 29.2583C137.341 29.2583 135.582 30.9419 135.582 33.0957C135.582 34.203 136.037 35.1737 136.75 35.8259C137.463 36.5388 138.434 36.9938 139.48 36.9938Z\" fill=\"#FFE200\"><\/path><path d=\"M149.491 35.4321C151.508 35.4321 153.192 33.7485 153.192 31.7312C153.192 30.6846 152.737 29.7746 152.084 29.0617C151.432 28.4095 150.461 28.0151 149.491 28.0151C147.413 28.0151 145.79 29.6381 145.79 31.716C145.79 32.6868 146.184 33.5968 146.897 34.3249C147.549 34.9771 148.459 35.4321 149.491 35.4321Z\" fill=\"#FFE200\"><\/path><path d=\"M158.849 34.0664C160.866 34.0664 162.55 32.3828 162.55 30.3655C162.55 29.3189 162.156 28.4089 161.443 27.696C160.791 27.0438 159.881 26.6494 158.849 26.6494C156.832 26.6494 155.148 28.2724 155.148 30.3503C155.148 31.3211 155.543 32.307 156.255 32.944C156.908 33.5962 157.818 34.0512 158.849 34.0512V34.0664Z\" fill=\"#FFE200\"><\/path><path d=\"M168.026 32.5798C170.043 32.5798 171.727 30.9569 171.727 28.9396C171.727 27.9689 171.272 27.0588 170.619 26.3307C169.967 25.6785 169.057 25.2842 168.01 25.2842C166.054 25.2842 164.37 26.9071 164.37 28.9244C164.37 29.8952 164.825 30.8052 165.477 31.5181C166.13 32.1703 167.04 32.5647 168.01 32.5647L168.026 32.5798Z\" fill=\"#FFE200\"><\/path><path d=\"M176.671 31.5336C178.628 31.5336 180.19 29.9713 180.19 28.0905C180.19 26.2097 178.628 24.6475 176.671 24.6475C174.714 24.6475 173.228 26.2097 173.228 28.0905C173.228 29.9713 174.79 31.5336 176.671 31.5336Z\" fill=\"#FFE200\"><\/path><path d=\"M108.462 45.9126C109.175 46.6862 110.222 47.1412 111.329 47.1412C113.604 47.1412 115.424 45.2604 115.424 43.046C115.424 41.878 114.969 40.9073 114.195 40.1186C113.483 39.4057 112.436 38.9507 111.329 38.9507C109.054 38.9507 107.234 40.7708 107.234 43.046C107.234 44.1532 107.689 45.1846 108.401 45.9126H108.462Z\" fill=\"#FFE200\"><\/path><path d=\"M101.955 48.9005C104.23 48.9005 106.05 47.0197 106.05 44.8052C106.05 43.6373 105.595 42.6666 104.882 41.8779C104.109 41.165 103.123 40.71 101.955 40.71C99.7407 40.71 97.8599 42.5301 97.8599 44.8052C97.8599 45.9125 98.3149 46.9439 99.0884 47.6719C99.8013 48.3848 100.848 48.9005 101.955 48.9005Z\" fill=\"#FFE200\"><\/path><path d=\"M92.0052 52.2831C94.5988 52.2831 96.7527 50.1444 96.7527 47.5356C96.7527 46.2311 96.1611 45.0632 95.3269 44.1532C94.4775 43.3038 93.3096 42.7881 92.0052 42.7881C89.4115 42.7881 87.2577 44.9267 87.2577 47.5356C87.2577 48.84 87.7734 50.0079 88.6228 50.8573C89.4722 51.7067 90.7008 52.2831 92.0052 52.2831Z\" fill=\"#FFE200\"><\/path><path d=\"M82.1918 57.8647C84.9219 57.8647 87.1971 55.5895 87.1971 52.8594C87.1971 51.4943 86.6056 50.2505 85.6955 49.3405C84.7854 48.4304 83.5569 47.8389 82.1766 47.8389C79.4464 47.8389 77.1713 50.114 77.1713 52.8442C77.1713 54.2093 77.7628 55.4379 78.6729 56.3479C79.5829 57.258 80.8115 57.8495 82.1766 57.8495L82.1918 57.8647Z\" fill=\"#FFE200\"><\/path><path d=\"M73.8646 67.2379C76.6555 67.2379 79.0065 64.9021 79.0065 62.0354C79.0065 59.1687 76.6706 56.8936 73.8646 56.8936C71.0586 56.8936 68.6621 59.2294 68.6621 62.0354C68.6621 64.8414 70.9979 67.2379 73.8646 67.2379Z\" fill=\"#FFE200\"><\/path><path d=\"M69.1931 78.811C71.9839 78.811 74.1984 76.5358 74.1984 73.8056C74.1984 71.0754 71.9839 68.8003 69.1931 68.8003C66.4022 68.8003 64.2484 71.0754 64.2484 73.8056C64.2484 76.5358 66.4629 78.811 69.1931 78.811Z\" fill=\"#FFE200\"><\/path><path d=\"M74.0012 85.4397C74.0012 83.028 71.9839 81.0107 69.5722 81.0107C67.1606 81.0107 65.2191 83.028 65.2191 85.4397C65.2191 87.8514 67.1758 89.8687 69.5722 89.8687C71.9687 89.8687 74.0012 87.8514 74.0012 85.4397Z\" fill=\"#FFE200\"><\/path><path d=\"M72.439 98.772C74.517 98.772 76.2764 97.0884 76.2764 94.9346C76.2764 92.7808 74.517 91.0972 72.439 91.0972C70.361 91.0972 68.6016 92.8566 68.6016 94.9346C68.6016 97.0126 70.2852 98.772 72.439 98.772Z\" fill=\"#FFE200\"><\/path><path d=\"M72.4995 103.52C72.4995 105.598 74.259 107.357 76.3976 107.357C78.5362 107.357 80.235 105.598 80.235 103.52C80.235 101.442 78.4756 99.6216 76.3976 99.6216C74.3196 99.6216 72.4995 101.381 72.4995 103.52Z\" fill=\"#FFE200\"><\/path><path d=\"M112.421 52.4797C112.102 57.5457 111.829 62.6269 112.421 67.6929C113.012 72.1219 114.241 76.3992 116.577 81.3438C118.397 85.3026 120.869 89.7922 123.342 92.9774C124.51 94.479 125.677 95.7076 126.785 96.4205C127.755 97.012 128.605 97.1334 129.318 96.6783C129.515 96.5418 129.712 96.3598 129.909 96.1626C130.561 95.3133 130.88 94.7369 130.956 94.2819C131.016 93.8875 130.759 93.569 130.364 93.1139C128.15 91.036 125.935 88.3058 123.994 85.3178C121.916 82.1932 120.096 78.7502 118.533 75.2464C117.108 72.0005 116.198 68.421 115.803 64.7201C115.288 60.4883 115.348 56.1352 115.803 51.9034C115.94 50.9933 116.061 49.6282 115.94 48.5816C115.803 47.8081 115.545 47.2166 114.969 47.2772C112.755 47.5958 112.633 50.3411 112.436 52.4797H112.421Z\" fill=\"#FFE200\"><\/path><path d=\"M132.912 81.1472C133.307 81.7387 133.625 82.3151 133.959 82.8308C135.127 84.8481 136.234 86.7289 139.025 86.0767C139.996 85.8188 140.648 85.561 140.845 85.1059C141.042 84.6509 140.709 83.7409 139.617 82.2393C138.449 80.5556 137.281 78.8569 136.234 77.0974C135.127 75.338 134.217 73.5178 133.504 71.4399C132.2 67.7996 131.487 64.1594 131.29 60.4433C131.153 56.7424 131.608 53.0263 132.715 49.2647C133.11 47.839 133.944 46.7317 133.762 45.3666C133.625 44.4566 133.443 43.5465 131.881 43.4858C131.168 43.4858 130.516 43.9409 129.924 44.5931C129.014 45.5638 128.362 47.0047 128.044 48.0361C126.224 53.4965 125.632 59.2906 126.481 65.0694C127.255 70.4691 129.348 75.8688 132.912 81.132V81.1472Z\" fill=\"#FFE200\"><\/path><path d=\"M78.4149 68.4059C73.8039 74.6549 74.259 82.6483 76.2004 89.7923C77.884 95.7683 80.9479 101.502 84.6488 106.765C85.0432 107.281 85.5589 107.478 86.1504 107.356C87.197 107.099 88.2891 107.038 89.3356 107.159C90.185 107.296 90.3822 106.386 89.9878 105.794C87.652 102.67 85.5589 99.2872 83.9359 95.7835C81.9793 91.6882 80.69 87.3958 80.2957 83.0427C79.6435 75.3072 82.5102 67.8295 87.7734 61.6562C84.5275 63.082 81.0086 64.8415 78.4149 68.421V68.4059Z\" fill=\"#FFE200\"><\/path><path d=\"M298.134 54.9526C297.224 54.4369 296.314 53.9818 295.343 53.5268C293.978 52.8746 292.021 54.4369 293.523 55.4834C294.691 56.3328 295.798 57.2429 296.905 58.2136C298.407 59.5787 301.258 56.7879 298.134 54.9677V54.9526Z\" fill=\"#FFE200\"><\/path><path d=\"M304.11 95.7842C301.896 100.592 298.771 105.082 295.525 109.117C294.297 110.618 293.902 112.241 294.16 113.409C294.357 114.001 294.752 114.516 295.389 114.577C296.299 114.577 297.603 113.925 299.09 112.165C304.747 105.598 309.555 97.9228 311.83 89.7929C313.651 83.0888 313.711 76.2027 310.92 69.4986C309.04 65.009 306.309 61.3687 303.048 58.4413C301.168 56.8791 299.014 60.125 300.318 61.6872C305.581 67.8605 308.387 75.3381 307.735 83.013C307.341 87.3661 306.052 91.6586 304.095 95.7538L304.11 95.7842Z\" fill=\"#FFE200\"><\/path><path d=\"M194.038 459.52C274.533 459.52 340.209 393.844 340.209 313.288C340.209 232.733 274.533 167.178 194.038 167.178C113.543 167.178 47.8521 232.854 47.8521 313.288C47.8521 393.723 113.528 459.52 194.023 459.52H194.038Z\" fill=\"#ED1B24\"><\/path><path d=\"M194.038 113.924C193.977 114.637 191.702 117.504 191.05 117.822H193.067C193.522 117.504 193.841 117.17 194.038 116.715C194.235 117.17 194.554 117.489 195.009 117.822H197.026C196.374 117.504 194.099 114.637 194.038 113.924Z\" fill=\"black\"><\/path><path d=\"M194.038 103.064C193.977 103.717 191.702 106.052 191.05 106.31H193.067C193.522 106.052 193.841 105.795 194.038 105.4C194.235 105.795 194.554 106.052 195.009 106.31H197.026C196.374 106.052 194.099 103.717 194.038 103.064Z\" fill=\"black\"><\/path><path d=\"M156.255 119.127L155.345 119.9C151.189 123.677 146.048 124.587 139.935 122.827L138.706 122.433L139.753 121.72C142.089 119.961 144.561 118.929 147.094 118.535C149.627 118.08 152.297 118.217 155.027 118.854L156.255 119.111V119.127Z\" fill=\"black\"><\/path><path d=\"M169.846 104.884C169.846 105.4 167.828 107.675 167.252 108.009L169.269 107.751C169.664 107.493 169.921 107.235 170.179 106.902C170.437 107.159 170.832 107.417 171.226 107.554L173.243 107.357C172.591 107.22 170.058 105.4 169.861 104.884H169.846Z\" fill=\"black\"><\/path><path d=\"M144.607 107.873C144.667 108.464 142.923 111.118 142.392 111.513L144.349 111.058C144.743 110.739 145.001 110.406 145.123 110.011C145.441 110.269 145.835 110.466 146.29 110.603L148.247 110.148C147.595 110.087 144.804 108.388 144.607 107.873Z\" fill=\"black\"><\/path><path d=\"M117.563 114.956C117.623 115.547 116.137 118.338 115.606 118.732L117.487 118.141C117.805 117.822 118.078 117.489 118.2 117.094C118.518 117.352 118.913 117.489 119.368 117.61L121.324 117.018C120.672 116.958 117.805 115.456 117.548 114.94L117.563 114.956Z\" fill=\"black\"><\/path><path d=\"M153.449 119.839C151.311 119.445 149.293 119.445 147.337 119.779C145.32 120.097 143.439 120.825 141.619 121.993C146.169 123.04 150.143 122.312 153.449 119.855V119.839Z\" fill=\"#ED1B24\"><\/path><path d=\"M231.806 119.127L232.716 119.9C236.948 123.677 242.013 124.587 248.126 122.827L249.355 122.433L248.308 121.72C245.972 119.961 243.5 118.929 240.967 118.535C238.434 118.08 235.764 118.217 233.034 118.854L231.806 119.111V119.127Z\" fill=\"black\"><\/path><path d=\"M218.215 104.884C218.215 105.4 220.233 107.675 220.809 108.009L218.792 107.751C218.397 107.493 218.14 107.235 217.882 106.902C217.624 107.159 217.23 107.417 216.835 107.554L214.818 107.357C215.47 107.22 218.003 105.4 218.2 104.884H218.215Z\" fill=\"black\"><\/path><path d=\"M243.454 107.873C243.394 108.464 245.138 111.118 245.669 111.513L243.712 111.058C243.394 110.739 243.121 110.406 242.939 110.011C242.62 110.269 242.226 110.466 241.771 110.603L239.814 110.148C240.466 110.087 243.257 108.388 243.454 107.873Z\" fill=\"black\"><\/path><path d=\"M270.498 114.956C270.438 115.547 271.924 118.338 272.455 118.732L270.574 118.141C270.256 117.822 269.983 117.489 269.861 117.094C269.543 117.352 269.148 117.489 268.693 117.61L266.737 117.018C267.389 116.958 270.256 115.456 270.514 114.94L270.498 114.956Z\" fill=\"black\"><\/path><path d=\"M234.612 119.839C236.75 119.445 238.768 119.445 240.724 119.779C242.741 120.097 244.622 120.825 246.442 121.993C241.892 123.04 237.918 122.312 234.612 119.855V119.839Z\" fill=\"#ED1B24\"><\/path><path d=\"M247.095 93.4331C246.898 99.1513 247.034 97.6649 252.1 100.319C249.688 99.6064 247.292 99.1513 245.138 100.577C243.97 98.2413 241.695 97.4525 239.223 96.8762C244.941 97.0733 244.365 98.4384 247.095 93.4331Z\" fill=\"black\"><\/path><path d=\"M140.967 93.4331C141.164 99.1513 141.027 97.6649 135.961 100.319C138.373 99.6064 140.769 99.1513 142.923 100.577C144.091 98.2413 146.366 97.4525 148.839 96.8762C143.12 97.0733 143.697 98.4384 140.967 93.4331Z\" fill=\"black\"><\/path><path d=\"M148.581 63.0675C146.048 66.1921 142.074 66.7078 140.845 70.4845C140.254 72.1681 141.695 73.5484 143.06 73.9276C144.622 74.4433 145.396 72.1075 147.094 71.5159C146.381 72.3653 145.866 73.5332 146.321 74.1854C146.836 73.4119 147.291 72.881 148.596 72.5625C146.518 75.5505 147.428 76.0814 148.99 75.8842C149.9 75.8235 150.492 74.9742 151.584 74.4585C151.523 74.7163 148.657 77.3858 150.992 77.583C151.508 77.6437 153.207 76.8701 153.662 76.4151C153.525 77.4617 151.902 77.8408 153.465 78.6902C154.314 79.2059 155.346 78.2352 156.134 77.9167C154.253 80.5104 155.164 81.0412 156.331 80.6469C157.181 80.3283 157.894 79.4183 159.259 79.4183C158.485 80.0705 157.833 80.1918 157.833 81.0412C157.894 83.7714 160.427 83.5742 161.868 83.3164C160.821 84.0899 161.868 87.2145 162.323 87.2903C164.992 87.6088 165.644 86.8353 168.117 86.1224C171.696 85.0151 172.409 80.207 172.348 74.0338C172.288 68.6341 171.636 63.113 170.726 61.4143C169.618 61.0957 167.025 62.5822 167.025 64.1444C166.827 63.4316 166.372 62.84 165.978 62.84C165.129 62.9007 164.294 64.1444 163.566 64.463C160.958 65.6309 163.172 62.1271 163.172 61.93C159.532 61.7934 159.532 66.9353 159.532 61.6114C156.999 61.2171 155.3 66.4196 155.497 61.8693C153.874 60.4435 152.631 61.8086 151.66 62.9765C150.947 63.8866 150.295 64.6601 150.234 64.2809C150.098 63.5074 150.553 62.1423 150.431 61.7479C150.173 61.0351 148.808 62.8552 148.611 63.113L148.581 63.0675Z\" fill=\"#ED1B24\"><\/path><path d=\"M220.233 59.0472C220.551 61.383 220.233 62.4903 219.914 63.734C218.231 69.1337 220.688 74.1997 220.506 79.6601C222.584 80.8887 222.387 78.8107 223.039 77.1271C224.267 71.7274 229.348 85.4541 235.127 79.6601C237.008 77.1878 240.588 74.5182 244.289 74.8519C249.173 77.84 247.019 63.9919 245.654 63.279C245.138 63.0211 244.031 63.6734 244.031 63.4762C243.894 62.3083 243.439 61.5196 242.802 61.5196C241.634 61.2617 241.179 62.1111 240.921 63.3397C240.785 64.1891 239.875 63.5975 239.951 61.7774C239.298 62.3689 238.843 63.5975 238.586 63.7947C238.07 64.1891 238.722 63.7947 238.191 62.2324C237.736 60.7308 237.145 59.8966 236.568 62.4296C236.174 64.0525 234.232 66.7221 231.229 64.9626C229.864 64.1132 229.606 60.0179 227.453 59.5629C226.345 59.3657 227.195 60.7308 226.285 60.6095C226.027 60.5488 225.83 59.8359 225.314 59.4416C224.404 58.7894 225.708 59.7601 223.099 56.3777C220.824 53.5869 219.975 57.5456 220.233 59.0472Z\" fill=\"#ED1B24\"><\/path><path d=\"M273.881 97.6042C272.516 97.7407 271.606 98.3777 271.272 99.6215C270.559 102.488 275.367 101.699 278.234 101.305C282.845 100.714 282.466 104.627 285.12 103.717C286.682 103.201 285.833 97.0127 287.85 95.0712C288.897 94.1005 291.354 93.0539 291.748 92.0073C292.522 89.9293 291.035 88.1092 288.047 87.3205C286.819 87.0627 286.622 85.7582 284.801 85.8947C282.39 86.0313 281.616 87.9727 280.448 89.7928C279.538 91.1579 278.568 92.523 276.929 93.1752C274.912 93.9488 274.715 96.1026 273.881 97.6042Z\" fill=\"#ED1B24\"><\/path><path d=\"M110.934 94.0852C113.801 97.9226 117.639 100.911 120.096 100.713C122.113 100.395 123.16 97.9833 121.977 95.3744C119.504 89.7169 114.817 88.0333 114.696 81.587C110.995 79.9034 106.824 81.1927 102.41 83.4071C97.0105 87.3811 91.808 89.9747 82.6467 89.004C83.8146 93.0993 85.6954 96.9974 87.9099 100.577C90.4429 100.638 92.263 99.5304 92.6574 97.3917C92.9152 96.2845 93.8253 94.2065 95.5848 94.2065C94.3562 95.1166 93.3703 97.4524 94.614 97.9833C96.7527 98.954 97.8599 92.9173 99.8165 92.4622C99.3008 93.6302 97.0864 96.5575 99.4222 96.5575C101.242 96.239 101.106 92.9173 103.002 93.1145C103.26 94.161 102.744 96.6334 104.23 96.5575C106.308 96.0418 105.656 93.0538 106.961 93.0538C106.642 96.0418 110.009 95.5261 110.934 94.1004V94.0852Z\" fill=\"#ED1B24\"><\/path><path d=\"M235.977 135.447C237.539 136.221 240.269 136.357 242.408 136.297C246.443 136.16 244.031 138.83 246.564 138.83C250.72 138.83 253.844 143.714 250.007 145.595C249.097 146.05 247.535 145.989 245.851 145.989C244.349 146.444 248.9 148.325 244.622 148.977C242.999 149.235 238.313 147.87 238.313 150.736C238.313 152.359 233.429 153.33 232.064 153.527C219.899 155.211 206.9 156.06 194.023 156.06C185.635 156.06 177.187 155.666 168.981 155.014C166.19 154.756 166.115 152.541 163.384 151.829C161.883 151.434 159.941 151.631 157.924 151.434C153.434 150.979 153.95 147.657 149.855 148.31C146.215 148.901 142.635 146.489 143.227 144.669C143.621 143.623 145.896 143.046 149.278 142.713C146.867 141.742 147.519 142.121 144.925 142.061C141.877 142 141.088 141.469 141.937 140.559C142.65 139.846 147.276 139.588 144.212 138.997C139.601 138.087 147.731 135.933 148.566 135.554C151.887 134.128 154.739 132.035 158.379 131.458C170.468 129.578 182.238 128.667 194.008 128.667C203.821 128.667 213.65 129.32 223.6 130.624C227.953 131.14 232.124 133.551 235.962 135.432L235.977 135.447Z\" fill=\"#ED1B24\"><\/path><path d=\"M227.847 190.264C221.734 188.58 215.485 187.336 209.054 186.563C208.144 186.426 207.173 186.365 206.263 186.244V229.032C202.305 228.441 198.194 228.122 194.038 228.122C189.882 228.122 185.787 228.441 181.813 229.032V186.244C117.184 192.493 66.3264 247.173 66.3264 313.304C66.3264 379.435 120.035 437.239 187.213 440.879V427.289C127.452 423.709 79.856 373.899 79.856 313.304C79.856 259.398 117.639 214.077 168.026 202.185V232.233C145.077 239.65 126.284 256.486 116.395 278.206L128.484 284.258C131.153 278.342 134.535 272.806 138.631 267.877V358.852C130.956 349.418 125.556 338.103 123.357 325.62L110.161 328.411C117.32 368.211 152.236 398.637 194.038 398.637C199.104 398.637 204.185 398.182 209.054 397.272C215.622 396.104 221.932 394.147 227.847 391.614C258.076 378.419 279.281 348.311 279.281 313.319C279.281 287.504 267.647 264.297 249.431 248.689V213.637C284.407 233.203 308.205 270.531 308.205 313.319C308.205 364.495 274.321 407.935 227.832 422.435C221.78 424.316 215.47 425.681 209.039 426.53C206.309 426.925 203.639 427.183 200.849 427.304V440.894C203.639 440.697 206.309 440.5 209.039 440.181C215.47 439.408 221.719 438.164 227.832 436.48C281.859 421.586 321.72 371.972 321.72 313.319C321.72 254.666 281.859 205.189 227.832 190.294L227.847 190.264ZM220.036 202.155C222.705 202.807 225.299 203.52 227.832 204.294C230.501 205.143 233.095 206.053 235.628 207.085V239.012C233.095 237.587 230.486 236.282 227.832 235.114C225.299 234.007 222.69 233.036 220.036 232.187V202.14V202.155ZM265.751 313.289C265.751 340.606 250.341 364.404 227.847 376.553C221.992 379.677 215.683 382.013 209.054 383.439C204.17 384.486 199.165 385.062 194.038 385.062C178.567 385.062 164.188 380.057 152.418 371.669V255.014C157.226 251.571 162.429 248.705 168.026 246.49V303.976H181.813V242.653C185.787 242.001 189.882 241.606 194.038 241.606C198.194 241.606 202.289 242.001 206.263 242.653V352.543H220.051V246.49C222.72 247.597 225.314 248.765 227.847 250.13C230.577 251.632 233.186 253.255 235.643 255.014V304.309H249.431V267.831C259.638 280.253 265.751 296.058 265.751 313.289Z\" fill=\"#FFE200\"><\/path><path d=\"M54.2377 416.277C54.8899 418.75 55.8606 420.888 57.165 422.708C58.4694 424.468 60.153 425.894 62.231 426.864C63.9146 427.259 65.6134 427.774 67.2363 428.366C71.9232 430.247 76.2763 433.174 80.8873 437.072C79.3857 435.191 77.8992 433.371 76.337 431.612C73.7433 428.624 70.9373 425.696 68.2677 422.83C67.9492 422.511 67.6762 422.178 67.4184 421.859C65.9926 421.601 64.6882 421.085 63.3231 420.433C61.958 419.72 60.5929 418.871 59.1671 417.9C58.4543 417.385 59.1671 416.338 59.88 416.854C61.2451 417.764 62.5495 418.613 63.9146 419.265C64.5668 419.584 65.219 419.918 65.9319 420.115C65.3404 419.523 64.8854 418.886 64.3697 418.295C63.2017 416.732 62.1552 415.307 61.1844 413.805C60.6687 413.092 61.7001 412.379 62.231 413.092C63.2017 414.518 64.2483 416.019 65.4162 417.521C66.5841 419.023 67.8886 420.509 69.193 421.95C71.8625 424.817 74.532 427.668 77.2622 430.793C79.0216 432.81 80.7659 434.827 82.404 436.966C81.0996 433.72 80.1289 430.262 79.3402 426.622C78.6273 424.544 77.4594 422.329 76.0184 420.115C71.6653 413.229 67.0392 407.571 59.8345 403.794C55.7392 401.58 50.9918 400.154 45.3949 399.562C47.215 401.777 48.838 404.173 50.2789 406.782C51.9625 409.831 53.3428 413.092 54.2528 416.277H54.2377Z\" fill=\"#00844B\"><\/path><path d=\"M38.8879 243.517C38.7514 244.29 38.5694 245.018 38.175 245.792C38.7666 245.534 39.2823 245.473 39.798 245.473C39.4795 244.821 39.1458 244.169 38.8879 243.517Z\" fill=\"#00844B\"><\/path><path d=\"M36.6128 258.669C35.5055 259.579 34.6561 260.626 34.0039 261.794C33.291 262.962 32.836 264.266 32.5023 265.631C33.3517 269.332 33.8067 273.109 33.9281 276.886C34.4438 274.474 35.1567 272.199 35.9454 269.924C36.2639 269.074 37.5077 269.469 37.174 270.379C36.2639 272.851 35.4903 275.521 34.9595 278.114C36.3246 275.521 37.9475 273.367 39.5705 271.486C40.2833 270.713 41.0721 269.924 41.7849 269.211C43.7416 267.33 45.7589 265.829 47.761 264.463C46.1381 260.11 44.3786 255.879 42.5585 251.723C42.3006 252.117 42.0428 252.496 41.7849 252.83C40.4198 254.908 38.7969 256.864 36.5824 258.685L36.6128 258.669ZM40.9659 262.234C41.2844 262.097 41.5574 261.915 41.8153 261.779C42.331 261.324 42.7253 260.808 43.1804 260.217C43.4989 260.535 43.6354 261.187 43.6354 261.9C43.6354 264.115 42.9832 264.433 41.8153 264.949C41.3602 265.146 40.7687 265.404 40.1317 265.798C40.071 264.297 39.6766 262.674 40.981 262.219L40.9659 262.234Z\" fill=\"#00844B\"><\/path><path d=\"M45.9105 428.123C46.9571 429.033 47.9278 429.943 48.8986 430.914C50.203 432.142 51.5681 433.583 52.9938 435.267C56.4976 439.498 62.1551 444.307 68.9199 445.611C73.1517 446.385 77.7626 445.869 82.5708 443.017C82.4343 442.76 82.2523 442.502 82.1158 442.244C82.0551 442.244 81.9186 442.183 81.8579 442.183C78.612 440.682 75.6847 439.392 72.6966 439.316H72.4995C71.8472 439.316 71.1344 439.377 70.4822 439.514C69.1171 439.771 67.9492 439.969 66.9026 440.105C65.856 440.166 64.946 440.166 64.1724 440.045C63.8539 439.984 63.5202 439.908 63.6567 439.271C63.7932 438.679 64.1117 438.679 64.3696 438.755C65.0825 438.892 65.8712 438.892 66.8419 438.816C67.6913 438.755 68.662 438.619 69.7693 438.361C69.0564 438.103 68.3435 437.845 67.6306 437.451C66.0684 436.738 64.3847 435.828 62.5646 434.66C62.3068 434.463 62.0489 434.266 62.3675 433.75C62.7618 433.234 63.0197 433.431 63.2775 433.553C65.037 434.721 66.6599 435.631 68.2222 436.344C69.7238 437.056 71.2102 437.572 72.6511 438.027C75.897 438.088 78.9609 439.453 82.4039 441.015C82.5405 441.076 82.6618 441.152 82.7983 441.152L83.1168 440.757C77.3986 435.555 72.3174 431.778 66.7357 429.639C60.1075 426.97 52.9483 426.97 45.9257 428.138L45.9105 428.123Z\" fill=\"#00844B\"><\/path><path d=\"M48.0492 394.299C46.7448 392.995 45.2584 391.705 43.6202 390.462C42.1186 390.204 40.6929 390.067 39.1913 390.265C38.3419 390.401 38.1447 389.157 39.0548 389.036C39.9648 388.899 40.8142 388.839 41.5271 388.899C41.2086 388.642 40.8749 388.384 40.5564 388.187C39.7828 387.595 38.9941 387.019 38.2206 386.503C36.719 386.184 35.1718 385.593 33.4731 384.88C31.8501 384.167 30.0907 383.318 28.2099 382.286C27.3605 381.892 27.952 380.785 28.8014 381.179C30.6822 382.15 32.381 383.06 34.0039 383.712C34.459 383.97 34.9747 384.167 35.4297 384.304C35.0353 384.046 34.6561 383.712 34.3225 383.394C32.2445 381.771 30.2879 380.148 28.2706 378.388C27.5577 377.797 28.4071 376.826 29.0441 377.418C31.1221 379.177 33.0787 380.8 35.096 382.423C37.1133 384.046 39.1913 385.669 41.2693 387.17C43.9994 389.051 46.5324 391.068 48.9441 393.344C50.6277 394.967 52.0686 396.665 53.1759 398.288C52.9787 395.695 52.1293 393.086 50.5822 390.492C48.3071 386.594 44.9853 383.272 41.5423 380.345C36.8555 376.31 31.7288 373.519 26.1319 371.502C21.2479 369.743 16.0606 368.711 10.6609 368.059L10.7216 368.12C13.4517 370.137 16.0606 372.018 18.2599 374.687C22.158 379.374 26.2533 383.727 30.5457 387.686C34.7775 391.584 39.252 395.103 43.9994 398.212C47.0481 398.41 49.8542 398.865 52.4478 399.578C51.3406 397.757 49.8542 395.998 48.0189 394.314L48.0492 394.299Z\" fill=\"#00844B\"><\/path><path d=\"M38.5544 412.06C37.8415 412.257 37.5078 412.773 37.8415 413.425C38.2965 414.199 39.4037 414.593 40.1773 414.396C40.8902 414.259 41.2239 413.683 40.8902 413.031C40.4958 412.257 39.3886 411.863 38.5544 412.06Z\" fill=\"#00844B\"><\/path><path d=\"M68.6016 398.925C69.6481 397.423 67.7522 395.224 66.6449 396.71C66.1899 397.363 66.2506 398.394 66.8421 398.986C67.3578 399.501 68.1465 399.501 68.6016 398.925Z\" fill=\"#00844B\"><\/path><path d=\"M33.0333 357.305C34.2012 358.989 35.3084 360.809 36.2792 362.826C37.0527 364.389 37.7049 366.012 38.3571 367.771C39.5857 364.252 40.7688 361.856 39.0094 358.079C37.3257 354.378 34.9747 350.859 31.926 348.068C28.8015 345.277 25.0399 343.184 20.611 341.956C21.8395 344.231 22.9468 346.506 23.9327 348.918C25.1006 351.784 26.0107 354.712 26.86 357.897C27.5123 360.627 27.8308 363.691 28.0886 366.74C28.2858 368.165 28.4071 369.606 28.6043 371.032C31.471 372.2 34.2619 373.626 36.8555 375.324C36.992 373.959 37.1134 372.655 37.3712 371.426C37.5078 370.577 37.7656 370.198 37.5078 369.348C36.7949 367.21 36.0062 365.253 35.0961 363.372C34.186 361.492 33.1395 359.671 31.9716 358.033C31.4558 357.32 32.4266 356.608 33.0181 357.32L33.0333 357.305Z\" fill=\"#00844B\"><\/path><path d=\"M50.203 387.61C50.4002 384.288 50.1423 381.179 49.5508 378.054C48.7773 374.353 47.4728 370.713 45.7134 366.936C44.409 364.145 42.9225 361.415 41.4816 358.685C41.2844 361.415 41.0266 364.343 39.8587 367.391C39.343 368.756 38.8879 370.182 38.6301 371.684C38.3722 373.11 38.175 374.55 38.175 376.113C39.6008 377.083 41.0417 378.191 42.4068 379.359C43.2562 380.071 44.0298 380.784 44.8185 381.497C44.8792 379.874 44.682 378.373 44.3028 376.947C43.8478 375.188 43.1349 373.504 42.1641 371.805C41.7091 371.032 42.8164 370.379 43.2714 371.214C44.2421 372.973 45.0915 374.732 45.5465 376.613C46.0622 378.494 46.1987 380.451 46.0016 382.665C47.6245 384.288 49.0654 385.911 50.2334 387.61H50.203Z\" fill=\"#00844B\"><\/path><path d=\"M45.1219 362.826C45.7135 363.994 46.2899 365.162 46.8814 366.406C48.565 370.107 49.8694 373.626 50.6581 377.205C50.7947 375.249 50.916 373.231 51.0525 371.35C51.2497 367.847 51.371 364.464 51.4469 361.143C51.4469 360.233 52.7513 360.233 52.7513 361.143C52.6906 364.525 52.5541 367.968 52.2963 371.411C52.1598 374.536 51.9019 377.721 51.6441 380.845C51.3862 383.636 51.644 386.503 51.3862 389.294C52.2356 390.659 53.0091 392.16 53.5248 393.723C54.4956 392.752 55.2084 391.25 55.7393 389.233C56.3915 386.821 56.7859 383.773 56.9072 380.33C57.1651 373.049 56.5129 366.284 55.345 359.52C53.6613 354.454 52.2204 349.251 51.1132 343.912C49.9453 345.535 48.9745 347.492 48.0645 349.888C46.7601 353.331 45.7893 357.684 45.1371 362.826H45.1219Z\" fill=\"#00844B\"><\/path><path d=\"M15.4084 331.232C18.3965 334.159 21.3845 337.147 23.4018 341.439C23.4018 341.5 23.4625 341.5 23.4625 341.576C26.1927 342.547 28.6043 343.912 30.743 345.474C29.3779 342.744 27.7549 339.953 25.9955 337.223C23.781 333.704 21.4452 330.261 19.1094 326.878C19.1094 326.878 19.1094 326.818 19.0487 326.818C17.5471 326.302 16.0607 325.513 14.5591 324.603C12.9968 323.633 11.4345 322.389 9.87224 321.024C9.22003 320.432 10.0088 319.461 10.7216 320.114C12.2232 321.342 13.7097 322.525 15.2719 323.496C16.182 324.088 17.0921 324.603 18.0021 324.998C17.4864 324.224 16.9555 323.375 16.3792 322.586C15.4691 321.282 14.4984 319.992 13.3911 318.749C12.7996 318.096 13.7097 317.247 14.3619 317.899C15.4691 319.204 16.5005 320.508 17.4106 321.797C20.7323 326.348 24.0389 331.747 27.1027 336.555C29.3779 340.196 31.4558 343.836 33.1546 347.476C33.6703 347.931 34.1254 348.447 34.5804 348.978C35.3539 348.068 35.0961 346.05 33.9282 342.926C31.9109 337.405 28.7257 331.808 25.859 326.666C23.326 322.176 19.5492 317.763 15.0596 313.925C10.9036 310.346 6.15616 307.358 1.40868 305.34C1.27217 308.328 2.06089 311.316 3.42598 314.38C4.92758 317.763 7.06622 321.145 9.53855 324.725C11.2222 327.197 13.3153 329.214 15.3933 331.232H15.4084Z\" fill=\"#00844B\"><\/path><path d=\"M41.6183 345.671C40.4504 345.611 39.7375 346.066 39.4796 346.642C38.7061 348.144 40.1925 349.691 41.6941 349.691C42.5435 349.752 43.1199 349.236 43.3777 348.584C43.6356 348.068 43.6356 347.416 43.4384 346.9C43.2412 346.248 42.589 345.671 41.6183 345.671Z\" fill=\"#00844B\"><\/path><path d=\"M16.7128 355.287C16.4549 355.151 16.1213 355.151 15.8027 355.151C15.287 355.212 14.832 355.348 14.4376 355.667C14.0433 355.924 13.7248 356.319 13.5883 356.713C13.5276 356.971 13.5276 357.168 13.5276 357.426C13.5883 358.533 14.2405 359.504 15.1505 360.156C16.0606 360.808 17.1678 361.127 18.2751 361.066C18.6694 359.641 18.7301 358.336 18.4722 357.365C18.2144 356.258 17.5622 355.545 16.7128 355.287Z\" fill=\"#00844B\"><\/path><path d=\"M20.8687 300.077C23.9933 305.734 26.3898 311.453 28.2099 317.307C29.6357 322.115 30.7429 326.999 31.5923 331.944C31.653 329.472 31.9108 327.136 32.2445 324.861V324.542C31.5923 314.789 30.1059 306.599 27.497 300.228C25.4797 295.087 22.3552 290.157 17.6077 287.093C16.8341 292.356 16.637 297.559 17.3498 302.761C18.0021 307.645 19.3671 312.454 21.5058 317.262C23.0074 320.583 25.2067 322.919 26.9662 326.105C28.1947 328.319 29.3778 330.397 30.3485 332.278C29.575 327.333 28.4678 322.525 26.9662 317.717C25.146 311.923 22.8102 306.265 19.7463 300.744C19.2913 299.971 20.4592 299.318 20.8536 300.092L20.8687 300.077Z\" fill=\"#00844B\"><\/path><path d=\"M47.8521 313.288C47.8521 311.726 47.8521 310.164 47.9128 308.601C47.655 306.645 47.1393 304.825 46.487 303.202C45.4405 300.472 43.954 298.257 42.1946 296.437C41.2845 299.228 40.3138 301.958 39.3279 304.628C38.16 307.873 36.9921 311.134 35.9455 314.244C33.8069 321.069 32.7603 328.031 32.821 335.251C32.8816 338.376 34.7776 341.106 35.6118 344.033C36.0669 339.999 36.6584 335.964 37.2954 332.066C38.069 327.379 38.9791 322.829 40.0256 318.339C39.8284 317.232 39.7071 316.064 39.6313 314.896C39.6313 313.728 39.6919 312.484 39.8284 311.195C39.965 310.285 41.1935 310.422 41.1329 311.332C40.9357 312.56 40.875 313.743 40.9357 314.911C40.9357 315.503 40.9964 316.079 41.0722 316.671C41.3907 316.352 41.7244 315.897 41.9823 315.442C42.4373 314.669 42.8316 313.758 43.1502 312.651C43.2867 312.393 43.3473 312.06 43.9996 312.257C44.5911 312.454 44.5153 312.773 44.3939 313.03C44.0754 314.198 43.6204 315.245 43.0895 316.094C42.5738 316.944 41.9823 317.657 41.33 318.233C40.2835 322.844 39.3127 327.591 38.5392 332.278C37.7656 336.889 37.1741 341.576 36.7191 346.46C37.8263 346.263 37.8263 344.898 38.1448 343.988C39.1156 341.257 40.2835 338.33 41.4666 335.403C44.1361 328.699 46.9269 321.676 47.837 316.352V313.303L47.8521 313.288Z\" fill=\"#00844B\"><\/path><path d=\"M16.0607 283.696C18.1387 286.684 21.0054 287.731 23.4019 290.582C21.9761 286.426 20.4745 282.255 18.5937 278.297C16.2579 273.231 13.4519 268.483 9.81166 264.448C9.61448 264.191 9.35663 263.933 9.87233 263.538C10.3274 263.083 10.5245 263.341 10.7217 263.599C14.4985 267.755 17.35 272.578 19.7617 277.781C20.8082 279.995 21.7183 282.21 22.6283 284.546C21.2633 279.282 20.4139 274.338 19.9588 269.651C18.7303 266.466 16.9101 263.675 14.6198 261.127C12.4053 258.715 9.81166 256.576 6.94497 254.756C6.8843 259.64 7.46067 264.57 9.02294 269.575C10.4487 274.262 12.7239 278.934 16.0456 283.681L16.0607 283.696Z\" fill=\"#00844B\"><\/path><path d=\"M27.315 295.663C27.7093 292.933 27.9065 290.142 28.0279 287.336C28.1644 283.635 28.0279 279.798 27.77 275.96C27.5122 272.578 25.6314 268.619 23.9326 264.964C23.2804 263.735 22.704 262.431 22.1731 261.263C22.0366 260.944 21.9153 260.671 22.4917 260.414C23.068 260.156 23.2045 260.474 23.341 260.732C23.7961 261.9 24.4483 263.144 25.0247 264.433C25.6769 265.798 26.3291 267.163 26.9054 268.528C26.7689 267.36 26.6476 266.253 26.5111 265.085C26.0561 262.355 25.5404 259.564 24.9488 256.758C24.8881 256.44 24.7516 256.106 25.4038 255.985C26.0561 255.924 26.1167 256.182 26.1774 256.5C26.7689 259.367 27.3453 262.158 27.7397 264.888C28.0582 267.3 28.3312 269.635 28.5132 271.971C28.6497 273.336 28.9076 274.58 28.9683 275.869C29.2261 279.707 29.3626 283.605 29.2261 287.382C29.1654 291.083 28.7711 294.799 28.1189 298.378C28.3767 298.894 28.5739 299.485 28.7711 300.001C29.7418 299.349 30.1968 297.21 30.849 293.949C31.0462 293.039 31.2434 291.993 31.4406 290.885C33.3214 282.498 33.0029 273.261 31.0462 264.934C29.3626 257.653 26.2381 250.888 21.5513 245.822C20.6412 252.981 20.3227 260.459 21.0962 268.574C21.9456 277.735 24.1601 286.911 27.2695 295.618L27.315 295.663Z\" fill=\"#00844B\"><\/path><path d=\"M6.4443 297.999C7.03584 297.999 7.49087 297.802 7.87006 297.483C8.18859 297.165 8.4616 296.71 8.4616 296.179C8.4616 295.648 8.20375 295.208 7.87006 294.875C7.4757 294.556 6.96 294.359 6.36846 294.359C5.85276 294.359 5.3219 294.556 4.9427 294.875C4.62418 295.193 4.427 295.648 4.427 296.179C4.427 296.71 4.62418 297.15 5.01854 297.483C5.33706 297.802 5.86793 297.999 6.4443 297.999Z\" fill=\"#00844B\"><\/path><path d=\"M38.4329 247.02C37.0678 247.612 35.6421 248.78 35.1112 249.296C33.3518 251.116 32.0625 252.739 31.2131 254.24C29.7115 256.713 30.1666 257.425 30.9553 259.837C31.4103 258.866 31.7288 257.759 32.0625 256.713C32.9726 253.785 34.5955 252.481 37.1285 250.539C37.3864 250.342 37.6442 250.084 37.8414 249.948C38.5543 249.432 39.343 250.403 38.6149 250.918C38.3571 251.176 38.0992 251.374 37.9021 251.51C35.5662 253.33 34.004 254.498 33.2911 257.031C33.0332 257.88 32.7754 258.791 32.4417 259.503C32.1839 260.277 31.8502 260.929 31.471 261.46C31.6075 261.976 31.7895 262.567 31.926 263.144C32.1839 262.431 32.5175 261.779 32.8967 261.126C33.6096 259.822 34.5804 258.715 35.8241 257.683C38.3571 255.666 40.0559 253.254 41.6182 250.858C41.2996 249.629 41.1025 247.673 40.1166 246.884C39.798 246.565 39.1458 246.687 38.4329 247.02Z\" fill=\"#00844B\"><\/path><path d=\"M40.5717 272.32C38.0387 275.187 35.6877 278.752 33.8676 283.499C33.8676 283.499 33.8069 283.56 33.8069 283.636C33.6097 286.169 33.2912 288.777 32.6997 291.25C32.9575 291.053 33.2154 290.734 33.549 290.476C34.3984 289.505 35.3085 288.398 35.6877 287.609C37.1135 285.334 38.2965 283.711 39.6616 281.755C39.6616 281.694 39.7981 281.497 40.511 280.526C41.0267 279.813 42.0733 280.526 41.5576 281.3C41.4211 281.436 41.2391 281.755 40.7082 282.468C39.3431 284.424 38.1752 286.047 36.8101 288.322C36.3551 289.096 35.3843 290.34 34.4743 291.31C33.3064 292.539 32.457 292.539 32.1385 294.238C31.8199 295.739 31.5469 297.029 31.2891 298.136C34.2771 295.8 36.9466 293.328 39.2824 290.795C42.0733 287.746 44.2878 284.621 45.7135 281.633C47.0179 279.04 47.8522 276.294 48.1859 273.564C48.5044 271.092 48.383 268.62 47.7915 266.026C45.3192 267.709 42.8468 269.727 40.5717 272.336V272.32Z\" fill=\"#00844B\"><\/path><path d=\"M10.661 250.539C11.2526 250.858 11.9654 250.934 12.5418 250.736C13.194 250.479 13.649 250.024 13.9069 249.432C14.1647 248.841 14.1647 248.203 13.9069 247.475C13.649 246.823 13.194 246.308 12.6025 245.974C12.0109 245.716 11.2981 245.579 10.7217 245.837C10.0695 246.035 9.61445 246.49 9.3566 247.066C9.09875 247.657 9.09875 248.37 9.3566 249.023C9.55378 249.735 10.0695 250.251 10.661 250.524V250.539Z\" fill=\"#00844B\"><\/path><path d=\"M30.6974 245.914C31.4103 242.986 32.4569 240.195 33.7613 237.526C34.1556 236.677 35.3236 237.268 34.9292 238.042C33.6248 240.711 32.654 243.441 31.9412 246.232C31.4255 248.31 30.9704 250.464 30.7126 252.603C31.6226 251.298 32.7905 249.872 34.2315 248.371C36.1881 246.414 38.0689 245.246 37.6139 241.803C37.356 240.18 36.6431 237.647 34.8837 235.099C32.745 237.374 30.7884 240.362 29.8784 243.487C29.1655 246.081 28.9683 249.084 29.484 252.466C29.7418 250.252 30.1362 248.037 30.7126 245.898L30.6974 245.914Z\" fill=\"#00844B\"><\/path><path d=\"M83.6934 410.301C83.5569 409.906 83.7541 409.588 84.0877 409.451C82.2069 407.313 80.4475 405.159 78.688 402.884C78.5515 409.846 78.8852 416.474 79.856 422.587C80.766 428.183 82.2676 433.704 84.6034 438.846C85.7714 437.284 86.0292 436.571 86.8786 434.812C87.1971 432.339 87.3336 429.67 87.1364 426.879C86.8786 421.419 85.7107 415.625 83.6934 410.301Z\" fill=\"#00844B\"><\/path><path d=\"M85.2404 410.756C87.0605 415.958 88.1677 421.555 88.4256 426.879C88.4863 428.639 88.4863 430.322 88.4256 432.021C89.1992 430.792 89.4722 429.685 89.6542 428.184C90.1092 425.393 90.1699 421.419 89.9727 416.611C89.9727 416.353 90.0334 416.156 90.1699 416.095C88.4863 414.335 86.8482 412.576 85.2252 410.756H85.2404Z\" fill=\"#00844B\"><\/path><path d=\"M91.0344 427.926C91.9445 426.242 92.718 424.483 93.3702 422.526C93.6281 421.677 93.8253 420.767 94.0831 419.796C93.1124 418.946 92.2023 418.036 91.2923 417.202C91.4895 421.555 91.3529 425.196 91.0344 427.926Z\" fill=\"#00844B\"><\/path><path d=\"M373.244 318.157C368.299 321.342 364.204 326.742 361.474 332.005C361.277 332.4 361.155 332.46 361.155 332.855C361.216 334.675 361.095 336.495 360.761 338.315C362.778 336.176 364.856 334.083 366.934 332.005C367.071 330.959 367.192 329.988 367.45 329.017C367.708 327.971 368.042 326.879 368.497 325.832C368.815 324.861 369.998 325.377 369.665 326.226C369.27 327.334 368.952 328.304 368.694 329.351C368.633 329.745 368.497 330.2 368.436 330.58C371.303 327.849 374.291 325.18 377.279 322.51C377.992 321.919 378.78 322.905 378.128 323.481C375.064 326.151 372.076 328.82 369.149 331.611C369.467 331.611 369.801 331.611 370.12 331.672C370.893 331.672 371.743 331.732 372.531 331.808C373.441 331.869 373.305 333.173 372.395 333.037C371.682 332.976 370.893 332.9 370.059 332.9H367.844C365.236 335.433 362.703 338.042 360.23 340.833C359.457 343.7 358.152 346.551 356.453 349.221C356.969 348.902 357.5 348.629 358.016 348.311C359.244 346.49 360.609 344.61 362.445 343.245C366.934 339.862 370.514 337.132 373.623 333.886C376.809 330.701 379.539 327.061 382.269 321.919C383.695 319.249 384.408 315.67 385.97 313.395C380.964 314.502 377.188 315.609 373.229 318.142L373.244 318.157Z\" fill=\"#00844B\"><\/path><path d=\"M374.473 292.736C369.589 296.71 365.312 300.806 362.187 305.098C358.805 309.785 356.787 314.79 356.984 320.114C358.607 322.647 359.775 325.256 360.428 327.986C360.488 325.969 360.488 324.012 360.625 322.268C360.822 319.674 361.14 317.323 361.671 315.306C362.323 313.228 363.097 311.605 364.007 310.3C364.917 308.996 366.024 308.025 367.132 307.252C367.905 306.736 368.633 307.767 367.905 308.298C366.798 309.011 365.888 309.921 365.038 311.089C364.189 312.257 363.476 313.759 362.9 315.64C362.763 316.095 362.703 316.55 362.581 317.065C363.097 316.474 363.628 315.958 364.144 315.503C365.251 314.532 366.358 313.683 367.587 312.909C368.3 312.454 369.012 313.501 368.239 314.017C367.132 314.729 366.024 315.518 364.993 316.428C364.022 317.399 363.036 318.385 362.202 319.477C362.066 320.387 362.005 321.358 361.944 322.404C361.808 324.422 361.747 326.56 361.747 328.911C364.417 324.361 367.268 321.115 370.332 318.703C371.181 316.747 371.955 314.866 372.41 313.046C372.804 311.226 373.062 309.148 372.668 307.328C371.955 303.354 373.062 298.879 374.033 294.784C374.23 294.071 374.351 293.419 374.488 292.767L374.473 292.736Z\" fill=\"#00844B\"><\/path><path d=\"M353.663 352.815C349.173 356.592 346.246 361.794 344.501 367.316C344.441 367.316 344.441 367.376 344.441 367.376C344.896 375.567 342.621 383.439 340.148 390.856C342.363 387.155 344.501 383.06 346.519 378.828L346.913 378.054H346.852C346.989 377.084 347.049 376.173 347.049 375.263C346.989 374.353 346.852 373.443 346.731 372.594C346.534 371.744 347.778 371.487 347.96 372.336C348.142 373.185 348.217 374.095 348.278 375.006C350.159 370.713 351.979 366.36 353.617 362.189C353.936 361.339 355.119 361.794 354.785 362.644C353.162 366.876 351.342 371.229 349.446 375.521C349.643 375.385 349.765 375.203 349.962 375.066C351.008 374.293 352.04 373.565 353.086 372.928C353.86 372.533 354.391 373.64 353.738 374.035C352.692 374.626 351.721 375.339 350.75 376.052C349.446 377.099 348.339 377.933 347.687 379.374C346.382 382.165 345.017 384.834 343.591 387.367C346.124 384.698 349.052 382.225 352.176 380.087C354.391 378.661 356.666 377.357 359.002 376.249C360.17 372.928 359.396 370.395 358.744 368.256C358.425 367.209 358.152 366.299 358.031 365.329C357.379 359.413 362.126 351.875 365.251 346.93C361.095 348.098 356.924 350.115 353.678 352.846L353.663 352.815Z\" fill=\"#00844B\"><\/path><path d=\"M371.803 262.568C372.319 262.704 372.911 262.507 373.366 262.173C373.957 261.718 374.336 261.127 374.534 260.353C374.731 259.58 374.67 258.851 374.397 258.336C374.139 257.82 373.745 257.426 373.168 257.289C372.653 257.153 372.061 257.289 371.546 257.684C371.03 258.078 370.635 258.654 370.438 259.443C370.241 260.156 370.302 260.945 370.575 261.521C370.833 262.037 371.288 262.431 371.803 262.568Z\" fill=\"#00844B\"><\/path><path d=\"M345.214 272.578C346.64 272.776 348.005 273.488 349.446 274.793C349.507 273.17 349.765 271.471 350.159 269.848C350.296 269.135 350.478 268.483 350.751 267.77C350.356 266.405 349.901 265.101 349.446 263.872C348.93 262.568 348.4 261.4 347.763 260.368C347.247 259.595 348.354 258.943 348.809 259.716C349.522 260.823 350.114 262.052 350.629 263.356C350.948 264.13 351.221 264.979 351.479 265.829C352.252 263.948 353.238 262.189 354.345 260.49C353.83 257.502 352.525 255.682 350.826 254.514C349.264 253.406 347.308 252.951 345.366 252.83C343.091 256.986 342.12 259.458 342.181 261.991C342.242 264.661 343.349 267.452 345.245 272.457V272.594L345.214 272.578Z\" fill=\"#00844B\"><\/path><path d=\"M354.315 288.838C355.089 290.067 355.938 291.311 356.909 292.479C357.045 292.084 357.167 291.705 357.303 291.371C355.999 285.911 355.741 281.224 356.393 275.764C356.651 273.807 357.045 271.79 357.5 269.788C357.106 268.878 356.727 267.968 356.393 267.058C356.135 266.087 355.938 265.04 355.877 263.933C355.817 263.023 357.106 263.023 357.182 263.933C357.182 264.843 357.379 265.814 357.637 266.663C357.773 267.058 357.895 267.513 358.092 267.892C358.805 265.359 359.775 262.826 360.958 260.278C361.353 259.504 362.521 260.02 362.126 260.869C361.019 263.144 360.17 265.419 359.457 267.755C359.518 267.619 359.654 267.497 359.775 267.361C360.367 266.769 360.943 266.193 361.338 265.541C361.853 264.767 362.9 265.48 362.445 266.254C361.929 266.967 361.338 267.619 360.685 268.271C360.094 268.863 359.457 269.378 358.805 269.894C358.289 271.911 357.895 273.929 357.697 275.946C357.561 277.053 357.44 278.16 357.379 279.268C357.697 278.949 358.092 278.555 358.425 278.221C359.017 277.508 359.593 276.856 359.851 276.401C360.306 275.551 361.413 276.143 361.019 276.992C360.625 277.584 360.048 278.297 359.336 279.07C358.623 279.844 357.834 280.693 357.379 281.482C357.379 284.076 357.697 286.685 358.152 289.278C360.23 284.849 362.703 281.088 365.494 277.902C366.146 275.627 366.464 273.413 366.404 271.198C366.343 268.923 365.949 266.648 365.236 264.434C364.462 262.022 364.265 259.489 364.523 256.956C364.659 255.136 365.039 253.179 365.494 251.298C364.189 252.208 362.9 253.118 361.717 254.165C356.833 258.26 352.874 263.857 351.372 270.167C349.871 276.143 350.599 282.65 354.3 288.823L354.315 288.838Z\" fill=\"#00844B\"><\/path><path d=\"M355.422 300.274C355.422 299.759 355.483 299.228 355.483 298.712C353.602 296.498 351.782 294.222 350.022 291.947H348.066C347.414 291.947 346.761 291.887 346.049 291.75C345.139 291.614 345.336 290.385 346.185 290.521C346.837 290.582 347.489 290.658 348.142 290.658C348.46 290.719 348.733 290.719 349.052 290.719C348.4 289.869 347.823 289.035 347.232 288.246C346.185 286.821 345.154 285.455 344.183 284.015C342.56 283.878 340.998 283.559 339.572 282.847C338.723 282.452 339.314 281.284 340.088 281.679C341.058 282.134 342.105 282.452 343.212 282.649C341.908 280.89 340.679 279.07 339.511 277.31C338.996 276.537 340.027 275.809 340.558 276.598C341.726 278.281 342.894 279.98 344.077 281.664C344.016 281.072 343.88 280.435 343.819 279.843C343.622 278.615 343.364 277.432 343.106 276.203C342.909 275.293 344.153 275.035 344.335 275.885C344.592 277.113 344.85 278.418 345.047 279.661C345.305 281.027 345.503 282.452 345.639 283.893C346.488 285.061 347.398 286.305 348.233 287.473C348.748 288.125 349.203 288.838 349.734 289.49C349.734 289.232 349.795 288.974 349.795 288.777C349.856 287.928 349.856 287.094 349.856 286.305C349.856 285.395 351.16 285.395 351.16 286.305C351.16 287.154 351.16 287.988 351.099 288.838C351.039 289.551 350.963 290.203 350.842 290.916C352.464 292.994 354.087 295.011 355.786 297.028C355.983 295.982 356.181 294.95 356.499 293.904H356.438C355.271 292.478 354.163 290.977 353.314 289.475C350.781 285.243 349.537 280.89 349.416 276.598C346.291 272.957 343.364 273.534 339.602 274.262C338.889 274.398 338.177 274.52 337.388 274.656C338.237 281.482 339.86 286.623 342.727 290.658C345.518 294.693 349.613 297.681 355.468 300.274H355.422Z\" fill=\"#00844B\"><\/path><path d=\"M356.651 300.73C356.514 303.854 356.909 306.979 357.879 309.83C358.592 308.329 359.442 306.842 360.473 305.34L360.412 305.28C360.155 303.778 359.957 302.61 360.352 301.124C361.52 296.437 363.218 292.145 365.296 287.989C366.267 286.169 367.253 284.288 368.345 282.528C368.482 281.679 368.603 281.027 368.664 280.39C368.8 279.737 368.8 279.161 368.861 278.372C368.861 277.462 370.089 277.523 370.089 278.433C370.089 278.827 370.089 279.282 370.029 279.662C370.742 278.494 371.53 277.326 372.243 276.219C372.44 275.961 372.562 275.703 373.093 276.021C373.684 276.34 373.487 276.613 373.29 276.931C370.878 280.632 368.482 284.606 366.464 288.565C366.146 289.157 365.873 289.733 365.615 290.325L365.676 290.264C366.388 289.748 367.177 289.217 367.951 288.838C368.724 288.444 369.316 289.551 368.542 290.006C367.769 290.324 367.117 290.78 366.404 291.31C365.751 291.826 365.099 292.418 364.447 293.07C364.386 293.07 364.386 293.131 364.386 293.131C363.218 295.8 362.308 298.53 361.595 301.458C361.338 302.307 361.338 303.081 361.459 303.93C363.082 301.791 364.963 299.698 367.056 297.62C367.056 297.62 367.117 297.559 367.117 297.484C369.194 294.359 370.893 291.113 372.183 287.792C373.608 284.409 374.594 281.027 375.246 277.584C375.701 275.051 376.02 272.442 376.672 269.848C373.35 272.063 370.302 274.535 367.511 277.584C364.128 281.224 361.262 285.577 359.184 290.127C357.682 293.373 356.772 297.089 356.651 300.73Z\" fill=\"#00844B\"><\/path><path d=\"M385.333 299.167C385.591 298.576 386.243 297.15 385.136 297.089C384.62 297.089 383.907 297.347 383.058 297.802C381.753 298.652 381.374 299.759 380.843 301.124C380.843 301.185 380.782 301.26 380.782 301.321C381.95 301.321 382.86 301.124 383.573 300.805C384.347 300.487 384.938 299.895 385.333 299.183V299.167Z\" fill=\"#00844B\"><\/path><path d=\"M354.573 318.946C352.616 316.474 350.872 314.138 349.31 311.863C348.081 310.043 347.035 308.344 346.124 306.721C344.562 310.953 343.455 315.503 343 320.054C342.484 324.862 342.606 329.746 343.455 334.493C344.107 337.739 345.275 340.803 347.095 343.654C348.597 345.99 350.538 348.205 352.95 350.161C352.556 344.898 351.721 339.696 350.538 334.554C349.568 333.962 348.718 333.325 347.808 332.537C346.898 331.687 345.988 330.716 345.139 329.609C344.547 328.896 345.594 328.108 346.109 328.836C346.959 329.882 347.793 330.792 348.703 331.566C349.158 332.021 349.613 332.339 350.068 332.734C349.158 329.23 348.111 325.848 346.944 322.389C346.686 321.54 347.854 321.161 348.172 321.995C349.279 325.241 350.311 328.563 351.16 331.884C351.418 330.777 351.615 329.609 351.676 328.502C351.676 327.592 352.98 327.653 352.904 328.563C352.844 330.443 352.389 332.339 351.676 334.16C352.904 339.423 353.754 344.822 354.148 350.283C361.171 340.727 362.081 328.502 354.543 318.946H354.573Z\" fill=\"#00844B\"><\/path><path d=\"M337.6 398.591C341.18 397.029 344.562 395.406 347.869 393.192C348.066 392.282 348.324 391.372 348.718 390.522C349.112 389.612 349.628 388.702 350.22 387.853C350.417 387.595 350.614 387.337 351.13 387.716C351.645 388.035 351.448 388.308 351.266 388.565C350.675 389.339 350.22 390.188 349.901 391.038C349.704 391.356 349.583 391.69 349.507 392.084C353.739 389.021 357.576 385.577 361.277 381.937C361.929 381.346 362.839 382.195 362.187 382.847C358.349 386.624 354.512 390.006 350.675 392.797C347.156 395.33 343.394 397.605 339.299 399.304C339.102 399.82 338.844 400.275 338.647 400.806C342.878 400.548 347.095 399.183 351.266 396.65C355.877 393.92 360.427 389.824 364.856 384.425C367.905 380.784 371.166 377.341 374.351 373.898C366.874 373.838 359.138 376.947 352.889 381.118C346.003 385.805 340.27 392.115 337.615 398.606L337.6 398.591Z\" fill=\"#00844B\"><\/path><path d=\"M372.91 359.58C371.743 359.383 370.377 360.035 370.044 361.203C369.649 362.31 370.438 363.281 371.545 363.478C372.653 363.675 374.018 363.023 374.412 361.855C374.731 360.748 374.018 359.838 372.91 359.58Z\" fill=\"#00844B\"><\/path><path d=\"M344.365 348.144C343.713 347.37 342.681 347.37 341.953 348.144C341.635 348.538 341.438 349.054 341.438 349.706C341.438 350.297 341.635 350.874 342.029 351.268C342.681 352.042 343.652 352.315 344.365 351.405C344.684 351.01 344.881 350.434 344.881 349.782C344.881 349.13 344.684 348.553 344.365 348.159V348.144Z\" fill=\"#00844B\"><\/path><path d=\"M333.444 399.304C332.595 397.621 332.019 395.406 331.624 392.797C331.169 389.551 331.033 385.714 331.306 381.543C331.503 378.221 331.897 374.914 332.474 371.471C333.065 368.028 333.899 364.509 335.082 361.006C335.34 360.096 336.584 360.49 336.25 361.4C335.143 364.843 334.294 368.286 333.717 371.669C333.126 375.051 332.807 378.373 332.61 381.619V381.679C332.807 381.361 332.929 381.027 333.126 380.769C333.839 379.662 334.552 378.555 335.401 377.523C335.993 376.871 336.963 377.66 336.372 378.373C335.598 379.343 334.87 380.329 334.233 381.437C333.581 382.483 333.004 383.575 332.474 384.758C332.413 387.686 332.534 390.355 332.868 392.691C333.187 395.027 333.839 397.636 335.143 399.714C336.705 399.001 337.873 393.54 338.586 391.523C342.029 381.315 345.214 370.258 341.574 358.822C340.861 356.486 339.815 354.211 338.526 351.996C337.813 350.692 336.963 349.402 335.993 348.159C333.581 357.972 330.198 367.406 325.921 376.386L325.663 376.841C325.603 382.635 326.058 388.277 327.483 392.312C328.651 395.755 330.547 398.227 333.46 399.334L333.444 399.304Z\" fill=\"#00844B\"><\/path><path d=\"M307.765 434.296C311.011 430.398 314.333 428.441 315.501 423.239C315.819 421.677 315.956 420.19 315.895 418.628C315.834 417.657 317.063 417.521 317.124 418.491C317.26 420.175 317.124 421.874 316.729 423.497C316.593 424.149 316.411 424.801 316.214 425.378C317.518 424.012 318.747 422.647 319.915 421.222C321.932 418.749 323.752 416.156 325.254 413.092C325.709 412.318 326.816 412.895 326.421 413.683C324.799 416.808 322.978 419.477 320.961 422.01C320.188 422.92 319.459 423.83 318.625 424.68C319.596 424.164 320.506 423.633 321.416 423.254C322.19 422.86 322.781 423.967 321.932 424.361C320.764 424.953 319.52 425.59 318.352 426.318C314.454 428.654 311.648 431.657 308.736 435.161C307.234 436.981 305.809 438.862 304.504 440.879C309.707 438.998 314.318 436.389 318.413 432.749C322.842 428.851 326.664 423.709 329.925 417.081C331.745 413.243 333.429 409.467 335.128 405.629C335.901 403.748 336.751 401.852 337.6 399.972C320.43 407.449 309.191 419.993 304.899 438.073C305.809 436.768 306.719 435.54 307.765 434.296Z\" fill=\"#00844B\"><\/path><path d=\"M315.562 404.188C316.077 404.188 316.532 404.052 316.866 403.733C317.185 403.415 317.458 402.884 317.579 402.11C317.579 401.853 317.579 401.519 317.518 401.261C317.458 400.806 317.26 400.412 317.063 400.154C316.805 399.896 316.548 399.699 316.214 399.699H315.956C315.501 399.759 315.107 400.017 314.788 400.412C314.47 400.806 314.272 401.382 314.197 402.035C314.197 402.626 314.333 403.202 314.652 403.658C314.849 403.976 315.167 404.173 315.562 404.173V404.188Z\" fill=\"#00844B\"><\/path><path d=\"M347.429 415.504C346.322 414.73 344.638 414.851 343.531 415.64C342.302 416.55 342.424 417.976 343.986 418.507C344.699 418.765 345.548 418.704 346.322 418.507C347.687 418.112 348.794 416.626 347.429 415.519V415.504Z\" fill=\"#00844B\"><\/path><path d=\"M315.88 436.374C312.24 438.968 308.205 440.985 303.852 442.486C302.805 443.397 301.971 444.564 301.319 445.808C300.864 446.718 300.409 447.689 300.015 448.857C303.261 448.72 306.779 447.75 310.617 446.187C313.347 444.109 315.956 441.758 318.231 439.165C318.883 438.452 319.793 439.301 319.202 440.014C317.837 441.576 316.335 443.002 314.773 444.443C317.897 442.941 321.204 441.197 324.783 439.241C325.557 438.786 326.209 439.893 325.375 440.348C321.143 442.684 317.245 444.701 313.605 446.324C315.031 446.46 316.472 446.718 317.958 447.37C318.474 447.568 318.474 447.886 318.155 448.341C319.52 447.75 320.825 447.113 322.053 446.324C328.621 442.486 334.278 436.768 338.829 431.308C331.548 430.14 321.856 432.081 315.88 436.374Z\" fill=\"#00844B\"><\/path><path d=\"M311.785 447.492H310.875C307.098 448.993 303.655 449.903 300.409 450.161C306.582 451.663 312.376 450.813 317.639 448.599C317.579 448.538 317.503 448.538 317.442 448.462C315.622 447.689 313.665 447.613 311.785 447.492Z\" fill=\"#00844B\"><\/path><path d=\"M303.079 440.348C303.473 438.468 303.928 436.648 304.444 434.888C302.942 432.931 301.85 429.291 301.198 426.895C300.94 425.787 299.12 424.559 298.073 424.028C297.3 423.634 297.815 422.526 298.665 422.921C299.636 423.376 300.546 424.028 301.334 424.877C301.592 423.77 301.926 422.663 302.305 421.632C302.821 420.13 303.473 418.704 304.383 417.476C304.975 416.763 306.006 417.536 305.43 418.249C304.58 419.356 304.004 420.661 303.473 422.026C303.018 423.391 302.624 424.817 302.366 426.182C302.821 428.715 303.731 431.126 304.975 433.144C305.945 430.216 307.053 427.426 308.418 424.756C309.009 420.069 308.933 415.974 308.281 412.394C307.963 410.256 307.371 408.238 306.597 406.479C303.215 410.574 299.575 414.472 295.737 418.188C295.995 426.576 298.665 431.642 301.395 437.042C301.987 438.088 302.502 439.181 303.079 440.364V440.348Z\" fill=\"#00844B\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">RCD MALLORCA<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d414e0 elementor-widget elementor-widget-text-editor\" data-id=\"1d414e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Experience the passion of top-level football at Estadi Mallorca Son Moix! Come cheer on RCD Mallorca in LALIGA EA SPORTS and enjoy a unique atmosphere full of energy and excitement. Don\u2019t miss the chance to be part of every play and support our team on their way to victory.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f96947 elementor-widget elementor-widget-button\" data-id=\"9f96947\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.rcdmallorca.es\/en\/entradas\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">BUY TICKETS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bbdae51 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"bbdae51\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-d229e36 e-con-full e-flex e-con e-child\" data-id=\"d229e36\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e21ac7f elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"e21ac7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"159\" height=\"51\" viewBox=\"0 0 159 51\" fill=\"none\"><g id=\"Frame 1272637892\"><g id=\"Group\"><g id=\"Group_2\"><path id=\"Vector\" d=\"M33.4819 28.9795L32.1154 24.5887C30.4254 23.5452 28.1227 23.7966 26.6496 24.5525C26.6134 24.661 26.5411 24.8039 26.505 24.9847L25.6771 28.9795H20.8945L21.0391 28.2597L22.2266 22.7893C24.3125 13.2175 26.2899 4.5824 26.5429 3.86266L26.6875 3.46662L29.3481 3.86266L32.2257 3.43045L38.2681 28.9777H33.4855L33.4819 28.9795ZM29.3463 11.1686C28.7716 14.0837 27.9437 18.0061 27.0797 21.9267C27.7268 21.6392 28.4462 21.3155 29.274 21.1708C29.9934 21.2793 30.6766 21.4222 31.396 21.8182C30.6405 18.3642 29.885 14.2266 29.3463 11.1668V11.1686Z\" fill=\"#ED1B24\"><\/path><path id=\"Vector_2\" d=\"M39.1646 28.9614V3.45035L41.8252 3.81022L44.522 3.45035L44.7009 26.4441C48.7298 24.5362 49.4112 24.0335 51.3543 21.6591L52.4695 20.2919L52.146 28.9632H39.1628L39.1646 28.9614Z\" fill=\"#ED1B24\"><\/path><path id=\"Vector_3\" d=\"M53.9101 28.9614V3.45035L56.5707 3.81022L59.2675 3.45035L59.4464 26.4441C63.4753 24.5362 64.1567 24.0335 66.0998 21.6591L67.215 20.2919L66.8914 28.9632H53.9083L53.9101 28.9614Z\" fill=\"#ED1B24\"><\/path><path id=\"Vector_4\" d=\"M76.3373 29.1603C69.7924 29.1603 68.0645 25.3102 68.0645 16.3135C68.0645 7.89358 69.7906 3.25143 76.3373 3.25143C82.884 3.25143 84.6807 7.89358 84.6807 16.3135C84.6807 25.3102 82.7394 29.1603 76.3373 29.1603ZM76.3373 7.56988C73.3875 7.56988 73.2809 10.3403 73.2809 15.1272V16.3153C73.2809 23.2234 74.1087 25.2397 76.3373 25.2397C78.819 25.2397 79.5022 23.8364 79.5022 16.3153C79.5022 10.702 79.4661 7.57169 76.3373 7.57169V7.56988Z\" fill=\"#ED1B24\"><\/path><path id=\"Vector_5\" d=\"M96.9553 28.9795C95.4804 21.4945 94.6887 18.6155 90.7339 17.6444V28.9795H86.058L86.2026 8.3963L86.0941 3.43045L90.2297 4.2587L93.8627 3.64746H93.935C97.8916 3.64746 100.301 7.46136 100.301 11.9245C100.301 14.5159 98.5387 16.3858 96.8125 17.4654C99.69 19.6246 100.876 24.3735 101.272 28.9795H96.9553ZM92.9626 15.4147C94.761 15.4147 95.5889 14.0114 95.5889 11.9968C95.5889 10.1975 94.8695 8.36194 93.4669 8.36194H90.6616L90.7339 15.4147H92.9644H92.9626Z\" fill=\"#ED1B24\"><\/path><path id=\"Vector_6\" d=\"M111.721 14.9825C111.936 13.9029 112.08 12.0312 112.08 11.1686C112.08 9.00936 111.361 7.56987 109.599 7.56987C106.757 7.56987 106.578 10.8087 106.578 16.3135C106.578 23.2215 107.083 25.2379 109.671 25.2379C112.691 25.2379 112.44 22.6465 112.44 19.3733H116.863C116.935 20.0207 116.935 20.6319 116.935 21.245C116.935 26.4983 114.813 29.1621 109.671 29.1621C102.766 29.1621 101.364 25.312 101.364 16.3153C101.364 7.89538 102.73 3.25323 109.168 3.25323C114.347 3.25323 116.829 6.95864 116.829 10.9895C116.829 11.7816 116.72 13.4001 116.541 14.1922L111.722 14.9843L111.721 14.9825Z\" fill=\"#ED1B24\"><\/path><path id=\"Vector_7\" d=\"M129.956 28.9795L128.59 24.5887C126.9 23.5452 124.597 23.7966 123.124 24.5525C123.088 24.661 123.016 24.8039 122.98 24.9847L122.152 28.9795H117.369L117.514 28.2597L118.701 22.7893C120.787 13.2175 122.764 4.5824 123.017 3.86266L123.162 3.46662L125.823 3.86266L128.7 3.43045L134.743 28.9777H129.96L129.956 28.9795ZM125.821 11.1686C125.246 14.0837 124.418 18.0061 123.554 21.9267C124.201 21.6392 124.921 21.3155 125.749 21.1708C126.468 21.2793 127.151 21.4222 127.871 21.8182C127.115 18.3642 126.36 14.2266 125.821 11.1668V11.1686Z\" fill=\"#ED1B24\"><\/path><path id=\"Vector_8\" d=\"M15.3564 28.9795V19.3353C15.3564 16.205 15.3925 13.326 15.4287 11.2391C13.811 16.1326 12.515 22.4295 11.9041 28.4026L9.78211 27.9342L7.76857 28.4026C7.33658 22.934 6.15087 16.9952 4.35243 11.382C4.42473 13.8649 4.46087 16.8506 4.46087 19.7295V28.9777H0V3.43228L3.20106 3.86449L6.40211 3.46845L6.54671 3.82832C7.87702 7.13949 9.31578 11.6008 9.96286 15.5594C10.1418 14.8035 10.3226 14.0837 10.431 13.5448C11.2932 10.0185 12.4445 6.41975 13.4875 3.83013L13.6321 3.47026L16.7247 3.8663L19.998 3.43409V28.9813H15.3582L15.3564 28.9795Z\" fill=\"#ED1B24\"><\/path><\/g><g id=\"Group_3\"><path id=\"Vector_9\" d=\"M147.075 2.8174C147.091 3.06696 147.095 3.32556 147.082 3.55523C147.075 3.75596 147.053 3.93861 147.023 4.07966C147.006 4.13572 146.99 4.18816 146.97 4.23337C146.925 4.34549 146.898 4.42687 147.023 4.55165C147.03 4.55888 147.043 4.56793 147.052 4.57516C147.081 4.59505 147.108 4.60771 147.14 4.60771C147.169 4.60771 147.2 4.59144 147.232 4.55888C147.245 4.55165 147.252 4.53899 147.261 4.52633C147.317 4.454 147.362 4.33284 147.39 4.17189C147.419 4.00732 147.435 3.79755 147.429 3.54799C147.429 3.20982 147.413 2.81017 147.353 2.42317C147.294 2.03617 147.196 1.66184 147.032 1.37611C146.996 1.31101 146.95 1.23505 146.898 1.18261C146.849 1.1374 146.793 1.11389 146.733 1.1374C146.6 1.19708 146.629 1.33813 146.741 1.41047C146.874 1.49546 146.954 1.78481 147.003 2.08319C147.052 2.37796 147.068 2.68358 147.075 2.81559V2.8174Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_10\" d=\"M150.639 7.30044C149.233 6.91344 147.793 6.71633 146.354 6.71633C145.118 6.71633 143.878 6.861 142.658 7.14673C142.546 7.17566 142.598 7.13949 142.533 7.11417C142.497 7.0979 142.461 7.12683 142.363 7.13045C142.238 7.13768 142.262 7.06173 142.318 6.99663C142.367 6.94418 142.426 6.92791 142.423 6.90078C142.338 6.92429 142.302 6.92972 142.274 6.92429C142.229 6.91163 142.262 6.83206 142.173 6.85196C142.105 6.86823 142.012 6.90802 142.012 6.86823C142.009 6.83206 142.061 6.75973 142.108 6.74707C142.961 6.49751 143.843 6.32391 144.742 6.23168C144.798 6.26061 144.915 6.34922 144.922 6.37997C144.922 6.35103 145.018 6.24253 145.071 6.20274C145.494 6.16657 145.924 6.1503 146.35 6.1503C146.777 6.1503 147.203 6.16657 147.635 6.20274C147.688 6.24795 147.78 6.35103 147.78 6.37997C147.787 6.35103 147.905 6.2588 147.957 6.23168C149.069 6.34922 150.16 6.58251 151.194 6.94057C150.981 6.93333 150.759 6.86462 150.551 6.80675C150.531 6.8827 150.99 7.00386 151.099 6.99663C151.144 6.99301 151.328 7.02014 151.473 7.10875C151.59 7.18108 151.662 7.2697 151.449 7.29863C151.236 7.32756 150.938 7.17385 150.878 7.15034C150.757 7.10513 150.524 7.13045 150.636 7.29863L150.639 7.30044Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_11\" d=\"M145.835 1.18082C146.108 1.09583 145.96 1.3906 145.891 1.48644C145.803 1.61484 145.747 1.8445 145.707 2.08321C145.658 2.37798 145.642 2.6836 145.635 2.81561C145.618 3.06517 145.615 3.32377 145.627 3.55344C145.635 3.75417 145.656 3.93682 145.687 4.07787C145.703 4.13393 145.719 4.18637 145.739 4.23158C145.785 4.34371 145.812 4.42508 145.687 4.54986C145.68 4.5571 145.667 4.56614 145.658 4.57337C145.629 4.59326 145.602 4.60592 145.569 4.60592C145.541 4.60592 145.51 4.58965 145.477 4.5571C145.47 4.54986 145.457 4.5372 145.448 4.52454C145.392 4.45221 145.353 4.33105 145.32 4.1701C145.291 4.00554 145.275 3.79576 145.28 3.5462C145.28 3.22431 145.287 2.99826 145.329 2.78849C145.374 2.5751 145.447 2.37436 145.571 2.09225C145.6 2.02353 145.624 1.90237 145.653 1.77036C145.685 1.60037 145.725 1.4123 145.781 1.27848C145.797 1.24231 145.817 1.20976 145.837 1.18263L145.835 1.18082Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_12\" d=\"M146.058 1.76492C146.086 1.88247 146.182 1.9747 146.303 1.99459C146.155 2.02352 146.041 2.15192 146.041 2.30563C146.041 2.4702 146.17 2.60402 146.33 2.62029C146.157 2.63295 146.02 2.77762 146.02 2.95485C146.02 3.13207 146.161 3.28036 146.338 3.2894C146.168 3.29663 146.032 3.44311 146.032 3.61491C146.032 3.77224 146.144 3.90425 146.298 3.93319C146.17 3.96212 146.072 4.07786 146.072 4.2153C146.072 4.23157 146.072 4.24785 146.076 4.26413C146.011 4.32019 145.964 4.40156 145.942 4.50102C145.893 4.50464 145.846 4.5173 145.801 4.53358C145.889 4.41241 145.853 4.3238 145.808 4.20264C145.792 4.15743 145.772 4.11403 145.759 4.05797C145.727 3.92415 145.707 3.74692 145.7 3.54981C145.692 3.32376 145.696 3.07058 145.707 2.82103C145.714 2.69986 145.73 2.43765 145.767 2.17724C145.795 2.00725 145.884 1.83545 146.052 1.76673L146.058 1.76492Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_13\" d=\"M146.911 4.53721C146.865 4.51732 146.818 4.50466 146.766 4.50104C146.746 4.39977 146.697 4.3202 146.632 4.26414C146.636 4.24787 146.636 4.23159 146.636 4.21532C146.636 4.07788 146.54 3.96214 146.41 3.93321C146.564 3.90427 146.676 3.77226 146.676 3.61493C146.676 3.44132 146.538 3.29665 146.37 3.28942C146.547 3.28218 146.688 3.13209 146.688 2.95486C146.688 2.77764 146.551 2.63297 146.377 2.62031C146.538 2.60404 146.667 2.47202 146.667 2.30565C146.667 2.15194 146.555 2.02354 146.405 1.99461C146.578 1.96206 146.686 1.79749 146.654 1.6275C146.771 1.70346 146.86 1.77579 146.887 1.91685C146.9 1.97291 146.911 2.03439 146.92 2.09407C146.968 2.37979 146.988 2.68722 146.996 2.81923C147.008 3.06879 147.012 3.32197 147.003 3.54802C146.996 3.74513 146.974 3.92236 146.943 4.05618C146.93 4.11224 146.911 4.15745 146.894 4.20085C146.846 4.32201 146.813 4.41424 146.907 4.5354L146.911 4.53721Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_14\" d=\"M146.311 5.32746C146.114 5.60957 145.891 5.74701 145.651 5.77414C145.409 5.79765 145.148 5.70903 144.87 5.54447C144.841 5.52819 144.846 5.48479 144.877 5.47213C144.966 5.44863 145.022 5.38352 145.047 5.31119C145.063 5.2714 145.067 5.22619 145.06 5.18279C145.053 5.13758 145.036 5.0978 145.011 5.06163C144.966 5.00195 144.899 4.95674 144.801 4.95674C144.684 4.95674 144.608 5.01642 144.568 5.0978C144.552 5.13396 144.545 5.17013 144.545 5.20992C144.541 5.2497 144.548 5.29129 144.561 5.32746C144.593 5.40884 144.666 5.47575 144.783 5.48479C144.812 5.48479 144.832 5.52458 144.812 5.5499C144.631 5.77594 144.402 5.89168 144.169 5.92423C143.899 5.9604 143.625 5.88806 143.399 5.74339C143.37 5.7235 143.386 5.66744 143.428 5.67106C143.637 5.69095 143.769 5.60234 143.834 5.47756C143.87 5.40884 143.887 5.32385 143.883 5.24789C143.876 5.16652 143.851 5.09056 143.811 5.03089C143.742 4.93504 143.621 4.87717 143.46 4.91877C143.444 4.92238 143.42 4.91153 143.415 4.89526C143.366 4.76686 143.278 4.69814 143.178 4.66921C143.126 4.65655 143.07 4.65655 143.014 4.66921C142.961 4.68187 142.912 4.70537 142.869 4.74154C142.793 4.81026 142.744 4.91153 142.757 5.04716C142.757 5.06344 142.741 5.08333 142.724 5.08695C142.564 5.1195 142.482 5.228 142.462 5.34916C142.45 5.41427 142.459 5.4866 142.482 5.55532C142.506 5.62042 142.547 5.68372 142.6 5.73254C142.705 5.82477 142.865 5.86094 143.059 5.76871C143.091 5.75244 143.128 5.79765 143.108 5.82477C142.931 6.05805 142.741 6.20815 142.52 6.27145C142.298 6.34016 142.048 6.32751 141.743 6.23528C141.72 6.23166 141.71 6.19911 141.723 6.17922C141.752 6.13401 141.763 6.08699 141.763 6.03816C141.763 5.99295 141.756 5.94955 141.73 5.90977C141.71 5.86998 141.682 5.83743 141.642 5.81392C141.606 5.79041 141.557 5.77414 141.501 5.77414C141.409 5.77414 141.336 5.81392 141.291 5.87541C141.268 5.91157 141.251 5.95136 141.242 5.99657C141.239 6.04178 141.239 6.08518 141.255 6.13039C141.278 6.19911 141.331 6.26421 141.425 6.29134C141.445 6.29495 141.457 6.3275 141.445 6.3474C141.369 6.46494 141.271 6.5409 141.172 6.58972C141.047 6.6494 140.913 6.6711 140.794 6.66567C140.762 6.66567 140.742 6.62951 140.762 6.606C140.827 6.52462 140.863 6.42516 140.863 6.3275C140.863 6.27868 140.856 6.23528 140.839 6.19368C140.819 6.1539 140.794 6.11773 140.763 6.0888C140.711 6.05263 140.646 6.02912 140.557 6.02912C140.489 6.0255 140.436 6.04178 140.387 6.0689C140.339 6.09784 140.295 6.14124 140.254 6.19368C140.237 6.21358 140.201 6.20996 140.189 6.18645C140.124 6.07795 140.048 6.00923 139.963 5.97306C139.878 5.93689 139.789 5.93327 139.701 5.95678C139.612 5.97668 139.527 6.0255 139.458 6.09422C139.366 6.17922 139.297 6.30038 139.281 6.43239C139.278 6.46856 139.274 6.50473 139.274 6.54994C139.274 6.61504 139.281 6.68376 139.307 6.73982C139.33 6.78865 139.366 6.82481 139.424 6.83205C139.431 6.83205 139.444 6.83566 139.453 6.83566C139.489 6.83566 139.522 6.82301 139.549 6.80311C139.572 6.78684 139.588 6.76694 139.601 6.74344C139.614 6.71993 139.621 6.69099 139.621 6.66206C139.621 6.62951 139.614 6.59696 139.592 6.56983C139.585 6.5626 139.585 6.53728 139.588 6.53005C139.637 6.42516 139.701 6.36548 139.778 6.34016C139.847 6.31665 139.926 6.32027 140.004 6.35282C140.064 6.37271 140.125 6.4125 140.178 6.45771C140.266 6.53005 140.315 6.65482 140.431 6.54632C140.467 6.51377 140.496 6.47399 140.512 6.42878C140.536 6.37633 140.608 6.40527 140.584 6.45771C140.565 6.51377 140.528 6.5626 140.489 6.60238C140.331 6.72716 140.456 6.72716 140.456 6.92789C140.456 6.9514 140.46 6.9731 140.469 6.99299C140.518 7.11777 140.722 7.16298 140.839 7.11416C142.555 6.42516 144.46 6.07795 146.365 6.07795C148.27 6.07795 150.17 6.42516 151.885 7.11416C151.997 7.16298 152.207 7.11777 152.255 6.99299C152.4 6.69461 151.764 6.73439 151.55 6.58972C151.449 6.5409 151.353 6.46494 151.278 6.3474C151.265 6.3275 151.274 6.29495 151.297 6.29134C151.39 6.2624 151.442 6.19911 151.467 6.13039C151.48 6.08518 151.484 6.04178 151.48 5.99657C151.473 5.95136 151.456 5.91157 151.428 5.87541C151.388 5.81573 151.315 5.77414 151.221 5.77414C151.165 5.77414 151.117 5.79041 151.077 5.81392C151.041 5.83743 151.012 5.86998 150.988 5.90977C150.968 5.94955 150.956 5.99476 150.956 6.03816C150.956 6.08699 150.972 6.13401 151.001 6.17922C151.014 6.19911 151.001 6.23166 150.977 6.23528C150.676 6.32751 150.423 6.34016 150.2 6.27145C149.978 6.20634 149.79 6.05805 149.613 5.81935C149.593 5.79041 149.629 5.74701 149.665 5.76329C149.855 5.85913 150.016 5.82296 150.121 5.73435C150.177 5.68552 150.217 5.62585 150.242 5.55713C150.271 5.48841 150.278 5.41607 150.265 5.35097C150.249 5.22981 150.164 5.12131 150.003 5.08514C149.987 5.08152 149.971 5.06163 149.971 5.04535C149.983 4.90791 149.935 4.80845 149.859 4.73973C149.813 4.70357 149.766 4.68006 149.714 4.6674C149.658 4.65474 149.602 4.65474 149.55 4.6674C149.448 4.69633 149.36 4.76324 149.313 4.89345C149.309 4.90972 149.284 4.92238 149.268 4.91696C149.103 4.87717 148.982 4.93685 148.913 5.0345C148.874 5.09418 148.848 5.17194 148.845 5.24789C148.841 5.32385 148.852 5.40161 148.89 5.47033C148.949 5.59511 149.083 5.68733 149.296 5.67106C149.333 5.66744 149.353 5.7235 149.32 5.74339C149.098 5.88806 148.825 5.9604 148.555 5.92423C148.322 5.89168 148.093 5.77594 147.912 5.5499C147.892 5.52639 147.908 5.48479 147.941 5.48479C148.058 5.47756 148.131 5.40884 148.163 5.32746C148.176 5.29129 148.179 5.25151 148.179 5.20992C148.179 5.16832 148.167 5.13396 148.151 5.0978C148.114 5.01642 148.038 4.95674 147.921 4.95674C147.825 4.95674 147.751 5.00195 147.711 5.06163C147.682 5.0978 147.666 5.13758 147.663 5.18279C147.655 5.228 147.659 5.2714 147.67 5.31119C147.693 5.38352 147.751 5.44863 147.843 5.47213C147.876 5.48479 147.879 5.52819 147.851 5.54447C147.569 5.71446 147.306 5.79765 147.066 5.77052C146.824 5.74701 146.603 5.60596 146.406 5.31842C146.383 5.28587 146.43 5.23704 146.462 5.26236C146.511 5.30757 146.587 5.32746 146.672 5.32746C146.737 5.32746 146.806 5.3148 146.865 5.28768C146.925 5.26417 146.983 5.228 147.023 5.17556C147.071 5.1195 147.099 5.04174 147.099 4.94589C147.099 4.85005 147.059 4.75239 146.994 4.68367C146.929 4.61857 146.846 4.57879 146.744 4.5824C146.728 4.5824 146.708 4.56251 146.708 4.54624C146.696 4.46124 146.663 4.39795 146.62 4.34912C146.571 4.43773 146.482 4.49741 146.374 4.50283C146.45 4.8175 146.446 4.79218 146.78 4.86994C146.623 4.86632 146.475 4.87356 146.37 4.99472C146.265 4.87356 146.117 4.86632 145.96 4.86994C146.294 4.79399 146.291 4.8175 146.367 4.50283C146.258 4.49922 146.17 4.43773 146.121 4.34912C146.076 4.39795 146.045 4.46124 146.032 4.54624C146.032 4.56251 146.012 4.5824 145.996 4.5824C145.904 4.57879 145.812 4.61495 145.743 4.67102C145.683 4.72346 145.647 4.79579 145.651 4.87717C145.651 4.93323 145.68 4.98206 145.719 5.02184C145.739 5.03812 145.765 5.05439 145.788 5.06163C145.812 5.07429 145.837 5.0779 145.86 5.07429C145.893 5.07429 145.929 5.06163 145.956 5.02908C145.98 5.00014 146.032 5.02908 146.021 5.06525C146.014 5.11407 146.018 5.15747 146.034 5.19364C146.047 5.22619 146.07 5.25332 146.094 5.27502C146.123 5.29129 146.15 5.30395 146.182 5.30395C146.211 5.30395 146.242 5.29672 146.271 5.2714C146.303 5.24789 146.347 5.29491 146.327 5.32746H146.311Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_15\" d=\"M146.356 1.45932C146.231 1.45932 146.126 1.56421 146.126 1.68899C146.126 1.81377 146.231 1.92227 146.356 1.92227C146.48 1.92227 146.585 1.81738 146.585 1.68899C146.585 1.56059 146.48 1.45932 146.356 1.45932Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_16\" d=\"M144.454 29.9596C144.373 30.1242 144.257 30.2019 144.067 30.1821C143.861 30.1585 143.701 30.0645 143.601 29.9361C143.549 29.871 143.513 29.7987 143.493 29.7227C143.473 29.6468 143.464 29.5654 143.473 29.4858C143.493 29.3122 143.585 29.1386 143.755 29.0066C143.939 28.8583 144.31 28.7371 144.644 28.6232C144.778 28.578 144.906 28.5382 145.011 28.4984C145.168 28.4388 145.244 28.3212 145.257 28.2127C145.264 28.1404 145.241 28.059 145.175 28.0156C145.119 27.9794 145.034 27.9794 144.926 28.0445C144.693 28.182 144.474 28.267 144.25 28.3502C144.133 28.399 144.008 28.4424 143.883 28.4984C143.598 28.6268 143.359 28.8366 143.211 29.0826C143.03 29.3809 142.958 29.748 143.102 30.0699C143.184 30.2472 143.319 30.4081 143.532 30.5365C143.758 30.6776 144.031 30.7065 144.27 30.645C144.463 30.5926 144.653 30.4804 144.758 30.3068C144.879 30.1133 144.886 29.7878 144.722 29.6142C144.593 29.4804 144.355 29.4894 144.279 29.6703C144.246 29.7426 144.263 29.824 144.315 29.8801C144.355 29.9198 144.407 29.9397 144.456 29.9614L144.454 29.9596Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_17\" d=\"M147.265 27.9541C147.386 28.0879 147.462 28.2326 147.599 28.361C147.655 28.417 147.708 28.4623 147.76 28.502C147.852 28.5671 147.957 28.5943 148.062 28.6304C148.4 28.7389 148.774 28.8601 148.957 29.0048C149.127 29.1386 149.219 29.3104 149.239 29.484C149.255 29.6449 149.21 29.8059 149.11 29.9361C149.009 30.0645 148.848 30.1585 148.644 30.182C148.454 30.2019 148.339 30.126 148.257 29.9596C148.306 29.9397 148.358 29.9198 148.398 29.8782C148.451 29.8222 148.467 29.7408 148.434 29.6685C148.358 29.4876 148.12 29.4786 147.992 29.6124C147.827 29.786 147.834 30.1115 147.955 30.305C148.06 30.4786 148.25 30.5907 148.443 30.6432C148.68 30.7029 148.955 30.6757 149.181 30.5347C149.394 30.4063 149.531 30.2453 149.611 30.0681C149.756 29.7462 149.683 29.3791 149.503 29.0807C149.354 28.8348 149.116 28.625 148.83 28.4966C148.705 28.4406 148.581 28.3953 148.463 28.3483C148.237 28.2633 148.02 28.1783 147.787 28.0427C147.634 27.9541 147.449 27.9505 147.269 27.9541H147.265Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_18\" d=\"M146.356 27.6955C151.341 27.6955 155.408 23.6266 155.408 18.6336C155.408 13.6407 151.341 9.58081 146.356 9.58081C141.371 9.58081 137.304 13.6497 137.304 18.6336C137.304 23.6176 141.371 27.6955 146.356 27.6955Z\" fill=\"#E20613\"><\/path><path id=\"Vector_19\" d=\"M147.16 28.1639C147.256 28.2236 147.35 28.2977 147.429 28.3773C147.702 28.6467 147.876 29.0265 147.876 29.4406C147.876 29.5129 147.872 29.5889 147.86 29.663C147.879 29.6233 147.905 29.5871 147.932 29.5582C147.984 29.5057 148.044 29.4732 148.105 29.4569C148.17 29.4406 148.23 29.4406 148.29 29.4533C148.342 29.4695 148.391 29.4985 148.431 29.5346C148.463 29.5672 148.487 29.6034 148.503 29.6431C148.523 29.6884 148.532 29.739 148.523 29.7914C148.516 29.8439 148.49 29.8927 148.451 29.9361C148.427 29.956 148.398 29.9813 148.362 30.0012C148.385 30.0374 148.418 30.0609 148.451 30.0772C148.503 30.1061 148.563 30.1097 148.628 30.1061C148.812 30.0826 148.953 30.0012 149.047 29.8891C149.092 29.833 149.123 29.7715 149.139 29.7046C149.159 29.6359 149.163 29.5672 149.155 29.4949C149.139 29.3411 149.06 29.1892 148.906 29.0681C148.736 28.9306 148.366 28.8149 148.037 28.7046C147.988 28.6883 147.944 28.6757 147.919 28.6684C147.834 28.6395 147.775 28.6087 147.713 28.5672C147.657 28.5274 147.605 28.4785 147.54 28.4189C147.475 28.3538 147.415 28.2905 147.355 28.2217L147.352 28.2181C147.306 28.2055 147.259 28.1946 147.214 28.182C147.194 28.1783 147.178 28.1693 147.158 28.1657L147.16 28.1639Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_20\" d=\"M148.449 11.0112C151.794 11.9335 154.263 15.0078 154.263 18.6336C154.263 22.2595 151.794 25.3428 148.449 26.2651V25.3952C151.328 24.4964 153.427 21.8056 153.427 18.6354C153.427 15.9843 151.953 13.6714 149.786 12.4598V14.6317C150.914 15.5991 151.635 17.0368 151.635 18.6372C151.635 20.8055 150.323 22.67 148.451 23.4874V22.556C149.844 21.8019 150.798 20.3281 150.798 18.6354C150.798 17.5685 150.421 16.5883 149.788 15.8198V18.0803H148.935V15.0259C148.781 14.9174 148.62 14.8161 148.452 14.7239V13.7926C148.617 13.8649 148.778 13.9463 148.935 14.0349V12.0565C148.778 11.9914 148.617 11.9353 148.452 11.8829V11.0131L148.449 11.0112ZM147.285 10.7816C147.684 10.8304 148.069 10.9064 148.449 11.0112V11.8811C148.292 11.8323 148.131 11.7889 147.966 11.7473V13.6081C148.131 13.6605 148.292 13.7202 148.449 13.7889V14.7203C148.292 14.6353 148.131 14.5629 147.966 14.4942V21.0659H147.285V10.7798V10.7816ZM148.449 26.2651C148.071 26.3699 147.684 26.4459 147.285 26.4947V25.6484C147.684 25.596 148.075 25.511 148.449 25.3952V26.2651ZM148.449 23.4856C148.082 23.6429 147.691 23.764 147.285 23.8364V22.9828C147.695 22.8942 148.085 22.7495 148.449 22.556V23.4874V23.4856ZM147.111 10.7617C147.167 10.7689 147.229 10.7743 147.285 10.7816V21.0677H147.111V14.2591C146.865 14.2193 146.612 14.194 146.354 14.194C146.095 14.194 145.842 14.2175 145.597 14.2591V18.0586H144.743V14.4978C144.396 14.6353 144.075 14.8125 143.776 15.0259V22.254C144.505 22.773 145.396 23.0841 146.354 23.0841C146.672 23.0841 146.983 23.0479 147.285 22.9828V23.8364C146.983 23.8924 146.668 23.9214 146.354 23.9214C143.764 23.9214 141.602 22.0352 141.159 19.5704L141.976 19.3968C142.114 20.1708 142.448 20.8706 142.923 21.4547V15.818C142.67 16.1236 142.461 16.4672 142.294 16.8325L141.546 16.4581C142.159 15.1127 143.323 14.0692 144.743 13.6099V11.7491C141.622 12.4869 139.283 15.2953 139.283 18.6354C139.283 22.3897 142.231 25.4766 145.931 25.699V26.5417C141.772 26.3157 138.444 22.8544 138.444 18.6372C138.444 14.4201 141.593 11.1523 145.597 10.7653V13.4164C145.842 13.3802 146.095 13.3604 146.354 13.3604C146.612 13.3604 146.865 13.3802 147.111 13.4164V10.7653V10.7617ZM147.285 26.4947V25.6484C147.115 25.6719 146.95 25.6882 146.777 25.6972V26.5399C146.95 26.5273 147.115 26.5164 147.285 26.4947Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_21\" d=\"M146.363 28.6232C146.282 28.7643 146.198 28.9089 146.104 29.059C146.032 29.1802 145.956 29.3014 145.875 29.4225C145.851 29.4623 145.842 29.4912 145.882 29.5147C145.938 29.5473 146.016 29.5509 146.076 29.5545C146.423 29.5871 146.752 29.7553 147.043 29.9451C147.124 29.994 147.268 30.1151 147.348 30.1224C147.388 30.1296 147.424 30.1097 147.473 30.0536H147.469C147.514 29.9885 147.57 29.9289 147.606 29.8601C147.702 29.6865 147.567 29.5455 147.422 29.4659C147.091 29.2815 146.737 29.1404 146.376 29.0391C146.323 29.0229 146.343 28.9469 146.395 28.9632C146.721 29.0554 147.039 29.1766 147.337 29.3303C147.511 29.4189 147.619 29.2381 147.652 29.097C147.697 28.8872 147.587 28.6973 147.379 28.6341C147.109 28.5491 146.835 28.4731 146.558 28.4279C146.361 28.3917 146.457 28.4641 146.365 28.625L146.363 28.6232Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_22\" d=\"M147.373 28.4297C147.128 28.1874 146.797 28.0355 146.432 28.0156C146.432 28.0156 146.43 28.0168 146.428 28.0192C146.395 28.0391 146.392 28.0952 146.395 28.1404C146.399 28.2001 146.419 28.3248 146.484 28.3339C146.75 28.37 147.012 28.4388 147.268 28.5147C147.305 28.5274 147.344 28.5274 147.37 28.4912C147.377 28.4785 147.386 28.4424 147.373 28.4315V28.4297Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_23\" d=\"M146.267 30.862C146.296 30.8656 146.327 30.8656 146.356 30.8656H146.388C146.401 30.8059 146.404 30.7444 146.408 30.6848C146.408 30.6287 146.484 30.6323 146.484 30.6884C146.484 30.7444 146.48 30.8059 146.468 30.862C146.52 30.8584 146.573 30.8493 146.625 30.8421C146.629 30.7734 146.629 30.7047 146.621 30.6359C146.618 30.5799 146.694 30.5708 146.703 30.6287C146.706 30.6938 146.706 30.7571 146.706 30.8222C146.752 30.8095 146.799 30.7987 146.844 30.7824C146.844 30.7101 146.84 30.6341 146.824 30.56C146.811 30.5075 146.892 30.4913 146.9 30.5473C146.916 30.6124 146.92 30.6811 146.923 30.7481C146.968 30.7282 147.015 30.7083 147.057 30.683C147.061 30.6142 147.07 30.5546 147.05 30.4895C147.037 30.4334 147.115 30.4135 147.126 30.4696C147.142 30.5292 147.142 30.5871 147.142 30.6341C147.182 30.6052 147.214 30.5528 147.207 30.5057C147.203 30.4931 147.2 30.4822 147.194 30.4659C147.171 30.4135 147.243 30.381 147.263 30.4334C147.263 30.4334 147.264 30.4358 147.267 30.4406C147.283 30.4008 147.296 30.3593 147.29 30.3195C147.287 30.182 147.129 30.0699 147.012 30.0211C146.674 29.8764 146.529 30.1422 146.267 30.2544C146.05 30.3466 145.795 30.4027 145.562 30.3954C145.595 30.4678 145.647 30.5329 145.71 30.5889L145.734 30.5564C145.766 30.5075 145.83 30.5564 145.799 30.6016L145.77 30.6377C145.79 30.654 145.806 30.6667 145.826 30.6775C145.842 30.6613 145.85 30.6377 145.855 30.6124C145.868 30.56 145.944 30.5763 145.931 30.6287C145.927 30.6613 145.915 30.6938 145.895 30.7209C145.924 30.7372 145.951 30.7535 145.983 30.7661C146 30.7336 146.012 30.701 146.016 30.6649C146.023 30.6088 146.104 30.6197 146.092 30.6775C146.088 30.7227 146.072 30.7625 146.056 30.7987C146.101 30.8186 146.144 30.8349 146.184 30.8475C146.2 30.7987 146.207 30.7553 146.204 30.7101C146.2 30.654 146.28 30.6504 146.285 30.7028C146.285 30.7553 146.282 30.8077 146.265 30.8602L146.267 30.862Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_24\" d=\"M145.569 30.3195C145.674 30.3231 145.779 30.3123 145.864 30.296C146.061 30.2634 146.424 30.1585 146.529 29.965C146.574 29.8891 146.542 29.7589 146.457 29.7281C146.264 29.6522 146.001 29.5998 145.788 29.6233C145.712 29.6305 145.644 29.6594 145.571 29.6721V30.3213L145.569 30.3195ZM145.569 29.5889C145.642 29.5726 145.71 29.5292 145.754 29.4605C145.855 29.3122 145.947 29.1621 146.036 29.0175C146.124 28.8728 146.213 28.7281 146.298 28.5816C146.383 28.4279 146.394 28.2109 146.233 28.1096C146.226 28.106 146.22 28.1024 146.213 28.1024C146.157 28.0735 145.971 28.0735 146.003 28.1784C146.023 28.2507 146.108 28.2905 146.124 28.3755C146.132 28.4279 146.121 28.4804 146.085 28.5654C145.989 28.7751 145.871 28.9759 145.747 29.1694C145.714 29.2182 145.651 29.173 145.682 29.1241C145.806 28.9343 145.918 28.7408 146.012 28.531C146.041 28.4623 146.052 28.4225 146.045 28.3899C146.038 28.3411 145.976 28.2724 145.936 28.2416C145.828 28.1657 145.691 28.1928 145.569 28.2579V28.6937C145.598 28.6449 145.625 28.6015 145.654 28.5563C145.683 28.5075 145.75 28.5491 145.719 28.5961C145.683 28.6558 145.647 28.7173 145.611 28.7769C145.595 28.7968 145.582 28.8131 145.571 28.833V29.5871L145.569 29.5889ZM145.336 28.4333C145.074 28.6919 144.913 29.0464 144.913 29.4406C144.913 29.6829 144.973 29.9126 145.083 30.1097C145.179 30.2671 145.378 30.3159 145.571 30.3195V29.6703C145.548 29.6739 145.522 29.6775 145.499 29.6775C145.371 29.6847 145.237 29.6323 145.145 29.5437C145.105 29.5039 145.157 29.4478 145.197 29.4876C145.278 29.5636 145.391 29.6052 145.495 29.5998C145.524 29.5998 145.548 29.5961 145.571 29.5871V28.833C145.542 28.8728 145.515 28.9144 145.486 28.9542C145.45 29.003 145.385 28.9542 145.421 28.9089C145.461 28.8493 145.506 28.7914 145.542 28.7317C145.55 28.7191 145.562 28.7028 145.571 28.6919V28.2561C145.479 28.3049 145.394 28.3737 145.338 28.4297L145.336 28.4333Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_25\" d=\"M144.848 29.6612C144.836 29.5889 144.832 29.5129 144.832 29.4388C144.832 29.0844 144.957 28.757 145.166 28.5002C145.13 28.5292 145.085 28.5527 145.038 28.569C144.93 28.6087 144.801 28.654 144.668 28.6974C144.342 28.8059 143.975 28.927 143.802 29.0645C143.648 29.1856 143.569 29.3375 143.552 29.4912C143.545 29.5636 143.549 29.6323 143.569 29.701C143.585 29.7697 143.617 29.8294 143.661 29.8855C143.802 30.0627 144.113 30.1513 144.225 29.8927C144.205 29.8602 144.192 29.824 144.185 29.7878C144.178 29.7354 144.185 29.6829 144.205 29.6395C144.221 29.5997 144.245 29.5636 144.277 29.531C144.317 29.4949 144.366 29.4659 144.418 29.4497C144.478 29.437 144.539 29.437 144.602 29.4533C144.662 29.4695 144.724 29.5021 144.776 29.5545C144.805 29.5835 144.828 29.6196 144.848 29.6594V29.6612Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_26\" d=\"M146.356 27.9342C146.674 27.9342 146.999 28.0391 147.306 28.1241C147.205 27.9668 146.871 27.6847 146.674 27.6937C146.569 27.6937 146.461 27.6973 146.356 27.6973C146.26 27.6973 146.159 27.6973 146.061 27.6937C145.916 27.6901 145.803 27.8709 145.949 27.9921C146.077 27.9559 146.215 27.936 146.356 27.936V27.9342Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_27\" d=\"M142.959 29.5292C142.983 29.3646 143.048 29.1947 143.14 29.0409C143.301 28.7823 143.547 28.5617 143.849 28.4243C143.977 28.3682 144.102 28.323 144.223 28.276C144.445 28.191 144.658 28.106 144.888 27.974C144.904 27.9668 144.921 27.9577 144.937 27.9505C144.96 27.898 144.966 27.8492 144.949 27.8022C144.865 27.8058 144.796 27.8148 144.74 27.8221C144.606 27.8384 144.555 27.8347 144.543 27.6883C144.539 27.6557 144.539 27.6159 144.536 27.5635C144.48 27.587 144.427 27.6087 144.387 27.6286C144.335 27.6575 144.292 27.6846 144.254 27.7136C144.246 27.7208 144.225 27.7208 144.214 27.7172C144.093 27.6648 143.961 27.6159 143.827 27.5924C143.699 27.5635 143.565 27.5562 143.437 27.5725C143.404 27.5798 143.381 27.54 143.4 27.5128C143.429 27.4676 143.46 27.4242 143.496 27.379C143.509 27.3627 143.52 27.3465 143.536 27.3302C143.513 27.3338 143.487 27.3374 143.464 27.3465C143.404 27.3591 143.352 27.3754 143.294 27.3953C143.261 27.4025 143.234 27.3664 143.249 27.3392L143.334 27.1855C143.261 27.1891 143.189 27.2018 143.12 27.2181C143.032 27.2344 142.94 27.2633 142.851 27.2995C142.822 27.3121 142.786 27.2759 142.802 27.247L142.903 27.0137L142.896 27.0101C142.788 27.03 142.679 27.0553 142.571 27.0788C142.542 27.0824 142.518 27.0553 142.526 27.0264L142.574 26.8691C142.562 26.8618 142.551 26.8564 142.538 26.8492C142.433 26.9179 142.338 26.9613 142.249 26.9866C142.168 27.0029 142.092 27.0029 142.032 26.9739C141.967 26.945 141.92 26.8889 141.891 26.804C141.868 26.7316 141.859 26.6303 141.871 26.502C141.868 26.502 141.864 26.4983 141.859 26.4983L141.738 26.5996C141.714 26.6195 141.673 26.5996 141.673 26.5707L141.66 26.3808C141.66 26.3808 141.644 26.3681 141.636 26.3645C141.613 26.3844 141.584 26.4097 141.555 26.4332C141.548 26.4405 141.539 26.4459 141.535 26.4495C141.515 26.4694 141.476 26.4531 141.47 26.426C141.466 26.3736 141.466 26.3247 141.47 26.2813C141.43 26.3103 141.389 26.3338 141.342 26.35C141.318 26.3573 141.289 26.3428 141.289 26.3175C141.286 26.2578 141.282 26.1963 141.286 26.1403C141.273 26.1276 141.257 26.1204 141.246 26.1113C141.197 26.1348 141.15 26.1511 141.101 26.1511C141.045 26.1547 140.989 26.1439 140.94 26.115C140.892 26.086 140.852 26.0499 140.823 25.9974C140.787 25.9323 140.767 25.8564 140.778 25.7641C140.588 25.6158 140.407 25.4621 140.23 25.3012C140.223 25.3464 140.21 25.3862 140.194 25.4296C140.138 25.614 140.057 25.7677 139.952 25.9287C139.863 26.0571 139.791 26.1819 139.735 26.3283C139.686 26.4459 139.598 26.6502 139.643 26.775C139.679 26.8835 139.813 26.8871 139.896 26.8401C139.932 26.7443 139.972 26.6502 140.008 26.558C140.057 26.4495 140.1 26.3482 140.145 26.256C140.169 26.2036 140.237 26.2397 140.214 26.2886C140.169 26.3844 140.125 26.4857 140.08 26.5869C140.04 26.6918 139.995 26.7967 139.955 26.898C139.936 26.9541 139.943 27.0716 139.972 27.124C139.995 27.1801 140.044 27.2054 140.105 27.1928C140.174 27.1765 140.23 27.1367 140.254 27.0752C140.286 26.9902 140.319 26.9106 140.355 26.8329C140.387 26.7479 140.424 26.6629 140.463 26.5743C140.483 26.5218 140.555 26.5544 140.536 26.6068C140.499 26.6882 140.463 26.7714 140.427 26.86C140.391 26.9486 140.355 27.0372 140.319 27.1258C140.286 27.1982 140.274 27.2904 140.29 27.3718C140.302 27.4369 140.339 27.493 140.395 27.5327C140.46 27.5725 140.552 27.4966 140.572 27.4405C140.592 27.3844 140.608 27.3284 140.628 27.2705L140.668 27.1494C140.687 27.0969 140.763 27.1204 140.743 27.1729L140.698 27.2976C140.682 27.3501 140.662 27.4061 140.642 27.4622C140.613 27.5472 140.606 27.6358 140.619 27.7208C140.635 27.7968 140.668 27.8745 140.724 27.9342C140.763 27.983 140.8 28.0264 140.861 27.9993C140.901 27.983 140.937 27.9469 140.95 27.9107C140.998 27.7769 141.045 27.6376 141.091 27.5002C141.119 27.4188 141.143 27.3429 141.163 27.294C141.179 27.2416 141.255 27.2651 141.235 27.3175C141.206 27.4025 141.186 27.4622 141.166 27.5237C141.118 27.6611 141.074 27.7931 141.025 27.9342C140.993 28.0228 140.993 28.1042 141.013 28.1566C141.036 28.2163 141.085 28.2452 141.147 28.2416C141.228 28.2344 141.307 28.1693 141.316 28.0879C141.324 28.012 141.336 27.9179 141.356 27.8185C141.38 27.6973 141.412 27.5599 141.448 27.4116C141.465 27.3591 141.541 27.379 141.524 27.4315C141.488 27.5761 141.456 27.7136 141.432 27.8347C141.412 27.9469 141.396 28.0481 141.392 28.1331C141.389 28.1928 141.396 28.2344 141.416 28.2543C141.436 28.2832 141.468 28.2868 141.501 28.2742C141.566 28.2543 141.602 28.1892 141.635 28.1295C141.683 28.0373 141.723 27.9324 141.756 27.8185C141.792 27.681 141.824 27.5364 141.848 27.3718C141.855 27.3193 141.933 27.332 141.924 27.3844C141.9 27.5544 141.868 27.7027 141.832 27.8402C141.795 27.9613 141.756 28.0698 141.703 28.1657C141.644 28.2832 141.667 28.5292 141.844 28.3881C141.962 28.2995 142.09 28.0698 142.166 27.9324C142.186 27.8926 142.206 27.8601 142.218 27.8438C142.247 27.795 142.314 27.8365 142.283 27.8836C142.271 27.9035 142.255 27.9324 142.235 27.9722C142.166 28.0897 142.065 28.2742 141.949 28.3917C141.877 28.4731 141.765 28.6087 141.788 28.7227C141.801 28.7787 141.844 28.8113 141.9 28.8113C142.005 28.8149 142.081 28.7154 142.133 28.634C142.206 28.5129 142.287 28.4044 142.367 28.2959C142.455 28.1783 142.544 28.0662 142.632 27.9577C142.668 27.9179 142.728 27.9649 142.692 28.0102C142.6 28.1187 142.511 28.2326 142.43 28.3447C142.349 28.446 142.273 28.5545 142.2 28.6702C142.151 28.7426 142.072 28.8077 142.047 28.8872C142.023 28.9596 142.027 29.0156 142.047 29.0572C142.063 29.0934 142.099 29.1133 142.139 29.1097C142.208 29.1024 142.273 29.0373 142.309 28.9849C142.421 28.8239 142.538 28.6702 142.663 28.5183C142.784 28.37 142.916 28.2235 143.05 28.0825C143.09 28.0427 143.146 28.0988 143.106 28.1386C142.972 28.276 142.844 28.4207 142.723 28.5689C142.598 28.7136 142.486 28.8709 142.372 29.0283C142.339 29.0807 142.3 29.1169 142.264 29.1404C142.215 29.2525 142.231 29.3827 142.28 29.4623C142.3 29.4858 142.32 29.5075 142.339 29.522C142.457 29.5816 142.549 29.3737 142.576 29.2995C142.649 29.1223 142.746 28.9686 142.858 28.8366C142.976 28.7082 143.108 28.5943 143.252 28.4948C143.269 28.4821 143.285 28.4713 143.308 28.502C143.328 28.5346 143.312 28.5472 143.296 28.5581C143.158 28.6539 143.026 28.7643 142.918 28.889C142.809 29.0174 142.717 29.1585 142.652 29.3285C142.612 29.4334 142.508 29.5346 142.616 29.6395C142.636 29.6594 142.665 29.6757 142.692 29.6847C142.721 29.6974 142.752 29.6974 142.784 29.692C142.849 29.6847 142.912 29.6359 142.954 29.531L142.959 29.5292Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_28\" d=\"M148.151 28.1386C148.263 28.191 148.377 28.2308 148.489 28.276C148.61 28.3248 148.731 28.3682 148.859 28.4243C149.161 28.5617 149.407 28.7823 149.568 29.0409C149.669 29.2055 149.732 29.3882 149.757 29.5654C149.774 29.7064 149.761 29.8475 149.725 29.9849C149.77 30.0301 149.846 29.9976 149.895 29.965C149.987 29.8999 150.059 29.7516 150.101 29.5943C150.15 29.4099 150.157 29.2073 150.117 29.0952C150.009 28.8095 149.839 28.5798 149.618 28.4098C149.396 28.2362 149.123 28.115 148.805 28.0391C148.749 28.0264 148.769 27.9505 148.821 27.9631C149.152 28.0391 149.437 28.1639 149.667 28.3465C149.9 28.5274 150.077 28.7661 150.191 29.0681C150.211 29.1205 150.22 29.1929 150.224 29.2688C150.224 29.314 150.247 29.3538 150.292 29.3773C150.374 29.4298 150.417 29.305 150.43 29.2435C150.479 28.9777 150.401 28.7281 150.26 28.5219C150.079 28.2489 149.781 28.0427 149.506 27.9505C149.45 27.9342 149.477 27.8583 149.53 27.8781C149.819 27.974 150.13 28.1928 150.327 28.4785C150.484 28.7154 150.569 29.003 150.491 29.3086C150.479 29.3574 150.475 29.39 150.504 29.437C150.517 29.4659 150.544 29.4894 150.576 29.4822C150.721 29.4533 150.75 29.1965 150.761 29.088C150.777 28.9758 150.784 28.8583 150.784 28.7371C150.78 28.5834 150.761 28.4315 150.688 28.3067C150.583 28.1096 150.265 27.9559 150.012 27.8275C149.936 27.7913 149.864 27.7552 149.803 27.719C149.754 27.6955 149.79 27.6232 149.839 27.6503C149.898 27.6865 149.973 27.719 150.048 27.7588C150.311 27.8872 150.641 28.0536 150.761 28.2706C150.836 28.408 150.862 28.5726 150.865 28.7371C150.865 28.8583 150.853 28.9831 150.836 29.1006C150.829 29.1929 150.902 29.2344 150.974 29.173C151.091 29.0771 151.167 28.8909 151.2 28.6974C151.232 28.484 151.216 28.2579 151.144 28.1295C151.059 27.9722 150.938 27.8438 150.789 27.7353C150.641 27.6304 150.464 27.5418 150.271 27.4658C150.218 27.4459 150.247 27.3736 150.3 27.3935C150.497 27.4695 150.683 27.5635 150.835 27.6756C150.996 27.7877 151.124 27.9252 151.218 28.0952C151.274 28.2 151.303 28.3646 151.294 28.5346C151.294 28.5798 151.278 28.6033 151.323 28.6359C151.372 28.672 151.428 28.6919 151.48 28.6431C151.509 28.6142 151.532 28.5708 151.552 28.5219C151.597 28.3935 151.608 28.2199 151.592 28.0988C151.552 27.7642 151.241 27.511 150.88 27.3248C150.542 27.1548 150.175 27.0517 149.897 26.9776H149.893C149.909 27.0264 149.897 27.0698 149.897 27.1222C149.893 27.1457 149.864 27.1675 149.841 27.1548C149.781 27.1259 149.732 27.0987 149.683 27.0698C149.707 27.1222 149.723 27.1783 149.736 27.247C149.739 27.276 149.716 27.2995 149.687 27.2922C149.606 27.276 149.526 27.2524 149.45 27.2271C149.434 27.2235 149.385 27.191 149.369 27.1873C149.414 27.2326 149.49 27.2995 149.546 27.3519C149.569 27.3754 149.539 27.4279 149.506 27.417C149.378 27.3718 149.28 27.3212 149.168 27.2597C149.213 27.3447 149.277 27.4369 149.338 27.5129C149.358 27.5454 149.315 27.5942 149.282 27.5689C149.165 27.493 149.053 27.408 148.944 27.3194C148.928 27.323 148.912 27.332 148.895 27.3356C148.919 27.4007 148.948 27.464 148.977 27.5255C148.993 27.5617 148.937 27.5978 148.912 27.5707C148.859 27.5056 148.807 27.4423 148.763 27.3736C148.687 27.3935 148.61 27.4134 148.534 27.4333C148.606 27.5092 148.682 27.5816 148.76 27.6503C148.805 27.6865 148.752 27.7461 148.707 27.71C148.615 27.6286 148.53 27.5454 148.449 27.4514C148.389 27.4676 148.328 27.4803 148.272 27.4912L148.485 27.7244C148.521 27.7642 148.465 27.8167 148.425 27.7769L148.179 27.511C148.098 27.5273 148.015 27.5436 147.93 27.5599C147.963 27.5834 147.995 27.6123 148.031 27.6358C148.113 27.6955 148.192 27.7534 148.281 27.8094C148.33 27.8384 148.284 27.9053 148.236 27.8781C148.147 27.8221 148.062 27.7606 147.982 27.7009C147.93 27.6611 147.878 27.6195 147.829 27.5761C147.769 27.5888 147.704 27.596 147.644 27.6051C147.697 27.7009 147.753 27.7859 147.822 27.8637C147.91 27.965 148.006 28.0481 148.12 28.1169C148.132 28.1241 148.143 28.1331 148.156 28.1404L148.151 28.1386Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_29\" d=\"M150.455 27.0553C150.609 27.1114 150.766 27.1765 150.914 27.2525C151.297 27.446 151.623 27.719 151.672 28.0861C151.675 28.1386 151.679 28.1983 151.675 28.2634C151.735 28.3122 151.751 28.3321 151.82 28.267C151.912 28.1747 151.993 28.0138 151.964 27.8764C151.928 27.7154 151.863 27.5617 151.747 27.4243C151.63 27.2904 151.465 27.1711 151.24 27.0698C151.127 27.0174 151.014 26.945 150.905 26.8727C150.846 26.8329 150.784 26.7967 150.724 26.7515C150.665 26.7063 150.623 26.6792 150.544 26.6792C150.504 26.6792 150.488 26.6919 150.495 26.7316C150.508 26.7714 150.544 26.8203 150.564 26.86C150.511 26.86 150.471 26.8564 150.419 26.8401C150.354 26.8239 150.291 26.804 150.278 26.8438C150.249 26.9089 150.39 27.0336 150.455 27.0535V27.0553Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_30\" d=\"M152.243 25.9757C152.338 26.0517 152.427 26.1529 152.508 26.2614C152.604 26.3953 152.689 26.5309 152.738 26.6394C152.751 26.6629 152.761 26.6918 152.774 26.7244C152.863 26.7479 152.855 26.7316 152.855 26.6521C152.855 26.6394 152.855 26.6231 152.859 26.6069C152.863 26.5056 152.852 26.3736 152.823 26.2434C152.79 26.1059 152.742 25.9739 152.669 25.869C152.601 25.7732 152.508 25.7081 152.391 25.699C152.358 25.699 152.326 25.7027 152.29 25.7117C152.244 25.7189 152.205 25.7442 152.188 25.7876C152.165 25.8437 152.196 25.9359 152.241 25.9721L152.243 25.9757Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_31\" d=\"M151.993 26.3699C152.167 26.5508 152.344 26.737 152.496 26.9631C152.541 27.0318 152.588 27.1277 152.608 27.2253C152.66 27.2452 152.729 27.2651 152.756 27.2018C152.769 27.1692 152.772 27.1258 152.772 27.077C152.765 26.9396 152.707 26.7714 152.664 26.6774C152.615 26.5689 152.539 26.435 152.442 26.3103C152.369 26.2054 152.281 26.1095 152.192 26.0408C152.14 25.9956 152.075 25.9721 152.015 25.9757C151.963 25.9829 151.91 26.0083 151.867 26.0643C151.843 26.0933 151.831 26.124 151.834 26.1565C151.838 26.2325 151.943 26.3211 151.991 26.3699H151.993Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_32\" d=\"M151.643 26.6611C151.711 26.7262 151.78 26.7895 151.852 26.851C151.977 26.9595 152.085 27.077 152.17 27.2181C152.216 27.2995 152.252 27.3827 152.275 27.4803C152.282 27.5201 152.292 27.5563 152.351 27.5653C152.476 27.5725 152.548 27.4279 152.545 27.3194C152.541 27.2109 152.485 27.0897 152.427 27.0083C152.279 26.7859 152.105 26.605 151.935 26.4278C151.899 26.388 151.86 26.3519 151.843 26.332C151.807 26.2922 151.751 26.256 151.695 26.2434C151.655 26.2361 151.614 26.2397 151.578 26.2723C151.538 26.3085 151.476 26.3446 151.473 26.4097C151.456 26.5381 151.554 26.5833 151.643 26.6629V26.6611Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_33\" d=\"M151.272 26.9993C151.509 27.1042 151.682 27.2326 151.807 27.3772C151.932 27.5219 152.004 27.6883 152.04 27.8601C152.044 27.8836 152.048 27.9125 152.048 27.936H152.08C152.116 27.936 152.145 27.9234 152.169 27.9071C152.192 27.8872 152.208 27.8583 152.221 27.8185C152.225 27.7896 152.228 27.7624 152.228 27.7263C152.221 27.5418 152.172 27.3845 152.1 27.2543C152.024 27.1204 151.919 27.0083 151.798 26.9071C151.726 26.8474 151.657 26.7787 151.585 26.7136C151.516 26.6485 151.447 26.5797 151.372 26.5164C151.312 26.4676 151.227 26.4206 151.158 26.4079C151.129 26.4043 151.086 26.3953 151.073 26.4315C151.061 26.4767 151.09 26.5526 151.097 26.6014C151.028 26.5852 150.864 26.4893 150.887 26.634C150.916 26.8148 151.12 26.9288 151.27 26.9975L151.272 26.9993Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_34\" d=\"M137.608 16.2972C137.382 15.5069 137.056 14.8016 136.738 14.1054C136.65 13.9155 136.557 13.7311 136.637 13.5177C136.677 13.4128 136.765 13.4218 136.854 13.4526C136.979 13.6425 137.1 13.8468 137.212 14.0656C137.329 14.2917 137.438 14.5286 137.53 14.7745C137.55 14.827 137.622 14.798 137.602 14.7456C137.51 14.496 137.396 14.2537 137.28 14.0276C137.163 13.8016 137.038 13.5918 136.91 13.3983C136.834 13.2772 136.801 13.1488 136.841 13.0077C136.861 12.9354 136.91 12.8667 136.989 12.854C137.006 12.8865 137.025 12.9191 137.045 12.9462C137.174 13.1108 137.291 13.2808 137.409 13.449C137.521 13.6226 137.631 13.7962 137.73 13.977C137.759 14.0258 137.832 13.9897 137.799 13.9372C137.698 13.7564 137.589 13.5792 137.474 13.4056C137.356 13.232 137.237 13.0638 137.11 12.8974C137.062 12.8323 137.025 12.76 137.022 12.684C137.015 12.5267 137.195 12.3133 137.317 12.4833C137.465 12.693 137.615 12.9137 137.759 13.1361C137.917 13.3784 138.07 13.6244 138.218 13.8775C138.247 13.9264 138.314 13.8848 138.287 13.8378C138.133 13.5846 137.982 13.335 137.824 13.0963C137.671 12.8594 137.519 12.6298 137.362 12.4109C137.333 12.3712 137.313 12.3296 137.317 12.2735C137.317 12.241 137.324 12.2138 137.34 12.1885C137.389 12.1198 137.488 12.1035 137.541 12.1686C137.711 12.3693 137.855 12.5719 137.996 12.7726C138.141 12.9824 138.278 13.1994 138.423 13.4218C138.452 13.4707 138.518 13.4254 138.488 13.382C138.343 13.156 138.206 12.9426 138.061 12.7292C137.913 12.5122 137.756 12.3024 137.579 12.089C137.533 12.033 137.546 11.9552 137.571 11.8992C137.584 11.8829 137.595 11.8666 137.604 11.854C137.68 11.769 137.748 11.7617 137.817 11.8413C138.083 12.1144 138.381 12.429 138.659 12.8884C138.688 12.9372 138.755 12.8956 138.725 12.8486C138.443 12.382 138.141 12.0673 137.875 11.7852C137.819 11.7292 137.767 11.693 137.779 11.6044C137.786 11.5393 137.819 11.4869 137.864 11.4471C137.953 11.3747 137.993 11.3621 138.074 11.4471C138.211 11.5881 138.343 11.7527 138.477 11.9353C138.611 12.1198 138.743 12.3187 138.88 12.5285C138.887 12.5448 138.9 12.561 138.932 12.5411C138.965 12.5213 138.956 12.505 138.945 12.4851C138.811 12.2753 138.676 12.0746 138.542 11.8919C138.405 11.7075 138.269 11.5375 138.132 11.3964C138.063 11.3241 138.023 11.268 138.079 11.1704C138.184 11.0058 138.273 11.1107 138.365 11.2156C138.502 11.3693 138.634 11.5266 138.764 11.6948C138.893 11.8684 139.017 12.0493 139.138 12.2428C139.151 12.259 139.158 12.2753 139.194 12.2554C139.227 12.2355 139.214 12.2192 139.207 12.203C139.082 12.0059 138.958 11.8196 138.829 11.6514C138.696 11.4778 138.564 11.3169 138.426 11.1631C138.361 11.0908 138.33 11.0384 138.325 10.9932C138.318 10.957 138.338 10.9208 138.37 10.8847C138.446 10.7997 138.62 10.6224 138.708 10.8196C138.793 11.004 138.914 11.1505 139.055 11.259C139.213 11.3802 139.393 11.4597 139.583 11.5013C140.035 11.5972 140.494 11.4055 140.852 11.1469C141.219 10.881 141.58 10.5067 141.806 10.0799C141.996 9.7092 142.095 9.2788 141.991 8.86649C142.672 9.1486 143.303 9.28965 143.912 9.30593C144.368 9.31858 144.899 9.2571 145.362 9.10881C145.978 8.9117 146.743 8.9117 147.359 9.10881C147.822 9.2571 148.358 9.31858 148.808 9.30593C149.416 9.28965 150.048 9.1486 150.73 8.86649C150.625 9.27699 150.726 9.7092 150.92 10.0799C151.142 10.5067 151.503 10.881 151.87 11.1469C152.228 11.4055 152.687 11.599 153.139 11.5013C153.329 11.4615 153.51 11.3802 153.667 11.259C153.808 11.1505 153.929 11.0058 154.014 10.8196C154.103 10.6224 154.276 10.7997 154.352 10.8847C154.385 10.9208 154.404 10.957 154.397 10.9932C154.394 11.0384 154.361 11.089 154.296 11.1631C154.159 11.3169 154.027 11.4778 153.893 11.6514C153.765 11.8214 153.64 12.0059 153.515 12.203C153.508 12.2192 153.495 12.2355 153.528 12.2554C153.564 12.2753 153.573 12.259 153.584 12.2428C153.705 12.0493 153.83 11.8684 153.958 11.6948C154.086 11.5248 154.22 11.3693 154.357 11.2156C154.45 11.1107 154.538 11.0058 154.643 11.1704C154.699 11.2662 154.659 11.3241 154.591 11.3964C154.453 11.5375 154.318 11.7075 154.18 11.8919C154.047 12.0728 153.915 12.2753 153.777 12.4851C153.765 12.505 153.757 12.5213 153.79 12.5411C153.822 12.561 153.835 12.5448 153.842 12.5285C153.98 12.3187 154.112 12.1216 154.245 11.9353C154.379 11.7545 154.511 11.5881 154.648 11.4471C154.73 11.3621 154.77 11.3747 154.858 11.4471C154.903 11.4869 154.934 11.5393 154.943 11.6044C154.956 11.693 154.903 11.7292 154.847 11.7852C154.582 12.0673 154.28 12.382 153.998 12.8486C153.965 12.8974 154.034 12.9372 154.063 12.8884C154.341 12.429 154.639 12.1144 154.905 11.8413C154.974 11.7599 155.043 11.769 155.118 11.854C155.126 11.8666 155.138 11.8829 155.151 11.8992C155.174 11.9552 155.187 12.033 155.144 12.089C154.967 12.3024 154.809 12.5122 154.661 12.7292C154.517 12.9426 154.379 13.156 154.235 13.382C154.202 13.4273 154.271 13.4707 154.3 13.4218C154.444 13.1994 154.582 12.9824 154.726 12.7726C154.867 12.5719 155.012 12.3693 155.182 12.1686C155.234 12.1035 155.335 12.1198 155.382 12.1885C155.399 12.212 155.406 12.241 155.406 12.2735C155.409 12.3296 155.39 12.3693 155.361 12.4109C155.203 12.6279 155.05 12.8576 154.898 13.0963C154.741 13.3332 154.587 13.5846 154.435 13.8378C154.406 13.8866 154.475 13.9264 154.504 13.8775C154.652 13.6244 154.806 13.3784 154.963 13.1361C155.108 12.9137 155.258 12.693 155.406 12.4833C155.527 12.3133 155.708 12.5285 155.7 12.684C155.697 12.76 155.664 12.8323 155.612 12.8974C155.487 13.062 155.366 13.232 155.249 13.4056C155.136 13.5792 155.023 13.7564 154.923 13.9372C154.891 13.9897 154.963 14.0258 154.992 13.977C155.093 13.7962 155.202 13.6226 155.314 13.449C155.431 13.279 155.547 13.1108 155.677 12.9462C155.697 12.9173 155.717 12.8865 155.733 12.854C155.814 12.8667 155.861 12.9354 155.881 13.0077C155.921 13.1488 155.888 13.2772 155.812 13.3983C155.684 13.5918 155.559 13.8016 155.442 14.0276C155.324 14.2537 155.212 14.4942 155.12 14.7456C155.1 14.798 155.173 14.827 155.193 14.7745C155.285 14.5286 155.393 14.2917 155.511 14.0656C155.623 13.8486 155.744 13.6425 155.869 13.4526C155.957 13.42 156.046 13.4128 156.085 13.5177C156.167 13.7311 156.073 13.9173 155.984 14.1054C155.666 14.8016 155.341 15.5069 155.115 16.2972C154.079 12.4381 150.544 9.5808 146.368 9.5808C142.193 9.5808 138.658 12.4381 137.622 16.2972H137.608Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_35\" d=\"M153.519 10.23C153.526 10.3421 153.62 10.3548 153.709 10.3512C153.725 10.4796 153.725 10.6007 153.676 10.7219C153.58 10.9841 153.338 11.136 153.069 11.1686C152.899 11.1921 152.714 11.1722 152.545 11.1197C152.279 11.0384 152.017 10.8611 151.796 10.6369C151.554 10.4 151.361 10.1016 151.252 9.82313C151.171 9.61697 151.131 9.40358 151.144 9.18295C151.16 8.98946 151.216 8.79234 151.334 8.60246C151.409 8.47768 151.534 8.47406 151.652 8.46864C151.744 8.46502 151.829 8.4614 151.858 8.38726C151.881 8.3312 151.865 8.26971 151.829 8.22631C151.78 8.16121 151.7 8.12504 151.619 8.12143C151.229 8.10877 150.93 8.4596 150.826 8.80319C150.701 9.20285 150.786 9.66941 150.983 10.0437C151.2 10.4579 151.554 10.825 151.908 11.0836C152.246 11.3295 152.689 11.5194 153.116 11.4254C153.293 11.3856 153.466 11.3132 153.611 11.1993C153.745 11.0944 153.857 10.9624 153.933 10.7888C153.992 10.6604 154.018 10.494 153.992 10.353C153.98 10.2933 153.963 10.2354 153.933 10.192C153.884 10.1034 153.756 10.022 153.651 10.0474C153.566 10.0673 153.51 10.1432 153.517 10.2282L153.519 10.23Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_36\" d=\"M150.797 8.65854C150.865 8.50121 150.967 8.35654 151.095 8.24442C150.036 8.6513 148.631 8.8882 147.165 8.95331C147.693 9.15042 148.232 9.24807 148.805 9.2318C149.372 9.21552 149.972 9.08713 150.609 8.82853C150.69 8.79598 150.762 8.74353 150.799 8.65854H150.797Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_37\" d=\"M139.191 10.23C139.184 10.3421 139.09 10.3548 139.001 10.3512C138.985 10.4796 138.988 10.6007 139.034 10.7219C139.129 10.9841 139.372 11.136 139.641 11.1686C139.811 11.1921 139.995 11.1722 140.165 11.1197C140.431 11.0384 140.693 10.8611 140.913 10.6369C141.156 10.4 141.353 10.1016 141.457 9.82313C141.539 9.61697 141.579 9.40358 141.566 9.18295C141.55 8.98946 141.494 8.79234 141.376 8.60246C141.3 8.47768 141.175 8.47406 141.058 8.46864C140.966 8.46502 140.881 8.4614 140.852 8.38726C140.828 8.3312 140.845 8.26971 140.881 8.22631C140.93 8.16121 141.015 8.12504 141.091 8.12143C141.481 8.10877 141.779 8.4596 141.884 8.80319C142.012 9.20285 141.924 9.66941 141.727 10.0437C141.51 10.4579 141.156 10.825 140.801 11.0836C140.463 11.3295 140.02 11.5194 139.594 11.4254C139.417 11.3856 139.243 11.3132 139.099 11.1993C138.965 11.0944 138.853 10.9624 138.777 10.7888C138.717 10.6604 138.692 10.494 138.717 10.353C138.73 10.2933 138.746 10.2354 138.777 10.192C138.826 10.1034 138.954 10.022 139.059 10.0474C139.144 10.0673 139.2 10.1432 139.193 10.2282L139.191 10.23Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_38\" d=\"M144.534 9.14319C144.353 9.22456 143.986 9.23903 143.905 9.2318C143.337 9.21552 142.737 9.08713 142.101 8.82853H142.097C142.016 8.79598 141.949 8.73991 141.913 8.65854C141.844 8.50121 141.743 8.35654 141.615 8.24442C142.399 8.54642 143.382 8.75619 144.434 8.86831C144.588 8.88459 144.733 9.05819 144.536 9.14138L144.534 9.14319Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_39\" d=\"M138.191 25.6737C138.296 25.6972 138.401 25.7298 138.502 25.7659C138.791 25.8835 139.063 26.0643 139.348 26.3067C139.256 26.1891 139.164 26.077 139.066 25.9685C138.905 25.784 138.732 25.6014 138.567 25.4242C138.547 25.4043 138.531 25.3844 138.515 25.3645C138.426 25.3482 138.345 25.3157 138.262 25.2759C138.177 25.2307 138.092 25.18 138.003 25.1185C137.958 25.086 138.003 25.0227 138.049 25.0534C138.133 25.1095 138.213 25.1619 138.298 25.2017C138.338 25.2216 138.379 25.2415 138.423 25.2542C138.387 25.218 138.358 25.1782 138.327 25.142C138.255 25.0462 138.189 24.9576 138.13 24.8636C138.097 24.8183 138.162 24.7749 138.195 24.8183C138.255 24.907 138.32 24.9992 138.392 25.0914C138.464 25.1836 138.546 25.2759 138.625 25.3645C138.79 25.5417 138.956 25.7189 139.124 25.9124C139.232 26.0372 139.341 26.162 139.442 26.2958C139.361 26.0951 139.301 25.8817 139.252 25.6556C139.207 25.5272 139.135 25.3898 139.046 25.2524C138.777 24.8256 138.491 24.4747 138.043 24.2415C137.79 24.104 137.495 24.0154 137.148 23.9792C137.26 24.1167 137.362 24.265 137.45 24.4259C137.555 24.6158 137.64 24.8165 137.696 25.0137C137.736 25.1674 137.797 25.2994 137.877 25.4133C137.958 25.5218 138.061 25.6104 138.191 25.6719V25.6737Z\" fill=\"#00844B\"><\/path><path id=\"Vector_40\" d=\"M136.747 14.3116C136.763 14.3514 136.783 14.393 136.803 14.4327C136.771 14.4327 136.738 14.4364 136.702 14.4526C136.725 14.4038 136.738 14.3604 136.747 14.3116Z\" fill=\"#00844B\"><\/path><path id=\"Vector_41\" d=\"M136.977 14.8197C137.089 15.0783 137.199 15.3387 137.298 15.61C137.174 15.695 137.049 15.7872 136.928 15.9048V15.6426C137 15.61 137.04 15.5901 137.04 15.4527C137.04 15.4075 137.033 15.3677 137.011 15.3478C136.982 15.384 136.959 15.4165 136.926 15.4436V14.8885C136.942 14.8686 136.959 14.8432 136.975 14.8197H136.977ZM136.928 15.903C136.883 15.9482 136.836 15.9952 136.79 16.044C136.689 16.1616 136.59 16.2936 136.505 16.4545C136.537 16.2936 136.586 16.129 136.642 15.9753C136.662 15.9192 136.586 15.8939 136.566 15.9464C136.518 16.0874 136.474 16.2285 136.442 16.3768C136.434 16.1435 136.406 15.9102 136.353 15.6805C136.373 15.5955 136.402 15.516 136.445 15.4436C136.485 15.3713 136.537 15.3062 136.606 15.2501C136.744 15.138 136.843 15.0168 136.928 14.8866V15.4418C136.912 15.4491 136.895 15.4617 136.875 15.4708C136.794 15.4997 136.819 15.5991 136.823 15.6932C136.863 15.6697 136.899 15.6534 136.928 15.6407V15.903Z\" fill=\"#00844B\"><\/path><path id=\"Vector_42\" d=\"M137.181 25.7497C137.246 25.8057 137.306 25.8618 137.365 25.9233C137.447 25.9992 137.53 26.0878 137.618 26.1927C137.835 26.455 138.186 26.7533 138.605 26.8329C138.867 26.8817 139.153 26.8492 139.451 26.672C139.444 26.6557 139.431 26.6394 139.422 26.6231C139.419 26.6231 139.41 26.6195 139.406 26.6195C139.205 26.5273 139.023 26.4459 138.838 26.4423H138.826C138.786 26.4423 138.741 26.4459 138.701 26.455C138.616 26.4712 138.544 26.4839 138.479 26.4911C138.414 26.4947 138.358 26.4947 138.309 26.4875C138.289 26.4839 138.269 26.4803 138.276 26.4387C138.284 26.4025 138.305 26.4025 138.321 26.4061C138.367 26.4134 138.414 26.4134 138.475 26.4097C138.528 26.4061 138.587 26.3971 138.656 26.3808C138.611 26.3645 138.567 26.3483 138.522 26.3247C138.426 26.2795 138.321 26.2235 138.208 26.1511C138.191 26.1385 138.175 26.1276 138.195 26.0951C138.218 26.0625 138.235 26.0752 138.251 26.0824C138.359 26.1548 138.461 26.2108 138.556 26.256C138.649 26.3012 138.741 26.332 138.829 26.3609C139.03 26.3645 139.22 26.4495 139.433 26.5454C139.44 26.549 139.449 26.5526 139.457 26.5526L139.476 26.5291C139.122 26.2072 138.808 25.9739 138.462 25.8401C138.052 25.6755 137.609 25.6755 137.174 25.7479L137.181 25.7497Z\" fill=\"#00844B\"><\/path><path id=\"Vector_43\" d=\"M137.065 23.8961C137.255 23.9087 137.429 23.9359 137.589 23.9811C137.521 23.869 137.429 23.7586 137.317 23.6556C137.235 23.5742 137.143 23.4946 137.044 23.4187C136.951 23.4024 136.863 23.3952 136.771 23.406C136.718 23.4132 136.706 23.3373 136.763 23.3301C136.819 23.3228 136.872 23.3174 136.917 23.3228C136.897 23.3065 136.877 23.2903 136.857 23.2776C136.809 23.2414 136.762 23.2053 136.713 23.1727C136.621 23.1528 136.523 23.1167 136.418 23.0715C136.317 23.0262 136.209 22.9756 136.093 22.9105C136.04 22.887 136.077 22.8183 136.129 22.8418C136.246 22.9015 136.351 22.9593 136.451 22.9991C136.48 23.0154 136.51 23.0281 136.539 23.0353C136.516 23.019 136.49 22.9991 136.471 22.9792C136.342 22.878 136.221 22.7785 136.096 22.6682C136.051 22.632 136.104 22.5723 136.145 22.6085C136.274 22.717 136.395 22.8183 136.519 22.9195C136.644 23.0208 136.772 23.1203 136.903 23.2143C137.072 23.3319 137.228 23.4566 137.378 23.5977C137.483 23.699 137.571 23.8039 137.64 23.9033C137.627 23.7424 137.575 23.5814 137.479 23.4205C137.338 23.1781 137.132 22.9738 136.919 22.7911C136.63 22.5416 136.312 22.368 135.964 22.2432C135.663 22.1347 135.341 22.0696 135.007 22.0298L135.01 22.0334C135.18 22.1582 135.341 22.2758 135.476 22.4403C135.719 22.7297 135.972 23.0009 136.237 23.2469C136.5 23.4892 136.778 23.7062 137.071 23.8997L137.065 23.8961Z\" fill=\"#00844B\"><\/path><path id=\"Vector_44\" d=\"M136.727 24.7551C136.682 24.7677 136.662 24.8003 136.682 24.8401C136.711 24.8889 136.778 24.9124 136.827 24.8997C136.872 24.8925 136.892 24.8545 136.872 24.8147C136.848 24.7659 136.78 24.7424 136.727 24.7551Z\" fill=\"#00844B\"><\/path><path id=\"Vector_45\" d=\"M138.466 23.8038C138.437 23.8436 138.443 23.9087 138.479 23.9449C138.511 23.9774 138.56 23.9774 138.587 23.9413C138.652 23.849 138.535 23.7116 138.466 23.8038Z\" fill=\"#00844B\"><\/path><path id=\"Vector_46\" d=\"M136.111 22.2125C136.288 22.2848 136.462 22.3734 136.622 22.4783C136.63 22.3933 136.639 22.3137 136.655 22.236C136.662 22.1835 136.678 22.16 136.662 22.1076C136.617 21.9737 136.57 21.8544 136.514 21.7368C136.458 21.6193 136.393 21.5072 136.321 21.4059C136.288 21.3607 136.349 21.3173 136.386 21.3607C136.458 21.4656 136.527 21.5777 136.586 21.7025C136.635 21.7983 136.675 21.8996 136.715 22.0081C136.791 21.7911 136.863 21.641 136.754 21.4077C136.65 21.1781 136.505 20.961 136.315 20.7874C136.122 20.6138 135.889 20.4854 135.614 20.4095C135.69 20.5505 135.758 20.6916 135.82 20.8399C135.892 21.0171 135.948 21.1979 136.001 21.3951C136.04 21.5651 136.06 21.7531 136.077 21.943C136.089 22.0316 136.096 22.1202 136.109 22.2088L136.111 22.2125Z\" fill=\"#00844B\"><\/path><path id=\"Vector_47\" d=\"M136.702 22.5271C136.79 22.5868 136.879 22.6555 136.964 22.7278C137.016 22.773 137.065 22.8164 137.112 22.8617C137.116 22.7604 137.105 22.6682 137.08 22.5795C137.051 22.471 137.007 22.3662 136.946 22.2613C136.917 22.2124 136.986 22.1727 137.015 22.2251C137.074 22.3336 137.127 22.4421 137.156 22.5596C137.188 22.6772 137.195 22.7965 137.184 22.934C137.286 23.0353 137.374 23.1347 137.447 23.2396C137.459 23.0334 137.443 22.84 137.407 22.6465C137.358 22.4168 137.278 22.1907 137.17 21.9575C137.089 21.7838 136.997 21.6157 136.908 21.4457C136.895 21.6157 136.879 21.7965 136.807 21.9864C136.774 22.0714 136.747 22.16 136.731 22.2522C136.715 22.3408 136.702 22.4294 136.702 22.5271Z\" fill=\"#00844B\"><\/path><path id=\"Vector_48\" d=\"M137.519 23.3445C137.571 23.4295 137.62 23.5217 137.653 23.6176C137.712 23.5579 137.757 23.4639 137.79 23.3391C137.83 23.1908 137.855 23.0009 137.862 22.7875C137.879 22.3354 137.839 21.9177 137.767 21.4981C137.662 21.1835 137.573 20.8616 137.504 20.5306C137.432 20.6319 137.371 20.7531 137.315 20.9014C137.233 21.1148 137.174 21.3842 137.134 21.7025C137.17 21.7748 137.206 21.8472 137.242 21.9249C137.347 22.1546 137.427 22.3716 137.476 22.594C137.483 22.4729 137.492 22.3481 137.499 22.2305C137.512 22.0135 137.519 21.8038 137.523 21.5976C137.523 21.5415 137.604 21.5415 137.604 21.5976C137.6 21.8074 137.591 22.0208 137.575 22.2341C137.568 22.4276 137.551 22.6248 137.535 22.8183C137.519 22.9919 137.535 23.1691 137.519 23.3427V23.3445Z\" fill=\"#00844B\"><\/path><path id=\"Vector_49\" d=\"M135.793 20.3878C135.963 20.4474 136.111 20.5324 136.245 20.6301C136.16 20.4601 136.06 20.2883 135.95 20.1183C135.813 19.9013 135.668 19.6879 135.523 19.4781C135.523 19.4781 135.523 19.4745 135.52 19.4745C135.428 19.442 135.335 19.3931 135.241 19.3371C135.146 19.2774 135.048 19.1996 134.952 19.1147C134.913 19.0785 134.96 19.0188 135.005 19.0586C135.097 19.1345 135.189 19.2069 135.287 19.2684C135.343 19.3045 135.399 19.3371 135.457 19.3606C135.424 19.3118 135.392 19.2593 135.355 19.2123C135.299 19.1309 135.238 19.0514 135.171 18.9754C135.135 18.9356 135.191 18.8832 135.231 18.923C135.299 19.0043 135.364 19.0839 135.42 19.1653C135.626 19.4474 135.831 19.782 136.021 20.0803C136.161 20.3064 136.29 20.5324 136.395 20.7567C136.427 20.7856 136.454 20.8164 136.483 20.8489C136.532 20.7928 136.516 20.6681 136.443 20.4746C136.319 20.1328 136.122 19.7856 135.945 19.4673C135.787 19.1888 135.554 18.9157 135.276 18.677C135.017 18.4546 134.725 18.2701 134.43 18.1454C134.423 18.3298 134.47 18.5161 134.555 18.706C134.647 18.9157 134.781 19.1255 134.932 19.3461C135.037 19.4998 135.166 19.6246 135.296 19.7494C135.48 19.9302 135.666 20.1165 135.791 20.3823C135.791 20.386 135.795 20.386 135.795 20.3896L135.793 20.3878Z\" fill=\"#00844B\"><\/path><path id=\"Vector_50\" d=\"M136.915 20.6409C136.843 20.6373 136.798 20.6645 136.781 20.7006C136.733 20.7929 136.827 20.8905 136.919 20.8905C136.971 20.8941 137.007 20.8616 137.024 20.8218C137.04 20.7892 137.04 20.7495 137.027 20.7169C137.015 20.6771 136.975 20.6409 136.915 20.6409Z\" fill=\"#00844B\"><\/path><path id=\"Vector_51\" d=\"M135.469 21.5958C135.493 21.5072 135.498 21.4258 135.482 21.3661C135.466 21.2974 135.426 21.254 135.373 21.2377C135.357 21.2305 135.337 21.2305 135.317 21.2305C135.285 21.2341 135.258 21.2432 135.232 21.2631C135.209 21.2793 135.187 21.3028 135.18 21.3282C135.176 21.3444 135.176 21.3571 135.176 21.3734C135.18 21.4421 135.222 21.5018 135.278 21.5434C135.334 21.5831 135.402 21.603 135.471 21.5994L135.469 21.5958Z\" fill=\"#00844B\"><\/path><path id=\"Vector_52\" d=\"M136.01 19.4293C136.086 19.5668 136.158 19.6952 136.219 19.8127C136.171 19.5071 136.102 19.2087 136.01 18.9103C135.898 18.5522 135.751 18.2014 135.563 17.8596C135.534 17.8108 135.608 17.771 135.632 17.8198C135.825 18.1707 135.974 18.5251 136.087 18.8868C136.176 19.1852 136.245 19.4872 136.297 19.7928C136.301 19.6391 136.317 19.4944 136.337 19.3534V19.3335C136.297 18.7295 136.203 18.2213 136.042 17.8271C135.918 17.5088 135.724 17.2032 135.429 17.0133C135.381 17.3388 135.37 17.6625 135.413 17.9844C135.453 18.2864 135.538 18.5848 135.672 18.8832C135.764 19.0893 135.901 19.234 136.01 19.4311V19.4293Z\" fill=\"#00844B\"><\/path><path id=\"Vector_53\" d=\"M136.545 20.5397C136.574 20.2901 136.61 20.0406 136.65 19.7983C136.698 19.5089 136.754 19.2268 136.819 18.9483C136.807 18.8796 136.8 18.8073 136.796 18.7349C136.796 18.6626 136.8 18.5866 136.809 18.5053C136.816 18.4492 136.894 18.4564 136.89 18.5125C136.877 18.5884 136.874 18.6608 136.877 18.7349C136.877 18.7711 136.881 18.8073 136.885 18.8434C136.904 18.8235 136.924 18.7946 136.941 18.7675C136.969 18.7186 136.993 18.6626 137.013 18.5939C137.02 18.5776 137.025 18.5577 137.065 18.5704C137.101 18.583 137.098 18.6029 137.089 18.6192C137.069 18.6915 137.04 18.7566 137.007 18.8091C136.975 18.8615 136.939 18.9049 136.899 18.9429C136.834 19.2286 136.774 19.5234 136.725 19.8127C136.677 20.0984 136.64 20.3896 136.613 20.6916C136.682 20.6789 136.682 20.5958 136.702 20.5379C136.762 20.3679 136.836 20.1871 136.908 20.0062C137.072 19.5921 137.246 19.1563 137.302 18.8253V18.6355C137.302 18.5396 137.302 18.442 137.306 18.3461C137.289 18.2249 137.257 18.1128 137.217 18.0116C137.152 17.8416 137.06 17.7059 136.951 17.592C136.895 17.7656 136.834 17.9338 136.774 18.1002C136.702 18.3009 136.63 18.5034 136.565 18.6969C136.431 19.1201 136.368 19.5505 136.371 19.999C136.375 20.1925 136.492 20.3625 136.545 20.5433V20.5397Z\" fill=\"#00844B\"><\/path><path id=\"Vector_54\" d=\"M135.787 17.2285C135.699 16.9699 135.607 16.7131 135.489 16.4672C135.345 16.1525 135.171 15.8596 134.945 15.6082C134.932 15.5919 134.916 15.5756 134.949 15.5521C134.978 15.5232 134.988 15.5395 135.001 15.5557C135.234 15.8143 135.411 16.1109 135.561 16.4346C135.627 16.5721 135.683 16.7077 135.739 16.8542C135.654 16.5287 135.601 16.2212 135.574 15.9319C135.498 15.7348 135.384 15.5612 135.243 15.4038C135.106 15.2556 134.945 15.1217 134.768 15.0096C134.764 15.3116 134.8 15.6172 134.896 15.9283C134.985 16.2176 135.126 16.5088 135.332 16.8017C135.46 16.988 135.637 17.0513 135.787 17.2285Z\" fill=\"#00844B\"><\/path><path id=\"Vector_55\" d=\"M136.082 17.7113C136.098 17.7439 136.111 17.7801 136.122 17.8126C136.181 17.7728 136.21 17.639 136.25 17.4383C136.263 17.3822 136.274 17.3171 136.286 17.2484C136.404 16.7294 136.382 16.1561 136.263 15.6407C136.158 15.1886 135.964 14.7709 135.675 14.4562C135.619 14.8993 135.599 15.3622 135.646 15.8668C135.699 16.4346 135.836 17.0025 136.03 17.5432C136.053 17.3732 136.066 17.2014 136.075 17.0278C136.082 16.7981 136.075 16.5612 136.058 16.3225C136.042 16.1127 135.925 15.8668 135.822 15.6407C135.782 15.5648 135.746 15.4834 135.713 15.4111C135.706 15.3912 135.697 15.3749 135.733 15.3586C135.769 15.3424 135.778 15.3622 135.786 15.3785C135.814 15.4509 135.854 15.5268 135.89 15.6082C135.93 15.6932 135.972 15.7782 136.008 15.8614C136.001 15.789 135.992 15.7203 135.984 15.648C135.955 15.478 135.925 15.3062 135.889 15.1326C135.885 15.1127 135.876 15.0928 135.917 15.0838C135.957 15.0801 135.963 15.0964 135.966 15.1163C136.002 15.2935 136.039 15.4671 136.062 15.6353C136.082 15.7836 136.098 15.9301 136.111 16.0748C136.118 16.1597 136.134 16.2357 136.14 16.3171C136.156 16.554 136.163 16.7963 136.156 17.0296C136.152 17.2593 136.127 17.4889 136.087 17.7113H136.082Z\" fill=\"#00844B\"><\/path><path id=\"Vector_56\" d=\"M134.734 17.4618C134.701 17.4618 134.669 17.4745 134.645 17.4943C134.625 17.5142 134.612 17.5432 134.612 17.5757C134.612 17.6083 134.625 17.6354 134.649 17.6571C134.669 17.677 134.701 17.6896 134.737 17.6896C134.773 17.6896 134.802 17.677 134.826 17.6571C134.846 17.6372 134.862 17.6083 134.862 17.5757C134.862 17.5432 134.846 17.516 134.826 17.4943C134.802 17.4745 134.77 17.4618 134.734 17.4618Z\" fill=\"#00844B\"><\/path><path id=\"Vector_57\" d=\"M136.256 15.3225C136.284 15.2628 136.304 15.1941 136.324 15.129C136.38 14.9481 136.481 14.8667 136.639 14.7456C136.655 14.7329 136.671 14.7167 136.684 14.7094C136.729 14.6769 136.776 14.7384 136.733 14.7691C136.716 14.7854 136.7 14.798 136.687 14.8053C136.543 14.9174 136.445 14.9897 136.402 15.147C136.386 15.1995 136.369 15.2556 136.349 15.3008C136.333 15.3496 136.313 15.3894 136.29 15.4219C136.297 15.4545 136.31 15.4906 136.319 15.5268C136.335 15.4816 136.355 15.4418 136.378 15.402C136.424 15.3207 136.483 15.2537 136.559 15.1886C136.716 15.0639 136.821 14.9156 136.917 14.7655C136.897 14.6895 136.885 14.5684 136.825 14.5195C136.805 14.4996 136.765 14.5069 136.72 14.5268C136.635 14.5629 136.547 14.6353 136.514 14.6678C136.406 14.7799 136.324 14.8812 136.272 14.9734C136.18 15.1272 136.207 15.1706 136.256 15.3207V15.3225Z\" fill=\"#00844B\"><\/path><path id=\"Vector_58\" d=\"M136.433 16.7981C136.42 16.9554 136.4 17.1164 136.364 17.2701C136.38 17.2574 136.396 17.2375 136.416 17.2213C136.469 17.1616 136.525 17.0929 136.55 17.044C136.639 16.903 136.711 16.8017 136.796 16.6806C136.796 16.6769 136.803 16.6643 136.848 16.6046C136.881 16.5594 136.944 16.6046 136.913 16.6534C136.906 16.6607 136.894 16.6824 136.861 16.7258C136.776 16.8469 136.704 16.9482 136.619 17.0893C136.59 17.1381 136.53 17.214 136.474 17.2737C136.402 17.3497 136.349 17.3497 136.33 17.4546C136.31 17.5468 136.293 17.6282 136.277 17.6969C136.462 17.5522 136.628 17.3985 136.772 17.2412C136.946 17.0513 137.083 16.8578 137.172 16.6733C137.253 16.5124 137.306 16.3424 137.326 16.1742C137.345 16.0205 137.338 15.8686 137.302 15.7076C137.148 15.8125 136.997 15.9373 136.856 16.0983C136.698 16.2755 136.554 16.4979 136.442 16.7909C136.442 16.7909 136.438 16.7945 136.438 16.7981H136.433Z\" fill=\"#00844B\"><\/path><path id=\"Vector_59\" d=\"M135.003 14.4563C134.963 14.4689 134.934 14.496 134.918 14.5322C134.902 14.5684 134.902 14.6136 134.918 14.6534C134.931 14.6986 134.963 14.7293 134.999 14.7456C135.035 14.7655 135.081 14.7691 135.117 14.7583C135.157 14.742 135.185 14.713 135.202 14.6769C135.218 14.6407 135.218 14.6009 135.202 14.5557C135.185 14.5159 135.157 14.4834 135.12 14.4635C135.084 14.4472 135.039 14.44 135.003 14.4563Z\" fill=\"#00844B\"><\/path><path id=\"Vector_60\" d=\"M136.239 14.8758C136.295 14.7944 136.368 14.7058 136.456 14.6136C136.577 14.4924 136.693 14.4201 136.666 14.2067C136.65 14.1054 136.606 13.9481 136.496 13.7926C136.362 13.9336 136.243 14.1181 136.185 14.3116C136.14 14.4725 136.129 14.6588 136.162 14.8668C136.178 14.7293 136.201 14.5937 136.237 14.4599C136.283 14.279 136.346 14.1054 136.427 13.9409C136.451 13.8884 136.523 13.9246 136.5 13.9734C136.418 14.138 136.359 14.308 136.315 14.4816C136.283 14.61 136.255 14.7438 136.239 14.8758Z\" fill=\"#00844B\"><\/path><path id=\"Vector_61\" d=\"M139.719 26.1656C139.738 26.0119 139.748 25.8473 139.735 25.6737C139.719 25.3356 139.646 24.9775 139.522 24.6466C139.514 24.6231 139.525 24.6013 139.545 24.5941C139.428 24.4603 139.319 24.3283 139.211 24.1872C139.203 24.6176 139.223 25.0299 139.283 25.4079C139.339 25.7551 139.431 26.0969 139.578 26.4152C139.65 26.3193 139.666 26.2741 139.719 26.1656Z\" fill=\"#00844B\"><\/path><path id=\"Vector_62\" d=\"M139.617 24.6737C139.729 24.9956 139.798 25.3428 139.814 25.6737C139.818 25.7822 139.818 25.8871 139.814 25.992C139.863 25.916 139.88 25.8473 139.89 25.7551C139.919 25.5815 139.923 25.3355 139.91 25.0372C139.91 25.0209 139.914 25.0082 139.923 25.0046C139.818 24.8961 139.717 24.7876 139.617 24.6737Z\" fill=\"#00844B\"><\/path><path id=\"Vector_63\" d=\"M139.992 25.0733C140.004 25.3428 139.995 25.5688 139.975 25.7388C140.031 25.6339 140.08 25.5254 140.12 25.4043C140.136 25.3518 140.149 25.2958 140.165 25.2343C140.105 25.1818 140.048 25.1258 139.992 25.0733Z\" fill=\"#00844B\"><\/path><path id=\"Vector_64\" d=\"M156.704 19.8471C156.707 19.9592 156.7 20.0731 156.68 20.1852C156.805 20.0514 156.933 19.923 157.063 19.7946C157.071 19.7295 157.08 19.6699 157.096 19.6102C157.112 19.5451 157.132 19.4764 157.161 19.4131C157.181 19.3534 157.253 19.3841 157.233 19.4366C157.21 19.5053 157.188 19.565 157.174 19.6301C157.17 19.6536 157.161 19.6825 157.157 19.706C157.334 19.536 157.521 19.3715 157.705 19.2069C157.75 19.1707 157.797 19.2304 157.757 19.2666C157.568 19.4311 157.383 19.5975 157.202 19.7693C157.222 19.7693 157.242 19.7693 157.262 19.7729C157.311 19.7729 157.363 19.7765 157.41 19.7802C157.466 19.7838 157.459 19.8652 157.403 19.8561C157.358 19.8525 157.311 19.8489 157.258 19.8489H157.121C156.96 20.0062 156.803 20.1672 156.649 20.3408C156.601 20.518 156.521 20.6952 156.416 20.8598C156.449 20.8399 156.481 20.8236 156.512 20.8037C156.588 20.6916 156.673 20.5741 156.785 20.4891C157.063 20.2793 157.284 20.1111 157.477 19.9086C157.674 19.7114 157.844 19.4854 158.012 19.1671C158.101 19.0026 158.146 18.7801 158.242 18.6391C157.931 18.7078 157.698 18.7765 157.452 18.9338C157.146 19.131 156.892 19.4655 156.723 19.7928C156.711 19.8163 156.704 19.8218 156.704 19.8453V19.8471Z\" fill=\"#00844B\"><\/path><path id=\"Vector_65\" d=\"M157.271 18.97C157.324 18.8488 157.372 18.7331 157.399 18.6192C157.423 18.507 157.439 18.3768 157.416 18.2647C157.371 18.0188 157.439 17.7403 157.501 17.4871C157.513 17.4419 157.521 17.4021 157.53 17.3623C157.228 17.6083 156.962 17.8615 156.769 18.1273C156.559 18.4166 156.434 18.7277 156.447 19.0586C156.548 19.2159 156.62 19.3769 156.66 19.5469C156.664 19.4221 156.664 19.3009 156.673 19.1924C156.686 19.0315 156.705 18.8868 156.738 18.762C156.778 18.6336 156.827 18.5324 156.883 18.451C156.939 18.3696 157.007 18.3099 157.076 18.2611C157.125 18.2286 157.168 18.2937 157.125 18.3262C157.056 18.3714 157 18.4275 156.948 18.4998C156.895 18.5722 156.852 18.6644 156.814 18.7819C156.807 18.8109 156.801 18.838 156.794 18.8705C156.826 18.8344 156.859 18.8018 156.89 18.7747C156.958 18.715 157.027 18.6626 157.103 18.6137C157.148 18.5848 157.192 18.6499 157.143 18.6825C157.074 18.7277 157.005 18.7747 156.942 18.8308C156.883 18.8904 156.821 18.9519 156.769 19.0206C156.761 19.0767 156.756 19.1382 156.752 19.2015C156.745 19.3263 156.74 19.4601 156.74 19.6047C156.904 19.3226 157.081 19.1219 157.271 18.9718V18.97Z\" fill=\"#00844B\"><\/path><path id=\"Vector_66\" d=\"M155.673 21.9828L155.67 21.9864C155.699 22.4945 155.558 22.981 155.404 23.4403C155.541 23.2107 155.673 22.9575 155.798 22.6953C155.805 22.679 155.814 22.6627 155.822 22.6465H155.818C155.825 22.5868 155.831 22.5289 155.831 22.4728C155.827 22.4168 155.818 22.3607 155.811 22.3083C155.798 22.2558 155.876 22.2396 155.887 22.292C155.899 22.3445 155.903 22.4005 155.906 22.4566C156.024 22.1907 156.136 21.9213 156.237 21.6627C156.257 21.6102 156.329 21.6392 156.31 21.6916C156.208 21.9538 156.096 22.2233 155.979 22.4891C155.991 22.4819 155.999 22.4692 156.011 22.4602C156.076 22.4114 156.14 22.368 156.205 22.3264C156.254 22.3029 156.286 22.3716 156.244 22.3951C156.179 22.4313 156.12 22.4765 156.06 22.5199C155.979 22.585 155.912 22.6374 155.87 22.726C155.789 22.8996 155.706 23.0642 155.617 23.2215C155.775 23.057 155.955 22.9032 156.149 22.7694C156.286 22.6808 156.427 22.5994 156.572 22.5325C156.644 22.3264 156.595 22.169 156.555 22.037C156.535 21.9719 156.519 21.9159 156.51 21.8562C156.47 21.4891 156.763 21.0225 156.957 20.7151C156.698 20.7874 156.441 20.9122 156.239 21.0822C155.961 21.3155 155.78 21.6374 155.671 21.981L155.673 21.9828Z\" fill=\"#00844B\"><\/path><path id=\"Vector_67\" d=\"M157.448 15.1651C157.416 15.1579 157.38 15.1651 157.347 15.1886C157.314 15.2121 157.291 15.2483 157.278 15.2971C157.266 15.3424 157.271 15.3894 157.286 15.4255C157.302 15.4581 157.331 15.4816 157.361 15.4906C157.394 15.4979 157.43 15.487 157.457 15.4671C157.493 15.4382 157.517 15.402 157.53 15.355C157.542 15.3062 157.537 15.2628 157.522 15.2302C157.506 15.1977 157.483 15.1742 157.446 15.1651H157.448Z\" fill=\"#00844B\"><\/path><path id=\"Vector_68\" d=\"M155.939 15.3152C155.984 15.384 156.02 15.4599 156.051 15.5413C156.071 15.5901 156.087 15.6426 156.104 15.695C156.152 15.5775 156.212 15.469 156.281 15.3641C156.248 15.1796 156.169 15.0657 156.064 14.9933C155.968 14.9246 155.847 14.8975 155.726 14.8885C155.585 15.1471 155.525 15.299 155.529 15.4563C155.532 15.6209 155.601 15.7945 155.719 16.1055V16.1127C155.807 16.1254 155.892 16.1688 155.981 16.2502C155.984 16.1489 156 16.044 156.026 15.9446C156.033 15.8994 156.046 15.8596 156.062 15.8162C156.038 15.7312 156.01 15.6516 155.981 15.5738C155.948 15.4925 155.916 15.4201 155.876 15.3568C155.843 15.308 155.912 15.2682 155.941 15.317L155.939 15.3152Z\" fill=\"#00844B\"><\/path><path id=\"Vector_69\" d=\"M156.1 15.9626C156.008 16.3334 156.051 16.7366 156.281 17.1182C156.329 17.1942 156.382 17.2719 156.441 17.3442C156.449 17.3207 156.458 17.2954 156.465 17.2755C156.384 16.9374 156.369 16.6462 156.409 16.308C156.425 16.1869 156.449 16.0621 156.478 15.9373C156.454 15.8813 156.429 15.8252 156.409 15.7673C156.393 15.7077 156.38 15.6425 156.376 15.5738C156.373 15.5178 156.452 15.5178 156.458 15.5738C156.458 15.6299 156.47 15.6914 156.487 15.7438C156.494 15.7673 156.503 15.7963 156.516 15.8198C156.561 15.6624 156.62 15.5051 156.693 15.3478C156.716 15.299 156.789 15.3315 156.765 15.3839C156.696 15.525 156.644 15.6661 156.601 15.8107C156.604 15.8035 156.613 15.7945 156.62 15.7872C156.657 15.7511 156.693 15.7149 156.716 15.6751C156.749 15.6263 156.812 15.6715 156.785 15.7203C156.752 15.7655 156.716 15.8053 156.676 15.8451C156.64 15.8813 156.601 15.9138 156.559 15.9464C156.526 16.0711 156.503 16.1959 156.49 16.3207C156.483 16.3894 156.474 16.4581 156.47 16.5269C156.49 16.507 156.516 16.4816 156.535 16.4618C156.572 16.4165 156.608 16.3768 156.624 16.3496C156.653 16.2972 156.72 16.3334 156.696 16.3858C156.673 16.422 156.637 16.4672 156.592 16.5142C156.546 16.563 156.499 16.6155 156.47 16.6625C156.47 16.8234 156.49 16.9844 156.519 17.1453C156.648 16.8723 156.801 16.6372 156.975 16.4401C157.014 16.299 157.034 16.1616 157.031 16.0259C157.027 15.8849 157.002 15.7438 156.958 15.6064C156.91 15.4581 156.899 15.3008 156.913 15.1434C156.92 15.0313 156.946 14.9101 156.973 14.7926C156.892 14.8487 156.812 14.9047 156.74 14.9698C156.438 15.223 156.192 15.5702 156.1 15.9608V15.9626Z\" fill=\"#00844B\"><\/path><path id=\"Vector_70\" d=\"M155.399 16.677C155.458 16.7059 155.523 16.7258 155.592 16.7366C155.511 16.6281 155.435 16.5142 155.362 16.4057C155.33 16.3569 155.395 16.3135 155.427 16.3605C155.5 16.4654 155.572 16.5703 155.644 16.6752C155.641 16.639 155.632 16.5992 155.628 16.563C155.615 16.4871 155.599 16.4147 155.583 16.337C155.57 16.2809 155.648 16.2646 155.659 16.3171C155.675 16.393 155.691 16.4744 155.704 16.5504C155.72 16.6354 155.733 16.724 155.74 16.8126C155.793 16.8849 155.849 16.9609 155.901 17.035C155.934 17.0748 155.961 17.12 155.993 17.1598C155.993 17.1435 155.997 17.1273 155.997 17.1146C156 17.0621 156 17.0097 156 16.9609C156 16.9048 156.082 16.9048 156.082 16.9609C156.082 17.0133 156.082 17.0658 156.078 17.1182C156.075 17.1634 156.071 17.2032 156.062 17.2466C156.163 17.375 156.263 17.4998 156.367 17.6246C156.38 17.5595 156.391 17.4962 156.413 17.4311H156.409C156.337 17.3424 156.268 17.2502 156.216 17.158C156.058 16.8958 155.982 16.6263 155.973 16.3605C155.78 16.1344 155.599 16.1706 155.366 16.2158C155.321 16.2231 155.277 16.2321 155.229 16.2393C155.281 16.6625 155.382 16.9808 155.559 17.2303C155.733 17.4799 155.986 17.6662 156.349 17.8271C156.349 17.7945 156.353 17.762 156.353 17.7313C156.235 17.5938 156.123 17.4528 156.015 17.3117H155.894C155.854 17.3117 155.812 17.3081 155.769 17.299C155.713 17.2918 155.724 17.2141 155.776 17.2231C155.816 17.2267 155.858 17.2303 155.897 17.2303C155.917 17.2339 155.934 17.2339 155.953 17.2339C155.914 17.1815 155.878 17.1291 155.841 17.0802C155.776 16.9916 155.713 16.9066 155.652 16.818C155.55 16.8108 155.455 16.7891 155.366 16.7457C155.314 16.7222 155.35 16.6498 155.399 16.6733V16.677Z\" fill=\"#00844B\"><\/path><path id=\"Vector_71\" d=\"M156.582 17.1996C156.49 17.4003 156.434 17.63 156.425 17.856C156.418 18.0495 156.441 18.243 156.501 18.4203C156.546 18.328 156.597 18.2358 156.662 18.1418L156.658 18.1381C156.642 18.0459 156.629 17.9736 156.655 17.8795C156.727 17.5902 156.832 17.3244 156.96 17.0658C157.02 16.9536 157.081 16.8361 157.15 16.7276C157.157 16.6752 157.166 16.6354 157.17 16.5938C157.177 16.554 157.177 16.5178 157.183 16.469C157.183 16.4129 157.258 16.4166 157.258 16.4726C157.258 16.4961 157.258 16.5251 157.255 16.5486C157.3 16.4762 157.347 16.4039 157.392 16.3352C157.405 16.3189 157.412 16.3026 157.445 16.3225C157.481 16.3424 157.468 16.3587 157.457 16.3786C157.309 16.6082 157.159 16.8542 157.034 17.1001C157.014 17.1363 156.998 17.1725 156.982 17.2086L156.986 17.205C157.031 17.1725 157.078 17.1399 157.127 17.1164C157.175 17.0929 157.211 17.1616 157.163 17.1887C157.114 17.2086 157.074 17.2376 157.029 17.2701C156.989 17.3027 156.948 17.3388 156.908 17.3786C156.904 17.3786 156.904 17.3822 156.904 17.3822C156.832 17.5468 156.776 17.7168 156.731 17.8976C156.714 17.9501 156.714 17.9989 156.723 18.0513C156.825 17.9175 156.94 17.7891 157.07 17.6607C157.07 17.6607 157.074 17.6571 157.074 17.6535C157.202 17.46 157.307 17.2593 157.389 17.0531C157.477 16.8433 157.537 16.6336 157.578 16.4202C157.607 16.2628 157.627 16.1019 157.667 15.9409C157.461 16.0784 157.273 16.2303 157.099 16.4202C156.89 16.6462 156.713 16.9157 156.584 17.1978L156.582 17.1996Z\" fill=\"#00844B\"><\/path><path id=\"Vector_72\" d=\"M158.061 17.6752C157.98 17.7276 157.956 17.7963 157.924 17.8813C157.924 17.885 157.92 17.8886 157.92 17.894C157.992 17.894 158.048 17.8813 158.093 17.8614C158.142 17.8415 158.178 17.8054 158.202 17.7602C158.218 17.724 158.258 17.6354 158.189 17.6318C158.157 17.6318 158.113 17.6481 158.061 17.677V17.6752Z\" fill=\"#00844B\"><\/path><path id=\"Vector_73\" d=\"M156.297 18.9845C156.176 18.8308 156.067 18.6861 155.972 18.545C155.896 18.4329 155.831 18.328 155.775 18.2267C155.679 18.489 155.61 18.7711 155.581 19.0532C155.549 19.3516 155.558 19.6536 155.61 19.9483C155.65 20.1491 155.722 20.339 155.836 20.5162C155.928 20.6608 156.049 20.7983 156.199 20.9194C156.176 20.5939 156.123 20.2702 156.051 19.952C155.991 19.9158 155.939 19.876 155.881 19.8272C155.825 19.7747 155.769 19.7151 155.717 19.6463C155.681 19.6011 155.746 19.5541 155.776 19.5975C155.829 19.6626 155.881 19.7187 155.937 19.7675C155.966 19.7964 155.993 19.8163 156.022 19.8398C155.966 19.6228 155.901 19.4131 155.829 19.1997C155.812 19.1472 155.885 19.1237 155.905 19.1762C155.973 19.3769 156.038 19.583 156.089 19.7892C156.105 19.7205 156.118 19.6481 156.122 19.5794C156.122 19.5234 156.203 19.527 156.197 19.583C156.194 19.7006 156.165 19.8163 156.122 19.9303C156.197 20.2558 156.25 20.5903 156.275 20.9303C156.711 20.3371 156.767 19.5812 156.299 18.9881L156.297 18.9845Z\" fill=\"#00844B\"><\/path><path id=\"Vector_74\" d=\"M156.192 22.8363C155.765 23.1257 155.411 23.5181 155.245 23.9196C155.467 23.8237 155.675 23.7225 155.881 23.585C155.894 23.529 155.91 23.4729 155.934 23.4205C155.957 23.3644 155.99 23.3083 156.026 23.2559C156.038 23.2396 156.049 23.2233 156.082 23.2487C156.114 23.2685 156.102 23.2848 156.089 23.3011C156.053 23.3499 156.024 23.4024 156.004 23.4548C155.991 23.4747 155.984 23.4946 155.981 23.5199C156.243 23.33 156.479 23.1166 156.709 22.8906C156.749 22.8544 156.805 22.9069 156.765 22.9467C156.528 23.1799 156.29 23.3897 156.053 23.5633C155.836 23.7206 155.601 23.8617 155.348 23.9666C155.335 23.9991 155.319 24.0263 155.308 24.0588C155.57 24.0425 155.832 23.9575 156.089 23.8002C156.375 23.6302 156.657 23.3771 156.931 23.0425C157.121 22.8164 157.322 22.6031 157.519 22.3897C157.056 22.3861 156.577 22.5795 156.19 22.8363H156.192Z\" fill=\"#00844B\"><\/path><path id=\"Vector_75\" d=\"M157.257 21.6048C157.233 21.6736 157.28 21.7332 157.349 21.7459C157.418 21.7585 157.502 21.717 157.526 21.6446C157.546 21.5759 157.502 21.5198 157.434 21.5036C157.362 21.4909 157.277 21.5325 157.257 21.6048Z\" fill=\"#00844B\"><\/path><path id=\"Vector_76\" d=\"M155.516 20.7947C155.496 20.8182 155.484 20.8507 155.484 20.8905C155.484 20.9267 155.496 20.9628 155.52 20.9864C155.559 21.0352 155.621 21.0515 155.664 20.9936C155.684 20.9701 155.697 20.9339 155.697 20.8923C155.697 20.8507 155.684 20.8164 155.664 20.791C155.625 20.7422 155.559 20.7422 155.516 20.791V20.7947Z\" fill=\"#00844B\"><\/path><path id=\"Vector_77\" d=\"M155.169 22.6682C155.12 22.7278 155.077 22.7893 155.035 22.858C154.995 22.9232 154.959 22.9919 154.927 23.0642C154.923 23.245 154.93 23.4114 154.95 23.5561C154.97 23.7008 155.01 23.8617 155.091 23.9919C155.187 23.9467 155.261 23.6085 155.305 23.4838C155.518 22.8508 155.715 22.1654 155.489 21.4565C155.444 21.3119 155.38 21.1708 155.299 21.0334C155.254 20.952 155.203 20.8724 155.142 20.7965C154.994 21.4041 154.784 21.9882 154.518 22.5452L154.502 22.5741C154.498 22.9322 154.526 23.283 154.614 23.5326C154.686 23.746 154.804 23.8997 154.985 23.9684C154.932 23.8635 154.896 23.7261 154.873 23.5651C154.844 23.3644 154.836 23.1257 154.853 22.8689C154.865 22.6627 154.889 22.4584 154.925 22.245C154.961 22.0316 155.014 21.8146 155.086 21.5958C155.102 21.5397 155.178 21.5632 155.158 21.6193C155.089 21.8327 155.037 22.0461 155.001 22.2559C154.965 22.4656 154.945 22.67 154.932 22.8725V22.8761C154.945 22.8562 154.952 22.8363 154.965 22.8201C155.01 22.7514 155.053 22.6826 155.106 22.6193C155.142 22.5796 155.202 22.6266 155.165 22.6718L155.169 22.6682Z\" fill=\"#00844B\"><\/path><path id=\"Vector_78\" d=\"M153.221 26.3663C153.277 26.2849 153.333 26.209 153.398 26.133C153.598 25.8907 153.804 25.7696 153.877 25.4477C153.897 25.3518 153.906 25.2578 153.9 25.1619C153.897 25.1023 153.972 25.0932 153.976 25.1547C153.983 25.2596 153.976 25.3645 153.953 25.4657C153.945 25.5055 153.933 25.5471 153.92 25.5833C154.001 25.4983 154.077 25.4133 154.15 25.3247C154.274 25.171 154.386 25.01 154.48 24.822C154.509 24.7731 154.576 24.8093 154.553 24.8581C154.451 25.0516 154.339 25.2162 154.215 25.3735C154.166 25.4296 154.122 25.4856 154.07 25.5381C154.13 25.5055 154.188 25.473 154.244 25.4495C154.292 25.426 154.329 25.4947 154.276 25.5182C154.204 25.5544 154.128 25.5941 154.054 25.6393C153.812 25.784 153.64 25.9703 153.457 26.1873C153.365 26.2994 153.277 26.417 153.195 26.5417C153.517 26.4242 153.803 26.2632 154.057 26.039C154.33 25.7967 154.569 25.4784 154.77 25.0679C154.882 24.831 154.986 24.5959 155.091 24.359C155.14 24.2415 155.193 24.1257 155.245 24.0082C154.182 24.4711 153.484 25.2487 153.219 26.3699L153.221 26.3663Z\" fill=\"#00844B\"><\/path><path id=\"Vector_79\" d=\"M153.906 23.9901C153.877 23.9937 153.853 24.01 153.833 24.0353C153.813 24.0588 153.801 24.095 153.797 24.1366C153.797 24.1728 153.804 24.2089 153.826 24.2379C153.839 24.2578 153.859 24.2704 153.882 24.2704C153.915 24.2704 153.942 24.2632 153.963 24.2415C153.983 24.2216 154 24.189 154.009 24.1402C154.009 24.1239 154.009 24.104 154.005 24.0878C154.001 24.0588 153.989 24.0353 153.976 24.019C153.96 24.0028 153.944 23.9901 153.924 23.9901H153.907H153.906Z\" fill=\"#00844B\"><\/path><path id=\"Vector_80\" d=\"M155.614 24.9757C155.538 25.0317 155.545 25.1203 155.643 25.1529C155.688 25.1692 155.738 25.1655 155.787 25.1529C155.872 25.1294 155.941 25.0353 155.856 24.9684C155.787 24.9196 155.682 24.9286 155.614 24.9757Z\" fill=\"#00844B\"><\/path><path id=\"Vector_81\" d=\"M154.106 26.4875C154.021 26.5833 153.929 26.672 153.833 26.7606C154.027 26.6683 154.233 26.5598 154.453 26.4387C154.502 26.4097 154.542 26.4785 154.489 26.5074C154.227 26.6521 153.987 26.7768 153.761 26.8781C153.85 26.8853 153.938 26.9016 154.03 26.9432C154.063 26.9559 154.063 26.9758 154.043 27.0029C154.128 26.9667 154.207 26.9269 154.285 26.8781C154.692 26.6412 155.042 26.285 155.324 25.9468C154.873 25.8745 154.274 25.9956 153.904 26.2615C153.678 26.4224 153.428 26.5472 153.159 26.6394C153.094 26.6955 153.042 26.7678 153.002 26.8456C152.973 26.9016 152.946 26.9631 152.92 27.0354C153.121 27.0282 153.34 26.9667 153.577 26.8709C153.746 26.7425 153.907 26.5978 154.048 26.4351C154.088 26.3898 154.144 26.4423 154.108 26.4875H154.106Z\" fill=\"#00844B\"><\/path><path id=\"Vector_82\" d=\"M154.01 27.0191C154.01 27.0191 154.003 27.0155 153.998 27.0119C153.886 26.9631 153.765 26.9595 153.647 26.9522H153.591C153.358 27.0445 153.145 27.1005 152.942 27.1168C153.325 27.209 153.683 27.1566 154.009 27.021L154.01 27.0191Z\" fill=\"#00844B\"><\/path><path id=\"Vector_83\" d=\"M153.253 25.1366C153.201 25.2053 153.165 25.2849 153.132 25.3699C153.103 25.4549 153.08 25.5435 153.063 25.6285C153.092 25.7858 153.148 25.9341 153.224 26.0589C153.284 25.8781 153.353 25.7045 153.437 25.5399C153.474 25.2505 153.47 24.9956 153.43 24.7749C153.41 24.6411 153.374 24.5163 153.325 24.4078C153.116 24.661 152.89 24.9033 152.653 25.133C152.669 25.652 152.834 25.9667 153.004 26.3012C153.04 26.3663 153.072 26.435 153.109 26.5074C153.132 26.3898 153.161 26.2777 153.193 26.1692C153.101 26.0481 153.033 25.822 152.993 25.6737C152.977 25.605 152.864 25.529 152.799 25.4965C152.751 25.473 152.783 25.4043 152.836 25.4278C152.895 25.4567 152.953 25.4965 153 25.5489C153.016 25.4802 153.036 25.4115 153.06 25.3482C153.092 25.256 153.132 25.1674 153.188 25.0896C153.224 25.0444 153.289 25.0932 153.253 25.1384V25.1366Z\" fill=\"#00844B\"><\/path><path id=\"Vector_84\" d=\"M152.174 6.02368C152.085 6.02368 152.004 6.05985 151.944 6.11591C151.888 6.17559 151.849 6.25697 151.849 6.34558C151.849 6.52642 151.997 6.67109 152.174 6.67109C152.266 6.67109 152.348 6.63492 152.404 6.57886C152.463 6.51918 152.499 6.4378 152.499 6.34558C152.499 6.16835 152.355 6.02368 152.174 6.02368Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_85\" d=\"M146.356 6.28229C146.352 6.3275 146.211 6.50472 146.171 6.52461H146.296C146.325 6.50472 146.345 6.48483 146.356 6.45589C146.368 6.48483 146.388 6.50472 146.415 6.52461H146.54C146.5 6.50472 146.359 6.3275 146.356 6.28229Z\" fill=\"black\"><\/path><path id=\"Vector_86\" d=\"M146.356 5.60959C146.352 5.64937 146.211 5.79405 146.171 5.81032H146.296C146.325 5.79405 146.345 5.77777 146.356 5.75426C146.368 5.77777 146.388 5.79405 146.415 5.81032H146.54C146.5 5.79405 146.359 5.64937 146.356 5.60959Z\" fill=\"black\"><\/path><path id=\"Vector_87\" d=\"M141.197 7.65126C141.085 7.68743 141.033 7.74711 141.024 7.80859C141.02 7.8321 141.024 7.85742 141.027 7.87731C141.034 7.90082 141.051 7.92252 141.067 7.93699C141.112 7.98581 141.188 8.00932 141.268 7.9822C143.091 7.40532 144.724 7.11598 146.354 7.11598C147.984 7.11598 149.616 7.40532 151.44 7.9822C151.521 8.01113 151.597 7.98581 151.641 7.93699C151.657 7.92071 151.673 7.90082 151.681 7.87731C151.684 7.85742 151.688 7.8321 151.684 7.80859C151.677 7.74891 151.624 7.68743 151.511 7.65126C149.831 7.08342 148.091 6.7977 146.352 6.7977C144.613 6.7977 142.873 7.08342 141.193 7.65126H141.197Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_88\" d=\"M144.015 6.60418L143.959 6.65301C143.701 6.88629 143.382 6.94235 143.005 6.83385L142.929 6.81034L142.994 6.76513C143.138 6.65662 143.292 6.59152 143.449 6.56801C143.607 6.53908 143.771 6.54812 143.941 6.58791L144.017 6.60418H144.015Z\" fill=\"black\"><\/path><path id=\"Vector_89\" d=\"M144.857 5.72169C144.857 5.75424 144.733 5.89529 144.696 5.91519L144.821 5.89891C144.845 5.88263 144.861 5.86636 144.877 5.84647C144.893 5.86274 144.917 5.87902 144.942 5.88625L145.067 5.87359C145.027 5.86636 144.87 5.75243 144.857 5.71988V5.72169Z\" fill=\"black\"><\/path><path id=\"Vector_90\" d=\"M143.294 5.90797C143.297 5.94413 143.189 6.1087 143.156 6.13402L143.278 6.10508C143.301 6.08519 143.317 6.0653 143.326 6.03998C143.346 6.05626 143.372 6.06891 143.399 6.07615L143.52 6.04721C143.48 6.0436 143.306 5.93871 143.294 5.90616V5.90797Z\" fill=\"black\"><\/path><path id=\"Vector_91\" d=\"M141.618 6.34558C141.622 6.38175 141.53 6.55535 141.497 6.57886L141.615 6.5427C141.635 6.5228 141.651 6.50291 141.66 6.47759C141.68 6.49387 141.705 6.5011 141.732 6.51014L141.853 6.47398C141.813 6.47036 141.636 6.37813 141.62 6.34558H141.618Z\" fill=\"black\"><\/path><path id=\"Vector_92\" d=\"M143.841 6.6494C143.708 6.62589 143.583 6.62589 143.464 6.64578C143.339 6.66567 143.222 6.71088 143.109 6.78322C143.391 6.84832 143.637 6.80311 143.841 6.6494Z\" fill=\"#E20613\"><\/path><path id=\"Vector_93\" d=\"M148.695 6.60418L148.751 6.65301C149.013 6.88629 149.327 6.94235 149.705 6.83385L149.781 6.81034L149.716 6.76513C149.571 6.65662 149.418 6.59152 149.26 6.56801C149.103 6.53908 148.939 6.54812 148.769 6.58791L148.693 6.60418H148.695Z\" fill=\"black\"><\/path><path id=\"Vector_94\" d=\"M147.852 5.72169C147.852 5.75424 147.977 5.89529 148.013 5.91519L147.888 5.89891C147.865 5.88263 147.849 5.86636 147.832 5.84647C147.816 5.86274 147.793 5.87902 147.767 5.88625L147.643 5.87359C147.682 5.86636 147.84 5.75243 147.852 5.71988V5.72169Z\" fill=\"black\"><\/path><path id=\"Vector_95\" d=\"M149.416 5.90797C149.412 5.94413 149.521 6.1087 149.553 6.13402L149.432 6.10508C149.412 6.08519 149.396 6.0653 149.383 6.03998C149.363 6.05626 149.338 6.06891 149.311 6.07615L149.19 6.04721C149.23 6.0436 149.403 5.93871 149.416 5.90616V5.90797Z\" fill=\"black\"><\/path><path id=\"Vector_96\" d=\"M151.091 6.34558C151.088 6.38175 151.18 6.55535 151.212 6.57886L151.095 6.5427C151.075 6.5228 151.059 6.50291 151.05 6.47759C151.03 6.49387 151.005 6.5011 150.977 6.51014L150.856 6.47398C150.896 6.47036 151.073 6.37813 151.089 6.34558H151.091Z\" fill=\"black\"><\/path><path id=\"Vector_97\" d=\"M148.868 6.6494C149.002 6.62589 149.127 6.62589 149.246 6.64578C149.371 6.66567 149.488 6.71088 149.6 6.78322C149.318 6.84832 149.072 6.80311 148.868 6.6494Z\" fill=\"#E20613\"><\/path><path id=\"Vector_98\" d=\"M149.642 5.01282C149.629 5.36726 149.638 5.27503 149.953 5.4396C149.804 5.39439 149.654 5.36726 149.522 5.45587C149.45 5.3112 149.309 5.26238 149.156 5.22621C149.51 5.23887 149.474 5.32205 149.644 5.01282H149.642Z\" fill=\"black\"><\/path><path id=\"Vector_99\" d=\"M145.871 5.59331C145.964 5.59331 146.041 5.51736 146.041 5.42332C146.041 5.32929 145.965 5.25876 145.871 5.25876C145.777 5.25876 145.707 5.33109 145.707 5.42332C145.707 5.51555 145.779 5.59331 145.871 5.59331Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_100\" d=\"M143.07 5.01282C143.082 5.36726 143.073 5.27503 142.759 5.4396C142.907 5.39439 143.057 5.36726 143.189 5.45587C143.261 5.3112 143.402 5.26238 143.556 5.22621C143.202 5.23887 143.238 5.32205 143.068 5.01282H143.07Z\" fill=\"black\"><\/path><path id=\"Vector_101\" d=\"M146.356 4.00552C146.244 4.00552 146.15 4.09775 146.15 4.2153C146.15 4.33284 146.242 4.42145 146.356 4.42145C146.47 4.42145 146.562 4.32923 146.562 4.2153C146.562 4.10137 146.47 4.00552 146.356 4.00552Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_102\" d=\"M146.356 2.69626C146.215 2.69626 146.103 2.8138 146.103 2.95486C146.103 3.09591 146.215 3.20803 146.356 3.20803C146.497 3.20803 146.609 3.09591 146.609 2.95486C146.609 2.8138 146.497 2.69626 146.356 2.69626Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_103\" d=\"M146.356 2.06693C146.227 2.06693 146.123 2.17543 146.123 2.30382C146.123 2.43222 146.227 2.53711 146.356 2.53711C146.484 2.53711 146.589 2.43222 146.589 2.30382C146.589 2.17543 146.484 2.06693 146.356 2.06693Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_104\" d=\"M146.356 3.36536C146.222 3.36536 146.11 3.47748 146.11 3.61491C146.11 3.75235 146.222 3.86086 146.356 3.86086C146.489 3.86086 146.602 3.74874 146.602 3.61491C146.602 3.48109 146.489 3.36536 146.356 3.36536Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_105\" d=\"M146.356 0.169922C146.077 0.169922 145.853 0.395971 145.853 0.678081C145.853 0.96019 146.079 1.18624 146.356 1.18624C146.632 1.18624 146.858 0.956574 146.858 0.678081C146.858 0.399588 146.632 0.169922 146.356 0.169922Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_106\" d=\"M150.282 4.34369C150.16 4.34369 150.065 4.43953 150.065 4.5607C150.065 4.68186 150.16 4.78313 150.282 4.78313C150.341 4.78313 150.399 4.75962 150.439 4.71803C150.479 4.67824 150.504 4.62218 150.504 4.5607C150.504 4.43953 150.403 4.34369 150.282 4.34369Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_107\" d=\"M150.84 3.2442C150.775 3.2442 150.715 3.27314 150.67 3.31654C150.625 3.36175 150.598 3.42142 150.598 3.48653C150.598 3.62035 150.706 3.72885 150.84 3.72885C150.909 3.72885 150.968 3.69992 151.01 3.66013C151.055 3.61492 151.082 3.55525 151.082 3.48653C151.082 3.35271 150.974 3.2442 150.84 3.2442Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_108\" d=\"M150.607 3.82108C150.542 3.82108 150.482 3.84458 150.442 3.88979C150.397 3.92958 150.374 3.99106 150.374 4.05436C150.374 4.17914 150.479 4.28402 150.607 4.28402C150.672 4.28402 150.728 4.26052 150.768 4.21531C150.813 4.17552 150.836 4.11946 150.836 4.05436C150.836 3.92596 150.732 3.82108 150.607 3.82108Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_109\" d=\"M150.885 2.66733C150.82 2.66733 150.761 2.69084 150.715 2.73605C150.67 2.78126 150.647 2.84093 150.647 2.90604C150.647 3.03986 150.755 3.14836 150.883 3.14836C150.952 3.14836 151.012 3.11943 151.057 3.07964C151.102 3.03443 151.126 2.97475 151.126 2.90604C151.126 2.77221 151.017 2.66914 150.883 2.66914L150.885 2.66733Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_110\" d=\"M150.84 2.04703C150.771 2.04703 150.712 2.07596 150.667 2.11936C150.621 2.16457 150.594 2.22425 150.594 2.29297C150.594 2.43041 150.703 2.53891 150.84 2.53891C150.909 2.53891 150.968 2.50998 151.014 2.46658C151.062 2.42137 151.086 2.36169 151.086 2.29297C151.086 2.15553 150.977 2.04703 150.84 2.04703Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_111\" d=\"M150.898 1.41953C150.764 1.41953 150.656 1.52803 150.656 1.66185C150.656 1.79567 150.764 1.90779 150.898 1.90779C151.032 1.90779 151.144 1.79929 151.144 1.66185C151.144 1.52441 151.035 1.41953 150.898 1.41953Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_112\" d=\"M150.285 1.24231C150.148 1.24231 150.039 1.35443 150.039 1.48825C150.039 1.62207 150.148 1.73419 150.285 1.73419C150.423 1.73419 150.527 1.62207 150.527 1.48825C150.527 1.35443 150.419 1.24231 150.285 1.24231Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_113\" d=\"M149.734 1.03613C149.669 1.03613 149.609 1.05964 149.564 1.10485C149.519 1.15006 149.492 1.20974 149.492 1.27484C149.492 1.40866 149.6 1.51717 149.734 1.51717C149.799 1.51717 149.859 1.48823 149.904 1.44483C149.949 1.40505 149.976 1.34356 149.976 1.27484C149.976 1.14102 149.868 1.03794 149.734 1.03794V1.03613Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_114\" d=\"M149.114 0.960205C149.054 0.960205 148.993 0.983714 148.953 1.02531C148.913 1.07052 148.884 1.12658 148.884 1.18987C148.884 1.31465 148.989 1.41954 149.114 1.41954C149.179 1.41954 149.235 1.3906 149.278 1.35082C149.318 1.30561 149.343 1.24955 149.343 1.18987C149.343 1.06148 149.242 0.960205 149.114 0.960205Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_115\" d=\"M148.534 0.875183C148.469 0.875183 148.413 0.898692 148.373 0.940285C148.328 0.985495 148.304 1.04156 148.304 1.10485C148.304 1.22963 148.409 1.33452 148.534 1.33452C148.599 1.33452 148.655 1.30558 148.695 1.2658C148.74 1.22601 148.763 1.16453 148.763 1.10485C148.763 0.976453 148.658 0.875183 148.534 0.875183Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_116\" d=\"M147.966 0.790192C147.901 0.790192 147.845 0.813701 147.805 0.855294C147.766 0.900504 147.737 0.956564 147.737 1.01624C147.737 1.14102 147.841 1.24229 147.966 1.24229C148.026 1.24229 148.084 1.21878 148.123 1.17719C148.163 1.13198 148.192 1.07592 148.192 1.01624C148.192 0.891462 148.087 0.790192 147.966 0.790192Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_117\" d=\"M147.429 0.750427C147.308 0.750427 147.212 0.846272 147.212 0.963818C147.212 1.08136 147.308 1.17721 147.429 1.17721C147.55 1.17721 147.643 1.08136 147.643 0.963818C147.643 0.846272 147.547 0.750427 147.429 0.750427Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_118\" d=\"M151.476 1.63654C151.408 1.63654 151.343 1.66547 151.299 1.70887C151.25 1.7577 151.223 1.81738 151.223 1.88971C151.223 2.02715 151.335 2.14289 151.476 2.14289C151.545 2.14289 151.61 2.11395 151.653 2.06693H151.657C151.702 2.02172 151.729 1.95843 151.729 1.88971C151.729 1.74866 151.617 1.63654 151.476 1.63654Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_119\" d=\"M152.057 1.74503C151.984 1.74503 151.923 1.77396 151.876 1.81736C151.831 1.86619 151.803 1.92587 151.803 1.9982C151.803 2.13564 151.916 2.25138 152.057 2.25138C152.125 2.25138 152.19 2.21883 152.234 2.17542C152.282 2.13021 152.31 2.06692 152.31 1.9982C152.31 1.85715 152.192 1.74503 152.057 1.74503Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_120\" d=\"M152.673 1.87344C152.592 1.87344 152.519 1.90599 152.467 1.95844C152.414 2.0145 152.378 2.08683 152.378 2.16821C152.378 2.32916 152.512 2.46298 152.673 2.46298C152.754 2.46298 152.83 2.42681 152.883 2.37437C152.935 2.32193 152.967 2.24959 152.967 2.16821C152.967 2.00726 152.834 1.87344 152.673 1.87344Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_121\" d=\"M153.282 2.18808C153.197 2.18808 153.121 2.22425 153.065 2.28031C153.009 2.33637 152.973 2.41413 152.973 2.49732C152.973 2.6673 153.114 2.80836 153.284 2.80836C153.369 2.80836 153.445 2.77219 153.501 2.71613C153.557 2.66007 153.593 2.58231 153.593 2.49912C153.593 2.32913 153.452 2.18808 153.282 2.18808Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_122\" d=\"M153.797 2.74869C153.624 2.74869 153.479 2.89336 153.479 3.06697C153.479 3.24057 153.624 3.38886 153.797 3.38886C153.971 3.38886 154.119 3.24419 154.119 3.06697C154.119 2.88974 153.974 2.74869 153.797 2.74869Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_123\" d=\"M154.086 3.48651C153.913 3.48651 153.775 3.62757 153.775 3.79756C153.775 3.96754 153.913 4.1086 154.086 4.1086C154.26 4.1086 154.392 3.96754 154.392 3.79756C154.392 3.62757 154.254 3.48651 154.086 3.48651Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_124\" d=\"M154.063 4.24243C153.915 4.24243 153.79 4.36721 153.79 4.5155C153.79 4.66379 153.915 4.78857 154.063 4.78857C154.211 4.78857 154.332 4.66379 154.332 4.5155C154.332 4.36721 154.211 4.24243 154.063 4.24243Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_125\" d=\"M153.886 4.86813C153.757 4.86813 153.649 4.97664 153.649 5.10503C153.649 5.23343 153.757 5.34193 153.886 5.34193C154.014 5.34193 154.122 5.23705 154.122 5.10503C154.122 4.97302 154.018 4.86813 153.886 4.86813Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_126\" d=\"M153.64 5.39618C153.512 5.39618 153.403 5.50468 153.403 5.6385C153.403 5.77233 153.512 5.8754 153.64 5.8754C153.768 5.8754 153.882 5.7669 153.882 5.6385C153.882 5.51011 153.774 5.39618 153.64 5.39618Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_127\" d=\"M151.2 3.23153C151.176 3.4612 151.118 3.68363 151.03 3.88436C150.934 4.10137 150.82 4.31476 150.692 4.50826C150.571 4.69272 150.433 4.86271 150.298 4.9911C150.274 5.02004 150.258 5.03993 150.262 5.06344C150.265 5.09237 150.285 5.12854 150.327 5.18098C150.339 5.19364 150.35 5.20449 150.363 5.21353C150.408 5.24247 150.459 5.23343 150.52 5.19726C150.589 5.15205 150.661 5.0761 150.733 4.98387C150.887 4.78675 151.039 4.50826 151.153 4.26232C151.297 3.9567 151.375 3.69087 151.411 3.41599C151.447 3.10133 151.431 2.78667 151.411 2.47382C151.399 2.33999 151.391 2.17181 151.254 2.15192C151.218 2.1483 151.202 2.18447 151.194 2.2333C151.187 2.2984 151.194 2.38159 151.202 2.43946C151.23 2.70167 151.234 2.97112 151.202 3.23334L151.2 3.23153Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_128\" d=\"M150.151 2.2767C150.22 2.50999 150.247 2.73965 150.24 2.96932C150.227 3.19898 150.184 3.42503 150.103 3.65108C150.057 3.77948 150.001 3.89341 149.938 4.00191C149.869 4.11041 149.797 4.2153 149.725 4.32019C149.656 4.41242 149.636 4.46848 149.649 4.49741C149.662 4.52635 149.701 4.54262 149.761 4.55709C149.935 4.59687 150.003 4.48114 150.076 4.35636C150.095 4.32381 150.115 4.28764 150.141 4.25147C150.363 3.92596 150.491 3.59141 150.54 3.25685C150.592 2.89879 150.556 2.53892 150.444 2.20075C150.424 2.13565 150.385 2.04704 150.327 1.98736C150.291 1.94757 150.251 1.91864 150.206 1.91864C150.11 1.92226 150.097 1.97832 150.088 2.03619C150.076 2.12118 150.128 2.1899 150.153 2.27851L150.151 2.2767Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_129\" d=\"M142.428 4.34369C142.549 4.34369 142.645 4.43953 142.645 4.5607C142.645 4.68186 142.549 4.78313 142.428 4.78313C142.368 4.78313 142.311 4.75962 142.271 4.71803C142.231 4.67824 142.206 4.62218 142.206 4.5607C142.206 4.43953 142.307 4.34369 142.428 4.34369Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_130\" d=\"M141.87 3.2442C141.935 3.2442 141.994 3.27314 142.039 3.31654C142.085 3.36175 142.112 3.42142 142.112 3.48653C142.112 3.62035 142.003 3.72885 141.87 3.72885C141.801 3.72885 141.741 3.69992 141.7 3.66013C141.654 3.61492 141.627 3.55525 141.627 3.48653C141.627 3.35271 141.736 3.2442 141.87 3.2442Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_131\" d=\"M142.103 3.82108C142.168 3.82108 142.227 3.84458 142.267 3.88979C142.312 3.92958 142.336 3.99106 142.336 4.05436C142.336 4.17914 142.231 4.28402 142.103 4.28402C142.038 4.28402 141.982 4.26052 141.942 4.21531C141.897 4.17552 141.873 4.11946 141.873 4.05436C141.873 3.92596 141.978 3.82108 142.103 3.82108Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_132\" d=\"M141.824 2.66733C141.889 2.66733 141.949 2.69084 141.994 2.73605C142.039 2.78126 142.063 2.84093 142.063 2.90604C142.063 3.03986 141.954 3.14836 141.826 3.14836C141.757 3.14836 141.698 3.11943 141.653 3.07964C141.607 3.03443 141.584 2.97475 141.584 2.90604C141.584 2.77221 141.692 2.66914 141.826 2.66914L141.824 2.66733Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_133\" d=\"M141.87 2.04703C141.938 2.04703 141.998 2.07596 142.043 2.11936C142.088 2.16457 142.115 2.22425 142.115 2.29297C142.115 2.43041 142.007 2.53891 141.87 2.53891C141.801 2.53891 141.741 2.50998 141.696 2.46658C141.647 2.42137 141.624 2.36169 141.624 2.29297C141.624 2.15553 141.732 2.04703 141.87 2.04703Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_134\" d=\"M141.812 1.41953C141.945 1.41953 142.054 1.52803 142.054 1.66185C142.054 1.79567 141.945 1.90779 141.812 1.90779C141.678 1.90779 141.566 1.79929 141.566 1.66185C141.566 1.52441 141.674 1.41953 141.812 1.41953Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_135\" d=\"M142.424 1.24231C142.562 1.24231 142.67 1.35443 142.67 1.48825C142.67 1.62207 142.562 1.73419 142.424 1.73419C142.287 1.73419 142.182 1.62207 142.182 1.48825C142.182 1.35443 142.291 1.24231 142.424 1.24231Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_136\" d=\"M142.976 1.03613C143.041 1.03613 143.1 1.05964 143.146 1.10485C143.191 1.15006 143.218 1.20974 143.218 1.27484C143.218 1.40866 143.109 1.51717 142.976 1.51717C142.911 1.51717 142.851 1.48823 142.806 1.44483C142.761 1.40505 142.734 1.34356 142.734 1.27484C142.734 1.14102 142.842 1.03794 142.976 1.03794V1.03613Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_137\" d=\"M143.596 0.960205C143.655 0.960205 143.717 0.983714 143.757 1.02531C143.796 1.07052 143.825 1.12658 143.825 1.18987C143.825 1.31465 143.72 1.41954 143.596 1.41954C143.531 1.41954 143.475 1.3906 143.435 1.35082C143.39 1.30561 143.366 1.24955 143.366 1.18987C143.366 1.06148 143.467 0.960205 143.596 0.960205Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_138\" d=\"M144.176 0.875183C144.241 0.875183 144.297 0.898692 144.337 0.940285C144.382 0.985495 144.405 1.04156 144.405 1.10485C144.405 1.22963 144.301 1.33452 144.176 1.33452C144.111 1.33452 144.055 1.30558 144.015 1.2658C143.97 1.22601 143.946 1.16453 143.946 1.10485C143.946 0.976453 144.051 0.875183 144.176 0.875183Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_139\" d=\"M144.743 0.790192C144.809 0.790192 144.865 0.813701 144.904 0.855294C144.944 0.900504 144.973 0.956564 144.973 1.01624C144.973 1.14102 144.868 1.24229 144.743 1.24229C144.684 1.24229 144.626 1.21878 144.586 1.17719C144.546 1.13198 144.518 1.07592 144.518 1.01624C144.518 0.891462 144.622 0.790192 144.743 0.790192Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_140\" d=\"M145.28 0.750427C145.401 0.750427 145.497 0.846272 145.497 0.963818C145.497 1.08136 145.401 1.17721 145.28 1.17721C145.159 1.17721 145.067 1.08136 145.067 0.963818C145.067 0.846272 145.163 0.750427 145.28 0.750427Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_141\" d=\"M141.233 1.63654C141.302 1.63654 141.367 1.66547 141.41 1.70887C141.459 1.7577 141.486 1.81738 141.486 1.88971C141.486 2.02715 141.374 2.14289 141.233 2.14289C141.165 2.14289 141.1 2.11395 141.056 2.06693H141.053C141.007 2.02172 140.98 1.95843 140.98 1.88971C140.98 1.74866 141.092 1.63654 141.233 1.63654Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_142\" d=\"M140.653 1.74503C140.725 1.74503 140.787 1.77396 140.834 1.81736C140.879 1.86619 140.906 1.92587 140.906 1.9982C140.906 2.13564 140.794 2.25138 140.653 2.25138C140.584 2.25138 140.519 2.21883 140.476 2.17542C140.427 2.13021 140.4 2.06692 140.4 1.9982C140.4 1.85715 140.518 1.74503 140.653 1.74503Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_143\" d=\"M140.037 1.87344C140.118 1.87344 140.19 1.90599 140.243 1.95844C140.295 2.0145 140.331 2.08683 140.331 2.16821C140.331 2.32916 140.198 2.46298 140.037 2.46298C139.955 2.46298 139.879 2.42681 139.827 2.37437C139.775 2.32193 139.742 2.24959 139.742 2.16821C139.742 2.00726 139.876 1.87344 140.037 1.87344Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_144\" d=\"M139.428 2.18808C139.513 2.18808 139.588 2.22425 139.644 2.28031C139.701 2.33637 139.737 2.41413 139.737 2.49732C139.737 2.6673 139.596 2.80836 139.426 2.80836C139.341 2.80836 139.265 2.77219 139.209 2.71613C139.153 2.66007 139.117 2.58231 139.117 2.49912C139.117 2.32913 139.258 2.18808 139.428 2.18808Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_145\" d=\"M138.912 2.74869C139.086 2.74869 139.231 2.89336 139.231 3.06697C139.231 3.24057 139.086 3.38886 138.912 3.38886C138.739 3.38886 138.591 3.24419 138.591 3.06697C138.591 2.88974 138.735 2.74869 138.912 2.74869Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_146\" d=\"M138.623 3.48651C138.797 3.48651 138.934 3.62757 138.934 3.79756C138.934 3.96754 138.797 4.1086 138.623 4.1086C138.45 4.1086 138.318 3.96754 138.318 3.79756C138.318 3.62757 138.455 3.48651 138.623 3.48651Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_147\" d=\"M138.647 4.24243C138.795 4.24243 138.92 4.36721 138.92 4.5155C138.92 4.66379 138.795 4.78857 138.647 4.78857C138.499 4.78857 138.377 4.66379 138.377 4.5155C138.377 4.36721 138.499 4.24243 138.647 4.24243Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_148\" d=\"M138.824 4.86813C138.952 4.86813 139.061 4.97664 139.061 5.10503C139.061 5.23343 138.952 5.34193 138.824 5.34193C138.696 5.34193 138.587 5.23705 138.587 5.10503C138.587 4.97302 138.692 4.86813 138.824 4.86813Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_149\" d=\"M139.07 5.39618C139.198 5.39618 139.306 5.50468 139.306 5.6385C139.306 5.77233 139.198 5.8754 139.07 5.8754C138.941 5.8754 138.828 5.7669 138.828 5.6385C138.828 5.51011 138.936 5.39618 139.07 5.39618Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_150\" d=\"M141.51 3.23153C141.533 3.4612 141.591 3.68363 141.68 3.88436C141.776 4.10137 141.889 4.31476 142.018 4.50826C142.139 4.69272 142.276 4.86271 142.412 4.9911C142.435 5.02004 142.452 5.03993 142.448 5.06344C142.444 5.09237 142.424 5.12854 142.383 5.18098C142.37 5.19364 142.359 5.20449 142.347 5.21353C142.302 5.24247 142.251 5.23343 142.189 5.19726C142.121 5.15205 142.048 5.0761 141.976 4.98387C141.823 4.78675 141.671 4.50826 141.557 4.26232C141.412 3.9567 141.335 3.69087 141.298 3.41599C141.262 3.10133 141.278 2.78667 141.298 2.47382C141.311 2.33999 141.318 2.17181 141.456 2.15192C141.492 2.1483 141.508 2.18447 141.515 2.2333C141.522 2.2984 141.515 2.38159 141.508 2.43946C141.479 2.70167 141.475 2.97112 141.508 3.23334L141.51 3.23153Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_151\" d=\"M142.558 2.2767C142.489 2.50999 142.462 2.73965 142.47 2.96932C142.482 3.19898 142.526 3.42503 142.607 3.65108C142.652 3.77948 142.708 3.89341 142.777 4.00191C142.842 4.11041 142.914 4.2153 142.987 4.32019C143.055 4.41242 143.075 4.46848 143.062 4.49741C143.05 4.52635 143.01 4.54262 142.95 4.55709C142.777 4.59687 142.708 4.48114 142.636 4.35636C142.616 4.32381 142.596 4.28764 142.571 4.25147C142.349 3.92596 142.22 3.59141 142.171 3.25685C142.119 2.89879 142.155 2.53892 142.267 2.20075C142.287 2.13565 142.327 2.04704 142.385 1.98736C142.421 1.94757 142.461 1.91864 142.506 1.91864C142.602 1.92226 142.614 1.97832 142.623 2.03619C142.636 2.12118 142.583 2.1899 142.558 2.27851V2.2767Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_152\" d=\"M139.673 5.87541C139.738 5.85914 139.807 5.85552 139.87 5.86275C139.923 5.86999 139.936 5.81393 139.91 5.77776C139.766 5.58426 139.637 5.37449 139.536 5.15748C139.415 4.9043 139.335 4.63847 139.31 4.36721C139.27 3.88799 139.447 3.42504 139.773 3.04166C139.572 3.13027 139.353 3.23877 139.193 3.4612C138.907 3.8482 138.934 4.3437 139.055 4.78676C139.16 5.15748 139.35 5.51192 139.579 5.83744C139.603 5.86999 139.635 5.88265 139.672 5.8736L139.673 5.87541Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_153\" d=\"M152.801 2.62752C152.745 2.59497 152.689 2.56784 152.628 2.53891C152.543 2.49912 152.422 2.59497 152.516 2.66007C152.588 2.71251 152.657 2.76857 152.725 2.83006C152.817 2.91505 152.995 2.74145 152.801 2.62933V2.62752Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_154\" d=\"M152.64 5.98393C152.564 6.07615 152.539 6.17742 152.555 6.24976C152.568 6.28593 152.592 6.31848 152.631 6.3221C152.687 6.3221 152.769 6.28231 152.861 6.17381C153.211 5.76692 153.51 5.29131 153.651 4.78858C153.763 4.37445 153.768 3.94586 153.595 3.53174C153.477 3.25325 153.309 3.02901 153.107 2.84636C152.989 2.75052 152.857 2.95125 152.937 3.04709C153.262 3.43047 153.436 3.89342 153.396 4.36903C153.372 4.63848 153.291 4.90431 153.17 5.1593C153.033 5.45768 152.839 5.73618 152.639 5.98573L152.64 5.98393Z\" fill=\"#FFE200\"><\/path><path id=\"Vector_155\" d=\"M143.54 3.13207C143.382 3.32557 143.137 3.35812 143.061 3.5914C143.025 3.69629 143.113 3.78128 143.198 3.80479C143.294 3.83735 143.343 3.69267 143.447 3.65651C143.402 3.70895 143.372 3.78128 143.399 3.82107C143.431 3.77224 143.458 3.73969 143.54 3.7198C143.411 3.90426 143.467 3.93681 143.563 3.92596C143.619 3.92234 143.655 3.8699 143.724 3.83735C143.72 3.85362 143.543 4.01818 143.688 4.03084C143.72 4.03446 143.825 3.98563 143.852 3.95851C143.845 4.02361 143.744 4.04712 143.84 4.09956C143.892 4.13211 143.957 4.07063 144.004 4.05074C143.887 4.21168 143.945 4.24423 144.017 4.22072C144.069 4.20083 144.113 4.14477 144.198 4.14477C144.149 4.18456 144.109 4.1936 144.109 4.24604C144.113 4.41603 144.27 4.40337 144.358 4.3871C144.293 4.43592 144.358 4.62942 144.387 4.63304C144.552 4.65293 144.593 4.6041 144.745 4.5607C144.968 4.49198 145.011 4.1936 145.007 3.81203C145.004 3.47747 144.962 3.13569 144.906 3.0308C144.837 3.01091 144.677 3.10314 144.677 3.20079C144.664 3.15558 144.637 3.11941 144.611 3.11941C144.559 3.12303 144.507 3.20079 144.463 3.22068C144.302 3.29302 144.44 3.07601 144.44 3.06335C144.214 3.05612 144.214 3.3744 144.214 3.04346C144.057 3.01995 143.952 3.34184 143.964 3.05974C143.863 2.97112 143.787 3.05612 143.728 3.12845C143.682 3.18451 143.643 3.23334 143.639 3.20983C143.632 3.16101 143.659 3.07601 143.652 3.0525C143.635 3.00729 143.551 3.12122 143.54 3.1375V3.13207Z\" fill=\"#E20613\"><\/path><path id=\"Vector_156\" d=\"M147.977 2.8807C147.997 3.02537 147.977 3.09409 147.957 3.17004C147.852 3.5046 148.006 3.81926 147.993 4.15743C148.122 4.23338 148.111 4.10498 148.151 4.0001C148.226 3.66554 148.541 4.51549 148.899 4.15743C149.016 4.00371 149.237 3.83915 149.466 3.85904C149.768 4.0435 149.636 3.18632 149.551 3.14111C149.519 3.12483 149.45 3.16462 149.45 3.15377C149.443 3.08143 149.414 3.03261 149.374 3.03261C149.302 3.01633 149.273 3.06877 149.257 3.14473C149.25 3.19717 149.192 3.161 149.197 3.04888C149.157 3.08505 149.128 3.161 149.112 3.17366C149.08 3.19717 149.119 3.17366 149.089 3.07782C149.06 2.98559 149.024 2.93314 148.987 3.09047C148.964 3.19174 148.843 3.35631 148.657 3.2478C148.572 3.19536 148.555 2.94219 148.423 2.91325C148.355 2.90059 148.407 2.98559 148.351 2.97835C148.335 2.97474 148.322 2.92953 148.292 2.90602C148.236 2.86623 148.315 2.92591 148.154 2.71614C148.013 2.54253 147.961 2.78847 147.977 2.8807Z\" fill=\"#E20613\"><\/path><path id=\"Vector_157\" d=\"M151.299 5.27141C151.214 5.27864 151.158 5.32023 151.138 5.39619C151.093 5.57341 151.391 5.52458 151.569 5.50107C151.854 5.4649 151.831 5.70723 151.995 5.64936C152.091 5.61681 152.04 5.23524 152.165 5.11408C152.23 5.0544 152.382 4.9893 152.407 4.92419C152.456 4.7958 152.362 4.68187 152.178 4.63485C152.102 4.61858 152.089 4.53901 151.977 4.54624C151.829 4.55347 151.78 4.67464 151.708 4.78856C151.652 4.87356 151.59 4.95855 151.491 4.99834C151.366 5.04717 151.353 5.17918 151.301 5.27321L151.299 5.27141Z\" fill=\"#E20613\"><\/path><path id=\"Vector_158\" d=\"M141.208 5.0526C141.385 5.2895 141.622 5.47576 141.776 5.4631C141.9 5.44321 141.965 5.29311 141.893 5.13217C141.739 4.78134 141.45 4.67645 141.441 4.2786C141.212 4.17372 140.953 4.2551 140.68 4.39073C140.346 4.63667 140.024 4.79761 139.457 4.73794C139.529 4.99111 139.646 5.23344 139.782 5.45587C139.939 5.45949 140.051 5.39077 140.077 5.25875C140.093 5.19004 140.149 5.06164 140.257 5.06164C140.181 5.1177 140.12 5.26237 140.198 5.29492C140.331 5.3546 140.398 4.98026 140.519 4.95314C140.487 5.02547 140.349 5.20631 140.496 5.20631C140.608 5.18642 140.601 4.98026 140.718 4.99292C140.734 5.05802 140.702 5.20993 140.794 5.20631C140.922 5.17376 140.883 4.9893 140.964 4.9893C140.944 5.17376 141.154 5.14302 141.21 5.05441L141.208 5.0526Z\" fill=\"#E20613\"><\/path><path id=\"Vector_159\" d=\"M148.953 7.6151C149.049 7.66392 149.219 7.67116 149.353 7.66754C149.602 7.66031 149.454 7.82487 149.611 7.82487C149.869 7.82487 150.063 8.12687 149.824 8.24442C149.768 8.27335 149.671 8.26793 149.566 8.26793C149.474 8.29686 149.756 8.4126 149.49 8.45238C149.389 8.46866 149.099 8.38366 149.099 8.56089C149.099 8.66216 148.798 8.72183 148.713 8.73449C147.959 8.83938 147.155 8.89182 146.358 8.89182C145.839 8.89182 145.315 8.86831 144.807 8.82672C144.633 8.81045 144.63 8.67301 144.46 8.62961C144.367 8.6061 144.246 8.61695 144.122 8.6061C143.843 8.57716 143.876 8.37281 143.623 8.4126C143.397 8.44877 143.176 8.30048 143.213 8.18655C143.236 8.12145 143.377 8.08528 143.587 8.06539C143.438 8.00571 143.478 8.02922 143.317 8.0256C143.128 8.02198 143.081 7.98943 143.133 7.93337C143.178 7.88816 143.464 7.8737 143.274 7.83753C142.988 7.78147 143.491 7.64765 143.543 7.62414C143.749 7.53553 143.926 7.40713 144.151 7.37096C144.899 7.25342 145.629 7.19736 146.358 7.19736C146.965 7.19736 147.574 7.23714 148.19 7.31852C148.46 7.35107 148.718 7.49936 148.955 7.6169L148.953 7.6151Z\" fill=\"#E20613\"><\/path><\/g><\/g><g id=\"Group_4\"><path id=\"Vector_160\" d=\"M54.8879 31.623C54.0673 31.142 53.0316 30.8653 51.7248 30.8653C49.3715 30.8653 47.7574 31.699 46.7886 33.4151C45.9409 34.9161 45.5631 37.0663 45.5631 40.3865C45.5631 43.7067 45.8487 45.9889 46.8898 47.5911C47.9996 49.4194 49.8631 50.1681 52.4984 50.1681C56.9882 50.1681 58.3493 47.4682 58.3493 41.1605C58.3493 36.4948 57.4708 32.9196 54.8879 31.6248V31.623ZM50.3529 41.1587V40.3268C50.3529 36.9704 50.7108 34.8112 52.1261 35.0065C52.8961 35.1132 53.2666 35.672 53.4456 36.6883C53.5612 37.5762 53.5829 38.7879 53.5829 40.3865C53.5829 43.0611 53.4528 44.5494 53.1491 45.3668C52.8943 46.0522 52.5346 46.2837 51.7248 46.2837C51.658 46.2837 51.5929 46.2801 51.5296 46.2728C50.5662 46.0793 50.3529 45.1751 50.3529 41.1605V41.1587Z\" fill=\"#ED1B24\"><\/path><path id=\"Vector_161\" d=\"M70.7053 50.0397C70.4269 46.8099 69.8395 43.1533 67.8223 41.6397C69.0333 40.882 70.0238 39.8964 70.0238 38.079C70.0238 36.7118 69.7021 35.4333 69.1074 34.4242C68.3375 32.4223 66.7523 31.1402 64.7876 31.1402H64.7062L64.6773 31.1456L62.1956 31.5633L59.3597 30.9955L58.9168 30.9069L58.9259 31.3572L59.0018 34.8347L58.9006 49.2639V49.6274H58.9186V49.6382L59.8531 50.0397H63.3126V42.0918C63.8061 42.213 64.2272 42.5403 64.5887 42.9906C65.4437 44.1245 65.901 46.0486 66.5499 49.3381L66.6005 49.5985C66.6005 49.6165 66.6023 49.6274 66.6023 49.6274H66.6059V49.6292C66.6547 49.6491 67.347 49.9475 67.4934 50.0397H70.6998H70.7053ZM63.2657 35.5816H64.22C65.1979 35.5816 65.5792 36.1802 65.5847 37.4262C65.5612 39.0465 64.7731 39.3919 64.1079 39.3919H63.3054L63.2675 35.5798L63.2657 35.5816Z\" fill=\"#ED1B24\"><\/path><path id=\"Vector_162\" d=\"M131.527 41.8404C131.502 41.8079 131.473 41.779 131.448 41.7464C132.545 40.967 133.57 39.7337 133.57 38.079C133.57 36.0717 132.881 33.9667 131.655 32.7153C130.81 31.7243 129.658 31.142 128.333 31.142H128.252L128.223 31.1474L125.741 31.5651L122.905 30.9973L122.463 30.9087L122.472 31.359L122.548 34.8365L122.446 49.2657V49.2693L122.416 49.6147L122.445 49.6274V49.631H122.452L123.401 50.0415H126.86V42.0936C127.345 42.213 127.76 42.5294 128.116 42.9671C128.984 44.0973 129.443 46.0251 130.096 49.3399L130.153 49.631V49.6346C130.153 49.6346 130.858 49.9366 131.041 50.0433H134.247C133.993 47.0667 133.217 43.5078 131.525 41.8441L131.527 41.8404ZM131.169 41.9779C131.155 41.9797 131.139 41.9779 131.122 41.9652C131.129 41.9598 131.137 41.9544 131.146 41.9508C131.153 41.9598 131.162 41.9688 131.169 41.9779ZM129.13 37.3574C129.13 39.0392 128.326 39.3937 127.65 39.3937H126.848L126.81 35.5816H127.937C128.65 35.5816 128.986 36.2163 129.12 37.0446C129.127 37.1495 129.132 37.2525 129.132 37.3574H129.13Z\" fill=\"#ED1B24\"><\/path><path id=\"Vector_163\" d=\"M118.087 31.9431L117.59 30.9448V30.9394L117.581 30.9467L117.261 30.9955L115.296 31.2903L113.483 31.0208L113.19 30.9774L113.089 31.2541L112.988 31.5308C112.793 32.0878 111.374 38.3086 109.948 44.8496L109.114 48.6852L109.013 49.1952L108.926 49.6256H108.93L109.958 50.0361H113.494L114.074 47.2349C114.099 47.1083 114.15 47.007 114.175 46.9329C114.929 46.5459 115.992 46.3488 116.973 46.5549L117.85 49.3724L117.929 49.6274H117.937V49.631L118.788 50.0379H122.323L118.087 31.9413V31.9431ZM115.542 40.1442C115.789 41.457 116.019 42.618 116.234 43.638C115.9 43.5313 115.585 43.4752 115.3 43.4336L115.242 43.4246L115.184 43.4354C115.059 43.4571 114.942 43.4843 114.824 43.515C115.077 42.3486 115.319 41.2057 115.54 40.1442H115.542Z\" fill=\"#ED1B24\"><\/path><path id=\"Vector_164\" d=\"M108.265 41.0665C108.265 41.0665 108.265 41.0665 108.263 41.0646C108.079 40.8567 107.869 40.6686 107.636 40.4986C108.944 39.7463 109.393 38.589 109.393 36.9686C109.393 34.7027 108.145 32.3608 106.155 31.6031C105.478 31.2993 104.713 31.1402 103.903 31.1402H103.822L103.791 31.1456L101.335 31.5633L98.5007 30.9955L98.0579 30.9069L98.0669 31.3572L98.1428 34.8347L98.0416 49.2621V49.6256H98.0471V49.6364L98.9942 50.0379H104.42C107.119 50.0379 109.741 48.5749 109.741 45.2438C109.741 43.6452 108.982 41.8242 108.259 41.0646L108.265 41.0665ZM105.763 44.4735C105.763 45.7665 104.682 46.6345 103.074 46.6345H102.459V42.0195C104.737 42.2202 105.469 42.958 105.72 43.9346C105.749 44.1027 105.763 44.28 105.763 44.4717V44.4735ZM104.957 37.3574C104.957 38.522 104.326 39.1911 103.226 39.1911H102.459V35.5816H103.242C103.976 35.5816 104.605 35.9722 104.879 36.6938C104.928 36.9071 104.957 37.1314 104.957 37.3574Z\" fill=\"#ED1B24\"><\/path><path id=\"Vector_165\" d=\"M44.5889 34.2072C44.3973 33.7009 44.1569 33.2506 43.8659 32.8581C43.0308 31.7351 41.7981 31.142 40.3033 31.142H40.2202L40.1876 31.1474L37.9608 31.5633L35.1285 30.9973L34.6856 30.9087L34.6947 31.359L34.7706 34.8365L34.6694 49.2639V49.6274H34.673V49.6364L35.8045 50.0379H39.0833V43.6036H40.8745C44.0014 43.6036 45.5396 41.2816 45.5396 38.4063C45.5396 36.6323 45.2034 35.2235 44.5889 34.2054V34.2072ZM41.1022 37.7354C41.1022 38.9362 40.6449 40.1496 39.6219 40.1496H39.0724L39.0326 35.5816H39.9852C40.5853 35.5816 40.8907 36.2037 41.0408 36.9759C41.0787 37.2272 41.1022 37.484 41.1022 37.7372V37.7354Z\" fill=\"#ED1B24\"><\/path><path id=\"Vector_166\" d=\"M33.5723 42.9399C33.0192 41.4354 31.8515 40.4136 30.7869 39.4841C30.0513 38.8421 29.3717 38.249 28.9144 37.56C28.8041 37.2164 28.7372 36.8475 28.7372 36.4388C28.7372 35.6648 28.8854 35.021 29.2885 34.804C29.3518 35.0535 29.3933 35.4261 29.3933 35.9957C29.3933 36.5147 29.3229 36.8294 29.2108 37.1675L29.068 37.5943H29.0716C29.0716 37.5943 29.068 37.5998 29.068 37.6016L29.9627 38.0555L33.6283 38.4081C33.6283 38.4081 33.9301 37.5509 33.9301 36.3899C33.9301 35.3302 33.8 34.2705 33.2397 33.4585C33.1168 33.0824 32.9451 32.7171 32.6974 32.3843C31.9383 31.3626 30.6694 30.8671 28.8204 30.8671C25.7241 30.8671 24.0197 32.7514 24.0197 36.1747C24.0197 39.1206 25.838 40.6776 27.4431 42.0502C28.6776 43.1063 29.744 44.0196 29.744 45.3596C29.744 45.5115 29.7241 46.8407 29.021 46.8407C28.7806 46.8407 28.5836 46.7846 28.4263 46.6761C28.4137 46.5694 28.4065 46.4555 28.4065 46.3343V44.1552L27.9962 43.421H27.9943L27.6762 43.3848L24.3975 43.0069L23.9944 42.9598V44.8804C23.9944 45.1679 24.0107 45.4373 24.036 45.6977C24.0667 48.2186 26.1652 50.1699 29.7187 50.1699C33.2722 50.1699 34.3097 48.2765 34.3097 45.6019C34.3097 44.5313 34.0187 43.6742 33.5704 42.9418L33.5723 42.9399Z\" fill=\"#ED1B24\"><\/path><path id=\"Vector_167\" d=\"M91.1913 42.9399C90.6382 41.4354 89.4705 40.4136 88.4059 39.4841C87.6703 38.8421 86.9907 38.249 86.5334 37.56C86.4231 37.2164 86.3562 36.8475 86.3562 36.4388C86.3562 35.663 86.5045 35.021 86.9075 34.804C86.9708 35.0535 87.0124 35.4261 87.0124 35.9957C87.0124 36.5147 86.9419 36.8294 86.8298 37.1675L86.687 37.5943H86.6906C86.6906 37.5943 86.687 37.5998 86.687 37.6016L87.5817 38.0555L91.2473 38.4081C91.2473 38.4081 91.5492 37.5509 91.5492 36.3899C91.5492 35.3302 91.419 34.2705 90.8587 33.4585C90.7358 33.0824 90.5641 32.7171 90.3165 32.3843C89.5573 31.3626 88.2885 30.8671 86.4394 30.8671C83.3432 30.8671 81.6387 32.7514 81.6387 36.1747C81.6387 39.1206 83.457 40.6776 85.0621 42.0502C86.2966 43.1063 87.363 44.0196 87.363 45.3596C87.363 45.5115 87.3431 46.8407 86.64 46.8407C86.3996 46.8407 86.2026 46.7846 86.0454 46.6761C86.0327 46.5694 86.0255 46.4555 86.0255 46.3343V44.1552L85.6152 43.421H85.6134L85.2953 43.3848L82.0165 43.0069L81.6134 42.9598V44.8804C81.6134 45.1679 81.6297 45.4373 81.655 45.6977C81.6857 48.2186 83.7842 50.1699 87.3377 50.1699C90.8912 50.1699 91.9287 48.2765 91.9287 45.6019C91.9287 44.5313 91.6377 43.6742 91.1895 42.9418L91.1913 42.9399Z\" fill=\"#ED1B24\"><\/path><path id=\"Vector_168\" d=\"M81.4273 30.981V30.972L81.0115 30.9901L75.3035 31.2414L70.1504 30.9901L69.731 30.9702L69.7726 31.3879L70.3022 36.7118L70.4233 37.9253V37.9198L70.4251 37.9235L71.0848 38.5618C71.5963 37.5726 72.379 36.2236 73.2357 35.3827L73.3261 49.2711V49.631H73.3388V49.6382L74.2787 50.0433H78.2425L78.3437 34.6503C79.0341 34.8112 79.6686 35.8076 80.106 36.6919C80.1259 36.7353 80.1439 36.7769 80.1638 36.8222L80.6681 37.9994C80.6952 38.0736 80.7097 38.117 80.7097 38.117C80.7097 38.117 81.1091 38.5166 81.261 38.6703L81.796 32.1276L81.4236 30.9828L81.4273 30.981Z\" fill=\"#ED1B24\"><\/path><path id=\"Vector_169\" d=\"M51.7248 31.2252C46.9097 31.2252 45.9246 34.8872 45.9246 40.3847C45.9246 43.7736 46.2879 45.893 47.1031 47.2548C47.9761 48.7141 49.4456 49.3941 51.7248 49.3941C55.9905 49.3941 57.5757 46.9528 57.5757 40.3865C57.5757 33.8202 55.826 31.227 51.7248 31.227V31.2252ZM51.7248 46.6435C50.3349 46.6435 49.5812 45.6471 49.5812 40.3865V39.5546C49.5812 36.1711 49.6806 34.256 51.7248 34.256C53.7691 34.256 53.9444 36.2471 53.9444 40.3883C53.9444 45.7827 53.4166 46.6453 51.7248 46.6453V46.6435Z\" fill=\"#F2F1F0\"><\/path><path id=\"Vector_170\" d=\"M66.9059 49.2675H69.9316C69.5141 44.4156 68.1042 42.2817 66.9963 41.3449L66.8137 41.1912L67.0107 41.0574C67.8476 40.4859 69.2502 39.2382 69.2502 37.3068C69.2502 33.9432 67.3722 31.5037 64.7857 31.5037H64.7351L62.1883 31.9322L59.2873 31.3517L59.3632 34.8293L59.262 49.2675H62.5408V41.3142L62.7704 41.3793C65.2791 42.0954 65.8666 44.0015 66.9041 49.2675H66.9059ZM62.492 34.8094H64.4585C65.4346 34.8094 65.9461 36.0915 65.9461 37.3574C65.9461 38.8801 65.2755 39.7554 64.1043 39.7554H62.5408L62.4902 34.8094H62.492Z\" fill=\"#F2F1F0\"><\/path><path id=\"Vector_171\" d=\"M130.45 49.2675H133.476C133.058 44.4156 131.648 42.2817 130.54 41.3449L130.358 41.1912L130.555 41.0574C131.392 40.4859 132.794 39.2382 132.794 37.3068C132.794 33.9432 130.916 31.5037 128.33 31.5037H128.279L125.732 31.9322L122.831 31.3517L122.907 34.8293L122.806 49.2675H126.085V41.3142L126.314 41.3793C128.823 42.0954 129.411 44.0015 130.448 49.2675H130.45ZM126.036 34.8094H128.002C128.979 34.8094 129.49 36.0915 129.49 37.3574C129.49 38.8801 128.819 39.7554 127.648 39.7554H126.085L126.034 34.8094H126.036Z\" fill=\"#F2F1F0\"><\/path><path id=\"Vector_172\" d=\"M113.376 46.2385L113.402 46.1734L113.469 46.1318C114.029 45.8587 114.728 45.7014 115.384 45.7014C116.041 45.7014 116.671 45.8569 117.176 46.1516L117.237 46.1878L118.195 49.2675H121.55L117.313 31.3517L115.296 31.6537L113.429 31.3771L113.328 31.6574C113.141 32.1872 111.699 38.5148 110.302 44.9274L109.469 48.7648L109.367 49.2657H112.722L113.302 46.4627C113.32 46.3759 113.351 46.2981 113.375 46.2366L113.376 46.2385ZM113.783 43.9743C114.275 41.7283 114.746 39.5058 115.108 37.7155L115.296 36.786L115.464 37.7191C115.91 40.2129 116.301 42.2292 116.655 43.8839L116.727 44.2221L116.408 44.0883C115.986 43.911 115.587 43.8423 115.244 43.7899C114.783 43.8695 114.37 44.0304 114.029 44.1769L113.705 44.3161L113.781 43.9725L113.783 43.9743Z\" fill=\"#F2F1F0\"><\/path><path id=\"Vector_173\" d=\"M108.975 44.4735C108.975 42.3287 108.194 40.9977 106.521 40.2852L106.164 40.1333L106.51 39.9579C107.932 39.2309 108.623 38.0012 108.623 36.1982C108.623 33.435 106.683 31.5055 103.907 31.5055H103.856L101.335 31.934L98.4339 31.3535L98.5098 34.8311L98.4086 49.2693H103.654C105.082 49.2693 106.387 48.8624 107.327 48.121C108.406 47.271 108.975 46.0106 108.975 44.4753V44.4735ZM101.686 34.8094H103.578C104.603 34.8094 105.319 36.153 105.319 37.3574C105.319 38.7119 104.516 39.5528 103.226 39.5528H101.687V34.8094H101.686ZM103.074 46.9962H101.687V41.0646L101.886 41.0845C104.738 41.3793 106.127 42.4878 106.127 44.4716C106.127 45.9581 104.872 46.9944 103.075 46.9944L103.074 46.9962Z\" fill=\"#F2F1F0\"><\/path><path id=\"Vector_174\" d=\"M40.3033 31.5037H40.2527L37.9572 31.9322L35.0562 31.3517L35.1321 34.8293L35.0309 49.2675H38.3097V42.8332H40.1009C42.935 42.8332 44.766 40.7934 44.766 37.6359C44.766 33.7388 43.1393 31.5037 40.3015 31.5037H40.3033ZM39.6219 40.5113H38.3097L38.2591 34.8094H39.9744C40.9902 34.8094 41.4619 36.5563 41.4619 37.7372C41.4619 39.1188 40.8926 40.5131 39.6201 40.5131L39.6219 40.5113Z\" fill=\"#F2F1F0\"><\/path><path id=\"Vector_175\" d=\"M30.5483 39.7572C29.2198 38.598 27.9654 37.5039 27.9654 35.6666C27.9654 34.2488 28.4462 33.9504 28.8475 33.9504C29.4928 33.9504 29.7549 34.5418 29.7549 35.9939C29.7549 36.5617 29.6771 36.9071 29.5524 37.2815L32.8565 37.6341C32.8692 37.5979 33.1584 36.7643 33.1584 35.6159C33.1584 33.4441 32.6432 31.2252 28.8204 31.2252C26.796 31.2252 24.3812 32.0841 24.3812 36.1711C24.3812 38.9506 26.1327 40.4498 27.6781 41.7717C28.9813 42.8857 30.1055 43.8496 30.1055 45.356C30.1055 46.2059 29.8217 47.1987 29.021 47.1987C28.1263 47.1987 27.6347 46.6164 27.6347 45.5585V43.7411L24.3559 43.3631V44.8767C24.3559 47.9582 25.8145 49.3941 28.9469 49.3941C32.0793 49.3941 33.5379 47.8154 33.5379 44.8261C33.5379 42.3649 32.0178 41.0393 30.5465 39.7554L30.5483 39.7572Z\" fill=\"#F2F1F0\"><\/path><path id=\"Vector_176\" d=\"M88.1674 39.7572C86.8389 38.598 85.5845 37.5039 85.5845 35.6684C85.5845 34.2506 86.0653 33.9522 86.4665 33.9522C87.1118 33.9522 87.3739 34.5436 87.3739 35.9957C87.3739 36.5635 87.2962 36.9089 87.1714 37.2833L90.4755 37.6359C90.4882 37.5997 90.7774 36.7643 90.7774 35.6177C90.7774 33.4459 90.2622 31.227 86.4394 31.227C84.415 31.227 82.0002 32.0859 82.0002 36.1729C82.0002 38.9524 83.7517 40.4516 85.2971 41.7735C86.6003 42.8875 87.7245 43.8514 87.7245 45.3578C87.7245 46.2077 87.4408 47.2005 86.64 47.2005C85.7453 47.2005 85.2537 46.6182 85.2537 45.5603V43.7429L81.9749 43.3649V44.8785C81.9749 47.96 83.4336 49.3959 86.5659 49.3959C89.6983 49.3959 91.1569 47.8588 91.1569 44.8279C91.1569 42.3667 89.6368 41.0411 88.1656 39.7572H88.1674Z\" fill=\"#F2F1F0\"><\/path><path id=\"Vector_177\" d=\"M80.4964 36.6757L81.026 31.3517L75.3179 31.6049L70.1304 31.3517L70.66 36.6757C71.4119 35.2235 72.2904 34.332 73.3441 33.9522L73.5845 33.8654L73.6858 49.2675H77.4688L77.57 33.869L77.7996 33.9359C79.0016 34.2868 79.833 35.1331 80.4946 36.6775L80.4964 36.6757Z\" fill=\"#F2F1F0\"><\/path><\/g><\/g><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11c166f elementor-widget elementor-widget-text-editor\" data-id=\"11c166f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Come to Mallorca Sports Bar and enjoy sports your way! Each table has its own personalized screen so you can choose your favorite sport while savoring our delicious gourmet burgers at Estadi Mallorca Son Moix. The best atmosphere for sports and food lovers awaits you!  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6d228d elementor-widget elementor-widget-button\" data-id=\"c6d228d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/mallorcasportsbar.es\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">MAKE A RESERVATION<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dceef64 e-con-full e-flex e-con e-child\" data-id=\"dceef64\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_scale_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_scale_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:2,&quot;sizes&quot;:[]},&quot;background_motion_fx_scale_direction&quot;:&quot;out-in&quot;,&quot;background_motion_fx_scale_range&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:20,&quot;end&quot;:80}},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e970704 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"e970704\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-54021a6 e-con-full e-flex e-con e-child\" data-id=\"54021a6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6a4143a e-con-full e-flex e-con e-child\" data-id=\"6a4143a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-faa4eb8 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"faa4eb8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"388\" height=\"512\" viewBox=\"0 0 388 512\" fill=\"none\"><path d=\"M363.158 344.23C367.708 340.909 371.288 338.118 374.534 334.796C377.779 331.474 380.585 327.773 383.376 322.51C385.257 318.991 386.304 315.23 387.927 311.59C382.466 312.697 377.006 314.123 372.258 317.247C372.85 315.943 373.229 314.653 373.563 313.349C373.957 311.726 374.154 310.164 374.078 308.602C374.215 308.465 374.336 308.283 374.473 308.146C375.064 307.373 375.58 306.721 376.293 306.19C377.658 305.083 379.023 303.975 380.191 302.61C381.814 302.61 383.058 302.413 384.028 301.958C385.136 301.503 385.909 300.729 386.44 299.683C386.895 298.773 387.032 297.999 386.956 297.408C386.819 296.437 386.106 295.845 385.136 295.845C384.362 295.785 383.376 296.103 382.406 296.756C380.722 297.802 380.191 299.091 379.615 300.654C378.902 302.671 377.142 303.9 375.519 305.143C374.867 305.659 374.351 306.19 373.896 306.827C373.244 303.247 374.291 298.955 375.262 294.996C375.656 293.312 376.035 291.553 376.49 289.794C374.215 291.098 372.334 292.782 370.378 294.48C371.545 292.463 372.516 290.385 373.366 288.231C374.791 284.849 375.777 281.345 376.429 277.826C377.142 274.125 377.658 270.546 378.841 266.966C374.609 269.575 370.711 272.366 367.268 275.945C367.587 274.323 367.723 272.76 367.663 271.137C367.663 270.622 367.663 270.167 367.602 269.636C368.512 268.786 369.285 267.876 370.014 266.906C370.742 265.935 371.318 264.949 371.834 263.842C372.683 263.902 373.457 263.644 374.169 263.129C374.882 262.537 375.535 261.703 375.792 260.656C376.05 259.61 375.929 258.579 375.535 257.729C375.14 256.88 374.427 256.228 373.517 256.045C372.547 255.848 371.637 256.045 370.787 256.637C370.074 257.153 369.483 258.063 369.225 259.109C368.967 260.156 369.028 261.187 369.422 262.037C369.68 262.628 370.074 263.083 370.59 263.402C370.135 264.373 369.619 265.283 368.967 266.193C368.512 266.845 367.996 267.421 367.405 268.013C367.208 266.708 366.889 265.343 366.434 264.039C365.721 261.824 365.585 259.428 365.782 257.077C365.979 254.21 366.828 251.48 367.541 248.629C365.13 249.933 362.991 251.419 360.913 253.179C358.835 254.938 356.939 256.88 355.316 259.034C354.603 256.364 353.238 254.605 351.539 253.437C349.78 252.208 347.702 251.677 345.563 251.556C347.186 247.855 348.809 244.275 350.508 240.696C351.357 238.815 352.192 236.919 352.586 236.085C354.467 231.929 354.406 228.744 353.754 224.315C352.783 218.339 347.126 209.951 340.482 201.624C337.16 197.392 333.52 193.175 330.214 189.262C327.089 185.622 324.238 182.3 322.144 179.57C320.976 178.068 319.611 176.248 317.988 174.959C316.305 173.533 314.348 172.684 312.073 173.139C309.859 173.533 308.236 175.475 308.433 177.75C308.569 179.434 309.859 180.738 311.618 180.875C311.755 182.497 311.557 183.863 311.026 185.167C309.661 188.868 306.142 191.022 302.32 191.537C299.727 191.856 296.921 191.537 294.327 190.764C293.28 190.506 292.31 190.051 291.263 189.596C288.275 188.17 285.348 185.956 282.739 183.347C279.038 179.57 275.974 174.959 274.29 170.606C273.062 167.481 272.41 164.175 272.667 160.793C272.865 157.865 273.714 154.938 275.534 152.01C276.384 150.645 278.067 150.509 279.629 150.448C281.51 150.387 283.27 150.312 284.058 148.37C284.574 147.066 284.316 145.64 283.406 144.533C282.435 143.228 280.812 142.455 279.174 142.394C279.629 142.136 280.024 141.878 280.342 141.545C280.797 141.09 281.055 140.635 281.252 140.043C281.45 139.527 281.51 138.936 281.389 138.36C281.252 137.586 280.934 136.858 280.221 136.221C280.737 134.537 281.268 132.778 282.435 131.534C283.406 130.487 284.058 129.577 284.453 128.804H284.847C285.894 128.804 287.062 128.607 288.032 128.152C289.079 127.636 289.989 126.847 290.368 125.74C290.565 125.346 290.687 124.83 290.687 124.238C290.687 123.526 290.944 122.737 291.278 121.903C291.93 120.538 292.962 119.172 294.145 118.065C295.116 117.216 296.101 116.503 297.133 116.109C298.104 115.714 299.09 115.654 299.924 115.911C300.697 116.23 301.486 116.882 302.062 117.989C301.092 119.809 301.607 122.085 303.291 123.253C305.308 124.678 307.978 123.965 309.009 121.69C310.571 118.369 309.722 114.349 307.508 111.346C307.963 109.981 308.675 108.934 309.464 108.1C310.177 108.419 310.89 108.616 311.679 108.616C314.545 108.616 316.821 106.28 316.821 103.474C316.821 102.109 316.365 100.941 315.516 100.031H315.653C318.443 100.031 320.794 97.7557 320.794 94.889C320.794 93.3874 320.082 91.9616 319.035 91.0515C321.902 90.7937 324.177 88.3214 324.177 85.394C324.177 82.8003 322.417 80.5859 319.945 79.9336C322.933 79.4179 325.148 76.8091 325.148 73.7604C325.148 70.3173 322.357 67.5113 318.898 67.5113C318.246 67.5113 317.731 67.572 317.139 67.7085C319.217 66.6619 320.643 64.5233 320.643 61.9903C320.643 58.4714 317.776 55.5592 314.212 55.5592C313.044 55.5592 311.937 55.8777 310.966 56.4692C311.739 55.4227 312.134 54.1941 312.134 52.829C312.134 49.3859 309.343 46.5799 305.885 46.5799C304.459 46.5799 303.154 47.035 302.108 47.8843V47.49C302.108 44.1683 299.378 41.4381 296.056 41.4381C294.433 41.4381 292.931 42.151 291.824 43.2582C291.627 43.3947 291.506 43.5767 291.369 43.7132C291.309 43.5767 291.308 43.4554 291.233 43.3189C290.641 41.0437 288.563 39.3601 286.091 39.3601C284.589 39.3601 283.224 39.9517 282.253 40.9224C282.117 41.1196 281.996 41.2409 281.859 41.4381C281.207 39.2236 279.129 37.6007 276.717 37.6007C275.216 37.6007 273.926 38.1922 272.94 39.1629C272.804 39.2994 272.683 39.4208 272.622 39.5573V39.2994C272.622 36.4328 270.286 34.0969 267.359 34.0969C265.281 34.0969 263.461 35.3255 262.611 37.1456C262.672 36.9485 262.672 36.6906 262.672 36.4934C262.672 33.6267 260.336 31.2909 257.469 31.2909C255.968 31.2909 254.679 31.8825 253.693 32.8532C253.556 30.123 251.281 27.9085 248.551 27.9085C247.125 27.9085 245.821 28.5001 244.911 29.4101C244.258 30.123 243.743 30.9724 243.545 31.9431V31.6853C243.545 28.8944 241.27 26.6799 238.54 26.6799C237.175 26.6799 235.946 27.2715 235.021 28.1057C234.627 28.5001 234.308 28.9551 234.111 29.4708C233.793 27.59 232.428 26.0884 230.592 25.4969C230.137 25.3603 229.682 25.2997 229.167 25.2997C227.801 25.2997 226.573 25.8912 225.663 26.8013C225.344 27.1198 225.011 27.5142 224.813 27.9085C224.358 25.694 222.341 23.9346 220.005 23.9346C218.64 23.9346 217.412 24.5261 216.486 25.4362C216.229 25.694 215.971 26.0277 215.773 26.3463C215.061 24.5261 213.362 23.2975 211.345 23.2975C208.675 23.2975 206.536 25.512 206.597 28.1057C205.171 28.1057 203.867 27.8478 202.562 27.3321C203.078 26.1642 203.412 24.7991 203.412 23.4341C203.412 18.7472 199.969 14.7885 195.479 14.0756V9.19161H201.197V6.06707H195.479V0H192.491V6.11257H186.773V9.23711H192.491V14.1211C188.001 14.834 184.558 18.8079 184.558 23.4796C184.558 24.8446 184.877 26.2097 185.408 27.3777C184.103 27.8934 182.814 28.1512 181.373 28.1512C181.434 25.5575 179.295 23.3431 176.626 23.3431C174.608 23.3431 172.925 24.5716 172.197 26.3918C172 26.0732 171.742 25.7395 171.484 25.4817C170.574 24.5716 169.345 23.9801 167.965 23.9801C165.629 23.9801 163.612 25.7395 163.157 27.954C162.96 27.5597 162.641 27.1805 162.307 26.8468C161.397 25.9367 160.169 25.3452 158.789 25.3452C158.47 25.3452 158.136 25.4059 157.818 25.4817C155.801 25.8761 154.238 27.4383 153.844 29.5163C153.647 29.0006 153.328 28.5456 152.934 28.1512C152.024 27.3018 150.795 26.7254 149.415 26.7254C146.685 26.7254 144.41 28.9399 144.41 31.7308V31.9886C144.212 31.0179 143.697 30.1685 143.044 29.4556C142.134 28.5456 140.83 27.954 139.404 27.954C136.674 27.954 134.399 30.1685 134.262 32.8987C133.292 31.928 131.987 31.3364 130.486 31.3364C127.619 31.3364 125.283 33.6722 125.283 36.5389C125.283 36.7361 125.283 36.994 125.344 37.1911C124.494 35.371 122.674 34.1424 120.596 34.1424C117.669 34.1424 115.333 36.4783 115.333 39.3449V39.6028C115.272 39.4663 115.136 39.3449 115.015 39.2084C114.044 38.2377 112.739 37.6462 111.238 37.6462C108.826 37.6462 106.748 39.2691 106.096 41.4836C105.96 41.2864 105.838 41.1651 105.702 40.9679C104.731 39.9972 103.366 39.4056 101.864 39.4056C99.2706 39.4056 97.0561 41.2864 96.6011 43.7587C96.4646 43.5616 96.2826 43.4402 96.146 43.3037C95.0388 42.1965 93.5524 41.4836 91.9143 41.4836C88.5925 41.4836 85.8624 44.2138 85.8624 47.5355C85.8624 47.672 85.8624 47.7933 85.923 47.9298C84.8158 47.0805 83.5114 46.6254 82.0856 46.6254C78.6426 46.6254 75.8365 49.4163 75.8365 52.8745C75.8365 54.2396 76.2309 55.4682 77.0044 56.5148C76.0337 55.9232 74.9265 55.6047 73.7586 55.6047C70.179 55.6047 67.3275 58.5321 67.3275 62.0358C67.3275 64.5688 68.7532 66.7226 70.8312 67.754C70.2397 67.6175 69.724 67.5568 69.0717 67.5568C65.6287 67.5568 62.8227 70.3477 62.8227 73.8059C62.8227 76.8698 65.0371 79.4634 68.0252 79.9791C65.6135 80.6314 63.7934 82.8458 63.7934 85.4395C63.7934 88.3669 66.0685 90.8392 68.9352 91.0971C67.8887 92.0071 67.1758 93.4329 67.1758 94.9345C67.1758 97.8012 69.5116 100.076 72.3176 100.076H72.4541C71.6047 100.986 71.1497 102.154 71.1497 103.519C71.1497 106.31 73.4249 108.661 76.2916 108.661C77.0651 108.661 77.8538 108.464 78.506 108.146C79.2796 108.919 79.9318 109.905 80.3868 111.209C79.2796 112.635 78.5667 114.334 78.3089 116.154C78.1117 117.974 78.1117 120.052 78.9004 121.751C79.8711 124.026 82.6013 124.739 84.6186 123.313C86.3022 122.145 86.8331 119.87 85.8472 118.05C86.4387 116.943 87.2123 116.291 87.9858 115.972C88.8352 115.714 89.806 115.775 90.7767 116.169C91.8233 116.564 92.794 117.276 93.7647 118.126H93.7041C94.9326 119.172 95.9185 120.538 96.5707 121.827C96.9651 122.676 97.2229 123.586 97.2229 124.299C97.2229 124.891 97.3595 125.406 97.4808 125.801C97.9358 126.908 98.8459 127.681 99.8925 128.212C100.863 128.667 102.031 128.865 103.078 128.865H103.533C103.927 129.638 104.579 130.548 105.55 131.595C106.779 132.823 107.234 134.583 107.764 136.282C107.052 136.934 106.718 137.647 106.597 138.42C106.46 139.012 106.536 139.588 106.733 140.104C106.93 140.695 107.249 141.15 107.643 141.605C107.962 141.924 108.356 142.197 108.811 142.455C107.188 142.515 105.565 143.304 104.519 144.593C103.669 145.701 103.351 147.126 103.866 148.431C104.716 150.387 106.46 150.448 108.356 150.509C109.918 150.57 111.541 150.706 112.451 152.071C114.211 154.998 115.121 157.926 115.318 160.853C115.515 164.236 114.863 167.557 113.695 170.667C112.011 175.02 108.948 179.646 105.171 183.408C102.577 186.001 99.5739 188.216 96.5859 189.717C95.6152 190.172 94.5686 190.567 93.5979 190.825C91.0042 191.598 88.1982 191.932 85.6652 191.598C81.7671 191.082 78.324 188.929 76.8831 185.228C76.4281 183.923 76.1702 182.558 76.2916 180.935C78.1117 180.799 79.3403 179.509 79.5374 177.811C79.7346 175.535 78.0358 173.579 75.8365 173.2C73.622 172.745 71.6806 173.594 69.9818 175.02C68.3589 176.324 66.9331 178.144 65.8259 179.631C63.6872 182.361 60.8205 185.683 57.696 189.323C50.734 197.513 42.5435 207.145 37.8567 215.335C35.9 218.657 34.6108 221.767 34.2164 224.375C33.6249 227.955 33.5036 230.685 34.4136 233.734C31.6228 236.464 29.5296 239.391 28.4982 243.229C27.6488 246.217 27.5275 249.599 28.1797 253.497C26.1624 249.539 23.6901 246.278 20.5049 243.092C19.8526 248.158 19.3976 253.239 19.3369 258.305C18.6847 257.198 17.9719 256.091 17.3196 255.12C16.2731 253.695 15.2417 252.329 14.1951 251.086C14.5136 250.767 14.7866 250.433 14.908 249.978C15.3023 249.129 15.363 248.098 14.9687 247.051C14.6501 246.08 13.8614 245.292 13.012 244.912C12.1626 244.457 11.1312 244.321 10.1453 244.655C9.1746 244.973 8.46172 245.701 8.06736 246.611C7.673 247.521 7.61233 248.568 8.00669 249.539C8.40105 250.509 9.11393 251.298 9.96332 251.753C10.8734 252.208 11.8441 252.269 12.83 251.95C12.9665 251.95 13.0272 251.89 13.0879 251.814C14.1951 253.042 15.2265 254.407 16.2124 255.848C17.3196 257.35 18.2904 259.094 19.2763 260.914L19.3369 260.975C19.3369 262.598 19.3976 264.297 19.5341 265.98C18.4269 263.963 17.0011 262.082 15.4389 260.323C12.5722 257.138 9.18977 254.802 5.54953 252.527C5.41302 258.442 5.86805 264.236 7.68817 269.954C9.31111 275.415 12.0413 280.875 16.2731 286.411C15.4237 291.932 15.2265 297.468 15.9546 302.989C16.3489 305.522 16.8646 308.055 17.5775 310.604C16.7281 309.178 15.818 307.737 14.908 306.372C12.9514 303.444 10.8734 300.775 8.59823 298.439C9.18977 297.848 9.56896 297.074 9.56896 296.225C9.56896 295.375 9.1746 294.541 8.52239 294.01C7.93085 293.419 7.1573 293.1 6.24724 293.1C5.33718 293.1 4.56363 293.419 3.91142 294.01C3.31988 294.602 3.00136 295.375 3.00136 296.225C3.00136 297.074 3.39572 297.848 3.97209 298.439C4.56363 299.031 5.39785 299.349 6.30791 299.349C6.70227 299.349 7.08146 299.289 7.47582 299.152C9.75098 301.427 11.9048 304.157 13.8462 307.085C15.8029 310.012 17.623 313.137 19.2459 316.246C18.1387 315.139 16.9708 314.032 15.8029 313C11.0554 308.966 5.91355 305.841 0.074 303.566C-0.244521 307.661 0.468359 311.18 2.15197 314.942C3.65357 318.385 5.85288 321.828 8.32521 325.468C10.1453 328.001 12.2233 330.079 14.3771 332.172C17.0466 334.842 19.7161 337.435 21.5969 341.015C20.3683 340.62 19.0639 340.363 17.8202 340.044C19.6403 343.108 21.2632 346.096 22.5677 349.403C23.7356 352.193 24.6456 355.121 25.4344 358.245C26.0259 360.52 26.3444 363.129 26.6023 365.723C25.3737 365.207 24.1906 364.616 23.0227 363.903C21.7941 363.19 20.5504 362.341 19.3218 361.43C19.8375 359.808 19.8375 358.306 19.519 357.077C19.1246 355.576 18.2145 354.484 16.986 354.089C16.4703 353.953 16.0152 353.892 15.5602 353.892C14.7866 353.953 14.1344 354.211 13.5429 354.666C12.9514 355.06 12.4963 355.712 12.2385 356.349C12.102 356.744 12.102 357.123 12.102 357.578C12.2385 359.08 13.0727 360.369 14.2406 361.218C15.4692 362.068 16.9708 362.447 18.3966 362.325C19.701 363.296 21.0661 364.206 22.3705 364.995C23.7962 365.844 25.2372 366.557 26.7236 367.073C26.8601 368.241 26.9208 369.409 27.118 370.516C26.8601 370.455 26.6629 370.379 26.4051 370.319C21.5211 368.635 12.4205 366.163 7.09663 366.8C7.94602 367.71 8.85608 368.362 9.82681 369.136C12.4963 371.092 15.0293 372.912 17.1073 375.445C21.0812 380.193 25.1765 384.607 29.5903 388.641C32.2598 391.053 34.99 393.389 37.8415 395.527C39.601 396.832 41.4211 398.121 43.3019 399.304C45.4405 401.716 47.3971 404.446 49.0201 407.373C50.643 410.361 51.9474 413.486 52.7968 416.611C53.0547 417.323 53.2519 418.036 53.5097 418.749C49.4751 417.976 45.577 416.337 42.0581 414.138C42.2553 413.622 42.1188 412.97 41.8609 412.455C41.1481 411.15 39.4493 410.498 38.0842 410.832C38.0235 410.832 37.887 410.892 37.8263 410.892C36.4613 411.347 35.8697 412.712 36.5978 414.017C36.8556 414.533 37.3106 414.988 37.8263 415.245C38.5999 415.7 39.51 415.837 40.3593 415.64C40.6779 415.579 41.0116 415.443 41.3301 415.185C45.1675 417.657 49.5206 419.417 54.0709 420.19C54.5866 421.358 55.2388 422.465 55.9517 423.512C56.7253 424.558 57.6353 425.529 58.6819 426.378C53.3429 425.726 48.1555 426.378 42.8772 427.349C44.5608 428.851 46.2596 430.277 47.8218 431.839C49.1263 433.067 50.4307 434.433 51.7958 436.131C55.4967 440.484 61.4121 445.49 68.5105 446.855C73.0002 447.704 77.9448 447.113 83.0715 444.125C87.1061 450.495 91.4592 456.866 96.5252 463.236C102.835 471.305 110.252 479.359 119.474 487.368C127.407 495.498 144.243 509.861 157.712 508.754C158.682 508.693 159.592 508.557 160.502 508.36C166.297 506.858 171.029 502.308 170.71 495.937C172.015 499.32 173.956 502.369 176.504 504.841C180.933 509.27 187.107 512 193.871 512C200.636 512 206.749 509.27 211.238 504.841C213.711 502.369 215.728 499.32 216.957 495.937C216.638 502.308 221.386 506.858 227.225 508.36C228.272 508.618 229.364 508.754 230.471 508.815C243.864 509.467 260.382 495.361 268.178 487.353C277.415 479.359 284.756 471.351 291.066 463.357C294.251 459.398 297.178 455.364 299.848 451.329C308.175 453.407 315.85 451.39 322.539 447.431C329.501 443.336 335.537 437.087 340.285 431.308C340.346 431.308 340.346 431.247 340.346 431.247L340.998 430.474L340.285 430.277L339.966 430.216C336.463 429.564 332.807 429.503 328.97 430.155C326.103 430.61 323.176 431.46 320.127 432.688C322.857 430.095 325.33 427.091 327.544 423.588C330.016 422.996 332.489 422.359 334.885 421.449C336.705 420.797 338.525 420.084 340.285 419.234C340.74 418.977 341.195 418.779 341.65 418.522C342.044 419.113 342.621 419.492 343.334 419.75C344.38 420.069 345.472 420.008 346.458 419.75C347.884 419.295 349.052 418.249 349.128 416.762C349.128 415.913 348.733 415.139 347.96 414.548C346.458 413.38 344.122 413.501 342.621 414.608C341.711 415.261 341.058 416.171 341.195 417.339C340.937 417.475 340.603 417.596 340.285 417.794C338.404 418.704 336.447 419.553 334.43 420.266C332.474 420.979 330.456 421.57 328.454 422.025C329.304 420.66 330.077 419.159 330.866 417.596C332.686 413.895 334.385 409.982 336.068 406.145C336.66 404.78 337.236 403.415 337.828 402.11C338.677 402.05 339.511 401.974 340.3 401.913C344.138 401.397 347.975 400.032 351.752 397.757C356.438 394.89 361.11 390.734 365.66 385.213C368.451 381.831 371.257 378.843 374.048 375.916C375.019 374.808 376.005 373.777 376.976 372.73C371.06 372.412 365.858 373.246 360.397 375.597C360.594 374.687 360.716 373.777 360.716 373.003C362.217 371.32 363.764 369.682 365.403 368.059C366.828 366.694 368.269 365.389 369.756 364.221C370.15 364.479 370.605 364.676 371.121 364.737C372.88 365.056 374.822 364.024 375.413 362.265C376.005 360.445 374.761 358.685 372.941 358.367C371.121 358.048 369.164 359.08 368.648 360.839C368.391 361.688 368.451 362.523 368.846 363.251C367.42 364.479 365.979 365.723 364.493 367.149C363.188 368.377 361.899 369.742 360.594 371.244C360.397 370.015 360.079 368.908 359.745 367.862C359.487 366.891 359.229 366.041 359.093 365.192C358.501 359.671 363.188 352.254 366.176 347.507C366.828 346.536 367.283 345.944 368.133 345.171C365.342 345.368 362.794 346.141 360.139 347.309C360.989 346.202 361.899 345.095 363.006 344.261L363.158 344.23ZM276.945 52.9352C276.884 52.6773 276.884 52.5408 276.884 52.4195C276.823 51.3729 276.748 50.3415 276.49 49.2949C282.011 50.5235 287.016 52.6167 291.248 55.4075C294.115 57.2276 296.587 59.3814 298.725 61.7173C304.247 67.7692 307.174 75.2468 306.522 82.9823C306.385 85.1968 305.93 87.4113 305.293 89.5499C303.534 89.0949 301.774 88.382 301.198 87.7298C298.725 84.8025 295.222 83.3009 291.248 82.5273C289.231 82.133 287.016 81.9358 284.817 81.8144C284.68 79.3421 284.362 76.8091 282.739 73.8211C280.464 73.3054 278.188 73.0475 275.913 72.9717C276.368 71.2122 276.687 69.5286 276.884 67.8298C277.476 63.2795 277.339 58.5927 276.945 52.9352ZM96.6921 75.4288V75.4895C91.171 79.3876 88.5622 81.4049 81.4789 79.5848C81.7974 73.0779 84.6641 66.8439 89.3509 61.7021C91.4289 59.3663 93.9012 57.2731 96.6921 55.453C100.985 52.6622 105.99 50.5084 111.587 49.2798C111.329 50.3263 111.268 51.3577 111.192 52.4043C111.192 52.5408 111.192 52.6622 111.132 52.92C110.737 58.5776 110.616 63.2644 111.192 67.8147C111.329 69.1191 111.587 70.4083 111.845 71.7734C106.126 70.2718 101.318 72.092 96.6921 75.4137V75.4288ZM340.467 263.796C340.603 263.402 340.725 263.083 340.922 262.689C341.119 265.283 342.151 268.028 343.789 272.442C342.742 272.381 341.65 272.578 340.467 272.76C340.073 272.821 339.693 272.897 339.299 273.018C338.647 273.155 337.934 273.276 337.221 273.337C338.192 270.091 339.299 266.906 340.467 263.781V263.796ZM209.904 34.0666C211.587 34.3244 213.347 34.7188 215.167 35.2952C219.323 36.5238 222.842 37.4338 226.421 38.0254C227.786 38.2225 229.212 38.4197 230.653 38.5411C232.989 38.7382 235.4 38.8596 238.131 38.8596C242.362 38.8596 245.805 39.5725 248.475 41.3319C251.084 43.0155 253.025 45.685 254.133 49.5831C255.043 52.6318 255.498 55.635 255.558 58.6837C255.164 58.6231 254.785 58.6231 254.451 58.5472C246.837 57.8343 246.003 51.6611 240.406 49.7045C237.812 48.7944 234.035 48.7337 230.653 49.0523C229.682 49.1888 228.772 49.3101 227.862 49.4466C224.025 50.1595 221.355 48.7337 217.715 47.49C215.303 46.7164 212.831 45.9277 210.237 45.2755C209.267 41.1196 207.901 37.2821 206.081 34.0211C206.021 33.8846 205.884 33.7026 205.823 33.5661C207.249 33.7026 208.614 33.8239 209.919 34.0211L209.904 34.0666ZM133.944 49.6135C135.051 45.7154 137.008 43.0459 139.601 41.3622C142.271 39.6028 145.714 38.8899 149.946 38.8899C152.873 38.8899 155.467 38.7534 157.878 38.4956C159.183 38.359 160.411 38.2377 161.655 38.0405C165.235 37.449 168.739 36.5389 172.91 35.3103C174.73 34.7188 176.489 34.3396 178.173 34.0818C179.796 33.8239 181.495 33.6874 183.239 33.4902C182.465 35.7047 181.874 38.3742 181.419 40.8314C180.964 42.9093 180.569 44.7901 180.19 45.776C180.054 45.9732 179.993 46.2311 179.872 46.4283C175.579 48.5062 172.712 52.5408 168.162 53.8452C166.342 54.3609 164.067 53.5267 161.458 53.193C160.29 52.9959 159.122 52.9959 157.878 53.0565C152.615 53.5116 147.155 56.3024 144.03 60.337C140.132 65.403 137.144 67.4962 133.959 68.7247C133.186 65.9946 132.73 63.2037 132.594 60.3977C132.457 56.8788 132.852 53.2385 133.959 49.5983L133.944 49.6135ZM40.3745 356.455C40.3138 356.971 40.238 357.366 40.238 357.76C39.5251 356.198 38.8122 354.772 37.9629 353.407C37.1893 352.178 36.3399 350.995 35.4298 349.964C35.8849 349.448 36.2034 348.735 36.2034 347.825C37.0528 347.764 37.5685 347.628 37.9629 347.431C37.9629 347.886 38.0994 348.341 38.2207 348.796C38.6151 349.645 39.3886 350.419 40.4352 350.813C40.4959 351.784 40.4959 352.77 40.4959 353.74C40.4352 354.651 40.4352 355.561 40.3593 356.471L40.3745 356.455ZM357.182 311.529C356.332 313.743 355.817 316.018 355.68 318.354C353.86 316.018 352.04 313.607 350.341 311.135C348.839 308.92 347.55 306.842 346.504 304.885L345.851 303.718L345.336 304.946C343.516 309.694 342.272 314.76 341.696 319.901C341.18 324.846 341.301 329.851 342.211 334.66C342.803 338.103 344.092 341.364 345.988 344.276C347.747 347.006 350.023 349.478 352.874 351.754C352.556 352.072 352.161 352.345 351.828 352.664C348.9 355.394 346.564 358.715 344.805 362.811C344.805 361.582 344.805 360.338 344.744 359.11C344.684 357.032 344.547 355.015 344.289 352.997C344.684 352.8 345.063 352.542 345.336 352.148C345.791 351.556 346.109 350.646 346.109 349.736C346.109 348.826 345.791 347.916 345.336 347.325C344.168 345.899 342.211 345.899 340.983 347.264C340.785 347.522 340.664 347.78 340.467 348.037C340.27 348.492 340.148 349.084 340.148 349.66C340.148 350.176 340.285 350.768 340.467 351.223C340.664 351.541 340.785 351.814 341.058 352.072C341.574 352.724 342.287 353.119 343.076 353.179C343.273 355.136 343.47 357.153 343.531 359.095V361.112C343.334 360.202 343.076 359.292 342.818 358.442C342.166 356.562 341.453 354.666 340.482 352.921C340.224 352.406 339.966 351.814 339.633 351.298C338.662 349.676 337.615 348.113 336.387 346.551C333.717 358.063 329.622 369.045 324.359 379.389C324.42 384.394 324.95 389.005 326.24 392.721C327.605 396.559 329.819 399.35 333.262 400.593C325.845 404.37 319.733 409.118 314.985 414.836C314.788 413.41 314.788 412.045 314.849 410.68C314.909 408.921 315.167 407.161 315.501 405.477C316.35 405.477 317.185 405.22 317.776 404.628C318.292 404.112 318.625 403.324 318.823 402.216C318.823 401.822 318.823 401.443 318.762 401.048C318.701 400.336 318.368 399.744 317.988 399.289C317.533 398.773 316.942 398.515 316.365 398.379C316.168 398.379 315.971 398.379 315.713 398.44C314.94 398.5 314.288 398.955 313.757 399.608C313.302 400.26 312.983 401.033 312.907 401.943C312.907 402.793 313.104 403.703 313.559 404.355C313.757 404.613 314.015 404.871 314.333 405.068C313.939 406.888 313.681 408.769 313.559 410.589C313.499 412.409 313.559 414.229 313.878 416.11C312.452 417.93 311.148 419.887 309.904 421.904C310.162 418.324 310.041 415.079 309.51 412.151C309.115 409.618 308.402 407.343 307.432 405.326C303.458 410.27 299.105 414.942 294.494 419.31C294.63 421.98 295.009 424.255 295.54 426.333L292.492 421.191C292.097 421.585 291.718 421.904 291.263 422.298C274.23 437.572 253.48 448.887 230.668 454.803C218.959 457.851 206.673 459.49 194.053 459.49C181.434 459.49 169.467 457.927 157.894 454.939C134.808 449.024 113.938 437.648 96.7073 422.162C89.6239 415.852 83.117 408.829 77.3988 401.23C77.2016 408.39 77.5353 415.276 78.4454 421.646C78.051 420.933 77.596 420.145 77.0803 419.371C74.6686 415.534 72.0749 411.893 68.8291 408.708C69.2841 405.978 69.3448 403.051 68.8291 400.32C69.1476 400.123 69.4206 399.926 69.6026 399.608C70.452 398.44 70.3155 396.68 69.2841 395.634C68.1769 394.587 66.5539 394.663 65.6439 395.891C64.7945 397.12 64.931 398.819 65.9624 399.85C66.4174 400.305 67.0089 400.563 67.5853 400.624C67.9797 402.899 67.9797 405.371 67.7218 407.646C65.5073 405.69 63.1109 404.006 60.4413 402.58C58.5606 401.61 56.5432 400.76 54.3894 400.047C54.5259 398.364 54.3894 396.665 53.9344 394.981C55.2995 393.874 56.2702 391.993 56.9831 389.521C57.6353 387.049 58.0297 383.924 58.151 380.36C58.3482 375.157 58.0904 370.213 57.4988 365.404C54.6321 357.927 52.357 350.191 50.734 342.259C49.2324 344.079 47.9432 346.49 46.8359 349.418C45.668 352.603 44.758 356.38 44.1058 360.869C43.5142 359.823 42.9378 358.791 42.4221 357.745C42.1643 357.29 41.9064 356.835 41.7093 356.44C41.7093 355.53 41.7699 354.62 41.7699 353.71V350.98C43.135 350.98 44.1058 350.131 44.5608 349.099C44.8793 348.25 44.9551 347.279 44.6215 346.43C44.2271 345.322 43.2564 344.412 41.6334 344.352C40.5869 344.352 39.7526 344.61 39.1611 345.065C39.2218 344.867 39.2976 344.61 39.4189 344.352C40.329 341.682 41.4969 338.831 42.6648 335.827C44.6821 330.822 46.7601 325.62 48.0645 321.009C47.928 318.476 47.8673 315.867 47.8673 313.273C47.8673 310.224 48.0038 307.1 48.1252 304.036C47.9887 303.581 47.8673 303.126 47.6702 302.732C46.3051 299.289 44.3484 296.619 41.6183 294.147C40.511 297.529 39.3431 300.851 38.0994 304.218C38.0387 304.355 38.0387 304.476 37.9629 304.612C36.8556 307.676 35.7484 310.725 34.717 313.85C34.1254 315.806 33.6097 317.748 33.094 319.765C32.3811 312.606 31.1374 306.372 29.2566 301.23C32.0475 299.349 35.3085 296.422 37.9629 293.813L40.1773 291.599C43.044 288.474 45.3192 285.228 46.8814 282.104C48.2465 279.373 49.0959 276.583 49.4144 273.655C49.6116 272.29 49.6116 270.864 49.551 269.363C50.5217 272.154 51.3711 275.081 52.1598 278.008C59.3796 249.205 75.1843 223.708 96.7073 204.46C113.938 188.989 134.808 177.598 157.894 171.683C169.467 168.695 181.631 167.133 194.053 167.133C206.476 167.133 218.959 168.756 230.668 171.819C253.495 177.735 274.23 189.05 291.263 204.324C312.847 223.572 328.651 249.129 335.871 277.932C336.008 277.417 336.19 276.886 336.326 276.431C337.1 281.77 338.404 286.047 340.482 289.627C340.876 290.218 341.195 290.795 341.589 291.386C344.653 295.679 349.067 298.803 355.377 301.594C355.316 304.976 355.892 308.359 357.197 311.408V311.468L357.182 311.529Z\" fill=\"black\"><\/path><path d=\"M200.151 30.8812C198.012 31.852 198.467 34.1271 200.287 35.3102C202.426 36.6753 203.73 41.3621 204.519 46.1703C205.293 50.9177 205.566 55.8624 205.687 58.001C205.945 62.0356 206.005 66.1916 205.823 69.9077C205.687 73.1535 205.368 76.0809 204.853 78.3561C204.595 79.2661 204.337 80.1155 204.003 80.8284C203.29 82.6485 202.835 83.9529 204.853 85.9702C204.989 86.1067 205.171 86.2281 205.308 86.3646C205.763 86.6831 206.218 86.8803 206.733 86.8803C207.188 86.8803 207.704 86.6224 208.235 86.1067C208.432 85.9702 208.554 85.7882 208.69 85.591C209.6 84.4231 210.313 82.4665 210.768 79.8728C211.223 77.2033 211.481 73.8209 211.42 69.8015C211.42 64.3411 211.162 57.8949 210.192 51.661C209.221 45.427 207.659 39.3751 204.989 34.749C204.398 33.7024 203.685 32.4738 202.851 31.6245C202.077 30.9116 201.167 30.5172 200.181 30.9116L200.151 30.8812Z\" fill=\"#FFE200\"><\/path><path d=\"M219.975 113.135C219.125 113.59 217.245 115.092 217.108 115.547C217.108 115.092 215.606 113.408 214.772 112.68C207.81 112.089 200.924 111.831 194.023 111.831C187.122 111.831 180.175 112.089 173.349 112.68C172.5 113.333 170.938 115.092 170.938 115.547C170.801 115.031 168.92 113.59 168.01 113.135C153.51 114.637 139.268 117.428 125.48 121.463C124.707 121.66 123.857 122.828 123.918 123.419C123.918 124.071 125.419 123.419 126.512 123.161C127.937 122.843 127.422 124.132 128.134 124.329C128.59 124.39 129.181 124.329 130.546 123.935C130.607 124.39 129.636 124.648 128.863 125.497C127.952 126.544 127.558 127.772 129.575 127.636C131.138 127.575 131.714 127.12 132.306 127.378C133.352 127.772 132.503 128.349 134.323 127.894C154.026 123.283 174.047 120.932 194.008 120.932C217.214 120.932 240.497 124.117 263.187 130.366C261.367 127.636 265.144 127.241 267.086 127.954C268.056 128.349 272.88 130.821 276.323 130.366C279.766 129.911 278.598 128.485 276.717 127.317C274.381 125.891 271.378 125.436 270.665 125.497C268.906 125.634 261.504 123.677 261.822 122.448C265.205 123.358 268.784 124.466 272.227 124.587C255.513 118.793 237.888 115.031 219.944 113.135H219.975Z\" fill=\"#FFE200\"><\/path><path d=\"M176.671 69.7708C176.61 73.8054 176.868 77.1877 177.323 79.8421C177.839 82.4358 178.491 84.3924 179.401 85.5603C179.538 85.7575 179.72 85.9547 179.856 86.076C180.372 86.5917 180.903 86.8496 181.358 86.8496C181.874 86.8496 182.329 86.6524 182.784 86.3339C182.92 86.1973 183.102 86.076 183.239 85.9395C185.256 83.9222 184.801 82.6178 184.088 80.7977C183.77 80.0848 183.497 79.2354 183.239 78.3253C182.723 76.0502 182.389 73.1228 182.268 69.8769C182.071 66.176 182.131 62.0049 182.405 57.9703C182.541 55.8317 182.799 50.887 183.572 46.1395C184.225 42.3021 185.135 38.6012 186.56 36.5232C187.668 34.9609 190.079 30.2135 185.65 31.5786C185.332 32.0336 184.998 32.5493 184.74 33.1408C183.83 35.2795 183.178 38.3433 182.662 41.0735C182.207 43.2122 181.813 45.1688 181.358 46.276C179.341 50.8263 178.173 54.0722 177.46 57.5304C176.808 60.9128 176.686 64.5531 176.686 69.7556L176.671 69.7708Z\" fill=\"#FFE200\"><\/path><path d=\"M193.128 76.005C190.656 75.5499 188.836 73.4113 188.836 70.8631C188.836 68.0723 191.05 65.7213 193.78 65.6C190.914 65.4634 188.638 63.0669 188.638 60.2003C188.638 57.3336 190.853 54.9978 193.644 54.8006C191.05 54.5427 188.957 52.3889 188.957 49.7346C188.957 47.2622 190.777 45.1843 193.189 44.7292C191.232 44.4107 189.67 42.9091 189.215 41.0283C186.485 42.1356 185.059 44.9264 184.604 47.6566C184.012 51.8884 183.754 56.105 183.633 58.0616C183.436 62.0962 183.375 66.1915 183.497 69.8317C183.633 73.0169 183.952 75.8836 184.467 78.0223C184.664 78.9323 184.983 79.6452 185.241 80.3581C185.954 82.3147 186.545 83.7405 185.104 85.6971C185.817 85.4393 186.606 85.2421 187.379 85.1814C187.698 83.5585 188.487 82.2541 189.518 81.344C189.457 81.0861 189.457 80.8283 189.457 80.5704C189.457 78.356 191.02 76.4752 193.098 76.0201L193.128 76.005Z\" fill=\"#FFE200\"><\/path><path d=\"M203.594 78.0224C204.11 75.8838 204.443 73.0171 204.565 69.8319C204.701 66.1917 204.625 62.0964 204.428 58.0618C204.292 55.9231 203.973 50.9785 203.199 46.3523C203.063 45.3816 202.881 44.3957 202.684 43.4856C202.229 41.2105 200.803 40.0426 198.907 38.7988C199.423 41.529 197.678 44.1985 194.872 44.7142C197.284 45.1693 199.104 47.2472 199.104 49.7196C199.104 52.3891 197.026 54.5277 194.417 54.7856C197.208 54.9827 199.423 57.3186 199.423 60.1853C199.423 63.0519 197.148 65.4484 194.281 65.5849C197.011 65.7215 199.226 68.0573 199.226 70.8481C199.226 73.3811 197.405 75.5349 194.933 75.99C197.011 76.445 198.573 78.3258 198.573 80.5403C198.573 80.7981 198.573 81.056 198.513 81.3138C199.559 82.2239 200.333 83.5283 200.651 85.1512C201.501 85.2119 202.274 85.4091 202.987 85.7428C201.486 83.7862 202.016 82.2997 202.79 80.3431C203.048 79.6302 203.382 78.9173 203.564 78.0073L203.594 78.0224Z\" fill=\"#FFE200\"><\/path><path d=\"M95.3876 112.423C95.1298 112.741 94.5382 112.68 94.3411 112.286C93.2945 110.527 92.0659 109.419 90.7008 108.843C89.3357 108.267 87.91 108.191 86.469 108.585C85.0433 108.904 83.6782 109.692 82.5709 110.8C81.0693 112.165 79.9773 114.121 79.7043 116.26C79.6436 116.851 79.5677 117.428 79.5677 118.141C79.5677 119.187 79.7043 120.279 80.0835 121.189C80.4778 121.963 81.0542 122.555 81.9642 122.691C82.1007 122.691 82.2828 122.752 82.4193 122.752C83.0108 122.752 83.5265 122.555 83.9815 122.236C84.3759 121.978 84.6337 121.644 84.8309 121.265C85.0281 120.871 85.1495 120.416 85.1495 119.961C85.1495 119.445 85.0129 118.914 84.6944 118.459C84.5579 118.323 84.5579 117.944 84.6338 117.807C85.4073 116.123 86.4539 115.138 87.6825 114.758C88.7897 114.364 90.0941 114.44 91.3227 114.956C92.2934 115.274 93.2793 115.926 94.1135 116.639C95.5393 117.807 96.328 119.824 98.2088 118.065C98.8004 117.549 99.2554 116.897 99.5132 116.184C99.9076 115.335 101.076 115.79 100.681 116.639C100.363 117.549 99.7711 118.323 99.1189 118.975C96.5859 120.992 98.6032 120.992 98.6032 124.238C98.6032 124.633 98.6638 124.951 98.8004 125.285C99.5739 127.302 102.896 128.015 104.776 127.241C132.473 116.123 163.233 110.527 193.993 110.527C224.753 110.527 255.437 116.123 283.133 127.241C284.953 128.015 288.336 127.302 289.109 125.285C291.445 120.477 281.176 121.129 277.733 118.778C276.11 118.004 274.548 116.76 273.304 114.88C273.107 114.561 273.244 114.03 273.623 113.97C275.125 113.515 275.959 112.468 276.353 111.376C276.55 110.663 276.611 109.95 276.55 109.237C276.414 108.524 276.156 107.872 275.701 107.281C275.049 106.31 273.881 105.658 272.379 105.658C271.469 105.658 270.696 105.916 270.043 106.31C269.452 106.704 268.997 107.22 268.618 107.872C268.299 108.524 268.102 109.237 268.102 109.95C268.102 110.724 268.36 111.512 268.815 112.225C269.012 112.544 268.815 113.075 268.42 113.135C263.536 114.637 259.441 114.819 255.877 113.727C252.297 112.68 249.249 110.284 246.382 106.446C246.063 105.991 246.64 105.279 247.231 105.536C250.28 107.099 252.889 106.507 254.572 105.081C255.482 104.308 256.135 103.322 256.529 102.215C256.984 101.107 257.121 99.9395 256.923 98.893C256.666 96.9363 255.3 95.192 252.692 94.6005C252.434 94.5398 252.176 94.2061 252.176 93.9483C252.373 91.7338 251.584 90.1109 250.356 89.0036C249.643 88.4121 248.854 88.0329 248.02 87.8357C247.11 87.6385 246.2 87.6385 245.35 87.8357C243.727 88.2908 242.287 89.398 241.513 91.476C241.452 91.7338 241.058 91.931 240.8 91.8703C238.131 91.2181 236.189 92.1888 235.082 93.7511C234.43 94.7218 234.035 95.9656 233.975 97.1942C233.914 98.4228 234.111 99.6665 234.688 100.774C235.658 102.791 237.812 104.277 241.255 104.02C241.847 103.959 242.165 104.869 241.65 105.188C238.07 107.523 233.656 108.691 229.288 108.115C225.511 107.599 221.81 105.703 218.883 102.063C218.564 101.669 218.822 101.016 219.338 101.016C221.219 100.88 222.387 99.7879 222.917 98.4834C223.115 97.8919 223.175 97.2548 223.175 96.6026C223.175 95.9504 222.978 95.3741 222.72 94.7825C222.129 93.4781 220.9 92.5074 219.019 92.5074C217.457 92.5074 216.289 93.2202 215.637 94.191C215.182 94.7825 214.924 95.4196 214.863 96.1476C214.727 96.8605 214.803 97.5734 215 98.2256C215.394 99.3935 216.304 100.44 217.791 100.819C218.306 101.016 218.382 101.729 217.927 101.987C213.377 104.717 209.145 106.082 205.247 105.627C201.349 105.233 197.769 102.958 194.584 98.3469C194.19 97.8312 194.979 97.0425 195.494 97.4369C196.268 98.1497 197.512 98.4834 198.877 98.4834C199.923 98.4834 201.015 98.2862 202.001 97.8312C202.972 97.4369 203.882 96.8605 204.534 96.0111C205.308 95.101 205.763 93.8725 205.763 92.3102C205.763 90.7479 205.111 89.1856 204.079 88.0784C203.033 87.0318 201.668 86.3948 200.045 86.4555C199.787 86.4555 199.453 86.1369 199.453 85.8639C199.256 84.4988 198.74 83.4523 198.027 82.6787C197.254 84.1045 195.813 85.0904 194.053 85.151C195.282 90.217 195.221 89.8379 200.621 91.0664C198.088 91.0058 195.676 91.1271 193.993 93.0837C192.309 91.1271 189.897 91.0058 187.364 91.0664C192.764 89.8379 192.703 90.217 193.932 85.151C192.173 85.0904 190.747 84.1045 189.958 82.6787C189.245 83.4523 188.73 84.4988 188.532 85.8639C188.532 86.1218 188.214 86.4555 187.941 86.4555C186.439 86.3948 184.953 86.9712 183.846 87.8812C182.875 88.7306 182.283 89.8985 182.344 91.2029C182.344 92.113 182.799 92.8866 183.451 93.5388C183.77 93.7966 184.164 94.0545 184.558 94.191C184.953 94.3882 185.332 94.4488 185.726 94.3882C186.242 94.3882 186.834 94.191 187.289 93.6753C187.683 93.2202 188.517 93.6753 188.335 94.2668C188.199 95.0404 188.274 95.7684 188.532 96.3448C188.73 96.8605 189.124 97.3155 189.503 97.6492C189.958 97.9071 190.413 98.1042 190.929 98.1042C191.384 98.1042 191.9 97.9677 192.355 97.5885C192.87 97.1942 193.583 97.9829 193.265 98.4986C190.079 103.049 186.5 105.263 182.602 105.718C178.704 106.113 174.472 104.672 169.982 102.018C169.527 101.76 169.588 101.047 170.119 100.85C171.545 100.455 172.455 99.4238 172.849 98.2559C173.107 97.6037 173.167 96.8908 173.046 96.1779C172.925 95.4651 172.652 94.8129 172.273 94.2213C171.56 93.2506 170.452 92.5377 168.89 92.5377C167.009 92.5377 165.766 93.5084 165.113 94.8128C164.856 95.4044 164.719 95.9808 164.719 96.633C164.658 97.2852 164.78 97.9374 164.977 98.5138C165.493 99.8182 166.661 100.925 168.557 101.047C169.012 101.047 169.33 101.699 169.012 102.093C166.084 105.734 162.383 107.614 158.606 108.145C154.253 108.737 149.824 107.554 146.184 105.218C145.729 104.899 145.987 103.989 146.639 104.05C150.022 104.368 152.16 102.943 153.207 100.925C153.798 99.8182 154.056 98.4531 153.98 97.2245C153.844 95.9201 153.465 94.6915 152.812 93.7056C151.705 92.1433 149.764 91.2333 147.155 91.8855C146.897 91.9462 146.503 91.749 146.442 91.4911C145.668 89.4132 144.228 88.3059 142.605 87.8509C141.755 87.6537 140.845 87.6537 139.935 87.8509C139.086 88.0481 138.312 88.4424 137.599 89.0188C136.371 90.126 135.582 91.749 135.779 93.9635C135.779 94.2213 135.521 94.555 135.263 94.6157C132.67 95.1314 131.365 96.8908 131.032 98.8475C130.834 99.894 130.971 101.062 131.35 102.169C131.745 103.216 132.397 104.247 133.231 105.036C134.915 106.537 137.523 107.114 140.648 105.627C141.164 105.37 141.755 106.082 141.422 106.537C138.555 110.314 135.506 112.711 131.927 113.757C128.347 114.865 124.312 114.667 119.383 113.166C118.989 113.105 118.867 112.574 119.064 112.256C119.519 111.543 119.717 110.754 119.717 109.981C119.717 109.268 119.58 108.555 119.201 107.903C118.882 107.25 118.427 106.735 117.775 106.34C117.184 105.946 116.41 105.688 115.5 105.688C113.998 105.688 112.83 106.34 112.118 107.311C111.723 107.903 111.465 108.54 111.344 109.268C111.283 109.981 111.283 110.693 111.541 111.406C111.936 112.514 112.77 113.545 114.271 114C114.59 114.061 114.787 114.592 114.59 114.91C113.361 116.791 111.799 118.035 110.161 118.808C108.144 119.779 106.005 120.113 104.048 120.037C103.533 120.037 103.199 119.445 103.533 119.066C104.579 117.762 105.156 116.139 105.156 114.576C105.156 113.803 105.019 113.075 104.761 112.438C104.443 111.785 104.048 111.209 103.533 110.754C102.683 110.163 101.652 109.783 100.211 109.783C99.1037 109.723 98.2543 109.981 97.4808 110.436C96.7072 110.891 95.9792 111.603 95.3421 112.453L95.3876 112.423Z\" fill=\"#FFE200\"><\/path><path d=\"M197.739 39.7995C197.739 37.7822 196.055 36.0986 194.038 36.0986C192.021 36.0986 190.337 37.7822 190.337 39.7995C190.337 41.8168 192.021 43.5763 194.038 43.5763C196.055 43.5763 197.739 41.8927 197.739 39.7995Z\" fill=\"#FFE200\"><\/path><path d=\"M160.472 491.387C159.956 492.555 160.214 493.86 161.064 494.77C161.716 495.422 162.565 495.741 163.339 496.074C162.034 498.744 160.153 499.972 157.09 499.654C153.768 499.259 151.174 497.773 149.551 495.68C148.702 494.633 148.126 493.465 147.792 492.237C147.473 491.008 147.337 489.704 147.473 488.399C147.792 485.609 149.293 482.802 152.024 480.664C155.012 478.252 161.003 476.311 166.387 474.491C168.526 473.778 170.619 473.126 172.303 472.473C174.836 471.503 176.08 469.607 176.277 467.862C176.413 466.694 176.019 465.39 174.972 464.677C174.062 464.086 172.697 464.086 170.938 465.132C167.161 467.347 163.657 468.712 160.017 470.077C158.136 470.85 156.119 471.578 154.102 472.488C149.491 474.566 145.653 477.949 143.242 481.923C140.314 486.731 139.146 492.646 141.482 497.849C142.787 500.716 145.001 503.309 148.444 505.387C152.084 507.662 156.513 508.117 160.351 507.147C163.475 506.297 166.524 504.477 168.223 501.686C170.179 498.562 170.301 493.299 167.631 490.508C165.553 488.369 161.716 488.49 160.472 491.418V491.387Z\" fill=\"#FFE200\"><\/path><path d=\"M233.96 472.458C231.942 471.548 229.925 470.835 228.044 470.046C224.404 468.681 220.885 467.316 217.123 465.102C214.651 463.676 211.663 463.6 208.736 463.676C210.692 465.815 211.921 468.165 214.135 470.243C215.045 471.154 215.895 471.866 216.729 472.519C218.231 473.565 219.914 474.02 221.613 474.597C227.073 476.356 233.125 478.298 236.053 480.649C238.783 482.787 240.284 485.593 240.603 488.384C240.861 490.978 240.148 493.587 238.525 495.664C236.902 497.742 234.293 499.244 230.987 499.638C227.923 499.957 226.042 498.728 224.738 496.059C225.511 495.74 226.361 495.407 227.013 494.754C227.862 493.844 228.12 492.54 227.604 491.372C226.376 488.445 222.538 488.323 220.445 490.462C217.776 493.253 217.912 498.531 219.854 501.641C221.537 504.431 224.601 506.251 227.726 507.101C231.563 508.072 235.977 507.617 239.632 505.341C243.075 503.264 245.29 500.655 246.594 497.803C248.93 492.601 247.762 486.685 244.835 481.877C242.423 477.918 238.586 474.536 233.975 472.443L233.96 472.458Z\" fill=\"#FFE200\"><\/path><path d=\"M219.52 489.567C220.369 488.718 221.34 488.202 222.311 487.944C223.357 487.687 224.328 487.687 225.299 487.884C226.148 488.142 226.922 488.597 227.574 489.188C228.09 489.704 228.484 490.295 228.742 490.948C229.06 491.66 229.197 492.51 229.06 493.359C228.924 494.209 228.545 494.982 227.892 495.695C227.498 496.014 227.043 496.408 226.467 496.742C226.861 497.333 227.377 497.712 227.892 497.97C228.742 498.425 229.713 498.486 230.759 498.425C233.747 498.031 236.022 496.742 237.524 494.922C238.237 494.011 238.752 493.041 239.025 491.933C239.344 490.826 239.42 489.719 239.283 488.551C239.025 486.079 237.721 483.606 235.249 481.665C232.519 479.45 226.542 477.57 221.203 475.81C220.43 475.552 219.702 475.355 219.323 475.219C217.958 474.764 216.987 474.248 216.001 473.596C215.091 472.944 214.242 472.17 213.21 471.184C212.164 470.138 211.193 469.106 210.222 467.999L210.161 467.938C209.449 467.741 208.66 467.544 207.947 467.347C207.628 467.286 207.355 467.15 207.037 467.089C208.599 468.06 210.086 469.227 211.39 470.532C215.819 474.885 218.61 480.998 218.61 487.702C218.61 488.87 218.549 490.113 218.352 491.281C218.67 490.629 219.065 490.053 219.52 489.598V489.567Z\" fill=\"#FFE200\"><\/path><path d=\"M210.541 474.612C206.187 473.247 201.759 472.018 197.269 471.29C194.084 470.699 195.646 471.882 194.144 474.475C192.84 476.751 191.475 479.086 189.988 481.498C188.82 483.455 187.577 485.396 186.287 487.353C185.893 488.005 185.772 488.46 186.424 488.854C187.334 489.37 188.563 489.446 189.549 489.507C195.145 490.022 200.469 492.753 205.156 495.816C206.46 496.59 208.796 498.547 210.101 498.683C210.753 498.82 211.329 498.486 212.118 497.576H212.057C212.77 496.529 213.68 495.559 214.272 494.451C215.834 491.66 213.62 489.385 211.284 488.081C205.945 485.093 200.227 482.818 194.372 481.195C193.522 480.937 193.856 479.693 194.69 479.966C199.954 481.468 205.095 483.409 209.904 485.882C212.694 487.307 214.454 484.38 214.97 482.105C215.682 478.722 213.923 475.674 210.541 474.627V474.612Z\" fill=\"#FFE200\"><\/path><path d=\"M194.675 466.679C194.736 467.65 195.07 469.667 196.101 469.804C200.393 470.395 204.625 471.487 208.781 472.731C209.373 472.928 210.01 472.928 210.404 472.337C210.541 472.14 210.662 471.563 210.465 471.366C206.491 467.468 201.167 464.996 195.252 464.662C195.252 464.662 195.231 464.682 195.191 464.723C194.675 465.041 194.599 465.951 194.675 466.679Z\" fill=\"#FFE200\"><\/path><path d=\"M204.625 497.105C199.165 494.769 196.829 499.062 192.597 500.882C189.078 502.383 184.983 503.293 181.221 503.157C181.737 504.325 182.587 505.371 183.633 506.282L184.027 505.766C184.543 504.992 185.59 505.766 185.074 506.479L184.619 507.07C184.938 507.328 185.211 507.525 185.529 507.722C185.787 507.465 185.923 507.07 185.984 506.676C186.181 505.826 187.41 506.084 187.213 506.934C187.152 507.449 186.955 507.98 186.621 508.435C187.076 508.693 187.531 508.951 188.047 509.148C188.305 508.632 188.502 508.102 188.563 507.525C188.699 506.615 189.988 506.812 189.791 507.722C189.731 508.435 189.473 509.088 189.2 509.679C189.913 509.998 190.625 510.271 191.278 510.453C191.535 509.679 191.672 508.951 191.596 508.238C191.535 507.328 192.825 507.267 192.901 508.102C192.901 508.951 192.84 509.785 192.582 510.635C193.037 510.695 193.553 510.695 194.008 510.695H194.523C194.721 509.725 194.781 508.739 194.842 507.768C194.842 506.858 196.071 506.919 196.071 507.829C196.071 508.739 196.01 509.709 195.813 510.619C196.662 510.559 197.496 510.422 198.346 510.301C198.406 509.194 198.406 508.086 198.285 506.979C198.224 506.069 199.453 505.933 199.589 506.843C199.65 507.889 199.65 508.921 199.65 509.967C200.363 509.77 201.152 509.573 201.865 509.315C201.865 508.147 201.804 506.903 201.546 505.735C201.349 504.886 202.653 504.628 202.775 505.538C203.033 506.585 203.093 507.677 203.169 508.784C203.882 508.466 204.671 508.132 205.308 507.738C205.368 506.63 205.505 505.66 205.171 504.613C204.974 503.703 206.218 503.385 206.4 504.295C206.658 505.265 206.658 506.175 206.658 506.964C207.31 506.509 207.826 505.66 207.704 504.886C207.644 504.689 207.568 504.492 207.507 504.234C207.113 503.384 208.281 502.869 208.614 503.718C208.614 503.718 208.634 503.764 208.675 503.855C208.933 503.202 209.13 502.55 209.069 501.898C209.009 499.684 206.476 497.863 204.58 497.09L204.625 497.105Z\" fill=\"#FFE200\"><\/path><path d=\"M186.105 501.458C189.291 500.943 195.145 499.244 196.829 496.119C197.542 494.891 197.026 492.798 195.661 492.282C192.537 491.053 188.32 490.204 184.862 490.598C183.633 490.735 182.526 491.19 181.358 491.372C180.964 491.433 180.584 491.508 180.19 491.508C178.112 491.645 175.958 490.796 174.472 489.37C173.82 488.718 174.669 487.808 175.321 488.46C176.626 489.688 178.446 490.341 180.129 490.28C180.584 490.28 180.979 490.219 181.358 490.083C182.526 489.825 183.633 489.112 184.346 488.005C185.969 485.593 187.471 483.197 188.896 480.846C190.322 478.51 191.763 476.159 193.128 473.823C194.493 471.351 194.69 467.847 192.081 466.209C191.945 466.148 191.884 466.072 191.763 466.072C190.853 465.617 187.865 465.617 188.381 467.301C188.699 468.469 190.064 469.121 190.337 470.486C190.474 471.335 190.277 472.17 189.685 473.535C188.123 476.917 186.242 480.163 184.225 483.288C183.709 484.061 182.662 483.348 183.178 482.575C185.195 479.526 187.015 476.401 188.517 473.019C188.972 471.912 189.169 471.26 189.033 470.744C188.896 469.97 187.926 468.863 187.273 468.332C185.514 467.104 183.299 467.559 181.358 468.59C179.856 469.364 178.491 470.471 177.581 471.381C173.349 475.537 170.756 481.27 170.756 487.641C170.756 491.539 171.726 495.255 173.486 498.44C175.048 500.973 178.233 501.762 181.358 501.822C183.042 501.883 184.74 501.686 186.105 501.428V501.458ZM178.946 479.162C179.598 478.191 180.311 477.281 180.903 476.295C181.039 476.098 181.221 475.84 181.358 475.643C181.813 474.87 182.268 474.141 182.723 473.429C183.178 472.655 184.285 473.292 183.77 474.081C183.178 475.052 182.602 476.037 182.01 477.008C181.752 477.327 181.555 477.6 181.358 477.918C180.903 478.57 180.448 479.223 179.993 479.875C179.401 480.648 178.37 479.875 178.946 479.162Z\" fill=\"#FFE200\"><\/path><path d=\"M174.851 472.534C174.26 472.989 173.547 473.383 172.773 473.641C171.014 474.293 168.936 475.006 166.797 475.719C161.534 477.478 155.618 479.42 152.812 481.634C150.34 483.591 149.036 486.063 148.778 488.52C148.641 489.688 148.717 490.796 149.036 491.903C149.294 493.01 149.809 493.981 150.537 494.891C152.812 497.758 157.818 499.183 159.638 495.027C159.319 494.512 159.122 493.92 158.986 493.344C158.849 492.494 158.986 491.66 159.304 490.932C159.562 490.28 159.956 489.704 160.472 489.173C161.124 488.581 161.898 488.126 162.747 487.868C163.718 487.671 164.704 487.671 165.735 487.929C166.706 488.187 167.692 488.703 168.526 489.552C168.981 490.007 169.376 490.598 169.694 491.236C169.497 490.068 169.436 488.824 169.436 487.656C169.436 481.938 171.454 476.675 174.836 472.503L174.851 472.534Z\" fill=\"#FFE200\"><\/path><path d=\"M199.165 459.459C197.481 459.459 195.722 459.52 194.023 459.52C192.461 459.52 190.838 459.52 189.276 459.459C186.94 459.398 185.12 462.326 187.455 464.267C189.533 463.676 191.748 463.357 194.023 463.357C199.165 463.357 204.428 465.041 209.373 466.421C207.75 463.888 202.35 459.338 199.165 459.459Z\" fill=\"#FFE200\"><\/path><path d=\"M153.586 471.29C155.664 470.38 157.681 469.667 159.638 468.878C163.217 467.513 166.661 466.148 170.361 463.994C170.619 463.858 170.877 463.737 171.135 463.6C171.529 462.751 171.59 461.977 171.332 461.188C169.967 461.249 168.86 461.386 167.95 461.507C165.811 461.765 164.962 461.704 164.765 459.368C164.704 458.853 164.704 458.2 164.628 457.351C163.718 457.745 162.869 458.064 162.216 458.398C161.367 458.853 160.654 459.308 160.078 459.763C159.941 459.899 159.623 459.899 159.426 459.823C157.469 458.974 155.33 458.2 153.176 457.806C151.099 457.351 148.945 457.214 146.867 457.487C146.351 457.624 145.957 456.972 146.275 456.517C146.73 455.804 147.246 455.091 147.837 454.378C148.035 454.12 148.232 453.862 148.49 453.605C148.095 453.665 147.716 453.741 147.322 453.862C146.351 454.06 145.502 454.317 144.592 454.636C144.076 454.772 143.621 454.181 143.879 453.726L145.244 451.254C144.076 451.314 142.908 451.511 141.801 451.769C140.375 452.027 138.873 452.482 137.448 453.074C136.993 453.271 136.401 452.679 136.674 452.224L138.297 448.448L138.16 448.387C136.401 448.705 134.642 449.1 132.897 449.494C132.442 449.555 132.048 449.1 132.184 448.645L132.958 446.112C132.761 445.975 132.564 445.915 132.366 445.793C130.683 446.9 129.121 447.613 127.68 448.008C126.375 448.265 125.147 448.265 124.161 447.81C123.114 447.355 122.341 446.445 121.886 445.08C121.491 443.912 121.37 442.289 121.567 440.196C121.506 440.196 121.431 440.136 121.37 440.136L119.413 441.759C119.019 442.077 118.367 441.759 118.367 441.304L118.169 438.24C118.033 438.103 117.912 438.043 117.775 437.982C117.381 438.3 116.926 438.695 116.471 439.089C116.334 439.226 116.213 439.286 116.152 439.347C115.834 439.665 115.181 439.408 115.106 438.953C115.045 438.103 115.045 437.33 115.106 436.617C114.453 437.072 113.801 437.466 113.028 437.724C112.633 437.86 112.178 437.587 112.178 437.208C112.118 436.238 112.042 435.252 112.118 434.342C111.92 434.144 111.663 434.023 111.465 433.887C110.692 434.281 109.903 434.539 109.13 434.539C108.219 434.599 107.309 434.402 106.521 433.947C105.747 433.492 105.095 432.901 104.64 432.066C104.048 431.02 103.73 429.791 103.927 428.29C100.878 425.878 97.951 423.406 95.0843 420.812C94.9478 421.525 94.7658 422.177 94.4927 422.89C93.5827 425.878 92.2783 428.35 90.5947 430.959C89.1689 433.037 87.9858 435.054 87.0758 437.39C86.3022 439.271 84.8613 442.593 85.5742 444.61C86.1657 446.37 88.3043 446.43 89.6694 445.657C90.261 444.094 90.898 442.608 91.4896 441.106C92.2631 439.347 92.9911 437.724 93.704 436.222C94.0984 435.373 95.2056 435.965 94.8113 436.738C94.0984 438.3 93.3855 439.923 92.6726 441.546C92.0204 443.23 91.3075 444.929 90.6553 446.552C90.3368 447.462 90.4581 449.342 90.9132 450.192C91.3075 451.102 92.0811 451.496 93.0518 451.299C94.1591 451.041 95.0691 450.389 95.4635 449.418C95.9792 448.053 96.51 446.749 97.0864 445.52C97.6021 444.155 98.1937 442.79 98.8459 441.364C99.1644 440.515 100.347 441.046 100.014 441.88C99.4222 443.184 98.8459 444.549 98.2543 445.975C97.6628 447.401 97.0864 448.842 96.4949 450.268C95.9792 451.436 95.782 452.937 96.0399 454.242C96.237 455.288 96.8134 456.198 97.7235 456.835C98.77 457.487 100.256 456.244 100.59 455.334C100.909 454.424 101.182 453.514 101.5 452.603L102.152 450.647C102.471 449.797 103.715 450.192 103.381 451.041L102.668 453.059C102.41 453.908 102.077 454.818 101.758 455.728C101.303 457.093 101.167 458.519 101.364 459.884C101.622 461.113 102.137 462.356 103.047 463.327C103.7 464.101 104.276 464.829 105.262 464.374C105.914 464.116 106.49 463.524 106.688 462.948C107.461 460.809 108.25 458.519 108.963 456.32C109.418 455.015 109.812 453.787 110.131 452.998C110.388 452.148 111.632 452.543 111.299 453.392C110.844 454.757 110.525 455.728 110.191 456.714C109.418 458.928 108.69 461.067 107.916 463.342C107.4 464.768 107.4 466.072 107.719 466.922C108.113 467.892 108.887 468.347 109.858 468.287C111.162 468.15 112.451 467.119 112.588 465.814C112.724 464.586 112.906 463.084 113.24 461.461C113.634 459.505 114.15 457.305 114.742 454.894C114.999 454.044 116.243 454.378 115.97 455.212C115.379 457.548 114.863 459.763 114.469 461.719C114.15 463.539 113.877 465.162 113.816 466.527C113.756 467.498 113.877 468.15 114.211 468.484C114.529 468.939 115.06 469 115.576 468.803C116.622 468.484 117.199 467.437 117.714 466.467C118.488 464.965 119.14 463.281 119.671 461.461C120.263 459.247 120.778 456.911 121.173 454.242C121.309 453.392 122.538 453.589 122.401 454.439C122.007 457.169 121.491 459.581 120.9 461.78C120.308 463.737 119.671 465.481 118.822 467.043C117.851 468.924 118.23 472.898 121.097 470.623C122.978 469.197 125.071 465.481 126.299 463.281C126.618 462.629 126.952 462.114 127.149 461.856C127.604 461.082 128.711 461.719 128.195 462.508C127.998 462.826 127.74 463.281 127.422 463.934C126.315 465.814 124.692 468.818 122.811 470.698C121.643 472.003 119.823 474.217 120.217 476.038C120.414 476.948 121.127 477.463 122.037 477.463C123.721 477.524 124.965 475.901 125.814 474.597C126.982 472.64 128.286 470.896 129.591 469.136C131.017 467.255 132.457 465.435 133.883 463.676C134.475 463.024 135.445 463.812 134.854 464.525C133.352 466.285 131.927 468.105 130.622 469.925C129.318 471.548 128.089 473.307 126.921 475.188C126.148 476.356 124.843 477.403 124.449 478.707C124.055 479.875 124.13 480.785 124.449 481.437C124.707 482.029 125.298 482.347 125.951 482.287C127.058 482.15 128.089 481.119 128.681 480.269C130.501 477.676 132.382 475.203 134.399 472.731C136.356 470.319 138.494 467.983 140.648 465.708C141.3 465.056 142.21 465.966 141.558 466.618C139.419 468.833 137.326 471.169 135.385 473.58C133.368 475.916 131.547 478.464 129.727 480.997C129.212 481.847 128.559 482.423 127.968 482.817C127.194 484.638 127.452 486.716 128.226 488.02C128.544 488.414 128.878 488.733 129.196 488.991C131.077 489.961 132.579 486.579 133.034 485.411C134.202 482.544 135.764 480.072 137.584 477.933C139.465 475.856 141.619 474.035 143.955 472.412C144.212 472.215 144.47 472.018 144.865 472.549C145.183 473.065 144.925 473.262 144.667 473.459C142.453 475.021 140.314 476.781 138.555 478.798C136.795 480.876 135.309 483.151 134.262 485.881C133.61 487.565 131.927 489.203 133.671 490.887C133.989 491.205 134.444 491.478 134.899 491.6C135.354 491.797 135.87 491.797 136.401 491.736C137.448 491.6 138.479 490.826 139.131 489.142C139.526 486.473 140.557 483.743 142.059 481.27C144.652 477.114 148.626 473.535 153.51 471.32L153.586 471.29Z\" fill=\"#FFE200\"><\/path><path d=\"M267.055 453.483C261.595 450.753 255.68 449.054 251.19 447.886H251.129C251.387 448.66 251.19 449.388 251.19 450.222C251.129 450.616 250.674 450.935 250.28 450.738C249.309 450.283 248.521 449.828 247.747 449.373C248.141 450.222 248.399 451.132 248.596 452.239C248.657 452.694 248.278 453.089 247.823 452.952C246.518 452.694 245.229 452.3 243.985 451.906C243.728 451.845 242.939 451.314 242.681 451.253C243.394 451.966 244.638 453.074 245.548 453.923C245.942 454.317 245.411 455.152 244.895 454.97C242.817 454.257 241.255 453.407 239.435 452.437C240.148 453.802 241.195 455.303 242.165 456.532C242.484 457.047 241.771 457.836 241.255 457.442C239.374 456.213 237.554 454.848 235.795 453.407C235.537 453.468 235.279 453.604 235.021 453.665C235.416 454.712 235.871 455.743 236.326 456.729C236.584 457.321 235.673 457.897 235.279 457.442C234.43 456.395 233.596 455.364 232.867 454.257C231.639 454.575 230.395 454.909 229.167 455.227C230.334 456.456 231.578 457.639 232.807 458.746C233.52 459.338 232.67 460.309 231.957 459.717C230.456 458.413 229.091 457.048 227.801 455.561C226.831 455.819 225.845 456.016 224.935 456.213L228.378 459.99C228.969 460.642 228.059 461.492 227.407 460.839L223.433 456.547C222.129 456.805 220.764 457.063 219.399 457.321C219.914 457.715 220.445 458.17 221.022 458.549C222.326 459.52 223.615 460.43 225.056 461.34C225.83 461.795 225.117 462.902 224.343 462.447C222.917 461.537 221.552 460.566 220.248 459.58C219.399 458.928 218.564 458.276 217.776 457.563C216.805 457.76 215.758 457.882 214.788 458.018C215.637 459.58 216.547 460.946 217.654 462.174C219.08 463.797 220.642 465.162 222.462 466.269C222.66 466.406 222.857 466.527 223.054 466.664C224.874 467.513 226.694 468.165 228.514 468.878C230.471 469.652 232.412 470.38 234.49 471.29C239.374 473.504 243.333 477.084 245.942 481.24C247.565 483.909 248.612 486.837 248.991 489.688C249.249 491.963 249.051 494.239 248.475 496.453C249.188 497.166 250.432 496.65 251.205 496.135C252.707 495.088 253.875 492.692 254.527 490.159C255.3 487.17 255.437 483.909 254.785 482.089C253.025 477.478 250.295 473.762 246.716 471.032C243.136 468.241 238.722 466.285 233.58 465.056C232.67 464.859 232.989 463.63 233.838 463.827C239.177 465.056 243.788 467.073 247.489 470.001C251.266 472.928 254.117 476.765 255.938 481.634C256.256 482.484 256.393 483.652 256.453 484.88C256.453 485.593 256.848 486.245 257.56 486.64C258.865 487.489 259.578 485.472 259.775 484.501C260.548 480.209 259.32 476.174 257.045 472.867C254.117 468.438 249.309 465.132 244.88 463.63C243.97 463.372 244.425 462.129 245.275 462.462C249.961 464.025 254.967 467.528 258.152 472.155C260.685 475.992 262.05 480.603 260.822 485.548C260.624 486.321 260.564 486.852 261.019 487.626C261.216 488.081 261.671 488.475 262.187 488.338C264.522 487.883 264.977 483.727 265.175 481.968C265.432 480.148 265.569 478.267 265.569 476.31C265.508 473.838 265.175 471.366 264.007 469.348C262.323 466.163 257.181 463.691 253.086 461.613C251.857 461.021 250.674 460.445 249.704 459.854C248.93 459.459 249.506 458.291 250.295 458.746C251.266 459.338 252.434 459.853 253.678 460.506C257.909 462.584 263.233 465.253 265.19 468.757C266.418 470.971 266.813 473.641 266.873 476.295C266.873 478.252 266.676 480.269 266.418 482.15C266.282 483.652 267.465 484.289 268.633 483.318C270.514 481.756 271.757 478.768 272.273 475.643C272.789 472.2 272.531 468.56 271.363 466.482C269.998 463.949 268.041 461.871 265.645 460.111C263.233 458.428 260.382 456.987 257.257 455.758C256.408 455.44 256.863 454.257 257.712 454.59C260.897 455.819 263.885 457.32 266.358 459.141C268.951 460.961 271.045 463.175 272.531 465.905C273.441 467.589 273.896 470.259 273.76 472.989C273.76 473.702 273.502 474.096 274.215 474.612C274.988 475.203 275.898 475.522 276.748 474.748C277.203 474.293 277.597 473.58 277.915 472.792C278.628 470.714 278.826 467.908 278.568 465.966C277.915 460.566 272.91 456.471 267.055 453.483Z\" fill=\"#FFE200\"><\/path><path d=\"M281.1 455.167C279.22 453.028 276.55 451.072 272.91 449.449C271.09 448.6 269.27 447.432 267.51 446.264C266.54 445.611 265.554 445.035 264.583 444.307C263.612 443.594 262.96 443.139 261.656 443.139C261.003 443.139 260.745 443.336 260.882 443.989C261.079 444.641 261.656 445.414 261.989 446.067C261.14 446.067 260.488 446.006 259.653 445.748C258.607 445.49 257.575 445.156 257.378 445.809C256.923 446.855 259.198 448.857 260.245 449.191C262.717 450.101 265.25 451.148 267.662 452.376C273.835 455.501 279.114 459.915 279.887 465.83C279.948 466.679 280.024 467.65 279.948 468.697C280.918 469.47 281.176 469.804 282.284 468.757C283.785 467.256 285.074 464.662 284.619 462.448C284.028 459.854 282.996 457.382 281.1 455.167Z\" fill=\"#FFE200\"><\/path><path d=\"M298.467 436.117C297.952 433.902 297.163 431.763 295.995 430.065C294.888 428.502 293.386 427.471 291.506 427.334C290.99 427.334 290.459 427.395 289.883 427.532C289.17 427.668 288.517 428.047 288.26 428.76C287.865 429.67 288.396 431.172 289.109 431.748C290.671 432.977 292.097 434.615 293.401 436.359C294.964 438.498 296.329 440.712 297.102 442.472C297.3 442.866 297.497 443.321 297.694 443.837C299.12 444.231 298.998 443.973 298.998 442.669C298.998 442.472 298.998 442.214 299.059 441.956C299.12 440.333 298.922 438.179 298.467 436.101V436.117Z\" fill=\"#FFE200\"><\/path><path d=\"M292.355 437.163C291.187 435.479 289.761 433.917 288.32 432.81C287.471 432.097 286.44 431.702 285.454 431.763C284.604 431.899 283.77 432.279 283.042 433.189C282.648 433.644 282.451 434.159 282.526 434.69C282.587 435.919 284.286 437.36 285.059 438.133C287.85 441.061 290.717 444.049 293.189 447.689C293.902 448.796 294.691 450.359 295.009 451.921C295.859 452.239 296.966 452.573 297.421 451.526C297.618 451.011 297.679 450.298 297.679 449.509C297.542 447.295 296.632 444.564 295.919 443.078C295.146 441.319 293.902 439.18 292.34 437.163H292.355Z\" fill=\"#FFE200\"><\/path><path d=\"M284.149 439.043C283.558 438.391 282.921 437.815 282.648 437.481C282.056 436.829 281.146 436.253 280.236 436.055C279.584 435.919 278.932 435.995 278.355 436.51C277.703 437.102 276.732 437.678 276.672 438.725C276.414 440.803 277.976 441.516 279.402 442.82C280.509 443.867 281.616 444.898 282.784 445.884C284.801 447.643 286.561 449.524 287.926 451.799C288.639 453.104 289.23 454.469 289.61 456.031C289.746 456.683 289.867 457.26 290.838 457.396C292.855 457.533 294.023 455.182 293.963 453.438C293.902 451.678 292.992 449.737 292.082 448.432C289.67 444.853 286.879 441.925 284.149 439.074V439.043Z\" fill=\"#FFE200\"><\/path><path d=\"M281.95 446.84C280.782 445.869 279.675 444.762 278.507 443.715C277.4 442.668 276.292 441.576 275.064 440.53C274.093 439.756 272.728 438.968 271.621 438.77C271.166 438.71 270.453 438.573 270.256 439.165C270.059 439.878 270.514 441.121 270.65 441.895C269.543 441.637 266.873 440.075 267.268 442.411C267.723 445.338 271.044 447.158 273.441 448.265C277.278 449.949 280.069 452.042 282.086 454.378C284.104 456.714 285.272 459.383 285.863 462.174C285.924 462.568 286 463.023 286 463.403H286.515C287.107 463.403 287.562 463.205 287.941 462.948C288.336 462.629 288.593 462.174 288.791 461.522C288.851 461.067 288.927 460.612 288.927 460.02C288.791 457.032 288.017 454.499 286.849 452.406C285.621 450.267 283.922 448.432 281.965 446.809L281.95 446.84Z\" fill=\"#FFE200\"><\/path><path d=\"M350.933 230.7C350.28 229.017 348.855 229.138 347.414 229.654C345.396 232.703 343.455 236.024 341.62 239.543C339.739 243.183 337.979 247.021 336.478 250.995C336.159 251.844 334.976 251.389 335.31 250.54C336.811 246.505 338.632 242.607 340.512 238.967C342.393 235.327 344.41 231.944 346.488 228.82C347.717 226.863 348.248 224.785 347.596 222.51C347.277 221.342 346.488 220.235 345.184 220.038C344.926 220.553 344.592 221.084 344.274 221.539C342.196 224.209 340.315 226.939 338.419 229.669C336.599 232.46 334.84 235.266 333.217 238.193C332.762 238.967 331.594 238.39 332.11 237.541C333.732 234.614 335.553 231.747 337.373 228.956C339.253 226.165 341.21 223.435 343.227 220.766C344.077 219.719 344.592 218.551 344.653 217.323C344.79 214.79 341.862 211.347 339.906 214.077C337.494 217.459 335.098 221.039 332.747 224.603C330.214 228.501 327.741 232.475 325.33 236.57C324.875 237.344 323.767 236.707 324.222 235.918C326.695 231.823 329.167 227.788 331.7 223.951C334.172 220.113 336.645 216.413 339.178 212.894C339.633 212.241 339.951 211.589 339.891 210.679C339.891 210.163 339.754 209.708 339.496 209.314C338.723 208.207 337.085 207.949 336.25 208.996C333.52 212.241 331.184 215.502 328.909 218.748C326.573 222.131 324.359 225.634 322.023 229.214C321.568 229.988 320.461 229.275 320.976 228.562C323.312 224.922 325.527 221.479 327.863 218.035C330.274 214.517 332.807 211.149 335.659 207.691C336.372 206.781 336.174 205.552 335.795 204.642C335.598 204.385 335.401 204.127 335.28 203.93C334.051 202.564 332.944 202.428 331.836 203.732C327.544 208.161 322.736 213.227 318.246 220.644C317.791 221.418 316.684 220.781 317.2 219.992C321.75 212.454 326.634 207.373 330.926 202.822C331.836 201.912 332.686 201.321 332.489 199.895C332.352 198.848 331.836 198.014 331.124 197.362C329.698 196.194 329.046 195.997 327.741 197.362C325.527 199.637 323.388 202.307 321.234 205.234C319.096 208.222 316.942 211.407 314.727 214.79C314.591 215.047 314.409 215.305 313.878 214.987C313.362 214.668 313.484 214.395 313.681 214.077C315.895 210.694 318.034 207.448 320.188 204.521C322.402 201.533 324.617 198.803 326.816 196.528C327.923 195.36 328.575 194.45 327.665 192.887C325.982 190.218 324.541 191.917 323.054 193.6C320.84 196.073 318.701 198.606 316.623 201.336C314.545 204.127 312.528 207.054 310.571 210.179C310.374 210.436 310.253 210.694 309.661 210.376C309.146 210.057 309.343 209.784 309.464 209.526C311.481 206.341 313.499 203.353 315.577 200.623C317.715 197.832 319.869 195.223 322.084 192.751C323.13 191.583 323.646 190.734 323.707 190.021C323.843 189.429 323.509 188.853 322.994 188.261C321.765 186.896 318.959 184.03 317.533 187.215C316.168 190.203 314.212 192.554 311.937 194.298C309.404 196.255 306.476 197.544 303.412 198.196C296.132 199.758 288.715 196.634 282.936 192.478C277.021 188.185 271.166 182.134 267.586 175.247C264.462 169.271 262.839 162.309 264.522 155.681C253.526 160.231 243.318 162.507 233.504 162.764C226.224 162.962 217.578 161.991 210.101 159.579C200.151 156.394 187.804 156.394 177.854 159.579C170.377 161.991 161.792 162.962 154.451 162.764C144.637 162.507 134.429 160.231 123.433 155.681C125.116 162.309 123.493 169.271 120.445 175.247C116.804 182.134 110.95 188.185 105.034 192.478C99.2402 196.634 91.8384 199.758 84.5579 198.196C81.5092 197.544 78.5818 196.24 76.0337 194.298C73.7585 192.539 71.8019 190.203 70.4368 187.215C69.011 184.03 66.205 186.896 64.9764 188.261C64.4607 188.853 64.1271 189.429 64.2636 190.021C64.3242 190.734 64.8551 191.583 65.8865 192.751C68.101 195.223 70.2396 197.817 72.3934 200.623C74.4714 203.353 76.4887 206.341 78.506 209.526C78.6425 209.784 78.8245 210.042 78.3088 210.376C77.7173 210.694 77.596 210.436 77.3988 210.179C75.4421 207.054 73.4248 204.127 71.3469 201.336C69.2689 198.606 67.1151 196.073 64.9158 193.6C63.4142 191.917 61.9884 190.218 60.3048 192.887C59.3947 194.45 60.047 195.36 61.1542 196.528C63.3687 198.803 65.5832 201.533 67.7825 204.521C69.9211 207.448 72.1356 210.694 74.2894 214.077C74.4866 214.395 74.6079 214.668 74.0922 214.987C73.5765 215.305 73.3793 215.047 73.2428 214.79C71.0283 211.407 68.8897 208.222 66.7359 205.234C64.5973 202.307 62.4434 199.637 60.229 197.362C58.9245 195.997 58.2723 196.194 56.8466 197.362C56.1337 198.014 55.618 198.864 55.4815 199.895C55.2843 201.321 56.1337 201.912 57.0438 202.822C61.3362 207.373 66.205 212.439 70.7705 219.992C71.2862 220.766 70.179 221.418 69.7239 220.644C65.2343 213.227 60.4261 208.161 56.1337 203.732C55.0265 202.428 53.9192 202.564 52.6906 203.93C52.5541 204.127 52.3721 204.385 52.1749 204.642C51.7806 205.552 51.5834 206.781 52.3114 207.691C55.1781 211.134 57.7111 214.517 60.1076 218.035C62.4434 221.479 64.6579 224.922 66.9937 228.562C67.5094 229.275 66.4022 229.988 65.9472 229.214C63.6114 225.634 61.3969 222.131 59.0611 218.748C56.7859 215.502 54.4501 212.241 51.7199 208.996C50.8705 207.949 49.2476 208.222 48.474 209.314C48.2162 209.708 48.0797 210.163 48.0797 210.679C48.019 211.589 48.3375 212.241 48.7925 212.894C51.3255 216.413 53.7979 220.113 56.2702 223.951C58.8032 227.788 61.2755 231.823 63.7479 235.918C64.2029 236.692 63.0957 237.344 62.6406 236.57C60.229 232.475 57.7566 228.501 55.2236 224.603C52.8878 221.023 50.4762 217.444 48.0645 214.077C46.1079 211.347 43.1805 214.79 43.317 217.323C43.3777 218.551 43.9692 219.734 44.7428 220.766C46.7601 223.435 48.7167 226.165 50.5975 228.956C52.4783 231.747 54.2377 234.614 55.8607 237.541C56.3764 238.39 55.2085 238.967 54.7534 238.193C53.1305 235.266 51.371 232.475 49.5509 229.669C47.6701 226.939 45.7742 224.209 43.6962 221.539C43.3777 221.084 43.044 220.568 42.7861 220.038C41.4817 220.235 40.7082 221.342 40.3745 222.51C39.7223 224.785 40.238 226.863 41.4817 228.82C43.5597 231.944 45.577 235.327 47.4578 238.967C49.3386 242.607 51.1587 246.505 52.6603 250.54C52.9788 251.389 51.8109 251.844 51.4924 250.995C49.9908 247.021 48.2465 243.199 46.3505 239.543C44.5304 236.024 42.5738 232.718 40.5565 229.654C39.1307 229.138 37.6898 229.002 37.0376 230.7C35.7332 234.144 37.2348 237.132 38.6605 240.195C43.8024 251.45 49.0656 262.826 52.7058 275.566C69.4206 213.273 126.512 167.178 193.932 167.178C261.352 167.178 318.459 213.288 335.158 275.566C338.798 262.826 344.062 251.45 349.203 240.195C350.629 237.147 352.131 234.144 350.826 230.7H350.933Z\" fill=\"#FFE200\"><\/path><path d=\"M283.694 191.431C289.155 195.405 296.314 198.454 303.2 196.952C306.067 196.3 308.857 195.132 311.193 193.312C313.332 191.628 315.167 189.474 316.396 186.684C317.366 184.606 317.761 181.936 317.366 179.661C317.169 178.69 316.911 177.78 316.396 177.067C315.622 175.642 313.529 174.337 311.845 174.731C310.48 175.05 309.57 176.294 309.707 177.659C309.843 179.479 311.33 179.676 312.755 179.615C313.013 181.693 313.013 183.65 312.24 185.592C310.677 189.823 306.779 192.296 302.426 192.811C299.696 193.206 296.708 192.872 293.978 192.038C289.685 190.733 285.454 187.882 281.889 184.242C277.991 180.404 274.867 175.596 273.107 171.106C271.803 167.785 271.151 164.342 271.348 160.762C271.606 157.637 272.516 154.452 274.396 151.404C275.625 149.386 277.642 149.326 279.538 149.265C281.04 149.204 282.405 149.128 282.86 147.961C283.254 147.05 282.996 146.08 282.405 145.367C281.631 144.32 280.327 143.744 279.023 143.683C272.713 143.486 267.905 149.144 266.206 154.68C264.189 161.111 265.554 168.664 268.739 174.701C272.243 181.405 277.976 187.321 283.694 191.477V191.431Z\" fill=\"#FFE200\"><\/path><path d=\"M233.565 161.52C242.726 161.262 252.419 159.184 262.702 155.013C264.007 154.498 265.175 153.648 265.766 152.283C266.873 149.75 268.496 147.399 270.574 145.579C253.48 152.147 230.774 155.984 207.113 157.031C215.637 160.216 224.343 161.778 233.58 161.52H233.565Z\" fill=\"#FFE200\"><\/path><path d=\"M76.8527 193.312C79.1885 195.132 81.9945 196.3 84.8461 196.952C91.7322 198.454 98.8913 195.39 104.352 191.431C110.07 187.275 115.803 181.36 119.307 174.656C122.492 168.604 123.918 161.066 121.84 154.635C120.156 149.114 115.333 143.456 109.023 143.638C107.795 143.699 106.414 144.29 105.641 145.322C105.049 146.035 104.792 147.005 105.186 147.915C105.641 149.083 107.006 149.144 108.508 149.22C110.388 149.28 112.406 149.356 113.649 151.358C115.53 154.407 116.44 157.607 116.698 160.717C116.895 164.296 116.243 167.74 114.939 171.061C113.255 175.551 110.055 180.359 106.157 184.196C102.577 187.837 98.3605 190.703 94.068 191.993C91.3378 192.842 88.3498 193.161 85.6196 192.766C81.2665 192.25 77.3684 189.778 75.8061 185.546C75.0933 183.59 75.0326 181.648 75.2904 179.57C76.7162 179.631 78.2178 179.434 78.3391 177.614C78.4756 176.249 77.5656 175.02 76.2005 174.686C74.5169 174.292 72.4237 175.596 71.6502 177.022C71.1345 177.735 70.8766 178.645 70.6795 179.616C70.2851 181.891 70.6795 184.56 71.6502 186.638C72.8788 189.429 74.7141 191.583 76.8527 193.267V193.312Z\" fill=\"#FFE200\"><\/path><path d=\"M125.298 155.014H125.359C135.627 159.17 145.32 161.263 154.496 161.521C155.8 161.657 161.716 161.384 164.643 160.095C167.828 158.73 165.493 155.939 163.02 155.666C146.048 153.846 130.182 150.464 117.502 145.595C119.58 147.415 121.203 149.751 122.31 152.299C122.902 153.603 123.994 154.513 125.298 155.029V155.014Z\" fill=\"#FFE200\"><\/path><path d=\"M287.987 109.753C286.561 109.753 285.257 110.345 284.286 111.255C283.376 112.226 282.724 113.53 282.724 114.956C282.724 117.883 285.135 120.219 287.987 120.219C289.488 120.219 290.778 119.628 291.688 118.718C292.658 117.747 293.25 116.442 293.25 114.941C293.25 112.074 290.914 109.738 287.987 109.738V109.753Z\" fill=\"#FFE200\"><\/path><path d=\"M276.156 141.363C277.46 141.818 278.689 141.423 279.402 140.65C279.66 140.392 279.918 140.058 280.054 139.679C280.115 139.361 280.191 138.966 280.115 138.572C279.978 137.601 279.144 136.615 277.324 136.039C250.204 126.878 222.114 122.251 194.023 122.251C165.933 122.251 137.842 126.862 110.722 136.039C108.902 136.63 108.053 137.601 107.931 138.572C107.871 138.966 107.931 139.345 107.992 139.679C108.129 140.073 108.386 140.392 108.644 140.65C109.357 141.423 110.601 141.818 111.89 141.363C141.346 132.065 167.677 127.378 194.008 127.378C220.339 127.378 246.67 132.065 276.126 141.363H276.156Z\" fill=\"#FFE200\"><\/path><path d=\"M188.957 100.077C188.957 98.5751 187.728 97.4072 186.227 97.4072C184.725 97.4072 183.557 98.5751 183.557 100.077C183.557 101.578 184.725 102.807 186.227 102.807C187.728 102.807 188.957 101.578 188.957 100.077Z\" fill=\"#FFE200\"><\/path><path d=\"M194.038 83.877C195.858 83.877 197.36 82.3754 197.36 80.5552C197.36 78.7351 195.858 77.1729 194.038 77.1729C192.218 77.1729 190.716 78.6745 190.716 80.5552C190.716 82.436 192.218 83.877 194.038 83.877Z\" fill=\"#FFE200\"><\/path><path d=\"M198.133 60.2155C198.133 57.9404 196.313 56.0596 194.038 56.0596C191.763 56.0596 189.943 57.9404 189.943 60.2155C189.943 62.4907 191.763 64.3108 194.038 64.3108C196.313 64.3108 198.133 62.4907 198.133 60.2155Z\" fill=\"#FFE200\"><\/path><path d=\"M197.8 49.75C197.8 47.672 196.116 45.9126 194.023 45.9126C191.93 45.9126 190.246 47.672 190.246 49.75C190.246 51.828 191.93 53.5268 194.023 53.5268C196.116 53.5268 197.8 51.8432 197.8 49.75Z\" fill=\"#FFE200\"><\/path><path d=\"M190.064 70.8784C190.064 73.017 191.884 74.8523 194.038 74.8523C196.192 74.8523 197.997 73.0322 197.997 70.8784C197.997 68.7245 196.177 66.8438 194.038 66.8438C191.899 66.8438 190.064 68.6639 190.064 70.8784Z\" fill=\"#FFE200\"><\/path><path d=\"M194.038 31.6701C198.528 31.6701 202.168 27.9692 202.168 23.4796C202.168 18.99 198.528 15.2891 194.038 15.2891C189.548 15.2891 185.908 18.9293 185.908 23.4796C185.908 28.0299 189.548 31.6701 194.038 31.6701Z\" fill=\"#FFE200\"><\/path><path d=\"M253.92 86.1522C253.92 88.1088 255.482 89.7318 257.424 89.7318C258.395 89.7318 259.305 89.3374 259.957 88.6852C260.609 88.033 261.003 87.1229 261.003 86.1522C261.003 84.1956 259.38 82.6333 257.424 82.6333C255.467 82.6333 253.92 84.1956 253.92 86.1522Z\" fill=\"#FFE200\"><\/path><path d=\"M266.464 72.6985C267.571 72.6985 268.542 72.2435 269.194 71.5913C269.907 70.8784 270.362 69.9077 270.362 68.8004C270.362 66.6618 268.602 64.9023 266.464 64.9023C265.417 64.9023 264.446 65.3574 263.734 66.0703C263.021 66.7831 262.566 67.7539 262.566 68.8004C262.566 70.9391 264.325 72.6985 266.464 72.6985Z\" fill=\"#FFE200\"><\/path><path d=\"M258.925 77.9623C258.925 79.9796 260.609 81.6632 262.702 81.6632C263.749 81.6632 264.659 81.2689 265.296 80.556C266.009 79.9038 266.403 78.9937 266.403 77.9623C266.403 75.8843 264.719 74.1855 262.702 74.1855C261.656 74.1855 260.685 74.5799 260.033 75.2928C259.32 75.945 258.925 76.9157 258.925 77.9623Z\" fill=\"#FFE200\"><\/path><path d=\"M267.177 63.3405C268.284 63.3405 269.255 62.8855 269.968 62.2333C270.681 61.5204 271.075 60.5496 271.075 59.4424C271.075 57.3038 269.315 55.605 267.177 55.605C266.13 55.605 265.159 55.9993 264.447 56.7122C263.734 57.4251 263.339 58.3958 263.339 59.4424C263.339 61.581 265.099 63.3405 267.177 63.3405Z\" fill=\"#FFE200\"><\/path><path d=\"M266.464 53.5113C267.571 53.5113 268.542 53.0563 269.255 52.3434C270.028 51.6305 270.423 50.6598 270.423 49.5525C270.423 47.3381 268.663 45.5786 266.464 45.5786C265.357 45.5786 264.386 46.0336 263.673 46.7465C262.96 47.4594 262.505 48.4301 262.505 49.5374C262.505 51.7519 264.264 53.5113 266.479 53.5113H266.464Z\" fill=\"#FFE200\"><\/path><path d=\"M267.374 43.3041C269.588 43.3041 271.348 41.5447 271.348 39.3454C271.348 37.146 269.588 35.4473 267.374 35.4473C265.159 35.4473 263.476 37.2067 263.476 39.3454C263.476 41.484 265.235 43.3041 267.374 43.3041Z\" fill=\"#FFE200\"><\/path><path d=\"M257.5 40.5133C259.638 40.5133 261.398 38.6932 261.398 36.5394C261.398 34.3856 259.638 32.5654 257.5 32.5654C255.361 32.5654 253.526 34.3856 253.526 36.5394C253.526 38.6932 255.285 40.5133 257.5 40.5133Z\" fill=\"#FFE200\"><\/path><path d=\"M248.581 36.9938C249.628 36.9938 250.598 36.5388 251.311 35.8259C252.024 35.1737 252.479 34.203 252.479 33.0957C252.479 30.9571 250.72 29.2583 248.581 29.2583C247.534 29.2583 246.564 29.6527 245.851 30.3655C245.138 31.0784 244.683 32.0492 244.683 33.0957C244.683 35.2344 246.442 36.9938 248.581 36.9938Z\" fill=\"#FFE200\"><\/path><path d=\"M238.571 35.4321C239.617 35.4321 240.527 34.9771 241.24 34.3249C241.892 33.612 242.287 32.7019 242.287 31.716C242.287 29.6381 240.664 28.0151 238.586 28.0151C237.615 28.0151 236.629 28.4095 235.992 29.0617C235.34 29.7746 234.885 30.6846 234.885 31.7312C234.885 33.7485 236.568 35.4321 238.586 35.4321H238.571Z\" fill=\"#FFE200\"><\/path><path d=\"M229.212 34.0669C230.259 34.0669 231.169 33.6118 231.821 32.9596C232.534 32.3074 232.928 31.3367 232.928 30.366C232.928 28.288 231.244 26.665 229.227 26.665C228.181 26.665 227.271 27.0594 226.633 27.7116C225.921 28.4245 225.526 29.3346 225.526 30.3811C225.526 32.3984 227.21 34.082 229.227 34.082L229.212 34.0669Z\" fill=\"#FFE200\"><\/path><path d=\"M220.036 32.5803C221.006 32.5803 221.916 32.1859 222.569 31.5337C223.221 30.8208 223.676 29.9108 223.676 28.94C223.676 26.9227 221.992 25.2998 220.036 25.2998C218.989 25.2998 218.079 25.6942 217.442 26.3464C216.79 27.0593 216.335 27.9693 216.335 28.9552C216.335 30.9725 218.018 32.5955 220.036 32.5955V32.5803Z\" fill=\"#FFE200\"><\/path><path d=\"M211.39 31.5336C213.271 31.5336 214.833 29.9713 214.833 28.0905C214.833 26.2097 213.271 24.6475 211.39 24.6475C209.509 24.6475 207.886 26.2097 207.886 28.0905C207.886 29.9713 209.448 31.5336 211.39 31.5336Z\" fill=\"#FFE200\"><\/path><path d=\"M276.747 47.1412C277.855 47.1412 278.886 46.6862 279.614 45.9126H279.675C280.388 45.1998 280.843 44.1532 280.843 43.046C280.843 40.7708 279.023 38.9507 276.747 38.9507C275.64 38.9507 274.609 39.4057 273.881 40.1186C273.107 40.8921 272.652 41.878 272.652 43.046C272.652 45.2604 274.472 47.1412 276.747 47.1412Z\" fill=\"#FFE200\"><\/path><path d=\"M286.106 48.9005C287.213 48.9005 288.245 48.3848 288.973 47.6719C289.746 46.959 290.201 45.9125 290.201 44.8052C290.201 42.5301 288.32 40.71 286.106 40.71C284.938 40.71 283.967 41.165 283.179 41.8779C282.466 42.6514 282.011 43.6373 282.011 44.8052C282.011 47.0197 283.831 48.9005 286.106 48.9005Z\" fill=\"#FFE200\"><\/path><path d=\"M296.056 52.2831C297.36 52.2831 298.589 51.6915 299.438 50.8573C300.288 50.0079 300.803 48.84 300.803 47.5356C300.803 44.9419 298.665 42.7881 296.056 42.7881C294.751 42.7881 293.584 43.3038 292.734 44.1532C291.885 45.0632 291.308 46.2311 291.308 47.5356C291.308 50.1292 293.447 52.2831 296.056 52.2831Z\" fill=\"#FFE200\"><\/path><path d=\"M305.869 57.8642C307.235 57.8642 308.463 57.2726 309.388 56.3626C310.314 55.4525 310.89 54.2239 310.89 52.8588C310.89 50.1287 308.615 47.8535 305.885 47.8535C304.52 47.8535 303.291 48.4451 302.366 49.3551C301.456 50.2652 300.864 51.4938 300.864 52.874C300.864 55.6042 303.139 57.8793 305.869 57.8793V57.8642Z\" fill=\"#FFE200\"><\/path><path d=\"M309.054 62.0354C309.054 64.9021 311.39 67.2379 314.196 67.2379C317.002 67.2379 319.399 64.9021 319.399 62.0354C319.399 59.1687 317.063 56.8936 314.196 56.8936C311.33 56.8936 309.054 59.2294 309.054 62.0354Z\" fill=\"#FFE200\"><\/path><path d=\"M313.878 73.8056C313.878 76.5358 316.092 78.811 318.883 78.811C321.674 78.811 323.828 76.5358 323.828 73.8056C323.828 71.0754 321.613 68.8003 318.883 68.8003C316.153 68.8003 313.878 71.0754 313.878 73.8056Z\" fill=\"#FFE200\"><\/path><path d=\"M322.842 85.4397C322.842 83.028 320.885 81.0107 318.489 81.0107C316.092 81.0107 314.06 83.028 314.06 85.4397C314.06 87.8514 316.077 89.8687 318.489 89.8687C320.901 89.8687 322.842 87.8514 322.842 85.4397Z\" fill=\"#FFE200\"><\/path><path d=\"M319.46 94.9346C319.46 92.8566 317.776 91.0972 315.622 91.0972C313.468 91.0972 311.785 92.8566 311.785 94.9346C311.785 97.0126 313.544 98.772 315.622 98.772C317.7 98.772 319.46 97.0884 319.46 94.9346Z\" fill=\"#FFE200\"><\/path><path d=\"M311.663 107.357C313.802 107.357 315.562 105.598 315.562 103.52C315.562 101.442 313.802 99.6216 311.663 99.6216C309.525 99.6216 307.826 101.381 307.826 103.52C307.826 105.658 309.585 107.357 311.663 107.357Z\" fill=\"#FFE200\"><\/path><path d=\"M272.258 64.7055C271.864 68.4064 270.953 71.986 269.528 75.2319C267.965 78.7356 266.145 82.1938 264.067 85.3032C262.111 88.2912 259.911 91.0214 257.697 93.0994C257.303 93.5544 257.045 93.8729 257.105 94.2673C257.166 94.7223 257.5 95.3139 258.152 96.1481C258.349 96.3453 258.546 96.5425 258.743 96.6638C259.456 97.1188 260.306 96.9823 261.276 96.4059C262.384 95.6931 263.552 94.4493 264.72 92.9629C267.192 89.7777 269.664 85.288 271.484 81.3293C273.82 76.3846 275.064 72.0922 275.64 67.6784C276.232 62.6124 275.959 57.5312 275.64 52.4652C275.443 50.3266 275.322 47.5812 273.107 47.2627C272.516 47.202 272.258 47.7784 272.137 48.5671C272 49.6137 272.137 50.9788 272.273 51.8888C272.728 56.1206 272.789 60.4737 272.273 64.7055H272.258Z\" fill=\"#FFE200\"><\/path><path d=\"M258.152 44.6082C257.56 43.956 256.923 43.501 256.195 43.501C254.633 43.5616 254.436 44.4717 254.314 45.3818C254.117 46.7469 254.967 47.8541 255.361 49.2799C256.468 53.0566 256.923 56.7575 256.787 60.4584C256.59 64.1593 255.877 67.7996 254.572 71.455C253.859 73.533 252.949 75.3531 251.903 77.1125C250.796 78.872 249.628 80.5556 248.46 82.2544C247.352 83.756 247.034 84.666 247.231 85.1211C247.428 85.5761 248.081 85.834 249.051 86.0918C251.842 86.744 252.949 84.8632 254.117 82.8459C254.436 82.3302 254.769 81.7387 255.164 81.1623C258.743 75.8991 260.821 70.4994 261.595 65.0997C262.444 59.3057 261.853 53.5268 260.033 48.0664C259.714 47.0199 259.062 45.5941 258.152 44.6234V44.6082Z\" fill=\"#FFE200\"><\/path><path d=\"M130.637 89.7318C132.594 89.7318 134.156 88.1088 134.156 86.1522C134.156 84.1956 132.594 82.6333 130.637 82.6333C128.681 82.6333 127.058 84.1956 127.058 86.1522C127.058 87.1229 127.452 88.033 128.104 88.6852C128.756 89.3374 129.666 89.7318 130.637 89.7318Z\" fill=\"#FFE200\"><\/path><path d=\"M121.597 72.6985C123.736 72.6985 125.495 70.9391 125.495 68.8004C125.495 67.7539 125.04 66.7831 124.327 66.0703C123.615 65.3574 122.644 64.9023 121.597 64.9023C119.459 64.9023 117.699 66.6618 117.699 68.8004C117.699 69.9077 118.154 70.8784 118.867 71.5913C119.519 72.2435 120.49 72.6985 121.597 72.6985Z\" fill=\"#FFE200\"><\/path><path d=\"M125.374 81.6632C127.452 81.6632 129.151 79.9796 129.151 77.9623C129.151 76.9157 128.757 75.945 128.044 75.2928C127.391 74.5799 126.421 74.1855 125.374 74.1855C123.357 74.1855 121.673 75.8692 121.673 77.9623C121.673 79.0089 122.068 79.9189 122.78 80.556C123.433 81.2689 124.343 81.6632 125.374 81.6632Z\" fill=\"#FFE200\"><\/path><path d=\"M124.722 59.4268C124.722 58.3802 124.328 57.4095 123.615 56.6966C122.902 55.9837 121.931 55.5894 120.885 55.5894C118.746 55.5894 116.986 57.273 116.986 59.4268C116.986 60.534 117.381 61.5047 118.094 62.2176C118.807 62.8698 119.777 63.3249 120.885 63.3249C122.963 63.3249 124.722 61.5654 124.722 59.4268Z\" fill=\"#FFE200\"><\/path><path d=\"M121.597 45.5786C119.383 45.5786 117.623 47.3381 117.623 49.5525C117.623 50.6598 118.018 51.6305 118.791 52.3434C119.504 53.0563 120.475 53.5113 121.582 53.5113C123.797 53.5113 125.541 51.7519 125.541 49.5374C125.541 48.4301 125.086 47.4594 124.373 46.7465C123.66 46.0336 122.689 45.5786 121.582 45.5786H121.597Z\" fill=\"#FFE200\"><\/path><path d=\"M120.687 43.3041C122.826 43.3041 124.585 41.5447 124.585 39.3454C124.585 37.146 122.826 35.4473 120.687 35.4473C118.549 35.4473 116.713 37.2067 116.713 39.3454C116.713 41.484 118.473 43.3041 120.687 43.3041Z\" fill=\"#FFE200\"><\/path><path d=\"M130.562 40.5133C132.776 40.5133 134.52 38.6932 134.52 36.5394C134.52 34.3856 132.761 32.5654 130.562 32.5654C128.362 32.5654 126.663 34.3856 126.663 36.5394C126.663 38.6932 128.423 40.5133 130.562 40.5133Z\" fill=\"#FFE200\"><\/path><path d=\"M139.48 36.9938C141.619 36.9938 143.378 35.2344 143.378 33.0957C143.378 32.0492 142.923 31.0784 142.21 30.3655C141.497 29.6527 140.527 29.2583 139.48 29.2583C137.341 29.2583 135.582 30.9419 135.582 33.0957C135.582 34.203 136.037 35.1737 136.75 35.8259C137.463 36.5388 138.434 36.9938 139.48 36.9938Z\" fill=\"#FFE200\"><\/path><path d=\"M149.491 35.4321C151.508 35.4321 153.192 33.7485 153.192 31.7312C153.192 30.6846 152.737 29.7746 152.084 29.0617C151.432 28.4095 150.461 28.0151 149.491 28.0151C147.413 28.0151 145.79 29.6381 145.79 31.716C145.79 32.6868 146.184 33.5968 146.897 34.3249C147.549 34.9771 148.459 35.4321 149.491 35.4321Z\" fill=\"#FFE200\"><\/path><path d=\"M158.849 34.0664C160.866 34.0664 162.55 32.3828 162.55 30.3655C162.55 29.3189 162.156 28.4089 161.443 27.696C160.791 27.0438 159.881 26.6494 158.849 26.6494C156.832 26.6494 155.148 28.2724 155.148 30.3503C155.148 31.3211 155.543 32.307 156.255 32.944C156.908 33.5962 157.818 34.0512 158.849 34.0512V34.0664Z\" fill=\"#FFE200\"><\/path><path d=\"M168.026 32.5798C170.043 32.5798 171.727 30.9569 171.727 28.9396C171.727 27.9689 171.272 27.0588 170.619 26.3307C169.967 25.6785 169.057 25.2842 168.01 25.2842C166.054 25.2842 164.37 26.9071 164.37 28.9244C164.37 29.8952 164.825 30.8052 165.477 31.5181C166.13 32.1703 167.04 32.5647 168.01 32.5647L168.026 32.5798Z\" fill=\"#FFE200\"><\/path><path d=\"M176.671 31.5336C178.628 31.5336 180.19 29.9713 180.19 28.0905C180.19 26.2097 178.628 24.6475 176.671 24.6475C174.714 24.6475 173.228 26.2097 173.228 28.0905C173.228 29.9713 174.79 31.5336 176.671 31.5336Z\" fill=\"#FFE200\"><\/path><path d=\"M108.462 45.9126C109.175 46.6862 110.222 47.1412 111.329 47.1412C113.604 47.1412 115.424 45.2604 115.424 43.046C115.424 41.878 114.969 40.9073 114.195 40.1186C113.483 39.4057 112.436 38.9507 111.329 38.9507C109.054 38.9507 107.234 40.7708 107.234 43.046C107.234 44.1532 107.689 45.1846 108.401 45.9126H108.462Z\" fill=\"#FFE200\"><\/path><path d=\"M101.955 48.9005C104.23 48.9005 106.05 47.0197 106.05 44.8052C106.05 43.6373 105.595 42.6666 104.882 41.8779C104.109 41.165 103.123 40.71 101.955 40.71C99.7407 40.71 97.8599 42.5301 97.8599 44.8052C97.8599 45.9125 98.3149 46.9439 99.0884 47.6719C99.8013 48.3848 100.848 48.9005 101.955 48.9005Z\" fill=\"#FFE200\"><\/path><path d=\"M92.0052 52.2831C94.5988 52.2831 96.7527 50.1444 96.7527 47.5356C96.7527 46.2311 96.1611 45.0632 95.3269 44.1532C94.4775 43.3038 93.3096 42.7881 92.0052 42.7881C89.4115 42.7881 87.2577 44.9267 87.2577 47.5356C87.2577 48.84 87.7734 50.0079 88.6228 50.8573C89.4722 51.7067 90.7008 52.2831 92.0052 52.2831Z\" fill=\"#FFE200\"><\/path><path d=\"M82.1918 57.8647C84.9219 57.8647 87.1971 55.5895 87.1971 52.8594C87.1971 51.4943 86.6056 50.2505 85.6955 49.3405C84.7854 48.4304 83.5569 47.8389 82.1766 47.8389C79.4464 47.8389 77.1713 50.114 77.1713 52.8442C77.1713 54.2093 77.7628 55.4379 78.6729 56.3479C79.5829 57.258 80.8115 57.8495 82.1766 57.8495L82.1918 57.8647Z\" fill=\"#FFE200\"><\/path><path d=\"M73.8646 67.2379C76.6555 67.2379 79.0065 64.9021 79.0065 62.0354C79.0065 59.1687 76.6706 56.8936 73.8646 56.8936C71.0586 56.8936 68.6621 59.2294 68.6621 62.0354C68.6621 64.8414 70.9979 67.2379 73.8646 67.2379Z\" fill=\"#FFE200\"><\/path><path d=\"M69.1931 78.811C71.9839 78.811 74.1984 76.5358 74.1984 73.8056C74.1984 71.0754 71.9839 68.8003 69.1931 68.8003C66.4022 68.8003 64.2484 71.0754 64.2484 73.8056C64.2484 76.5358 66.4629 78.811 69.1931 78.811Z\" fill=\"#FFE200\"><\/path><path d=\"M74.0012 85.4397C74.0012 83.028 71.9839 81.0107 69.5722 81.0107C67.1606 81.0107 65.2191 83.028 65.2191 85.4397C65.2191 87.8514 67.1758 89.8687 69.5722 89.8687C71.9687 89.8687 74.0012 87.8514 74.0012 85.4397Z\" fill=\"#FFE200\"><\/path><path d=\"M72.439 98.772C74.517 98.772 76.2764 97.0884 76.2764 94.9346C76.2764 92.7808 74.517 91.0972 72.439 91.0972C70.361 91.0972 68.6016 92.8566 68.6016 94.9346C68.6016 97.0126 70.2852 98.772 72.439 98.772Z\" fill=\"#FFE200\"><\/path><path d=\"M72.4995 103.52C72.4995 105.598 74.259 107.357 76.3976 107.357C78.5362 107.357 80.235 105.598 80.235 103.52C80.235 101.442 78.4756 99.6216 76.3976 99.6216C74.3196 99.6216 72.4995 101.381 72.4995 103.52Z\" fill=\"#FFE200\"><\/path><path d=\"M112.421 52.4797C112.102 57.5457 111.829 62.6269 112.421 67.6929C113.012 72.1219 114.241 76.3992 116.577 81.3438C118.397 85.3026 120.869 89.7922 123.342 92.9774C124.51 94.479 125.677 95.7076 126.785 96.4205C127.755 97.012 128.605 97.1334 129.318 96.6783C129.515 96.5418 129.712 96.3598 129.909 96.1626C130.561 95.3133 130.88 94.7369 130.956 94.2819C131.016 93.8875 130.759 93.569 130.364 93.1139C128.15 91.036 125.935 88.3058 123.994 85.3178C121.916 82.1932 120.096 78.7502 118.533 75.2464C117.108 72.0005 116.198 68.421 115.803 64.7201C115.288 60.4883 115.348 56.1352 115.803 51.9034C115.94 50.9933 116.061 49.6282 115.94 48.5816C115.803 47.8081 115.545 47.2166 114.969 47.2772C112.755 47.5958 112.633 50.3411 112.436 52.4797H112.421Z\" fill=\"#FFE200\"><\/path><path d=\"M132.912 81.1472C133.307 81.7387 133.625 82.3151 133.959 82.8308C135.127 84.8481 136.234 86.7289 139.025 86.0767C139.996 85.8188 140.648 85.561 140.845 85.1059C141.042 84.6509 140.709 83.7409 139.617 82.2393C138.449 80.5556 137.281 78.8569 136.234 77.0974C135.127 75.338 134.217 73.5178 133.504 71.4399C132.2 67.7996 131.487 64.1594 131.29 60.4433C131.153 56.7424 131.608 53.0263 132.715 49.2647C133.11 47.839 133.944 46.7317 133.762 45.3666C133.625 44.4566 133.443 43.5465 131.881 43.4858C131.168 43.4858 130.516 43.9409 129.924 44.5931C129.014 45.5638 128.362 47.0047 128.044 48.0361C126.224 53.4965 125.632 59.2906 126.481 65.0694C127.255 70.4691 129.348 75.8688 132.912 81.132V81.1472Z\" fill=\"#FFE200\"><\/path><path d=\"M78.4149 68.4059C73.8039 74.6549 74.259 82.6483 76.2004 89.7923C77.884 95.7683 80.9479 101.502 84.6488 106.765C85.0432 107.281 85.5589 107.478 86.1504 107.356C87.197 107.099 88.2891 107.038 89.3356 107.159C90.185 107.296 90.3822 106.386 89.9878 105.794C87.652 102.67 85.5589 99.2872 83.9359 95.7835C81.9793 91.6882 80.69 87.3958 80.2957 83.0427C79.6435 75.3072 82.5102 67.8295 87.7734 61.6562C84.5275 63.082 81.0086 64.8415 78.4149 68.421V68.4059Z\" fill=\"#FFE200\"><\/path><path d=\"M298.134 54.9526C297.224 54.4369 296.314 53.9818 295.343 53.5268C293.978 52.8746 292.021 54.4369 293.523 55.4834C294.691 56.3328 295.798 57.2429 296.905 58.2136C298.407 59.5787 301.258 56.7879 298.134 54.9677V54.9526Z\" fill=\"#FFE200\"><\/path><path d=\"M304.11 95.7842C301.896 100.592 298.771 105.082 295.525 109.117C294.297 110.618 293.902 112.241 294.16 113.409C294.357 114.001 294.752 114.516 295.389 114.577C296.299 114.577 297.603 113.925 299.09 112.165C304.747 105.598 309.555 97.9228 311.83 89.7929C313.651 83.0888 313.711 76.2027 310.92 69.4986C309.04 65.009 306.309 61.3687 303.048 58.4413C301.168 56.8791 299.014 60.125 300.318 61.6872C305.581 67.8605 308.387 75.3381 307.735 83.013C307.341 87.3661 306.052 91.6586 304.095 95.7538L304.11 95.7842Z\" fill=\"#FFE200\"><\/path><path d=\"M194.038 459.52C274.533 459.52 340.209 393.844 340.209 313.288C340.209 232.733 274.533 167.178 194.038 167.178C113.543 167.178 47.8521 232.854 47.8521 313.288C47.8521 393.723 113.528 459.52 194.023 459.52H194.038Z\" fill=\"#ED1B24\"><\/path><path d=\"M194.038 113.924C193.977 114.637 191.702 117.504 191.05 117.822H193.067C193.522 117.504 193.841 117.17 194.038 116.715C194.235 117.17 194.554 117.489 195.009 117.822H197.026C196.374 117.504 194.099 114.637 194.038 113.924Z\" fill=\"black\"><\/path><path d=\"M194.038 103.064C193.977 103.717 191.702 106.052 191.05 106.31H193.067C193.522 106.052 193.841 105.795 194.038 105.4C194.235 105.795 194.554 106.052 195.009 106.31H197.026C196.374 106.052 194.099 103.717 194.038 103.064Z\" fill=\"black\"><\/path><path d=\"M156.255 119.127L155.345 119.9C151.189 123.677 146.048 124.587 139.935 122.827L138.706 122.433L139.753 121.72C142.089 119.961 144.561 118.929 147.094 118.535C149.627 118.08 152.297 118.217 155.027 118.854L156.255 119.111V119.127Z\" fill=\"black\"><\/path><path d=\"M169.846 104.884C169.846 105.4 167.828 107.675 167.252 108.009L169.269 107.751C169.664 107.493 169.921 107.235 170.179 106.902C170.437 107.159 170.832 107.417 171.226 107.554L173.243 107.357C172.591 107.22 170.058 105.4 169.861 104.884H169.846Z\" fill=\"black\"><\/path><path d=\"M144.607 107.873C144.667 108.464 142.923 111.118 142.392 111.513L144.349 111.058C144.743 110.739 145.001 110.406 145.123 110.011C145.441 110.269 145.835 110.466 146.29 110.603L148.247 110.148C147.595 110.087 144.804 108.388 144.607 107.873Z\" fill=\"black\"><\/path><path d=\"M117.563 114.956C117.623 115.547 116.137 118.338 115.606 118.732L117.487 118.141C117.805 117.822 118.078 117.489 118.2 117.094C118.518 117.352 118.913 117.489 119.368 117.61L121.324 117.018C120.672 116.958 117.805 115.456 117.548 114.94L117.563 114.956Z\" fill=\"black\"><\/path><path d=\"M153.449 119.839C151.311 119.445 149.293 119.445 147.337 119.779C145.32 120.097 143.439 120.825 141.619 121.993C146.169 123.04 150.143 122.312 153.449 119.855V119.839Z\" fill=\"#ED1B24\"><\/path><path d=\"M231.806 119.127L232.716 119.9C236.948 123.677 242.013 124.587 248.126 122.827L249.355 122.433L248.308 121.72C245.972 119.961 243.5 118.929 240.967 118.535C238.434 118.08 235.764 118.217 233.034 118.854L231.806 119.111V119.127Z\" fill=\"black\"><\/path><path d=\"M218.215 104.884C218.215 105.4 220.233 107.675 220.809 108.009L218.792 107.751C218.397 107.493 218.14 107.235 217.882 106.902C217.624 107.159 217.23 107.417 216.835 107.554L214.818 107.357C215.47 107.22 218.003 105.4 218.2 104.884H218.215Z\" fill=\"black\"><\/path><path d=\"M243.454 107.873C243.394 108.464 245.138 111.118 245.669 111.513L243.712 111.058C243.394 110.739 243.121 110.406 242.939 110.011C242.62 110.269 242.226 110.466 241.771 110.603L239.814 110.148C240.466 110.087 243.257 108.388 243.454 107.873Z\" fill=\"black\"><\/path><path d=\"M270.498 114.956C270.438 115.547 271.924 118.338 272.455 118.732L270.574 118.141C270.256 117.822 269.983 117.489 269.861 117.094C269.543 117.352 269.148 117.489 268.693 117.61L266.737 117.018C267.389 116.958 270.256 115.456 270.514 114.94L270.498 114.956Z\" fill=\"black\"><\/path><path d=\"M234.612 119.839C236.75 119.445 238.768 119.445 240.724 119.779C242.741 120.097 244.622 120.825 246.442 121.993C241.892 123.04 237.918 122.312 234.612 119.855V119.839Z\" fill=\"#ED1B24\"><\/path><path d=\"M247.095 93.4331C246.898 99.1513 247.034 97.6649 252.1 100.319C249.688 99.6064 247.292 99.1513 245.138 100.577C243.97 98.2413 241.695 97.4525 239.223 96.8762C244.941 97.0733 244.365 98.4384 247.095 93.4331Z\" fill=\"black\"><\/path><path d=\"M140.967 93.4331C141.164 99.1513 141.027 97.6649 135.961 100.319C138.373 99.6064 140.769 99.1513 142.923 100.577C144.091 98.2413 146.366 97.4525 148.839 96.8762C143.12 97.0733 143.697 98.4384 140.967 93.4331Z\" fill=\"black\"><\/path><path d=\"M148.581 63.0675C146.048 66.1921 142.074 66.7078 140.845 70.4845C140.254 72.1681 141.695 73.5484 143.06 73.9276C144.622 74.4433 145.396 72.1075 147.094 71.5159C146.381 72.3653 145.866 73.5332 146.321 74.1854C146.836 73.4119 147.291 72.881 148.596 72.5625C146.518 75.5505 147.428 76.0814 148.99 75.8842C149.9 75.8235 150.492 74.9742 151.584 74.4585C151.523 74.7163 148.657 77.3858 150.992 77.583C151.508 77.6437 153.207 76.8701 153.662 76.4151C153.525 77.4617 151.902 77.8408 153.465 78.6902C154.314 79.2059 155.346 78.2352 156.134 77.9167C154.253 80.5104 155.164 81.0412 156.331 80.6469C157.181 80.3283 157.894 79.4183 159.259 79.4183C158.485 80.0705 157.833 80.1918 157.833 81.0412C157.894 83.7714 160.427 83.5742 161.868 83.3164C160.821 84.0899 161.868 87.2145 162.323 87.2903C164.992 87.6088 165.644 86.8353 168.117 86.1224C171.696 85.0151 172.409 80.207 172.348 74.0338C172.288 68.6341 171.636 63.113 170.726 61.4143C169.618 61.0957 167.025 62.5822 167.025 64.1444C166.827 63.4316 166.372 62.84 165.978 62.84C165.129 62.9007 164.294 64.1444 163.566 64.463C160.958 65.6309 163.172 62.1271 163.172 61.93C159.532 61.7934 159.532 66.9353 159.532 61.6114C156.999 61.2171 155.3 66.4196 155.497 61.8693C153.874 60.4435 152.631 61.8086 151.66 62.9765C150.947 63.8866 150.295 64.6601 150.234 64.2809C150.098 63.5074 150.553 62.1423 150.431 61.7479C150.173 61.0351 148.808 62.8552 148.611 63.113L148.581 63.0675Z\" fill=\"#ED1B24\"><\/path><path d=\"M220.233 59.0472C220.551 61.383 220.233 62.4903 219.914 63.734C218.231 69.1337 220.688 74.1997 220.506 79.6601C222.584 80.8887 222.387 78.8107 223.039 77.1271C224.267 71.7274 229.348 85.4541 235.127 79.6601C237.008 77.1878 240.588 74.5182 244.289 74.8519C249.173 77.84 247.019 63.9919 245.654 63.279C245.138 63.0211 244.031 63.6734 244.031 63.4762C243.894 62.3083 243.439 61.5196 242.802 61.5196C241.634 61.2617 241.179 62.1111 240.921 63.3397C240.785 64.1891 239.875 63.5975 239.951 61.7774C239.298 62.3689 238.843 63.5975 238.586 63.7947C238.07 64.1891 238.722 63.7947 238.191 62.2324C237.736 60.7308 237.145 59.8966 236.568 62.4296C236.174 64.0525 234.232 66.7221 231.229 64.9626C229.864 64.1132 229.606 60.0179 227.453 59.5629C226.345 59.3657 227.195 60.7308 226.285 60.6095C226.027 60.5488 225.83 59.8359 225.314 59.4416C224.404 58.7894 225.708 59.7601 223.099 56.3777C220.824 53.5869 219.975 57.5456 220.233 59.0472Z\" fill=\"#ED1B24\"><\/path><path d=\"M273.881 97.6042C272.516 97.7407 271.606 98.3777 271.272 99.6215C270.559 102.488 275.367 101.699 278.234 101.305C282.845 100.714 282.466 104.627 285.12 103.717C286.682 103.201 285.833 97.0127 287.85 95.0712C288.897 94.1005 291.354 93.0539 291.748 92.0073C292.522 89.9293 291.035 88.1092 288.047 87.3205C286.819 87.0627 286.622 85.7582 284.801 85.8947C282.39 86.0313 281.616 87.9727 280.448 89.7928C279.538 91.1579 278.568 92.523 276.929 93.1752C274.912 93.9488 274.715 96.1026 273.881 97.6042Z\" fill=\"#ED1B24\"><\/path><path d=\"M110.934 94.0852C113.801 97.9226 117.639 100.911 120.096 100.713C122.113 100.395 123.16 97.9833 121.977 95.3744C119.504 89.7169 114.817 88.0333 114.696 81.587C110.995 79.9034 106.824 81.1927 102.41 83.4071C97.0105 87.3811 91.808 89.9747 82.6467 89.004C83.8146 93.0993 85.6954 96.9974 87.9099 100.577C90.4429 100.638 92.263 99.5304 92.6574 97.3917C92.9152 96.2845 93.8253 94.2065 95.5848 94.2065C94.3562 95.1166 93.3703 97.4524 94.614 97.9833C96.7527 98.954 97.8599 92.9173 99.8165 92.4622C99.3008 93.6302 97.0864 96.5575 99.4222 96.5575C101.242 96.239 101.106 92.9173 103.002 93.1145C103.26 94.161 102.744 96.6334 104.23 96.5575C106.308 96.0418 105.656 93.0538 106.961 93.0538C106.642 96.0418 110.009 95.5261 110.934 94.1004V94.0852Z\" fill=\"#ED1B24\"><\/path><path d=\"M235.977 135.447C237.539 136.221 240.269 136.357 242.408 136.297C246.443 136.16 244.031 138.83 246.564 138.83C250.72 138.83 253.844 143.714 250.007 145.595C249.097 146.05 247.535 145.989 245.851 145.989C244.349 146.444 248.9 148.325 244.622 148.977C242.999 149.235 238.313 147.87 238.313 150.736C238.313 152.359 233.429 153.33 232.064 153.527C219.899 155.211 206.9 156.06 194.023 156.06C185.635 156.06 177.187 155.666 168.981 155.014C166.19 154.756 166.115 152.541 163.384 151.829C161.883 151.434 159.941 151.631 157.924 151.434C153.434 150.979 153.95 147.657 149.855 148.31C146.215 148.901 142.635 146.489 143.227 144.669C143.621 143.623 145.896 143.046 149.278 142.713C146.867 141.742 147.519 142.121 144.925 142.061C141.877 142 141.088 141.469 141.937 140.559C142.65 139.846 147.276 139.588 144.212 138.997C139.601 138.087 147.731 135.933 148.566 135.554C151.887 134.128 154.739 132.035 158.379 131.458C170.468 129.578 182.238 128.667 194.008 128.667C203.821 128.667 213.65 129.32 223.6 130.624C227.953 131.14 232.124 133.551 235.962 135.432L235.977 135.447Z\" fill=\"#ED1B24\"><\/path><path d=\"M227.847 190.264C221.734 188.58 215.485 187.336 209.054 186.563C208.144 186.426 207.173 186.365 206.263 186.244V229.032C202.305 228.441 198.194 228.122 194.038 228.122C189.882 228.122 185.787 228.441 181.813 229.032V186.244C117.184 192.493 66.3264 247.173 66.3264 313.304C66.3264 379.435 120.035 437.239 187.213 440.879V427.289C127.452 423.709 79.856 373.899 79.856 313.304C79.856 259.398 117.639 214.077 168.026 202.185V232.233C145.077 239.65 126.284 256.486 116.395 278.206L128.484 284.258C131.153 278.342 134.535 272.806 138.631 267.877V358.852C130.956 349.418 125.556 338.103 123.357 325.62L110.161 328.411C117.32 368.211 152.236 398.637 194.038 398.637C199.104 398.637 204.185 398.182 209.054 397.272C215.622 396.104 221.932 394.147 227.847 391.614C258.076 378.419 279.281 348.311 279.281 313.319C279.281 287.504 267.647 264.297 249.431 248.689V213.637C284.407 233.203 308.205 270.531 308.205 313.319C308.205 364.495 274.321 407.935 227.832 422.435C221.78 424.316 215.47 425.681 209.039 426.53C206.309 426.925 203.639 427.183 200.849 427.304V440.894C203.639 440.697 206.309 440.5 209.039 440.181C215.47 439.408 221.719 438.164 227.832 436.48C281.859 421.586 321.72 371.972 321.72 313.319C321.72 254.666 281.859 205.189 227.832 190.294L227.847 190.264ZM220.036 202.155C222.705 202.807 225.299 203.52 227.832 204.294C230.501 205.143 233.095 206.053 235.628 207.085V239.012C233.095 237.587 230.486 236.282 227.832 235.114C225.299 234.007 222.69 233.036 220.036 232.187V202.14V202.155ZM265.751 313.289C265.751 340.606 250.341 364.404 227.847 376.553C221.992 379.677 215.683 382.013 209.054 383.439C204.17 384.486 199.165 385.062 194.038 385.062C178.567 385.062 164.188 380.057 152.418 371.669V255.014C157.226 251.571 162.429 248.705 168.026 246.49V303.976H181.813V242.653C185.787 242.001 189.882 241.606 194.038 241.606C198.194 241.606 202.289 242.001 206.263 242.653V352.543H220.051V246.49C222.72 247.597 225.314 248.765 227.847 250.13C230.577 251.632 233.186 253.255 235.643 255.014V304.309H249.431V267.831C259.638 280.253 265.751 296.058 265.751 313.289Z\" fill=\"#FFE200\"><\/path><path d=\"M54.2377 416.277C54.8899 418.75 55.8606 420.888 57.165 422.708C58.4694 424.468 60.153 425.894 62.231 426.864C63.9146 427.259 65.6134 427.774 67.2363 428.366C71.9232 430.247 76.2763 433.174 80.8873 437.072C79.3857 435.191 77.8992 433.371 76.337 431.612C73.7433 428.624 70.9373 425.696 68.2677 422.83C67.9492 422.511 67.6762 422.178 67.4184 421.859C65.9926 421.601 64.6882 421.085 63.3231 420.433C61.958 419.72 60.5929 418.871 59.1671 417.9C58.4543 417.385 59.1671 416.338 59.88 416.854C61.2451 417.764 62.5495 418.613 63.9146 419.265C64.5668 419.584 65.219 419.918 65.9319 420.115C65.3404 419.523 64.8854 418.886 64.3697 418.295C63.2017 416.732 62.1552 415.307 61.1844 413.805C60.6687 413.092 61.7001 412.379 62.231 413.092C63.2017 414.518 64.2483 416.019 65.4162 417.521C66.5841 419.023 67.8886 420.509 69.193 421.95C71.8625 424.817 74.532 427.668 77.2622 430.793C79.0216 432.81 80.7659 434.827 82.404 436.966C81.0996 433.72 80.1289 430.262 79.3402 426.622C78.6273 424.544 77.4594 422.329 76.0184 420.115C71.6653 413.229 67.0392 407.571 59.8345 403.794C55.7392 401.58 50.9918 400.154 45.3949 399.562C47.215 401.777 48.838 404.173 50.2789 406.782C51.9625 409.831 53.3428 413.092 54.2528 416.277H54.2377Z\" fill=\"#00844B\"><\/path><path d=\"M38.8879 243.517C38.7514 244.29 38.5694 245.018 38.175 245.792C38.7666 245.534 39.2823 245.473 39.798 245.473C39.4795 244.821 39.1458 244.169 38.8879 243.517Z\" fill=\"#00844B\"><\/path><path d=\"M36.6128 258.669C35.5055 259.579 34.6561 260.626 34.0039 261.794C33.291 262.962 32.836 264.266 32.5023 265.631C33.3517 269.332 33.8067 273.109 33.9281 276.886C34.4438 274.474 35.1567 272.199 35.9454 269.924C36.2639 269.074 37.5077 269.469 37.174 270.379C36.2639 272.851 35.4903 275.521 34.9595 278.114C36.3246 275.521 37.9475 273.367 39.5705 271.486C40.2833 270.713 41.0721 269.924 41.7849 269.211C43.7416 267.33 45.7589 265.829 47.761 264.463C46.1381 260.11 44.3786 255.879 42.5585 251.723C42.3006 252.117 42.0428 252.496 41.7849 252.83C40.4198 254.908 38.7969 256.864 36.5824 258.685L36.6128 258.669ZM40.9659 262.234C41.2844 262.097 41.5574 261.915 41.8153 261.779C42.331 261.324 42.7253 260.808 43.1804 260.217C43.4989 260.535 43.6354 261.187 43.6354 261.9C43.6354 264.115 42.9832 264.433 41.8153 264.949C41.3602 265.146 40.7687 265.404 40.1317 265.798C40.071 264.297 39.6766 262.674 40.981 262.219L40.9659 262.234Z\" fill=\"#00844B\"><\/path><path d=\"M45.9105 428.123C46.9571 429.033 47.9278 429.943 48.8986 430.914C50.203 432.142 51.5681 433.583 52.9938 435.267C56.4976 439.498 62.1551 444.307 68.9199 445.611C73.1517 446.385 77.7626 445.869 82.5708 443.017C82.4343 442.76 82.2523 442.502 82.1158 442.244C82.0551 442.244 81.9186 442.183 81.8579 442.183C78.612 440.682 75.6847 439.392 72.6966 439.316H72.4995C71.8472 439.316 71.1344 439.377 70.4822 439.514C69.1171 439.771 67.9492 439.969 66.9026 440.105C65.856 440.166 64.946 440.166 64.1724 440.045C63.8539 439.984 63.5202 439.908 63.6567 439.271C63.7932 438.679 64.1117 438.679 64.3696 438.755C65.0825 438.892 65.8712 438.892 66.8419 438.816C67.6913 438.755 68.662 438.619 69.7693 438.361C69.0564 438.103 68.3435 437.845 67.6306 437.451C66.0684 436.738 64.3847 435.828 62.5646 434.66C62.3068 434.463 62.0489 434.266 62.3675 433.75C62.7618 433.234 63.0197 433.431 63.2775 433.553C65.037 434.721 66.6599 435.631 68.2222 436.344C69.7238 437.056 71.2102 437.572 72.6511 438.027C75.897 438.088 78.9609 439.453 82.4039 441.015C82.5405 441.076 82.6618 441.152 82.7983 441.152L83.1168 440.757C77.3986 435.555 72.3174 431.778 66.7357 429.639C60.1075 426.97 52.9483 426.97 45.9257 428.138L45.9105 428.123Z\" fill=\"#00844B\"><\/path><path d=\"M48.0492 394.299C46.7448 392.995 45.2584 391.705 43.6202 390.462C42.1186 390.204 40.6929 390.067 39.1913 390.265C38.3419 390.401 38.1447 389.157 39.0548 389.036C39.9648 388.899 40.8142 388.839 41.5271 388.899C41.2086 388.642 40.8749 388.384 40.5564 388.187C39.7828 387.595 38.9941 387.019 38.2206 386.503C36.719 386.184 35.1718 385.593 33.4731 384.88C31.8501 384.167 30.0907 383.318 28.2099 382.286C27.3605 381.892 27.952 380.785 28.8014 381.179C30.6822 382.15 32.381 383.06 34.0039 383.712C34.459 383.97 34.9747 384.167 35.4297 384.304C35.0353 384.046 34.6561 383.712 34.3225 383.394C32.2445 381.771 30.2879 380.148 28.2706 378.388C27.5577 377.797 28.4071 376.826 29.0441 377.418C31.1221 379.177 33.0787 380.8 35.096 382.423C37.1133 384.046 39.1913 385.669 41.2693 387.17C43.9994 389.051 46.5324 391.068 48.9441 393.344C50.6277 394.967 52.0686 396.665 53.1759 398.288C52.9787 395.695 52.1293 393.086 50.5822 390.492C48.3071 386.594 44.9853 383.272 41.5423 380.345C36.8555 376.31 31.7288 373.519 26.1319 371.502C21.2479 369.743 16.0606 368.711 10.6609 368.059L10.7216 368.12C13.4517 370.137 16.0606 372.018 18.2599 374.687C22.158 379.374 26.2533 383.727 30.5457 387.686C34.7775 391.584 39.252 395.103 43.9994 398.212C47.0481 398.41 49.8542 398.865 52.4478 399.578C51.3406 397.757 49.8542 395.998 48.0189 394.314L48.0492 394.299Z\" fill=\"#00844B\"><\/path><path d=\"M38.5544 412.06C37.8415 412.257 37.5078 412.773 37.8415 413.425C38.2965 414.199 39.4037 414.593 40.1773 414.396C40.8902 414.259 41.2239 413.683 40.8902 413.031C40.4958 412.257 39.3886 411.863 38.5544 412.06Z\" fill=\"#00844B\"><\/path><path d=\"M68.6016 398.925C69.6481 397.423 67.7522 395.224 66.6449 396.71C66.1899 397.363 66.2506 398.394 66.8421 398.986C67.3578 399.501 68.1465 399.501 68.6016 398.925Z\" fill=\"#00844B\"><\/path><path d=\"M33.0333 357.305C34.2012 358.989 35.3084 360.809 36.2792 362.826C37.0527 364.389 37.7049 366.012 38.3571 367.771C39.5857 364.252 40.7688 361.856 39.0094 358.079C37.3257 354.378 34.9747 350.859 31.926 348.068C28.8015 345.277 25.0399 343.184 20.611 341.956C21.8395 344.231 22.9468 346.506 23.9327 348.918C25.1006 351.784 26.0107 354.712 26.86 357.897C27.5123 360.627 27.8308 363.691 28.0886 366.74C28.2858 368.165 28.4071 369.606 28.6043 371.032C31.471 372.2 34.2619 373.626 36.8555 375.324C36.992 373.959 37.1134 372.655 37.3712 371.426C37.5078 370.577 37.7656 370.198 37.5078 369.348C36.7949 367.21 36.0062 365.253 35.0961 363.372C34.186 361.492 33.1395 359.671 31.9716 358.033C31.4558 357.32 32.4266 356.608 33.0181 357.32L33.0333 357.305Z\" fill=\"#00844B\"><\/path><path d=\"M50.203 387.61C50.4002 384.288 50.1423 381.179 49.5508 378.054C48.7773 374.353 47.4728 370.713 45.7134 366.936C44.409 364.145 42.9225 361.415 41.4816 358.685C41.2844 361.415 41.0266 364.343 39.8587 367.391C39.343 368.756 38.8879 370.182 38.6301 371.684C38.3722 373.11 38.175 374.55 38.175 376.113C39.6008 377.083 41.0417 378.191 42.4068 379.359C43.2562 380.071 44.0298 380.784 44.8185 381.497C44.8792 379.874 44.682 378.373 44.3028 376.947C43.8478 375.188 43.1349 373.504 42.1641 371.805C41.7091 371.032 42.8164 370.379 43.2714 371.214C44.2421 372.973 45.0915 374.732 45.5465 376.613C46.0622 378.494 46.1987 380.451 46.0016 382.665C47.6245 384.288 49.0654 385.911 50.2334 387.61H50.203Z\" fill=\"#00844B\"><\/path><path d=\"M45.1219 362.826C45.7135 363.994 46.2899 365.162 46.8814 366.406C48.565 370.107 49.8694 373.626 50.6581 377.205C50.7947 375.249 50.916 373.231 51.0525 371.35C51.2497 367.847 51.371 364.464 51.4469 361.143C51.4469 360.233 52.7513 360.233 52.7513 361.143C52.6906 364.525 52.5541 367.968 52.2963 371.411C52.1598 374.536 51.9019 377.721 51.6441 380.845C51.3862 383.636 51.644 386.503 51.3862 389.294C52.2356 390.659 53.0091 392.16 53.5248 393.723C54.4956 392.752 55.2084 391.25 55.7393 389.233C56.3915 386.821 56.7859 383.773 56.9072 380.33C57.1651 373.049 56.5129 366.284 55.345 359.52C53.6613 354.454 52.2204 349.251 51.1132 343.912C49.9453 345.535 48.9745 347.492 48.0645 349.888C46.7601 353.331 45.7893 357.684 45.1371 362.826H45.1219Z\" fill=\"#00844B\"><\/path><path d=\"M15.4084 331.232C18.3965 334.159 21.3845 337.147 23.4018 341.439C23.4018 341.5 23.4625 341.5 23.4625 341.576C26.1927 342.547 28.6043 343.912 30.743 345.474C29.3779 342.744 27.7549 339.953 25.9955 337.223C23.781 333.704 21.4452 330.261 19.1094 326.878C19.1094 326.878 19.1094 326.818 19.0487 326.818C17.5471 326.302 16.0607 325.513 14.5591 324.603C12.9968 323.633 11.4345 322.389 9.87224 321.024C9.22003 320.432 10.0088 319.461 10.7216 320.114C12.2232 321.342 13.7097 322.525 15.2719 323.496C16.182 324.088 17.0921 324.603 18.0021 324.998C17.4864 324.224 16.9555 323.375 16.3792 322.586C15.4691 321.282 14.4984 319.992 13.3911 318.749C12.7996 318.096 13.7097 317.247 14.3619 317.899C15.4691 319.204 16.5005 320.508 17.4106 321.797C20.7323 326.348 24.0389 331.747 27.1027 336.555C29.3779 340.196 31.4558 343.836 33.1546 347.476C33.6703 347.931 34.1254 348.447 34.5804 348.978C35.3539 348.068 35.0961 346.05 33.9282 342.926C31.9109 337.405 28.7257 331.808 25.859 326.666C23.326 322.176 19.5492 317.763 15.0596 313.925C10.9036 310.346 6.15616 307.358 1.40868 305.34C1.27217 308.328 2.06089 311.316 3.42598 314.38C4.92758 317.763 7.06622 321.145 9.53855 324.725C11.2222 327.197 13.3153 329.214 15.3933 331.232H15.4084Z\" fill=\"#00844B\"><\/path><path d=\"M41.6183 345.671C40.4504 345.611 39.7375 346.066 39.4796 346.642C38.7061 348.144 40.1925 349.691 41.6941 349.691C42.5435 349.752 43.1199 349.236 43.3777 348.584C43.6356 348.068 43.6356 347.416 43.4384 346.9C43.2412 346.248 42.589 345.671 41.6183 345.671Z\" fill=\"#00844B\"><\/path><path d=\"M16.7128 355.287C16.4549 355.151 16.1213 355.151 15.8027 355.151C15.287 355.212 14.832 355.348 14.4376 355.667C14.0433 355.924 13.7248 356.319 13.5883 356.713C13.5276 356.971 13.5276 357.168 13.5276 357.426C13.5883 358.533 14.2405 359.504 15.1505 360.156C16.0606 360.808 17.1678 361.127 18.2751 361.066C18.6694 359.641 18.7301 358.336 18.4722 357.365C18.2144 356.258 17.5622 355.545 16.7128 355.287Z\" fill=\"#00844B\"><\/path><path d=\"M20.8687 300.077C23.9933 305.734 26.3898 311.453 28.2099 317.307C29.6357 322.115 30.7429 326.999 31.5923 331.944C31.653 329.472 31.9108 327.136 32.2445 324.861V324.542C31.5923 314.789 30.1059 306.599 27.497 300.228C25.4797 295.087 22.3552 290.157 17.6077 287.093C16.8341 292.356 16.637 297.559 17.3498 302.761C18.0021 307.645 19.3671 312.454 21.5058 317.262C23.0074 320.583 25.2067 322.919 26.9662 326.105C28.1947 328.319 29.3778 330.397 30.3485 332.278C29.575 327.333 28.4678 322.525 26.9662 317.717C25.146 311.923 22.8102 306.265 19.7463 300.744C19.2913 299.971 20.4592 299.318 20.8536 300.092L20.8687 300.077Z\" fill=\"#00844B\"><\/path><path d=\"M47.8521 313.288C47.8521 311.726 47.8521 310.164 47.9128 308.601C47.655 306.645 47.1393 304.825 46.487 303.202C45.4405 300.472 43.954 298.257 42.1946 296.437C41.2845 299.228 40.3138 301.958 39.3279 304.628C38.16 307.873 36.9921 311.134 35.9455 314.244C33.8069 321.069 32.7603 328.031 32.821 335.251C32.8816 338.376 34.7776 341.106 35.6118 344.033C36.0669 339.999 36.6584 335.964 37.2954 332.066C38.069 327.379 38.9791 322.829 40.0256 318.339C39.8284 317.232 39.7071 316.064 39.6313 314.896C39.6313 313.728 39.6919 312.484 39.8284 311.195C39.965 310.285 41.1935 310.422 41.1329 311.332C40.9357 312.56 40.875 313.743 40.9357 314.911C40.9357 315.503 40.9964 316.079 41.0722 316.671C41.3907 316.352 41.7244 315.897 41.9823 315.442C42.4373 314.669 42.8316 313.758 43.1502 312.651C43.2867 312.393 43.3473 312.06 43.9996 312.257C44.5911 312.454 44.5153 312.773 44.3939 313.03C44.0754 314.198 43.6204 315.245 43.0895 316.094C42.5738 316.944 41.9823 317.657 41.33 318.233C40.2835 322.844 39.3127 327.591 38.5392 332.278C37.7656 336.889 37.1741 341.576 36.7191 346.46C37.8263 346.263 37.8263 344.898 38.1448 343.988C39.1156 341.257 40.2835 338.33 41.4666 335.403C44.1361 328.699 46.9269 321.676 47.837 316.352V313.303L47.8521 313.288Z\" fill=\"#00844B\"><\/path><path d=\"M16.0607 283.696C18.1387 286.684 21.0054 287.731 23.4019 290.582C21.9761 286.426 20.4745 282.255 18.5937 278.297C16.2579 273.231 13.4519 268.483 9.81166 264.448C9.61448 264.191 9.35663 263.933 9.87233 263.538C10.3274 263.083 10.5245 263.341 10.7217 263.599C14.4985 267.755 17.35 272.578 19.7617 277.781C20.8082 279.995 21.7183 282.21 22.6283 284.546C21.2633 279.282 20.4139 274.338 19.9588 269.651C18.7303 266.466 16.9101 263.675 14.6198 261.127C12.4053 258.715 9.81166 256.576 6.94497 254.756C6.8843 259.64 7.46067 264.57 9.02294 269.575C10.4487 274.262 12.7239 278.934 16.0456 283.681L16.0607 283.696Z\" fill=\"#00844B\"><\/path><path d=\"M27.315 295.663C27.7093 292.933 27.9065 290.142 28.0279 287.336C28.1644 283.635 28.0279 279.798 27.77 275.96C27.5122 272.578 25.6314 268.619 23.9326 264.964C23.2804 263.735 22.704 262.431 22.1731 261.263C22.0366 260.944 21.9153 260.671 22.4917 260.414C23.068 260.156 23.2045 260.474 23.341 260.732C23.7961 261.9 24.4483 263.144 25.0247 264.433C25.6769 265.798 26.3291 267.163 26.9054 268.528C26.7689 267.36 26.6476 266.253 26.5111 265.085C26.0561 262.355 25.5404 259.564 24.9488 256.758C24.8881 256.44 24.7516 256.106 25.4038 255.985C26.0561 255.924 26.1167 256.182 26.1774 256.5C26.7689 259.367 27.3453 262.158 27.7397 264.888C28.0582 267.3 28.3312 269.635 28.5132 271.971C28.6497 273.336 28.9076 274.58 28.9683 275.869C29.2261 279.707 29.3626 283.605 29.2261 287.382C29.1654 291.083 28.7711 294.799 28.1189 298.378C28.3767 298.894 28.5739 299.485 28.7711 300.001C29.7418 299.349 30.1968 297.21 30.849 293.949C31.0462 293.039 31.2434 291.993 31.4406 290.885C33.3214 282.498 33.0029 273.261 31.0462 264.934C29.3626 257.653 26.2381 250.888 21.5513 245.822C20.6412 252.981 20.3227 260.459 21.0962 268.574C21.9456 277.735 24.1601 286.911 27.2695 295.618L27.315 295.663Z\" fill=\"#00844B\"><\/path><path d=\"M6.4443 297.999C7.03584 297.999 7.49087 297.802 7.87006 297.483C8.18859 297.165 8.4616 296.71 8.4616 296.179C8.4616 295.648 8.20375 295.208 7.87006 294.875C7.4757 294.556 6.96 294.359 6.36846 294.359C5.85276 294.359 5.3219 294.556 4.9427 294.875C4.62418 295.193 4.427 295.648 4.427 296.179C4.427 296.71 4.62418 297.15 5.01854 297.483C5.33706 297.802 5.86793 297.999 6.4443 297.999Z\" fill=\"#00844B\"><\/path><path d=\"M38.4329 247.02C37.0678 247.612 35.6421 248.78 35.1112 249.296C33.3518 251.116 32.0625 252.739 31.2131 254.24C29.7115 256.713 30.1666 257.425 30.9553 259.837C31.4103 258.866 31.7288 257.759 32.0625 256.713C32.9726 253.785 34.5955 252.481 37.1285 250.539C37.3864 250.342 37.6442 250.084 37.8414 249.948C38.5543 249.432 39.343 250.403 38.6149 250.918C38.3571 251.176 38.0992 251.374 37.9021 251.51C35.5662 253.33 34.004 254.498 33.2911 257.031C33.0332 257.88 32.7754 258.791 32.4417 259.503C32.1839 260.277 31.8502 260.929 31.471 261.46C31.6075 261.976 31.7895 262.567 31.926 263.144C32.1839 262.431 32.5175 261.779 32.8967 261.126C33.6096 259.822 34.5804 258.715 35.8241 257.683C38.3571 255.666 40.0559 253.254 41.6182 250.858C41.2996 249.629 41.1025 247.673 40.1166 246.884C39.798 246.565 39.1458 246.687 38.4329 247.02Z\" fill=\"#00844B\"><\/path><path d=\"M40.5717 272.32C38.0387 275.187 35.6877 278.752 33.8676 283.499C33.8676 283.499 33.8069 283.56 33.8069 283.636C33.6097 286.169 33.2912 288.777 32.6997 291.25C32.9575 291.053 33.2154 290.734 33.549 290.476C34.3984 289.505 35.3085 288.398 35.6877 287.609C37.1135 285.334 38.2965 283.711 39.6616 281.755C39.6616 281.694 39.7981 281.497 40.511 280.526C41.0267 279.813 42.0733 280.526 41.5576 281.3C41.4211 281.436 41.2391 281.755 40.7082 282.468C39.3431 284.424 38.1752 286.047 36.8101 288.322C36.3551 289.096 35.3843 290.34 34.4743 291.31C33.3064 292.539 32.457 292.539 32.1385 294.238C31.8199 295.739 31.5469 297.029 31.2891 298.136C34.2771 295.8 36.9466 293.328 39.2824 290.795C42.0733 287.746 44.2878 284.621 45.7135 281.633C47.0179 279.04 47.8522 276.294 48.1859 273.564C48.5044 271.092 48.383 268.62 47.7915 266.026C45.3192 267.709 42.8468 269.727 40.5717 272.336V272.32Z\" fill=\"#00844B\"><\/path><path d=\"M10.661 250.539C11.2526 250.858 11.9654 250.934 12.5418 250.736C13.194 250.479 13.649 250.024 13.9069 249.432C14.1647 248.841 14.1647 248.203 13.9069 247.475C13.649 246.823 13.194 246.308 12.6025 245.974C12.0109 245.716 11.2981 245.579 10.7217 245.837C10.0695 246.035 9.61445 246.49 9.3566 247.066C9.09875 247.657 9.09875 248.37 9.3566 249.023C9.55378 249.735 10.0695 250.251 10.661 250.524V250.539Z\" fill=\"#00844B\"><\/path><path d=\"M30.6974 245.914C31.4103 242.986 32.4569 240.195 33.7613 237.526C34.1556 236.677 35.3236 237.268 34.9292 238.042C33.6248 240.711 32.654 243.441 31.9412 246.232C31.4255 248.31 30.9704 250.464 30.7126 252.603C31.6226 251.298 32.7905 249.872 34.2315 248.371C36.1881 246.414 38.0689 245.246 37.6139 241.803C37.356 240.18 36.6431 237.647 34.8837 235.099C32.745 237.374 30.7884 240.362 29.8784 243.487C29.1655 246.081 28.9683 249.084 29.484 252.466C29.7418 250.252 30.1362 248.037 30.7126 245.898L30.6974 245.914Z\" fill=\"#00844B\"><\/path><path d=\"M83.6934 410.301C83.5569 409.906 83.7541 409.588 84.0877 409.451C82.2069 407.313 80.4475 405.159 78.688 402.884C78.5515 409.846 78.8852 416.474 79.856 422.587C80.766 428.183 82.2676 433.704 84.6034 438.846C85.7714 437.284 86.0292 436.571 86.8786 434.812C87.1971 432.339 87.3336 429.67 87.1364 426.879C86.8786 421.419 85.7107 415.625 83.6934 410.301Z\" fill=\"#00844B\"><\/path><path d=\"M85.2404 410.756C87.0605 415.958 88.1677 421.555 88.4256 426.879C88.4863 428.639 88.4863 430.322 88.4256 432.021C89.1992 430.792 89.4722 429.685 89.6542 428.184C90.1092 425.393 90.1699 421.419 89.9727 416.611C89.9727 416.353 90.0334 416.156 90.1699 416.095C88.4863 414.335 86.8482 412.576 85.2252 410.756H85.2404Z\" fill=\"#00844B\"><\/path><path d=\"M91.0344 427.926C91.9445 426.242 92.718 424.483 93.3702 422.526C93.6281 421.677 93.8253 420.767 94.0831 419.796C93.1124 418.946 92.2023 418.036 91.2923 417.202C91.4895 421.555 91.3529 425.196 91.0344 427.926Z\" fill=\"#00844B\"><\/path><path d=\"M373.244 318.157C368.299 321.342 364.204 326.742 361.474 332.005C361.277 332.4 361.155 332.46 361.155 332.855C361.216 334.675 361.095 336.495 360.761 338.315C362.778 336.176 364.856 334.083 366.934 332.005C367.071 330.959 367.192 329.988 367.45 329.017C367.708 327.971 368.042 326.879 368.497 325.832C368.815 324.861 369.998 325.377 369.665 326.226C369.27 327.334 368.952 328.304 368.694 329.351C368.633 329.745 368.497 330.2 368.436 330.58C371.303 327.849 374.291 325.18 377.279 322.51C377.992 321.919 378.78 322.905 378.128 323.481C375.064 326.151 372.076 328.82 369.149 331.611C369.467 331.611 369.801 331.611 370.12 331.672C370.893 331.672 371.743 331.732 372.531 331.808C373.441 331.869 373.305 333.173 372.395 333.037C371.682 332.976 370.893 332.9 370.059 332.9H367.844C365.236 335.433 362.703 338.042 360.23 340.833C359.457 343.7 358.152 346.551 356.453 349.221C356.969 348.902 357.5 348.629 358.016 348.311C359.244 346.49 360.609 344.61 362.445 343.245C366.934 339.862 370.514 337.132 373.623 333.886C376.809 330.701 379.539 327.061 382.269 321.919C383.695 319.249 384.408 315.67 385.97 313.395C380.964 314.502 377.188 315.609 373.229 318.142L373.244 318.157Z\" fill=\"#00844B\"><\/path><path d=\"M374.473 292.736C369.589 296.71 365.312 300.806 362.187 305.098C358.805 309.785 356.787 314.79 356.984 320.114C358.607 322.647 359.775 325.256 360.428 327.986C360.488 325.969 360.488 324.012 360.625 322.268C360.822 319.674 361.14 317.323 361.671 315.306C362.323 313.228 363.097 311.605 364.007 310.3C364.917 308.996 366.024 308.025 367.132 307.252C367.905 306.736 368.633 307.767 367.905 308.298C366.798 309.011 365.888 309.921 365.038 311.089C364.189 312.257 363.476 313.759 362.9 315.64C362.763 316.095 362.703 316.55 362.581 317.065C363.097 316.474 363.628 315.958 364.144 315.503C365.251 314.532 366.358 313.683 367.587 312.909C368.3 312.454 369.012 313.501 368.239 314.017C367.132 314.729 366.024 315.518 364.993 316.428C364.022 317.399 363.036 318.385 362.202 319.477C362.066 320.387 362.005 321.358 361.944 322.404C361.808 324.422 361.747 326.56 361.747 328.911C364.417 324.361 367.268 321.115 370.332 318.703C371.181 316.747 371.955 314.866 372.41 313.046C372.804 311.226 373.062 309.148 372.668 307.328C371.955 303.354 373.062 298.879 374.033 294.784C374.23 294.071 374.351 293.419 374.488 292.767L374.473 292.736Z\" fill=\"#00844B\"><\/path><path d=\"M353.663 352.815C349.173 356.592 346.246 361.794 344.501 367.316C344.441 367.316 344.441 367.376 344.441 367.376C344.896 375.567 342.621 383.439 340.148 390.856C342.363 387.155 344.501 383.06 346.519 378.828L346.913 378.054H346.852C346.989 377.084 347.049 376.173 347.049 375.263C346.989 374.353 346.852 373.443 346.731 372.594C346.534 371.744 347.778 371.487 347.96 372.336C348.142 373.185 348.217 374.095 348.278 375.006C350.159 370.713 351.979 366.36 353.617 362.189C353.936 361.339 355.119 361.794 354.785 362.644C353.162 366.876 351.342 371.229 349.446 375.521C349.643 375.385 349.765 375.203 349.962 375.066C351.008 374.293 352.04 373.565 353.086 372.928C353.86 372.533 354.391 373.64 353.738 374.035C352.692 374.626 351.721 375.339 350.75 376.052C349.446 377.099 348.339 377.933 347.687 379.374C346.382 382.165 345.017 384.834 343.591 387.367C346.124 384.698 349.052 382.225 352.176 380.087C354.391 378.661 356.666 377.357 359.002 376.249C360.17 372.928 359.396 370.395 358.744 368.256C358.425 367.209 358.152 366.299 358.031 365.329C357.379 359.413 362.126 351.875 365.251 346.93C361.095 348.098 356.924 350.115 353.678 352.846L353.663 352.815Z\" fill=\"#00844B\"><\/path><path d=\"M371.803 262.568C372.319 262.704 372.911 262.507 373.366 262.173C373.957 261.718 374.336 261.127 374.534 260.353C374.731 259.58 374.67 258.851 374.397 258.336C374.139 257.82 373.745 257.426 373.168 257.289C372.653 257.153 372.061 257.289 371.546 257.684C371.03 258.078 370.635 258.654 370.438 259.443C370.241 260.156 370.302 260.945 370.575 261.521C370.833 262.037 371.288 262.431 371.803 262.568Z\" fill=\"#00844B\"><\/path><path d=\"M345.214 272.578C346.64 272.776 348.005 273.488 349.446 274.793C349.507 273.17 349.765 271.471 350.159 269.848C350.296 269.135 350.478 268.483 350.751 267.77C350.356 266.405 349.901 265.101 349.446 263.872C348.93 262.568 348.4 261.4 347.763 260.368C347.247 259.595 348.354 258.943 348.809 259.716C349.522 260.823 350.114 262.052 350.629 263.356C350.948 264.13 351.221 264.979 351.479 265.829C352.252 263.948 353.238 262.189 354.345 260.49C353.83 257.502 352.525 255.682 350.826 254.514C349.264 253.406 347.308 252.951 345.366 252.83C343.091 256.986 342.12 259.458 342.181 261.991C342.242 264.661 343.349 267.452 345.245 272.457V272.594L345.214 272.578Z\" fill=\"#00844B\"><\/path><path d=\"M354.315 288.838C355.089 290.067 355.938 291.311 356.909 292.479C357.045 292.084 357.167 291.705 357.303 291.371C355.999 285.911 355.741 281.224 356.393 275.764C356.651 273.807 357.045 271.79 357.5 269.788C357.106 268.878 356.727 267.968 356.393 267.058C356.135 266.087 355.938 265.04 355.877 263.933C355.817 263.023 357.106 263.023 357.182 263.933C357.182 264.843 357.379 265.814 357.637 266.663C357.773 267.058 357.895 267.513 358.092 267.892C358.805 265.359 359.775 262.826 360.958 260.278C361.353 259.504 362.521 260.02 362.126 260.869C361.019 263.144 360.17 265.419 359.457 267.755C359.518 267.619 359.654 267.497 359.775 267.361C360.367 266.769 360.943 266.193 361.338 265.541C361.853 264.767 362.9 265.48 362.445 266.254C361.929 266.967 361.338 267.619 360.685 268.271C360.094 268.863 359.457 269.378 358.805 269.894C358.289 271.911 357.895 273.929 357.697 275.946C357.561 277.053 357.44 278.16 357.379 279.268C357.697 278.949 358.092 278.555 358.425 278.221C359.017 277.508 359.593 276.856 359.851 276.401C360.306 275.551 361.413 276.143 361.019 276.992C360.625 277.584 360.048 278.297 359.336 279.07C358.623 279.844 357.834 280.693 357.379 281.482C357.379 284.076 357.697 286.685 358.152 289.278C360.23 284.849 362.703 281.088 365.494 277.902C366.146 275.627 366.464 273.413 366.404 271.198C366.343 268.923 365.949 266.648 365.236 264.434C364.462 262.022 364.265 259.489 364.523 256.956C364.659 255.136 365.039 253.179 365.494 251.298C364.189 252.208 362.9 253.118 361.717 254.165C356.833 258.26 352.874 263.857 351.372 270.167C349.871 276.143 350.599 282.65 354.3 288.823L354.315 288.838Z\" fill=\"#00844B\"><\/path><path d=\"M355.422 300.274C355.422 299.759 355.483 299.228 355.483 298.712C353.602 296.498 351.782 294.222 350.022 291.947H348.066C347.414 291.947 346.761 291.887 346.049 291.75C345.139 291.614 345.336 290.385 346.185 290.521C346.837 290.582 347.489 290.658 348.142 290.658C348.46 290.719 348.733 290.719 349.052 290.719C348.4 289.869 347.823 289.035 347.232 288.246C346.185 286.821 345.154 285.455 344.183 284.015C342.56 283.878 340.998 283.559 339.572 282.847C338.723 282.452 339.314 281.284 340.088 281.679C341.058 282.134 342.105 282.452 343.212 282.649C341.908 280.89 340.679 279.07 339.511 277.31C338.996 276.537 340.027 275.809 340.558 276.598C341.726 278.281 342.894 279.98 344.077 281.664C344.016 281.072 343.88 280.435 343.819 279.843C343.622 278.615 343.364 277.432 343.106 276.203C342.909 275.293 344.153 275.035 344.335 275.885C344.592 277.113 344.85 278.418 345.047 279.661C345.305 281.027 345.503 282.452 345.639 283.893C346.488 285.061 347.398 286.305 348.233 287.473C348.748 288.125 349.203 288.838 349.734 289.49C349.734 289.232 349.795 288.974 349.795 288.777C349.856 287.928 349.856 287.094 349.856 286.305C349.856 285.395 351.16 285.395 351.16 286.305C351.16 287.154 351.16 287.988 351.099 288.838C351.039 289.551 350.963 290.203 350.842 290.916C352.464 292.994 354.087 295.011 355.786 297.028C355.983 295.982 356.181 294.95 356.499 293.904H356.438C355.271 292.478 354.163 290.977 353.314 289.475C350.781 285.243 349.537 280.89 349.416 276.598C346.291 272.957 343.364 273.534 339.602 274.262C338.889 274.398 338.177 274.52 337.388 274.656C338.237 281.482 339.86 286.623 342.727 290.658C345.518 294.693 349.613 297.681 355.468 300.274H355.422Z\" fill=\"#00844B\"><\/path><path d=\"M356.651 300.73C356.514 303.854 356.909 306.979 357.879 309.83C358.592 308.329 359.442 306.842 360.473 305.34L360.412 305.28C360.155 303.778 359.957 302.61 360.352 301.124C361.52 296.437 363.218 292.145 365.296 287.989C366.267 286.169 367.253 284.288 368.345 282.528C368.482 281.679 368.603 281.027 368.664 280.39C368.8 279.737 368.8 279.161 368.861 278.372C368.861 277.462 370.089 277.523 370.089 278.433C370.089 278.827 370.089 279.282 370.029 279.662C370.742 278.494 371.53 277.326 372.243 276.219C372.44 275.961 372.562 275.703 373.093 276.021C373.684 276.34 373.487 276.613 373.29 276.931C370.878 280.632 368.482 284.606 366.464 288.565C366.146 289.157 365.873 289.733 365.615 290.325L365.676 290.264C366.388 289.748 367.177 289.217 367.951 288.838C368.724 288.444 369.316 289.551 368.542 290.006C367.769 290.324 367.117 290.78 366.404 291.31C365.751 291.826 365.099 292.418 364.447 293.07C364.386 293.07 364.386 293.131 364.386 293.131C363.218 295.8 362.308 298.53 361.595 301.458C361.338 302.307 361.338 303.081 361.459 303.93C363.082 301.791 364.963 299.698 367.056 297.62C367.056 297.62 367.117 297.559 367.117 297.484C369.194 294.359 370.893 291.113 372.183 287.792C373.608 284.409 374.594 281.027 375.246 277.584C375.701 275.051 376.02 272.442 376.672 269.848C373.35 272.063 370.302 274.535 367.511 277.584C364.128 281.224 361.262 285.577 359.184 290.127C357.682 293.373 356.772 297.089 356.651 300.73Z\" fill=\"#00844B\"><\/path><path d=\"M385.333 299.167C385.591 298.576 386.243 297.15 385.136 297.089C384.62 297.089 383.907 297.347 383.058 297.802C381.753 298.652 381.374 299.759 380.843 301.124C380.843 301.185 380.782 301.26 380.782 301.321C381.95 301.321 382.86 301.124 383.573 300.805C384.347 300.487 384.938 299.895 385.333 299.183V299.167Z\" fill=\"#00844B\"><\/path><path d=\"M354.573 318.946C352.616 316.474 350.872 314.138 349.31 311.863C348.081 310.043 347.035 308.344 346.124 306.721C344.562 310.953 343.455 315.503 343 320.054C342.484 324.862 342.606 329.746 343.455 334.493C344.107 337.739 345.275 340.803 347.095 343.654C348.597 345.99 350.538 348.205 352.95 350.161C352.556 344.898 351.721 339.696 350.538 334.554C349.568 333.962 348.718 333.325 347.808 332.537C346.898 331.687 345.988 330.716 345.139 329.609C344.547 328.896 345.594 328.108 346.109 328.836C346.959 329.882 347.793 330.792 348.703 331.566C349.158 332.021 349.613 332.339 350.068 332.734C349.158 329.23 348.111 325.848 346.944 322.389C346.686 321.54 347.854 321.161 348.172 321.995C349.279 325.241 350.311 328.563 351.16 331.884C351.418 330.777 351.615 329.609 351.676 328.502C351.676 327.592 352.98 327.653 352.904 328.563C352.844 330.443 352.389 332.339 351.676 334.16C352.904 339.423 353.754 344.822 354.148 350.283C361.171 340.727 362.081 328.502 354.543 318.946H354.573Z\" fill=\"#00844B\"><\/path><path d=\"M337.6 398.591C341.18 397.029 344.562 395.406 347.869 393.192C348.066 392.282 348.324 391.372 348.718 390.522C349.112 389.612 349.628 388.702 350.22 387.853C350.417 387.595 350.614 387.337 351.13 387.716C351.645 388.035 351.448 388.308 351.266 388.565C350.675 389.339 350.22 390.188 349.901 391.038C349.704 391.356 349.583 391.69 349.507 392.084C353.739 389.021 357.576 385.577 361.277 381.937C361.929 381.346 362.839 382.195 362.187 382.847C358.349 386.624 354.512 390.006 350.675 392.797C347.156 395.33 343.394 397.605 339.299 399.304C339.102 399.82 338.844 400.275 338.647 400.806C342.878 400.548 347.095 399.183 351.266 396.65C355.877 393.92 360.427 389.824 364.856 384.425C367.905 380.784 371.166 377.341 374.351 373.898C366.874 373.838 359.138 376.947 352.889 381.118C346.003 385.805 340.27 392.115 337.615 398.606L337.6 398.591Z\" fill=\"#00844B\"><\/path><path d=\"M372.91 359.58C371.743 359.383 370.377 360.035 370.044 361.203C369.649 362.31 370.438 363.281 371.545 363.478C372.653 363.675 374.018 363.023 374.412 361.855C374.731 360.748 374.018 359.838 372.91 359.58Z\" fill=\"#00844B\"><\/path><path d=\"M344.365 348.144C343.713 347.37 342.681 347.37 341.953 348.144C341.635 348.538 341.438 349.054 341.438 349.706C341.438 350.297 341.635 350.874 342.029 351.268C342.681 352.042 343.652 352.315 344.365 351.405C344.684 351.01 344.881 350.434 344.881 349.782C344.881 349.13 344.684 348.553 344.365 348.159V348.144Z\" fill=\"#00844B\"><\/path><path d=\"M333.444 399.304C332.595 397.621 332.019 395.406 331.624 392.797C331.169 389.551 331.033 385.714 331.306 381.543C331.503 378.221 331.897 374.914 332.474 371.471C333.065 368.028 333.899 364.509 335.082 361.006C335.34 360.096 336.584 360.49 336.25 361.4C335.143 364.843 334.294 368.286 333.717 371.669C333.126 375.051 332.807 378.373 332.61 381.619V381.679C332.807 381.361 332.929 381.027 333.126 380.769C333.839 379.662 334.552 378.555 335.401 377.523C335.993 376.871 336.963 377.66 336.372 378.373C335.598 379.343 334.87 380.329 334.233 381.437C333.581 382.483 333.004 383.575 332.474 384.758C332.413 387.686 332.534 390.355 332.868 392.691C333.187 395.027 333.839 397.636 335.143 399.714C336.705 399.001 337.873 393.54 338.586 391.523C342.029 381.315 345.214 370.258 341.574 358.822C340.861 356.486 339.815 354.211 338.526 351.996C337.813 350.692 336.963 349.402 335.993 348.159C333.581 357.972 330.198 367.406 325.921 376.386L325.663 376.841C325.603 382.635 326.058 388.277 327.483 392.312C328.651 395.755 330.547 398.227 333.46 399.334L333.444 399.304Z\" fill=\"#00844B\"><\/path><path d=\"M307.765 434.296C311.011 430.398 314.333 428.441 315.501 423.239C315.819 421.677 315.956 420.19 315.895 418.628C315.834 417.657 317.063 417.521 317.124 418.491C317.26 420.175 317.124 421.874 316.729 423.497C316.593 424.149 316.411 424.801 316.214 425.378C317.518 424.012 318.747 422.647 319.915 421.222C321.932 418.749 323.752 416.156 325.254 413.092C325.709 412.318 326.816 412.895 326.421 413.683C324.799 416.808 322.978 419.477 320.961 422.01C320.188 422.92 319.459 423.83 318.625 424.68C319.596 424.164 320.506 423.633 321.416 423.254C322.19 422.86 322.781 423.967 321.932 424.361C320.764 424.953 319.52 425.59 318.352 426.318C314.454 428.654 311.648 431.657 308.736 435.161C307.234 436.981 305.809 438.862 304.504 440.879C309.707 438.998 314.318 436.389 318.413 432.749C322.842 428.851 326.664 423.709 329.925 417.081C331.745 413.243 333.429 409.467 335.128 405.629C335.901 403.748 336.751 401.852 337.6 399.972C320.43 407.449 309.191 419.993 304.899 438.073C305.809 436.768 306.719 435.54 307.765 434.296Z\" fill=\"#00844B\"><\/path><path d=\"M315.562 404.188C316.077 404.188 316.532 404.052 316.866 403.733C317.185 403.415 317.458 402.884 317.579 402.11C317.579 401.853 317.579 401.519 317.518 401.261C317.458 400.806 317.26 400.412 317.063 400.154C316.805 399.896 316.548 399.699 316.214 399.699H315.956C315.501 399.759 315.107 400.017 314.788 400.412C314.47 400.806 314.272 401.382 314.197 402.035C314.197 402.626 314.333 403.202 314.652 403.658C314.849 403.976 315.167 404.173 315.562 404.173V404.188Z\" fill=\"#00844B\"><\/path><path d=\"M347.429 415.504C346.322 414.73 344.638 414.851 343.531 415.64C342.302 416.55 342.424 417.976 343.986 418.507C344.699 418.765 345.548 418.704 346.322 418.507C347.687 418.112 348.794 416.626 347.429 415.519V415.504Z\" fill=\"#00844B\"><\/path><path d=\"M315.88 436.374C312.24 438.968 308.205 440.985 303.852 442.486C302.805 443.397 301.971 444.564 301.319 445.808C300.864 446.718 300.409 447.689 300.015 448.857C303.261 448.72 306.779 447.75 310.617 446.187C313.347 444.109 315.956 441.758 318.231 439.165C318.883 438.452 319.793 439.301 319.202 440.014C317.837 441.576 316.335 443.002 314.773 444.443C317.897 442.941 321.204 441.197 324.783 439.241C325.557 438.786 326.209 439.893 325.375 440.348C321.143 442.684 317.245 444.701 313.605 446.324C315.031 446.46 316.472 446.718 317.958 447.37C318.474 447.568 318.474 447.886 318.155 448.341C319.52 447.75 320.825 447.113 322.053 446.324C328.621 442.486 334.278 436.768 338.829 431.308C331.548 430.14 321.856 432.081 315.88 436.374Z\" fill=\"#00844B\"><\/path><path d=\"M311.785 447.492H310.875C307.098 448.993 303.655 449.903 300.409 450.161C306.582 451.663 312.376 450.813 317.639 448.599C317.579 448.538 317.503 448.538 317.442 448.462C315.622 447.689 313.665 447.613 311.785 447.492Z\" fill=\"#00844B\"><\/path><path d=\"M303.079 440.348C303.473 438.468 303.928 436.648 304.444 434.888C302.942 432.931 301.85 429.291 301.198 426.895C300.94 425.787 299.12 424.559 298.073 424.028C297.3 423.634 297.815 422.526 298.665 422.921C299.636 423.376 300.546 424.028 301.334 424.877C301.592 423.77 301.926 422.663 302.305 421.632C302.821 420.13 303.473 418.704 304.383 417.476C304.975 416.763 306.006 417.536 305.43 418.249C304.58 419.356 304.004 420.661 303.473 422.026C303.018 423.391 302.624 424.817 302.366 426.182C302.821 428.715 303.731 431.126 304.975 433.144C305.945 430.216 307.053 427.426 308.418 424.756C309.009 420.069 308.933 415.974 308.281 412.394C307.963 410.256 307.371 408.238 306.597 406.479C303.215 410.574 299.575 414.472 295.737 418.188C295.995 426.576 298.665 431.642 301.395 437.042C301.987 438.088 302.502 439.181 303.079 440.364V440.348Z\" fill=\"#00844B\"><\/path><path d=\"M200.151 30.8812C198.012 31.852 198.467 34.1271 200.287 35.3102C202.426 36.6753 203.73 41.3621 204.519 46.1703C205.293 50.9177 205.566 55.8624 205.687 58.001C205.945 62.0356 206.005 66.1916 205.823 69.9077C205.687 73.1535 205.368 76.0809 204.853 78.3561C204.595 79.2661 204.337 80.1155 204.003 80.8284C203.29 82.6485 202.835 83.9529 204.853 85.9702C204.989 86.1067 205.171 86.2281 205.308 86.3646C205.763 86.6831 206.218 86.8803 206.733 86.8803C207.188 86.8803 207.704 86.6224 208.235 86.1067C208.432 85.9702 208.554 85.7882 208.69 85.591C209.6 84.4231 210.313 82.4665 210.768 79.8728C211.223 77.2033 211.481 73.8209 211.42 69.8015C211.42 64.3411 211.162 57.8949 210.192 51.661C209.221 45.427 207.659 39.3751 204.989 34.749C204.398 33.7024 203.685 32.4738 202.851 31.6245C202.077 30.9116 201.167 30.5172 200.181 30.9116L200.151 30.8812Z\" fill=\"#FFE200\"><\/path><path d=\"M219.975 113.135C219.125 113.59 217.245 115.092 217.108 115.547C217.108 115.092 215.606 113.408 214.772 112.68C207.81 112.089 200.924 111.831 194.023 111.831C187.122 111.831 180.175 112.089 173.349 112.68C172.5 113.333 170.938 115.092 170.938 115.547C170.801 115.031 168.92 113.59 168.01 113.135C153.51 114.637 139.268 117.428 125.48 121.463C124.707 121.66 123.857 122.828 123.918 123.419C123.918 124.071 125.419 123.419 126.512 123.161C127.937 122.843 127.422 124.132 128.134 124.329C128.59 124.39 129.181 124.329 130.546 123.935C130.607 124.39 129.636 124.648 128.863 125.497C127.952 126.544 127.558 127.772 129.575 127.636C131.138 127.575 131.714 127.12 132.306 127.378C133.352 127.772 132.503 128.349 134.323 127.894C154.026 123.283 174.047 120.932 194.008 120.932C217.214 120.932 240.497 124.117 263.187 130.366C261.367 127.636 265.144 127.241 267.086 127.954C268.056 128.349 272.88 130.821 276.323 130.366C279.766 129.911 278.598 128.485 276.717 127.317C274.381 125.891 271.378 125.436 270.665 125.497C268.906 125.634 261.504 123.677 261.822 122.448C265.205 123.358 268.784 124.466 272.227 124.587C255.513 118.793 237.888 115.031 219.944 113.135H219.975Z\" fill=\"#FFE200\"><\/path><path d=\"M176.671 69.7708C176.61 73.8054 176.868 77.1877 177.323 79.8421C177.839 82.4358 178.491 84.3924 179.401 85.5603C179.538 85.7575 179.72 85.9547 179.856 86.076C180.372 86.5917 180.903 86.8496 181.358 86.8496C181.874 86.8496 182.329 86.6524 182.784 86.3339C182.92 86.1973 183.102 86.076 183.239 85.9395C185.256 83.9222 184.801 82.6178 184.088 80.7977C183.77 80.0848 183.497 79.2354 183.239 78.3253C182.723 76.0502 182.389 73.1228 182.268 69.8769C182.071 66.176 182.131 62.0049 182.405 57.9703C182.541 55.8317 182.799 50.887 183.572 46.1395C184.225 42.3021 185.135 38.6012 186.56 36.5232C187.668 34.9609 190.079 30.2135 185.65 31.5786C185.332 32.0336 184.998 32.5493 184.74 33.1408C183.83 35.2795 183.178 38.3433 182.662 41.0735C182.207 43.2122 181.813 45.1688 181.358 46.276C179.341 50.8263 178.173 54.0722 177.46 57.5304C176.808 60.9128 176.686 64.5531 176.686 69.7556L176.671 69.7708Z\" fill=\"#FFE200\"><\/path><path d=\"M193.128 76.005C190.656 75.5499 188.836 73.4113 188.836 70.8631C188.836 68.0723 191.05 65.7213 193.78 65.6C190.914 65.4634 188.638 63.0669 188.638 60.2003C188.638 57.3336 190.853 54.9978 193.644 54.8006C191.05 54.5427 188.957 52.3889 188.957 49.7346C188.957 47.2622 190.777 45.1843 193.189 44.7292C191.232 44.4107 189.67 42.9091 189.215 41.0283C186.485 42.1356 185.059 44.9264 184.604 47.6566C184.012 51.8884 183.754 56.105 183.633 58.0616C183.436 62.0962 183.375 66.1915 183.497 69.8317C183.633 73.0169 183.952 75.8836 184.467 78.0223C184.664 78.9323 184.983 79.6452 185.241 80.3581C185.954 82.3147 186.545 83.7405 185.104 85.6971C185.817 85.4393 186.606 85.2421 187.379 85.1814C187.698 83.5585 188.487 82.2541 189.518 81.344C189.457 81.0861 189.457 80.8283 189.457 80.5704C189.457 78.356 191.02 76.4752 193.098 76.0201L193.128 76.005Z\" fill=\"#FFE200\"><\/path><path d=\"M203.594 78.0224C204.11 75.8838 204.443 73.0171 204.565 69.8319C204.701 66.1917 204.625 62.0964 204.428 58.0618C204.292 55.9231 203.973 50.9785 203.199 46.3523C203.063 45.3816 202.881 44.3957 202.684 43.4856C202.229 41.2105 200.803 40.0426 198.907 38.7988C199.423 41.529 197.678 44.1985 194.872 44.7142C197.284 45.1693 199.104 47.2472 199.104 49.7196C199.104 52.3891 197.026 54.5277 194.417 54.7856C197.208 54.9827 199.423 57.3186 199.423 60.1853C199.423 63.0519 197.148 65.4484 194.281 65.5849C197.011 65.7215 199.226 68.0573 199.226 70.8481C199.226 73.3811 197.405 75.5349 194.933 75.99C197.011 76.445 198.573 78.3258 198.573 80.5403C198.573 80.7981 198.573 81.056 198.513 81.3138C199.559 82.2239 200.333 83.5283 200.651 85.1512C201.501 85.2119 202.274 85.4091 202.987 85.7428C201.486 83.7862 202.016 82.2997 202.79 80.3431C203.048 79.6302 203.382 78.9173 203.564 78.0073L203.594 78.0224Z\" fill=\"#FFE200\"><\/path><path d=\"M95.3876 112.423C95.1298 112.741 94.5382 112.68 94.3411 112.286C93.2945 110.527 92.0659 109.419 90.7008 108.843C89.3357 108.267 87.91 108.191 86.469 108.585C85.0433 108.904 83.6782 109.692 82.5709 110.8C81.0693 112.165 79.9773 114.121 79.7043 116.26C79.6436 116.851 79.5677 117.428 79.5677 118.141C79.5677 119.187 79.7043 120.279 80.0835 121.189C80.4778 121.963 81.0542 122.555 81.9642 122.691C82.1007 122.691 82.2828 122.752 82.4193 122.752C83.0108 122.752 83.5265 122.555 83.9815 122.236C84.3759 121.978 84.6337 121.644 84.8309 121.265C85.0281 120.871 85.1495 120.416 85.1495 119.961C85.1495 119.445 85.0129 118.914 84.6944 118.459C84.5579 118.323 84.5579 117.944 84.6338 117.807C85.4073 116.123 86.4539 115.138 87.6825 114.758C88.7897 114.364 90.0941 114.44 91.3227 114.956C92.2934 115.274 93.2793 115.926 94.1135 116.639C95.5393 117.807 96.328 119.824 98.2088 118.065C98.8004 117.549 99.2554 116.897 99.5132 116.184C99.9076 115.335 101.076 115.79 100.681 116.639C100.363 117.549 99.7711 118.323 99.1189 118.975C96.5859 120.992 98.6032 120.992 98.6032 124.238C98.6032 124.633 98.6638 124.951 98.8004 125.285C99.5739 127.302 102.896 128.015 104.776 127.241C132.473 116.123 163.233 110.527 193.993 110.527C224.753 110.527 255.437 116.123 283.133 127.241C284.953 128.015 288.336 127.302 289.109 125.285C291.445 120.477 281.176 121.129 277.733 118.778C276.11 118.004 274.548 116.76 273.304 114.88C273.107 114.561 273.244 114.03 273.623 113.97C275.125 113.515 275.959 112.468 276.353 111.376C276.55 110.663 276.611 109.95 276.55 109.237C276.414 108.524 276.156 107.872 275.701 107.281C275.049 106.31 273.881 105.658 272.379 105.658C271.469 105.658 270.696 105.916 270.043 106.31C269.452 106.704 268.997 107.22 268.618 107.872C268.299 108.524 268.102 109.237 268.102 109.95C268.102 110.724 268.36 111.512 268.815 112.225C269.012 112.544 268.815 113.075 268.42 113.135C263.536 114.637 259.441 114.819 255.877 113.727C252.297 112.68 249.249 110.284 246.382 106.446C246.063 105.991 246.64 105.279 247.231 105.536C250.28 107.099 252.889 106.507 254.572 105.081C255.482 104.308 256.135 103.322 256.529 102.215C256.984 101.107 257.121 99.9395 256.923 98.893C256.666 96.9363 255.3 95.192 252.692 94.6005C252.434 94.5398 252.176 94.2061 252.176 93.9483C252.373 91.7338 251.584 90.1109 250.356 89.0036C249.643 88.4121 248.854 88.0329 248.02 87.8357C247.11 87.6385 246.2 87.6385 245.35 87.8357C243.727 88.2908 242.287 89.398 241.513 91.476C241.452 91.7338 241.058 91.931 240.8 91.8703C238.131 91.2181 236.189 92.1888 235.082 93.7511C234.43 94.7218 234.035 95.9656 233.975 97.1942C233.914 98.4228 234.111 99.6665 234.688 100.774C235.658 102.791 237.812 104.277 241.255 104.02C241.847 103.959 242.165 104.869 241.65 105.188C238.07 107.523 233.656 108.691 229.288 108.115C225.511 107.599 221.81 105.703 218.883 102.063C218.564 101.669 218.822 101.016 219.338 101.016C221.219 100.88 222.387 99.7879 222.917 98.4834C223.115 97.8919 223.175 97.2548 223.175 96.6026C223.175 95.9504 222.978 95.3741 222.72 94.7825C222.129 93.4781 220.9 92.5074 219.019 92.5074C217.457 92.5074 216.289 93.2202 215.637 94.191C215.182 94.7825 214.924 95.4196 214.863 96.1476C214.727 96.8605 214.803 97.5734 215 98.2256C215.394 99.3935 216.304 100.44 217.791 100.819C218.306 101.016 218.382 101.729 217.927 101.987C213.377 104.717 209.145 106.082 205.247 105.627C201.349 105.233 197.769 102.958 194.584 98.3469C194.19 97.8312 194.979 97.0425 195.494 97.4369C196.268 98.1497 197.512 98.4834 198.877 98.4834C199.923 98.4834 201.015 98.2862 202.001 97.8312C202.972 97.4369 203.882 96.8605 204.534 96.0111C205.308 95.101 205.763 93.8725 205.763 92.3102C205.763 90.7479 205.111 89.1856 204.079 88.0784C203.033 87.0318 201.668 86.3948 200.045 86.4555C199.787 86.4555 199.453 86.1369 199.453 85.8639C199.256 84.4988 198.74 83.4523 198.027 82.6787C197.254 84.1045 195.813 85.0904 194.053 85.151C195.282 90.217 195.221 89.8379 200.621 91.0664C198.088 91.0058 195.676 91.1271 193.993 93.0837C192.309 91.1271 189.897 91.0058 187.364 91.0664C192.764 89.8379 192.703 90.217 193.932 85.151C192.173 85.0904 190.747 84.1045 189.958 82.6787C189.245 83.4523 188.73 84.4988 188.532 85.8639C188.532 86.1218 188.214 86.4555 187.941 86.4555C186.439 86.3948 184.953 86.9712 183.846 87.8812C182.875 88.7306 182.283 89.8985 182.344 91.2029C182.344 92.113 182.799 92.8866 183.451 93.5388C183.77 93.7966 184.164 94.0545 184.558 94.191C184.953 94.3882 185.332 94.4488 185.726 94.3882C186.242 94.3882 186.834 94.191 187.289 93.6753C187.683 93.2202 188.517 93.6753 188.335 94.2668C188.199 95.0404 188.274 95.7684 188.532 96.3448C188.73 96.8605 189.124 97.3155 189.503 97.6492C189.958 97.9071 190.413 98.1042 190.929 98.1042C191.384 98.1042 191.9 97.9677 192.355 97.5885C192.87 97.1942 193.583 97.9829 193.265 98.4986C190.079 103.049 186.5 105.263 182.602 105.718C178.704 106.113 174.472 104.672 169.982 102.018C169.527 101.76 169.588 101.047 170.119 100.85C171.545 100.455 172.455 99.4238 172.849 98.2559C173.107 97.6037 173.167 96.8908 173.046 96.1779C172.925 95.4651 172.652 94.8129 172.273 94.2213C171.56 93.2506 170.452 92.5377 168.89 92.5377C167.009 92.5377 165.766 93.5084 165.113 94.8128C164.856 95.4044 164.719 95.9808 164.719 96.633C164.658 97.2852 164.78 97.9374 164.977 98.5138C165.493 99.8182 166.661 100.925 168.557 101.047C169.012 101.047 169.33 101.699 169.012 102.093C166.084 105.734 162.383 107.614 158.606 108.145C154.253 108.737 149.824 107.554 146.184 105.218C145.729 104.899 145.987 103.989 146.639 104.05C150.022 104.368 152.16 102.943 153.207 100.925C153.798 99.8182 154.056 98.4531 153.98 97.2245C153.844 95.9201 153.465 94.6915 152.812 93.7056C151.705 92.1433 149.764 91.2333 147.155 91.8855C146.897 91.9462 146.503 91.749 146.442 91.4911C145.668 89.4132 144.228 88.3059 142.605 87.8509C141.755 87.6537 140.845 87.6537 139.935 87.8509C139.086 88.0481 138.312 88.4424 137.599 89.0188C136.371 90.126 135.582 91.749 135.779 93.9635C135.779 94.2213 135.521 94.555 135.263 94.6157C132.67 95.1314 131.365 96.8908 131.032 98.8475C130.834 99.894 130.971 101.062 131.35 102.169C131.745 103.216 132.397 104.247 133.231 105.036C134.915 106.537 137.523 107.114 140.648 105.627C141.164 105.37 141.755 106.082 141.422 106.537C138.555 110.314 135.506 112.711 131.927 113.757C128.347 114.865 124.312 114.667 119.383 113.166C118.989 113.105 118.867 112.574 119.064 112.256C119.519 111.543 119.717 110.754 119.717 109.981C119.717 109.268 119.58 108.555 119.201 107.903C118.882 107.25 118.427 106.735 117.775 106.34C117.184 105.946 116.41 105.688 115.5 105.688C113.998 105.688 112.83 106.34 112.118 107.311C111.723 107.903 111.465 108.54 111.344 109.268C111.283 109.981 111.283 110.693 111.541 111.406C111.936 112.514 112.77 113.545 114.271 114C114.59 114.061 114.787 114.592 114.59 114.91C113.361 116.791 111.799 118.035 110.161 118.808C108.144 119.779 106.005 120.113 104.048 120.037C103.533 120.037 103.199 119.445 103.533 119.066C104.579 117.762 105.156 116.139 105.156 114.576C105.156 113.803 105.019 113.075 104.761 112.438C104.443 111.785 104.048 111.209 103.533 110.754C102.683 110.163 101.652 109.783 100.211 109.783C99.1037 109.723 98.2543 109.981 97.4808 110.436C96.7072 110.891 95.9792 111.603 95.3421 112.453L95.3876 112.423Z\" fill=\"#FFE200\"><\/path><path d=\"M197.739 39.7995C197.739 37.7822 196.055 36.0986 194.038 36.0986C192.021 36.0986 190.337 37.7822 190.337 39.7995C190.337 41.8168 192.021 43.5763 194.038 43.5763C196.055 43.5763 197.739 41.8927 197.739 39.7995Z\" fill=\"#FFE200\"><\/path><path d=\"M160.472 491.387C159.956 492.555 160.214 493.86 161.064 494.77C161.716 495.422 162.565 495.741 163.339 496.074C162.034 498.744 160.153 499.972 157.09 499.654C153.768 499.259 151.174 497.773 149.551 495.68C148.702 494.633 148.126 493.465 147.792 492.237C147.473 491.008 147.337 489.704 147.473 488.399C147.792 485.609 149.293 482.802 152.024 480.664C155.012 478.252 161.003 476.311 166.387 474.491C168.526 473.778 170.619 473.126 172.303 472.473C174.836 471.503 176.08 469.607 176.277 467.862C176.413 466.694 176.019 465.39 174.972 464.677C174.062 464.086 172.697 464.086 170.938 465.132C167.161 467.347 163.657 468.712 160.017 470.077C158.136 470.85 156.119 471.578 154.102 472.488C149.491 474.566 145.653 477.949 143.242 481.923C140.314 486.731 139.146 492.646 141.482 497.849C142.787 500.716 145.001 503.309 148.444 505.387C152.084 507.662 156.513 508.117 160.351 507.147C163.475 506.297 166.524 504.477 168.223 501.686C170.179 498.562 170.301 493.299 167.631 490.508C165.553 488.369 161.716 488.49 160.472 491.418V491.387Z\" fill=\"#FFE200\"><\/path><path d=\"M233.96 472.458C231.942 471.548 229.925 470.835 228.044 470.046C224.404 468.681 220.885 467.316 217.123 465.102C214.651 463.676 211.663 463.6 208.736 463.676C210.692 465.815 211.921 468.165 214.135 470.243C215.045 471.154 215.895 471.866 216.729 472.519C218.231 473.565 219.914 474.02 221.613 474.597C227.073 476.356 233.125 478.298 236.053 480.649C238.783 482.787 240.284 485.593 240.603 488.384C240.861 490.978 240.148 493.587 238.525 495.664C236.902 497.742 234.293 499.244 230.987 499.638C227.923 499.957 226.042 498.728 224.738 496.059C225.511 495.74 226.361 495.407 227.013 494.754C227.862 493.844 228.12 492.54 227.604 491.372C226.376 488.445 222.538 488.323 220.445 490.462C217.776 493.253 217.912 498.531 219.854 501.641C221.537 504.431 224.601 506.251 227.726 507.101C231.563 508.072 235.977 507.617 239.632 505.341C243.075 503.264 245.29 500.655 246.594 497.803C248.93 492.601 247.762 486.685 244.835 481.877C242.423 477.918 238.586 474.536 233.975 472.443L233.96 472.458Z\" fill=\"#FFE200\"><\/path><path d=\"M219.52 489.567C220.369 488.718 221.34 488.202 222.311 487.944C223.357 487.687 224.328 487.687 225.299 487.884C226.148 488.142 226.922 488.597 227.574 489.188C228.09 489.704 228.484 490.295 228.742 490.948C229.06 491.66 229.197 492.51 229.06 493.359C228.924 494.209 228.545 494.982 227.892 495.695C227.498 496.014 227.043 496.408 226.467 496.742C226.861 497.333 227.377 497.712 227.892 497.97C228.742 498.425 229.713 498.486 230.759 498.425C233.747 498.031 236.022 496.742 237.524 494.922C238.237 494.011 238.752 493.041 239.025 491.933C239.344 490.826 239.42 489.719 239.283 488.551C239.025 486.079 237.721 483.606 235.249 481.665C232.519 479.45 226.542 477.57 221.203 475.81C220.43 475.552 219.702 475.355 219.323 475.219C217.958 474.764 216.987 474.248 216.001 473.596C215.091 472.944 214.242 472.17 213.21 471.184C212.164 470.138 211.193 469.106 210.222 467.999L210.161 467.938C209.449 467.741 208.66 467.544 207.947 467.347C207.628 467.286 207.355 467.15 207.037 467.089C208.599 468.06 210.086 469.227 211.39 470.532C215.819 474.885 218.61 480.998 218.61 487.702C218.61 488.87 218.549 490.113 218.352 491.281C218.67 490.629 219.065 490.053 219.52 489.598V489.567Z\" fill=\"#FFE200\"><\/path><path d=\"M210.541 474.612C206.187 473.247 201.759 472.018 197.269 471.29C194.084 470.699 195.646 471.882 194.144 474.475C192.84 476.751 191.475 479.086 189.988 481.498C188.82 483.455 187.577 485.396 186.287 487.353C185.893 488.005 185.772 488.46 186.424 488.854C187.334 489.37 188.563 489.446 189.549 489.507C195.145 490.022 200.469 492.753 205.156 495.816C206.46 496.59 208.796 498.547 210.101 498.683C210.753 498.82 211.329 498.486 212.118 497.576H212.057C212.77 496.529 213.68 495.559 214.272 494.451C215.834 491.66 213.62 489.385 211.284 488.081C205.945 485.093 200.227 482.818 194.372 481.195C193.522 480.937 193.856 479.693 194.69 479.966C199.954 481.468 205.095 483.409 209.904 485.882C212.694 487.307 214.454 484.38 214.97 482.105C215.682 478.722 213.923 475.674 210.541 474.627V474.612Z\" fill=\"#FFE200\"><\/path><path d=\"M194.675 466.679C194.736 467.65 195.07 469.667 196.101 469.804C200.393 470.395 204.625 471.487 208.781 472.731C209.373 472.928 210.01 472.928 210.404 472.337C210.541 472.14 210.662 471.563 210.465 471.366C206.491 467.468 201.167 464.996 195.252 464.662C195.252 464.662 195.231 464.682 195.191 464.723C194.675 465.041 194.599 465.951 194.675 466.679Z\" fill=\"#FFE200\"><\/path><path d=\"M204.625 497.105C199.165 494.769 196.829 499.062 192.597 500.882C189.078 502.383 184.983 503.293 181.221 503.157C181.737 504.325 182.587 505.371 183.633 506.282L184.027 505.766C184.543 504.992 185.59 505.766 185.074 506.479L184.619 507.07C184.938 507.328 185.211 507.525 185.529 507.722C185.787 507.465 185.923 507.07 185.984 506.676C186.181 505.826 187.41 506.084 187.213 506.934C187.152 507.449 186.955 507.98 186.621 508.435C187.076 508.693 187.531 508.951 188.047 509.148C188.305 508.632 188.502 508.102 188.563 507.525C188.699 506.615 189.988 506.812 189.791 507.722C189.731 508.435 189.473 509.088 189.2 509.679C189.913 509.998 190.625 510.271 191.278 510.453C191.535 509.679 191.672 508.951 191.596 508.238C191.535 507.328 192.825 507.267 192.901 508.102C192.901 508.951 192.84 509.785 192.582 510.635C193.037 510.695 193.553 510.695 194.008 510.695H194.523C194.721 509.725 194.781 508.739 194.842 507.768C194.842 506.858 196.071 506.919 196.071 507.829C196.071 508.739 196.01 509.709 195.813 510.619C196.662 510.559 197.496 510.422 198.346 510.301C198.406 509.194 198.406 508.086 198.285 506.979C198.224 506.069 199.453 505.933 199.589 506.843C199.65 507.889 199.65 508.921 199.65 509.967C200.363 509.77 201.152 509.573 201.865 509.315C201.865 508.147 201.804 506.903 201.546 505.735C201.349 504.886 202.653 504.628 202.775 505.538C203.033 506.585 203.093 507.677 203.169 508.784C203.882 508.466 204.671 508.132 205.308 507.738C205.368 506.63 205.505 505.66 205.171 504.613C204.974 503.703 206.218 503.385 206.4 504.295C206.658 505.265 206.658 506.175 206.658 506.964C207.31 506.509 207.826 505.66 207.704 504.886C207.644 504.689 207.568 504.492 207.507 504.234C207.113 503.384 208.281 502.869 208.614 503.718C208.614 503.718 208.634 503.764 208.675 503.855C208.933 503.202 209.13 502.55 209.069 501.898C209.009 499.684 206.476 497.863 204.58 497.09L204.625 497.105Z\" fill=\"#FFE200\"><\/path><path d=\"M186.105 501.458C189.291 500.943 195.145 499.244 196.829 496.119C197.542 494.891 197.026 492.798 195.661 492.282C192.537 491.053 188.32 490.204 184.862 490.598C183.633 490.735 182.526 491.19 181.358 491.372C180.964 491.433 180.584 491.508 180.19 491.508C178.112 491.645 175.958 490.796 174.472 489.37C173.82 488.718 174.669 487.808 175.321 488.46C176.626 489.688 178.446 490.341 180.129 490.28C180.584 490.28 180.979 490.219 181.358 490.083C182.526 489.825 183.633 489.112 184.346 488.005C185.969 485.593 187.471 483.197 188.896 480.846C190.322 478.51 191.763 476.159 193.128 473.823C194.493 471.351 194.69 467.847 192.081 466.209C191.945 466.148 191.884 466.072 191.763 466.072C190.853 465.617 187.865 465.617 188.381 467.301C188.699 468.469 190.064 469.121 190.337 470.486C190.474 471.335 190.277 472.17 189.685 473.535C188.123 476.917 186.242 480.163 184.225 483.288C183.709 484.061 182.662 483.348 183.178 482.575C185.195 479.526 187.015 476.401 188.517 473.019C188.972 471.912 189.169 471.26 189.033 470.744C188.896 469.97 187.926 468.863 187.273 468.332C185.514 467.104 183.299 467.559 181.358 468.59C179.856 469.364 178.491 470.471 177.581 471.381C173.349 475.537 170.756 481.27 170.756 487.641C170.756 491.539 171.726 495.255 173.486 498.44C175.048 500.973 178.233 501.762 181.358 501.822C183.042 501.883 184.74 501.686 186.105 501.428V501.458ZM178.946 479.162C179.598 478.191 180.311 477.281 180.903 476.295C181.039 476.098 181.221 475.84 181.358 475.643C181.813 474.87 182.268 474.141 182.723 473.429C183.178 472.655 184.285 473.292 183.77 474.081C183.178 475.052 182.602 476.037 182.01 477.008C181.752 477.327 181.555 477.6 181.358 477.918C180.903 478.57 180.448 479.223 179.993 479.875C179.401 480.648 178.37 479.875 178.946 479.162Z\" fill=\"#FFE200\"><\/path><path d=\"M174.851 472.534C174.26 472.989 173.547 473.383 172.773 473.641C171.014 474.293 168.936 475.006 166.797 475.719C161.534 477.478 155.618 479.42 152.812 481.634C150.34 483.591 149.036 486.063 148.778 488.52C148.641 489.688 148.717 490.796 149.036 491.903C149.294 493.01 149.809 493.981 150.537 494.891C152.812 497.758 157.818 499.183 159.638 495.027C159.319 494.512 159.122 493.92 158.986 493.344C158.849 492.494 158.986 491.66 159.304 490.932C159.562 490.28 159.956 489.704 160.472 489.173C161.124 488.581 161.898 488.126 162.747 487.868C163.718 487.671 164.704 487.671 165.735 487.929C166.706 488.187 167.692 488.703 168.526 489.552C168.981 490.007 169.376 490.598 169.694 491.236C169.497 490.068 169.436 488.824 169.436 487.656C169.436 481.938 171.454 476.675 174.836 472.503L174.851 472.534Z\" fill=\"#FFE200\"><\/path><path d=\"M199.165 459.459C197.481 459.459 195.722 459.52 194.023 459.52C192.461 459.52 190.838 459.52 189.276 459.459C186.94 459.398 185.12 462.326 187.455 464.267C189.533 463.676 191.748 463.357 194.023 463.357C199.165 463.357 204.428 465.041 209.373 466.421C207.75 463.888 202.35 459.338 199.165 459.459Z\" fill=\"#FFE200\"><\/path><path d=\"M153.586 471.29C155.664 470.38 157.681 469.667 159.638 468.878C163.217 467.513 166.661 466.148 170.361 463.994C170.619 463.858 170.877 463.737 171.135 463.6C171.529 462.751 171.59 461.977 171.332 461.188C169.967 461.249 168.86 461.386 167.95 461.507C165.811 461.765 164.962 461.704 164.765 459.368C164.704 458.853 164.704 458.2 164.628 457.351C163.718 457.745 162.869 458.064 162.216 458.398C161.367 458.853 160.654 459.308 160.078 459.763C159.941 459.899 159.623 459.899 159.426 459.823C157.469 458.974 155.33 458.2 153.176 457.806C151.099 457.351 148.945 457.214 146.867 457.487C146.351 457.624 145.957 456.972 146.275 456.517C146.73 455.804 147.246 455.091 147.837 454.378C148.035 454.12 148.232 453.862 148.49 453.605C148.095 453.665 147.716 453.741 147.322 453.862C146.351 454.06 145.502 454.317 144.592 454.636C144.076 454.772 143.621 454.181 143.879 453.726L145.244 451.254C144.076 451.314 142.908 451.511 141.801 451.769C140.375 452.027 138.873 452.482 137.448 453.074C136.993 453.271 136.401 452.679 136.674 452.224L138.297 448.448L138.16 448.387C136.401 448.705 134.642 449.1 132.897 449.494C132.442 449.555 132.048 449.1 132.184 448.645L132.958 446.112C132.761 445.975 132.564 445.915 132.366 445.793C130.683 446.9 129.121 447.613 127.68 448.008C126.375 448.265 125.147 448.265 124.161 447.81C123.114 447.355 122.341 446.445 121.886 445.08C121.491 443.912 121.37 442.289 121.567 440.196C121.506 440.196 121.431 440.136 121.37 440.136L119.413 441.759C119.019 442.077 118.367 441.759 118.367 441.304L118.169 438.24C118.033 438.103 117.912 438.043 117.775 437.982C117.381 438.3 116.926 438.695 116.471 439.089C116.334 439.226 116.213 439.286 116.152 439.347C115.834 439.665 115.181 439.408 115.106 438.953C115.045 438.103 115.045 437.33 115.106 436.617C114.453 437.072 113.801 437.466 113.028 437.724C112.633 437.86 112.178 437.587 112.178 437.208C112.118 436.238 112.042 435.252 112.118 434.342C111.92 434.144 111.663 434.023 111.465 433.887C110.692 434.281 109.903 434.539 109.13 434.539C108.219 434.599 107.309 434.402 106.521 433.947C105.747 433.492 105.095 432.901 104.64 432.066C104.048 431.02 103.73 429.791 103.927 428.29C100.878 425.878 97.951 423.406 95.0843 420.812C94.9478 421.525 94.7658 422.177 94.4927 422.89C93.5827 425.878 92.2783 428.35 90.5947 430.959C89.1689 433.037 87.9858 435.054 87.0758 437.39C86.3022 439.271 84.8613 442.593 85.5742 444.61C86.1657 446.37 88.3043 446.43 89.6694 445.657C90.261 444.094 90.898 442.608 91.4896 441.106C92.2631 439.347 92.9911 437.724 93.704 436.222C94.0984 435.373 95.2056 435.965 94.8113 436.738C94.0984 438.3 93.3855 439.923 92.6726 441.546C92.0204 443.23 91.3075 444.929 90.6553 446.552C90.3368 447.462 90.4581 449.342 90.9132 450.192C91.3075 451.102 92.0811 451.496 93.0518 451.299C94.1591 451.041 95.0691 450.389 95.4635 449.418C95.9792 448.053 96.51 446.749 97.0864 445.52C97.6021 444.155 98.1937 442.79 98.8459 441.364C99.1644 440.515 100.347 441.046 100.014 441.88C99.4222 443.184 98.8459 444.549 98.2543 445.975C97.6628 447.401 97.0864 448.842 96.4949 450.268C95.9792 451.436 95.782 452.937 96.0399 454.242C96.237 455.288 96.8134 456.198 97.7235 456.835C98.77 457.487 100.256 456.244 100.59 455.334C100.909 454.424 101.182 453.514 101.5 452.603L102.152 450.647C102.471 449.797 103.715 450.192 103.381 451.041L102.668 453.059C102.41 453.908 102.077 454.818 101.758 455.728C101.303 457.093 101.167 458.519 101.364 459.884C101.622 461.113 102.137 462.356 103.047 463.327C103.7 464.101 104.276 464.829 105.262 464.374C105.914 464.116 106.49 463.524 106.688 462.948C107.461 460.809 108.25 458.519 108.963 456.32C109.418 455.015 109.812 453.787 110.131 452.998C110.388 452.148 111.632 452.543 111.299 453.392C110.844 454.757 110.525 455.728 110.191 456.714C109.418 458.928 108.69 461.067 107.916 463.342C107.4 464.768 107.4 466.072 107.719 466.922C108.113 467.892 108.887 468.347 109.858 468.287C111.162 468.15 112.451 467.119 112.588 465.814C112.724 464.586 112.906 463.084 113.24 461.461C113.634 459.505 114.15 457.305 114.742 454.894C114.999 454.044 116.243 454.378 115.97 455.212C115.379 457.548 114.863 459.763 114.469 461.719C114.15 463.539 113.877 465.162 113.816 466.527C113.756 467.498 113.877 468.15 114.211 468.484C114.529 468.939 115.06 469 115.576 468.803C116.622 468.484 117.199 467.437 117.714 466.467C118.488 464.965 119.14 463.281 119.671 461.461C120.263 459.247 120.778 456.911 121.173 454.242C121.309 453.392 122.538 453.589 122.401 454.439C122.007 457.169 121.491 459.581 120.9 461.78C120.308 463.737 119.671 465.481 118.822 467.043C117.851 468.924 118.23 472.898 121.097 470.623C122.978 469.197 125.071 465.481 126.299 463.281C126.618 462.629 126.952 462.114 127.149 461.856C127.604 461.082 128.711 461.719 128.195 462.508C127.998 462.826 127.74 463.281 127.422 463.934C126.315 465.814 124.692 468.818 122.811 470.698C121.643 472.003 119.823 474.217 120.217 476.038C120.414 476.948 121.127 477.463 122.037 477.463C123.721 477.524 124.965 475.901 125.814 474.597C126.982 472.64 128.286 470.896 129.591 469.136C131.017 467.255 132.457 465.435 133.883 463.676C134.475 463.024 135.445 463.812 134.854 464.525C133.352 466.285 131.927 468.105 130.622 469.925C129.318 471.548 128.089 473.307 126.921 475.188C126.148 476.356 124.843 477.403 124.449 478.707C124.055 479.875 124.13 480.785 124.449 481.437C124.707 482.029 125.298 482.347 125.951 482.287C127.058 482.15 128.089 481.119 128.681 480.269C130.501 477.676 132.382 475.203 134.399 472.731C136.356 470.319 138.494 467.983 140.648 465.708C141.3 465.056 142.21 465.966 141.558 466.618C139.419 468.833 137.326 471.169 135.385 473.58C133.368 475.916 131.547 478.464 129.727 480.997C129.212 481.847 128.559 482.423 127.968 482.817C127.194 484.638 127.452 486.716 128.226 488.02C128.544 488.414 128.878 488.733 129.196 488.991C131.077 489.961 132.579 486.579 133.034 485.411C134.202 482.544 135.764 480.072 137.584 477.933C139.465 475.856 141.619 474.035 143.955 472.412C144.212 472.215 144.47 472.018 144.865 472.549C145.183 473.065 144.925 473.262 144.667 473.459C142.453 475.021 140.314 476.781 138.555 478.798C136.795 480.876 135.309 483.151 134.262 485.881C133.61 487.565 131.927 489.203 133.671 490.887C133.989 491.205 134.444 491.478 134.899 491.6C135.354 491.797 135.87 491.797 136.401 491.736C137.448 491.6 138.479 490.826 139.131 489.142C139.526 486.473 140.557 483.743 142.059 481.27C144.652 477.114 148.626 473.535 153.51 471.32L153.586 471.29Z\" fill=\"#FFE200\"><\/path><path d=\"M267.055 453.483C261.595 450.753 255.68 449.054 251.19 447.886H251.129C251.387 448.66 251.19 449.388 251.19 450.222C251.129 450.616 250.674 450.935 250.28 450.738C249.309 450.283 248.521 449.828 247.747 449.373C248.141 450.222 248.399 451.132 248.596 452.239C248.657 452.694 248.278 453.089 247.823 452.952C246.518 452.694 245.229 452.3 243.985 451.906C243.728 451.845 242.939 451.314 242.681 451.253C243.394 451.966 244.638 453.074 245.548 453.923C245.942 454.317 245.411 455.152 244.895 454.97C242.817 454.257 241.255 453.407 239.435 452.437C240.148 453.802 241.195 455.303 242.165 456.532C242.484 457.047 241.771 457.836 241.255 457.442C239.374 456.213 237.554 454.848 235.795 453.407C235.537 453.468 235.279 453.604 235.021 453.665C235.416 454.712 235.871 455.743 236.326 456.729C236.584 457.321 235.673 457.897 235.279 457.442C234.43 456.395 233.596 455.364 232.867 454.257C231.639 454.575 230.395 454.909 229.167 455.227C230.334 456.456 231.578 457.639 232.807 458.746C233.52 459.338 232.67 460.309 231.957 459.717C230.456 458.413 229.091 457.048 227.801 455.561C226.831 455.819 225.845 456.016 224.935 456.213L228.378 459.99C228.969 460.642 228.059 461.492 227.407 460.839L223.433 456.547C222.129 456.805 220.764 457.063 219.399 457.321C219.914 457.715 220.445 458.17 221.022 458.549C222.326 459.52 223.615 460.43 225.056 461.34C225.83 461.795 225.117 462.902 224.343 462.447C222.917 461.537 221.552 460.566 220.248 459.58C219.399 458.928 218.564 458.276 217.776 457.563C216.805 457.76 215.758 457.882 214.788 458.018C215.637 459.58 216.547 460.946 217.654 462.174C219.08 463.797 220.642 465.162 222.462 466.269C222.66 466.406 222.857 466.527 223.054 466.664C224.874 467.513 226.694 468.165 228.514 468.878C230.471 469.652 232.412 470.38 234.49 471.29C239.374 473.504 243.333 477.084 245.942 481.24C247.565 483.909 248.612 486.837 248.991 489.688C249.249 491.963 249.051 494.239 248.475 496.453C249.188 497.166 250.432 496.65 251.205 496.135C252.707 495.088 253.875 492.692 254.527 490.159C255.3 487.17 255.437 483.909 254.785 482.089C253.025 477.478 250.295 473.762 246.716 471.032C243.136 468.241 238.722 466.285 233.58 465.056C232.67 464.859 232.989 463.63 233.838 463.827C239.177 465.056 243.788 467.073 247.489 470.001C251.266 472.928 254.117 476.765 255.938 481.634C256.256 482.484 256.393 483.652 256.453 484.88C256.453 485.593 256.848 486.245 257.56 486.64C258.865 487.489 259.578 485.472 259.775 484.501C260.548 480.209 259.32 476.174 257.045 472.867C254.117 468.438 249.309 465.132 244.88 463.63C243.97 463.372 244.425 462.129 245.275 462.462C249.961 464.025 254.967 467.528 258.152 472.155C260.685 475.992 262.05 480.603 260.822 485.548C260.624 486.321 260.564 486.852 261.019 487.626C261.216 488.081 261.671 488.475 262.187 488.338C264.522 487.883 264.977 483.727 265.175 481.968C265.432 480.148 265.569 478.267 265.569 476.31C265.508 473.838 265.175 471.366 264.007 469.348C262.323 466.163 257.181 463.691 253.086 461.613C251.857 461.021 250.674 460.445 249.704 459.854C248.93 459.459 249.506 458.291 250.295 458.746C251.266 459.338 252.434 459.853 253.678 460.506C257.909 462.584 263.233 465.253 265.19 468.757C266.418 470.971 266.813 473.641 266.873 476.295C266.873 478.252 266.676 480.269 266.418 482.15C266.282 483.652 267.465 484.289 268.633 483.318C270.514 481.756 271.757 478.768 272.273 475.643C272.789 472.2 272.531 468.56 271.363 466.482C269.998 463.949 268.041 461.871 265.645 460.111C263.233 458.428 260.382 456.987 257.257 455.758C256.408 455.44 256.863 454.257 257.712 454.59C260.897 455.819 263.885 457.32 266.358 459.141C268.951 460.961 271.045 463.175 272.531 465.905C273.441 467.589 273.896 470.259 273.76 472.989C273.76 473.702 273.502 474.096 274.215 474.612C274.988 475.203 275.898 475.522 276.748 474.748C277.203 474.293 277.597 473.58 277.915 472.792C278.628 470.714 278.826 467.908 278.568 465.966C277.915 460.566 272.91 456.471 267.055 453.483Z\" fill=\"#FFE200\"><\/path><path d=\"M281.1 455.167C279.22 453.028 276.55 451.072 272.91 449.449C271.09 448.6 269.27 447.432 267.51 446.264C266.54 445.611 265.554 445.035 264.583 444.307C263.612 443.594 262.96 443.139 261.656 443.139C261.003 443.139 260.745 443.336 260.882 443.989C261.079 444.641 261.656 445.414 261.989 446.067C261.14 446.067 260.488 446.006 259.653 445.748C258.607 445.49 257.575 445.156 257.378 445.809C256.923 446.855 259.198 448.857 260.245 449.191C262.717 450.101 265.25 451.148 267.662 452.376C273.835 455.501 279.114 459.915 279.887 465.83C279.948 466.679 280.024 467.65 279.948 468.697C280.918 469.47 281.176 469.804 282.284 468.757C283.785 467.256 285.074 464.662 284.619 462.448C284.028 459.854 282.996 457.382 281.1 455.167Z\" fill=\"#FFE200\"><\/path><path d=\"M298.467 436.117C297.952 433.902 297.163 431.763 295.995 430.065C294.888 428.502 293.386 427.471 291.506 427.334C290.99 427.334 290.459 427.395 289.883 427.532C289.17 427.668 288.517 428.047 288.26 428.76C287.865 429.67 288.396 431.172 289.109 431.748C290.671 432.977 292.097 434.615 293.401 436.359C294.964 438.498 296.329 440.712 297.102 442.472C297.3 442.866 297.497 443.321 297.694 443.837C299.12 444.231 298.998 443.973 298.998 442.669C298.998 442.472 298.998 442.214 299.059 441.956C299.12 440.333 298.922 438.179 298.467 436.101V436.117Z\" fill=\"#FFE200\"><\/path><path d=\"M292.355 437.163C291.187 435.479 289.761 433.917 288.32 432.81C287.471 432.097 286.44 431.702 285.454 431.763C284.604 431.899 283.77 432.279 283.042 433.189C282.648 433.644 282.451 434.159 282.526 434.69C282.587 435.919 284.286 437.36 285.059 438.133C287.85 441.061 290.717 444.049 293.189 447.689C293.902 448.796 294.691 450.359 295.009 451.921C295.859 452.239 296.966 452.573 297.421 451.526C297.618 451.011 297.679 450.298 297.679 449.509C297.542 447.295 296.632 444.564 295.919 443.078C295.146 441.319 293.902 439.18 292.34 437.163H292.355Z\" fill=\"#FFE200\"><\/path><path d=\"M284.149 439.043C283.558 438.391 282.921 437.815 282.648 437.481C282.056 436.829 281.146 436.253 280.236 436.055C279.584 435.919 278.932 435.995 278.355 436.51C277.703 437.102 276.732 437.678 276.672 438.725C276.414 440.803 277.976 441.516 279.402 442.82C280.509 443.867 281.616 444.898 282.784 445.884C284.801 447.643 286.561 449.524 287.926 451.799C288.639 453.104 289.23 454.469 289.61 456.031C289.746 456.683 289.867 457.26 290.838 457.396C292.855 457.533 294.023 455.182 293.963 453.438C293.902 451.678 292.992 449.737 292.082 448.432C289.67 444.853 286.879 441.925 284.149 439.074V439.043Z\" fill=\"#FFE200\"><\/path><path d=\"M281.95 446.84C280.782 445.869 279.675 444.762 278.507 443.715C277.4 442.668 276.292 441.576 275.064 440.53C274.093 439.756 272.728 438.968 271.621 438.77C271.166 438.71 270.453 438.573 270.256 439.165C270.059 439.878 270.514 441.121 270.65 441.895C269.543 441.637 266.873 440.075 267.268 442.411C267.723 445.338 271.044 447.158 273.441 448.265C277.278 449.949 280.069 452.042 282.086 454.378C284.104 456.714 285.272 459.383 285.863 462.174C285.924 462.568 286 463.023 286 463.403H286.515C287.107 463.403 287.562 463.205 287.941 462.948C288.336 462.629 288.593 462.174 288.791 461.522C288.851 461.067 288.927 460.612 288.927 460.02C288.791 457.032 288.017 454.499 286.849 452.406C285.621 450.267 283.922 448.432 281.965 446.809L281.95 446.84Z\" fill=\"#FFE200\"><\/path><path d=\"M350.933 230.7C350.28 229.017 348.855 229.138 347.414 229.654C345.396 232.703 343.455 236.024 341.62 239.543C339.739 243.183 337.979 247.021 336.478 250.995C336.159 251.844 334.976 251.389 335.31 250.54C336.811 246.505 338.632 242.607 340.512 238.967C342.393 235.327 344.41 231.944 346.488 228.82C347.717 226.863 348.248 224.785 347.596 222.51C347.277 221.342 346.488 220.235 345.184 220.038C344.926 220.553 344.592 221.084 344.274 221.539C342.196 224.209 340.315 226.939 338.419 229.669C336.599 232.46 334.84 235.266 333.217 238.193C332.762 238.967 331.594 238.39 332.11 237.541C333.732 234.614 335.553 231.747 337.373 228.956C339.253 226.165 341.21 223.435 343.227 220.766C344.077 219.719 344.592 218.551 344.653 217.323C344.79 214.79 341.862 211.347 339.906 214.077C337.494 217.459 335.098 221.039 332.747 224.603C330.214 228.501 327.741 232.475 325.33 236.57C324.875 237.344 323.767 236.707 324.222 235.918C326.695 231.823 329.167 227.788 331.7 223.951C334.172 220.113 336.645 216.413 339.178 212.894C339.633 212.241 339.951 211.589 339.891 210.679C339.891 210.163 339.754 209.708 339.496 209.314C338.723 208.207 337.085 207.949 336.25 208.996C333.52 212.241 331.184 215.502 328.909 218.748C326.573 222.131 324.359 225.634 322.023 229.214C321.568 229.988 320.461 229.275 320.976 228.562C323.312 224.922 325.527 221.479 327.863 218.035C330.274 214.517 332.807 211.149 335.659 207.691C336.372 206.781 336.174 205.552 335.795 204.642C335.598 204.385 335.401 204.127 335.28 203.93C334.051 202.564 332.944 202.428 331.836 203.732C327.544 208.161 322.736 213.227 318.246 220.644C317.791 221.418 316.684 220.781 317.2 219.992C321.75 212.454 326.634 207.373 330.926 202.822C331.836 201.912 332.686 201.321 332.489 199.895C332.352 198.848 331.836 198.014 331.124 197.362C329.698 196.194 329.046 195.997 327.741 197.362C325.527 199.637 323.388 202.307 321.234 205.234C319.096 208.222 316.942 211.407 314.727 214.79C314.591 215.047 314.409 215.305 313.878 214.987C313.362 214.668 313.484 214.395 313.681 214.077C315.895 210.694 318.034 207.448 320.188 204.521C322.402 201.533 324.617 198.803 326.816 196.528C327.923 195.36 328.575 194.45 327.665 192.887C325.982 190.218 324.541 191.917 323.054 193.6C320.84 196.073 318.701 198.606 316.623 201.336C314.545 204.127 312.528 207.054 310.571 210.179C310.374 210.436 310.253 210.694 309.661 210.376C309.146 210.057 309.343 209.784 309.464 209.526C311.481 206.341 313.499 203.353 315.577 200.623C317.715 197.832 319.869 195.223 322.084 192.751C323.13 191.583 323.646 190.734 323.707 190.021C323.843 189.429 323.509 188.853 322.994 188.261C321.765 186.896 318.959 184.03 317.533 187.215C316.168 190.203 314.212 192.554 311.937 194.298C309.404 196.255 306.476 197.544 303.412 198.196C296.132 199.758 288.715 196.634 282.936 192.478C277.021 188.185 271.166 182.134 267.586 175.247C264.462 169.271 262.839 162.309 264.522 155.681C253.526 160.231 243.318 162.507 233.504 162.764C226.224 162.962 217.578 161.991 210.101 159.579C200.151 156.394 187.804 156.394 177.854 159.579C170.377 161.991 161.792 162.962 154.451 162.764C144.637 162.507 134.429 160.231 123.433 155.681C125.116 162.309 123.493 169.271 120.445 175.247C116.804 182.134 110.95 188.185 105.034 192.478C99.2402 196.634 91.8384 199.758 84.5579 198.196C81.5092 197.544 78.5818 196.24 76.0337 194.298C73.7585 192.539 71.8019 190.203 70.4368 187.215C69.011 184.03 66.205 186.896 64.9764 188.261C64.4607 188.853 64.1271 189.429 64.2636 190.021C64.3242 190.734 64.8551 191.583 65.8865 192.751C68.101 195.223 70.2396 197.817 72.3934 200.623C74.4714 203.353 76.4887 206.341 78.506 209.526C78.6425 209.784 78.8245 210.042 78.3088 210.376C77.7173 210.694 77.596 210.436 77.3988 210.179C75.4421 207.054 73.4248 204.127 71.3469 201.336C69.2689 198.606 67.1151 196.073 64.9158 193.6C63.4142 191.917 61.9884 190.218 60.3048 192.887C59.3947 194.45 60.047 195.36 61.1542 196.528C63.3687 198.803 65.5832 201.533 67.7825 204.521C69.9211 207.448 72.1356 210.694 74.2894 214.077C74.4866 214.395 74.6079 214.668 74.0922 214.987C73.5765 215.305 73.3793 215.047 73.2428 214.79C71.0283 211.407 68.8897 208.222 66.7359 205.234C64.5973 202.307 62.4434 199.637 60.229 197.362C58.9245 195.997 58.2723 196.194 56.8466 197.362C56.1337 198.014 55.618 198.864 55.4815 199.895C55.2843 201.321 56.1337 201.912 57.0438 202.822C61.3362 207.373 66.205 212.439 70.7705 219.992C71.2862 220.766 70.179 221.418 69.7239 220.644C65.2343 213.227 60.4261 208.161 56.1337 203.732C55.0265 202.428 53.9192 202.564 52.6906 203.93C52.5541 204.127 52.3721 204.385 52.1749 204.642C51.7806 205.552 51.5834 206.781 52.3114 207.691C55.1781 211.134 57.7111 214.517 60.1076 218.035C62.4434 221.479 64.6579 224.922 66.9937 228.562C67.5094 229.275 66.4022 229.988 65.9472 229.214C63.6114 225.634 61.3969 222.131 59.0611 218.748C56.7859 215.502 54.4501 212.241 51.7199 208.996C50.8705 207.949 49.2476 208.222 48.474 209.314C48.2162 209.708 48.0797 210.163 48.0797 210.679C48.019 211.589 48.3375 212.241 48.7925 212.894C51.3255 216.413 53.7979 220.113 56.2702 223.951C58.8032 227.788 61.2755 231.823 63.7479 235.918C64.2029 236.692 63.0957 237.344 62.6406 236.57C60.229 232.475 57.7566 228.501 55.2236 224.603C52.8878 221.023 50.4762 217.444 48.0645 214.077C46.1079 211.347 43.1805 214.79 43.317 217.323C43.3777 218.551 43.9692 219.734 44.7428 220.766C46.7601 223.435 48.7167 226.165 50.5975 228.956C52.4783 231.747 54.2377 234.614 55.8607 237.541C56.3764 238.39 55.2085 238.967 54.7534 238.193C53.1305 235.266 51.371 232.475 49.5509 229.669C47.6701 226.939 45.7742 224.209 43.6962 221.539C43.3777 221.084 43.044 220.568 42.7861 220.038C41.4817 220.235 40.7082 221.342 40.3745 222.51C39.7223 224.785 40.238 226.863 41.4817 228.82C43.5597 231.944 45.577 235.327 47.4578 238.967C49.3386 242.607 51.1587 246.505 52.6603 250.54C52.9788 251.389 51.8109 251.844 51.4924 250.995C49.9908 247.021 48.2465 243.199 46.3505 239.543C44.5304 236.024 42.5738 232.718 40.5565 229.654C39.1307 229.138 37.6898 229.002 37.0376 230.7C35.7332 234.144 37.2348 237.132 38.6605 240.195C43.8024 251.45 49.0656 262.826 52.7058 275.566C69.4206 213.273 126.512 167.178 193.932 167.178C261.352 167.178 318.459 213.288 335.158 275.566C338.798 262.826 344.062 251.45 349.203 240.195C350.629 237.147 352.131 234.144 350.826 230.7H350.933Z\" fill=\"#FFE200\"><\/path><path d=\"M283.694 191.431C289.155 195.405 296.314 198.454 303.2 196.952C306.067 196.3 308.857 195.132 311.193 193.312C313.332 191.628 315.167 189.474 316.396 186.684C317.366 184.606 317.761 181.936 317.366 179.661C317.169 178.69 316.911 177.78 316.396 177.067C315.622 175.642 313.529 174.337 311.845 174.731C310.48 175.05 309.57 176.294 309.707 177.659C309.843 179.479 311.33 179.676 312.755 179.615C313.013 181.693 313.013 183.65 312.24 185.592C310.677 189.823 306.779 192.296 302.426 192.811C299.696 193.206 296.708 192.872 293.978 192.038C289.685 190.733 285.454 187.882 281.889 184.242C277.991 180.404 274.867 175.596 273.107 171.106C271.803 167.785 271.151 164.342 271.348 160.762C271.606 157.637 272.516 154.452 274.396 151.404C275.625 149.386 277.642 149.326 279.538 149.265C281.04 149.204 282.405 149.128 282.86 147.961C283.254 147.05 282.996 146.08 282.405 145.367C281.631 144.32 280.327 143.744 279.023 143.683C272.713 143.486 267.905 149.144 266.206 154.68C264.189 161.111 265.554 168.664 268.739 174.701C272.243 181.405 277.976 187.321 283.694 191.477V191.431Z\" fill=\"#FFE200\"><\/path><path d=\"M233.565 161.52C242.726 161.262 252.419 159.184 262.702 155.013C264.007 154.498 265.175 153.648 265.766 152.283C266.873 149.75 268.496 147.399 270.574 145.579C253.48 152.147 230.774 155.984 207.113 157.031C215.637 160.216 224.343 161.778 233.58 161.52H233.565Z\" fill=\"#FFE200\"><\/path><path d=\"M76.8527 193.312C79.1885 195.132 81.9945 196.3 84.8461 196.952C91.7322 198.454 98.8913 195.39 104.352 191.431C110.07 187.275 115.803 181.36 119.307 174.656C122.492 168.604 123.918 161.066 121.84 154.635C120.156 149.114 115.333 143.456 109.023 143.638C107.795 143.699 106.414 144.29 105.641 145.322C105.049 146.035 104.792 147.005 105.186 147.915C105.641 149.083 107.006 149.144 108.508 149.22C110.388 149.28 112.406 149.356 113.649 151.358C115.53 154.407 116.44 157.607 116.698 160.717C116.895 164.296 116.243 167.74 114.939 171.061C113.255 175.551 110.055 180.359 106.157 184.196C102.577 187.837 98.3605 190.703 94.068 191.993C91.3378 192.842 88.3498 193.161 85.6196 192.766C81.2665 192.25 77.3684 189.778 75.8061 185.546C75.0933 183.59 75.0326 181.648 75.2904 179.57C76.7162 179.631 78.2178 179.434 78.3391 177.614C78.4756 176.249 77.5656 175.02 76.2005 174.686C74.5169 174.292 72.4237 175.596 71.6502 177.022C71.1345 177.735 70.8766 178.645 70.6795 179.616C70.2851 181.891 70.6795 184.56 71.6502 186.638C72.8788 189.429 74.7141 191.583 76.8527 193.267V193.312Z\" fill=\"#FFE200\"><\/path><path d=\"M125.298 155.014H125.359C135.627 159.17 145.32 161.263 154.496 161.521C155.8 161.657 161.716 161.384 164.643 160.095C167.828 158.73 165.493 155.939 163.02 155.666C146.048 153.846 130.182 150.464 117.502 145.595C119.58 147.415 121.203 149.751 122.31 152.299C122.902 153.603 123.994 154.513 125.298 155.029V155.014Z\" fill=\"#FFE200\"><\/path><path d=\"M287.987 109.753C286.561 109.753 285.257 110.345 284.286 111.255C283.376 112.226 282.724 113.53 282.724 114.956C282.724 117.883 285.135 120.219 287.987 120.219C289.488 120.219 290.778 119.628 291.688 118.718C292.658 117.747 293.25 116.442 293.25 114.941C293.25 112.074 290.914 109.738 287.987 109.738V109.753Z\" fill=\"#FFE200\"><\/path><path d=\"M276.156 141.363C277.46 141.818 278.689 141.423 279.402 140.65C279.66 140.392 279.918 140.058 280.054 139.679C280.115 139.361 280.191 138.966 280.115 138.572C279.978 137.601 279.144 136.615 277.324 136.039C250.204 126.878 222.114 122.251 194.023 122.251C165.933 122.251 137.842 126.862 110.722 136.039C108.902 136.63 108.053 137.601 107.931 138.572C107.871 138.966 107.931 139.345 107.992 139.679C108.129 140.073 108.386 140.392 108.644 140.65C109.357 141.423 110.601 141.818 111.89 141.363C141.346 132.065 167.677 127.378 194.008 127.378C220.339 127.378 246.67 132.065 276.126 141.363H276.156Z\" fill=\"#FFE200\"><\/path><path d=\"M188.957 100.077C188.957 98.5751 187.728 97.4072 186.227 97.4072C184.725 97.4072 183.557 98.5751 183.557 100.077C183.557 101.578 184.725 102.807 186.227 102.807C187.728 102.807 188.957 101.578 188.957 100.077Z\" fill=\"#FFE200\"><\/path><path d=\"M194.038 83.877C195.858 83.877 197.36 82.3754 197.36 80.5552C197.36 78.7351 195.858 77.1729 194.038 77.1729C192.218 77.1729 190.716 78.6745 190.716 80.5552C190.716 82.436 192.218 83.877 194.038 83.877Z\" fill=\"#FFE200\"><\/path><path d=\"M198.133 60.2155C198.133 57.9404 196.313 56.0596 194.038 56.0596C191.763 56.0596 189.943 57.9404 189.943 60.2155C189.943 62.4907 191.763 64.3108 194.038 64.3108C196.313 64.3108 198.133 62.4907 198.133 60.2155Z\" fill=\"#FFE200\"><\/path><path d=\"M197.8 49.75C197.8 47.672 196.116 45.9126 194.023 45.9126C191.93 45.9126 190.246 47.672 190.246 49.75C190.246 51.828 191.93 53.5268 194.023 53.5268C196.116 53.5268 197.8 51.8432 197.8 49.75Z\" fill=\"#FFE200\"><\/path><path d=\"M190.064 70.8784C190.064 73.017 191.884 74.8523 194.038 74.8523C196.192 74.8523 197.997 73.0322 197.997 70.8784C197.997 68.7245 196.177 66.8438 194.038 66.8438C191.899 66.8438 190.064 68.6639 190.064 70.8784Z\" fill=\"#FFE200\"><\/path><path d=\"M194.038 31.6701C198.528 31.6701 202.168 27.9692 202.168 23.4796C202.168 18.99 198.528 15.2891 194.038 15.2891C189.548 15.2891 185.908 18.9293 185.908 23.4796C185.908 28.0299 189.548 31.6701 194.038 31.6701Z\" fill=\"#FFE200\"><\/path><path d=\"M253.92 86.1522C253.92 88.1088 255.482 89.7318 257.424 89.7318C258.395 89.7318 259.305 89.3374 259.957 88.6852C260.609 88.033 261.003 87.1229 261.003 86.1522C261.003 84.1956 259.38 82.6333 257.424 82.6333C255.467 82.6333 253.92 84.1956 253.92 86.1522Z\" fill=\"#FFE200\"><\/path><path d=\"M266.464 72.6985C267.571 72.6985 268.542 72.2435 269.194 71.5913C269.907 70.8784 270.362 69.9077 270.362 68.8004C270.362 66.6618 268.602 64.9023 266.464 64.9023C265.417 64.9023 264.446 65.3574 263.734 66.0703C263.021 66.7831 262.566 67.7539 262.566 68.8004C262.566 70.9391 264.325 72.6985 266.464 72.6985Z\" fill=\"#FFE200\"><\/path><path d=\"M258.925 77.9623C258.925 79.9796 260.609 81.6632 262.702 81.6632C263.749 81.6632 264.659 81.2689 265.296 80.556C266.009 79.9038 266.403 78.9937 266.403 77.9623C266.403 75.8843 264.719 74.1855 262.702 74.1855C261.656 74.1855 260.685 74.5799 260.033 75.2928C259.32 75.945 258.925 76.9157 258.925 77.9623Z\" fill=\"#FFE200\"><\/path><path d=\"M267.177 63.3405C268.284 63.3405 269.255 62.8855 269.968 62.2333C270.681 61.5204 271.075 60.5496 271.075 59.4424C271.075 57.3038 269.315 55.605 267.177 55.605C266.13 55.605 265.159 55.9993 264.447 56.7122C263.734 57.4251 263.339 58.3958 263.339 59.4424C263.339 61.581 265.099 63.3405 267.177 63.3405Z\" fill=\"#FFE200\"><\/path><path d=\"M266.464 53.5113C267.571 53.5113 268.542 53.0563 269.255 52.3434C270.028 51.6305 270.423 50.6598 270.423 49.5525C270.423 47.3381 268.663 45.5786 266.464 45.5786C265.357 45.5786 264.386 46.0336 263.673 46.7465C262.96 47.4594 262.505 48.4301 262.505 49.5374C262.505 51.7519 264.264 53.5113 266.479 53.5113H266.464Z\" fill=\"#FFE200\"><\/path><path d=\"M267.374 43.3041C269.588 43.3041 271.348 41.5447 271.348 39.3454C271.348 37.146 269.588 35.4473 267.374 35.4473C265.159 35.4473 263.476 37.2067 263.476 39.3454C263.476 41.484 265.235 43.3041 267.374 43.3041Z\" fill=\"#FFE200\"><\/path><path d=\"M257.5 40.5133C259.638 40.5133 261.398 38.6932 261.398 36.5394C261.398 34.3856 259.638 32.5654 257.5 32.5654C255.361 32.5654 253.526 34.3856 253.526 36.5394C253.526 38.6932 255.285 40.5133 257.5 40.5133Z\" fill=\"#FFE200\"><\/path><path d=\"M248.581 36.9938C249.628 36.9938 250.598 36.5388 251.311 35.8259C252.024 35.1737 252.479 34.203 252.479 33.0957C252.479 30.9571 250.72 29.2583 248.581 29.2583C247.534 29.2583 246.564 29.6527 245.851 30.3655C245.138 31.0784 244.683 32.0492 244.683 33.0957C244.683 35.2344 246.442 36.9938 248.581 36.9938Z\" fill=\"#FFE200\"><\/path><path d=\"M238.571 35.4321C239.617 35.4321 240.527 34.9771 241.24 34.3249C241.892 33.612 242.287 32.7019 242.287 31.716C242.287 29.6381 240.664 28.0151 238.586 28.0151C237.615 28.0151 236.629 28.4095 235.992 29.0617C235.34 29.7746 234.885 30.6846 234.885 31.7312C234.885 33.7485 236.568 35.4321 238.586 35.4321H238.571Z\" fill=\"#FFE200\"><\/path><path d=\"M229.212 34.0669C230.259 34.0669 231.169 33.6118 231.821 32.9596C232.534 32.3074 232.928 31.3367 232.928 30.366C232.928 28.288 231.244 26.665 229.227 26.665C228.181 26.665 227.271 27.0594 226.633 27.7116C225.921 28.4245 225.526 29.3346 225.526 30.3811C225.526 32.3984 227.21 34.082 229.227 34.082L229.212 34.0669Z\" fill=\"#FFE200\"><\/path><path d=\"M220.036 32.5803C221.006 32.5803 221.916 32.1859 222.569 31.5337C223.221 30.8208 223.676 29.9108 223.676 28.94C223.676 26.9227 221.992 25.2998 220.036 25.2998C218.989 25.2998 218.079 25.6942 217.442 26.3464C216.79 27.0593 216.335 27.9693 216.335 28.9552C216.335 30.9725 218.018 32.5955 220.036 32.5955V32.5803Z\" fill=\"#FFE200\"><\/path><path d=\"M211.39 31.5336C213.271 31.5336 214.833 29.9713 214.833 28.0905C214.833 26.2097 213.271 24.6475 211.39 24.6475C209.509 24.6475 207.886 26.2097 207.886 28.0905C207.886 29.9713 209.448 31.5336 211.39 31.5336Z\" fill=\"#FFE200\"><\/path><path d=\"M276.747 47.1412C277.855 47.1412 278.886 46.6862 279.614 45.9126H279.675C280.388 45.1998 280.843 44.1532 280.843 43.046C280.843 40.7708 279.023 38.9507 276.747 38.9507C275.64 38.9507 274.609 39.4057 273.881 40.1186C273.107 40.8921 272.652 41.878 272.652 43.046C272.652 45.2604 274.472 47.1412 276.747 47.1412Z\" fill=\"#FFE200\"><\/path><path d=\"M286.106 48.9005C287.213 48.9005 288.245 48.3848 288.973 47.6719C289.746 46.959 290.201 45.9125 290.201 44.8052C290.201 42.5301 288.32 40.71 286.106 40.71C284.938 40.71 283.967 41.165 283.179 41.8779C282.466 42.6514 282.011 43.6373 282.011 44.8052C282.011 47.0197 283.831 48.9005 286.106 48.9005Z\" fill=\"#FFE200\"><\/path><path d=\"M296.056 52.2831C297.36 52.2831 298.589 51.6915 299.438 50.8573C300.288 50.0079 300.803 48.84 300.803 47.5356C300.803 44.9419 298.665 42.7881 296.056 42.7881C294.751 42.7881 293.584 43.3038 292.734 44.1532C291.885 45.0632 291.308 46.2311 291.308 47.5356C291.308 50.1292 293.447 52.2831 296.056 52.2831Z\" fill=\"#FFE200\"><\/path><path d=\"M305.869 57.8642C307.235 57.8642 308.463 57.2726 309.388 56.3626C310.314 55.4525 310.89 54.2239 310.89 52.8588C310.89 50.1287 308.615 47.8535 305.885 47.8535C304.52 47.8535 303.291 48.4451 302.366 49.3551C301.456 50.2652 300.864 51.4938 300.864 52.874C300.864 55.6042 303.139 57.8793 305.869 57.8793V57.8642Z\" fill=\"#FFE200\"><\/path><path d=\"M309.054 62.0354C309.054 64.9021 311.39 67.2379 314.196 67.2379C317.002 67.2379 319.399 64.9021 319.399 62.0354C319.399 59.1687 317.063 56.8936 314.196 56.8936C311.33 56.8936 309.054 59.2294 309.054 62.0354Z\" fill=\"#FFE200\"><\/path><path d=\"M313.878 73.8056C313.878 76.5358 316.092 78.811 318.883 78.811C321.674 78.811 323.828 76.5358 323.828 73.8056C323.828 71.0754 321.613 68.8003 318.883 68.8003C316.153 68.8003 313.878 71.0754 313.878 73.8056Z\" fill=\"#FFE200\"><\/path><path d=\"M322.842 85.4397C322.842 83.028 320.885 81.0107 318.489 81.0107C316.092 81.0107 314.06 83.028 314.06 85.4397C314.06 87.8514 316.077 89.8687 318.489 89.8687C320.901 89.8687 322.842 87.8514 322.842 85.4397Z\" fill=\"#FFE200\"><\/path><path d=\"M319.46 94.9346C319.46 92.8566 317.776 91.0972 315.622 91.0972C313.468 91.0972 311.785 92.8566 311.785 94.9346C311.785 97.0126 313.544 98.772 315.622 98.772C317.7 98.772 319.46 97.0884 319.46 94.9346Z\" fill=\"#FFE200\"><\/path><path d=\"M311.663 107.357C313.802 107.357 315.562 105.598 315.562 103.52C315.562 101.442 313.802 99.6216 311.663 99.6216C309.525 99.6216 307.826 101.381 307.826 103.52C307.826 105.658 309.585 107.357 311.663 107.357Z\" fill=\"#FFE200\"><\/path><path d=\"M272.258 64.7055C271.864 68.4064 270.953 71.986 269.528 75.2319C267.965 78.7356 266.145 82.1938 264.067 85.3032C262.111 88.2912 259.911 91.0214 257.697 93.0994C257.303 93.5544 257.045 93.8729 257.105 94.2673C257.166 94.7223 257.5 95.3139 258.152 96.1481C258.349 96.3453 258.546 96.5425 258.743 96.6638C259.456 97.1188 260.306 96.9823 261.276 96.4059C262.384 95.6931 263.552 94.4493 264.72 92.9629C267.192 89.7777 269.664 85.288 271.484 81.3293C273.82 76.3846 275.064 72.0922 275.64 67.6784C276.232 62.6124 275.959 57.5312 275.64 52.4652C275.443 50.3266 275.322 47.5812 273.107 47.2627C272.516 47.202 272.258 47.7784 272.137 48.5671C272 49.6137 272.137 50.9788 272.273 51.8888C272.728 56.1206 272.789 60.4737 272.273 64.7055H272.258Z\" fill=\"#FFE200\"><\/path><path d=\"M258.152 44.6082C257.56 43.956 256.923 43.501 256.195 43.501C254.633 43.5616 254.436 44.4717 254.314 45.3818C254.117 46.7469 254.967 47.8541 255.361 49.2799C256.468 53.0566 256.923 56.7575 256.787 60.4584C256.59 64.1593 255.877 67.7996 254.572 71.455C253.859 73.533 252.949 75.3531 251.903 77.1125C250.796 78.872 249.628 80.5556 248.46 82.2544C247.352 83.756 247.034 84.666 247.231 85.1211C247.428 85.5761 248.081 85.834 249.051 86.0918C251.842 86.744 252.949 84.8632 254.117 82.8459C254.436 82.3302 254.769 81.7387 255.164 81.1623C258.743 75.8991 260.821 70.4994 261.595 65.0997C262.444 59.3057 261.853 53.5268 260.033 48.0664C259.714 47.0199 259.062 45.5941 258.152 44.6234V44.6082Z\" fill=\"#FFE200\"><\/path><path d=\"M130.637 89.7318C132.594 89.7318 134.156 88.1088 134.156 86.1522C134.156 84.1956 132.594 82.6333 130.637 82.6333C128.681 82.6333 127.058 84.1956 127.058 86.1522C127.058 87.1229 127.452 88.033 128.104 88.6852C128.756 89.3374 129.666 89.7318 130.637 89.7318Z\" fill=\"#FFE200\"><\/path><path d=\"M121.597 72.6985C123.736 72.6985 125.495 70.9391 125.495 68.8004C125.495 67.7539 125.04 66.7831 124.327 66.0703C123.615 65.3574 122.644 64.9023 121.597 64.9023C119.459 64.9023 117.699 66.6618 117.699 68.8004C117.699 69.9077 118.154 70.8784 118.867 71.5913C119.519 72.2435 120.49 72.6985 121.597 72.6985Z\" fill=\"#FFE200\"><\/path><path d=\"M125.374 81.6632C127.452 81.6632 129.151 79.9796 129.151 77.9623C129.151 76.9157 128.757 75.945 128.044 75.2928C127.391 74.5799 126.421 74.1855 125.374 74.1855C123.357 74.1855 121.673 75.8692 121.673 77.9623C121.673 79.0089 122.068 79.9189 122.78 80.556C123.433 81.2689 124.343 81.6632 125.374 81.6632Z\" fill=\"#FFE200\"><\/path><path d=\"M124.722 59.4268C124.722 58.3802 124.328 57.4095 123.615 56.6966C122.902 55.9837 121.931 55.5894 120.885 55.5894C118.746 55.5894 116.986 57.273 116.986 59.4268C116.986 60.534 117.381 61.5047 118.094 62.2176C118.807 62.8698 119.777 63.3249 120.885 63.3249C122.963 63.3249 124.722 61.5654 124.722 59.4268Z\" fill=\"#FFE200\"><\/path><path d=\"M121.597 45.5786C119.383 45.5786 117.623 47.3381 117.623 49.5525C117.623 50.6598 118.018 51.6305 118.791 52.3434C119.504 53.0563 120.475 53.5113 121.582 53.5113C123.797 53.5113 125.541 51.7519 125.541 49.5374C125.541 48.4301 125.086 47.4594 124.373 46.7465C123.66 46.0336 122.689 45.5786 121.582 45.5786H121.597Z\" fill=\"#FFE200\"><\/path><path d=\"M120.687 43.3041C122.826 43.3041 124.585 41.5447 124.585 39.3454C124.585 37.146 122.826 35.4473 120.687 35.4473C118.549 35.4473 116.713 37.2067 116.713 39.3454C116.713 41.484 118.473 43.3041 120.687 43.3041Z\" fill=\"#FFE200\"><\/path><path d=\"M130.562 40.5133C132.776 40.5133 134.52 38.6932 134.52 36.5394C134.52 34.3856 132.761 32.5654 130.562 32.5654C128.362 32.5654 126.663 34.3856 126.663 36.5394C126.663 38.6932 128.423 40.5133 130.562 40.5133Z\" fill=\"#FFE200\"><\/path><path d=\"M139.48 36.9938C141.619 36.9938 143.378 35.2344 143.378 33.0957C143.378 32.0492 142.923 31.0784 142.21 30.3655C141.497 29.6527 140.527 29.2583 139.48 29.2583C137.341 29.2583 135.582 30.9419 135.582 33.0957C135.582 34.203 136.037 35.1737 136.75 35.8259C137.463 36.5388 138.434 36.9938 139.48 36.9938Z\" fill=\"#FFE200\"><\/path><path d=\"M149.491 35.4321C151.508 35.4321 153.192 33.7485 153.192 31.7312C153.192 30.6846 152.737 29.7746 152.084 29.0617C151.432 28.4095 150.461 28.0151 149.491 28.0151C147.413 28.0151 145.79 29.6381 145.79 31.716C145.79 32.6868 146.184 33.5968 146.897 34.3249C147.549 34.9771 148.459 35.4321 149.491 35.4321Z\" fill=\"#FFE200\"><\/path><path d=\"M158.849 34.0664C160.866 34.0664 162.55 32.3828 162.55 30.3655C162.55 29.3189 162.156 28.4089 161.443 27.696C160.791 27.0438 159.881 26.6494 158.849 26.6494C156.832 26.6494 155.148 28.2724 155.148 30.3503C155.148 31.3211 155.543 32.307 156.255 32.944C156.908 33.5962 157.818 34.0512 158.849 34.0512V34.0664Z\" fill=\"#FFE200\"><\/path><path d=\"M168.026 32.5798C170.043 32.5798 171.727 30.9569 171.727 28.9396C171.727 27.9689 171.272 27.0588 170.619 26.3307C169.967 25.6785 169.057 25.2842 168.01 25.2842C166.054 25.2842 164.37 26.9071 164.37 28.9244C164.37 29.8952 164.825 30.8052 165.477 31.5181C166.13 32.1703 167.04 32.5647 168.01 32.5647L168.026 32.5798Z\" fill=\"#FFE200\"><\/path><path d=\"M176.671 31.5336C178.628 31.5336 180.19 29.9713 180.19 28.0905C180.19 26.2097 178.628 24.6475 176.671 24.6475C174.714 24.6475 173.228 26.2097 173.228 28.0905C173.228 29.9713 174.79 31.5336 176.671 31.5336Z\" fill=\"#FFE200\"><\/path><path d=\"M108.462 45.9126C109.175 46.6862 110.222 47.1412 111.329 47.1412C113.604 47.1412 115.424 45.2604 115.424 43.046C115.424 41.878 114.969 40.9073 114.195 40.1186C113.483 39.4057 112.436 38.9507 111.329 38.9507C109.054 38.9507 107.234 40.7708 107.234 43.046C107.234 44.1532 107.689 45.1846 108.401 45.9126H108.462Z\" fill=\"#FFE200\"><\/path><path d=\"M101.955 48.9005C104.23 48.9005 106.05 47.0197 106.05 44.8052C106.05 43.6373 105.595 42.6666 104.882 41.8779C104.109 41.165 103.123 40.71 101.955 40.71C99.7407 40.71 97.8599 42.5301 97.8599 44.8052C97.8599 45.9125 98.3149 46.9439 99.0884 47.6719C99.8013 48.3848 100.848 48.9005 101.955 48.9005Z\" fill=\"#FFE200\"><\/path><path d=\"M92.0052 52.2831C94.5988 52.2831 96.7527 50.1444 96.7527 47.5356C96.7527 46.2311 96.1611 45.0632 95.3269 44.1532C94.4775 43.3038 93.3096 42.7881 92.0052 42.7881C89.4115 42.7881 87.2577 44.9267 87.2577 47.5356C87.2577 48.84 87.7734 50.0079 88.6228 50.8573C89.4722 51.7067 90.7008 52.2831 92.0052 52.2831Z\" fill=\"#FFE200\"><\/path><path d=\"M82.1918 57.8647C84.9219 57.8647 87.1971 55.5895 87.1971 52.8594C87.1971 51.4943 86.6056 50.2505 85.6955 49.3405C84.7854 48.4304 83.5569 47.8389 82.1766 47.8389C79.4464 47.8389 77.1713 50.114 77.1713 52.8442C77.1713 54.2093 77.7628 55.4379 78.6729 56.3479C79.5829 57.258 80.8115 57.8495 82.1766 57.8495L82.1918 57.8647Z\" fill=\"#FFE200\"><\/path><path d=\"M73.8646 67.2379C76.6555 67.2379 79.0065 64.9021 79.0065 62.0354C79.0065 59.1687 76.6706 56.8936 73.8646 56.8936C71.0586 56.8936 68.6621 59.2294 68.6621 62.0354C68.6621 64.8414 70.9979 67.2379 73.8646 67.2379Z\" fill=\"#FFE200\"><\/path><path d=\"M69.1931 78.811C71.9839 78.811 74.1984 76.5358 74.1984 73.8056C74.1984 71.0754 71.9839 68.8003 69.1931 68.8003C66.4022 68.8003 64.2484 71.0754 64.2484 73.8056C64.2484 76.5358 66.4629 78.811 69.1931 78.811Z\" fill=\"#FFE200\"><\/path><path d=\"M74.0012 85.4397C74.0012 83.028 71.9839 81.0107 69.5722 81.0107C67.1606 81.0107 65.2191 83.028 65.2191 85.4397C65.2191 87.8514 67.1758 89.8687 69.5722 89.8687C71.9687 89.8687 74.0012 87.8514 74.0012 85.4397Z\" fill=\"#FFE200\"><\/path><path d=\"M72.439 98.772C74.517 98.772 76.2764 97.0884 76.2764 94.9346C76.2764 92.7808 74.517 91.0972 72.439 91.0972C70.361 91.0972 68.6016 92.8566 68.6016 94.9346C68.6016 97.0126 70.2852 98.772 72.439 98.772Z\" fill=\"#FFE200\"><\/path><path d=\"M72.4995 103.52C72.4995 105.598 74.259 107.357 76.3976 107.357C78.5362 107.357 80.235 105.598 80.235 103.52C80.235 101.442 78.4756 99.6216 76.3976 99.6216C74.3196 99.6216 72.4995 101.381 72.4995 103.52Z\" fill=\"#FFE200\"><\/path><path d=\"M112.421 52.4797C112.102 57.5457 111.829 62.6269 112.421 67.6929C113.012 72.1219 114.241 76.3992 116.577 81.3438C118.397 85.3026 120.869 89.7922 123.342 92.9774C124.51 94.479 125.677 95.7076 126.785 96.4205C127.755 97.012 128.605 97.1334 129.318 96.6783C129.515 96.5418 129.712 96.3598 129.909 96.1626C130.561 95.3133 130.88 94.7369 130.956 94.2819C131.016 93.8875 130.759 93.569 130.364 93.1139C128.15 91.036 125.935 88.3058 123.994 85.3178C121.916 82.1932 120.096 78.7502 118.533 75.2464C117.108 72.0005 116.198 68.421 115.803 64.7201C115.288 60.4883 115.348 56.1352 115.803 51.9034C115.94 50.9933 116.061 49.6282 115.94 48.5816C115.803 47.8081 115.545 47.2166 114.969 47.2772C112.755 47.5958 112.633 50.3411 112.436 52.4797H112.421Z\" fill=\"#FFE200\"><\/path><path d=\"M132.912 81.1472C133.307 81.7387 133.625 82.3151 133.959 82.8308C135.127 84.8481 136.234 86.7289 139.025 86.0767C139.996 85.8188 140.648 85.561 140.845 85.1059C141.042 84.6509 140.709 83.7409 139.617 82.2393C138.449 80.5556 137.281 78.8569 136.234 77.0974C135.127 75.338 134.217 73.5178 133.504 71.4399C132.2 67.7996 131.487 64.1594 131.29 60.4433C131.153 56.7424 131.608 53.0263 132.715 49.2647C133.11 47.839 133.944 46.7317 133.762 45.3666C133.625 44.4566 133.443 43.5465 131.881 43.4858C131.168 43.4858 130.516 43.9409 129.924 44.5931C129.014 45.5638 128.362 47.0047 128.044 48.0361C126.224 53.4965 125.632 59.2906 126.481 65.0694C127.255 70.4691 129.348 75.8688 132.912 81.132V81.1472Z\" fill=\"#FFE200\"><\/path><path d=\"M78.4149 68.4059C73.8039 74.6549 74.259 82.6483 76.2004 89.7923C77.884 95.7683 80.9479 101.502 84.6488 106.765C85.0432 107.281 85.5589 107.478 86.1504 107.356C87.197 107.099 88.2891 107.038 89.3356 107.159C90.185 107.296 90.3822 106.386 89.9878 105.794C87.652 102.67 85.5589 99.2872 83.9359 95.7835C81.9793 91.6882 80.69 87.3958 80.2957 83.0427C79.6435 75.3072 82.5102 67.8295 87.7734 61.6562C84.5275 63.082 81.0086 64.8415 78.4149 68.421V68.4059Z\" fill=\"#FFE200\"><\/path><path d=\"M298.134 54.9526C297.224 54.4369 296.314 53.9818 295.343 53.5268C293.978 52.8746 292.021 54.4369 293.523 55.4834C294.691 56.3328 295.798 57.2429 296.905 58.2136C298.407 59.5787 301.258 56.7879 298.134 54.9677V54.9526Z\" fill=\"#FFE200\"><\/path><path d=\"M304.11 95.7842C301.896 100.592 298.771 105.082 295.525 109.117C294.297 110.618 293.902 112.241 294.16 113.409C294.357 114.001 294.752 114.516 295.389 114.577C296.299 114.577 297.603 113.925 299.09 112.165C304.747 105.598 309.555 97.9228 311.83 89.7929C313.651 83.0888 313.711 76.2027 310.92 69.4986C309.04 65.009 306.309 61.3687 303.048 58.4413C301.168 56.8791 299.014 60.125 300.318 61.6872C305.581 67.8605 308.387 75.3381 307.735 83.013C307.341 87.3661 306.052 91.6586 304.095 95.7538L304.11 95.7842Z\" fill=\"#FFE200\"><\/path><path d=\"M194.038 459.52C274.533 459.52 340.209 393.844 340.209 313.288C340.209 232.733 274.533 167.178 194.038 167.178C113.543 167.178 47.8521 232.854 47.8521 313.288C47.8521 393.723 113.528 459.52 194.023 459.52H194.038Z\" fill=\"#ED1B24\"><\/path><path d=\"M194.038 113.924C193.977 114.637 191.702 117.504 191.05 117.822H193.067C193.522 117.504 193.841 117.17 194.038 116.715C194.235 117.17 194.554 117.489 195.009 117.822H197.026C196.374 117.504 194.099 114.637 194.038 113.924Z\" fill=\"black\"><\/path><path d=\"M194.038 103.064C193.977 103.717 191.702 106.052 191.05 106.31H193.067C193.522 106.052 193.841 105.795 194.038 105.4C194.235 105.795 194.554 106.052 195.009 106.31H197.026C196.374 106.052 194.099 103.717 194.038 103.064Z\" fill=\"black\"><\/path><path d=\"M156.255 119.127L155.345 119.9C151.189 123.677 146.048 124.587 139.935 122.827L138.706 122.433L139.753 121.72C142.089 119.961 144.561 118.929 147.094 118.535C149.627 118.08 152.297 118.217 155.027 118.854L156.255 119.111V119.127Z\" fill=\"black\"><\/path><path d=\"M169.846 104.884C169.846 105.4 167.828 107.675 167.252 108.009L169.269 107.751C169.664 107.493 169.921 107.235 170.179 106.902C170.437 107.159 170.832 107.417 171.226 107.554L173.243 107.357C172.591 107.22 170.058 105.4 169.861 104.884H169.846Z\" fill=\"black\"><\/path><path d=\"M144.607 107.873C144.667 108.464 142.923 111.118 142.392 111.513L144.349 111.058C144.743 110.739 145.001 110.406 145.123 110.011C145.441 110.269 145.835 110.466 146.29 110.603L148.247 110.148C147.595 110.087 144.804 108.388 144.607 107.873Z\" fill=\"black\"><\/path><path d=\"M117.563 114.956C117.623 115.547 116.137 118.338 115.606 118.732L117.487 118.141C117.805 117.822 118.078 117.489 118.2 117.094C118.518 117.352 118.913 117.489 119.368 117.61L121.324 117.018C120.672 116.958 117.805 115.456 117.548 114.94L117.563 114.956Z\" fill=\"black\"><\/path><path d=\"M153.449 119.839C151.311 119.445 149.293 119.445 147.337 119.779C145.32 120.097 143.439 120.825 141.619 121.993C146.169 123.04 150.143 122.312 153.449 119.855V119.839Z\" fill=\"#ED1B24\"><\/path><path d=\"M231.806 119.127L232.716 119.9C236.948 123.677 242.013 124.587 248.126 122.827L249.355 122.433L248.308 121.72C245.972 119.961 243.5 118.929 240.967 118.535C238.434 118.08 235.764 118.217 233.034 118.854L231.806 119.111V119.127Z\" fill=\"black\"><\/path><path d=\"M218.215 104.884C218.215 105.4 220.233 107.675 220.809 108.009L218.792 107.751C218.397 107.493 218.14 107.235 217.882 106.902C217.624 107.159 217.23 107.417 216.835 107.554L214.818 107.357C215.47 107.22 218.003 105.4 218.2 104.884H218.215Z\" fill=\"black\"><\/path><path d=\"M243.454 107.873C243.394 108.464 245.138 111.118 245.669 111.513L243.712 111.058C243.394 110.739 243.121 110.406 242.939 110.011C242.62 110.269 242.226 110.466 241.771 110.603L239.814 110.148C240.466 110.087 243.257 108.388 243.454 107.873Z\" fill=\"black\"><\/path><path d=\"M270.498 114.956C270.438 115.547 271.924 118.338 272.455 118.732L270.574 118.141C270.256 117.822 269.983 117.489 269.861 117.094C269.543 117.352 269.148 117.489 268.693 117.61L266.737 117.018C267.389 116.958 270.256 115.456 270.514 114.94L270.498 114.956Z\" fill=\"black\"><\/path><path d=\"M234.612 119.839C236.75 119.445 238.768 119.445 240.724 119.779C242.741 120.097 244.622 120.825 246.442 121.993C241.892 123.04 237.918 122.312 234.612 119.855V119.839Z\" fill=\"#ED1B24\"><\/path><path d=\"M247.095 93.4331C246.898 99.1513 247.034 97.6649 252.1 100.319C249.688 99.6064 247.292 99.1513 245.138 100.577C243.97 98.2413 241.695 97.4525 239.223 96.8762C244.941 97.0733 244.365 98.4384 247.095 93.4331Z\" fill=\"black\"><\/path><path d=\"M140.967 93.4331C141.164 99.1513 141.027 97.6649 135.961 100.319C138.373 99.6064 140.769 99.1513 142.923 100.577C144.091 98.2413 146.366 97.4525 148.839 96.8762C143.12 97.0733 143.697 98.4384 140.967 93.4331Z\" fill=\"black\"><\/path><path d=\"M148.581 63.0675C146.048 66.1921 142.074 66.7078 140.845 70.4845C140.254 72.1681 141.695 73.5484 143.06 73.9276C144.622 74.4433 145.396 72.1075 147.094 71.5159C146.381 72.3653 145.866 73.5332 146.321 74.1854C146.836 73.4119 147.291 72.881 148.596 72.5625C146.518 75.5505 147.428 76.0814 148.99 75.8842C149.9 75.8235 150.492 74.9742 151.584 74.4585C151.523 74.7163 148.657 77.3858 150.992 77.583C151.508 77.6437 153.207 76.8701 153.662 76.4151C153.525 77.4617 151.902 77.8408 153.465 78.6902C154.314 79.2059 155.346 78.2352 156.134 77.9167C154.253 80.5104 155.164 81.0412 156.331 80.6469C157.181 80.3283 157.894 79.4183 159.259 79.4183C158.485 80.0705 157.833 80.1918 157.833 81.0412C157.894 83.7714 160.427 83.5742 161.868 83.3164C160.821 84.0899 161.868 87.2145 162.323 87.2903C164.992 87.6088 165.644 86.8353 168.117 86.1224C171.696 85.0151 172.409 80.207 172.348 74.0338C172.288 68.6341 171.636 63.113 170.726 61.4143C169.618 61.0957 167.025 62.5822 167.025 64.1444C166.827 63.4316 166.372 62.84 165.978 62.84C165.129 62.9007 164.294 64.1444 163.566 64.463C160.958 65.6309 163.172 62.1271 163.172 61.93C159.532 61.7934 159.532 66.9353 159.532 61.6114C156.999 61.2171 155.3 66.4196 155.497 61.8693C153.874 60.4435 152.631 61.8086 151.66 62.9765C150.947 63.8866 150.295 64.6601 150.234 64.2809C150.098 63.5074 150.553 62.1423 150.431 61.7479C150.173 61.0351 148.808 62.8552 148.611 63.113L148.581 63.0675Z\" fill=\"#ED1B24\"><\/path><path d=\"M220.233 59.0472C220.551 61.383 220.233 62.4903 219.914 63.734C218.231 69.1337 220.688 74.1997 220.506 79.6601C222.584 80.8887 222.387 78.8107 223.039 77.1271C224.267 71.7274 229.348 85.4541 235.127 79.6601C237.008 77.1878 240.588 74.5182 244.289 74.8519C249.173 77.84 247.019 63.9919 245.654 63.279C245.138 63.0211 244.031 63.6734 244.031 63.4762C243.894 62.3083 243.439 61.5196 242.802 61.5196C241.634 61.2617 241.179 62.1111 240.921 63.3397C240.785 64.1891 239.875 63.5975 239.951 61.7774C239.298 62.3689 238.843 63.5975 238.586 63.7947C238.07 64.1891 238.722 63.7947 238.191 62.2324C237.736 60.7308 237.145 59.8966 236.568 62.4296C236.174 64.0525 234.232 66.7221 231.229 64.9626C229.864 64.1132 229.606 60.0179 227.453 59.5629C226.345 59.3657 227.195 60.7308 226.285 60.6095C226.027 60.5488 225.83 59.8359 225.314 59.4416C224.404 58.7894 225.708 59.7601 223.099 56.3777C220.824 53.5869 219.975 57.5456 220.233 59.0472Z\" fill=\"#ED1B24\"><\/path><path d=\"M273.881 97.6042C272.516 97.7407 271.606 98.3777 271.272 99.6215C270.559 102.488 275.367 101.699 278.234 101.305C282.845 100.714 282.466 104.627 285.12 103.717C286.682 103.201 285.833 97.0127 287.85 95.0712C288.897 94.1005 291.354 93.0539 291.748 92.0073C292.522 89.9293 291.035 88.1092 288.047 87.3205C286.819 87.0627 286.622 85.7582 284.801 85.8947C282.39 86.0313 281.616 87.9727 280.448 89.7928C279.538 91.1579 278.568 92.523 276.929 93.1752C274.912 93.9488 274.715 96.1026 273.881 97.6042Z\" fill=\"#ED1B24\"><\/path><path d=\"M110.934 94.0852C113.801 97.9226 117.639 100.911 120.096 100.713C122.113 100.395 123.16 97.9833 121.977 95.3744C119.504 89.7169 114.817 88.0333 114.696 81.587C110.995 79.9034 106.824 81.1927 102.41 83.4071C97.0105 87.3811 91.808 89.9747 82.6467 89.004C83.8146 93.0993 85.6954 96.9974 87.9099 100.577C90.4429 100.638 92.263 99.5304 92.6574 97.3917C92.9152 96.2845 93.8253 94.2065 95.5848 94.2065C94.3562 95.1166 93.3703 97.4524 94.614 97.9833C96.7527 98.954 97.8599 92.9173 99.8165 92.4622C99.3008 93.6302 97.0864 96.5575 99.4222 96.5575C101.242 96.239 101.106 92.9173 103.002 93.1145C103.26 94.161 102.744 96.6334 104.23 96.5575C106.308 96.0418 105.656 93.0538 106.961 93.0538C106.642 96.0418 110.009 95.5261 110.934 94.1004V94.0852Z\" fill=\"#ED1B24\"><\/path><path d=\"M235.977 135.447C237.539 136.221 240.269 136.357 242.408 136.297C246.443 136.16 244.031 138.83 246.564 138.83C250.72 138.83 253.844 143.714 250.007 145.595C249.097 146.05 247.535 145.989 245.851 145.989C244.349 146.444 248.9 148.325 244.622 148.977C242.999 149.235 238.313 147.87 238.313 150.736C238.313 152.359 233.429 153.33 232.064 153.527C219.899 155.211 206.9 156.06 194.023 156.06C185.635 156.06 177.187 155.666 168.981 155.014C166.19 154.756 166.115 152.541 163.384 151.829C161.883 151.434 159.941 151.631 157.924 151.434C153.434 150.979 153.95 147.657 149.855 148.31C146.215 148.901 142.635 146.489 143.227 144.669C143.621 143.623 145.896 143.046 149.278 142.713C146.867 141.742 147.519 142.121 144.925 142.061C141.877 142 141.088 141.469 141.937 140.559C142.65 139.846 147.276 139.588 144.212 138.997C139.601 138.087 147.731 135.933 148.566 135.554C151.887 134.128 154.739 132.035 158.379 131.458C170.468 129.578 182.238 128.667 194.008 128.667C203.821 128.667 213.65 129.32 223.6 130.624C227.953 131.14 232.124 133.551 235.962 135.432L235.977 135.447Z\" fill=\"#ED1B24\"><\/path><path d=\"M227.847 190.264C221.734 188.58 215.485 187.336 209.054 186.563C208.144 186.426 207.173 186.365 206.263 186.244V229.032C202.305 228.441 198.194 228.122 194.038 228.122C189.882 228.122 185.787 228.441 181.813 229.032V186.244C117.184 192.493 66.3264 247.173 66.3264 313.304C66.3264 379.435 120.035 437.239 187.213 440.879V427.289C127.452 423.709 79.856 373.899 79.856 313.304C79.856 259.398 117.639 214.077 168.026 202.185V232.233C145.077 239.65 126.284 256.486 116.395 278.206L128.484 284.258C131.153 278.342 134.535 272.806 138.631 267.877V358.852C130.956 349.418 125.556 338.103 123.357 325.62L110.161 328.411C117.32 368.211 152.236 398.637 194.038 398.637C199.104 398.637 204.185 398.182 209.054 397.272C215.622 396.104 221.932 394.147 227.847 391.614C258.076 378.419 279.281 348.311 279.281 313.319C279.281 287.504 267.647 264.297 249.431 248.689V213.637C284.407 233.203 308.205 270.531 308.205 313.319C308.205 364.495 274.321 407.935 227.832 422.435C221.78 424.316 215.47 425.681 209.039 426.53C206.309 426.925 203.639 427.183 200.849 427.304V440.894C203.639 440.697 206.309 440.5 209.039 440.181C215.47 439.408 221.719 438.164 227.832 436.48C281.859 421.586 321.72 371.972 321.72 313.319C321.72 254.666 281.859 205.189 227.832 190.294L227.847 190.264ZM220.036 202.155C222.705 202.807 225.299 203.52 227.832 204.294C230.501 205.143 233.095 206.053 235.628 207.085V239.012C233.095 237.587 230.486 236.282 227.832 235.114C225.299 234.007 222.69 233.036 220.036 232.187V202.14V202.155ZM265.751 313.289C265.751 340.606 250.341 364.404 227.847 376.553C221.992 379.677 215.683 382.013 209.054 383.439C204.17 384.486 199.165 385.062 194.038 385.062C178.567 385.062 164.188 380.057 152.418 371.669V255.014C157.226 251.571 162.429 248.705 168.026 246.49V303.976H181.813V242.653C185.787 242.001 189.882 241.606 194.038 241.606C198.194 241.606 202.289 242.001 206.263 242.653V352.543H220.051V246.49C222.72 247.597 225.314 248.765 227.847 250.13C230.577 251.632 233.186 253.255 235.643 255.014V304.309H249.431V267.831C259.638 280.253 265.751 296.058 265.751 313.289Z\" fill=\"#FFE200\"><\/path><path d=\"M54.2377 416.277C54.8899 418.75 55.8606 420.888 57.165 422.708C58.4694 424.468 60.153 425.894 62.231 426.864C63.9146 427.259 65.6134 427.774 67.2363 428.366C71.9232 430.247 76.2763 433.174 80.8873 437.072C79.3857 435.191 77.8992 433.371 76.337 431.612C73.7433 428.624 70.9373 425.696 68.2677 422.83C67.9492 422.511 67.6762 422.178 67.4184 421.859C65.9926 421.601 64.6882 421.085 63.3231 420.433C61.958 419.72 60.5929 418.871 59.1671 417.9C58.4543 417.385 59.1671 416.338 59.88 416.854C61.2451 417.764 62.5495 418.613 63.9146 419.265C64.5668 419.584 65.219 419.918 65.9319 420.115C65.3404 419.523 64.8854 418.886 64.3697 418.295C63.2017 416.732 62.1552 415.307 61.1844 413.805C60.6687 413.092 61.7001 412.379 62.231 413.092C63.2017 414.518 64.2483 416.019 65.4162 417.521C66.5841 419.023 67.8886 420.509 69.193 421.95C71.8625 424.817 74.532 427.668 77.2622 430.793C79.0216 432.81 80.7659 434.827 82.404 436.966C81.0996 433.72 80.1289 430.262 79.3402 426.622C78.6273 424.544 77.4594 422.329 76.0184 420.115C71.6653 413.229 67.0392 407.571 59.8345 403.794C55.7392 401.58 50.9918 400.154 45.3949 399.562C47.215 401.777 48.838 404.173 50.2789 406.782C51.9625 409.831 53.3428 413.092 54.2528 416.277H54.2377Z\" fill=\"#00844B\"><\/path><path d=\"M38.8879 243.517C38.7514 244.29 38.5694 245.018 38.175 245.792C38.7666 245.534 39.2823 245.473 39.798 245.473C39.4795 244.821 39.1458 244.169 38.8879 243.517Z\" fill=\"#00844B\"><\/path><path d=\"M36.6128 258.669C35.5055 259.579 34.6561 260.626 34.0039 261.794C33.291 262.962 32.836 264.266 32.5023 265.631C33.3517 269.332 33.8067 273.109 33.9281 276.886C34.4438 274.474 35.1567 272.199 35.9454 269.924C36.2639 269.074 37.5077 269.469 37.174 270.379C36.2639 272.851 35.4903 275.521 34.9595 278.114C36.3246 275.521 37.9475 273.367 39.5705 271.486C40.2833 270.713 41.0721 269.924 41.7849 269.211C43.7416 267.33 45.7589 265.829 47.761 264.463C46.1381 260.11 44.3786 255.879 42.5585 251.723C42.3006 252.117 42.0428 252.496 41.7849 252.83C40.4198 254.908 38.7969 256.864 36.5824 258.685L36.6128 258.669ZM40.9659 262.234C41.2844 262.097 41.5574 261.915 41.8153 261.779C42.331 261.324 42.7253 260.808 43.1804 260.217C43.4989 260.535 43.6354 261.187 43.6354 261.9C43.6354 264.115 42.9832 264.433 41.8153 264.949C41.3602 265.146 40.7687 265.404 40.1317 265.798C40.071 264.297 39.6766 262.674 40.981 262.219L40.9659 262.234Z\" fill=\"#00844B\"><\/path><path d=\"M45.9105 428.123C46.9571 429.033 47.9278 429.943 48.8986 430.914C50.203 432.142 51.5681 433.583 52.9938 435.267C56.4976 439.498 62.1551 444.307 68.9199 445.611C73.1517 446.385 77.7626 445.869 82.5708 443.017C82.4343 442.76 82.2523 442.502 82.1158 442.244C82.0551 442.244 81.9186 442.183 81.8579 442.183C78.612 440.682 75.6847 439.392 72.6966 439.316H72.4995C71.8472 439.316 71.1344 439.377 70.4822 439.514C69.1171 439.771 67.9492 439.969 66.9026 440.105C65.856 440.166 64.946 440.166 64.1724 440.045C63.8539 439.984 63.5202 439.908 63.6567 439.271C63.7932 438.679 64.1117 438.679 64.3696 438.755C65.0825 438.892 65.8712 438.892 66.8419 438.816C67.6913 438.755 68.662 438.619 69.7693 438.361C69.0564 438.103 68.3435 437.845 67.6306 437.451C66.0684 436.738 64.3847 435.828 62.5646 434.66C62.3068 434.463 62.0489 434.266 62.3675 433.75C62.7618 433.234 63.0197 433.431 63.2775 433.553C65.037 434.721 66.6599 435.631 68.2222 436.344C69.7238 437.056 71.2102 437.572 72.6511 438.027C75.897 438.088 78.9609 439.453 82.4039 441.015C82.5405 441.076 82.6618 441.152 82.7983 441.152L83.1168 440.757C77.3986 435.555 72.3174 431.778 66.7357 429.639C60.1075 426.97 52.9483 426.97 45.9257 428.138L45.9105 428.123Z\" fill=\"#00844B\"><\/path><path d=\"M48.0492 394.299C46.7448 392.995 45.2584 391.705 43.6202 390.462C42.1186 390.204 40.6929 390.067 39.1913 390.265C38.3419 390.401 38.1447 389.157 39.0548 389.036C39.9648 388.899 40.8142 388.839 41.5271 388.899C41.2086 388.642 40.8749 388.384 40.5564 388.187C39.7828 387.595 38.9941 387.019 38.2206 386.503C36.719 386.184 35.1718 385.593 33.4731 384.88C31.8501 384.167 30.0907 383.318 28.2099 382.286C27.3605 381.892 27.952 380.785 28.8014 381.179C30.6822 382.15 32.381 383.06 34.0039 383.712C34.459 383.97 34.9747 384.167 35.4297 384.304C35.0353 384.046 34.6561 383.712 34.3225 383.394C32.2445 381.771 30.2879 380.148 28.2706 378.388C27.5577 377.797 28.4071 376.826 29.0441 377.418C31.1221 379.177 33.0787 380.8 35.096 382.423C37.1133 384.046 39.1913 385.669 41.2693 387.17C43.9994 389.051 46.5324 391.068 48.9441 393.344C50.6277 394.967 52.0686 396.665 53.1759 398.288C52.9787 395.695 52.1293 393.086 50.5822 390.492C48.3071 386.594 44.9853 383.272 41.5423 380.345C36.8555 376.31 31.7288 373.519 26.1319 371.502C21.2479 369.743 16.0606 368.711 10.6609 368.059L10.7216 368.12C13.4517 370.137 16.0606 372.018 18.2599 374.687C22.158 379.374 26.2533 383.727 30.5457 387.686C34.7775 391.584 39.252 395.103 43.9994 398.212C47.0481 398.41 49.8542 398.865 52.4478 399.578C51.3406 397.757 49.8542 395.998 48.0189 394.314L48.0492 394.299Z\" fill=\"#00844B\"><\/path><path d=\"M38.5544 412.06C37.8415 412.257 37.5078 412.773 37.8415 413.425C38.2965 414.199 39.4037 414.593 40.1773 414.396C40.8902 414.259 41.2239 413.683 40.8902 413.031C40.4958 412.257 39.3886 411.863 38.5544 412.06Z\" fill=\"#00844B\"><\/path><path d=\"M68.6016 398.925C69.6481 397.423 67.7522 395.224 66.6449 396.71C66.1899 397.363 66.2506 398.394 66.8421 398.986C67.3578 399.501 68.1465 399.501 68.6016 398.925Z\" fill=\"#00844B\"><\/path><path d=\"M33.0333 357.305C34.2012 358.989 35.3084 360.809 36.2792 362.826C37.0527 364.389 37.7049 366.012 38.3571 367.771C39.5857 364.252 40.7688 361.856 39.0094 358.079C37.3257 354.378 34.9747 350.859 31.926 348.068C28.8015 345.277 25.0399 343.184 20.611 341.956C21.8395 344.231 22.9468 346.506 23.9327 348.918C25.1006 351.784 26.0107 354.712 26.86 357.897C27.5123 360.627 27.8308 363.691 28.0886 366.74C28.2858 368.165 28.4071 369.606 28.6043 371.032C31.471 372.2 34.2619 373.626 36.8555 375.324C36.992 373.959 37.1134 372.655 37.3712 371.426C37.5078 370.577 37.7656 370.198 37.5078 369.348C36.7949 367.21 36.0062 365.253 35.0961 363.372C34.186 361.492 33.1395 359.671 31.9716 358.033C31.4558 357.32 32.4266 356.608 33.0181 357.32L33.0333 357.305Z\" fill=\"#00844B\"><\/path><path d=\"M50.203 387.61C50.4002 384.288 50.1423 381.179 49.5508 378.054C48.7773 374.353 47.4728 370.713 45.7134 366.936C44.409 364.145 42.9225 361.415 41.4816 358.685C41.2844 361.415 41.0266 364.343 39.8587 367.391C39.343 368.756 38.8879 370.182 38.6301 371.684C38.3722 373.11 38.175 374.55 38.175 376.113C39.6008 377.083 41.0417 378.191 42.4068 379.359C43.2562 380.071 44.0298 380.784 44.8185 381.497C44.8792 379.874 44.682 378.373 44.3028 376.947C43.8478 375.188 43.1349 373.504 42.1641 371.805C41.7091 371.032 42.8164 370.379 43.2714 371.214C44.2421 372.973 45.0915 374.732 45.5465 376.613C46.0622 378.494 46.1987 380.451 46.0016 382.665C47.6245 384.288 49.0654 385.911 50.2334 387.61H50.203Z\" fill=\"#00844B\"><\/path><path d=\"M45.1219 362.826C45.7135 363.994 46.2899 365.162 46.8814 366.406C48.565 370.107 49.8694 373.626 50.6581 377.205C50.7947 375.249 50.916 373.231 51.0525 371.35C51.2497 367.847 51.371 364.464 51.4469 361.143C51.4469 360.233 52.7513 360.233 52.7513 361.143C52.6906 364.525 52.5541 367.968 52.2963 371.411C52.1598 374.536 51.9019 377.721 51.6441 380.845C51.3862 383.636 51.644 386.503 51.3862 389.294C52.2356 390.659 53.0091 392.16 53.5248 393.723C54.4956 392.752 55.2084 391.25 55.7393 389.233C56.3915 386.821 56.7859 383.773 56.9072 380.33C57.1651 373.049 56.5129 366.284 55.345 359.52C53.6613 354.454 52.2204 349.251 51.1132 343.912C49.9453 345.535 48.9745 347.492 48.0645 349.888C46.7601 353.331 45.7893 357.684 45.1371 362.826H45.1219Z\" fill=\"#00844B\"><\/path><path d=\"M15.4084 331.232C18.3965 334.159 21.3845 337.147 23.4018 341.439C23.4018 341.5 23.4625 341.5 23.4625 341.576C26.1927 342.547 28.6043 343.912 30.743 345.474C29.3779 342.744 27.7549 339.953 25.9955 337.223C23.781 333.704 21.4452 330.261 19.1094 326.878C19.1094 326.878 19.1094 326.818 19.0487 326.818C17.5471 326.302 16.0607 325.513 14.5591 324.603C12.9968 323.633 11.4345 322.389 9.87224 321.024C9.22003 320.432 10.0088 319.461 10.7216 320.114C12.2232 321.342 13.7097 322.525 15.2719 323.496C16.182 324.088 17.0921 324.603 18.0021 324.998C17.4864 324.224 16.9555 323.375 16.3792 322.586C15.4691 321.282 14.4984 319.992 13.3911 318.749C12.7996 318.096 13.7097 317.247 14.3619 317.899C15.4691 319.204 16.5005 320.508 17.4106 321.797C20.7323 326.348 24.0389 331.747 27.1027 336.555C29.3779 340.196 31.4558 343.836 33.1546 347.476C33.6703 347.931 34.1254 348.447 34.5804 348.978C35.3539 348.068 35.0961 346.05 33.9282 342.926C31.9109 337.405 28.7257 331.808 25.859 326.666C23.326 322.176 19.5492 317.763 15.0596 313.925C10.9036 310.346 6.15616 307.358 1.40868 305.34C1.27217 308.328 2.06089 311.316 3.42598 314.38C4.92758 317.763 7.06622 321.145 9.53855 324.725C11.2222 327.197 13.3153 329.214 15.3933 331.232H15.4084Z\" fill=\"#00844B\"><\/path><path d=\"M41.6183 345.671C40.4504 345.611 39.7375 346.066 39.4796 346.642C38.7061 348.144 40.1925 349.691 41.6941 349.691C42.5435 349.752 43.1199 349.236 43.3777 348.584C43.6356 348.068 43.6356 347.416 43.4384 346.9C43.2412 346.248 42.589 345.671 41.6183 345.671Z\" fill=\"#00844B\"><\/path><path d=\"M16.7128 355.287C16.4549 355.151 16.1213 355.151 15.8027 355.151C15.287 355.212 14.832 355.348 14.4376 355.667C14.0433 355.924 13.7248 356.319 13.5883 356.713C13.5276 356.971 13.5276 357.168 13.5276 357.426C13.5883 358.533 14.2405 359.504 15.1505 360.156C16.0606 360.808 17.1678 361.127 18.2751 361.066C18.6694 359.641 18.7301 358.336 18.4722 357.365C18.2144 356.258 17.5622 355.545 16.7128 355.287Z\" fill=\"#00844B\"><\/path><path d=\"M20.8687 300.077C23.9933 305.734 26.3898 311.453 28.2099 317.307C29.6357 322.115 30.7429 326.999 31.5923 331.944C31.653 329.472 31.9108 327.136 32.2445 324.861V324.542C31.5923 314.789 30.1059 306.599 27.497 300.228C25.4797 295.087 22.3552 290.157 17.6077 287.093C16.8341 292.356 16.637 297.559 17.3498 302.761C18.0021 307.645 19.3671 312.454 21.5058 317.262C23.0074 320.583 25.2067 322.919 26.9662 326.105C28.1947 328.319 29.3778 330.397 30.3485 332.278C29.575 327.333 28.4678 322.525 26.9662 317.717C25.146 311.923 22.8102 306.265 19.7463 300.744C19.2913 299.971 20.4592 299.318 20.8536 300.092L20.8687 300.077Z\" fill=\"#00844B\"><\/path><path d=\"M47.8521 313.288C47.8521 311.726 47.8521 310.164 47.9128 308.601C47.655 306.645 47.1393 304.825 46.487 303.202C45.4405 300.472 43.954 298.257 42.1946 296.437C41.2845 299.228 40.3138 301.958 39.3279 304.628C38.16 307.873 36.9921 311.134 35.9455 314.244C33.8069 321.069 32.7603 328.031 32.821 335.251C32.8816 338.376 34.7776 341.106 35.6118 344.033C36.0669 339.999 36.6584 335.964 37.2954 332.066C38.069 327.379 38.9791 322.829 40.0256 318.339C39.8284 317.232 39.7071 316.064 39.6313 314.896C39.6313 313.728 39.6919 312.484 39.8284 311.195C39.965 310.285 41.1935 310.422 41.1329 311.332C40.9357 312.56 40.875 313.743 40.9357 314.911C40.9357 315.503 40.9964 316.079 41.0722 316.671C41.3907 316.352 41.7244 315.897 41.9823 315.442C42.4373 314.669 42.8316 313.758 43.1502 312.651C43.2867 312.393 43.3473 312.06 43.9996 312.257C44.5911 312.454 44.5153 312.773 44.3939 313.03C44.0754 314.198 43.6204 315.245 43.0895 316.094C42.5738 316.944 41.9823 317.657 41.33 318.233C40.2835 322.844 39.3127 327.591 38.5392 332.278C37.7656 336.889 37.1741 341.576 36.7191 346.46C37.8263 346.263 37.8263 344.898 38.1448 343.988C39.1156 341.257 40.2835 338.33 41.4666 335.403C44.1361 328.699 46.9269 321.676 47.837 316.352V313.303L47.8521 313.288Z\" fill=\"#00844B\"><\/path><path d=\"M16.0607 283.696C18.1387 286.684 21.0054 287.731 23.4019 290.582C21.9761 286.426 20.4745 282.255 18.5937 278.297C16.2579 273.231 13.4519 268.483 9.81166 264.448C9.61448 264.191 9.35663 263.933 9.87233 263.538C10.3274 263.083 10.5245 263.341 10.7217 263.599C14.4985 267.755 17.35 272.578 19.7617 277.781C20.8082 279.995 21.7183 282.21 22.6283 284.546C21.2633 279.282 20.4139 274.338 19.9588 269.651C18.7303 266.466 16.9101 263.675 14.6198 261.127C12.4053 258.715 9.81166 256.576 6.94497 254.756C6.8843 259.64 7.46067 264.57 9.02294 269.575C10.4487 274.262 12.7239 278.934 16.0456 283.681L16.0607 283.696Z\" fill=\"#00844B\"><\/path><path d=\"M27.315 295.663C27.7093 292.933 27.9065 290.142 28.0279 287.336C28.1644 283.635 28.0279 279.798 27.77 275.96C27.5122 272.578 25.6314 268.619 23.9326 264.964C23.2804 263.735 22.704 262.431 22.1731 261.263C22.0366 260.944 21.9153 260.671 22.4917 260.414C23.068 260.156 23.2045 260.474 23.341 260.732C23.7961 261.9 24.4483 263.144 25.0247 264.433C25.6769 265.798 26.3291 267.163 26.9054 268.528C26.7689 267.36 26.6476 266.253 26.5111 265.085C26.0561 262.355 25.5404 259.564 24.9488 256.758C24.8881 256.44 24.7516 256.106 25.4038 255.985C26.0561 255.924 26.1167 256.182 26.1774 256.5C26.7689 259.367 27.3453 262.158 27.7397 264.888C28.0582 267.3 28.3312 269.635 28.5132 271.971C28.6497 273.336 28.9076 274.58 28.9683 275.869C29.2261 279.707 29.3626 283.605 29.2261 287.382C29.1654 291.083 28.7711 294.799 28.1189 298.378C28.3767 298.894 28.5739 299.485 28.7711 300.001C29.7418 299.349 30.1968 297.21 30.849 293.949C31.0462 293.039 31.2434 291.993 31.4406 290.885C33.3214 282.498 33.0029 273.261 31.0462 264.934C29.3626 257.653 26.2381 250.888 21.5513 245.822C20.6412 252.981 20.3227 260.459 21.0962 268.574C21.9456 277.735 24.1601 286.911 27.2695 295.618L27.315 295.663Z\" fill=\"#00844B\"><\/path><path d=\"M6.4443 297.999C7.03584 297.999 7.49087 297.802 7.87006 297.483C8.18859 297.165 8.4616 296.71 8.4616 296.179C8.4616 295.648 8.20375 295.208 7.87006 294.875C7.4757 294.556 6.96 294.359 6.36846 294.359C5.85276 294.359 5.3219 294.556 4.9427 294.875C4.62418 295.193 4.427 295.648 4.427 296.179C4.427 296.71 4.62418 297.15 5.01854 297.483C5.33706 297.802 5.86793 297.999 6.4443 297.999Z\" fill=\"#00844B\"><\/path><path d=\"M38.4329 247.02C37.0678 247.612 35.6421 248.78 35.1112 249.296C33.3518 251.116 32.0625 252.739 31.2131 254.24C29.7115 256.713 30.1666 257.425 30.9553 259.837C31.4103 258.866 31.7288 257.759 32.0625 256.713C32.9726 253.785 34.5955 252.481 37.1285 250.539C37.3864 250.342 37.6442 250.084 37.8414 249.948C38.5543 249.432 39.343 250.403 38.6149 250.918C38.3571 251.176 38.0992 251.374 37.9021 251.51C35.5662 253.33 34.004 254.498 33.2911 257.031C33.0332 257.88 32.7754 258.791 32.4417 259.503C32.1839 260.277 31.8502 260.929 31.471 261.46C31.6075 261.976 31.7895 262.567 31.926 263.144C32.1839 262.431 32.5175 261.779 32.8967 261.126C33.6096 259.822 34.5804 258.715 35.8241 257.683C38.3571 255.666 40.0559 253.254 41.6182 250.858C41.2996 249.629 41.1025 247.673 40.1166 246.884C39.798 246.565 39.1458 246.687 38.4329 247.02Z\" fill=\"#00844B\"><\/path><path d=\"M40.5717 272.32C38.0387 275.187 35.6877 278.752 33.8676 283.499C33.8676 283.499 33.8069 283.56 33.8069 283.636C33.6097 286.169 33.2912 288.777 32.6997 291.25C32.9575 291.053 33.2154 290.734 33.549 290.476C34.3984 289.505 35.3085 288.398 35.6877 287.609C37.1135 285.334 38.2965 283.711 39.6616 281.755C39.6616 281.694 39.7981 281.497 40.511 280.526C41.0267 279.813 42.0733 280.526 41.5576 281.3C41.4211 281.436 41.2391 281.755 40.7082 282.468C39.3431 284.424 38.1752 286.047 36.8101 288.322C36.3551 289.096 35.3843 290.34 34.4743 291.31C33.3064 292.539 32.457 292.539 32.1385 294.238C31.8199 295.739 31.5469 297.029 31.2891 298.136C34.2771 295.8 36.9466 293.328 39.2824 290.795C42.0733 287.746 44.2878 284.621 45.7135 281.633C47.0179 279.04 47.8522 276.294 48.1859 273.564C48.5044 271.092 48.383 268.62 47.7915 266.026C45.3192 267.709 42.8468 269.727 40.5717 272.336V272.32Z\" fill=\"#00844B\"><\/path><path d=\"M10.661 250.539C11.2526 250.858 11.9654 250.934 12.5418 250.736C13.194 250.479 13.649 250.024 13.9069 249.432C14.1647 248.841 14.1647 248.203 13.9069 247.475C13.649 246.823 13.194 246.308 12.6025 245.974C12.0109 245.716 11.2981 245.579 10.7217 245.837C10.0695 246.035 9.61445 246.49 9.3566 247.066C9.09875 247.657 9.09875 248.37 9.3566 249.023C9.55378 249.735 10.0695 250.251 10.661 250.524V250.539Z\" fill=\"#00844B\"><\/path><path d=\"M30.6974 245.914C31.4103 242.986 32.4569 240.195 33.7613 237.526C34.1556 236.677 35.3236 237.268 34.9292 238.042C33.6248 240.711 32.654 243.441 31.9412 246.232C31.4255 248.31 30.9704 250.464 30.7126 252.603C31.6226 251.298 32.7905 249.872 34.2315 248.371C36.1881 246.414 38.0689 245.246 37.6139 241.803C37.356 240.18 36.6431 237.647 34.8837 235.099C32.745 237.374 30.7884 240.362 29.8784 243.487C29.1655 246.081 28.9683 249.084 29.484 252.466C29.7418 250.252 30.1362 248.037 30.7126 245.898L30.6974 245.914Z\" fill=\"#00844B\"><\/path><path d=\"M83.6934 410.301C83.5569 409.906 83.7541 409.588 84.0877 409.451C82.2069 407.313 80.4475 405.159 78.688 402.884C78.5515 409.846 78.8852 416.474 79.856 422.587C80.766 428.183 82.2676 433.704 84.6034 438.846C85.7714 437.284 86.0292 436.571 86.8786 434.812C87.1971 432.339 87.3336 429.67 87.1364 426.879C86.8786 421.419 85.7107 415.625 83.6934 410.301Z\" fill=\"#00844B\"><\/path><path d=\"M85.2404 410.756C87.0605 415.958 88.1677 421.555 88.4256 426.879C88.4863 428.639 88.4863 430.322 88.4256 432.021C89.1992 430.792 89.4722 429.685 89.6542 428.184C90.1092 425.393 90.1699 421.419 89.9727 416.611C89.9727 416.353 90.0334 416.156 90.1699 416.095C88.4863 414.335 86.8482 412.576 85.2252 410.756H85.2404Z\" fill=\"#00844B\"><\/path><path d=\"M91.0344 427.926C91.9445 426.242 92.718 424.483 93.3702 422.526C93.6281 421.677 93.8253 420.767 94.0831 419.796C93.1124 418.946 92.2023 418.036 91.2923 417.202C91.4895 421.555 91.3529 425.196 91.0344 427.926Z\" fill=\"#00844B\"><\/path><path d=\"M373.244 318.157C368.299 321.342 364.204 326.742 361.474 332.005C361.277 332.4 361.155 332.46 361.155 332.855C361.216 334.675 361.095 336.495 360.761 338.315C362.778 336.176 364.856 334.083 366.934 332.005C367.071 330.959 367.192 329.988 367.45 329.017C367.708 327.971 368.042 326.879 368.497 325.832C368.815 324.861 369.998 325.377 369.665 326.226C369.27 327.334 368.952 328.304 368.694 329.351C368.633 329.745 368.497 330.2 368.436 330.58C371.303 327.849 374.291 325.18 377.279 322.51C377.992 321.919 378.78 322.905 378.128 323.481C375.064 326.151 372.076 328.82 369.149 331.611C369.467 331.611 369.801 331.611 370.12 331.672C370.893 331.672 371.743 331.732 372.531 331.808C373.441 331.869 373.305 333.173 372.395 333.037C371.682 332.976 370.893 332.9 370.059 332.9H367.844C365.236 335.433 362.703 338.042 360.23 340.833C359.457 343.7 358.152 346.551 356.453 349.221C356.969 348.902 357.5 348.629 358.016 348.311C359.244 346.49 360.609 344.61 362.445 343.245C366.934 339.862 370.514 337.132 373.623 333.886C376.809 330.701 379.539 327.061 382.269 321.919C383.695 319.249 384.408 315.67 385.97 313.395C380.964 314.502 377.188 315.609 373.229 318.142L373.244 318.157Z\" fill=\"#00844B\"><\/path><path d=\"M374.473 292.736C369.589 296.71 365.312 300.806 362.187 305.098C358.805 309.785 356.787 314.79 356.984 320.114C358.607 322.647 359.775 325.256 360.428 327.986C360.488 325.969 360.488 324.012 360.625 322.268C360.822 319.674 361.14 317.323 361.671 315.306C362.323 313.228 363.097 311.605 364.007 310.3C364.917 308.996 366.024 308.025 367.132 307.252C367.905 306.736 368.633 307.767 367.905 308.298C366.798 309.011 365.888 309.921 365.038 311.089C364.189 312.257 363.476 313.759 362.9 315.64C362.763 316.095 362.703 316.55 362.581 317.065C363.097 316.474 363.628 315.958 364.144 315.503C365.251 314.532 366.358 313.683 367.587 312.909C368.3 312.454 369.012 313.501 368.239 314.017C367.132 314.729 366.024 315.518 364.993 316.428C364.022 317.399 363.036 318.385 362.202 319.477C362.066 320.387 362.005 321.358 361.944 322.404C361.808 324.422 361.747 326.56 361.747 328.911C364.417 324.361 367.268 321.115 370.332 318.703C371.181 316.747 371.955 314.866 372.41 313.046C372.804 311.226 373.062 309.148 372.668 307.328C371.955 303.354 373.062 298.879 374.033 294.784C374.23 294.071 374.351 293.419 374.488 292.767L374.473 292.736Z\" fill=\"#00844B\"><\/path><path d=\"M353.663 352.815C349.173 356.592 346.246 361.794 344.501 367.316C344.441 367.316 344.441 367.376 344.441 367.376C344.896 375.567 342.621 383.439 340.148 390.856C342.363 387.155 344.501 383.06 346.519 378.828L346.913 378.054H346.852C346.989 377.084 347.049 376.173 347.049 375.263C346.989 374.353 346.852 373.443 346.731 372.594C346.534 371.744 347.778 371.487 347.96 372.336C348.142 373.185 348.217 374.095 348.278 375.006C350.159 370.713 351.979 366.36 353.617 362.189C353.936 361.339 355.119 361.794 354.785 362.644C353.162 366.876 351.342 371.229 349.446 375.521C349.643 375.385 349.765 375.203 349.962 375.066C351.008 374.293 352.04 373.565 353.086 372.928C353.86 372.533 354.391 373.64 353.738 374.035C352.692 374.626 351.721 375.339 350.75 376.052C349.446 377.099 348.339 377.933 347.687 379.374C346.382 382.165 345.017 384.834 343.591 387.367C346.124 384.698 349.052 382.225 352.176 380.087C354.391 378.661 356.666 377.357 359.002 376.249C360.17 372.928 359.396 370.395 358.744 368.256C358.425 367.209 358.152 366.299 358.031 365.329C357.379 359.413 362.126 351.875 365.251 346.93C361.095 348.098 356.924 350.115 353.678 352.846L353.663 352.815Z\" fill=\"#00844B\"><\/path><path d=\"M371.803 262.568C372.319 262.704 372.911 262.507 373.366 262.173C373.957 261.718 374.336 261.127 374.534 260.353C374.731 259.58 374.67 258.851 374.397 258.336C374.139 257.82 373.745 257.426 373.168 257.289C372.653 257.153 372.061 257.289 371.546 257.684C371.03 258.078 370.635 258.654 370.438 259.443C370.241 260.156 370.302 260.945 370.575 261.521C370.833 262.037 371.288 262.431 371.803 262.568Z\" fill=\"#00844B\"><\/path><path d=\"M345.214 272.578C346.64 272.776 348.005 273.488 349.446 274.793C349.507 273.17 349.765 271.471 350.159 269.848C350.296 269.135 350.478 268.483 350.751 267.77C350.356 266.405 349.901 265.101 349.446 263.872C348.93 262.568 348.4 261.4 347.763 260.368C347.247 259.595 348.354 258.943 348.809 259.716C349.522 260.823 350.114 262.052 350.629 263.356C350.948 264.13 351.221 264.979 351.479 265.829C352.252 263.948 353.238 262.189 354.345 260.49C353.83 257.502 352.525 255.682 350.826 254.514C349.264 253.406 347.308 252.951 345.366 252.83C343.091 256.986 342.12 259.458 342.181 261.991C342.242 264.661 343.349 267.452 345.245 272.457V272.594L345.214 272.578Z\" fill=\"#00844B\"><\/path><path d=\"M354.315 288.838C355.089 290.067 355.938 291.311 356.909 292.479C357.045 292.084 357.167 291.705 357.303 291.371C355.999 285.911 355.741 281.224 356.393 275.764C356.651 273.807 357.045 271.79 357.5 269.788C357.106 268.878 356.727 267.968 356.393 267.058C356.135 266.087 355.938 265.04 355.877 263.933C355.817 263.023 357.106 263.023 357.182 263.933C357.182 264.843 357.379 265.814 357.637 266.663C357.773 267.058 357.895 267.513 358.092 267.892C358.805 265.359 359.775 262.826 360.958 260.278C361.353 259.504 362.521 260.02 362.126 260.869C361.019 263.144 360.17 265.419 359.457 267.755C359.518 267.619 359.654 267.497 359.775 267.361C360.367 266.769 360.943 266.193 361.338 265.541C361.853 264.767 362.9 265.48 362.445 266.254C361.929 266.967 361.338 267.619 360.685 268.271C360.094 268.863 359.457 269.378 358.805 269.894C358.289 271.911 357.895 273.929 357.697 275.946C357.561 277.053 357.44 278.16 357.379 279.268C357.697 278.949 358.092 278.555 358.425 278.221C359.017 277.508 359.593 276.856 359.851 276.401C360.306 275.551 361.413 276.143 361.019 276.992C360.625 277.584 360.048 278.297 359.336 279.07C358.623 279.844 357.834 280.693 357.379 281.482C357.379 284.076 357.697 286.685 358.152 289.278C360.23 284.849 362.703 281.088 365.494 277.902C366.146 275.627 366.464 273.413 366.404 271.198C366.343 268.923 365.949 266.648 365.236 264.434C364.462 262.022 364.265 259.489 364.523 256.956C364.659 255.136 365.039 253.179 365.494 251.298C364.189 252.208 362.9 253.118 361.717 254.165C356.833 258.26 352.874 263.857 351.372 270.167C349.871 276.143 350.599 282.65 354.3 288.823L354.315 288.838Z\" fill=\"#00844B\"><\/path><path d=\"M355.422 300.274C355.422 299.759 355.483 299.228 355.483 298.712C353.602 296.498 351.782 294.222 350.022 291.947H348.066C347.414 291.947 346.761 291.887 346.049 291.75C345.139 291.614 345.336 290.385 346.185 290.521C346.837 290.582 347.489 290.658 348.142 290.658C348.46 290.719 348.733 290.719 349.052 290.719C348.4 289.869 347.823 289.035 347.232 288.246C346.185 286.821 345.154 285.455 344.183 284.015C342.56 283.878 340.998 283.559 339.572 282.847C338.723 282.452 339.314 281.284 340.088 281.679C341.058 282.134 342.105 282.452 343.212 282.649C341.908 280.89 340.679 279.07 339.511 277.31C338.996 276.537 340.027 275.809 340.558 276.598C341.726 278.281 342.894 279.98 344.077 281.664C344.016 281.072 343.88 280.435 343.819 279.843C343.622 278.615 343.364 277.432 343.106 276.203C342.909 275.293 344.153 275.035 344.335 275.885C344.592 277.113 344.85 278.418 345.047 279.661C345.305 281.027 345.503 282.452 345.639 283.893C346.488 285.061 347.398 286.305 348.233 287.473C348.748 288.125 349.203 288.838 349.734 289.49C349.734 289.232 349.795 288.974 349.795 288.777C349.856 287.928 349.856 287.094 349.856 286.305C349.856 285.395 351.16 285.395 351.16 286.305C351.16 287.154 351.16 287.988 351.099 288.838C351.039 289.551 350.963 290.203 350.842 290.916C352.464 292.994 354.087 295.011 355.786 297.028C355.983 295.982 356.181 294.95 356.499 293.904H356.438C355.271 292.478 354.163 290.977 353.314 289.475C350.781 285.243 349.537 280.89 349.416 276.598C346.291 272.957 343.364 273.534 339.602 274.262C338.889 274.398 338.177 274.52 337.388 274.656C338.237 281.482 339.86 286.623 342.727 290.658C345.518 294.693 349.613 297.681 355.468 300.274H355.422Z\" fill=\"#00844B\"><\/path><path d=\"M356.651 300.73C356.514 303.854 356.909 306.979 357.879 309.83C358.592 308.329 359.442 306.842 360.473 305.34L360.412 305.28C360.155 303.778 359.957 302.61 360.352 301.124C361.52 296.437 363.218 292.145 365.296 287.989C366.267 286.169 367.253 284.288 368.345 282.528C368.482 281.679 368.603 281.027 368.664 280.39C368.8 279.737 368.8 279.161 368.861 278.372C368.861 277.462 370.089 277.523 370.089 278.433C370.089 278.827 370.089 279.282 370.029 279.662C370.742 278.494 371.53 277.326 372.243 276.219C372.44 275.961 372.562 275.703 373.093 276.021C373.684 276.34 373.487 276.613 373.29 276.931C370.878 280.632 368.482 284.606 366.464 288.565C366.146 289.157 365.873 289.733 365.615 290.325L365.676 290.264C366.388 289.748 367.177 289.217 367.951 288.838C368.724 288.444 369.316 289.551 368.542 290.006C367.769 290.324 367.117 290.78 366.404 291.31C365.751 291.826 365.099 292.418 364.447 293.07C364.386 293.07 364.386 293.131 364.386 293.131C363.218 295.8 362.308 298.53 361.595 301.458C361.338 302.307 361.338 303.081 361.459 303.93C363.082 301.791 364.963 299.698 367.056 297.62C367.056 297.62 367.117 297.559 367.117 297.484C369.194 294.359 370.893 291.113 372.183 287.792C373.608 284.409 374.594 281.027 375.246 277.584C375.701 275.051 376.02 272.442 376.672 269.848C373.35 272.063 370.302 274.535 367.511 277.584C364.128 281.224 361.262 285.577 359.184 290.127C357.682 293.373 356.772 297.089 356.651 300.73Z\" fill=\"#00844B\"><\/path><path d=\"M385.333 299.167C385.591 298.576 386.243 297.15 385.136 297.089C384.62 297.089 383.907 297.347 383.058 297.802C381.753 298.652 381.374 299.759 380.843 301.124C380.843 301.185 380.782 301.26 380.782 301.321C381.95 301.321 382.86 301.124 383.573 300.805C384.347 300.487 384.938 299.895 385.333 299.183V299.167Z\" fill=\"#00844B\"><\/path><path d=\"M354.573 318.946C352.616 316.474 350.872 314.138 349.31 311.863C348.081 310.043 347.035 308.344 346.124 306.721C344.562 310.953 343.455 315.503 343 320.054C342.484 324.862 342.606 329.746 343.455 334.493C344.107 337.739 345.275 340.803 347.095 343.654C348.597 345.99 350.538 348.205 352.95 350.161C352.556 344.898 351.721 339.696 350.538 334.554C349.568 333.962 348.718 333.325 347.808 332.537C346.898 331.687 345.988 330.716 345.139 329.609C344.547 328.896 345.594 328.108 346.109 328.836C346.959 329.882 347.793 330.792 348.703 331.566C349.158 332.021 349.613 332.339 350.068 332.734C349.158 329.23 348.111 325.848 346.944 322.389C346.686 321.54 347.854 321.161 348.172 321.995C349.279 325.241 350.311 328.563 351.16 331.884C351.418 330.777 351.615 329.609 351.676 328.502C351.676 327.592 352.98 327.653 352.904 328.563C352.844 330.443 352.389 332.339 351.676 334.16C352.904 339.423 353.754 344.822 354.148 350.283C361.171 340.727 362.081 328.502 354.543 318.946H354.573Z\" fill=\"#00844B\"><\/path><path d=\"M337.6 398.591C341.18 397.029 344.562 395.406 347.869 393.192C348.066 392.282 348.324 391.372 348.718 390.522C349.112 389.612 349.628 388.702 350.22 387.853C350.417 387.595 350.614 387.337 351.13 387.716C351.645 388.035 351.448 388.308 351.266 388.565C350.675 389.339 350.22 390.188 349.901 391.038C349.704 391.356 349.583 391.69 349.507 392.084C353.739 389.021 357.576 385.577 361.277 381.937C361.929 381.346 362.839 382.195 362.187 382.847C358.349 386.624 354.512 390.006 350.675 392.797C347.156 395.33 343.394 397.605 339.299 399.304C339.102 399.82 338.844 400.275 338.647 400.806C342.878 400.548 347.095 399.183 351.266 396.65C355.877 393.92 360.427 389.824 364.856 384.425C367.905 380.784 371.166 377.341 374.351 373.898C366.874 373.838 359.138 376.947 352.889 381.118C346.003 385.805 340.27 392.115 337.615 398.606L337.6 398.591Z\" fill=\"#00844B\"><\/path><path d=\"M372.91 359.58C371.743 359.383 370.377 360.035 370.044 361.203C369.649 362.31 370.438 363.281 371.545 363.478C372.653 363.675 374.018 363.023 374.412 361.855C374.731 360.748 374.018 359.838 372.91 359.58Z\" fill=\"#00844B\"><\/path><path d=\"M344.365 348.144C343.713 347.37 342.681 347.37 341.953 348.144C341.635 348.538 341.438 349.054 341.438 349.706C341.438 350.297 341.635 350.874 342.029 351.268C342.681 352.042 343.652 352.315 344.365 351.405C344.684 351.01 344.881 350.434 344.881 349.782C344.881 349.13 344.684 348.553 344.365 348.159V348.144Z\" fill=\"#00844B\"><\/path><path d=\"M333.444 399.304C332.595 397.621 332.019 395.406 331.624 392.797C331.169 389.551 331.033 385.714 331.306 381.543C331.503 378.221 331.897 374.914 332.474 371.471C333.065 368.028 333.899 364.509 335.082 361.006C335.34 360.096 336.584 360.49 336.25 361.4C335.143 364.843 334.294 368.286 333.717 371.669C333.126 375.051 332.807 378.373 332.61 381.619V381.679C332.807 381.361 332.929 381.027 333.126 380.769C333.839 379.662 334.552 378.555 335.401 377.523C335.993 376.871 336.963 377.66 336.372 378.373C335.598 379.343 334.87 380.329 334.233 381.437C333.581 382.483 333.004 383.575 332.474 384.758C332.413 387.686 332.534 390.355 332.868 392.691C333.187 395.027 333.839 397.636 335.143 399.714C336.705 399.001 337.873 393.54 338.586 391.523C342.029 381.315 345.214 370.258 341.574 358.822C340.861 356.486 339.815 354.211 338.526 351.996C337.813 350.692 336.963 349.402 335.993 348.159C333.581 357.972 330.198 367.406 325.921 376.386L325.663 376.841C325.603 382.635 326.058 388.277 327.483 392.312C328.651 395.755 330.547 398.227 333.46 399.334L333.444 399.304Z\" fill=\"#00844B\"><\/path><path d=\"M307.765 434.296C311.011 430.398 314.333 428.441 315.501 423.239C315.819 421.677 315.956 420.19 315.895 418.628C315.834 417.657 317.063 417.521 317.124 418.491C317.26 420.175 317.124 421.874 316.729 423.497C316.593 424.149 316.411 424.801 316.214 425.378C317.518 424.012 318.747 422.647 319.915 421.222C321.932 418.749 323.752 416.156 325.254 413.092C325.709 412.318 326.816 412.895 326.421 413.683C324.799 416.808 322.978 419.477 320.961 422.01C320.188 422.92 319.459 423.83 318.625 424.68C319.596 424.164 320.506 423.633 321.416 423.254C322.19 422.86 322.781 423.967 321.932 424.361C320.764 424.953 319.52 425.59 318.352 426.318C314.454 428.654 311.648 431.657 308.736 435.161C307.234 436.981 305.809 438.862 304.504 440.879C309.707 438.998 314.318 436.389 318.413 432.749C322.842 428.851 326.664 423.709 329.925 417.081C331.745 413.243 333.429 409.467 335.128 405.629C335.901 403.748 336.751 401.852 337.6 399.972C320.43 407.449 309.191 419.993 304.899 438.073C305.809 436.768 306.719 435.54 307.765 434.296Z\" fill=\"#00844B\"><\/path><path d=\"M315.562 404.188C316.077 404.188 316.532 404.052 316.866 403.733C317.185 403.415 317.458 402.884 317.579 402.11C317.579 401.853 317.579 401.519 317.518 401.261C317.458 400.806 317.26 400.412 317.063 400.154C316.805 399.896 316.548 399.699 316.214 399.699H315.956C315.501 399.759 315.107 400.017 314.788 400.412C314.47 400.806 314.272 401.382 314.197 402.035C314.197 402.626 314.333 403.202 314.652 403.658C314.849 403.976 315.167 404.173 315.562 404.173V404.188Z\" fill=\"#00844B\"><\/path><path d=\"M347.429 415.504C346.322 414.73 344.638 414.851 343.531 415.64C342.302 416.55 342.424 417.976 343.986 418.507C344.699 418.765 345.548 418.704 346.322 418.507C347.687 418.112 348.794 416.626 347.429 415.519V415.504Z\" fill=\"#00844B\"><\/path><path d=\"M315.88 436.374C312.24 438.968 308.205 440.985 303.852 442.486C302.805 443.397 301.971 444.564 301.319 445.808C300.864 446.718 300.409 447.689 300.015 448.857C303.261 448.72 306.779 447.75 310.617 446.187C313.347 444.109 315.956 441.758 318.231 439.165C318.883 438.452 319.793 439.301 319.202 440.014C317.837 441.576 316.335 443.002 314.773 444.443C317.897 442.941 321.204 441.197 324.783 439.241C325.557 438.786 326.209 439.893 325.375 440.348C321.143 442.684 317.245 444.701 313.605 446.324C315.031 446.46 316.472 446.718 317.958 447.37C318.474 447.568 318.474 447.886 318.155 448.341C319.52 447.75 320.825 447.113 322.053 446.324C328.621 442.486 334.278 436.768 338.829 431.308C331.548 430.14 321.856 432.081 315.88 436.374Z\" fill=\"#00844B\"><\/path><path d=\"M311.785 447.492H310.875C307.098 448.993 303.655 449.903 300.409 450.161C306.582 451.663 312.376 450.813 317.639 448.599C317.579 448.538 317.503 448.538 317.442 448.462C315.622 447.689 313.665 447.613 311.785 447.492Z\" fill=\"#00844B\"><\/path><path d=\"M303.079 440.348C303.473 438.468 303.928 436.648 304.444 434.888C302.942 432.931 301.85 429.291 301.198 426.895C300.94 425.787 299.12 424.559 298.073 424.028C297.3 423.634 297.815 422.526 298.665 422.921C299.636 423.376 300.546 424.028 301.334 424.877C301.592 423.77 301.926 422.663 302.305 421.632C302.821 420.13 303.473 418.704 304.383 417.476C304.975 416.763 306.006 417.536 305.43 418.249C304.58 419.356 304.004 420.661 303.473 422.026C303.018 423.391 302.624 424.817 302.366 426.182C302.821 428.715 303.731 431.126 304.975 433.144C305.945 430.216 307.053 427.426 308.418 424.756C309.009 420.069 308.933 415.974 308.281 412.394C307.963 410.256 307.371 408.238 306.597 406.479C303.215 410.574 299.575 414.472 295.737 418.188C295.995 426.576 298.665 431.642 301.395 437.042C301.987 438.088 302.502 439.181 303.079 440.364V440.348Z\" fill=\"#00844B\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">TOUR ESTADI MALLORCA SON MOIX<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b6ebdb elementor-widget elementor-widget-text-editor\" data-id=\"4b6ebdb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Discover Estadi Mallorca Son Moix and get up close to the history of RCD Mallorca on a unique guided tour! After the spectacular renovation, you can access exclusive areas and explore the heart of the stadium. Experience an unforgettable journey that will captivate all football fans and enthusiasts.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ef21b9 elementor-widget elementor-widget-button\" data-id=\"7ef21b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/bstadium.es\/tours-originales\/tour-por-el-estadi-de-son-moix-estadio-del-rcd-mallorca\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">BUY TICKETS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-907cad2 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"907cad2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-93c0832 e-con-full e-flex e-con e-child\" data-id=\"93c0832\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2a5100f elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2a5100f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" viewBox=\"0 0 792 243.78\"><defs><style>      .cls-1, .cls-2 {        fill: none;      }      .cls-3 {        fill: url(#linear-gradient-3);      }      .cls-4 {        fill: url(#linear-gradient-2);      }      .cls-5 {        fill: url(#linear-gradient);      }      .cls-6 {        fill: #1d1d1b;      }      .cls-2 {        stroke: #e30b17;        stroke-miterlimit: 10;        stroke-width: .5px;      }      .cls-7 {        isolation: isolate;      }      .cls-8 {        clip-path: url(#clippath-1);      }      .cls-9 {        clip-path: url(#clippath-2);      }      .cls-10 {        fill: #fff;      }      .cls-11 {        fill: url(#radial-gradient);        mix-blend-mode: color-burn;      }      .cls-12 {        fill: #e30b17;      }    <\/style><clipPath id=\"clippath-1\"><rect class=\"cls-1\" x=\"812.82\" y=\"-.55\" width=\"435.35\" height=\"244.88\"><\/rect><\/clipPath><linearGradient id=\"linear-gradient\" x1=\"-10560.56\" y1=\"1108.29\" x2=\"-10681.83\" y2=\"1229.56\" gradientTransform=\"translate(10336 -10545.03) rotate(-45) scale(1.41 .71) skewX(26.57)\" gradientUnits=\"userSpaceOnUse\"><stop offset=\"0\" stop-color=\"#e4e8e9\"><\/stop><stop offset=\"1\" stop-color=\"#fff\"><\/stop><\/linearGradient><linearGradient id=\"linear-gradient-2\" x1=\"-10684.24\" y1=\"1284.63\" x2=\"-10798.9\" y2=\"1399.28\" xlink:href=\"#linear-gradient\"><\/linearGradient><linearGradient id=\"linear-gradient-3\" x1=\"-10527.39\" y1=\"1012.54\" x2=\"-10605.55\" y2=\"1090.7\" gradientTransform=\"translate(10336 -10545.03) rotate(-45) scale(1.41 .71) skewX(26.57)\" gradientUnits=\"userSpaceOnUse\"><stop offset=\"0\" stop-color=\"#fff\"><\/stop><stop offset=\"1\" stop-color=\"#e4e8e9\"><\/stop><\/linearGradient><radialGradient id=\"radial-gradient\" cx=\"8351.42\" cy=\"10578.91\" fx=\"8351.42\" fy=\"10578.91\" r=\"105.11\" gradientTransform=\"translate(8316.67 -4318.85) rotate(135) scale(1 .21)\" gradientUnits=\"userSpaceOnUse\"><stop offset=\"0\" stop-color=\"#6e6f72\"><\/stop><stop offset=\"1\" stop-color=\"#fff\"><\/stop><\/radialGradient><clipPath id=\"clippath-2\"><rect class=\"cls-1\" width=\"792\" height=\"244.33\"><\/rect><\/clipPath><\/defs><g class=\"cls-7\"><g id=\"Capa_1\" data-name=\"Capa 1\"><rect class=\"cls-6\" x=\"-.49\" width=\"792\" height=\"243.78\"><\/rect><rect class=\"cls-6\" width=\"792\" height=\"243.78\"><\/rect><g class=\"cls-8\"><polygon class=\"cls-5\" points=\"1041.4 -16.24 851.07 174.09 726.05 174.09 916.38 -16.24 1041.4 -16.24\"><\/polygon><polygon class=\"cls-4\" points=\"1085.45 109.18 905.51 289.12 787.31 289.12 967.25 109.18 1085.45 109.18\"><\/polygon><g><polygon class=\"cls-3\" points=\"922.77 -51.49 773.36 97.93 719.53 97.93 868.95 -51.49 922.77 -51.49\"><\/polygon><path class=\"cls-11\" d=\"M863.71,38.87c41.26-41.26,67.7-81.71,59.06-90.35l-149.41,149.41c8.64,8.64,49.09-17.8,90.35-59.06Z\"><\/path><\/g><\/g><polygon class=\"cls-12\" points=\"184.21 190.07 208.2 190.16 282.05 116.32 257.93 116.34 184.21 190.07\"><\/polygon><polygon class=\"cls-12\" points=\"282.05 239.22 306.63 239.32 380.47 165.48 355.77 165.49 282.05 239.22\"><\/polygon><polygon class=\"cls-12\" points=\"380.43 189.93 405.02 190.03 478.86 116.19 454.15 116.2 380.43 189.93\"><\/polygon><polygon class=\"cls-12\" points=\"380.75 140.77 405.34 140.87 479.18 67.02 454.48 67.04 380.75 140.77\"><\/polygon><polygon class=\"cls-12\" points=\"601.19 140.01 625.78 140.1 699.62 66.26 674.92 66.28 601.19 140.01\"><\/polygon><polygon class=\"cls-12\" points=\"601.71 91.31 626.3 91.4 675.33 42.37 650.63 42.39 601.71 91.31\"><\/polygon><polygon class=\"cls-12\" points=\"110.55 140.45 135.13 140.54 159.52 116.16 134.81 116.18 110.55 140.45\"><\/polygon><polygon class=\"cls-12\" points=\"111.17 214.32 135.76 214.42 160.14 190.03 135.44 190.05 111.17 214.32\"><\/polygon><polygon class=\"cls-12\" points=\"282.72 189.98 307.31 190.07 331.69 165.69 306.99 165.71 282.72 189.98\"><\/polygon><polygon class=\"cls-12\" points=\"356.15 140.68 380.74 140.78 405.12 116.39 380.42 116.41 356.15 140.68\"><\/polygon><polygon class=\"cls-12\" points=\"331.48 214.2 356.07 214.29 380.45 189.91 355.74 189.93 331.48 214.2\"><\/polygon><g class=\"cls-9\"><g><polygon class=\"cls-2\" points=\"600.05 62.9 576.06 62.8 502.22 136.64 526.33 136.63 600.05 62.9\"><\/polygon><polygon class=\"cls-2\" points=\"478.04 141.66 453.45 141.56 379.61 215.4 404.32 215.39 478.04 141.66\"><\/polygon><polygon class=\"cls-2\" points=\"130.43 92.94 105.84 92.85 32 166.69 56.7 166.67 130.43 92.94\"><\/polygon><polygon class=\"cls-2\" points=\"132.96 166.78 108.38 166.69 34.54 240.53 59.24 240.51 132.96 166.78\"><\/polygon><polygon class=\"cls-2\" points=\"35.72 115.67 11.13 115.57 -62.71 189.41 -38 189.4 35.72 115.67\"><\/polygon><polygon class=\"cls-2\" points=\"771.44 166.39 746.85 166.29 722.46 190.67 747.17 190.66 771.44 166.39\"><\/polygon><polygon class=\"cls-2\" points=\"796.16 14.64 771.58 14.55 697.74 88.39 722.44 88.37 796.16 14.64\"><\/polygon><\/g><\/g><g><g><path class=\"cls-10\" d=\"M342.2,116.66h51.03v4.54h-23.04v68.8h-4.96v-68.8h-23.03v-4.54Z\"><\/path><path class=\"cls-10\" d=\"M123.5,127.63c-2.74-4.95-7.99-7.67-15.25-7.67-11.36,0-18.91,5.99-18.91,15.19,0,7.03,4.24,11.68,12.6,13.84l13.02,3.3c11.05,2.79,16.94,9.4,16.94,18.8,0,12.29-9.5,20.15-24.17,20.15-13.74,0-23.04-7.13-24.17-18.59h5.27c.41,8.37,7.95,13.95,18.9,13.95,11.67,0,19.21-5.99,19.21-15.39,0-7.23-4.24-12.09-12.91-14.26l-12.71-3.2c-11.05-2.79-16.94-9.09-16.94-18.59,0-11.98,9.4-19.73,23.86-19.73,8.41,0,14.93,3.13,18.77,8.71\"><\/path><path class=\"cls-10\" d=\"M150.8,124.97v32.9h21.59c11.47,0,18.29-7.75,18.29-18.69s-6.92-17.98-17.67-17.98h-18.44l4.54-4.54h14.1c13.95,0,22.52,9.09,22.52,22.73,0,12.91-8.68,23.04-22.52,23.04h-22.42v27.58h-4.96v-60.07l4.96-4.96Z\"><\/path><path class=\"cls-10\" d=\"M205.89,168.23c-1.57-4.5-2.41-9.51-2.41-14.9,0-22.21,14.36-37.91,34.61-37.91,6.12,0,11.69,1.42,16.5,4.01l-3.53,3.63c-3.84-1.87-8.21-2.89-12.97-2.89-17.36,0-29.55,13.64-29.55,33.16,0,3.87.48,7.51,1.38,10.86l-4.04,4.04ZM219.02,179.45c4.98,4.51,11.55,7.04,19.07,7.04,17.46,0,29.65-13.64,29.65-33.16,0-6.95-1.55-13.16-4.33-18.27l3.66-3.66c3.66,6.04,5.72,13.52,5.72,21.93,0,22.21-14.36,37.91-34.71,37.91-8.9,0-16.64-3.01-22.53-8.25l3.46-3.54Z\"><\/path><path class=\"cls-10\" d=\"M331.44,189.75l-15.88-31.46h-23.86v31.71h-4.96v-73.34h27.07c13.95,0,22.73,8.06,22.73,20.56,0,10.74-5.99,18.39-15.81,20.45l14.45,28.45-3.73,3.63ZM291.69,153.74h22.31c11.05,0,17.46-6.2,17.46-16.32s-6.92-16.22-17.67-16.22h-22.11v32.54Z\"><\/path><path class=\"cls-10\" d=\"M342.2,116.66h51.03v4.54h-23.04v68.8h-4.96v-68.8h-23.03v-4.54Z\"><\/path><g><path class=\"cls-10\" d=\"M427.55,142.71c3.19-14.59,13.22-24.73,27.07-27.07,2.01-.34,4.1-.51,6.26-.51,5.53,0,10.67,1.26,15.13,3.56,7.62,3.93,13.22,10.88,15.24,19.68h-5.47c-2.15-7.38-6.99-12.97-13.46-15.99-3.5-1.63-7.47-2.51-11.74-2.51-4.94,0-9.42,1.1-13.32,3.13-4.76,2.49-8.63,6.37-11.34,11.34M432.46,162.23c3.09,14.57,13.69,23.87,28.1,23.87,12.19,0,22.21-6.82,25.62-17.35h5.48c-3.51,13.22-16.12,22.11-31.2,22.11s-27.72-9.56-32.14-24.48\"><\/path><path class=\"cls-10\" d=\"M510.04,185.17h34.91v4.54h-39.87v-73.34h4.96v68.8Z\"><\/path><path class=\"cls-10\" d=\"M561.27,189.72h-4.96v-73.34h4.96v73.34Z\"><\/path><path class=\"cls-10\" d=\"M632.85,133.04v56.68h-4.96l-43.08-65.18v65.18h-4.96v-73.34h5.06l42.97,64.97v-43.35l4.96-4.96Z\"><\/path><path class=\"cls-10\" d=\"M656.4,189.72h-4.96v-73.34h4.96v73.34Z\"><\/path><path class=\"cls-10\" d=\"M670.34,153.04c0-22.41,14.05-37.91,34.4-37.91,14.98,0,27.17,9.3,30.37,23.24h-5.47c-3.31-11.36-13.02-18.49-25.21-18.49-17.25,0-29.03,13.43-29.03,33.16s11.77,33.06,29.03,33.06c12.19,0,22.21-6.82,25.62-17.35h5.48c-3.51,13.22-16.12,22.11-31.2,22.11-20.04,0-33.99-15.5-33.99-37.81Z\"><\/path><\/g><\/g><g><path class=\"cls-10\" d=\"M230.67,90.29l-.17-21.08-2.86.38-2.84-.38v24.32l-5.76-24.32-2.95.44-2.71-.4-.24.66c-.25.72-2.12,8.91-4,17.53l-1.1,5.06-.22,1.11v-24.4l-3.4.45-3.1-.4-.24.6c-1.01,2.5-2.07,5.88-2.85,9.04,0,.04-.02.08-.03.12-.84-3.96-2.23-7.64-2.85-9.17l-.24-.6-3.2.4-3.34-.45v24.41h4.87v-8.92c0-1.7-.01-3.39-.04-4.95,1.21,4.34,2.02,8.79,2.35,12.99l.03.43,2.2-.51,2.29.5.04-.42c.46-4.52,1.34-9.21,2.47-13.25-.02,1.66-.03,3.28-.03,4.83v9.28h10.22l.83-3.99c.02-.08.04-.14.06-.2,1.2-.57,3.03-.78,4.44.01l1.3,4.18h5.17v-.02s12.72,0,12.72,0l.36-9.49-1.74,2.13c-1.67,2.04-2.31,2.55-5.49,4.07ZM217.48,85.96c-.44-.16-.89-.25-1.38-.32h-.06s-.06,0-.06,0c-.52.09-1,.25-1.44.43.57-2.61,1.11-5.15,1.55-7.3.52,2.85.98,5.22,1.39,7.19Z\"><\/path><path class=\"cls-10\" d=\"M244.3,90.29l-.17-21.08-2.86.38-2.83-.38v24.37h12.74l.35-9.49-1.74,2.13c-1.67,2.04-2.31,2.55-5.49,4.07Z\"><\/path><path class=\"cls-10\" d=\"M259.54,69.08c-6.66,0-8.02,4.97-8.02,12.44s1.31,12.24,8.02,12.24,8.09-4.68,8.09-12.24c0-6.15-.96-12.44-8.09-12.44ZM262.09,81.52c0,7.16-.74,7.87-2.55,7.87-1.59,0-2.45-1.25-2.45-7.87v-1.1c0-4.69.22-6.61,2.45-6.61,2.45,0,2.55,2.36,2.55,7.7Z\"><\/path><path class=\"cls-10\" d=\"M279.09,82.62c1.89-1.34,2.97-3.19,2.97-5.15,0-4.65-2.63-8.02-6.26-8.02l-3.42.56-4.21-.84.11,5.04-.14,19.39h5.07v-10.35c2.97.93,3.69,3.37,5.01,10.05l.06.3h4.71l-.04-.41c-.31-3.58-1.23-8.23-3.87-10.57ZM276.96,77.54c0,1.04-.27,2.78-2.05,2.78h-1.69l-.06-5.77h2.21c1.03,0,1.59,1.54,1.59,2.98Z\"><\/path><path class=\"cls-10\" d=\"M297.49,84.19l-.04-.33h-4.8v1.03c.01,1.72.02,3.21-.67,3.9-.33.33-.82.49-1.52.49-1.89,0-2.48-1.09-2.48-7.87,0-5.24.24-7.7,2.42-7.7,1.27,0,1.92.99,1.92,2.95,0,.75-.13,2.46-.33,3.45l-.11.53,5.24-.86.06-.25c.17-.75.28-2.28.28-3.04,0-3.74-2.31-7.52-7.46-7.52-6.32,0-7.59,4.76-7.59,12.44,0,8.12,1.25,12.24,8.05,12.24,4.84,0,7.09-2.44,7.09-7.69,0-.57,0-1.15-.07-1.77Z\"><\/path><path class=\"cls-10\" d=\"M308.22,69.2l-2.95.44-2.71-.4-.24.66c-.25.72-2.12,8.91-4,17.53l-1.1,5.06-.22,1.11h5.18l.83-3.99c.02-.08.04-.14.06-.2,1.2-.57,3.03-.78,4.44.01l1.3,4.18h5.17l-5.77-24.4ZM306.65,85.96c-.44-.16-.89-.25-1.38-.32h-.06s-.06,0-.06,0c-.52.09-1,.25-1.44.43.57-2.61,1.11-5.15,1.55-7.3.52,2.85.98,5.22,1.39,7.19Z\"><\/path><path class=\"cls-10\" d=\"M146.57,82.62c1.89-1.34,2.97-3.19,2.97-5.15,0-4.65-2.63-8.02-6.26-8.02l-3.42.56-4.21-.84.11,5.04-.14,19.39h5.07v-10.35c2.97.93,3.69,3.37,5.01,10.05l.06.3h4.71l-.04-.41c-.31-3.58-1.23-8.23-3.87-10.57ZM144.43,77.54c0,1.04-.27,2.78-2.05,2.78h-1.69l-.06-5.77h2.21c1.03,0,1.59,1.54,1.59,2.98Z\"><\/path><path class=\"cls-10\" d=\"M165.2,83.98h-4.8v1.03c.01,1.72.02,3.21-.67,3.9-.33.33-.82.49-1.52.49-1.89,0-2.48-1.09-2.48-7.87,0-5.24.24-7.7,2.42-7.7,1.27,0,1.92.99,1.92,2.95,0,.75-.13,2.46-.33,3.45l-.11.53,5.24-.86.06-.25c.17-.75.28-2.28.28-3.04,0-3.74-2.31-7.52-7.46-7.52-6.32,0-7.59,4.76-7.59,12.44,0,8.12,1.25,12.24,8.05,12.24,4.84,0,7.09-2.44,7.09-7.69,0-.57,0-1.15-.07-1.77l-.04-.33Z\"><\/path><path class=\"cls-10\" d=\"M172.44,69.42h0l-3.61.46-2.53-.75v24.48h5.79c6.85,0,9.65-3.48,9.65-12.01,0-10.06-5.02-12.17-9.29-12.17ZM176.32,81.66c0,5.93-1.01,7.74-4.31,7.74h-.82v-14.77h.82c3.63,0,4.31,2.47,4.31,7.04Z\"><\/path><path class=\"cls-10\" d=\"M90.57,59.89c-.25.07-.44.3-.44.57,0,.31.24.57.54.59-.11.1-.18.25-.18.4,0,.3.25.54.54.54h.01c-.09.1-.14.22-.14.36,0,.29.24.54.54.54.08,0,.16-.02.23-.05.08.08.15.18.2.32-.12.15-.19.33-.22.52-.02.19-.02.41.06.59.1.24.39.31.6.16.18-.12.23-.36.13-.55.06-.12.14-.18.23-.22.09-.03.19-.02.29.02.11.04.21.12.31.21h0c.13.11.23.25.3.39.04.09.07.18.07.26,0,.06.01.12.03.16.05.12.14.2.25.25.1.05.23.07.33.07h.05c.04.08.11.18.21.29.13.13.3.44.35.62-.04.03,4.22-1.36,8.59-1.36,4.61,0,9.34,1.4,9.3,1.36.05-.18.2-.49.33-.62.1-.11.17-.21.21-.29h.04c.11,0,.23-.02.33-.07.11-.05.21-.14.25-.25.02-.04.03-.1.03-.16,0-.08.03-.16.06-.25h0c.07-.14.18-.29.3-.4.1-.09.21-.16.31-.21.1-.04.21-.05.29-.02.08.03.16.1.23.22-.1.19-.05.43.13.55.21.15.49.08.6-.16.16-.35.08-.77-.16-1.09.05-.14.12-.25.21-.34.08.03.15.05.23.05.3,0,.54-.25.54-.54,0-.14-.05-.27-.14-.36h.01c.29,0,.54-.24.54-.54,0-.16-.08-.31-.18-.4.3-.03.54-.29.54-.59,0-.27-.18-.51-.44-.57.31-.05.55-.33.55-.65,0-.36-.29-.66-.66-.66-.07,0-.12,0-.18.02.22-.11.37-.33.37-.6,0-.37-.3-.68-.68-.68-.12,0-.24.03-.34.1.08-.11.12-.24.12-.38,0-.36-.29-.66-.66-.66-.15,0-.29.05-.4.14v-.04c0-.35-.29-.64-.64-.64-.17,0-.33.08-.44.19-.02.01-.03.03-.05.05,0-.01,0-.03-.01-.04-.06-.24-.28-.42-.54-.42-.16,0-.3.06-.4.16-.01.02-.03.03-.04.05-.07-.23-.29-.4-.54-.4-.16,0-.29.06-.4.16-.01.01-.03.03-.03.04v-.03c0-.3-.25-.55-.55-.55-.22,0-.41.13-.5.32,0-.02,0-.05,0-.07,0-.3-.25-.55-.55-.55-.16,0-.29.06-.4.16-.01-.29-.25-.52-.54-.52-.15,0-.29.06-.38.16-.07.08-.12.16-.14.27v-.03c0-.29-.24-.53-.53-.53-.14,0-.27.06-.37.15-.04.04-.08.09-.1.14-.03-.2-.18-.36-.37-.42-.05-.01-.1-.02-.15-.02-.14,0-.27.06-.37.16-.03.03-.07.08-.09.12-.05-.23-.26-.42-.51-.42-.14,0-.27.06-.37.16-.03.03-.05.06-.08.1-.08-.19-.25-.32-.46-.32-.28,0-.51.23-.5.51-.15,0-.29-.03-.42-.08.05-.12.09-.27.09-.41,0-.49-.36-.91-.83-.98v-.51h.6v-.33h-.6v-.64h-.31v.64h-.6v.33h.6v.51c-.47.08-.83.49-.83.98,0,.14.03.29.09.41-.14.05-.27.08-.42.08,0-.27-.22-.51-.5-.51-.21,0-.39.13-.46.32-.02-.03-.05-.07-.08-.1-.1-.1-.23-.16-.37-.16-.25,0-.46.18-.51.42-.02-.04-.05-.08-.09-.12-.1-.1-.23-.16-.37-.16-.03,0-.07,0-.1.01h0c-.21.04-.38.21-.42.42-.02-.05-.05-.1-.1-.14-.1-.09-.23-.15-.37-.15-.29,0-.53.23-.53.53v.03c-.02-.1-.08-.19-.14-.27-.1-.1-.23-.16-.38-.16-.29,0-.53.23-.54.52-.1-.1-.24-.16-.4-.16-.3,0-.55.25-.55.55,0,.02,0,.05,0,.07-.09-.19-.28-.32-.5-.32-.31,0-.55.25-.55.55v.03s-.02-.03-.03-.04c-.1-.1-.24-.16-.4-.16-.25,0-.47.17-.54.4-.01-.02-.03-.03-.04-.05-.1-.1-.25-.16-.4-.16-.27,0-.51.2-.55.46-.01-.02-.03-.03-.05-.05-.12-.12-.27-.19-.44-.19-.35,0-.64.29-.64.64,0,.01,0,.03,0,.04-.12-.09-.25-.14-.4-.14-.36,0-.66.29-.66.66,0,.14.04.27.12.38-.1-.06-.22-.1-.34-.1-.38,0-.68.31-.68.68,0,.27.15.49.37.6-.06-.01-.12-.02-.18-.02-.36,0-.66.29-.66.66,0,.32.23.59.55.65ZM90.26,60.47c0-.25.21-.46.46-.46s.46.21.46.46-.21.46-.46.46-.46-.21-.46-.46ZM91.02,61.87c-.23,0-.4-.18-.4-.4s.18-.4.4-.4.4.18.4.4-.18.4-.4.4ZM91.44,62.77c-.23,0-.41-.18-.41-.4s.18-.41.41-.41.4.18.4.41-.18.4-.4.4ZM91.42,60.93c-.21-.75-.25-1.59.23-2.25.27-.38.64-.56.98-.71-.55.65-.85,1.44-.79,2.25.04.46.18.91.38,1.34.17.37.39.72.64,1.05.04.06.02.16-.07.14-.11-.01-.23,0-.33.02-.06.01-.12,0-.16-.06-.39-.55-.71-1.15-.89-1.78ZM93.35,61.79c-.13-.05-.03-.3.1-.4-.18,0-.28.22-.31.33-.04.23-.23.34-.5.33-.23-.38-.43-.79-.55-1.22.96.1,1.51-.17,2.08-.59.46-.23.9-.37,1.29-.19.01.68.51.85.77,1.45.12.27.01.53-.2.56-.26.02-.66-.29-.96-.7-.1.15-.45.21-.42-.11-.14,0-.07.31-.29.37-.16,0-.1-.25-.13-.36-.2-.02-.18.33-.38.36-.25,0-.01-.31.04-.43-.21.05-.32.68-.55.58ZM112.45,65.19c-.36.05-.87-.21-.97-.25-.21-.08-.6-.03-.41.25-2.39-.66-4.83-.99-7.27-.99-2.1,0-4.2.25-6.27.73-.19.05-.1-.01-.21-.05-.06-.03-.12.02-.29.03-.21.01-.17-.12-.08-.23.08-.09.18-.12.18-.16-.14.04-.2.05-.25.04-.08-.02-.02-.16-.17-.12-.12.03-.27.1-.27.03,0-.06.08-.18.16-.21,1.45-.42,2.95-.72,4.47-.87.1.05.29.2.31.25,0-.05.16-.23.25-.3.72-.06,1.45-.09,2.17-.09s1.45.03,2.18.09c.09.08.25.25.25.3.01-.05.21-.21.3-.25,1.89.2,3.74.59,5.49,1.2-.36-.01-.74-.13-1.09-.23-.03.13.74.33.93.32.08,0,.39.04.64.19.2.12.32.27-.04.32ZM113.8,64.66c-.08.21-.44.29-.63.21-2.91-1.17-6.14-1.76-9.37-1.76s-6.46.59-9.38,1.76c-.2.08-.55,0-.63-.21-.01-.03-.02-.07-.02-.11,0-.34-.21-.34.05-.55.07-.07.13-.15.16-.25.04-.09-.08-.14-.12-.05-.03.08-.08.14-.14.2-.2.18-.28-.03-.43-.15-.09-.08-.19-.14-.29-.18-.13-.05-.27-.06-.38-.02-.13.04-.24.14-.32.32,0,.01,0,.05,0,.07.03.05.05.1.05.16,0,.05-.01.1-.03.14-.02.04-.05.08-.09.1-.05.03-.1.05-.16.05-.01,0-.03,0-.05,0-.1-.01-.16-.08-.2-.16-.04-.1-.05-.21-.05-.32,0-.08,0-.14.01-.2.03-.23.14-.43.3-.57.12-.12.26-.2.41-.23.15-.04.3-.03.44.03.14.06.27.18.38.36.02.04.08.05.11.01.07-.09.14-.16.23-.21.08-.05.17-.08.29-.07.15,0,.26.04.35.1.05.05.1.11.13.18.03.07.04.14.04.23,0,.16-.06.33-.17.47-.03.04,0,.1.05.1.21,0,.43-.03.64-.13.17-.08.33-.21.46-.41.02-.03,0-.09-.03-.1-.16-.05-.25-.16-.29-.27-.03-.08-.03-.15-.02-.23.01-.08.04-.14.08-.21.08-.1.2-.17.36-.17.1,0,.18.03.24.07.07.04.12.1.15.16.04.07.05.14.05.22,0,.08-.02.16-.07.24-.02.03,0,.09.03.1.52.16.94.18,1.32.06.38-.11.7-.36,1-.76.03-.05-.03-.12-.08-.1-.33.16-.6.1-.78-.06-.09-.08-.16-.19-.2-.3-.04-.12-.05-.24-.03-.35.03-.21.17-.39.44-.44.03,0,.05-.04.05-.07-.02-.23.06-.4.19-.52.08-.06.16-.1.25-.12.1-.02.19-.02.28,0,.17.05.32.16.4.38,0,.03.05.05.08.04.27-.07.48.03.59.19.07.1.11.23.12.37,0,.13-.02.27-.08.39-.11.21-.33.36-.69.33-.07,0-.1.09-.05.12.38.25.85.37,1.31.31.4-.05.79-.25,1.09-.64.03-.04,0-.11-.05-.11-.2-.01-.32-.13-.38-.27-.02-.06-.03-.13-.03-.2,0-.07.01-.13.04-.19.07-.14.2-.24.4-.24.16,0,.28.08.36.18.04.06.07.13.08.21.01.08,0,.15-.02.22-.04.12-.14.23-.29.27-.05.02-.06.1-.01.12.47.28.92.43,1.33.39.41-.05.79-.28,1.12-.76.03-.05-.04-.14-.1-.1-.05.04-.1.05-.15.05-.05,0-.1-.02-.15-.05-.04-.03-.08-.08-.1-.14-.03-.06-.03-.14-.02-.22.02-.06-.07-.11-.11-.06-.05.05-.11.08-.16.08-.04,0-.08,0-.12-.02-.04-.01-.08-.04-.12-.07-.07-.07-.12-.15-.12-.25,0-.14.05-.26.16-.35.12-.1.27-.16.43-.15.03,0,.06-.03.06-.06.02-.14.08-.25.15-.33.08.15.23.25.42.26-.13.53-.12.49-.69.62.27,0,.52,0,.7.21.18-.21.43-.22.7-.21-.57-.13-.56-.09-.69-.62.18,0,.33-.11.42-.26.08.08.13.19.15.33,0,.03.03.06.06.06.17,0,.31.06.42.17.11.12.18.28.18.44s-.05.29-.13.39c-.07.09-.16.15-.27.19-.1.05-.22.07-.33.07-.14,0-.27-.03-.36-.11-.05-.04-.14.04-.1.1.33.49.71.72,1.12.77.41.05.85-.1,1.33-.38.05-.03.04-.1-.01-.12-.16-.04-.25-.15-.29-.27-.02-.07-.03-.14-.01-.22,0-.08.03-.14.08-.21.07-.1.19-.18.36-.18.2,0,.33.1.39.24.03.06.05.12.05.19s0,.14-.03.2c-.05.14-.18.25-.38.27-.05,0-.08.07-.05.11.31.38.7.58,1.09.64.46.06.92-.06,1.3-.31.05-.03.02-.13-.04-.12-.36.03-.59-.13-.69-.34-.06-.12-.08-.25-.08-.38,0-.13.05-.26.12-.36.12-.16.32-.27.6-.2.03,0,.07-.01.08-.04.08-.22.23-.33.4-.38.09-.02.18-.02.28,0,.09.02.17.06.25.12.13.12.21.29.19.52,0,.03.03.06.05.07.27.06.42.25.44.45.02.11,0,.23-.04.35-.04.12-.11.22-.21.3-.18.15-.45.21-.77.05-.06-.03-.12.05-.09.1.3.4.62.66,1,.77.38.12.81.1,1.32-.06.04,0,.06-.06.04-.1-.05-.08-.08-.16-.08-.24,0-.08.02-.15.05-.22.04-.07.09-.12.15-.16.07-.04.15-.07.25-.07.16,0,.28.07.35.17.05.06.08.13.09.21,0,.08,0,.15-.02.23-.04.12-.13.23-.29.27-.04,0-.05.06-.03.1.13.2.29.33.46.41.36.25,1.44.18,1.2.68ZM96.19,58.31c.11,0,.21.05.29.12.08.08.12.18.12.29,0,.23-.18.41-.41.41-.12,0-.22-.05-.29-.12-.08-.08-.12-.18-.12-.29,0-.23.18-.41.41-.41ZM95.7,57.74c0-.23.18-.4.41-.4.11,0,.21.04.29.12.08.08.12.18.12.29,0,.23-.18.41-.4.41-.12,0-.22-.05-.29-.12-.08-.08-.12-.18-.12-.29ZM96.59,59.29c.11,0,.21.04.28.12.08.07.12.17.12.28,0,.21-.18.39-.4.39-.11,0-.21-.04-.27-.12-.08-.07-.12-.16-.12-.27,0-.22.18-.4.39-.4ZM97.14,60.18c.21,0,.37.16.37.37s-.16.38-.37.38c-.1,0-.2-.04-.27-.11-.07-.07-.11-.16-.11-.27,0-.21.17-.37.38-.37ZM99.2,58.24s.08-.04.15-.14c.1-.12.23-.27.4-.12-.02.48.16-.07.42-.03,0,.56,0,.02.38.03,0,.02-.23.39.04.27.08-.03.16-.16.25-.17.04,0,.09.06.11.14,0-.16.27-.32.39-.29.1.18.16.76.17,1.33,0,.65-.07,1.15-.44,1.27-.26.08-.33.16-.61.12-.05,0-.16-.33-.05-.42-.15.03-.42.05-.42-.24,0-.09.07-.1.15-.17-.14,0-.22.1-.31.13-.12.04-.22-.01-.02-.29-.08.03-.19.14-.28.08-.16-.09,0-.13.02-.24-.05.05-.23.13-.28.12-.25-.02.05-.3.06-.33-.12.05-.18.14-.27.15-.16.02-.26-.03-.04-.35-.14.03-.18.09-.24.17-.05-.07,0-.19.08-.28-.18.06-.26.31-.42.25-.14-.04-.29-.18-.23-.36.13-.4.55-.45.81-.78.02-.03.16-.22.19-.14.01.04-.03.18-.02.27ZM102.7,62.01c0-.16.12-.28.28-.28s.29.12.29.28-.13.29-.29.29-.28-.13-.28-.29ZM102.88,59.94c-.03-.08-.06-.15-.08-.25-.05-.23-.09-.53-.1-.86-.01-.38,0-.81.01-1.24.01-.21.04-.65.1-1.09.05-.29.2-.58.49-.7.05.2.21.36.42.39-.25.05-.44.27-.44.53,0,.28.22.51.49.53-.29.02-.53.27-.53.57s.24.55.54.57c-.29.01-.52.26-.52.55,0,.27.19.49.45.54-.22.05-.38.25-.38.48,0,.03,0,.05,0,.08-.11.1-.19.23-.23.4-.08,0-.16.03-.24.05.15-.21.09-.36.01-.56ZM104.32,55.57c.2.13.35.25.4.49.02.1.04.2.05.3.08.49.12,1,.13,1.23.02.42.03.85.01,1.24-.01.33-.05.64-.1.86-.02.1-.05.17-.08.25-.08.21-.14.36.02.57-.08-.03-.16-.05-.25-.06-.03-.17-.12-.31-.23-.4,0-.03,0-.05,0-.08,0-.23-.16-.43-.38-.48.26-.05.45-.27.45-.54,0-.29-.23-.54-.52-.55.3-.01.54-.27.54-.57s-.23-.55-.53-.57c.27-.03.49-.25.49-.53,0-.26-.19-.48-.44-.53.29-.05.48-.33.42-.62ZM104.23,57.82c0,.24-.19.43-.43.43s-.43-.19-.43-.43.19-.44.43-.44.43.2.43.44ZM103.41,56.72c0-.22.18-.4.4-.4s.4.18.4.4-.18.4-.4.4-.4-.18-.4-.4ZM104.22,58.94c0,.23-.19.42-.42.42s-.42-.19-.42-.42.19-.42.42-.42.42.19.42.42ZM104.15,59.96c0,.19-.16.35-.35.35s-.35-.16-.35-.35.16-.36.35-.36.35.16.35.36ZM103.8,56.07c-.21,0-.39-.18-.39-.4s.18-.39.39-.39.39.18.39.39-.18.4-.39.4ZM106.56,57.69c-.03-.16.06-.57.3-.28.27.36.14.25.23.32.05.04.08.12.1.12.1.01,0-.13.12-.11.23.05.25.48.4.57.31.18.52-.1.56-.27.06-.27.12-.18.17-.02.05.16-.01.21.04.16.03-.02.08-.15.14-.21,0,.19.09.25.1.16.03-.13.08-.22.2-.19.07,0,.12.08.13.21,0,.02.12-.05.17-.02.14.08.37,1.53-.14,1.22-.39-.03-.77.25-.96.51-.61.61-1.14-.83-1.27-.27-.07.18-.05.4-.27.27.02-.57-.24-1.11-.06-1.67.03-.13.07-.25.03-.49ZM111.13,58.43c.08-.08.18-.12.29-.12.23,0,.41.18.41.41,0,.12-.05.22-.12.29-.07.07-.17.12-.29.12-.23,0-.41-.18-.41-.41,0-.11.05-.21.12-.29ZM111.09,57.74c0-.11.04-.21.12-.29.08-.08.18-.12.29-.12.23,0,.41.18.41.4,0,.12-.04.22-.12.29-.08.07-.18.12-.29.12-.22,0-.4-.18-.4-.41ZM111.02,59.29c.21,0,.39.18.39.4,0,.11-.04.21-.12.27-.07.08-.16.12-.27.12-.22,0-.4-.18-.4-.39,0-.11.04-.21.12-.28.07-.08.17-.12.28-.12ZM110.84,60.54c0,.1-.04.2-.11.27-.07.07-.16.11-.27.11-.21,0-.37-.17-.37-.38s.16-.37.37-.37.38.16.38.37ZM111.92,61.96c.03-.13.13-.2.27-.21.09-.16.11-.38.32-.46.17-.07.27-.21.37-.36.12-.19.21-.4.46-.41.19-.01.21.12.34.15.31.08.47.27.39.49-.04.11-.3.22-.41.32-.21.21-.12.85-.29.91-.28.1-.24-.31-.72-.25-.3.04-.81.12-.73-.18ZM114.07,63.97c-.1.1-.23.16-.39.16-.3,0-.55-.25-.55-.55,0-.15.07-.29.16-.39.1-.1.24-.16.39-.16.31,0,.55.25.55.55,0,.16-.06.29-.16.4ZM114.85,63.28c-.16.18-.29.25-.39.25-.07,0-.11-.06-.13-.12-.03-.12.01-.29.14-.45.34-.42.67-.9.9-1.4.21-.43.34-.88.38-1.34.07-.81-.23-1.59-.78-2.24-.14-.16.09-.51.29-.34.34.31.63.69.83,1.16.29.7.29,1.43.1,2.13-.24.85-.74,1.66-1.34,2.35ZM116.58,62.37c0,.22-.18.4-.41.4s-.4-.18-.4-.4.18-.41.4-.41.41.18.41.41ZM116.99,61.47c0,.23-.18.4-.4.4s-.4-.18-.4-.4.18-.4.4-.4.4.18.4.4ZM117.34,60.47c0,.25-.21.46-.46.46s-.46-.21-.46-.46.21-.46.46-.46.46.21.46.46ZM116.92,58.72c.29,0,.52.24.52.53s-.23.53-.52.53-.53-.24-.53-.53.23-.53.53-.53ZM116.43,57.47c.3,0,.55.25.55.54s-.25.55-.55.55-.54-.25-.54-.55.25-.54.54-.54ZM115.19,56.68c.1-.1.23-.16.37-.16.29,0,.53.24.53.53,0,.14-.06.27-.16.37-.1.1-.23.16-.37.16-.29,0-.53-.24-.53-.53,0-.14.06-.27.16-.37ZM114.18,56.13c.09-.09.21-.14.35-.14.27,0,.5.23.5.5,0,.14-.05.26-.14.35-.09.09-.22.15-.36.15-.27,0-.5-.23-.5-.5,0-.14.06-.26.15-.36ZM113.17,55.89c.08-.08.18-.12.31-.12.23,0,.43.19.43.43,0,.12-.05.23-.13.3-.08.08-.18.13-.3.13-.24,0-.43-.2-.43-.43,0-.12.05-.23.12-.31ZM114.01,57.31c.3.19.56.42.79.66.58.64.89,1.42.82,2.23-.01.23-.06.46-.13.69-.18-.05-.37-.12-.43-.19-.26-.31-.63-.46-1.05-.55-.21-.04-.44-.06-.68-.08-.01-.26-.05-.53-.22-.84-.24-.05-.48-.08-.72-.09.05-.18.08-.36.1-.54.06-.48.05-.97,0-1.56,0-.03,0-.04,0-.05,0-.11-.01-.22-.04-.33.58.13,1.11.35,1.55.64ZM112.2,55.71c.08-.08.18-.12.3-.12.24,0,.43.19.43.43,0,.12-.05.23-.12.3h0c-.08.08-.18.13-.3.13-.24,0-.43-.2-.43-.43,0-.12.05-.23.13-.31ZM112.01,56.59c.01-.08.04-.14.1-.14.23.03.25.32.27.55.03.53.06,1.07,0,1.6-.06.46-.19.92-.44,1.44-.19.42-.45.89-.71,1.22-.12.16-.25.29-.36.36-.1.06-.19.08-.27.03-.02-.01-.04-.03-.06-.05-.07-.09-.1-.15-.11-.2,0-.04.02-.08.06-.12.23-.22.46-.51.67-.82.22-.33.41-.69.57-1.06.15-.34.25-.72.29-1.11.05-.44.05-.9,0-1.35-.01-.1-.03-.24-.01-.35ZM111.51,55.21c.23,0,.42.18.42.41s-.18.42-.42.42-.41-.18-.41-.42.18-.41.41-.41ZM111.12,56.4c.08-.08.18-.12.29-.12.23,0,.42.18.42.42,0,.12-.04.22-.12.29-.08.08-.18.12-.29.12-.23,0-.42-.18-.42-.42,0-.12.05-.22.12-.29ZM110.9,58.33c-.08.57-.3,1.13-.68,1.69-.04.06-.08.12-.11.18-.12.21-.24.41-.53.34-.1-.03-.17-.05-.19-.1-.02-.05.01-.14.13-.3.12-.18.25-.36.36-.54.11-.18.21-.38.28-.59.14-.38.21-.77.23-1.15.01-.39-.03-.78-.15-1.18-.04-.15-.13-.27-.11-.41.01-.1.03-.19.2-.2.08,0,.14.05.21.12.1.1.16.25.2.36.19.57.25,1.18.16,1.79ZM110.47,54.91c.23,0,.41.19.41.42s-.18.42-.41.42-.42-.19-.42-.42.18-.42.42-.42ZM109.25,54.68c.08-.08.18-.12.29-.12.23,0,.41.18.41.4,0,.12-.05.22-.12.29-.08.08-.18.12-.29.12-.23,0-.41-.18-.41-.41,0-.11.05-.21.12-.29ZM108.21,54.54c.07-.07.17-.11.27-.11.22,0,.39.17.39.39,0,.1-.04.2-.11.27-.08.07-.17.12-.28.12-.21,0-.39-.18-.39-.39,0-.11.05-.21.12-.28ZM107.23,54.4c.07-.07.16-.11.27-.11.21,0,.39.17.39.39,0,.1-.04.21-.12.27-.07.07-.16.12-.27.12-.21,0-.39-.18-.39-.39,0-.11.04-.21.12-.28ZM106.26,54.26c.07-.07.16-.11.27-.11.21,0,.38.17.38.38,0,.1-.05.2-.12.27-.07.07-.16.11-.27.11-.21,0-.39-.17-.39-.38,0-.1.05-.2.12-.27ZM105.63,54.08c.2,0,.36.16.36.36s-.16.36-.36.36-.37-.16-.37-.36.16-.36.37-.36ZM105.46,55.07c.18.03.36.07.55.13.44.13.81.23,1.18.29.14.02.29.04.44.05.25.02.5.03.79.03.44,0,.81.08,1.09.26.27.18.48.46.59.87.1.32.14.64.15.96-.04,0-.08,0-.12-.01-.8-.08-.89-.72-1.48-.93-.27-.1-.67-.1-1.03-.07-.1.01-.2.03-.29.04-.4.08-.68-.08-1.07-.21-.25-.08-.51-.16-.79-.23-.1-.44-.25-.84-.44-1.18,0-.01-.02-.03-.03-.05.15.01.29.03.43.05ZM104.73,54.81c.09.09.16.22.23.33.28.49.44,1.12.55,1.78.1.66.13,1.33.13,1.91,0,.42-.02.78-.07,1.06-.05.27-.12.48-.22.6-.01.02-.03.04-.05.05-.05.05-.11.08-.16.08-.05,0-.1-.02-.15-.05-.01-.01-.03-.03-.05-.04-.21-.21-.16-.35-.09-.54.03-.08.06-.16.09-.26.05-.24.09-.55.1-.89.02-.39.01-.83-.01-1.25-.01-.23-.04-.74-.12-1.24-.08-.51-.22-1-.44-1.14-.19-.12-.24-.36-.01-.46.1-.04.2,0,.28.08ZM103.8,53.1c.47,0,.85.38.85.86s-.38.86-.85.86-.85-.39-.85-.86.38-.86.85-.86ZM102.92,54.81c.46-.14.21.36.1.52-.15.22-.25.61-.31,1.01-.08.5-.11,1.02-.12,1.24-.03.42-.03.86-.01,1.25.01.34.05.65.1.89.03.1.05.18.09.26.08.19.12.33-.09.54-.01.01-.03.03-.05.04-.05.03-.1.05-.15.05-.05,0-.1-.03-.16-.08-.01-.01-.03-.03-.05-.05-.1-.12-.16-.33-.22-.6-.05-.28-.08-.64-.07-1.06,0-.55.01-.93.08-1.28.08-.36.2-.7.41-1.18.05-.12.09-.32.14-.55.05-.29.12-.61.22-.83.03-.06.06-.12.1-.16ZM101.98,54.08c.21,0,.37.16.37.36s-.16.36-.37.36-.36-.16-.36-.36.16-.36.36-.36ZM101.07,54.15c.11,0,.21.04.27.11.07.08.12.17.12.27,0,.21-.18.38-.39.38-.1,0-.2-.04-.27-.11-.07-.08-.12-.17-.12-.27,0-.21.18-.38.38-.38ZM100.11,54.29c.11,0,.21.04.27.11.08.08.12.17.12.28,0,.21-.18.39-.39.39-.11,0-.21-.05-.27-.12-.08-.07-.12-.17-.12-.27,0-.22.18-.39.39-.39ZM99.12,54.43c.1,0,.2.04.27.11.07.08.12.17.12.28,0,.21-.18.39-.39.39-.11,0-.21-.05-.27-.12-.08-.08-.12-.17-.12-.27,0-.22.17-.39.39-.39ZM99.16,55.58c.31,0,.58-.01.83-.04.14-.01.27-.03.4-.05.38-.06.74-.16,1.18-.29.19-.06.38-.1.55-.13.17-.03.35-.04.53-.06-.08.23-.14.51-.19.77-.05.22-.09.42-.13.52-.01.02-.02.05-.03.07-.45.22-.75.64-1.23.78-.19.05-.43-.03-.7-.07-.12-.02-.25-.02-.38-.01-.55.05-1.13.34-1.46.77-.41.53-.72.75-1.06.88-.08-.29-.13-.58-.14-.87-.01-.37.03-.75.14-1.13.12-.41.32-.69.59-.87.28-.18.64-.26,1.09-.26ZM98.07,54.56c.11,0,.21.04.29.12.08.08.12.18.12.29,0,.23-.18.41-.41.41-.11,0-.21-.05-.29-.12-.08-.07-.12-.17-.12-.29,0-.23.18-.4.41-.4ZM97.13,54.91c.23,0,.42.19.42.42s-.18.42-.42.42-.41-.19-.41-.42.18-.42.41-.42ZM96.87,56.54c.03-.11.1-.26.2-.36.06-.07.13-.12.21-.12.16,0,.18.1.2.2.02.14-.07.26-.11.41-.12.4-.16.79-.15,1.18.02.39.1.77.23,1.15.08.22.17.41.29.59.11.18.23.36.36.54.12.16.15.25.13.3-.02.05-.09.08-.19.1-.29.07-.41-.13-.53-.34-.03-.05-.07-.12-.11-.18-.38-.55-.59-1.12-.68-1.69-.09-.61-.03-1.22.16-1.79ZM96.61,56.7c0,.23-.18.42-.42.42-.12,0-.22-.05-.29-.12-.08-.08-.12-.18-.12-.29,0-.23.18-.42.42-.42.12,0,.22.05.29.12.08.08.12.18.12.29ZM96.09,55.21c.23,0,.41.18.41.41s-.18.42-.41.42-.42-.18-.42-.42.18-.41.42-.41ZM95.6,56.59c.01.11,0,.25-.01.35-.05.44-.05.9,0,1.35.04.39.14.77.29,1.11.16.37.36.73.57,1.06.2.31.44.6.67.82.04.05.07.08.06.12,0,.05-.04.11-.11.2-.02.02-.04.04-.06.05-.08.05-.16.03-.27-.03-.12-.08-.24-.21-.36-.36-.26-.33-.52-.81-.71-1.22-.25-.52-.38-.97-.44-1.44-.06-.53-.03-1.07,0-1.6.02-.23.03-.51.27-.55.06,0,.09.05.1.14ZM95.11,55.58c.12,0,.23.05.3.12.08.08.13.18.13.31,0,.23-.19.43-.43.43-.12,0-.23-.05-.3-.13h0c-.08-.08-.12-.18-.12-.3,0-.24.19-.43.43-.43ZM94.13,55.77c.12,0,.23.05.31.12.08.08.12.18.12.31,0,.23-.19.43-.43.43-.12,0-.23-.05-.3-.13-.08-.08-.13-.18-.13-.3,0-.24.2-.43.43-.43ZM95.13,56.67c-.03.11-.03.22-.04.33,0,.01,0,.03,0,.05-.04.59-.05,1.09,0,1.56.01.14.04.27.07.42-.6-.16-1.11.03-1.59.38h0c-.58.42-.85.63-1.6.44.03-.68.33-1.34.83-1.88.22-.25.48-.46.77-.66h0c.45-.29.98-.52,1.57-.65ZM93.08,55.99c.14,0,.26.05.35.14.09.1.15.22.15.36,0,.27-.23.5-.5.5-.14,0-.27-.06-.36-.15-.09-.09-.14-.21-.14-.35,0-.27.23-.5.5-.5ZM92.05,56.52c.14,0,.27.06.37.16.1.1.16.23.16.37,0,.29-.24.53-.53.53-.14,0-.27-.06-.37-.16-.1-.1-.16-.23-.16-.37,0-.29.24-.53.53-.53ZM90.63,58.01c0-.29.25-.54.55-.54s.54.25.54.54-.25.55-.54.55-.55-.25-.55-.55ZM90.68,58.72c.29,0,.53.24.53.53s-.23.53-.53.53-.52-.24-.52-.53.23-.53.52-.53Z\"><\/path><path class=\"cls-10\" d=\"M119.19,96.82s0,0,0,0l.07-.08-.08-.02v.11Z\"><\/path><path class=\"cls-10\" d=\"M100.28,103.13c-.05.12-.03.26.06.36.07.07.16.1.24.14-.14.28-.33.41-.66.38-.35-.04-.62-.2-.79-.42-.09-.11-.15-.23-.18-.36-.03-.13-.05-.27-.03-.4.03-.29.19-.59.48-.81.31-.25.94-.46,1.51-.65.23-.08.44-.14.62-.21.27-.1.4-.3.42-.49.01-.12-.03-.26-.14-.33-.1-.06-.24-.06-.42.05-.4.23-.77.38-1.15.52-.2.08-.41.16-.62.25-.49.22-.89.57-1.14.99-.31.51-.43,1.13-.18,1.67.14.3.37.57.73.79.38.24.85.29,1.25.18.33-.09.65-.28.83-.57.21-.33.22-.88-.06-1.18-.22-.23-.62-.21-.75.1Z\"><\/path><path class=\"cls-10\" d=\"M108,101.15c-.21-.1-.42-.17-.62-.25-.38-.14-.75-.29-1.15-.52-.26-.15-.57-.16-.88-.15.21.23.33.47.57.69.1.1.18.17.27.24.16.11.33.16.51.22.57.18,1.21.39,1.52.64.29.23.44.52.48.81.03.27-.05.55-.22.77-.17.22-.44.38-.79.42-.32.03-.52-.1-.66-.38.08-.03.17-.07.24-.14.09-.1.12-.23.06-.36-.13-.31-.53-.32-.75-.1-.28.29-.27.85-.06,1.18.18.29.5.49.83.57.4.1.87.05,1.25-.18.36-.22.59-.49.73-.79.25-.55.12-1.17-.18-1.67-.25-.42-.66-.77-1.14-.99Z\"><\/path><path class=\"cls-10\" d=\"M106.48,102.94c.09-.09.19-.14.29-.17.11-.03.21-.03.31,0,.09.03.17.08.24.14.05.05.1.12.12.18.03.08.05.16.03.25-.01.09-.05.17-.12.25-.04.03-.09.08-.15.11.04.06.1.1.15.13.09.05.19.05.3.05.31-.04.55-.18.71-.37.08-.1.13-.2.16-.31.03-.12.04-.23.03-.36-.03-.26-.16-.52-.42-.72-.29-.23-.92-.43-1.48-.62-.08-.03-.16-.05-.2-.06-.14-.05-.25-.1-.35-.17-.1-.07-.18-.15-.29-.25-.11-.11-.21-.22-.31-.33h0c-.08-.03-.16-.05-.23-.07-.03,0-.06-.02-.1-.03h0c.16.1.32.23.46.36.46.46.76,1.1.76,1.8,0,.12,0,.25-.03.38.03-.07.08-.13.12-.18Z\"><\/path><path class=\"cls-10\" d=\"M107.36,97.36c5.68-1.56,9.87-6.78,9.87-12.94s-4.19-11.36-9.87-12.93c-.64-.18-1.3-.31-1.98-.39-.1-.01-.2-.02-.29-.03v4.5c-.42-.06-.85-.1-1.28-.1s-.87.03-1.28.1v-4.5c-6.79.66-12.14,6.4-12.14,13.35s5.64,13.03,12.7,13.41v-1.43c-6.28-.38-11.28-5.61-11.28-11.98,0-5.67,3.97-10.43,9.27-11.68v3.16c-2.41.78-4.39,2.55-5.43,4.83l1.27.64c.28-.62.64-1.2,1.07-1.72v9.56c-.81-.99-1.37-2.18-1.61-3.49l-1.39.29c.75,4.18,4.42,7.38,8.82,7.38.53,0,1.07-.05,1.58-.14.69-.12,1.35-.33,1.98-.59,3.18-1.39,5.41-4.55,5.41-8.23,0-2.71-1.22-5.15-3.14-6.79v-3.68c3.68,2.06,6.18,5.98,6.18,10.48,0,5.38-3.56,9.94-8.45,11.47-.64.2-1.3.34-1.98.43-.29.04-.57.07-.86.08v1.43c.29-.02.57-.04.86-.08.68-.08,1.33-.21,1.98-.39ZM106.54,72.74c.28.07.55.14.82.23.28.09.55.18.82.29v3.36c-.27-.15-.54-.29-.82-.41-.27-.12-.54-.22-.82-.31v-3.16ZM111.34,84.42c0,2.87-1.62,5.37-3.98,6.65-.62.33-1.28.57-1.98.72-.51.11-1.04.17-1.58.17-1.63,0-3.14-.53-4.37-1.41v-12.26c.51-.36,1.05-.66,1.64-.9v6.04h1.45v-6.44c.42-.07.85-.11,1.28-.11s.87.04,1.28.11v11.55h1.45v-11.15c.28.12.55.24.82.38.29.16.56.33.82.51v5.18h1.45v-3.83c1.07,1.31,1.72,2.97,1.72,4.78Z\"><\/path><path class=\"cls-10\" d=\"M105.54,101.37c-.46-.14-.92-.27-1.39-.35-.33-.06-.17.06-.33.33-.14.24-.28.49-.44.74-.12.21-.25.41-.39.62-.04.07-.05.12.01.16.1.05.23.06.33.07.59.05,1.15.34,1.64.66.14.08.38.29.52.3.07.01.13-.02.21-.12h0c.08-.11.17-.21.23-.33.16-.29-.07-.53-.31-.67-.56-.31-1.16-.55-1.78-.72-.09-.03-.05-.16.03-.13.55.16,1.09.36,1.6.62.29.15.48-.16.53-.4.08-.36-.11-.68-.46-.79Z\"><\/path><path class=\"cls-10\" d=\"M103.87,100.54c0,.1.04.31.15.33.45.06.9.18,1.33.31.06.02.13.02.17-.04.01-.02.03-.08,0-.1-.42-.41-.98-.67-1.6-.7t0,0c-.05.03-.06.13-.05.21Z\"><\/path><path class=\"cls-10\" d=\"M102.46,104.24c.18,0,.36-.01.51-.04.33-.05.95-.23,1.13-.56.08-.13.02-.35-.12-.4-.33-.13-.77-.22-1.13-.18-.13.01-.25.06-.37.08-.04,0-.08.01-.12.01-.22.01-.44-.08-.6-.23-.07-.07.02-.16.09-.1.14.13.33.2.51.19.05,0,.09,0,.13-.02.12-.03.24-.1.31-.22.17-.25.33-.51.48-.75.15-.25.3-.49.44-.74.14-.26.16-.63-.11-.8-.01,0-.02-.01-.03-.01-.1-.05-.41-.05-.36.13.03.12.18.19.21.33.01.09,0,.18-.07.32-.16.36-.36.7-.57,1.03-.05.08-.16,0-.11-.08.21-.32.4-.65.56-1,.05-.12.07-.18.05-.24-.01-.08-.12-.2-.18-.25-.18-.13-.42-.08-.62.03-.16.08-.3.2-.4.29-.44.44-.72,1.04-.72,1.71,0,.41.1.8.29,1.13.16.26.49.35.82.36h0ZM102.22,101.85c.07-.1.14-.2.21-.3.01-.02.03-.05.05-.07h0c.05-.08.1-.16.14-.23.05-.08.16-.01.11.07-.06.1-.12.21-.18.31-.03.03-.05.06-.07.1h0c-.05.07-.1.14-.14.21-.06.08-.17,0-.11-.08Z\"><\/path><path class=\"cls-10\" d=\"M101.79,101.15c-.06.05-.14.09-.22.12-.18.07-.4.14-.63.22-.55.18-1.18.39-1.47.62-.26.21-.4.46-.42.72-.01.12,0,.24.03.36.03.12.08.22.16.31.24.3.77.45.96.01-.03-.05-.05-.12-.07-.18-.01-.09,0-.18.03-.25.03-.07.07-.13.12-.18.07-.06.15-.11.24-.14.1-.02.21-.02.31,0,.1.03.21.08.29.17.05.05.09.11.12.18-.02-.12-.03-.25-.03-.38,0-.6.21-1.15.57-1.59Z\"><\/path><path class=\"cls-10\" d=\"M104.34,99.78c-.16,0-.33,0-.49,0-.02,0-.03,0-.05,0h0c-.16,0-.33,0-.5,0-.25,0-.44.3-.19.51.22-.06.45-.1.69-.1.54,0,1.09.18,1.61.32-.17-.27-.74-.74-1.07-.73Z\"><\/path><path class=\"cls-10\" d=\"M98.35,102.07c.27-.44.69-.81,1.2-1.05.22-.1.43-.17.64-.25.38-.14.74-.29,1.13-.51.03-.01.05-.03.08-.04.04-.09.05-.17.02-.25-.14,0-.26.02-.36.03-.23.03-.31.02-.33-.23,0-.05,0-.12-.01-.21-.1.04-.18.08-.25.11-.09.05-.16.1-.23.14-.01.01-.05.01-.07,0-.21-.09-.43-.17-.66-.21-.22-.05-.44-.06-.66-.03-.05.01-.1-.05-.06-.1.05-.08.1-.15.16-.23.02-.03.04-.05.07-.08-.04,0-.08.01-.12.03-.1.02-.19.05-.29.08-.05.01-.1-.05-.08-.1l.14-.26c-.12,0-.25.03-.36.05-.15.03-.31.08-.46.14-.05.02-.11-.04-.08-.09l.17-.4s-.01,0-.01,0c-.18.03-.37.08-.55.12-.05,0-.09-.04-.08-.09l.08-.27s-.02-.01-.03-.02c-.01,0-.02-.01-.03-.02,0,0,0,0,0,0-.18.12-.34.19-.49.23-.14.03-.27.03-.37-.02-.11-.05-.19-.14-.24-.29-.04-.12-.05-.29-.03-.51,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0-.01,0l-.21.17s-.11,0-.11-.05l-.02-.32s-.03-.02-.04-.03c-.04.03-.09.08-.14.12-.01.01-.03.02-.03.03-.03.03-.1,0-.11-.04,0-.09,0-.17,0-.25-.07.05-.14.09-.22.12-.04.01-.09-.01-.09-.05,0-.1-.01-.21,0-.3-.02-.02-.05-.03-.07-.05-.08.04-.16.07-.25.07-.1,0-.19-.01-.27-.06-.08-.05-.15-.11-.2-.2-.06-.11-.1-.24-.08-.39-.23-.18-.45-.36-.66-.55-.09-.08-.18-.16-.27-.24-.01.08-.03.14-.06.22-.1.31-.23.57-.41.85-.15.22-.27.43-.37.68-.08.2-.23.55-.16.76.06.18.29.19.43.11.06-.16.13-.32.19-.48.08-.18.16-.36.23-.51.04-.09.16-.03.12.05-.08.16-.15.33-.23.51-.07.18-.14.36-.21.53-.03.1-.02.29.03.38.04.1.12.14.23.12.12-.03.21-.1.25-.2.05-.14.11-.28.17-.41.05-.14.12-.29.18-.44.03-.09.16-.03.12.05-.06.14-.12.28-.18.43-.06.15-.12.3-.18.45-.05.12-.08.28-.05.42.02.11.08.21.18.27.11.07.27-.06.3-.16.03-.1.06-.19.1-.29l.07-.21c.03-.09.16-.05.13.04l-.08.21c-.03.09-.06.18-.1.28-.05.14-.06.29-.04.44.03.13.08.26.18.36.07.08.13.16.23.11.07-.03.13-.09.15-.15.08-.23.16-.46.24-.7.05-.14.09-.27.12-.35.03-.09.16-.05.12.04-.05.14-.08.25-.12.35-.08.23-.16.46-.24.7-.05.15-.05.29-.02.38.04.1.12.15.23.14.14-.01.27-.12.29-.26.01-.13.03-.29.07-.46.04-.21.1-.44.16-.69.03-.09.16-.05.13.03-.06.25-.12.48-.16.68-.03.19-.06.36-.07.51,0,.1,0,.17.04.21.03.05.09.05.14.03.11-.03.17-.14.23-.25.08-.16.15-.33.21-.53.06-.23.12-.48.16-.76.01-.09.14-.07.13.02-.04.29-.1.54-.16.77-.06.21-.13.39-.22.55-.1.2-.06.62.24.38.2-.15.42-.54.55-.77.03-.07.07-.12.09-.15.05-.08.16-.01.11.07-.02.03-.05.08-.08.15-.12.2-.29.51-.49.71-.12.14-.31.37-.27.56.02.1.1.15.19.15.18,0,.31-.16.4-.3.12-.21.26-.39.4-.57.15-.2.3-.39.45-.57.06-.07.16.01.1.09-.16.18-.31.38-.44.57-.14.17-.27.36-.39.55-.08.12-.22.23-.26.37-.04.12-.03.22,0,.29.03.06.09.1.16.09.12-.01.23-.12.29-.21.19-.27.39-.53.6-.79.21-.25.43-.5.66-.74.07-.07.16.03.1.1-.23.23-.44.48-.65.73-.21.25-.4.51-.59.78-.05.09-.12.15-.18.19-.08.19-.05.41.03.55.03.04.07.08.1.1.2.1.36-.25.4-.38.12-.3.29-.56.48-.79.2-.22.42-.41.67-.58.03-.02.05-.04.1.01.03.05,0,.08-.02.1-.23.16-.46.35-.64.56-.18.22-.34.46-.45.74-.07.18-.25.35-.06.53.03.03.08.06.13.08.05.02.1.02.16.01.11-.01.22-.1.29-.27h0c.04-.28.15-.57.31-.83Z\"><\/path><path class=\"cls-10\" d=\"M111.48,99.15c-.57-.29-1.2-.46-1.67-.59h0c.03.08,0,.16,0,.25,0,.04-.05.08-.1.05-.1-.05-.18-.1-.27-.14.04.09.07.18.09.3,0,.05-.03.09-.08.08-.14-.03-.27-.07-.4-.11-.03,0-.11-.06-.14-.07.08.08.21.19.3.28.04.04-.01.13-.07.11-.22-.08-.38-.16-.57-.27.08.14.18.3.29.43.03.05-.04.14-.1.1-.2-.13-.39-.27-.57-.42,0,0,0,0,0,0,0,0-.02,0-.03,0-.02,0-.04.01-.05.02.04.11.09.22.14.32.03.06-.07.12-.11.08-.09-.11-.18-.22-.25-.33-.13.04-.26.07-.39.1.12.13.25.25.38.37.08.06-.01.16-.09.1-.16-.14-.3-.28-.44-.44-.1.02-.2.05-.3.07l.36.4c.06.07-.03.16-.1.09l-.42-.45c-.14.03-.27.05-.41.08,0,0-.01,0-.02,0,.05.04.11.09.17.13.14.1.27.2.42.29.08.05,0,.16-.08.12-.15-.1-.29-.2-.43-.3-.09-.07-.18-.14-.26-.21-.1.02-.21.03-.31.05.09.16.18.31.3.44.15.17.31.31.51.43.02.01.04.03.06.04.19.09.38.16.57.23.21.08.41.16.63.25.51.23.93.61,1.2,1.05.17.28.28.59.32.89.03.24,0,.48-.05.71.08.08.21.02.29-.03.16-.11.28-.36.35-.63.08-.31.1-.66.03-.85-.18-.49-.47-.87-.85-1.16-.38-.29-.84-.5-1.38-.63-.1-.02-.06-.15.03-.13.56.13,1.05.34,1.44.65.4.31.7.71.89,1.22.03.09.05.21.05.34,0,.08.04.14.12.18.14.09.21-.12.23-.23.08-.45-.05-.87-.29-1.22-.31-.46-.81-.81-1.28-.97-.1-.03-.05-.16.04-.12.49.16,1.02.53,1.35,1.02.27.4.41.89.28,1.41-.02.08-.03.14.02.22.02.05.07.09.12.08.25-.05.29-.49.31-.67.03-.19.04-.39.04-.59,0-.26-.04-.52-.16-.73-.18-.33-.72-.59-1.15-.81-.13-.06-.25-.12-.36-.18-.08-.04-.02-.16.06-.12.1.06.23.12.36.18.44.22,1,.5,1.21.87.13.23.17.51.18.79,0,.21-.02.42-.05.62-.01.16.11.23.23.12.2-.16.33-.48.38-.81.05-.36.03-.74-.1-.96-.14-.27-.35-.49-.6-.67-.25-.18-.55-.33-.88-.46-.09-.03-.04-.16.05-.12.33.13.65.29.91.48.27.19.49.42.65.71.1.18.14.46.13.74,0,.08-.03.12.05.17.08.06.18.1.27.01.05-.05.09-.12.12-.21.08-.22.1-.51.07-.72-.07-.57-.59-1-1.21-1.31Z\"><\/path><path class=\"cls-10\" d=\"M112.95,99.33c-.2-.23-.48-.43-.86-.6-.19-.09-.38-.21-.57-.33-.1-.07-.21-.13-.31-.21-.1-.08-.17-.12-.31-.12-.07,0-.1.02-.08.09.02.07.08.15.12.22-.09,0-.16,0-.25-.03-.11-.03-.22-.06-.24,0-.05.11.19.32.3.36.26.1.53.21.78.33.65.33,1.2.79,1.28,1.41,0,.09.01.19,0,.3.1.08.13.12.25,0,.16-.16.29-.43.25-.66-.06-.27-.17-.53-.37-.77Z\"><\/path><path class=\"cls-10\" d=\"M114.52,96.69c-.12-.16-.27-.27-.47-.29-.05,0-.11,0-.17.02-.08.01-.14.05-.17.13-.04.1.01.25.09.31.16.13.31.3.45.49.16.23.31.46.39.64.02.04.04.09.06.14.15.04.14.01.14-.12,0-.02,0-.05,0-.08,0-.17-.01-.4-.06-.62-.05-.23-.14-.46-.26-.64Z\"><\/path><path class=\"cls-10\" d=\"M114.14,97.43c-.12-.18-.27-.34-.42-.46-.09-.08-.2-.12-.3-.11-.09.01-.18.05-.25.15-.04.05-.06.1-.05.16,0,.13.18.28.27.36.29.31.59.62.85,1,.08.12.16.28.19.44.09.03.21.07.25-.04.02-.05.03-.13.03-.21-.01-.23-.11-.52-.18-.68-.08-.18-.21-.41-.38-.62Z\"><\/path><path class=\"cls-10\" d=\"M113.27,97.63c-.06-.07-.13-.13-.16-.16-.06-.07-.16-.13-.25-.15-.07-.01-.14,0-.2.05-.07.06-.17.12-.18.23-.03.22.14.29.29.43.12.11.23.22.36.32.21.18.4.38.54.62.08.14.14.28.18.44.01.07.03.13.13.14.21.01.33-.23.33-.42,0-.18-.1-.39-.2-.53-.25-.38-.55-.68-.83-.98Z\"><\/path><path class=\"cls-10\" d=\"M113.04,98.45c-.12-.1-.24-.22-.36-.33-.12-.11-.23-.23-.36-.33-.1-.08-.25-.16-.36-.18-.05,0-.12-.02-.14.04-.02.08.03.21.04.29-.12-.03-.4-.19-.36.05.05.31.4.5.65.62.4.18.7.4.91.64.21.25.33.53.4.82,0,.04.01.09.01.13h.05c.06,0,.11-.02.15-.05.04-.03.07-.08.09-.15,0-.05.01-.1.01-.16-.01-.31-.1-.58-.22-.8-.13-.23-.31-.42-.51-.59Z\"><\/path><path class=\"cls-10\" d=\"M88.96,80.45c.64-2.4,1.85-4.56,3.48-6.35,0,0,0,0,0,0,.08-.09.16-.18.25-.27,0,0,0,0,0,0,.15-.16.31-.32.48-.48.19-.18.38-.35.57-.53.01-.01.03-.02.04-.03.08-.07.15-.13.23-.19.02-.01.03-.03.05-.04.08-.07.16-.13.24-.19.01,0,.02-.02.04-.03.19-.15.38-.29.57-.43.01-.01.03-.02.04-.03.08-.06.16-.11.24-.17.03-.02.05-.04.08-.05.07-.05.14-.09.21-.14.03-.02.06-.04.09-.06.07-.04.14-.09.21-.13.03-.02.06-.04.09-.05.08-.05.17-.1.26-.15.01,0,.03-.02.04-.02.1-.06.2-.11.3-.17.03-.01.06-.03.08-.04.07-.04.15-.08.22-.12.04-.02.08-.04.11-.06.06-.03.13-.07.2-.1.04-.02.08-.04.12-.06.06-.03.13-.06.2-.09.04-.02.08-.04.12-.06.07-.03.15-.07.22-.1.03-.01.06-.03.1-.04.1-.04.21-.09.31-.13.03-.01.07-.03.1-.04.07-.03.15-.06.22-.08.04-.02.09-.03.13-.05.07-.02.13-.05.2-.07.05-.02.09-.03.14-.05.07-.02.13-.04.2-.06.05-.01.09-.03.14-.04.07-.02.14-.04.22-.06.04-.01.08-.02.12-.03.11-.03.22-.06.33-.09.03,0,.06-.02.1-.02.08-.02.16-.04.25-.06.04-.01.09-.02.13-.03.07-.02.14-.03.21-.05.05,0,.1-.02.14-.03.07-.01.14-.03.21-.04.05,0,.09-.02.14-.03.08-.01.16-.03.23-.04.04,0,.08-.01.12-.02.12-.02.23-.03.35-.05.02,0,.04,0,.06,0,.1-.01.2-.02.3-.03.04,0,.08,0,.13-.01.08,0,.16-.01.24-.02.05,0,.09,0,.14-.01.08,0,.15-.01.23-.01.05,0,.09,0,.14,0,.08,0,.17,0,.25,0,.04,0,.08,0,.12,0,.12,0,.24,0,.37,0s.25,0,.37,0c.04,0,.08,0,.12,0,.08,0,.17,0,.25,0,.05,0,.09,0,.14,0,.08,0,.15,0,.23.01.05,0,.09,0,.14.01.08,0,.16.01.24.02.04,0,.08,0,.12.01.1.01.2.02.3.03.02,0,.04,0,.06,0,.12.02.23.03.35.05.04,0,.08.01.12.02.08.01.16.03.23.04.05,0,.09.02.14.03.07.01.14.03.21.04.05,0,.1.02.14.03.07.01.14.03.21.05.04.01.09.02.13.03.08.02.16.04.25.06.03,0,.06.02.1.02.11.03.22.06.33.09.04.01.08.02.12.03.07.02.15.04.22.07.05.01.09.03.14.04.07.02.13.04.2.06.05.02.09.03.14.05.07.02.13.05.2.07.04.02.09.03.13.05.07.03.15.06.22.08.03.01.07.03.1.04.11.04.21.08.31.13.03.01.06.03.1.04.07.03.15.06.22.1.04.02.08.04.12.06.07.03.13.06.2.09.04.02.08.04.12.06.07.03.13.06.2.1.04.02.08.04.11.06.07.04.15.08.22.12.03.01.05.03.08.04.1.06.2.11.3.17.01,0,.03.02.04.02.09.05.17.1.26.15.03.02.06.04.09.05.07.04.14.09.21.13.03.02.06.04.09.06.07.05.14.09.21.14.03.02.05.04.08.05.08.05.16.11.24.17.01.01.03.02.04.03.19.14.39.28.57.43.01,0,.02.02.04.03.08.06.16.13.24.19.02.01.03.03.05.04.08.06.15.13.23.19.01.01.03.02.04.03.18.16.36.32.54.49.18.17.35.34.51.51,0,0,0,0,0,0,.08.09.17.18.25.27,0,0,0,0,0,0,1.62,1.79,2.84,3.95,3.48,6.35.38-1.34.94-2.54,1.48-3.72.15-.32.31-.64.17-1-.07-.18-.22-.16-.37-.11-.21.32-.42.67-.61,1.04-.2.38-.38.79-.54,1.2-.03.09-.16.04-.12-.05.16-.42.35-.83.55-1.22.2-.38.41-.74.63-1.07.13-.21.18-.42.12-.66-.03-.12-.12-.24-.25-.26-.03.05-.06.11-.1.16-.22.28-.42.57-.62.85-.19.29-.38.59-.55.9-.05.08-.17.02-.12-.07.17-.31.36-.61.55-.9.2-.29.4-.58.62-.86.09-.11.14-.23.15-.36.01-.27-.29-.63-.5-.34-.25.36-.51.73-.75,1.11-.27.41-.53.83-.78,1.26-.05.08-.16.01-.12-.07.26-.43.52-.85.79-1.26.26-.4.52-.79.79-1.16.05-.07.08-.14.08-.23,0-.05-.01-.1-.04-.14-.08-.12-.25-.14-.34-.03-.29.34-.53.68-.77,1.03-.25.36-.48.72-.72,1.1-.05.08-.16,0-.11-.07.25-.38.48-.74.72-1.11.25-.37.52-.72.82-1.09.08-.1.05-.23.01-.32-.02-.03-.04-.05-.05-.08-.13-.14-.25-.16-.36-.02-.45.46-.96,1-1.43,1.78-.05.08-.16.01-.11-.07.48-.79.99-1.33,1.44-1.8.1-.1.18-.16.16-.31-.01-.11-.07-.2-.14-.27-.15-.12-.22-.14-.36,0-.23.24-.46.52-.68.83-.23.31-.45.65-.68,1-.01.03-.03.05-.09.02-.05-.03-.04-.06-.02-.1.23-.36.46-.7.68-1,.23-.31.46-.6.7-.84.12-.12.18-.22.09-.38-.18-.28-.33-.1-.49.08-.23.26-.46.53-.68.81-.22.29-.43.6-.64.93-.02.03-.03.05-.1.02-.05-.03-.03-.06-.02-.09.21-.33.42-.65.64-.94.23-.29.45-.57.68-.83.11-.12.16-.21.17-.29.01-.06-.02-.12-.08-.18-.13-.14-.42-.44-.57-.11-.14.31-.35.56-.59.74-.27.21-.57.34-.9.41-.77.16-1.54-.16-2.15-.6-.62-.45-1.24-1.09-1.61-1.81-.33-.63-.5-1.36-.32-2.06-1.15.48-2.23.72-3.26.74-.77.02-1.67-.08-2.46-.33-1.05-.33-2.34-.33-3.39,0-.79.25-1.69.36-2.46.33-1.03-.03-2.1-.27-3.26-.74.18.7,0,1.43-.31,2.06-.38.72-1,1.36-1.62,1.81-.61.44-1.39.77-2.15.6-.32-.07-.63-.21-.9-.41-.24-.18-.44-.43-.59-.74-.15-.33-.44-.03-.57.11-.05.06-.09.12-.08.18,0,.08.06.16.17.29.23.26.46.53.68.83.22.29.43.6.64.94.01.03.03.05-.02.09-.06.03-.08,0-.1-.02-.2-.33-.42-.64-.64-.93-.22-.29-.44-.55-.68-.81-.16-.18-.31-.36-.49-.08-.1.16-.03.26.09.38.23.24.46.53.7.84.23.31.46.65.68,1,.02.03.03.06-.02.1-.05.03-.08,0-.09-.02-.23-.36-.46-.69-.68-1-.23-.31-.45-.59-.68-.83-.14-.14-.21-.12-.36,0-.08.07-.13.16-.14.27-.02.15.07.21.16.31.45.48.96,1.01,1.44,1.8.05.08-.06.15-.11.07-.47-.78-.98-1.31-1.43-1.78-.12-.14-.23-.12-.36.02-.01.02-.03.05-.05.08-.04.1-.06.23.01.32.3.36.57.72.82,1.09.25.36.48.72.72,1.11.05.08-.06.15-.11.07-.25-.38-.48-.74-.72-1.1-.24-.34-.49-.68-.77-1.03-.09-.11-.26-.08-.34.03-.03.04-.04.09-.04.14,0,.1.03.16.08.23.27.37.53.76.79,1.16.27.4.53.83.79,1.26.05.08-.07.15-.12.07-.25-.43-.51-.85-.78-1.26-.25-.38-.5-.75-.75-1.11-.2-.29-.51.08-.5.34,0,.13.07.25.15.36.21.28.42.57.62.86.2.29.38.59.55.9.05.09-.07.15-.12.07-.17-.31-.36-.6-.55-.9-.2-.29-.4-.57-.62-.85-.03-.05-.07-.1-.1-.16-.14.02-.22.14-.25.26-.07.24-.01.46.12.66.22.33.43.68.63,1.07s.39.79.55,1.22c.03.09-.09.14-.12.05-.16-.42-.34-.82-.54-1.2-.19-.37-.4-.72-.61-1.04-.15-.05-.3-.07-.37.11-.14.36.02.68.17,1,.54,1.18,1.09,2.38,1.48,3.72Z\"><\/path><path class=\"cls-10\" d=\"M113.23,71.61c.57.42,1.33.74,2.05.58.3-.07.59-.19.84-.38.23-.18.42-.4.55-.7.1-.22.14-.5.1-.74-.02-.1-.05-.2-.1-.27-.08-.15-.3-.29-.48-.25-.14.03-.24.16-.23.31.01.19.17.21.32.21.03.22.03.42-.05.63-.16.44-.57.7-1.03.76-.29.04-.6,0-.89-.08-.45-.14-.9-.44-1.27-.82-.41-.4-.74-.91-.92-1.38-.14-.35-.21-.71-.18-1.09.03-.33.12-.66.32-.98.13-.21.34-.22.54-.23.16,0,.3-.01.35-.14.04-.1.01-.2-.05-.27-.08-.11-.22-.17-.36-.18-.66-.02-1.17.57-1.35,1.15-.21.68-.07,1.47.27,2.1.37.7.97,1.33,1.57,1.76Z\"><\/path><path class=\"cls-10\" d=\"M107.96,68.46c.96-.03,1.98-.25,3.06-.68.14-.05.26-.14.32-.29.12-.27.29-.51.51-.7-1.8.69-4.18,1.09-6.67,1.2.9.33,1.81.5,2.78.47Z\"><\/path><path class=\"cls-10\" d=\"M91.65,70.16c.01-.14-.08-.27-.23-.31-.18-.04-.4.1-.48.25-.05.08-.08.17-.1.27-.04.24,0,.52.1.74.13.29.32.52.55.7.25.19.54.31.84.38.72.16,1.48-.16,2.05-.58.6-.44,1.2-1.06,1.57-1.76.33-.64.49-1.43.27-2.1-.18-.58-.68-1.18-1.35-1.15-.13,0-.27.07-.36.18-.06.08-.09.18-.05.27.05.12.19.13.35.14.2,0,.41.01.54.23.2.32.29.66.32.98.02.38-.05.74-.18,1.09-.18.47-.51.98-.92,1.38-.38.38-.82.68-1.27.82-.29.09-.6.12-.89.08-.46-.05-.87-.31-1.03-.76-.08-.21-.08-.41-.05-.63.15,0,.31-.01.32-.21Z\"><\/path><path class=\"cls-10\" d=\"M96.58,67.78h0c1.08.44,2.1.66,3.06.68.14.01.76-.01,1.07-.15.33-.14.09-.44-.17-.46-1.78-.19-3.45-.55-4.78-1.06.22.19.39.44.51.7.06.14.18.23.31.29Z\"><\/path><path class=\"cls-10\" d=\"M89.11,95.24c.07.26.17.49.31.68.14.18.31.33.53.44.18.04.36.1.53.16.49.2.95.51,1.44.92-.16-.2-.31-.39-.48-.57-.27-.31-.57-.62-.85-.92-.03-.03-.06-.07-.09-.1-.15-.03-.29-.08-.43-.15-.14-.08-.29-.16-.44-.27-.08-.05,0-.16.08-.11.14.1.28.18.42.25.07.03.14.07.21.09-.06-.06-.11-.13-.16-.19-.12-.16-.23-.31-.33-.47-.05-.08.05-.15.11-.08.1.15.21.31.33.46s.26.31.4.46c.28.3.56.6.85.93.18.21.37.42.54.65-.14-.34-.24-.7-.32-1.09-.08-.22-.2-.45-.35-.68-.46-.72-.94-1.32-1.7-1.72-.43-.23-.93-.38-1.52-.44.19.23.36.49.51.76.18.32.32.66.42,1Z\"><\/path><path class=\"cls-10\" d=\"M87.5,77.08c-.01.08-.03.16-.08.24.06-.03.12-.03.17-.03-.03-.07-.07-.14-.1-.21Z\"><\/path><path class=\"cls-10\" d=\"M87.19,79.86c.03-.09.16-.05.13.05-.1.26-.18.54-.23.81.14-.27.31-.5.49-.7.08-.08.16-.16.23-.24.21-.2.42-.36.63-.5-.17-.46-.36-.9-.55-1.34-.03.04-.05.08-.08.12-.14.22-.31.42-.55.62-.12.1-.21.21-.27.33-.08.12-.12.26-.16.4.09.39.14.79.15,1.18.05-.25.13-.49.21-.73ZM87.72,79.05s.06-.03.09-.05c.05-.05.1-.1.14-.16.03.03.05.1.05.18,0,.23-.07.27-.19.32-.05.02-.11.05-.18.09,0-.16-.05-.33.09-.38Z\"><\/path><path class=\"cls-10\" d=\"M88.23,96.48c.11.1.21.19.31.29.14.13.28.28.43.46.37.44.96.95,1.67,1.09.44.08.93.03,1.44-.27-.01-.03-.03-.05-.05-.08,0,0-.02,0-.03,0-.34-.16-.65-.29-.96-.3h-.02c-.07,0-.14,0-.21.02-.14.03-.27.05-.38.06-.11,0-.21,0-.29,0-.03,0-.07-.01-.05-.08.01-.06.05-.06.08-.05.08.01.16.01.26,0,.09,0,.19-.02.31-.05-.08-.03-.15-.05-.23-.1-.16-.08-.34-.17-.53-.29-.03-.02-.05-.04-.02-.1.04-.05.07-.03.1-.02.18.12.36.22.52.29.16.08.31.13.46.18.34,0,.66.15,1.03.31.01,0,.03.01.04.01l.03-.04c-.6-.55-1.13-.94-1.72-1.17-.7-.28-1.45-.28-2.19-.16Z\"><\/path><path class=\"cls-10\" d=\"M88.46,92.93c-.14-.14-.29-.27-.46-.4-.16-.03-.31-.04-.46-.02-.09.01-.11-.12-.01-.13.1-.01.18-.02.26-.01-.03-.03-.07-.05-.1-.08-.08-.06-.16-.12-.25-.18-.16-.03-.32-.1-.5-.17-.17-.08-.36-.16-.55-.27-.09-.04-.03-.16.06-.12.2.1.38.2.55.27.05.03.1.05.15.06-.04-.03-.08-.06-.12-.1-.22-.17-.42-.34-.64-.53-.08-.06.01-.16.08-.1.22.18.42.36.64.53.21.17.43.34.65.5.29.2.55.41.81.65.18.17.33.35.44.52-.02-.27-.11-.55-.27-.82-.24-.41-.59-.76-.95-1.07-.49-.42-1.03-.72-1.62-.93-.51-.18-1.06-.29-1.63-.36h0c.29.22.56.42.79.7.41.49.84.95,1.29,1.37.44.41.92.78,1.41,1.11.32.02.62.07.89.14-.12-.19-.27-.38-.46-.55Z\"><\/path><path class=\"cls-10\" d=\"M87.46,94.8c-.08.02-.11.08-.08.14.05.08.16.12.25.1.08-.01.11-.08.08-.14-.04-.08-.16-.12-.25-.1Z\"><\/path><path class=\"cls-10\" d=\"M90.41,93.18c-.05.07-.04.18.02.24.05.05.14.05.18,0,.11-.16-.09-.39-.21-.23Z\"><\/path><path class=\"cls-10\" d=\"M86.88,89.04c.12.18.24.37.34.58.08.16.15.33.22.52.13-.37.25-.62.07-1.02-.18-.39-.42-.76-.74-1.05-.33-.29-.72-.51-1.19-.64.13.24.25.48.35.73.12.3.22.61.31.94.07.29.1.61.13.93.02.15.03.3.05.45.3.12.59.27.87.45.01-.14.03-.28.05-.41.01-.09.04-.13.01-.22-.08-.23-.16-.43-.25-.63-.1-.2-.21-.39-.33-.56-.05-.08.05-.15.11-.08Z\"><\/path><path class=\"cls-10\" d=\"M88.69,92.23c.02-.35,0-.68-.07-1-.08-.39-.22-.77-.4-1.17-.14-.29-.29-.58-.44-.87-.02.29-.05.59-.17.92-.05.14-.1.29-.13.45-.03.15-.05.3-.05.46.15.1.3.22.44.34.09.08.17.15.25.23,0-.17-.01-.33-.05-.48-.05-.18-.12-.36-.23-.54-.05-.08.07-.15.12-.06.1.18.19.37.24.57.05.2.07.4.05.64.17.17.32.34.44.52Z\"><\/path><path class=\"cls-10\" d=\"M88.84,91.52c-.03.29,0,.59-.03.89.09.14.17.3.23.46.1-.1.18-.26.23-.47.07-.25.11-.57.12-.94.03-.77-.04-1.48-.16-2.19-.11-.32-.2-.66-.29-.99,0-.03-.01-.06-.02-.08-.02-.07-.04-.15-.06-.23-.02-.08-.04-.17-.06-.25,0-.03-.01-.06-.02-.09,0,0,0,0,0,0-.12.17-.23.38-.32.63-.14.36-.24.82-.31,1.36.06.12.12.25.18.38.18.39.31.76.4,1.13.01-.21.03-.42.04-.62.02-.37.03-.72.04-1.07,0-.1.14-.1.14,0,0,.36-.02.72-.05,1.08-.01.33-.04.66-.07.99Z\"><\/path><path class=\"cls-10\" d=\"M85.03,86.3c.31.31.63.62.84,1.07,0,0,0,0,0,.01.29.1.54.25.77.41-.14-.29-.31-.58-.5-.87-.23-.37-.48-.73-.72-1.09,0,0,0,0,0,0-.16-.05-.31-.14-.47-.23-.16-.1-.33-.23-.49-.38-.07-.06.01-.16.09-.1.16.13.31.25.48.36.1.06.19.12.29.16-.05-.08-.11-.17-.17-.25-.1-.14-.2-.27-.31-.4-.06-.07.03-.16.1-.09.12.14.23.27.32.41.35.48.7,1.05,1.02,1.55.24.38.46.77.64,1.15.05.05.1.1.15.16.08-.1.05-.31-.07-.64-.21-.58-.55-1.17-.85-1.71-.27-.47-.66-.94-1.13-1.34-.44-.38-.94-.69-1.44-.9-.01.31.07.63.21.95.16.36.38.71.64,1.09.18.26.4.47.62.68Z\"><\/path><path class=\"cls-10\" d=\"M87.78,87.82c-.12,0-.2.04-.23.1-.08.16.08.32.23.32.09,0,.15-.05.18-.12.03-.05.03-.12,0-.18-.02-.07-.09-.13-.19-.13Z\"><\/path><path class=\"cls-10\" d=\"M85.17,88.83s-.06-.01-.1-.01c-.05,0-.1.02-.14.05-.04.03-.08.07-.09.11,0,.03,0,.05,0,.08,0,.12.08.22.17.29.1.07.21.1.33.1.04-.15.05-.29.02-.39-.03-.12-.1-.19-.18-.22Z\"><\/path><path class=\"cls-10\" d=\"M85.6,83.03c.33.59.58,1.2.77,1.81.15.51.27,1.02.36,1.54,0-.26.03-.51.07-.74v-.03c-.07-1.03-.23-1.89-.5-2.56-.21-.54-.54-1.06-1.04-1.38-.08.55-.1,1.1-.03,1.65.07.51.21,1.02.44,1.52.16.35.39.59.57.93.13.23.25.45.36.65-.08-.52-.2-1.03-.36-1.53-.19-.61-.44-1.2-.76-1.78-.05-.08.08-.15.12-.07Z\"><\/path><path class=\"cls-10\" d=\"M87.33,86.39c.08-.49.18-.97.29-1.44-.02-.12-.03-.24-.04-.36,0-.12,0-.25.02-.39.01-.1.14-.08.14.01-.02.13-.03.25-.02.38,0,.06,0,.12.01.18.03-.03.07-.08.1-.13.05-.08.09-.18.12-.29.01-.03.02-.06.09-.04.06.02.05.05.04.08-.03.12-.08.23-.14.32-.05.09-.12.16-.18.23-.11.49-.21.98-.29,1.48-.08.49-.14.98-.19,1.49.12-.02.12-.16.15-.26.1-.29.23-.59.35-.9.28-.7.57-1.44.67-2v-.32h0c0-.16,0-.33,0-.49-.03-.21-.08-.4-.15-.57-.11-.29-.27-.52-.45-.71-.1.29-.2.58-.3.86-.12.34-.25.68-.36,1.01-.23.72-.33,1.45-.33,2.21,0,.33.21.62.29.92.05-.42.11-.85.18-1.26Z\"><\/path><path class=\"cls-10\" d=\"M85.1,81.31c.22.31.52.42.77.72-.15-.44-.31-.87-.51-1.29-.25-.53-.54-1.03-.92-1.46-.02-.03-.05-.05,0-.1.05-.05.07-.02.09,0,.4.44.7.94.95,1.49.11.23.21.46.3.71-.14-.55-.23-1.07-.28-1.57-.13-.33-.32-.63-.56-.9-.23-.25-.51-.48-.81-.67,0,.51.05,1.03.22,1.56.15.49.39.98.74,1.48Z\"><\/path><path class=\"cls-10\" d=\"M86.28,82.56c.04-.29.06-.58.08-.87.01-.39,0-.79-.03-1.2-.03-.36-.23-.77-.4-1.15-.07-.13-.13-.27-.18-.39-.01-.03-.03-.06.03-.09.06-.03.08,0,.09.03.05.12.12.25.18.39.07.14.14.29.2.43-.01-.12-.03-.24-.04-.36-.05-.29-.1-.58-.16-.87,0-.03-.02-.07.05-.08.07,0,.08.02.08.05.06.3.12.59.16.88.03.25.06.5.08.74.01.14.04.27.05.41.03.4.04.81.03,1.21,0,.39-.05.78-.12,1.15.03.05.05.12.07.17.1-.07.15-.29.22-.64.02-.1.04-.21.06-.32.2-.88.16-1.85-.04-2.73-.18-.77-.51-1.48-1-2.01-.1.75-.13,1.54-.05,2.39.09.96.32,1.93.65,2.84Z\"><\/path><path class=\"cls-10\" d=\"M84.09,82.81c.06,0,.11-.02.15-.05.03-.03.06-.08.06-.14s-.03-.1-.06-.14c-.04-.03-.1-.05-.16-.05-.05,0-.11.02-.15.05-.03.03-.05.08-.05.14s.02.1.06.14c.03.03.09.05.15.05Z\"><\/path><path class=\"cls-10\" d=\"M87.39,77.92c-.25.19-.41.31-.49.58-.03.09-.05.18-.09.26-.03.08-.06.15-.1.21.01.05.03.12.05.18.03-.08.06-.14.1-.21.08-.14.18-.25.31-.36.27-.21.44-.46.61-.72-.03-.13-.05-.33-.16-.42-.03-.03-.1-.02-.18.01-.14.06-.29.18-.35.24-.18.19-.32.36-.41.52-.16.26-.11.33-.03.59.05-.1.08-.22.12-.33.1-.31.27-.44.53-.65.03-.02.05-.05.08-.06.08-.05.16.05.08.1-.03.03-.05.05-.08.06Z\"><\/path><path class=\"cls-10\" d=\"M88.21,81.09c.14-.27.23-.56.26-.85.03-.26.02-.52-.04-.79-.26.18-.52.39-.76.66-.27.3-.51.68-.7,1.18,0,0,0,0,0,.01-.02.27-.05.54-.12.8.03-.02.05-.05.09-.08.09-.1.18-.22.23-.3.15-.24.27-.41.42-.62,0,0,.01-.03.09-.13.05-.08.16,0,.11.08-.01.01-.03.05-.09.12-.14.21-.27.38-.41.62-.05.08-.15.21-.25.31-.12.13-.21.13-.25.31-.03.16-.06.29-.09.41.31-.25.59-.51.84-.77.29-.32.53-.65.68-.96Z\"><\/path><path class=\"cls-10\" d=\"M84.53,77.82c.06.03.14.04.2.02.07-.03.12-.08.14-.14.03-.06.03-.13,0-.21-.03-.07-.08-.12-.14-.16-.06-.03-.14-.04-.2-.01-.07.02-.12.07-.14.13-.03.06-.03.14,0,.21.02.08.08.13.14.16Z\"><\/path><path class=\"cls-10\" d=\"M86.64,77.34c.08-.31.18-.6.32-.88.04-.09.16-.03.12.05-.14.28-.24.57-.31.86-.05.22-.1.44-.13.67.1-.14.22-.29.37-.44.2-.21.4-.33.36-.69-.03-.17-.1-.44-.29-.7-.23.24-.43.55-.53.88-.08.27-.1.59-.04.94.03-.23.07-.46.13-.69Z\"><\/path><path class=\"cls-10\" d=\"M92.57,96.35c-.03-.57-.15-1.18-.36-1.74-.01-.04,0-.07.04-.09,0,0,0,0,0,0-.02-.02-.04-.04-.05-.06-.06-.07-.11-.13-.17-.2-.12-.14-.23-.28-.34-.43,0,0,0,0,0,0-.01.73.02,1.43.12,2.07.1.59.25,1.17.5,1.71.12-.16.15-.24.24-.42.03-.26.05-.54.03-.83Z\"><\/path><path class=\"cls-10\" d=\"M92.72,95.04c-.12-.12-.24-.25-.35-.38.19.55.31,1.13.33,1.69,0,.18,0,.36,0,.54.08-.13.11-.25.13-.4.05-.29.05-.71.03-1.22,0-.03,0-.05.02-.05-.06-.06-.11-.12-.17-.18Z\"><\/path><path class=\"cls-10\" d=\"M93.22,95.9c.03-.09.05-.18.07-.28-.04-.04-.09-.08-.13-.12-.06-.05-.11-.1-.16-.15.02.46,0,.84-.03,1.13.1-.18.18-.36.25-.57Z\"><\/path><path class=\"cls-10\" d=\"M121.4,86.38s-.03.05-.03.09c0,.19,0,.38-.04.57.21-.23.43-.44.65-.66.01-.11.03-.21.05-.31.03-.11.06-.23.11-.33.03-.1.16-.05.12.04-.04.12-.08.22-.1.33,0,.04-.02.09-.03.13.3-.29.62-.57.93-.85.08-.06.16.04.09.1-.32.28-.64.56-.94.85.03,0,.07,0,.1,0,.08,0,.17,0,.25.01.1,0,.08.14-.01.13-.08,0-.16-.01-.25-.01h-.23c-.27.27-.54.54-.8.83-.08.3-.22.6-.4.88.05-.03.11-.06.16-.1.13-.19.27-.39.46-.53.47-.36.85-.64,1.18-.98.33-.33.62-.72.91-1.26.15-.28.23-.66.39-.9-.53.12-.92.23-1.34.5-.52.33-.95.9-1.24,1.46Z\"><\/path><path class=\"cls-10\" d=\"M122.77,82.26c-.51.42-.96.85-1.29,1.3-.36.49-.57,1.02-.55,1.58.17.27.29.54.36.83,0-.21,0-.42.02-.6.02-.27.05-.52.11-.73.07-.22.15-.39.25-.53.1-.14.21-.24.33-.32.08-.05.16.05.08.11-.12.08-.21.17-.3.29s-.16.28-.23.48c-.01.05-.02.1-.03.15.05-.06.11-.12.16-.16.12-.1.23-.19.36-.27.08-.05.15.06.07.12-.12.08-.23.16-.34.25-.1.1-.2.21-.29.32-.01.1-.02.2-.03.31-.01.21-.02.44-.02.68.28-.48.58-.82.9-1.07.09-.21.17-.4.22-.59.04-.19.07-.41.03-.6-.08-.42.04-.89.14-1.32.02-.08.03-.14.05-.21Z\"><\/path><path class=\"cls-10\" d=\"M120.58,88.57c-.47.4-.78.94-.96,1.52,0,0,0,0,0,0,.05.86-.19,1.69-.45,2.47.23-.39.46-.82.67-1.26.01-.03.03-.05.04-.08h0c.01-.1.02-.2.02-.29,0-.1-.02-.19-.03-.28-.02-.09.11-.12.13-.03.02.09.03.18.03.28.2-.45.39-.91.56-1.35.03-.09.16-.04.12.05-.17.44-.36.9-.56,1.35.02-.01.03-.03.05-.05.11-.08.22-.16.33-.23.08-.04.14.08.07.12-.11.06-.21.14-.31.21-.14.11-.25.2-.32.35-.14.29-.28.57-.43.84.27-.28.57-.54.9-.77.23-.15.47-.29.72-.4.12-.35.04-.62-.03-.84-.03-.11-.06-.21-.08-.31-.07-.62.43-1.41.76-1.93-.44.12-.87.33-1.22.62Z\"><\/path><path class=\"cls-10\" d=\"M122.49,79.08c.05.01.12,0,.16-.04.06-.05.1-.11.12-.19.02-.08.01-.16-.01-.21-.03-.05-.07-.1-.13-.11-.05-.01-.12,0-.17.04-.05.04-.1.1-.12.18-.02.08-.01.16.01.22.03.05.08.1.13.11Z\"><\/path><path class=\"cls-10\" d=\"M119.71,78.06c-.24.44-.34.7-.33.96,0,.28.12.57.32,1.1h0c.15.03.29.11.44.25,0-.17.03-.35.08-.52.01-.08.03-.14.06-.22-.04-.14-.09-.28-.14-.41-.05-.14-.11-.26-.18-.37-.05-.08.06-.15.11-.07.08.12.14.25.19.38.03.08.06.17.09.26.08-.2.18-.38.3-.56-.05-.31-.19-.51-.37-.63-.16-.12-.37-.16-.57-.18Z\"><\/path><path class=\"cls-10\" d=\"M120.65,81.85c.08.13.17.26.27.38.01-.04.03-.08.04-.12-.14-.57-.16-1.07-.1-1.64.03-.21.07-.42.12-.63-.04-.1-.08-.19-.12-.29-.03-.1-.05-.21-.05-.33,0-.1.13-.1.14,0,0,.1.02.2.05.29.01.04.03.09.05.13.08-.27.18-.53.3-.8.04-.08.16-.03.12.06-.12.24-.21.48-.28.72,0-.01.02-.03.03-.04.06-.06.12-.12.16-.19.05-.08.16,0,.12.08-.05.08-.12.14-.18.21-.06.06-.13.12-.2.17-.05.21-.1.42-.12.64-.01.12-.03.23-.03.35.03-.03.08-.08.11-.11.06-.08.12-.14.15-.19.05-.09.16-.03.12.06-.04.06-.1.14-.18.22-.08.08-.16.17-.21.25,0,.27.03.55.08.82.22-.46.48-.86.77-1.2.07-.24.1-.47.1-.7,0-.24-.05-.48-.12-.71-.08-.25-.1-.52-.08-.79.01-.19.05-.4.1-.59-.14.1-.27.19-.4.3-.51.43-.93,1.02-1.09,1.68-.16.63-.08,1.31.31,1.96Z\"><\/path><path class=\"cls-10\" d=\"M120.28,82.06c.17.22.34.43.52.64.02-.11.04-.22.08-.33h0c-.12-.15-.24-.31-.33-.46-.27-.44-.4-.9-.41-1.35-.33-.38-.64-.32-1.03-.25-.08.01-.15.03-.23.04.09.72.26,1.26.56,1.68.29.42.72.74,1.34,1.01,0-.05,0-.11,0-.16-.2-.23-.39-.47-.57-.71h-.21c-.07,0-.14,0-.21-.02-.1-.01-.08-.14.01-.13.07,0,.14.01.21.01.03,0,.06,0,.1,0-.07-.09-.13-.18-.19-.26-.11-.15-.22-.29-.32-.44-.17-.01-.33-.05-.49-.12-.09-.04-.03-.16.05-.12.1.05.21.08.33.1-.14-.18-.27-.38-.39-.56-.05-.08.05-.16.11-.08.12.18.25.36.37.53,0-.06-.02-.13-.03-.19-.02-.13-.05-.25-.08-.38-.02-.1.11-.12.13-.03.03.13.05.27.08.4.03.14.05.29.06.44.09.12.18.25.27.38.05.07.1.14.16.21,0-.03,0-.05,0-.08,0-.09,0-.18,0-.26,0-.1.14-.1.14,0,0,.09,0,.18,0,.27,0,.08-.01.14-.03.22Z\"><\/path><path class=\"cls-10\" d=\"M120.89,83.1c-.01.33.03.66.13.96.08-.16.16-.31.27-.47h0c-.03-.16-.05-.29,0-.44.12-.49.3-.94.52-1.38.1-.19.21-.39.32-.57.01-.09.03-.16.03-.23.01-.07.01-.13.02-.21,0-.1.13-.09.13,0,0,.04,0,.09,0,.13.08-.12.16-.25.23-.36.02-.03.03-.05.09-.02.06.03.04.06.02.1-.25.39-.51.81-.72,1.22-.03.06-.06.12-.09.18h0c.08-.06.16-.12.24-.16.08-.04.14.08.06.12-.08.03-.15.08-.23.14-.07.05-.14.12-.2.18,0,0,0,0,0,0-.12.28-.22.57-.29.87-.03.09-.03.17-.01.26.17-.23.37-.44.59-.66,0,0,0,0,0-.01.22-.33.4-.67.53-1.02.15-.36.25-.71.32-1.07.05-.27.08-.54.15-.81-.35.23-.67.49-.96.81-.36.38-.66.84-.87,1.32-.16.34-.25.73-.27,1.11Z\"><\/path><path class=\"cls-10\" d=\"M123.91,82.93c.03-.06.1-.21-.02-.22-.05,0-.13.03-.22.08-.14.09-.18.21-.23.35,0,0,0,.01,0,.02.12,0,.22-.02.29-.05.08-.03.14-.1.18-.17Z\"><\/path><path class=\"cls-10\" d=\"M120.68,85.01c-.21-.26-.39-.51-.55-.74-.13-.19-.24-.37-.33-.54-.16.44-.28.92-.33,1.4-.05.51-.04,1.02.05,1.52.07.34.19.66.38.96.16.25.36.48.62.68-.04-.55-.13-1.1-.25-1.64-.1-.06-.19-.13-.29-.21-.1-.09-.19-.19-.28-.31-.06-.08.05-.16.1-.08.09.11.18.21.27.29.05.05.1.08.14.12-.1-.37-.21-.72-.33-1.09-.03-.09.1-.13.13-.04.12.34.23.69.31,1.04.03-.12.05-.24.05-.36,0-.1.14-.09.13,0,0,.2-.05.4-.13.59.13.55.22,1.12.26,1.69.74-1,.83-2.29.04-3.29Z\"><\/path><path class=\"cls-10\" d=\"M118.89,93.38c.38-.16.73-.33,1.08-.57.02-.1.05-.19.09-.28.04-.1.1-.19.16-.28.02-.03.04-.05.1-.01.05.03.03.06.01.09-.06.08-.11.17-.14.26-.02.03-.03.07-.04.11.44-.32.85-.68,1.24-1.07.07-.06.16.03.1.1-.4.4-.81.75-1.21,1.05-.37.27-.77.51-1.2.68-.02.05-.05.1-.07.16.44-.03.89-.17,1.33-.44.49-.29.96-.72,1.43-1.28.32-.38.66-.74,1-1.11-.79,0-1.6.32-2.26.76-.72.49-1.33,1.15-1.61,1.84Z\"><\/path><path class=\"cls-10\" d=\"M122.6,89.28c-.12-.02-.27.05-.3.17-.04.12.04.22.16.24s.26-.05.3-.17c.03-.12-.04-.21-.16-.24Z\"><\/path><path class=\"cls-10\" d=\"M119.36,88.41c.07.08.17.11.25.01.03-.04.05-.1.05-.17s-.02-.13-.05-.17c-.07-.08-.18-.08-.25,0-.03.04-.05.1-.05.16,0,.06.02.12.06.16Z\"><\/path><path class=\"cls-10\" d=\"M119.31,89.2c-.08-.25-.18-.49-.32-.72-.07-.14-.16-.27-.27-.4,0,0,0,0,0,0-.09.37-.2.73-.31,1.09,0,.03-.02.05-.03.08-.03.08-.05.15-.08.23-.02.06-.04.12-.06.18-.01.03-.03.07-.04.1-.17.45-.36.89-.57,1.32h0c0,.62.04,1.21.19,1.63.12.36.32.62.63.74-.09-.18-.15-.41-.19-.68-.05-.34-.06-.74-.03-1.18.02-.35.06-.7.12-1.06.06-.36.15-.73.27-1.1.03-.1.16-.05.12.04-.12.36-.2.72-.27,1.08-.06.36-.1.7-.12,1.05h0s.03-.06.05-.09c.08-.12.15-.23.24-.34.06-.07.16.01.1.09-.08.1-.16.21-.23.32-.07.11-.13.23-.18.35,0,.31,0,.59.04.83.03.25.1.52.24.74.16-.08.29-.65.36-.86.36-1.07.7-2.23.31-3.44Z\"><\/path><path class=\"cls-10\" d=\"M116.87,96.29c-.41.25-.7.56-1.01.93-.16.19-.31.39-.44.6.55-.2,1.03-.47,1.46-.85.46-.41.87-.95,1.21-1.65.19-.4.37-.8.55-1.2.08-.2.17-.4.26-.59-1.8.79-2.99,2.1-3.44,4,.1-.14.19-.27.3-.4.34-.41.69-.62.81-1.16.03-.16.05-.32.04-.49,0-.1.12-.12.13-.01.01.18,0,.36-.04.53-.01.07-.03.14-.05.2.14-.14.27-.29.39-.44.21-.26.4-.53.56-.85.05-.08.16-.02.12.06-.17.33-.36.61-.57.87-.08.1-.16.19-.25.28.1-.05.2-.11.29-.15.08-.04.14.08.05.12-.12.06-.25.13-.38.21Z\"><\/path><path class=\"cls-10\" d=\"M116.64,93.5h-.03s-.09.03-.12.08-.05.1-.06.17c0,.06.01.12.05.17.02.03.05.05.1.05.05,0,.1-.01.14-.05.03-.03.06-.09.08-.17,0-.03,0-.06,0-.09,0-.05-.03-.09-.05-.12-.03-.03-.05-.05-.09-.05Z\"><\/path><path class=\"cls-10\" d=\"M119.51,95.17c-.13.1-.12.25.05.3.08.03.16.02.25,0,.14-.04.26-.2.12-.31-.12-.08-.29-.07-.41.01Z\"><\/path><path class=\"cls-10\" d=\"M116.61,97.35c-.38.27-.81.49-1.26.64-.11.1-.2.22-.27.35-.05.1-.1.2-.14.32.34-.01.71-.12,1.11-.28.29-.22.56-.46.8-.74.07-.08.16.01.1.09-.14.16-.3.31-.46.46.33-.16.68-.34,1.05-.55.08-.05.15.07.06.12-.44.25-.85.46-1.24.63.15.01.3.04.46.11.05.02.05.05.02.1.14-.06.28-.13.41-.21.69-.4,1.28-1,1.76-1.58-.77-.12-1.78.08-2.41.53Z\"><\/path><path class=\"cls-10\" d=\"M116.18,98.52h-.1c-.4.16-.76.25-1.1.28.65.16,1.26.07,1.81-.16,0,0-.01,0-.02-.01-.19-.08-.4-.09-.59-.1Z\"><\/path><path class=\"cls-10\" d=\"M115.3,95.84c-.05.14-.09.29-.12.44.05.27.14.52.27.73.1-.31.22-.6.36-.88.06-.49.05-.92-.01-1.3-.03-.23-.1-.44-.18-.62-.3.36-.61.7-.94,1.03-.04.04-.08.08-.12.12-.03.03-.06.06-.09.08.03.88.31,1.41.59,1.98.06.11.12.23.18.35.04-.2.09-.39.14-.57-.16-.21-.27-.59-.34-.84-.03-.12-.22-.25-.33-.3-.08-.04-.03-.16.06-.12.1.05.2.12.28.21.03-.12.06-.23.1-.34.05-.16.12-.31.22-.44.06-.08.17,0,.11.08-.09.12-.15.25-.21.4Z\"><\/path><path class=\"cls-10\" d=\"M98.9,64.08c-.21.03-.41.11-.6.23.48.11.9.03,1.24-.23-.23-.04-.44-.04-.64,0Z\"><\/path><path class=\"cls-10\" d=\"M108.07,64.08c.35.26.77.33,1.24.23-.19-.12-.39-.2-.6-.23-.21-.03-.42-.03-.64,0Z\"><\/path><path class=\"cls-10\" d=\"M103.8,67.77c1.35,0,2.72-.09,4-.27.14-.02.66-.12.66-.29,0-.3.49-.16.66-.18.45-.07-.03-.27.13-.31.18,0,.34,0,.44-.04.4-.2.08-.71-.36-.71-.27,0-.01-.28-.44-.27-.23,0-.51,0-.68-.09-.4-.2-.84-.45-1.3-.51-1.05-.14-2.08-.21-3.11-.21-1.24,0-2.47.1-3.75.29-.38.06-.68.28-1.03.43-.09.04-.94.27-.46.36.32.06-.16.09-.24.16-.09.1,0,.15.31.16.27,0,.21-.03.46.07-.36.03-.59.1-.64.21-.06.19.31.44.7.38.43-.07.38.28.85.33.21.02.42,0,.57.04.29.08.29.31.59.33.86.07,1.75.11,2.63.11Z\"><\/path><path class=\"cls-10\" d=\"M104.91,103.74c-.57-.25-.82.21-1.26.4-.37.16-.8.25-1.2.24.05.12.14.23.25.33l.04-.05c.05-.08.16,0,.11.08l-.05.06s.06.05.1.07c.03-.03.04-.07.05-.11.02-.09.15-.06.13.03,0,.05-.03.11-.06.16.05.03.1.05.15.08.03-.05.05-.11.05-.17.01-.1.15-.08.13.02,0,.08-.03.14-.06.21.08.03.15.06.22.08.03-.08.04-.16.03-.23,0-.1.13-.1.14-.01,0,.09,0,.18-.03.27.05,0,.1,0,.15,0h.05c.02-.1.03-.21.03-.31,0-.1.13-.09.13,0s0,.2-.03.29c.09,0,.18-.02.27-.03,0-.12,0-.23,0-.35,0-.1.12-.11.14-.01,0,.11,0,.22,0,.33.08-.02.16-.04.23-.07,0-.12,0-.25-.03-.38-.02-.09.12-.12.13-.02.03.11.03.23.04.34.08-.03.16-.07.23-.11,0-.12.02-.22-.01-.33-.02-.1.11-.13.13-.03.03.1.03.2.03.28.07-.05.12-.14.11-.22,0-.02-.01-.04-.02-.07-.04-.09.08-.14.12-.05t0,.01c.03-.07.05-.14.04-.21,0-.23-.27-.42-.47-.51Z\"><\/path><\/g><\/g><\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a52cfe elementor-widget elementor-widget-text-editor\" data-id=\"4a52cfe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Located at Estadi Mallorca Son Moix, the RCD Mallorca Sport Clinic is a high-performance center designed to optimize every phase of the sports process. With state-of-the-art technology and an elite multidisciplinary team, it offers personalized programs for physical preparation, prevention, and recovery. A space where science and sport come together to take your performance to the highest level.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-830310d elementor-widget elementor-widget-button\" data-id=\"830310d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/rcdmallorcasportclinic.com\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">MORE INFORMATION<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d60a076 e-con-full e-flex e-con e-child\" data-id=\"d60a076\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_scale_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_scale_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:2,&quot;sizes&quot;:[]},&quot;background_motion_fx_scale_direction&quot;:&quot;out-in&quot;,&quot;background_motion_fx_scale_range&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:20,&quot;end&quot;:80}},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e3908f2 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"e3908f2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-35fc66f e-con-full e-flex e-con e-child\" data-id=\"35fc66f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_scale_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_scale_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:2,&quot;sizes&quot;:[]},&quot;background_motion_fx_scale_direction&quot;:&quot;out-in&quot;,&quot;background_motion_fx_scale_range&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:20,&quot;end&quot;:80}},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-347a3c5 e-con-full e-flex e-con e-child\" data-id=\"347a3c5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4f43da5 e-con-full e-flex e-con e-child\" data-id=\"4f43da5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5e1f48c elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"5e1f48c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"388\" height=\"512\" viewBox=\"0 0 388 512\" fill=\"none\"><path d=\"M363.158 344.23C367.708 340.909 371.288 338.118 374.534 334.796C377.779 331.474 380.585 327.773 383.376 322.51C385.257 318.991 386.304 315.23 387.927 311.59C382.466 312.697 377.006 314.123 372.258 317.247C372.85 315.943 373.229 314.653 373.563 313.349C373.957 311.726 374.154 310.164 374.078 308.602C374.215 308.465 374.336 308.283 374.473 308.146C375.064 307.373 375.58 306.721 376.293 306.19C377.658 305.083 379.023 303.975 380.191 302.61C381.814 302.61 383.058 302.413 384.028 301.958C385.136 301.503 385.909 300.729 386.44 299.683C386.895 298.773 387.032 297.999 386.956 297.408C386.819 296.437 386.106 295.845 385.136 295.845C384.362 295.785 383.376 296.103 382.406 296.756C380.722 297.802 380.191 299.091 379.615 300.654C378.902 302.671 377.142 303.9 375.519 305.143C374.867 305.659 374.351 306.19 373.896 306.827C373.244 303.247 374.291 298.955 375.262 294.996C375.656 293.312 376.035 291.553 376.49 289.794C374.215 291.098 372.334 292.782 370.378 294.48C371.545 292.463 372.516 290.385 373.366 288.231C374.791 284.849 375.777 281.345 376.429 277.826C377.142 274.125 377.658 270.546 378.841 266.966C374.609 269.575 370.711 272.366 367.268 275.945C367.587 274.323 367.723 272.76 367.663 271.137C367.663 270.622 367.663 270.167 367.602 269.636C368.512 268.786 369.285 267.876 370.014 266.906C370.742 265.935 371.318 264.949 371.834 263.842C372.683 263.902 373.457 263.644 374.169 263.129C374.882 262.537 375.535 261.703 375.792 260.656C376.05 259.61 375.929 258.579 375.535 257.729C375.14 256.88 374.427 256.228 373.517 256.045C372.547 255.848 371.637 256.045 370.787 256.637C370.074 257.153 369.483 258.063 369.225 259.109C368.967 260.156 369.028 261.187 369.422 262.037C369.68 262.628 370.074 263.083 370.59 263.402C370.135 264.373 369.619 265.283 368.967 266.193C368.512 266.845 367.996 267.421 367.405 268.013C367.208 266.708 366.889 265.343 366.434 264.039C365.721 261.824 365.585 259.428 365.782 257.077C365.979 254.21 366.828 251.48 367.541 248.629C365.13 249.933 362.991 251.419 360.913 253.179C358.835 254.938 356.939 256.88 355.316 259.034C354.603 256.364 353.238 254.605 351.539 253.437C349.78 252.208 347.702 251.677 345.563 251.556C347.186 247.855 348.809 244.275 350.508 240.696C351.357 238.815 352.192 236.919 352.586 236.085C354.467 231.929 354.406 228.744 353.754 224.315C352.783 218.339 347.126 209.951 340.482 201.624C337.16 197.392 333.52 193.175 330.214 189.262C327.089 185.622 324.238 182.3 322.144 179.57C320.976 178.068 319.611 176.248 317.988 174.959C316.305 173.533 314.348 172.684 312.073 173.139C309.859 173.533 308.236 175.475 308.433 177.75C308.569 179.434 309.859 180.738 311.618 180.875C311.755 182.497 311.557 183.863 311.026 185.167C309.661 188.868 306.142 191.022 302.32 191.537C299.727 191.856 296.921 191.537 294.327 190.764C293.28 190.506 292.31 190.051 291.263 189.596C288.275 188.17 285.348 185.956 282.739 183.347C279.038 179.57 275.974 174.959 274.29 170.606C273.062 167.481 272.41 164.175 272.667 160.793C272.865 157.865 273.714 154.938 275.534 152.01C276.384 150.645 278.067 150.509 279.629 150.448C281.51 150.387 283.27 150.312 284.058 148.37C284.574 147.066 284.316 145.64 283.406 144.533C282.435 143.228 280.812 142.455 279.174 142.394C279.629 142.136 280.024 141.878 280.342 141.545C280.797 141.09 281.055 140.635 281.252 140.043C281.45 139.527 281.51 138.936 281.389 138.36C281.252 137.586 280.934 136.858 280.221 136.221C280.737 134.537 281.268 132.778 282.435 131.534C283.406 130.487 284.058 129.577 284.453 128.804H284.847C285.894 128.804 287.062 128.607 288.032 128.152C289.079 127.636 289.989 126.847 290.368 125.74C290.565 125.346 290.687 124.83 290.687 124.238C290.687 123.526 290.944 122.737 291.278 121.903C291.93 120.538 292.962 119.172 294.145 118.065C295.116 117.216 296.101 116.503 297.133 116.109C298.104 115.714 299.09 115.654 299.924 115.911C300.697 116.23 301.486 116.882 302.062 117.989C301.092 119.809 301.607 122.085 303.291 123.253C305.308 124.678 307.978 123.965 309.009 121.69C310.571 118.369 309.722 114.349 307.508 111.346C307.963 109.981 308.675 108.934 309.464 108.1C310.177 108.419 310.89 108.616 311.679 108.616C314.545 108.616 316.821 106.28 316.821 103.474C316.821 102.109 316.365 100.941 315.516 100.031H315.653C318.443 100.031 320.794 97.7557 320.794 94.889C320.794 93.3874 320.082 91.9616 319.035 91.0515C321.902 90.7937 324.177 88.3214 324.177 85.394C324.177 82.8003 322.417 80.5859 319.945 79.9336C322.933 79.4179 325.148 76.8091 325.148 73.7604C325.148 70.3173 322.357 67.5113 318.898 67.5113C318.246 67.5113 317.731 67.572 317.139 67.7085C319.217 66.6619 320.643 64.5233 320.643 61.9903C320.643 58.4714 317.776 55.5592 314.212 55.5592C313.044 55.5592 311.937 55.8777 310.966 56.4692C311.739 55.4227 312.134 54.1941 312.134 52.829C312.134 49.3859 309.343 46.5799 305.885 46.5799C304.459 46.5799 303.154 47.035 302.108 47.8843V47.49C302.108 44.1683 299.378 41.4381 296.056 41.4381C294.433 41.4381 292.931 42.151 291.824 43.2582C291.627 43.3947 291.506 43.5767 291.369 43.7132C291.309 43.5767 291.308 43.4554 291.233 43.3189C290.641 41.0437 288.563 39.3601 286.091 39.3601C284.589 39.3601 283.224 39.9517 282.253 40.9224C282.117 41.1196 281.996 41.2409 281.859 41.4381C281.207 39.2236 279.129 37.6007 276.717 37.6007C275.216 37.6007 273.926 38.1922 272.94 39.1629C272.804 39.2994 272.683 39.4208 272.622 39.5573V39.2994C272.622 36.4328 270.286 34.0969 267.359 34.0969C265.281 34.0969 263.461 35.3255 262.611 37.1456C262.672 36.9485 262.672 36.6906 262.672 36.4934C262.672 33.6267 260.336 31.2909 257.469 31.2909C255.968 31.2909 254.679 31.8825 253.693 32.8532C253.556 30.123 251.281 27.9085 248.551 27.9085C247.125 27.9085 245.821 28.5001 244.911 29.4101C244.258 30.123 243.743 30.9724 243.545 31.9431V31.6853C243.545 28.8944 241.27 26.6799 238.54 26.6799C237.175 26.6799 235.946 27.2715 235.021 28.1057C234.627 28.5001 234.308 28.9551 234.111 29.4708C233.793 27.59 232.428 26.0884 230.592 25.4969C230.137 25.3603 229.682 25.2997 229.167 25.2997C227.801 25.2997 226.573 25.8912 225.663 26.8013C225.344 27.1198 225.011 27.5142 224.813 27.9085C224.358 25.694 222.341 23.9346 220.005 23.9346C218.64 23.9346 217.412 24.5261 216.486 25.4362C216.229 25.694 215.971 26.0277 215.773 26.3463C215.061 24.5261 213.362 23.2975 211.345 23.2975C208.675 23.2975 206.536 25.512 206.597 28.1057C205.171 28.1057 203.867 27.8478 202.562 27.3321C203.078 26.1642 203.412 24.7991 203.412 23.4341C203.412 18.7472 199.969 14.7885 195.479 14.0756V9.19161H201.197V6.06707H195.479V0H192.491V6.11257H186.773V9.23711H192.491V14.1211C188.001 14.834 184.558 18.8079 184.558 23.4796C184.558 24.8446 184.877 26.2097 185.408 27.3777C184.103 27.8934 182.814 28.1512 181.373 28.1512C181.434 25.5575 179.295 23.3431 176.626 23.3431C174.608 23.3431 172.925 24.5716 172.197 26.3918C172 26.0732 171.742 25.7395 171.484 25.4817C170.574 24.5716 169.345 23.9801 167.965 23.9801C165.629 23.9801 163.612 25.7395 163.157 27.954C162.96 27.5597 162.641 27.1805 162.307 26.8468C161.397 25.9367 160.169 25.3452 158.789 25.3452C158.47 25.3452 158.136 25.4059 157.818 25.4817C155.801 25.8761 154.238 27.4383 153.844 29.5163C153.647 29.0006 153.328 28.5456 152.934 28.1512C152.024 27.3018 150.795 26.7254 149.415 26.7254C146.685 26.7254 144.41 28.9399 144.41 31.7308V31.9886C144.212 31.0179 143.697 30.1685 143.044 29.4556C142.134 28.5456 140.83 27.954 139.404 27.954C136.674 27.954 134.399 30.1685 134.262 32.8987C133.292 31.928 131.987 31.3364 130.486 31.3364C127.619 31.3364 125.283 33.6722 125.283 36.5389C125.283 36.7361 125.283 36.994 125.344 37.1911C124.494 35.371 122.674 34.1424 120.596 34.1424C117.669 34.1424 115.333 36.4783 115.333 39.3449V39.6028C115.272 39.4663 115.136 39.3449 115.015 39.2084C114.044 38.2377 112.739 37.6462 111.238 37.6462C108.826 37.6462 106.748 39.2691 106.096 41.4836C105.96 41.2864 105.838 41.1651 105.702 40.9679C104.731 39.9972 103.366 39.4056 101.864 39.4056C99.2706 39.4056 97.0561 41.2864 96.6011 43.7587C96.4646 43.5616 96.2826 43.4402 96.146 43.3037C95.0388 42.1965 93.5524 41.4836 91.9143 41.4836C88.5925 41.4836 85.8624 44.2138 85.8624 47.5355C85.8624 47.672 85.8624 47.7933 85.923 47.9298C84.8158 47.0805 83.5114 46.6254 82.0856 46.6254C78.6426 46.6254 75.8365 49.4163 75.8365 52.8745C75.8365 54.2396 76.2309 55.4682 77.0044 56.5148C76.0337 55.9232 74.9265 55.6047 73.7586 55.6047C70.179 55.6047 67.3275 58.5321 67.3275 62.0358C67.3275 64.5688 68.7532 66.7226 70.8312 67.754C70.2397 67.6175 69.724 67.5568 69.0717 67.5568C65.6287 67.5568 62.8227 70.3477 62.8227 73.8059C62.8227 76.8698 65.0371 79.4634 68.0252 79.9791C65.6135 80.6314 63.7934 82.8458 63.7934 85.4395C63.7934 88.3669 66.0685 90.8392 68.9352 91.0971C67.8887 92.0071 67.1758 93.4329 67.1758 94.9345C67.1758 97.8012 69.5116 100.076 72.3176 100.076H72.4541C71.6047 100.986 71.1497 102.154 71.1497 103.519C71.1497 106.31 73.4249 108.661 76.2916 108.661C77.0651 108.661 77.8538 108.464 78.506 108.146C79.2796 108.919 79.9318 109.905 80.3868 111.209C79.2796 112.635 78.5667 114.334 78.3089 116.154C78.1117 117.974 78.1117 120.052 78.9004 121.751C79.8711 124.026 82.6013 124.739 84.6186 123.313C86.3022 122.145 86.8331 119.87 85.8472 118.05C86.4387 116.943 87.2123 116.291 87.9858 115.972C88.8352 115.714 89.806 115.775 90.7767 116.169C91.8233 116.564 92.794 117.276 93.7647 118.126H93.7041C94.9326 119.172 95.9185 120.538 96.5707 121.827C96.9651 122.676 97.2229 123.586 97.2229 124.299C97.2229 124.891 97.3595 125.406 97.4808 125.801C97.9358 126.908 98.8459 127.681 99.8925 128.212C100.863 128.667 102.031 128.865 103.078 128.865H103.533C103.927 129.638 104.579 130.548 105.55 131.595C106.779 132.823 107.234 134.583 107.764 136.282C107.052 136.934 106.718 137.647 106.597 138.42C106.46 139.012 106.536 139.588 106.733 140.104C106.93 140.695 107.249 141.15 107.643 141.605C107.962 141.924 108.356 142.197 108.811 142.455C107.188 142.515 105.565 143.304 104.519 144.593C103.669 145.701 103.351 147.126 103.866 148.431C104.716 150.387 106.46 150.448 108.356 150.509C109.918 150.57 111.541 150.706 112.451 152.071C114.211 154.998 115.121 157.926 115.318 160.853C115.515 164.236 114.863 167.557 113.695 170.667C112.011 175.02 108.948 179.646 105.171 183.408C102.577 186.001 99.5739 188.216 96.5859 189.717C95.6152 190.172 94.5686 190.567 93.5979 190.825C91.0042 191.598 88.1982 191.932 85.6652 191.598C81.7671 191.082 78.324 188.929 76.8831 185.228C76.4281 183.923 76.1702 182.558 76.2916 180.935C78.1117 180.799 79.3403 179.509 79.5374 177.811C79.7346 175.535 78.0358 173.579 75.8365 173.2C73.622 172.745 71.6806 173.594 69.9818 175.02C68.3589 176.324 66.9331 178.144 65.8259 179.631C63.6872 182.361 60.8205 185.683 57.696 189.323C50.734 197.513 42.5435 207.145 37.8567 215.335C35.9 218.657 34.6108 221.767 34.2164 224.375C33.6249 227.955 33.5036 230.685 34.4136 233.734C31.6228 236.464 29.5296 239.391 28.4982 243.229C27.6488 246.217 27.5275 249.599 28.1797 253.497C26.1624 249.539 23.6901 246.278 20.5049 243.092C19.8526 248.158 19.3976 253.239 19.3369 258.305C18.6847 257.198 17.9719 256.091 17.3196 255.12C16.2731 253.695 15.2417 252.329 14.1951 251.086C14.5136 250.767 14.7866 250.433 14.908 249.978C15.3023 249.129 15.363 248.098 14.9687 247.051C14.6501 246.08 13.8614 245.292 13.012 244.912C12.1626 244.457 11.1312 244.321 10.1453 244.655C9.1746 244.973 8.46172 245.701 8.06736 246.611C7.673 247.521 7.61233 248.568 8.00669 249.539C8.40105 250.509 9.11393 251.298 9.96332 251.753C10.8734 252.208 11.8441 252.269 12.83 251.95C12.9665 251.95 13.0272 251.89 13.0879 251.814C14.1951 253.042 15.2265 254.407 16.2124 255.848C17.3196 257.35 18.2904 259.094 19.2763 260.914L19.3369 260.975C19.3369 262.598 19.3976 264.297 19.5341 265.98C18.4269 263.963 17.0011 262.082 15.4389 260.323C12.5722 257.138 9.18977 254.802 5.54953 252.527C5.41302 258.442 5.86805 264.236 7.68817 269.954C9.31111 275.415 12.0413 280.875 16.2731 286.411C15.4237 291.932 15.2265 297.468 15.9546 302.989C16.3489 305.522 16.8646 308.055 17.5775 310.604C16.7281 309.178 15.818 307.737 14.908 306.372C12.9514 303.444 10.8734 300.775 8.59823 298.439C9.18977 297.848 9.56896 297.074 9.56896 296.225C9.56896 295.375 9.1746 294.541 8.52239 294.01C7.93085 293.419 7.1573 293.1 6.24724 293.1C5.33718 293.1 4.56363 293.419 3.91142 294.01C3.31988 294.602 3.00136 295.375 3.00136 296.225C3.00136 297.074 3.39572 297.848 3.97209 298.439C4.56363 299.031 5.39785 299.349 6.30791 299.349C6.70227 299.349 7.08146 299.289 7.47582 299.152C9.75098 301.427 11.9048 304.157 13.8462 307.085C15.8029 310.012 17.623 313.137 19.2459 316.246C18.1387 315.139 16.9708 314.032 15.8029 313C11.0554 308.966 5.91355 305.841 0.074 303.566C-0.244521 307.661 0.468359 311.18 2.15197 314.942C3.65357 318.385 5.85288 321.828 8.32521 325.468C10.1453 328.001 12.2233 330.079 14.3771 332.172C17.0466 334.842 19.7161 337.435 21.5969 341.015C20.3683 340.62 19.0639 340.363 17.8202 340.044C19.6403 343.108 21.2632 346.096 22.5677 349.403C23.7356 352.193 24.6456 355.121 25.4344 358.245C26.0259 360.52 26.3444 363.129 26.6023 365.723C25.3737 365.207 24.1906 364.616 23.0227 363.903C21.7941 363.19 20.5504 362.341 19.3218 361.43C19.8375 359.808 19.8375 358.306 19.519 357.077C19.1246 355.576 18.2145 354.484 16.986 354.089C16.4703 353.953 16.0152 353.892 15.5602 353.892C14.7866 353.953 14.1344 354.211 13.5429 354.666C12.9514 355.06 12.4963 355.712 12.2385 356.349C12.102 356.744 12.102 357.123 12.102 357.578C12.2385 359.08 13.0727 360.369 14.2406 361.218C15.4692 362.068 16.9708 362.447 18.3966 362.325C19.701 363.296 21.0661 364.206 22.3705 364.995C23.7962 365.844 25.2372 366.557 26.7236 367.073C26.8601 368.241 26.9208 369.409 27.118 370.516C26.8601 370.455 26.6629 370.379 26.4051 370.319C21.5211 368.635 12.4205 366.163 7.09663 366.8C7.94602 367.71 8.85608 368.362 9.82681 369.136C12.4963 371.092 15.0293 372.912 17.1073 375.445C21.0812 380.193 25.1765 384.607 29.5903 388.641C32.2598 391.053 34.99 393.389 37.8415 395.527C39.601 396.832 41.4211 398.121 43.3019 399.304C45.4405 401.716 47.3971 404.446 49.0201 407.373C50.643 410.361 51.9474 413.486 52.7968 416.611C53.0547 417.323 53.2519 418.036 53.5097 418.749C49.4751 417.976 45.577 416.337 42.0581 414.138C42.2553 413.622 42.1188 412.97 41.8609 412.455C41.1481 411.15 39.4493 410.498 38.0842 410.832C38.0235 410.832 37.887 410.892 37.8263 410.892C36.4613 411.347 35.8697 412.712 36.5978 414.017C36.8556 414.533 37.3106 414.988 37.8263 415.245C38.5999 415.7 39.51 415.837 40.3593 415.64C40.6779 415.579 41.0116 415.443 41.3301 415.185C45.1675 417.657 49.5206 419.417 54.0709 420.19C54.5866 421.358 55.2388 422.465 55.9517 423.512C56.7253 424.558 57.6353 425.529 58.6819 426.378C53.3429 425.726 48.1555 426.378 42.8772 427.349C44.5608 428.851 46.2596 430.277 47.8218 431.839C49.1263 433.067 50.4307 434.433 51.7958 436.131C55.4967 440.484 61.4121 445.49 68.5105 446.855C73.0002 447.704 77.9448 447.113 83.0715 444.125C87.1061 450.495 91.4592 456.866 96.5252 463.236C102.835 471.305 110.252 479.359 119.474 487.368C127.407 495.498 144.243 509.861 157.712 508.754C158.682 508.693 159.592 508.557 160.502 508.36C166.297 506.858 171.029 502.308 170.71 495.937C172.015 499.32 173.956 502.369 176.504 504.841C180.933 509.27 187.107 512 193.871 512C200.636 512 206.749 509.27 211.238 504.841C213.711 502.369 215.728 499.32 216.957 495.937C216.638 502.308 221.386 506.858 227.225 508.36C228.272 508.618 229.364 508.754 230.471 508.815C243.864 509.467 260.382 495.361 268.178 487.353C277.415 479.359 284.756 471.351 291.066 463.357C294.251 459.398 297.178 455.364 299.848 451.329C308.175 453.407 315.85 451.39 322.539 447.431C329.501 443.336 335.537 437.087 340.285 431.308C340.346 431.308 340.346 431.247 340.346 431.247L340.998 430.474L340.285 430.277L339.966 430.216C336.463 429.564 332.807 429.503 328.97 430.155C326.103 430.61 323.176 431.46 320.127 432.688C322.857 430.095 325.33 427.091 327.544 423.588C330.016 422.996 332.489 422.359 334.885 421.449C336.705 420.797 338.525 420.084 340.285 419.234C340.74 418.977 341.195 418.779 341.65 418.522C342.044 419.113 342.621 419.492 343.334 419.75C344.38 420.069 345.472 420.008 346.458 419.75C347.884 419.295 349.052 418.249 349.128 416.762C349.128 415.913 348.733 415.139 347.96 414.548C346.458 413.38 344.122 413.501 342.621 414.608C341.711 415.261 341.058 416.171 341.195 417.339C340.937 417.475 340.603 417.596 340.285 417.794C338.404 418.704 336.447 419.553 334.43 420.266C332.474 420.979 330.456 421.57 328.454 422.025C329.304 420.66 330.077 419.159 330.866 417.596C332.686 413.895 334.385 409.982 336.068 406.145C336.66 404.78 337.236 403.415 337.828 402.11C338.677 402.05 339.511 401.974 340.3 401.913C344.138 401.397 347.975 400.032 351.752 397.757C356.438 394.89 361.11 390.734 365.66 385.213C368.451 381.831 371.257 378.843 374.048 375.916C375.019 374.808 376.005 373.777 376.976 372.73C371.06 372.412 365.858 373.246 360.397 375.597C360.594 374.687 360.716 373.777 360.716 373.003C362.217 371.32 363.764 369.682 365.403 368.059C366.828 366.694 368.269 365.389 369.756 364.221C370.15 364.479 370.605 364.676 371.121 364.737C372.88 365.056 374.822 364.024 375.413 362.265C376.005 360.445 374.761 358.685 372.941 358.367C371.121 358.048 369.164 359.08 368.648 360.839C368.391 361.688 368.451 362.523 368.846 363.251C367.42 364.479 365.979 365.723 364.493 367.149C363.188 368.377 361.899 369.742 360.594 371.244C360.397 370.015 360.079 368.908 359.745 367.862C359.487 366.891 359.229 366.041 359.093 365.192C358.501 359.671 363.188 352.254 366.176 347.507C366.828 346.536 367.283 345.944 368.133 345.171C365.342 345.368 362.794 346.141 360.139 347.309C360.989 346.202 361.899 345.095 363.006 344.261L363.158 344.23ZM276.945 52.9352C276.884 52.6773 276.884 52.5408 276.884 52.4195C276.823 51.3729 276.748 50.3415 276.49 49.2949C282.011 50.5235 287.016 52.6167 291.248 55.4075C294.115 57.2276 296.587 59.3814 298.725 61.7173C304.247 67.7692 307.174 75.2468 306.522 82.9823C306.385 85.1968 305.93 87.4113 305.293 89.5499C303.534 89.0949 301.774 88.382 301.198 87.7298C298.725 84.8025 295.222 83.3009 291.248 82.5273C289.231 82.133 287.016 81.9358 284.817 81.8144C284.68 79.3421 284.362 76.8091 282.739 73.8211C280.464 73.3054 278.188 73.0475 275.913 72.9717C276.368 71.2122 276.687 69.5286 276.884 67.8298C277.476 63.2795 277.339 58.5927 276.945 52.9352ZM96.6921 75.4288V75.4895C91.171 79.3876 88.5622 81.4049 81.4789 79.5848C81.7974 73.0779 84.6641 66.8439 89.3509 61.7021C91.4289 59.3663 93.9012 57.2731 96.6921 55.453C100.985 52.6622 105.99 50.5084 111.587 49.2798C111.329 50.3263 111.268 51.3577 111.192 52.4043C111.192 52.5408 111.192 52.6622 111.132 52.92C110.737 58.5776 110.616 63.2644 111.192 67.8147C111.329 69.1191 111.587 70.4083 111.845 71.7734C106.126 70.2718 101.318 72.092 96.6921 75.4137V75.4288ZM340.467 263.796C340.603 263.402 340.725 263.083 340.922 262.689C341.119 265.283 342.151 268.028 343.789 272.442C342.742 272.381 341.65 272.578 340.467 272.76C340.073 272.821 339.693 272.897 339.299 273.018C338.647 273.155 337.934 273.276 337.221 273.337C338.192 270.091 339.299 266.906 340.467 263.781V263.796ZM209.904 34.0666C211.587 34.3244 213.347 34.7188 215.167 35.2952C219.323 36.5238 222.842 37.4338 226.421 38.0254C227.786 38.2225 229.212 38.4197 230.653 38.5411C232.989 38.7382 235.4 38.8596 238.131 38.8596C242.362 38.8596 245.805 39.5725 248.475 41.3319C251.084 43.0155 253.025 45.685 254.133 49.5831C255.043 52.6318 255.498 55.635 255.558 58.6837C255.164 58.6231 254.785 58.6231 254.451 58.5472C246.837 57.8343 246.003 51.6611 240.406 49.7045C237.812 48.7944 234.035 48.7337 230.653 49.0523C229.682 49.1888 228.772 49.3101 227.862 49.4466C224.025 50.1595 221.355 48.7337 217.715 47.49C215.303 46.7164 212.831 45.9277 210.237 45.2755C209.267 41.1196 207.901 37.2821 206.081 34.0211C206.021 33.8846 205.884 33.7026 205.823 33.5661C207.249 33.7026 208.614 33.8239 209.919 34.0211L209.904 34.0666ZM133.944 49.6135C135.051 45.7154 137.008 43.0459 139.601 41.3622C142.271 39.6028 145.714 38.8899 149.946 38.8899C152.873 38.8899 155.467 38.7534 157.878 38.4956C159.183 38.359 160.411 38.2377 161.655 38.0405C165.235 37.449 168.739 36.5389 172.91 35.3103C174.73 34.7188 176.489 34.3396 178.173 34.0818C179.796 33.8239 181.495 33.6874 183.239 33.4902C182.465 35.7047 181.874 38.3742 181.419 40.8314C180.964 42.9093 180.569 44.7901 180.19 45.776C180.054 45.9732 179.993 46.2311 179.872 46.4283C175.579 48.5062 172.712 52.5408 168.162 53.8452C166.342 54.3609 164.067 53.5267 161.458 53.193C160.29 52.9959 159.122 52.9959 157.878 53.0565C152.615 53.5116 147.155 56.3024 144.03 60.337C140.132 65.403 137.144 67.4962 133.959 68.7247C133.186 65.9946 132.73 63.2037 132.594 60.3977C132.457 56.8788 132.852 53.2385 133.959 49.5983L133.944 49.6135ZM40.3745 356.455C40.3138 356.971 40.238 357.366 40.238 357.76C39.5251 356.198 38.8122 354.772 37.9629 353.407C37.1893 352.178 36.3399 350.995 35.4298 349.964C35.8849 349.448 36.2034 348.735 36.2034 347.825C37.0528 347.764 37.5685 347.628 37.9629 347.431C37.9629 347.886 38.0994 348.341 38.2207 348.796C38.6151 349.645 39.3886 350.419 40.4352 350.813C40.4959 351.784 40.4959 352.77 40.4959 353.74C40.4352 354.651 40.4352 355.561 40.3593 356.471L40.3745 356.455ZM357.182 311.529C356.332 313.743 355.817 316.018 355.68 318.354C353.86 316.018 352.04 313.607 350.341 311.135C348.839 308.92 347.55 306.842 346.504 304.885L345.851 303.718L345.336 304.946C343.516 309.694 342.272 314.76 341.696 319.901C341.18 324.846 341.301 329.851 342.211 334.66C342.803 338.103 344.092 341.364 345.988 344.276C347.747 347.006 350.023 349.478 352.874 351.754C352.556 352.072 352.161 352.345 351.828 352.664C348.9 355.394 346.564 358.715 344.805 362.811C344.805 361.582 344.805 360.338 344.744 359.11C344.684 357.032 344.547 355.015 344.289 352.997C344.684 352.8 345.063 352.542 345.336 352.148C345.791 351.556 346.109 350.646 346.109 349.736C346.109 348.826 345.791 347.916 345.336 347.325C344.168 345.899 342.211 345.899 340.983 347.264C340.785 347.522 340.664 347.78 340.467 348.037C340.27 348.492 340.148 349.084 340.148 349.66C340.148 350.176 340.285 350.768 340.467 351.223C340.664 351.541 340.785 351.814 341.058 352.072C341.574 352.724 342.287 353.119 343.076 353.179C343.273 355.136 343.47 357.153 343.531 359.095V361.112C343.334 360.202 343.076 359.292 342.818 358.442C342.166 356.562 341.453 354.666 340.482 352.921C340.224 352.406 339.966 351.814 339.633 351.298C338.662 349.676 337.615 348.113 336.387 346.551C333.717 358.063 329.622 369.045 324.359 379.389C324.42 384.394 324.95 389.005 326.24 392.721C327.605 396.559 329.819 399.35 333.262 400.593C325.845 404.37 319.733 409.118 314.985 414.836C314.788 413.41 314.788 412.045 314.849 410.68C314.909 408.921 315.167 407.161 315.501 405.477C316.35 405.477 317.185 405.22 317.776 404.628C318.292 404.112 318.625 403.324 318.823 402.216C318.823 401.822 318.823 401.443 318.762 401.048C318.701 400.336 318.368 399.744 317.988 399.289C317.533 398.773 316.942 398.515 316.365 398.379C316.168 398.379 315.971 398.379 315.713 398.44C314.94 398.5 314.288 398.955 313.757 399.608C313.302 400.26 312.983 401.033 312.907 401.943C312.907 402.793 313.104 403.703 313.559 404.355C313.757 404.613 314.015 404.871 314.333 405.068C313.939 406.888 313.681 408.769 313.559 410.589C313.499 412.409 313.559 414.229 313.878 416.11C312.452 417.93 311.148 419.887 309.904 421.904C310.162 418.324 310.041 415.079 309.51 412.151C309.115 409.618 308.402 407.343 307.432 405.326C303.458 410.27 299.105 414.942 294.494 419.31C294.63 421.98 295.009 424.255 295.54 426.333L292.492 421.191C292.097 421.585 291.718 421.904 291.263 422.298C274.23 437.572 253.48 448.887 230.668 454.803C218.959 457.851 206.673 459.49 194.053 459.49C181.434 459.49 169.467 457.927 157.894 454.939C134.808 449.024 113.938 437.648 96.7073 422.162C89.6239 415.852 83.117 408.829 77.3988 401.23C77.2016 408.39 77.5353 415.276 78.4454 421.646C78.051 420.933 77.596 420.145 77.0803 419.371C74.6686 415.534 72.0749 411.893 68.8291 408.708C69.2841 405.978 69.3448 403.051 68.8291 400.32C69.1476 400.123 69.4206 399.926 69.6026 399.608C70.452 398.44 70.3155 396.68 69.2841 395.634C68.1769 394.587 66.5539 394.663 65.6439 395.891C64.7945 397.12 64.931 398.819 65.9624 399.85C66.4174 400.305 67.0089 400.563 67.5853 400.624C67.9797 402.899 67.9797 405.371 67.7218 407.646C65.5073 405.69 63.1109 404.006 60.4413 402.58C58.5606 401.61 56.5432 400.76 54.3894 400.047C54.5259 398.364 54.3894 396.665 53.9344 394.981C55.2995 393.874 56.2702 391.993 56.9831 389.521C57.6353 387.049 58.0297 383.924 58.151 380.36C58.3482 375.157 58.0904 370.213 57.4988 365.404C54.6321 357.927 52.357 350.191 50.734 342.259C49.2324 344.079 47.9432 346.49 46.8359 349.418C45.668 352.603 44.758 356.38 44.1058 360.869C43.5142 359.823 42.9378 358.791 42.4221 357.745C42.1643 357.29 41.9064 356.835 41.7093 356.44C41.7093 355.53 41.7699 354.62 41.7699 353.71V350.98C43.135 350.98 44.1058 350.131 44.5608 349.099C44.8793 348.25 44.9551 347.279 44.6215 346.43C44.2271 345.322 43.2564 344.412 41.6334 344.352C40.5869 344.352 39.7526 344.61 39.1611 345.065C39.2218 344.867 39.2976 344.61 39.4189 344.352C40.329 341.682 41.4969 338.831 42.6648 335.827C44.6821 330.822 46.7601 325.62 48.0645 321.009C47.928 318.476 47.8673 315.867 47.8673 313.273C47.8673 310.224 48.0038 307.1 48.1252 304.036C47.9887 303.581 47.8673 303.126 47.6702 302.732C46.3051 299.289 44.3484 296.619 41.6183 294.147C40.511 297.529 39.3431 300.851 38.0994 304.218C38.0387 304.355 38.0387 304.476 37.9629 304.612C36.8556 307.676 35.7484 310.725 34.717 313.85C34.1254 315.806 33.6097 317.748 33.094 319.765C32.3811 312.606 31.1374 306.372 29.2566 301.23C32.0475 299.349 35.3085 296.422 37.9629 293.813L40.1773 291.599C43.044 288.474 45.3192 285.228 46.8814 282.104C48.2465 279.373 49.0959 276.583 49.4144 273.655C49.6116 272.29 49.6116 270.864 49.551 269.363C50.5217 272.154 51.3711 275.081 52.1598 278.008C59.3796 249.205 75.1843 223.708 96.7073 204.46C113.938 188.989 134.808 177.598 157.894 171.683C169.467 168.695 181.631 167.133 194.053 167.133C206.476 167.133 218.959 168.756 230.668 171.819C253.495 177.735 274.23 189.05 291.263 204.324C312.847 223.572 328.651 249.129 335.871 277.932C336.008 277.417 336.19 276.886 336.326 276.431C337.1 281.77 338.404 286.047 340.482 289.627C340.876 290.218 341.195 290.795 341.589 291.386C344.653 295.679 349.067 298.803 355.377 301.594C355.316 304.976 355.892 308.359 357.197 311.408V311.468L357.182 311.529Z\" fill=\"black\"><\/path><path d=\"M200.151 30.8812C198.012 31.852 198.467 34.1271 200.287 35.3102C202.426 36.6753 203.73 41.3621 204.519 46.1703C205.293 50.9177 205.566 55.8624 205.687 58.001C205.945 62.0356 206.005 66.1916 205.823 69.9077C205.687 73.1535 205.368 76.0809 204.853 78.3561C204.595 79.2661 204.337 80.1155 204.003 80.8284C203.29 82.6485 202.835 83.9529 204.853 85.9702C204.989 86.1067 205.171 86.2281 205.308 86.3646C205.763 86.6831 206.218 86.8803 206.733 86.8803C207.188 86.8803 207.704 86.6224 208.235 86.1067C208.432 85.9702 208.554 85.7882 208.69 85.591C209.6 84.4231 210.313 82.4665 210.768 79.8728C211.223 77.2033 211.481 73.8209 211.42 69.8015C211.42 64.3411 211.162 57.8949 210.192 51.661C209.221 45.427 207.659 39.3751 204.989 34.749C204.398 33.7024 203.685 32.4738 202.851 31.6245C202.077 30.9116 201.167 30.5172 200.181 30.9116L200.151 30.8812Z\" fill=\"#FFE200\"><\/path><path d=\"M219.975 113.135C219.125 113.59 217.245 115.092 217.108 115.547C217.108 115.092 215.606 113.408 214.772 112.68C207.81 112.089 200.924 111.831 194.023 111.831C187.122 111.831 180.175 112.089 173.349 112.68C172.5 113.333 170.938 115.092 170.938 115.547C170.801 115.031 168.92 113.59 168.01 113.135C153.51 114.637 139.268 117.428 125.48 121.463C124.707 121.66 123.857 122.828 123.918 123.419C123.918 124.071 125.419 123.419 126.512 123.161C127.937 122.843 127.422 124.132 128.134 124.329C128.59 124.39 129.181 124.329 130.546 123.935C130.607 124.39 129.636 124.648 128.863 125.497C127.952 126.544 127.558 127.772 129.575 127.636C131.138 127.575 131.714 127.12 132.306 127.378C133.352 127.772 132.503 128.349 134.323 127.894C154.026 123.283 174.047 120.932 194.008 120.932C217.214 120.932 240.497 124.117 263.187 130.366C261.367 127.636 265.144 127.241 267.086 127.954C268.056 128.349 272.88 130.821 276.323 130.366C279.766 129.911 278.598 128.485 276.717 127.317C274.381 125.891 271.378 125.436 270.665 125.497C268.906 125.634 261.504 123.677 261.822 122.448C265.205 123.358 268.784 124.466 272.227 124.587C255.513 118.793 237.888 115.031 219.944 113.135H219.975Z\" fill=\"#FFE200\"><\/path><path d=\"M176.671 69.7708C176.61 73.8054 176.868 77.1877 177.323 79.8421C177.839 82.4358 178.491 84.3924 179.401 85.5603C179.538 85.7575 179.72 85.9547 179.856 86.076C180.372 86.5917 180.903 86.8496 181.358 86.8496C181.874 86.8496 182.329 86.6524 182.784 86.3339C182.92 86.1973 183.102 86.076 183.239 85.9395C185.256 83.9222 184.801 82.6178 184.088 80.7977C183.77 80.0848 183.497 79.2354 183.239 78.3253C182.723 76.0502 182.389 73.1228 182.268 69.8769C182.071 66.176 182.131 62.0049 182.405 57.9703C182.541 55.8317 182.799 50.887 183.572 46.1395C184.225 42.3021 185.135 38.6012 186.56 36.5232C187.668 34.9609 190.079 30.2135 185.65 31.5786C185.332 32.0336 184.998 32.5493 184.74 33.1408C183.83 35.2795 183.178 38.3433 182.662 41.0735C182.207 43.2122 181.813 45.1688 181.358 46.276C179.341 50.8263 178.173 54.0722 177.46 57.5304C176.808 60.9128 176.686 64.5531 176.686 69.7556L176.671 69.7708Z\" fill=\"#FFE200\"><\/path><path d=\"M193.128 76.005C190.656 75.5499 188.836 73.4113 188.836 70.8631C188.836 68.0723 191.05 65.7213 193.78 65.6C190.914 65.4634 188.638 63.0669 188.638 60.2003C188.638 57.3336 190.853 54.9978 193.644 54.8006C191.05 54.5427 188.957 52.3889 188.957 49.7346C188.957 47.2622 190.777 45.1843 193.189 44.7292C191.232 44.4107 189.67 42.9091 189.215 41.0283C186.485 42.1356 185.059 44.9264 184.604 47.6566C184.012 51.8884 183.754 56.105 183.633 58.0616C183.436 62.0962 183.375 66.1915 183.497 69.8317C183.633 73.0169 183.952 75.8836 184.467 78.0223C184.664 78.9323 184.983 79.6452 185.241 80.3581C185.954 82.3147 186.545 83.7405 185.104 85.6971C185.817 85.4393 186.606 85.2421 187.379 85.1814C187.698 83.5585 188.487 82.2541 189.518 81.344C189.457 81.0861 189.457 80.8283 189.457 80.5704C189.457 78.356 191.02 76.4752 193.098 76.0201L193.128 76.005Z\" fill=\"#FFE200\"><\/path><path d=\"M203.594 78.0224C204.11 75.8838 204.443 73.0171 204.565 69.8319C204.701 66.1917 204.625 62.0964 204.428 58.0618C204.292 55.9231 203.973 50.9785 203.199 46.3523C203.063 45.3816 202.881 44.3957 202.684 43.4856C202.229 41.2105 200.803 40.0426 198.907 38.7988C199.423 41.529 197.678 44.1985 194.872 44.7142C197.284 45.1693 199.104 47.2472 199.104 49.7196C199.104 52.3891 197.026 54.5277 194.417 54.7856C197.208 54.9827 199.423 57.3186 199.423 60.1853C199.423 63.0519 197.148 65.4484 194.281 65.5849C197.011 65.7215 199.226 68.0573 199.226 70.8481C199.226 73.3811 197.405 75.5349 194.933 75.99C197.011 76.445 198.573 78.3258 198.573 80.5403C198.573 80.7981 198.573 81.056 198.513 81.3138C199.559 82.2239 200.333 83.5283 200.651 85.1512C201.501 85.2119 202.274 85.4091 202.987 85.7428C201.486 83.7862 202.016 82.2997 202.79 80.3431C203.048 79.6302 203.382 78.9173 203.564 78.0073L203.594 78.0224Z\" fill=\"#FFE200\"><\/path><path d=\"M95.3876 112.423C95.1298 112.741 94.5382 112.68 94.3411 112.286C93.2945 110.527 92.0659 109.419 90.7008 108.843C89.3357 108.267 87.91 108.191 86.469 108.585C85.0433 108.904 83.6782 109.692 82.5709 110.8C81.0693 112.165 79.9773 114.121 79.7043 116.26C79.6436 116.851 79.5677 117.428 79.5677 118.141C79.5677 119.187 79.7043 120.279 80.0835 121.189C80.4778 121.963 81.0542 122.555 81.9642 122.691C82.1007 122.691 82.2828 122.752 82.4193 122.752C83.0108 122.752 83.5265 122.555 83.9815 122.236C84.3759 121.978 84.6337 121.644 84.8309 121.265C85.0281 120.871 85.1495 120.416 85.1495 119.961C85.1495 119.445 85.0129 118.914 84.6944 118.459C84.5579 118.323 84.5579 117.944 84.6338 117.807C85.4073 116.123 86.4539 115.138 87.6825 114.758C88.7897 114.364 90.0941 114.44 91.3227 114.956C92.2934 115.274 93.2793 115.926 94.1135 116.639C95.5393 117.807 96.328 119.824 98.2088 118.065C98.8004 117.549 99.2554 116.897 99.5132 116.184C99.9076 115.335 101.076 115.79 100.681 116.639C100.363 117.549 99.7711 118.323 99.1189 118.975C96.5859 120.992 98.6032 120.992 98.6032 124.238C98.6032 124.633 98.6638 124.951 98.8004 125.285C99.5739 127.302 102.896 128.015 104.776 127.241C132.473 116.123 163.233 110.527 193.993 110.527C224.753 110.527 255.437 116.123 283.133 127.241C284.953 128.015 288.336 127.302 289.109 125.285C291.445 120.477 281.176 121.129 277.733 118.778C276.11 118.004 274.548 116.76 273.304 114.88C273.107 114.561 273.244 114.03 273.623 113.97C275.125 113.515 275.959 112.468 276.353 111.376C276.55 110.663 276.611 109.95 276.55 109.237C276.414 108.524 276.156 107.872 275.701 107.281C275.049 106.31 273.881 105.658 272.379 105.658C271.469 105.658 270.696 105.916 270.043 106.31C269.452 106.704 268.997 107.22 268.618 107.872C268.299 108.524 268.102 109.237 268.102 109.95C268.102 110.724 268.36 111.512 268.815 112.225C269.012 112.544 268.815 113.075 268.42 113.135C263.536 114.637 259.441 114.819 255.877 113.727C252.297 112.68 249.249 110.284 246.382 106.446C246.063 105.991 246.64 105.279 247.231 105.536C250.28 107.099 252.889 106.507 254.572 105.081C255.482 104.308 256.135 103.322 256.529 102.215C256.984 101.107 257.121 99.9395 256.923 98.893C256.666 96.9363 255.3 95.192 252.692 94.6005C252.434 94.5398 252.176 94.2061 252.176 93.9483C252.373 91.7338 251.584 90.1109 250.356 89.0036C249.643 88.4121 248.854 88.0329 248.02 87.8357C247.11 87.6385 246.2 87.6385 245.35 87.8357C243.727 88.2908 242.287 89.398 241.513 91.476C241.452 91.7338 241.058 91.931 240.8 91.8703C238.131 91.2181 236.189 92.1888 235.082 93.7511C234.43 94.7218 234.035 95.9656 233.975 97.1942C233.914 98.4228 234.111 99.6665 234.688 100.774C235.658 102.791 237.812 104.277 241.255 104.02C241.847 103.959 242.165 104.869 241.65 105.188C238.07 107.523 233.656 108.691 229.288 108.115C225.511 107.599 221.81 105.703 218.883 102.063C218.564 101.669 218.822 101.016 219.338 101.016C221.219 100.88 222.387 99.7879 222.917 98.4834C223.115 97.8919 223.175 97.2548 223.175 96.6026C223.175 95.9504 222.978 95.3741 222.72 94.7825C222.129 93.4781 220.9 92.5074 219.019 92.5074C217.457 92.5074 216.289 93.2202 215.637 94.191C215.182 94.7825 214.924 95.4196 214.863 96.1476C214.727 96.8605 214.803 97.5734 215 98.2256C215.394 99.3935 216.304 100.44 217.791 100.819C218.306 101.016 218.382 101.729 217.927 101.987C213.377 104.717 209.145 106.082 205.247 105.627C201.349 105.233 197.769 102.958 194.584 98.3469C194.19 97.8312 194.979 97.0425 195.494 97.4369C196.268 98.1497 197.512 98.4834 198.877 98.4834C199.923 98.4834 201.015 98.2862 202.001 97.8312C202.972 97.4369 203.882 96.8605 204.534 96.0111C205.308 95.101 205.763 93.8725 205.763 92.3102C205.763 90.7479 205.111 89.1856 204.079 88.0784C203.033 87.0318 201.668 86.3948 200.045 86.4555C199.787 86.4555 199.453 86.1369 199.453 85.8639C199.256 84.4988 198.74 83.4523 198.027 82.6787C197.254 84.1045 195.813 85.0904 194.053 85.151C195.282 90.217 195.221 89.8379 200.621 91.0664C198.088 91.0058 195.676 91.1271 193.993 93.0837C192.309 91.1271 189.897 91.0058 187.364 91.0664C192.764 89.8379 192.703 90.217 193.932 85.151C192.173 85.0904 190.747 84.1045 189.958 82.6787C189.245 83.4523 188.73 84.4988 188.532 85.8639C188.532 86.1218 188.214 86.4555 187.941 86.4555C186.439 86.3948 184.953 86.9712 183.846 87.8812C182.875 88.7306 182.283 89.8985 182.344 91.2029C182.344 92.113 182.799 92.8866 183.451 93.5388C183.77 93.7966 184.164 94.0545 184.558 94.191C184.953 94.3882 185.332 94.4488 185.726 94.3882C186.242 94.3882 186.834 94.191 187.289 93.6753C187.683 93.2202 188.517 93.6753 188.335 94.2668C188.199 95.0404 188.274 95.7684 188.532 96.3448C188.73 96.8605 189.124 97.3155 189.503 97.6492C189.958 97.9071 190.413 98.1042 190.929 98.1042C191.384 98.1042 191.9 97.9677 192.355 97.5885C192.87 97.1942 193.583 97.9829 193.265 98.4986C190.079 103.049 186.5 105.263 182.602 105.718C178.704 106.113 174.472 104.672 169.982 102.018C169.527 101.76 169.588 101.047 170.119 100.85C171.545 100.455 172.455 99.4238 172.849 98.2559C173.107 97.6037 173.167 96.8908 173.046 96.1779C172.925 95.4651 172.652 94.8129 172.273 94.2213C171.56 93.2506 170.452 92.5377 168.89 92.5377C167.009 92.5377 165.766 93.5084 165.113 94.8128C164.856 95.4044 164.719 95.9808 164.719 96.633C164.658 97.2852 164.78 97.9374 164.977 98.5138C165.493 99.8182 166.661 100.925 168.557 101.047C169.012 101.047 169.33 101.699 169.012 102.093C166.084 105.734 162.383 107.614 158.606 108.145C154.253 108.737 149.824 107.554 146.184 105.218C145.729 104.899 145.987 103.989 146.639 104.05C150.022 104.368 152.16 102.943 153.207 100.925C153.798 99.8182 154.056 98.4531 153.98 97.2245C153.844 95.9201 153.465 94.6915 152.812 93.7056C151.705 92.1433 149.764 91.2333 147.155 91.8855C146.897 91.9462 146.503 91.749 146.442 91.4911C145.668 89.4132 144.228 88.3059 142.605 87.8509C141.755 87.6537 140.845 87.6537 139.935 87.8509C139.086 88.0481 138.312 88.4424 137.599 89.0188C136.371 90.126 135.582 91.749 135.779 93.9635C135.779 94.2213 135.521 94.555 135.263 94.6157C132.67 95.1314 131.365 96.8908 131.032 98.8475C130.834 99.894 130.971 101.062 131.35 102.169C131.745 103.216 132.397 104.247 133.231 105.036C134.915 106.537 137.523 107.114 140.648 105.627C141.164 105.37 141.755 106.082 141.422 106.537C138.555 110.314 135.506 112.711 131.927 113.757C128.347 114.865 124.312 114.667 119.383 113.166C118.989 113.105 118.867 112.574 119.064 112.256C119.519 111.543 119.717 110.754 119.717 109.981C119.717 109.268 119.58 108.555 119.201 107.903C118.882 107.25 118.427 106.735 117.775 106.34C117.184 105.946 116.41 105.688 115.5 105.688C113.998 105.688 112.83 106.34 112.118 107.311C111.723 107.903 111.465 108.54 111.344 109.268C111.283 109.981 111.283 110.693 111.541 111.406C111.936 112.514 112.77 113.545 114.271 114C114.59 114.061 114.787 114.592 114.59 114.91C113.361 116.791 111.799 118.035 110.161 118.808C108.144 119.779 106.005 120.113 104.048 120.037C103.533 120.037 103.199 119.445 103.533 119.066C104.579 117.762 105.156 116.139 105.156 114.576C105.156 113.803 105.019 113.075 104.761 112.438C104.443 111.785 104.048 111.209 103.533 110.754C102.683 110.163 101.652 109.783 100.211 109.783C99.1037 109.723 98.2543 109.981 97.4808 110.436C96.7072 110.891 95.9792 111.603 95.3421 112.453L95.3876 112.423Z\" fill=\"#FFE200\"><\/path><path d=\"M197.739 39.7995C197.739 37.7822 196.055 36.0986 194.038 36.0986C192.021 36.0986 190.337 37.7822 190.337 39.7995C190.337 41.8168 192.021 43.5763 194.038 43.5763C196.055 43.5763 197.739 41.8927 197.739 39.7995Z\" fill=\"#FFE200\"><\/path><path d=\"M160.472 491.387C159.956 492.555 160.214 493.86 161.064 494.77C161.716 495.422 162.565 495.741 163.339 496.074C162.034 498.744 160.153 499.972 157.09 499.654C153.768 499.259 151.174 497.773 149.551 495.68C148.702 494.633 148.126 493.465 147.792 492.237C147.473 491.008 147.337 489.704 147.473 488.399C147.792 485.609 149.293 482.802 152.024 480.664C155.012 478.252 161.003 476.311 166.387 474.491C168.526 473.778 170.619 473.126 172.303 472.473C174.836 471.503 176.08 469.607 176.277 467.862C176.413 466.694 176.019 465.39 174.972 464.677C174.062 464.086 172.697 464.086 170.938 465.132C167.161 467.347 163.657 468.712 160.017 470.077C158.136 470.85 156.119 471.578 154.102 472.488C149.491 474.566 145.653 477.949 143.242 481.923C140.314 486.731 139.146 492.646 141.482 497.849C142.787 500.716 145.001 503.309 148.444 505.387C152.084 507.662 156.513 508.117 160.351 507.147C163.475 506.297 166.524 504.477 168.223 501.686C170.179 498.562 170.301 493.299 167.631 490.508C165.553 488.369 161.716 488.49 160.472 491.418V491.387Z\" fill=\"#FFE200\"><\/path><path d=\"M233.96 472.458C231.942 471.548 229.925 470.835 228.044 470.046C224.404 468.681 220.885 467.316 217.123 465.102C214.651 463.676 211.663 463.6 208.736 463.676C210.692 465.815 211.921 468.165 214.135 470.243C215.045 471.154 215.895 471.866 216.729 472.519C218.231 473.565 219.914 474.02 221.613 474.597C227.073 476.356 233.125 478.298 236.053 480.649C238.783 482.787 240.284 485.593 240.603 488.384C240.861 490.978 240.148 493.587 238.525 495.664C236.902 497.742 234.293 499.244 230.987 499.638C227.923 499.957 226.042 498.728 224.738 496.059C225.511 495.74 226.361 495.407 227.013 494.754C227.862 493.844 228.12 492.54 227.604 491.372C226.376 488.445 222.538 488.323 220.445 490.462C217.776 493.253 217.912 498.531 219.854 501.641C221.537 504.431 224.601 506.251 227.726 507.101C231.563 508.072 235.977 507.617 239.632 505.341C243.075 503.264 245.29 500.655 246.594 497.803C248.93 492.601 247.762 486.685 244.835 481.877C242.423 477.918 238.586 474.536 233.975 472.443L233.96 472.458Z\" fill=\"#FFE200\"><\/path><path d=\"M219.52 489.567C220.369 488.718 221.34 488.202 222.311 487.944C223.357 487.687 224.328 487.687 225.299 487.884C226.148 488.142 226.922 488.597 227.574 489.188C228.09 489.704 228.484 490.295 228.742 490.948C229.06 491.66 229.197 492.51 229.06 493.359C228.924 494.209 228.545 494.982 227.892 495.695C227.498 496.014 227.043 496.408 226.467 496.742C226.861 497.333 227.377 497.712 227.892 497.97C228.742 498.425 229.713 498.486 230.759 498.425C233.747 498.031 236.022 496.742 237.524 494.922C238.237 494.011 238.752 493.041 239.025 491.933C239.344 490.826 239.42 489.719 239.283 488.551C239.025 486.079 237.721 483.606 235.249 481.665C232.519 479.45 226.542 477.57 221.203 475.81C220.43 475.552 219.702 475.355 219.323 475.219C217.958 474.764 216.987 474.248 216.001 473.596C215.091 472.944 214.242 472.17 213.21 471.184C212.164 470.138 211.193 469.106 210.222 467.999L210.161 467.938C209.449 467.741 208.66 467.544 207.947 467.347C207.628 467.286 207.355 467.15 207.037 467.089C208.599 468.06 210.086 469.227 211.39 470.532C215.819 474.885 218.61 480.998 218.61 487.702C218.61 488.87 218.549 490.113 218.352 491.281C218.67 490.629 219.065 490.053 219.52 489.598V489.567Z\" fill=\"#FFE200\"><\/path><path d=\"M210.541 474.612C206.187 473.247 201.759 472.018 197.269 471.29C194.084 470.699 195.646 471.882 194.144 474.475C192.84 476.751 191.475 479.086 189.988 481.498C188.82 483.455 187.577 485.396 186.287 487.353C185.893 488.005 185.772 488.46 186.424 488.854C187.334 489.37 188.563 489.446 189.549 489.507C195.145 490.022 200.469 492.753 205.156 495.816C206.46 496.59 208.796 498.547 210.101 498.683C210.753 498.82 211.329 498.486 212.118 497.576H212.057C212.77 496.529 213.68 495.559 214.272 494.451C215.834 491.66 213.62 489.385 211.284 488.081C205.945 485.093 200.227 482.818 194.372 481.195C193.522 480.937 193.856 479.693 194.69 479.966C199.954 481.468 205.095 483.409 209.904 485.882C212.694 487.307 214.454 484.38 214.97 482.105C215.682 478.722 213.923 475.674 210.541 474.627V474.612Z\" fill=\"#FFE200\"><\/path><path d=\"M194.675 466.679C194.736 467.65 195.07 469.667 196.101 469.804C200.393 470.395 204.625 471.487 208.781 472.731C209.373 472.928 210.01 472.928 210.404 472.337C210.541 472.14 210.662 471.563 210.465 471.366C206.491 467.468 201.167 464.996 195.252 464.662C195.252 464.662 195.231 464.682 195.191 464.723C194.675 465.041 194.599 465.951 194.675 466.679Z\" fill=\"#FFE200\"><\/path><path d=\"M204.625 497.105C199.165 494.769 196.829 499.062 192.597 500.882C189.078 502.383 184.983 503.293 181.221 503.157C181.737 504.325 182.587 505.371 183.633 506.282L184.027 505.766C184.543 504.992 185.59 505.766 185.074 506.479L184.619 507.07C184.938 507.328 185.211 507.525 185.529 507.722C185.787 507.465 185.923 507.07 185.984 506.676C186.181 505.826 187.41 506.084 187.213 506.934C187.152 507.449 186.955 507.98 186.621 508.435C187.076 508.693 187.531 508.951 188.047 509.148C188.305 508.632 188.502 508.102 188.563 507.525C188.699 506.615 189.988 506.812 189.791 507.722C189.731 508.435 189.473 509.088 189.2 509.679C189.913 509.998 190.625 510.271 191.278 510.453C191.535 509.679 191.672 508.951 191.596 508.238C191.535 507.328 192.825 507.267 192.901 508.102C192.901 508.951 192.84 509.785 192.582 510.635C193.037 510.695 193.553 510.695 194.008 510.695H194.523C194.721 509.725 194.781 508.739 194.842 507.768C194.842 506.858 196.071 506.919 196.071 507.829C196.071 508.739 196.01 509.709 195.813 510.619C196.662 510.559 197.496 510.422 198.346 510.301C198.406 509.194 198.406 508.086 198.285 506.979C198.224 506.069 199.453 505.933 199.589 506.843C199.65 507.889 199.65 508.921 199.65 509.967C200.363 509.77 201.152 509.573 201.865 509.315C201.865 508.147 201.804 506.903 201.546 505.735C201.349 504.886 202.653 504.628 202.775 505.538C203.033 506.585 203.093 507.677 203.169 508.784C203.882 508.466 204.671 508.132 205.308 507.738C205.368 506.63 205.505 505.66 205.171 504.613C204.974 503.703 206.218 503.385 206.4 504.295C206.658 505.265 206.658 506.175 206.658 506.964C207.31 506.509 207.826 505.66 207.704 504.886C207.644 504.689 207.568 504.492 207.507 504.234C207.113 503.384 208.281 502.869 208.614 503.718C208.614 503.718 208.634 503.764 208.675 503.855C208.933 503.202 209.13 502.55 209.069 501.898C209.009 499.684 206.476 497.863 204.58 497.09L204.625 497.105Z\" fill=\"#FFE200\"><\/path><path d=\"M186.105 501.458C189.291 500.943 195.145 499.244 196.829 496.119C197.542 494.891 197.026 492.798 195.661 492.282C192.537 491.053 188.32 490.204 184.862 490.598C183.633 490.735 182.526 491.19 181.358 491.372C180.964 491.433 180.584 491.508 180.19 491.508C178.112 491.645 175.958 490.796 174.472 489.37C173.82 488.718 174.669 487.808 175.321 488.46C176.626 489.688 178.446 490.341 180.129 490.28C180.584 490.28 180.979 490.219 181.358 490.083C182.526 489.825 183.633 489.112 184.346 488.005C185.969 485.593 187.471 483.197 188.896 480.846C190.322 478.51 191.763 476.159 193.128 473.823C194.493 471.351 194.69 467.847 192.081 466.209C191.945 466.148 191.884 466.072 191.763 466.072C190.853 465.617 187.865 465.617 188.381 467.301C188.699 468.469 190.064 469.121 190.337 470.486C190.474 471.335 190.277 472.17 189.685 473.535C188.123 476.917 186.242 480.163 184.225 483.288C183.709 484.061 182.662 483.348 183.178 482.575C185.195 479.526 187.015 476.401 188.517 473.019C188.972 471.912 189.169 471.26 189.033 470.744C188.896 469.97 187.926 468.863 187.273 468.332C185.514 467.104 183.299 467.559 181.358 468.59C179.856 469.364 178.491 470.471 177.581 471.381C173.349 475.537 170.756 481.27 170.756 487.641C170.756 491.539 171.726 495.255 173.486 498.44C175.048 500.973 178.233 501.762 181.358 501.822C183.042 501.883 184.74 501.686 186.105 501.428V501.458ZM178.946 479.162C179.598 478.191 180.311 477.281 180.903 476.295C181.039 476.098 181.221 475.84 181.358 475.643C181.813 474.87 182.268 474.141 182.723 473.429C183.178 472.655 184.285 473.292 183.77 474.081C183.178 475.052 182.602 476.037 182.01 477.008C181.752 477.327 181.555 477.6 181.358 477.918C180.903 478.57 180.448 479.223 179.993 479.875C179.401 480.648 178.37 479.875 178.946 479.162Z\" fill=\"#FFE200\"><\/path><path d=\"M174.851 472.534C174.26 472.989 173.547 473.383 172.773 473.641C171.014 474.293 168.936 475.006 166.797 475.719C161.534 477.478 155.618 479.42 152.812 481.634C150.34 483.591 149.036 486.063 148.778 488.52C148.641 489.688 148.717 490.796 149.036 491.903C149.294 493.01 149.809 493.981 150.537 494.891C152.812 497.758 157.818 499.183 159.638 495.027C159.319 494.512 159.122 493.92 158.986 493.344C158.849 492.494 158.986 491.66 159.304 490.932C159.562 490.28 159.956 489.704 160.472 489.173C161.124 488.581 161.898 488.126 162.747 487.868C163.718 487.671 164.704 487.671 165.735 487.929C166.706 488.187 167.692 488.703 168.526 489.552C168.981 490.007 169.376 490.598 169.694 491.236C169.497 490.068 169.436 488.824 169.436 487.656C169.436 481.938 171.454 476.675 174.836 472.503L174.851 472.534Z\" fill=\"#FFE200\"><\/path><path d=\"M199.165 459.459C197.481 459.459 195.722 459.52 194.023 459.52C192.461 459.52 190.838 459.52 189.276 459.459C186.94 459.398 185.12 462.326 187.455 464.267C189.533 463.676 191.748 463.357 194.023 463.357C199.165 463.357 204.428 465.041 209.373 466.421C207.75 463.888 202.35 459.338 199.165 459.459Z\" fill=\"#FFE200\"><\/path><path d=\"M153.586 471.29C155.664 470.38 157.681 469.667 159.638 468.878C163.217 467.513 166.661 466.148 170.361 463.994C170.619 463.858 170.877 463.737 171.135 463.6C171.529 462.751 171.59 461.977 171.332 461.188C169.967 461.249 168.86 461.386 167.95 461.507C165.811 461.765 164.962 461.704 164.765 459.368C164.704 458.853 164.704 458.2 164.628 457.351C163.718 457.745 162.869 458.064 162.216 458.398C161.367 458.853 160.654 459.308 160.078 459.763C159.941 459.899 159.623 459.899 159.426 459.823C157.469 458.974 155.33 458.2 153.176 457.806C151.099 457.351 148.945 457.214 146.867 457.487C146.351 457.624 145.957 456.972 146.275 456.517C146.73 455.804 147.246 455.091 147.837 454.378C148.035 454.12 148.232 453.862 148.49 453.605C148.095 453.665 147.716 453.741 147.322 453.862C146.351 454.06 145.502 454.317 144.592 454.636C144.076 454.772 143.621 454.181 143.879 453.726L145.244 451.254C144.076 451.314 142.908 451.511 141.801 451.769C140.375 452.027 138.873 452.482 137.448 453.074C136.993 453.271 136.401 452.679 136.674 452.224L138.297 448.448L138.16 448.387C136.401 448.705 134.642 449.1 132.897 449.494C132.442 449.555 132.048 449.1 132.184 448.645L132.958 446.112C132.761 445.975 132.564 445.915 132.366 445.793C130.683 446.9 129.121 447.613 127.68 448.008C126.375 448.265 125.147 448.265 124.161 447.81C123.114 447.355 122.341 446.445 121.886 445.08C121.491 443.912 121.37 442.289 121.567 440.196C121.506 440.196 121.431 440.136 121.37 440.136L119.413 441.759C119.019 442.077 118.367 441.759 118.367 441.304L118.169 438.24C118.033 438.103 117.912 438.043 117.775 437.982C117.381 438.3 116.926 438.695 116.471 439.089C116.334 439.226 116.213 439.286 116.152 439.347C115.834 439.665 115.181 439.408 115.106 438.953C115.045 438.103 115.045 437.33 115.106 436.617C114.453 437.072 113.801 437.466 113.028 437.724C112.633 437.86 112.178 437.587 112.178 437.208C112.118 436.238 112.042 435.252 112.118 434.342C111.92 434.144 111.663 434.023 111.465 433.887C110.692 434.281 109.903 434.539 109.13 434.539C108.219 434.599 107.309 434.402 106.521 433.947C105.747 433.492 105.095 432.901 104.64 432.066C104.048 431.02 103.73 429.791 103.927 428.29C100.878 425.878 97.951 423.406 95.0843 420.812C94.9478 421.525 94.7658 422.177 94.4927 422.89C93.5827 425.878 92.2783 428.35 90.5947 430.959C89.1689 433.037 87.9858 435.054 87.0758 437.39C86.3022 439.271 84.8613 442.593 85.5742 444.61C86.1657 446.37 88.3043 446.43 89.6694 445.657C90.261 444.094 90.898 442.608 91.4896 441.106C92.2631 439.347 92.9911 437.724 93.704 436.222C94.0984 435.373 95.2056 435.965 94.8113 436.738C94.0984 438.3 93.3855 439.923 92.6726 441.546C92.0204 443.23 91.3075 444.929 90.6553 446.552C90.3368 447.462 90.4581 449.342 90.9132 450.192C91.3075 451.102 92.0811 451.496 93.0518 451.299C94.1591 451.041 95.0691 450.389 95.4635 449.418C95.9792 448.053 96.51 446.749 97.0864 445.52C97.6021 444.155 98.1937 442.79 98.8459 441.364C99.1644 440.515 100.347 441.046 100.014 441.88C99.4222 443.184 98.8459 444.549 98.2543 445.975C97.6628 447.401 97.0864 448.842 96.4949 450.268C95.9792 451.436 95.782 452.937 96.0399 454.242C96.237 455.288 96.8134 456.198 97.7235 456.835C98.77 457.487 100.256 456.244 100.59 455.334C100.909 454.424 101.182 453.514 101.5 452.603L102.152 450.647C102.471 449.797 103.715 450.192 103.381 451.041L102.668 453.059C102.41 453.908 102.077 454.818 101.758 455.728C101.303 457.093 101.167 458.519 101.364 459.884C101.622 461.113 102.137 462.356 103.047 463.327C103.7 464.101 104.276 464.829 105.262 464.374C105.914 464.116 106.49 463.524 106.688 462.948C107.461 460.809 108.25 458.519 108.963 456.32C109.418 455.015 109.812 453.787 110.131 452.998C110.388 452.148 111.632 452.543 111.299 453.392C110.844 454.757 110.525 455.728 110.191 456.714C109.418 458.928 108.69 461.067 107.916 463.342C107.4 464.768 107.4 466.072 107.719 466.922C108.113 467.892 108.887 468.347 109.858 468.287C111.162 468.15 112.451 467.119 112.588 465.814C112.724 464.586 112.906 463.084 113.24 461.461C113.634 459.505 114.15 457.305 114.742 454.894C114.999 454.044 116.243 454.378 115.97 455.212C115.379 457.548 114.863 459.763 114.469 461.719C114.15 463.539 113.877 465.162 113.816 466.527C113.756 467.498 113.877 468.15 114.211 468.484C114.529 468.939 115.06 469 115.576 468.803C116.622 468.484 117.199 467.437 117.714 466.467C118.488 464.965 119.14 463.281 119.671 461.461C120.263 459.247 120.778 456.911 121.173 454.242C121.309 453.392 122.538 453.589 122.401 454.439C122.007 457.169 121.491 459.581 120.9 461.78C120.308 463.737 119.671 465.481 118.822 467.043C117.851 468.924 118.23 472.898 121.097 470.623C122.978 469.197 125.071 465.481 126.299 463.281C126.618 462.629 126.952 462.114 127.149 461.856C127.604 461.082 128.711 461.719 128.195 462.508C127.998 462.826 127.74 463.281 127.422 463.934C126.315 465.814 124.692 468.818 122.811 470.698C121.643 472.003 119.823 474.217 120.217 476.038C120.414 476.948 121.127 477.463 122.037 477.463C123.721 477.524 124.965 475.901 125.814 474.597C126.982 472.64 128.286 470.896 129.591 469.136C131.017 467.255 132.457 465.435 133.883 463.676C134.475 463.024 135.445 463.812 134.854 464.525C133.352 466.285 131.927 468.105 130.622 469.925C129.318 471.548 128.089 473.307 126.921 475.188C126.148 476.356 124.843 477.403 124.449 478.707C124.055 479.875 124.13 480.785 124.449 481.437C124.707 482.029 125.298 482.347 125.951 482.287C127.058 482.15 128.089 481.119 128.681 480.269C130.501 477.676 132.382 475.203 134.399 472.731C136.356 470.319 138.494 467.983 140.648 465.708C141.3 465.056 142.21 465.966 141.558 466.618C139.419 468.833 137.326 471.169 135.385 473.58C133.368 475.916 131.547 478.464 129.727 480.997C129.212 481.847 128.559 482.423 127.968 482.817C127.194 484.638 127.452 486.716 128.226 488.02C128.544 488.414 128.878 488.733 129.196 488.991C131.077 489.961 132.579 486.579 133.034 485.411C134.202 482.544 135.764 480.072 137.584 477.933C139.465 475.856 141.619 474.035 143.955 472.412C144.212 472.215 144.47 472.018 144.865 472.549C145.183 473.065 144.925 473.262 144.667 473.459C142.453 475.021 140.314 476.781 138.555 478.798C136.795 480.876 135.309 483.151 134.262 485.881C133.61 487.565 131.927 489.203 133.671 490.887C133.989 491.205 134.444 491.478 134.899 491.6C135.354 491.797 135.87 491.797 136.401 491.736C137.448 491.6 138.479 490.826 139.131 489.142C139.526 486.473 140.557 483.743 142.059 481.27C144.652 477.114 148.626 473.535 153.51 471.32L153.586 471.29Z\" fill=\"#FFE200\"><\/path><path d=\"M267.055 453.483C261.595 450.753 255.68 449.054 251.19 447.886H251.129C251.387 448.66 251.19 449.388 251.19 450.222C251.129 450.616 250.674 450.935 250.28 450.738C249.309 450.283 248.521 449.828 247.747 449.373C248.141 450.222 248.399 451.132 248.596 452.239C248.657 452.694 248.278 453.089 247.823 452.952C246.518 452.694 245.229 452.3 243.985 451.906C243.728 451.845 242.939 451.314 242.681 451.253C243.394 451.966 244.638 453.074 245.548 453.923C245.942 454.317 245.411 455.152 244.895 454.97C242.817 454.257 241.255 453.407 239.435 452.437C240.148 453.802 241.195 455.303 242.165 456.532C242.484 457.047 241.771 457.836 241.255 457.442C239.374 456.213 237.554 454.848 235.795 453.407C235.537 453.468 235.279 453.604 235.021 453.665C235.416 454.712 235.871 455.743 236.326 456.729C236.584 457.321 235.673 457.897 235.279 457.442C234.43 456.395 233.596 455.364 232.867 454.257C231.639 454.575 230.395 454.909 229.167 455.227C230.334 456.456 231.578 457.639 232.807 458.746C233.52 459.338 232.67 460.309 231.957 459.717C230.456 458.413 229.091 457.048 227.801 455.561C226.831 455.819 225.845 456.016 224.935 456.213L228.378 459.99C228.969 460.642 228.059 461.492 227.407 460.839L223.433 456.547C222.129 456.805 220.764 457.063 219.399 457.321C219.914 457.715 220.445 458.17 221.022 458.549C222.326 459.52 223.615 460.43 225.056 461.34C225.83 461.795 225.117 462.902 224.343 462.447C222.917 461.537 221.552 460.566 220.248 459.58C219.399 458.928 218.564 458.276 217.776 457.563C216.805 457.76 215.758 457.882 214.788 458.018C215.637 459.58 216.547 460.946 217.654 462.174C219.08 463.797 220.642 465.162 222.462 466.269C222.66 466.406 222.857 466.527 223.054 466.664C224.874 467.513 226.694 468.165 228.514 468.878C230.471 469.652 232.412 470.38 234.49 471.29C239.374 473.504 243.333 477.084 245.942 481.24C247.565 483.909 248.612 486.837 248.991 489.688C249.249 491.963 249.051 494.239 248.475 496.453C249.188 497.166 250.432 496.65 251.205 496.135C252.707 495.088 253.875 492.692 254.527 490.159C255.3 487.17 255.437 483.909 254.785 482.089C253.025 477.478 250.295 473.762 246.716 471.032C243.136 468.241 238.722 466.285 233.58 465.056C232.67 464.859 232.989 463.63 233.838 463.827C239.177 465.056 243.788 467.073 247.489 470.001C251.266 472.928 254.117 476.765 255.938 481.634C256.256 482.484 256.393 483.652 256.453 484.88C256.453 485.593 256.848 486.245 257.56 486.64C258.865 487.489 259.578 485.472 259.775 484.501C260.548 480.209 259.32 476.174 257.045 472.867C254.117 468.438 249.309 465.132 244.88 463.63C243.97 463.372 244.425 462.129 245.275 462.462C249.961 464.025 254.967 467.528 258.152 472.155C260.685 475.992 262.05 480.603 260.822 485.548C260.624 486.321 260.564 486.852 261.019 487.626C261.216 488.081 261.671 488.475 262.187 488.338C264.522 487.883 264.977 483.727 265.175 481.968C265.432 480.148 265.569 478.267 265.569 476.31C265.508 473.838 265.175 471.366 264.007 469.348C262.323 466.163 257.181 463.691 253.086 461.613C251.857 461.021 250.674 460.445 249.704 459.854C248.93 459.459 249.506 458.291 250.295 458.746C251.266 459.338 252.434 459.853 253.678 460.506C257.909 462.584 263.233 465.253 265.19 468.757C266.418 470.971 266.813 473.641 266.873 476.295C266.873 478.252 266.676 480.269 266.418 482.15C266.282 483.652 267.465 484.289 268.633 483.318C270.514 481.756 271.757 478.768 272.273 475.643C272.789 472.2 272.531 468.56 271.363 466.482C269.998 463.949 268.041 461.871 265.645 460.111C263.233 458.428 260.382 456.987 257.257 455.758C256.408 455.44 256.863 454.257 257.712 454.59C260.897 455.819 263.885 457.32 266.358 459.141C268.951 460.961 271.045 463.175 272.531 465.905C273.441 467.589 273.896 470.259 273.76 472.989C273.76 473.702 273.502 474.096 274.215 474.612C274.988 475.203 275.898 475.522 276.748 474.748C277.203 474.293 277.597 473.58 277.915 472.792C278.628 470.714 278.826 467.908 278.568 465.966C277.915 460.566 272.91 456.471 267.055 453.483Z\" fill=\"#FFE200\"><\/path><path d=\"M281.1 455.167C279.22 453.028 276.55 451.072 272.91 449.449C271.09 448.6 269.27 447.432 267.51 446.264C266.54 445.611 265.554 445.035 264.583 444.307C263.612 443.594 262.96 443.139 261.656 443.139C261.003 443.139 260.745 443.336 260.882 443.989C261.079 444.641 261.656 445.414 261.989 446.067C261.14 446.067 260.488 446.006 259.653 445.748C258.607 445.49 257.575 445.156 257.378 445.809C256.923 446.855 259.198 448.857 260.245 449.191C262.717 450.101 265.25 451.148 267.662 452.376C273.835 455.501 279.114 459.915 279.887 465.83C279.948 466.679 280.024 467.65 279.948 468.697C280.918 469.47 281.176 469.804 282.284 468.757C283.785 467.256 285.074 464.662 284.619 462.448C284.028 459.854 282.996 457.382 281.1 455.167Z\" fill=\"#FFE200\"><\/path><path d=\"M298.467 436.117C297.952 433.902 297.163 431.763 295.995 430.065C294.888 428.502 293.386 427.471 291.506 427.334C290.99 427.334 290.459 427.395 289.883 427.532C289.17 427.668 288.517 428.047 288.26 428.76C287.865 429.67 288.396 431.172 289.109 431.748C290.671 432.977 292.097 434.615 293.401 436.359C294.964 438.498 296.329 440.712 297.102 442.472C297.3 442.866 297.497 443.321 297.694 443.837C299.12 444.231 298.998 443.973 298.998 442.669C298.998 442.472 298.998 442.214 299.059 441.956C299.12 440.333 298.922 438.179 298.467 436.101V436.117Z\" fill=\"#FFE200\"><\/path><path d=\"M292.355 437.163C291.187 435.479 289.761 433.917 288.32 432.81C287.471 432.097 286.44 431.702 285.454 431.763C284.604 431.899 283.77 432.279 283.042 433.189C282.648 433.644 282.451 434.159 282.526 434.69C282.587 435.919 284.286 437.36 285.059 438.133C287.85 441.061 290.717 444.049 293.189 447.689C293.902 448.796 294.691 450.359 295.009 451.921C295.859 452.239 296.966 452.573 297.421 451.526C297.618 451.011 297.679 450.298 297.679 449.509C297.542 447.295 296.632 444.564 295.919 443.078C295.146 441.319 293.902 439.18 292.34 437.163H292.355Z\" fill=\"#FFE200\"><\/path><path d=\"M284.149 439.043C283.558 438.391 282.921 437.815 282.648 437.481C282.056 436.829 281.146 436.253 280.236 436.055C279.584 435.919 278.932 435.995 278.355 436.51C277.703 437.102 276.732 437.678 276.672 438.725C276.414 440.803 277.976 441.516 279.402 442.82C280.509 443.867 281.616 444.898 282.784 445.884C284.801 447.643 286.561 449.524 287.926 451.799C288.639 453.104 289.23 454.469 289.61 456.031C289.746 456.683 289.867 457.26 290.838 457.396C292.855 457.533 294.023 455.182 293.963 453.438C293.902 451.678 292.992 449.737 292.082 448.432C289.67 444.853 286.879 441.925 284.149 439.074V439.043Z\" fill=\"#FFE200\"><\/path><path d=\"M281.95 446.84C280.782 445.869 279.675 444.762 278.507 443.715C277.4 442.668 276.292 441.576 275.064 440.53C274.093 439.756 272.728 438.968 271.621 438.77C271.166 438.71 270.453 438.573 270.256 439.165C270.059 439.878 270.514 441.121 270.65 441.895C269.543 441.637 266.873 440.075 267.268 442.411C267.723 445.338 271.044 447.158 273.441 448.265C277.278 449.949 280.069 452.042 282.086 454.378C284.104 456.714 285.272 459.383 285.863 462.174C285.924 462.568 286 463.023 286 463.403H286.515C287.107 463.403 287.562 463.205 287.941 462.948C288.336 462.629 288.593 462.174 288.791 461.522C288.851 461.067 288.927 460.612 288.927 460.02C288.791 457.032 288.017 454.499 286.849 452.406C285.621 450.267 283.922 448.432 281.965 446.809L281.95 446.84Z\" fill=\"#FFE200\"><\/path><path d=\"M350.933 230.7C350.28 229.017 348.855 229.138 347.414 229.654C345.396 232.703 343.455 236.024 341.62 239.543C339.739 243.183 337.979 247.021 336.478 250.995C336.159 251.844 334.976 251.389 335.31 250.54C336.811 246.505 338.632 242.607 340.512 238.967C342.393 235.327 344.41 231.944 346.488 228.82C347.717 226.863 348.248 224.785 347.596 222.51C347.277 221.342 346.488 220.235 345.184 220.038C344.926 220.553 344.592 221.084 344.274 221.539C342.196 224.209 340.315 226.939 338.419 229.669C336.599 232.46 334.84 235.266 333.217 238.193C332.762 238.967 331.594 238.39 332.11 237.541C333.732 234.614 335.553 231.747 337.373 228.956C339.253 226.165 341.21 223.435 343.227 220.766C344.077 219.719 344.592 218.551 344.653 217.323C344.79 214.79 341.862 211.347 339.906 214.077C337.494 217.459 335.098 221.039 332.747 224.603C330.214 228.501 327.741 232.475 325.33 236.57C324.875 237.344 323.767 236.707 324.222 235.918C326.695 231.823 329.167 227.788 331.7 223.951C334.172 220.113 336.645 216.413 339.178 212.894C339.633 212.241 339.951 211.589 339.891 210.679C339.891 210.163 339.754 209.708 339.496 209.314C338.723 208.207 337.085 207.949 336.25 208.996C333.52 212.241 331.184 215.502 328.909 218.748C326.573 222.131 324.359 225.634 322.023 229.214C321.568 229.988 320.461 229.275 320.976 228.562C323.312 224.922 325.527 221.479 327.863 218.035C330.274 214.517 332.807 211.149 335.659 207.691C336.372 206.781 336.174 205.552 335.795 204.642C335.598 204.385 335.401 204.127 335.28 203.93C334.051 202.564 332.944 202.428 331.836 203.732C327.544 208.161 322.736 213.227 318.246 220.644C317.791 221.418 316.684 220.781 317.2 219.992C321.75 212.454 326.634 207.373 330.926 202.822C331.836 201.912 332.686 201.321 332.489 199.895C332.352 198.848 331.836 198.014 331.124 197.362C329.698 196.194 329.046 195.997 327.741 197.362C325.527 199.637 323.388 202.307 321.234 205.234C319.096 208.222 316.942 211.407 314.727 214.79C314.591 215.047 314.409 215.305 313.878 214.987C313.362 214.668 313.484 214.395 313.681 214.077C315.895 210.694 318.034 207.448 320.188 204.521C322.402 201.533 324.617 198.803 326.816 196.528C327.923 195.36 328.575 194.45 327.665 192.887C325.982 190.218 324.541 191.917 323.054 193.6C320.84 196.073 318.701 198.606 316.623 201.336C314.545 204.127 312.528 207.054 310.571 210.179C310.374 210.436 310.253 210.694 309.661 210.376C309.146 210.057 309.343 209.784 309.464 209.526C311.481 206.341 313.499 203.353 315.577 200.623C317.715 197.832 319.869 195.223 322.084 192.751C323.13 191.583 323.646 190.734 323.707 190.021C323.843 189.429 323.509 188.853 322.994 188.261C321.765 186.896 318.959 184.03 317.533 187.215C316.168 190.203 314.212 192.554 311.937 194.298C309.404 196.255 306.476 197.544 303.412 198.196C296.132 199.758 288.715 196.634 282.936 192.478C277.021 188.185 271.166 182.134 267.586 175.247C264.462 169.271 262.839 162.309 264.522 155.681C253.526 160.231 243.318 162.507 233.504 162.764C226.224 162.962 217.578 161.991 210.101 159.579C200.151 156.394 187.804 156.394 177.854 159.579C170.377 161.991 161.792 162.962 154.451 162.764C144.637 162.507 134.429 160.231 123.433 155.681C125.116 162.309 123.493 169.271 120.445 175.247C116.804 182.134 110.95 188.185 105.034 192.478C99.2402 196.634 91.8384 199.758 84.5579 198.196C81.5092 197.544 78.5818 196.24 76.0337 194.298C73.7585 192.539 71.8019 190.203 70.4368 187.215C69.011 184.03 66.205 186.896 64.9764 188.261C64.4607 188.853 64.1271 189.429 64.2636 190.021C64.3242 190.734 64.8551 191.583 65.8865 192.751C68.101 195.223 70.2396 197.817 72.3934 200.623C74.4714 203.353 76.4887 206.341 78.506 209.526C78.6425 209.784 78.8245 210.042 78.3088 210.376C77.7173 210.694 77.596 210.436 77.3988 210.179C75.4421 207.054 73.4248 204.127 71.3469 201.336C69.2689 198.606 67.1151 196.073 64.9158 193.6C63.4142 191.917 61.9884 190.218 60.3048 192.887C59.3947 194.45 60.047 195.36 61.1542 196.528C63.3687 198.803 65.5832 201.533 67.7825 204.521C69.9211 207.448 72.1356 210.694 74.2894 214.077C74.4866 214.395 74.6079 214.668 74.0922 214.987C73.5765 215.305 73.3793 215.047 73.2428 214.79C71.0283 211.407 68.8897 208.222 66.7359 205.234C64.5973 202.307 62.4434 199.637 60.229 197.362C58.9245 195.997 58.2723 196.194 56.8466 197.362C56.1337 198.014 55.618 198.864 55.4815 199.895C55.2843 201.321 56.1337 201.912 57.0438 202.822C61.3362 207.373 66.205 212.439 70.7705 219.992C71.2862 220.766 70.179 221.418 69.7239 220.644C65.2343 213.227 60.4261 208.161 56.1337 203.732C55.0265 202.428 53.9192 202.564 52.6906 203.93C52.5541 204.127 52.3721 204.385 52.1749 204.642C51.7806 205.552 51.5834 206.781 52.3114 207.691C55.1781 211.134 57.7111 214.517 60.1076 218.035C62.4434 221.479 64.6579 224.922 66.9937 228.562C67.5094 229.275 66.4022 229.988 65.9472 229.214C63.6114 225.634 61.3969 222.131 59.0611 218.748C56.7859 215.502 54.4501 212.241 51.7199 208.996C50.8705 207.949 49.2476 208.222 48.474 209.314C48.2162 209.708 48.0797 210.163 48.0797 210.679C48.019 211.589 48.3375 212.241 48.7925 212.894C51.3255 216.413 53.7979 220.113 56.2702 223.951C58.8032 227.788 61.2755 231.823 63.7479 235.918C64.2029 236.692 63.0957 237.344 62.6406 236.57C60.229 232.475 57.7566 228.501 55.2236 224.603C52.8878 221.023 50.4762 217.444 48.0645 214.077C46.1079 211.347 43.1805 214.79 43.317 217.323C43.3777 218.551 43.9692 219.734 44.7428 220.766C46.7601 223.435 48.7167 226.165 50.5975 228.956C52.4783 231.747 54.2377 234.614 55.8607 237.541C56.3764 238.39 55.2085 238.967 54.7534 238.193C53.1305 235.266 51.371 232.475 49.5509 229.669C47.6701 226.939 45.7742 224.209 43.6962 221.539C43.3777 221.084 43.044 220.568 42.7861 220.038C41.4817 220.235 40.7082 221.342 40.3745 222.51C39.7223 224.785 40.238 226.863 41.4817 228.82C43.5597 231.944 45.577 235.327 47.4578 238.967C49.3386 242.607 51.1587 246.505 52.6603 250.54C52.9788 251.389 51.8109 251.844 51.4924 250.995C49.9908 247.021 48.2465 243.199 46.3505 239.543C44.5304 236.024 42.5738 232.718 40.5565 229.654C39.1307 229.138 37.6898 229.002 37.0376 230.7C35.7332 234.144 37.2348 237.132 38.6605 240.195C43.8024 251.45 49.0656 262.826 52.7058 275.566C69.4206 213.273 126.512 167.178 193.932 167.178C261.352 167.178 318.459 213.288 335.158 275.566C338.798 262.826 344.062 251.45 349.203 240.195C350.629 237.147 352.131 234.144 350.826 230.7H350.933Z\" fill=\"#FFE200\"><\/path><path d=\"M283.694 191.431C289.155 195.405 296.314 198.454 303.2 196.952C306.067 196.3 308.857 195.132 311.193 193.312C313.332 191.628 315.167 189.474 316.396 186.684C317.366 184.606 317.761 181.936 317.366 179.661C317.169 178.69 316.911 177.78 316.396 177.067C315.622 175.642 313.529 174.337 311.845 174.731C310.48 175.05 309.57 176.294 309.707 177.659C309.843 179.479 311.33 179.676 312.755 179.615C313.013 181.693 313.013 183.65 312.24 185.592C310.677 189.823 306.779 192.296 302.426 192.811C299.696 193.206 296.708 192.872 293.978 192.038C289.685 190.733 285.454 187.882 281.889 184.242C277.991 180.404 274.867 175.596 273.107 171.106C271.803 167.785 271.151 164.342 271.348 160.762C271.606 157.637 272.516 154.452 274.396 151.404C275.625 149.386 277.642 149.326 279.538 149.265C281.04 149.204 282.405 149.128 282.86 147.961C283.254 147.05 282.996 146.08 282.405 145.367C281.631 144.32 280.327 143.744 279.023 143.683C272.713 143.486 267.905 149.144 266.206 154.68C264.189 161.111 265.554 168.664 268.739 174.701C272.243 181.405 277.976 187.321 283.694 191.477V191.431Z\" fill=\"#FFE200\"><\/path><path d=\"M233.565 161.52C242.726 161.262 252.419 159.184 262.702 155.013C264.007 154.498 265.175 153.648 265.766 152.283C266.873 149.75 268.496 147.399 270.574 145.579C253.48 152.147 230.774 155.984 207.113 157.031C215.637 160.216 224.343 161.778 233.58 161.52H233.565Z\" fill=\"#FFE200\"><\/path><path d=\"M76.8527 193.312C79.1885 195.132 81.9945 196.3 84.8461 196.952C91.7322 198.454 98.8913 195.39 104.352 191.431C110.07 187.275 115.803 181.36 119.307 174.656C122.492 168.604 123.918 161.066 121.84 154.635C120.156 149.114 115.333 143.456 109.023 143.638C107.795 143.699 106.414 144.29 105.641 145.322C105.049 146.035 104.792 147.005 105.186 147.915C105.641 149.083 107.006 149.144 108.508 149.22C110.388 149.28 112.406 149.356 113.649 151.358C115.53 154.407 116.44 157.607 116.698 160.717C116.895 164.296 116.243 167.74 114.939 171.061C113.255 175.551 110.055 180.359 106.157 184.196C102.577 187.837 98.3605 190.703 94.068 191.993C91.3378 192.842 88.3498 193.161 85.6196 192.766C81.2665 192.25 77.3684 189.778 75.8061 185.546C75.0933 183.59 75.0326 181.648 75.2904 179.57C76.7162 179.631 78.2178 179.434 78.3391 177.614C78.4756 176.249 77.5656 175.02 76.2005 174.686C74.5169 174.292 72.4237 175.596 71.6502 177.022C71.1345 177.735 70.8766 178.645 70.6795 179.616C70.2851 181.891 70.6795 184.56 71.6502 186.638C72.8788 189.429 74.7141 191.583 76.8527 193.267V193.312Z\" fill=\"#FFE200\"><\/path><path d=\"M125.298 155.014H125.359C135.627 159.17 145.32 161.263 154.496 161.521C155.8 161.657 161.716 161.384 164.643 160.095C167.828 158.73 165.493 155.939 163.02 155.666C146.048 153.846 130.182 150.464 117.502 145.595C119.58 147.415 121.203 149.751 122.31 152.299C122.902 153.603 123.994 154.513 125.298 155.029V155.014Z\" fill=\"#FFE200\"><\/path><path d=\"M287.987 109.753C286.561 109.753 285.257 110.345 284.286 111.255C283.376 112.226 282.724 113.53 282.724 114.956C282.724 117.883 285.135 120.219 287.987 120.219C289.488 120.219 290.778 119.628 291.688 118.718C292.658 117.747 293.25 116.442 293.25 114.941C293.25 112.074 290.914 109.738 287.987 109.738V109.753Z\" fill=\"#FFE200\"><\/path><path d=\"M276.156 141.363C277.46 141.818 278.689 141.423 279.402 140.65C279.66 140.392 279.918 140.058 280.054 139.679C280.115 139.361 280.191 138.966 280.115 138.572C279.978 137.601 279.144 136.615 277.324 136.039C250.204 126.878 222.114 122.251 194.023 122.251C165.933 122.251 137.842 126.862 110.722 136.039C108.902 136.63 108.053 137.601 107.931 138.572C107.871 138.966 107.931 139.345 107.992 139.679C108.129 140.073 108.386 140.392 108.644 140.65C109.357 141.423 110.601 141.818 111.89 141.363C141.346 132.065 167.677 127.378 194.008 127.378C220.339 127.378 246.67 132.065 276.126 141.363H276.156Z\" fill=\"#FFE200\"><\/path><path d=\"M188.957 100.077C188.957 98.5751 187.728 97.4072 186.227 97.4072C184.725 97.4072 183.557 98.5751 183.557 100.077C183.557 101.578 184.725 102.807 186.227 102.807C187.728 102.807 188.957 101.578 188.957 100.077Z\" fill=\"#FFE200\"><\/path><path d=\"M194.038 83.877C195.858 83.877 197.36 82.3754 197.36 80.5552C197.36 78.7351 195.858 77.1729 194.038 77.1729C192.218 77.1729 190.716 78.6745 190.716 80.5552C190.716 82.436 192.218 83.877 194.038 83.877Z\" fill=\"#FFE200\"><\/path><path d=\"M198.133 60.2155C198.133 57.9404 196.313 56.0596 194.038 56.0596C191.763 56.0596 189.943 57.9404 189.943 60.2155C189.943 62.4907 191.763 64.3108 194.038 64.3108C196.313 64.3108 198.133 62.4907 198.133 60.2155Z\" fill=\"#FFE200\"><\/path><path d=\"M197.8 49.75C197.8 47.672 196.116 45.9126 194.023 45.9126C191.93 45.9126 190.246 47.672 190.246 49.75C190.246 51.828 191.93 53.5268 194.023 53.5268C196.116 53.5268 197.8 51.8432 197.8 49.75Z\" fill=\"#FFE200\"><\/path><path d=\"M190.064 70.8784C190.064 73.017 191.884 74.8523 194.038 74.8523C196.192 74.8523 197.997 73.0322 197.997 70.8784C197.997 68.7245 196.177 66.8438 194.038 66.8438C191.899 66.8438 190.064 68.6639 190.064 70.8784Z\" fill=\"#FFE200\"><\/path><path d=\"M194.038 31.6701C198.528 31.6701 202.168 27.9692 202.168 23.4796C202.168 18.99 198.528 15.2891 194.038 15.2891C189.548 15.2891 185.908 18.9293 185.908 23.4796C185.908 28.0299 189.548 31.6701 194.038 31.6701Z\" fill=\"#FFE200\"><\/path><path d=\"M253.92 86.1522C253.92 88.1088 255.482 89.7318 257.424 89.7318C258.395 89.7318 259.305 89.3374 259.957 88.6852C260.609 88.033 261.003 87.1229 261.003 86.1522C261.003 84.1956 259.38 82.6333 257.424 82.6333C255.467 82.6333 253.92 84.1956 253.92 86.1522Z\" fill=\"#FFE200\"><\/path><path d=\"M266.464 72.6985C267.571 72.6985 268.542 72.2435 269.194 71.5913C269.907 70.8784 270.362 69.9077 270.362 68.8004C270.362 66.6618 268.602 64.9023 266.464 64.9023C265.417 64.9023 264.446 65.3574 263.734 66.0703C263.021 66.7831 262.566 67.7539 262.566 68.8004C262.566 70.9391 264.325 72.6985 266.464 72.6985Z\" fill=\"#FFE200\"><\/path><path d=\"M258.925 77.9623C258.925 79.9796 260.609 81.6632 262.702 81.6632C263.749 81.6632 264.659 81.2689 265.296 80.556C266.009 79.9038 266.403 78.9937 266.403 77.9623C266.403 75.8843 264.719 74.1855 262.702 74.1855C261.656 74.1855 260.685 74.5799 260.033 75.2928C259.32 75.945 258.925 76.9157 258.925 77.9623Z\" fill=\"#FFE200\"><\/path><path d=\"M267.177 63.3405C268.284 63.3405 269.255 62.8855 269.968 62.2333C270.681 61.5204 271.075 60.5496 271.075 59.4424C271.075 57.3038 269.315 55.605 267.177 55.605C266.13 55.605 265.159 55.9993 264.447 56.7122C263.734 57.4251 263.339 58.3958 263.339 59.4424C263.339 61.581 265.099 63.3405 267.177 63.3405Z\" fill=\"#FFE200\"><\/path><path d=\"M266.464 53.5113C267.571 53.5113 268.542 53.0563 269.255 52.3434C270.028 51.6305 270.423 50.6598 270.423 49.5525C270.423 47.3381 268.663 45.5786 266.464 45.5786C265.357 45.5786 264.386 46.0336 263.673 46.7465C262.96 47.4594 262.505 48.4301 262.505 49.5374C262.505 51.7519 264.264 53.5113 266.479 53.5113H266.464Z\" fill=\"#FFE200\"><\/path><path d=\"M267.374 43.3041C269.588 43.3041 271.348 41.5447 271.348 39.3454C271.348 37.146 269.588 35.4473 267.374 35.4473C265.159 35.4473 263.476 37.2067 263.476 39.3454C263.476 41.484 265.235 43.3041 267.374 43.3041Z\" fill=\"#FFE200\"><\/path><path d=\"M257.5 40.5133C259.638 40.5133 261.398 38.6932 261.398 36.5394C261.398 34.3856 259.638 32.5654 257.5 32.5654C255.361 32.5654 253.526 34.3856 253.526 36.5394C253.526 38.6932 255.285 40.5133 257.5 40.5133Z\" fill=\"#FFE200\"><\/path><path d=\"M248.581 36.9938C249.628 36.9938 250.598 36.5388 251.311 35.8259C252.024 35.1737 252.479 34.203 252.479 33.0957C252.479 30.9571 250.72 29.2583 248.581 29.2583C247.534 29.2583 246.564 29.6527 245.851 30.3655C245.138 31.0784 244.683 32.0492 244.683 33.0957C244.683 35.2344 246.442 36.9938 248.581 36.9938Z\" fill=\"#FFE200\"><\/path><path d=\"M238.571 35.4321C239.617 35.4321 240.527 34.9771 241.24 34.3249C241.892 33.612 242.287 32.7019 242.287 31.716C242.287 29.6381 240.664 28.0151 238.586 28.0151C237.615 28.0151 236.629 28.4095 235.992 29.0617C235.34 29.7746 234.885 30.6846 234.885 31.7312C234.885 33.7485 236.568 35.4321 238.586 35.4321H238.571Z\" fill=\"#FFE200\"><\/path><path d=\"M229.212 34.0669C230.259 34.0669 231.169 33.6118 231.821 32.9596C232.534 32.3074 232.928 31.3367 232.928 30.366C232.928 28.288 231.244 26.665 229.227 26.665C228.181 26.665 227.271 27.0594 226.633 27.7116C225.921 28.4245 225.526 29.3346 225.526 30.3811C225.526 32.3984 227.21 34.082 229.227 34.082L229.212 34.0669Z\" fill=\"#FFE200\"><\/path><path d=\"M220.036 32.5803C221.006 32.5803 221.916 32.1859 222.569 31.5337C223.221 30.8208 223.676 29.9108 223.676 28.94C223.676 26.9227 221.992 25.2998 220.036 25.2998C218.989 25.2998 218.079 25.6942 217.442 26.3464C216.79 27.0593 216.335 27.9693 216.335 28.9552C216.335 30.9725 218.018 32.5955 220.036 32.5955V32.5803Z\" fill=\"#FFE200\"><\/path><path d=\"M211.39 31.5336C213.271 31.5336 214.833 29.9713 214.833 28.0905C214.833 26.2097 213.271 24.6475 211.39 24.6475C209.509 24.6475 207.886 26.2097 207.886 28.0905C207.886 29.9713 209.448 31.5336 211.39 31.5336Z\" fill=\"#FFE200\"><\/path><path d=\"M276.747 47.1412C277.855 47.1412 278.886 46.6862 279.614 45.9126H279.675C280.388 45.1998 280.843 44.1532 280.843 43.046C280.843 40.7708 279.023 38.9507 276.747 38.9507C275.64 38.9507 274.609 39.4057 273.881 40.1186C273.107 40.8921 272.652 41.878 272.652 43.046C272.652 45.2604 274.472 47.1412 276.747 47.1412Z\" fill=\"#FFE200\"><\/path><path d=\"M286.106 48.9005C287.213 48.9005 288.245 48.3848 288.973 47.6719C289.746 46.959 290.201 45.9125 290.201 44.8052C290.201 42.5301 288.32 40.71 286.106 40.71C284.938 40.71 283.967 41.165 283.179 41.8779C282.466 42.6514 282.011 43.6373 282.011 44.8052C282.011 47.0197 283.831 48.9005 286.106 48.9005Z\" fill=\"#FFE200\"><\/path><path d=\"M296.056 52.2831C297.36 52.2831 298.589 51.6915 299.438 50.8573C300.288 50.0079 300.803 48.84 300.803 47.5356C300.803 44.9419 298.665 42.7881 296.056 42.7881C294.751 42.7881 293.584 43.3038 292.734 44.1532C291.885 45.0632 291.308 46.2311 291.308 47.5356C291.308 50.1292 293.447 52.2831 296.056 52.2831Z\" fill=\"#FFE200\"><\/path><path d=\"M305.869 57.8642C307.235 57.8642 308.463 57.2726 309.388 56.3626C310.314 55.4525 310.89 54.2239 310.89 52.8588C310.89 50.1287 308.615 47.8535 305.885 47.8535C304.52 47.8535 303.291 48.4451 302.366 49.3551C301.456 50.2652 300.864 51.4938 300.864 52.874C300.864 55.6042 303.139 57.8793 305.869 57.8793V57.8642Z\" fill=\"#FFE200\"><\/path><path d=\"M309.054 62.0354C309.054 64.9021 311.39 67.2379 314.196 67.2379C317.002 67.2379 319.399 64.9021 319.399 62.0354C319.399 59.1687 317.063 56.8936 314.196 56.8936C311.33 56.8936 309.054 59.2294 309.054 62.0354Z\" fill=\"#FFE200\"><\/path><path d=\"M313.878 73.8056C313.878 76.5358 316.092 78.811 318.883 78.811C321.674 78.811 323.828 76.5358 323.828 73.8056C323.828 71.0754 321.613 68.8003 318.883 68.8003C316.153 68.8003 313.878 71.0754 313.878 73.8056Z\" fill=\"#FFE200\"><\/path><path d=\"M322.842 85.4397C322.842 83.028 320.885 81.0107 318.489 81.0107C316.092 81.0107 314.06 83.028 314.06 85.4397C314.06 87.8514 316.077 89.8687 318.489 89.8687C320.901 89.8687 322.842 87.8514 322.842 85.4397Z\" fill=\"#FFE200\"><\/path><path d=\"M319.46 94.9346C319.46 92.8566 317.776 91.0972 315.622 91.0972C313.468 91.0972 311.785 92.8566 311.785 94.9346C311.785 97.0126 313.544 98.772 315.622 98.772C317.7 98.772 319.46 97.0884 319.46 94.9346Z\" fill=\"#FFE200\"><\/path><path d=\"M311.663 107.357C313.802 107.357 315.562 105.598 315.562 103.52C315.562 101.442 313.802 99.6216 311.663 99.6216C309.525 99.6216 307.826 101.381 307.826 103.52C307.826 105.658 309.585 107.357 311.663 107.357Z\" fill=\"#FFE200\"><\/path><path d=\"M272.258 64.7055C271.864 68.4064 270.953 71.986 269.528 75.2319C267.965 78.7356 266.145 82.1938 264.067 85.3032C262.111 88.2912 259.911 91.0214 257.697 93.0994C257.303 93.5544 257.045 93.8729 257.105 94.2673C257.166 94.7223 257.5 95.3139 258.152 96.1481C258.349 96.3453 258.546 96.5425 258.743 96.6638C259.456 97.1188 260.306 96.9823 261.276 96.4059C262.384 95.6931 263.552 94.4493 264.72 92.9629C267.192 89.7777 269.664 85.288 271.484 81.3293C273.82 76.3846 275.064 72.0922 275.64 67.6784C276.232 62.6124 275.959 57.5312 275.64 52.4652C275.443 50.3266 275.322 47.5812 273.107 47.2627C272.516 47.202 272.258 47.7784 272.137 48.5671C272 49.6137 272.137 50.9788 272.273 51.8888C272.728 56.1206 272.789 60.4737 272.273 64.7055H272.258Z\" fill=\"#FFE200\"><\/path><path d=\"M258.152 44.6082C257.56 43.956 256.923 43.501 256.195 43.501C254.633 43.5616 254.436 44.4717 254.314 45.3818C254.117 46.7469 254.967 47.8541 255.361 49.2799C256.468 53.0566 256.923 56.7575 256.787 60.4584C256.59 64.1593 255.877 67.7996 254.572 71.455C253.859 73.533 252.949 75.3531 251.903 77.1125C250.796 78.872 249.628 80.5556 248.46 82.2544C247.352 83.756 247.034 84.666 247.231 85.1211C247.428 85.5761 248.081 85.834 249.051 86.0918C251.842 86.744 252.949 84.8632 254.117 82.8459C254.436 82.3302 254.769 81.7387 255.164 81.1623C258.743 75.8991 260.821 70.4994 261.595 65.0997C262.444 59.3057 261.853 53.5268 260.033 48.0664C259.714 47.0199 259.062 45.5941 258.152 44.6234V44.6082Z\" fill=\"#FFE200\"><\/path><path d=\"M130.637 89.7318C132.594 89.7318 134.156 88.1088 134.156 86.1522C134.156 84.1956 132.594 82.6333 130.637 82.6333C128.681 82.6333 127.058 84.1956 127.058 86.1522C127.058 87.1229 127.452 88.033 128.104 88.6852C128.756 89.3374 129.666 89.7318 130.637 89.7318Z\" fill=\"#FFE200\"><\/path><path d=\"M121.597 72.6985C123.736 72.6985 125.495 70.9391 125.495 68.8004C125.495 67.7539 125.04 66.7831 124.327 66.0703C123.615 65.3574 122.644 64.9023 121.597 64.9023C119.459 64.9023 117.699 66.6618 117.699 68.8004C117.699 69.9077 118.154 70.8784 118.867 71.5913C119.519 72.2435 120.49 72.6985 121.597 72.6985Z\" fill=\"#FFE200\"><\/path><path d=\"M125.374 81.6632C127.452 81.6632 129.151 79.9796 129.151 77.9623C129.151 76.9157 128.757 75.945 128.044 75.2928C127.391 74.5799 126.421 74.1855 125.374 74.1855C123.357 74.1855 121.673 75.8692 121.673 77.9623C121.673 79.0089 122.068 79.9189 122.78 80.556C123.433 81.2689 124.343 81.6632 125.374 81.6632Z\" fill=\"#FFE200\"><\/path><path d=\"M124.722 59.4268C124.722 58.3802 124.328 57.4095 123.615 56.6966C122.902 55.9837 121.931 55.5894 120.885 55.5894C118.746 55.5894 116.986 57.273 116.986 59.4268C116.986 60.534 117.381 61.5047 118.094 62.2176C118.807 62.8698 119.777 63.3249 120.885 63.3249C122.963 63.3249 124.722 61.5654 124.722 59.4268Z\" fill=\"#FFE200\"><\/path><path d=\"M121.597 45.5786C119.383 45.5786 117.623 47.3381 117.623 49.5525C117.623 50.6598 118.018 51.6305 118.791 52.3434C119.504 53.0563 120.475 53.5113 121.582 53.5113C123.797 53.5113 125.541 51.7519 125.541 49.5374C125.541 48.4301 125.086 47.4594 124.373 46.7465C123.66 46.0336 122.689 45.5786 121.582 45.5786H121.597Z\" fill=\"#FFE200\"><\/path><path d=\"M120.687 43.3041C122.826 43.3041 124.585 41.5447 124.585 39.3454C124.585 37.146 122.826 35.4473 120.687 35.4473C118.549 35.4473 116.713 37.2067 116.713 39.3454C116.713 41.484 118.473 43.3041 120.687 43.3041Z\" fill=\"#FFE200\"><\/path><path d=\"M130.562 40.5133C132.776 40.5133 134.52 38.6932 134.52 36.5394C134.52 34.3856 132.761 32.5654 130.562 32.5654C128.362 32.5654 126.663 34.3856 126.663 36.5394C126.663 38.6932 128.423 40.5133 130.562 40.5133Z\" fill=\"#FFE200\"><\/path><path d=\"M139.48 36.9938C141.619 36.9938 143.378 35.2344 143.378 33.0957C143.378 32.0492 142.923 31.0784 142.21 30.3655C141.497 29.6527 140.527 29.2583 139.48 29.2583C137.341 29.2583 135.582 30.9419 135.582 33.0957C135.582 34.203 136.037 35.1737 136.75 35.8259C137.463 36.5388 138.434 36.9938 139.48 36.9938Z\" fill=\"#FFE200\"><\/path><path d=\"M149.491 35.4321C151.508 35.4321 153.192 33.7485 153.192 31.7312C153.192 30.6846 152.737 29.7746 152.084 29.0617C151.432 28.4095 150.461 28.0151 149.491 28.0151C147.413 28.0151 145.79 29.6381 145.79 31.716C145.79 32.6868 146.184 33.5968 146.897 34.3249C147.549 34.9771 148.459 35.4321 149.491 35.4321Z\" fill=\"#FFE200\"><\/path><path d=\"M158.849 34.0664C160.866 34.0664 162.55 32.3828 162.55 30.3655C162.55 29.3189 162.156 28.4089 161.443 27.696C160.791 27.0438 159.881 26.6494 158.849 26.6494C156.832 26.6494 155.148 28.2724 155.148 30.3503C155.148 31.3211 155.543 32.307 156.255 32.944C156.908 33.5962 157.818 34.0512 158.849 34.0512V34.0664Z\" fill=\"#FFE200\"><\/path><path d=\"M168.026 32.5798C170.043 32.5798 171.727 30.9569 171.727 28.9396C171.727 27.9689 171.272 27.0588 170.619 26.3307C169.967 25.6785 169.057 25.2842 168.01 25.2842C166.054 25.2842 164.37 26.9071 164.37 28.9244C164.37 29.8952 164.825 30.8052 165.477 31.5181C166.13 32.1703 167.04 32.5647 168.01 32.5647L168.026 32.5798Z\" fill=\"#FFE200\"><\/path><path d=\"M176.671 31.5336C178.628 31.5336 180.19 29.9713 180.19 28.0905C180.19 26.2097 178.628 24.6475 176.671 24.6475C174.714 24.6475 173.228 26.2097 173.228 28.0905C173.228 29.9713 174.79 31.5336 176.671 31.5336Z\" fill=\"#FFE200\"><\/path><path d=\"M108.462 45.9126C109.175 46.6862 110.222 47.1412 111.329 47.1412C113.604 47.1412 115.424 45.2604 115.424 43.046C115.424 41.878 114.969 40.9073 114.195 40.1186C113.483 39.4057 112.436 38.9507 111.329 38.9507C109.054 38.9507 107.234 40.7708 107.234 43.046C107.234 44.1532 107.689 45.1846 108.401 45.9126H108.462Z\" fill=\"#FFE200\"><\/path><path d=\"M101.955 48.9005C104.23 48.9005 106.05 47.0197 106.05 44.8052C106.05 43.6373 105.595 42.6666 104.882 41.8779C104.109 41.165 103.123 40.71 101.955 40.71C99.7407 40.71 97.8599 42.5301 97.8599 44.8052C97.8599 45.9125 98.3149 46.9439 99.0884 47.6719C99.8013 48.3848 100.848 48.9005 101.955 48.9005Z\" fill=\"#FFE200\"><\/path><path d=\"M92.0052 52.2831C94.5988 52.2831 96.7527 50.1444 96.7527 47.5356C96.7527 46.2311 96.1611 45.0632 95.3269 44.1532C94.4775 43.3038 93.3096 42.7881 92.0052 42.7881C89.4115 42.7881 87.2577 44.9267 87.2577 47.5356C87.2577 48.84 87.7734 50.0079 88.6228 50.8573C89.4722 51.7067 90.7008 52.2831 92.0052 52.2831Z\" fill=\"#FFE200\"><\/path><path d=\"M82.1918 57.8647C84.9219 57.8647 87.1971 55.5895 87.1971 52.8594C87.1971 51.4943 86.6056 50.2505 85.6955 49.3405C84.7854 48.4304 83.5569 47.8389 82.1766 47.8389C79.4464 47.8389 77.1713 50.114 77.1713 52.8442C77.1713 54.2093 77.7628 55.4379 78.6729 56.3479C79.5829 57.258 80.8115 57.8495 82.1766 57.8495L82.1918 57.8647Z\" fill=\"#FFE200\"><\/path><path d=\"M73.8646 67.2379C76.6555 67.2379 79.0065 64.9021 79.0065 62.0354C79.0065 59.1687 76.6706 56.8936 73.8646 56.8936C71.0586 56.8936 68.6621 59.2294 68.6621 62.0354C68.6621 64.8414 70.9979 67.2379 73.8646 67.2379Z\" fill=\"#FFE200\"><\/path><path d=\"M69.1931 78.811C71.9839 78.811 74.1984 76.5358 74.1984 73.8056C74.1984 71.0754 71.9839 68.8003 69.1931 68.8003C66.4022 68.8003 64.2484 71.0754 64.2484 73.8056C64.2484 76.5358 66.4629 78.811 69.1931 78.811Z\" fill=\"#FFE200\"><\/path><path d=\"M74.0012 85.4397C74.0012 83.028 71.9839 81.0107 69.5722 81.0107C67.1606 81.0107 65.2191 83.028 65.2191 85.4397C65.2191 87.8514 67.1758 89.8687 69.5722 89.8687C71.9687 89.8687 74.0012 87.8514 74.0012 85.4397Z\" fill=\"#FFE200\"><\/path><path d=\"M72.439 98.772C74.517 98.772 76.2764 97.0884 76.2764 94.9346C76.2764 92.7808 74.517 91.0972 72.439 91.0972C70.361 91.0972 68.6016 92.8566 68.6016 94.9346C68.6016 97.0126 70.2852 98.772 72.439 98.772Z\" fill=\"#FFE200\"><\/path><path d=\"M72.4995 103.52C72.4995 105.598 74.259 107.357 76.3976 107.357C78.5362 107.357 80.235 105.598 80.235 103.52C80.235 101.442 78.4756 99.6216 76.3976 99.6216C74.3196 99.6216 72.4995 101.381 72.4995 103.52Z\" fill=\"#FFE200\"><\/path><path d=\"M112.421 52.4797C112.102 57.5457 111.829 62.6269 112.421 67.6929C113.012 72.1219 114.241 76.3992 116.577 81.3438C118.397 85.3026 120.869 89.7922 123.342 92.9774C124.51 94.479 125.677 95.7076 126.785 96.4205C127.755 97.012 128.605 97.1334 129.318 96.6783C129.515 96.5418 129.712 96.3598 129.909 96.1626C130.561 95.3133 130.88 94.7369 130.956 94.2819C131.016 93.8875 130.759 93.569 130.364 93.1139C128.15 91.036 125.935 88.3058 123.994 85.3178C121.916 82.1932 120.096 78.7502 118.533 75.2464C117.108 72.0005 116.198 68.421 115.803 64.7201C115.288 60.4883 115.348 56.1352 115.803 51.9034C115.94 50.9933 116.061 49.6282 115.94 48.5816C115.803 47.8081 115.545 47.2166 114.969 47.2772C112.755 47.5958 112.633 50.3411 112.436 52.4797H112.421Z\" fill=\"#FFE200\"><\/path><path d=\"M132.912 81.1472C133.307 81.7387 133.625 82.3151 133.959 82.8308C135.127 84.8481 136.234 86.7289 139.025 86.0767C139.996 85.8188 140.648 85.561 140.845 85.1059C141.042 84.6509 140.709 83.7409 139.617 82.2393C138.449 80.5556 137.281 78.8569 136.234 77.0974C135.127 75.338 134.217 73.5178 133.504 71.4399C132.2 67.7996 131.487 64.1594 131.29 60.4433C131.153 56.7424 131.608 53.0263 132.715 49.2647C133.11 47.839 133.944 46.7317 133.762 45.3666C133.625 44.4566 133.443 43.5465 131.881 43.4858C131.168 43.4858 130.516 43.9409 129.924 44.5931C129.014 45.5638 128.362 47.0047 128.044 48.0361C126.224 53.4965 125.632 59.2906 126.481 65.0694C127.255 70.4691 129.348 75.8688 132.912 81.132V81.1472Z\" fill=\"#FFE200\"><\/path><path d=\"M78.4149 68.4059C73.8039 74.6549 74.259 82.6483 76.2004 89.7923C77.884 95.7683 80.9479 101.502 84.6488 106.765C85.0432 107.281 85.5589 107.478 86.1504 107.356C87.197 107.099 88.2891 107.038 89.3356 107.159C90.185 107.296 90.3822 106.386 89.9878 105.794C87.652 102.67 85.5589 99.2872 83.9359 95.7835C81.9793 91.6882 80.69 87.3958 80.2957 83.0427C79.6435 75.3072 82.5102 67.8295 87.7734 61.6562C84.5275 63.082 81.0086 64.8415 78.4149 68.421V68.4059Z\" fill=\"#FFE200\"><\/path><path d=\"M298.134 54.9526C297.224 54.4369 296.314 53.9818 295.343 53.5268C293.978 52.8746 292.021 54.4369 293.523 55.4834C294.691 56.3328 295.798 57.2429 296.905 58.2136C298.407 59.5787 301.258 56.7879 298.134 54.9677V54.9526Z\" fill=\"#FFE200\"><\/path><path d=\"M304.11 95.7842C301.896 100.592 298.771 105.082 295.525 109.117C294.297 110.618 293.902 112.241 294.16 113.409C294.357 114.001 294.752 114.516 295.389 114.577C296.299 114.577 297.603 113.925 299.09 112.165C304.747 105.598 309.555 97.9228 311.83 89.7929C313.651 83.0888 313.711 76.2027 310.92 69.4986C309.04 65.009 306.309 61.3687 303.048 58.4413C301.168 56.8791 299.014 60.125 300.318 61.6872C305.581 67.8605 308.387 75.3381 307.735 83.013C307.341 87.3661 306.052 91.6586 304.095 95.7538L304.11 95.7842Z\" fill=\"#FFE200\"><\/path><path d=\"M194.038 459.52C274.533 459.52 340.209 393.844 340.209 313.288C340.209 232.733 274.533 167.178 194.038 167.178C113.543 167.178 47.8521 232.854 47.8521 313.288C47.8521 393.723 113.528 459.52 194.023 459.52H194.038Z\" fill=\"#ED1B24\"><\/path><path d=\"M194.038 113.924C193.977 114.637 191.702 117.504 191.05 117.822H193.067C193.522 117.504 193.841 117.17 194.038 116.715C194.235 117.17 194.554 117.489 195.009 117.822H197.026C196.374 117.504 194.099 114.637 194.038 113.924Z\" fill=\"black\"><\/path><path d=\"M194.038 103.064C193.977 103.717 191.702 106.052 191.05 106.31H193.067C193.522 106.052 193.841 105.795 194.038 105.4C194.235 105.795 194.554 106.052 195.009 106.31H197.026C196.374 106.052 194.099 103.717 194.038 103.064Z\" fill=\"black\"><\/path><path d=\"M156.255 119.127L155.345 119.9C151.189 123.677 146.048 124.587 139.935 122.827L138.706 122.433L139.753 121.72C142.089 119.961 144.561 118.929 147.094 118.535C149.627 118.08 152.297 118.217 155.027 118.854L156.255 119.111V119.127Z\" fill=\"black\"><\/path><path d=\"M169.846 104.884C169.846 105.4 167.828 107.675 167.252 108.009L169.269 107.751C169.664 107.493 169.921 107.235 170.179 106.902C170.437 107.159 170.832 107.417 171.226 107.554L173.243 107.357C172.591 107.22 170.058 105.4 169.861 104.884H169.846Z\" fill=\"black\"><\/path><path d=\"M144.607 107.873C144.667 108.464 142.923 111.118 142.392 111.513L144.349 111.058C144.743 110.739 145.001 110.406 145.123 110.011C145.441 110.269 145.835 110.466 146.29 110.603L148.247 110.148C147.595 110.087 144.804 108.388 144.607 107.873Z\" fill=\"black\"><\/path><path d=\"M117.563 114.956C117.623 115.547 116.137 118.338 115.606 118.732L117.487 118.141C117.805 117.822 118.078 117.489 118.2 117.094C118.518 117.352 118.913 117.489 119.368 117.61L121.324 117.018C120.672 116.958 117.805 115.456 117.548 114.94L117.563 114.956Z\" fill=\"black\"><\/path><path d=\"M153.449 119.839C151.311 119.445 149.293 119.445 147.337 119.779C145.32 120.097 143.439 120.825 141.619 121.993C146.169 123.04 150.143 122.312 153.449 119.855V119.839Z\" fill=\"#ED1B24\"><\/path><path d=\"M231.806 119.127L232.716 119.9C236.948 123.677 242.013 124.587 248.126 122.827L249.355 122.433L248.308 121.72C245.972 119.961 243.5 118.929 240.967 118.535C238.434 118.08 235.764 118.217 233.034 118.854L231.806 119.111V119.127Z\" fill=\"black\"><\/path><path d=\"M218.215 104.884C218.215 105.4 220.233 107.675 220.809 108.009L218.792 107.751C218.397 107.493 218.14 107.235 217.882 106.902C217.624 107.159 217.23 107.417 216.835 107.554L214.818 107.357C215.47 107.22 218.003 105.4 218.2 104.884H218.215Z\" fill=\"black\"><\/path><path d=\"M243.454 107.873C243.394 108.464 245.138 111.118 245.669 111.513L243.712 111.058C243.394 110.739 243.121 110.406 242.939 110.011C242.62 110.269 242.226 110.466 241.771 110.603L239.814 110.148C240.466 110.087 243.257 108.388 243.454 107.873Z\" fill=\"black\"><\/path><path d=\"M270.498 114.956C270.438 115.547 271.924 118.338 272.455 118.732L270.574 118.141C270.256 117.822 269.983 117.489 269.861 117.094C269.543 117.352 269.148 117.489 268.693 117.61L266.737 117.018C267.389 116.958 270.256 115.456 270.514 114.94L270.498 114.956Z\" fill=\"black\"><\/path><path d=\"M234.612 119.839C236.75 119.445 238.768 119.445 240.724 119.779C242.741 120.097 244.622 120.825 246.442 121.993C241.892 123.04 237.918 122.312 234.612 119.855V119.839Z\" fill=\"#ED1B24\"><\/path><path d=\"M247.095 93.4331C246.898 99.1513 247.034 97.6649 252.1 100.319C249.688 99.6064 247.292 99.1513 245.138 100.577C243.97 98.2413 241.695 97.4525 239.223 96.8762C244.941 97.0733 244.365 98.4384 247.095 93.4331Z\" fill=\"black\"><\/path><path d=\"M140.967 93.4331C141.164 99.1513 141.027 97.6649 135.961 100.319C138.373 99.6064 140.769 99.1513 142.923 100.577C144.091 98.2413 146.366 97.4525 148.839 96.8762C143.12 97.0733 143.697 98.4384 140.967 93.4331Z\" fill=\"black\"><\/path><path d=\"M148.581 63.0675C146.048 66.1921 142.074 66.7078 140.845 70.4845C140.254 72.1681 141.695 73.5484 143.06 73.9276C144.622 74.4433 145.396 72.1075 147.094 71.5159C146.381 72.3653 145.866 73.5332 146.321 74.1854C146.836 73.4119 147.291 72.881 148.596 72.5625C146.518 75.5505 147.428 76.0814 148.99 75.8842C149.9 75.8235 150.492 74.9742 151.584 74.4585C151.523 74.7163 148.657 77.3858 150.992 77.583C151.508 77.6437 153.207 76.8701 153.662 76.4151C153.525 77.4617 151.902 77.8408 153.465 78.6902C154.314 79.2059 155.346 78.2352 156.134 77.9167C154.253 80.5104 155.164 81.0412 156.331 80.6469C157.181 80.3283 157.894 79.4183 159.259 79.4183C158.485 80.0705 157.833 80.1918 157.833 81.0412C157.894 83.7714 160.427 83.5742 161.868 83.3164C160.821 84.0899 161.868 87.2145 162.323 87.2903C164.992 87.6088 165.644 86.8353 168.117 86.1224C171.696 85.0151 172.409 80.207 172.348 74.0338C172.288 68.6341 171.636 63.113 170.726 61.4143C169.618 61.0957 167.025 62.5822 167.025 64.1444C166.827 63.4316 166.372 62.84 165.978 62.84C165.129 62.9007 164.294 64.1444 163.566 64.463C160.958 65.6309 163.172 62.1271 163.172 61.93C159.532 61.7934 159.532 66.9353 159.532 61.6114C156.999 61.2171 155.3 66.4196 155.497 61.8693C153.874 60.4435 152.631 61.8086 151.66 62.9765C150.947 63.8866 150.295 64.6601 150.234 64.2809C150.098 63.5074 150.553 62.1423 150.431 61.7479C150.173 61.0351 148.808 62.8552 148.611 63.113L148.581 63.0675Z\" fill=\"#ED1B24\"><\/path><path d=\"M220.233 59.0472C220.551 61.383 220.233 62.4903 219.914 63.734C218.231 69.1337 220.688 74.1997 220.506 79.6601C222.584 80.8887 222.387 78.8107 223.039 77.1271C224.267 71.7274 229.348 85.4541 235.127 79.6601C237.008 77.1878 240.588 74.5182 244.289 74.8519C249.173 77.84 247.019 63.9919 245.654 63.279C245.138 63.0211 244.031 63.6734 244.031 63.4762C243.894 62.3083 243.439 61.5196 242.802 61.5196C241.634 61.2617 241.179 62.1111 240.921 63.3397C240.785 64.1891 239.875 63.5975 239.951 61.7774C239.298 62.3689 238.843 63.5975 238.586 63.7947C238.07 64.1891 238.722 63.7947 238.191 62.2324C237.736 60.7308 237.145 59.8966 236.568 62.4296C236.174 64.0525 234.232 66.7221 231.229 64.9626C229.864 64.1132 229.606 60.0179 227.453 59.5629C226.345 59.3657 227.195 60.7308 226.285 60.6095C226.027 60.5488 225.83 59.8359 225.314 59.4416C224.404 58.7894 225.708 59.7601 223.099 56.3777C220.824 53.5869 219.975 57.5456 220.233 59.0472Z\" fill=\"#ED1B24\"><\/path><path d=\"M273.881 97.6042C272.516 97.7407 271.606 98.3777 271.272 99.6215C270.559 102.488 275.367 101.699 278.234 101.305C282.845 100.714 282.466 104.627 285.12 103.717C286.682 103.201 285.833 97.0127 287.85 95.0712C288.897 94.1005 291.354 93.0539 291.748 92.0073C292.522 89.9293 291.035 88.1092 288.047 87.3205C286.819 87.0627 286.622 85.7582 284.801 85.8947C282.39 86.0313 281.616 87.9727 280.448 89.7928C279.538 91.1579 278.568 92.523 276.929 93.1752C274.912 93.9488 274.715 96.1026 273.881 97.6042Z\" fill=\"#ED1B24\"><\/path><path d=\"M110.934 94.0852C113.801 97.9226 117.639 100.911 120.096 100.713C122.113 100.395 123.16 97.9833 121.977 95.3744C119.504 89.7169 114.817 88.0333 114.696 81.587C110.995 79.9034 106.824 81.1927 102.41 83.4071C97.0105 87.3811 91.808 89.9747 82.6467 89.004C83.8146 93.0993 85.6954 96.9974 87.9099 100.577C90.4429 100.638 92.263 99.5304 92.6574 97.3917C92.9152 96.2845 93.8253 94.2065 95.5848 94.2065C94.3562 95.1166 93.3703 97.4524 94.614 97.9833C96.7527 98.954 97.8599 92.9173 99.8165 92.4622C99.3008 93.6302 97.0864 96.5575 99.4222 96.5575C101.242 96.239 101.106 92.9173 103.002 93.1145C103.26 94.161 102.744 96.6334 104.23 96.5575C106.308 96.0418 105.656 93.0538 106.961 93.0538C106.642 96.0418 110.009 95.5261 110.934 94.1004V94.0852Z\" fill=\"#ED1B24\"><\/path><path d=\"M235.977 135.447C237.539 136.221 240.269 136.357 242.408 136.297C246.443 136.16 244.031 138.83 246.564 138.83C250.72 138.83 253.844 143.714 250.007 145.595C249.097 146.05 247.535 145.989 245.851 145.989C244.349 146.444 248.9 148.325 244.622 148.977C242.999 149.235 238.313 147.87 238.313 150.736C238.313 152.359 233.429 153.33 232.064 153.527C219.899 155.211 206.9 156.06 194.023 156.06C185.635 156.06 177.187 155.666 168.981 155.014C166.19 154.756 166.115 152.541 163.384 151.829C161.883 151.434 159.941 151.631 157.924 151.434C153.434 150.979 153.95 147.657 149.855 148.31C146.215 148.901 142.635 146.489 143.227 144.669C143.621 143.623 145.896 143.046 149.278 142.713C146.867 141.742 147.519 142.121 144.925 142.061C141.877 142 141.088 141.469 141.937 140.559C142.65 139.846 147.276 139.588 144.212 138.997C139.601 138.087 147.731 135.933 148.566 135.554C151.887 134.128 154.739 132.035 158.379 131.458C170.468 129.578 182.238 128.667 194.008 128.667C203.821 128.667 213.65 129.32 223.6 130.624C227.953 131.14 232.124 133.551 235.962 135.432L235.977 135.447Z\" fill=\"#ED1B24\"><\/path><path d=\"M227.847 190.264C221.734 188.58 215.485 187.336 209.054 186.563C208.144 186.426 207.173 186.365 206.263 186.244V229.032C202.305 228.441 198.194 228.122 194.038 228.122C189.882 228.122 185.787 228.441 181.813 229.032V186.244C117.184 192.493 66.3264 247.173 66.3264 313.304C66.3264 379.435 120.035 437.239 187.213 440.879V427.289C127.452 423.709 79.856 373.899 79.856 313.304C79.856 259.398 117.639 214.077 168.026 202.185V232.233C145.077 239.65 126.284 256.486 116.395 278.206L128.484 284.258C131.153 278.342 134.535 272.806 138.631 267.877V358.852C130.956 349.418 125.556 338.103 123.357 325.62L110.161 328.411C117.32 368.211 152.236 398.637 194.038 398.637C199.104 398.637 204.185 398.182 209.054 397.272C215.622 396.104 221.932 394.147 227.847 391.614C258.076 378.419 279.281 348.311 279.281 313.319C279.281 287.504 267.647 264.297 249.431 248.689V213.637C284.407 233.203 308.205 270.531 308.205 313.319C308.205 364.495 274.321 407.935 227.832 422.435C221.78 424.316 215.47 425.681 209.039 426.53C206.309 426.925 203.639 427.183 200.849 427.304V440.894C203.639 440.697 206.309 440.5 209.039 440.181C215.47 439.408 221.719 438.164 227.832 436.48C281.859 421.586 321.72 371.972 321.72 313.319C321.72 254.666 281.859 205.189 227.832 190.294L227.847 190.264ZM220.036 202.155C222.705 202.807 225.299 203.52 227.832 204.294C230.501 205.143 233.095 206.053 235.628 207.085V239.012C233.095 237.587 230.486 236.282 227.832 235.114C225.299 234.007 222.69 233.036 220.036 232.187V202.14V202.155ZM265.751 313.289C265.751 340.606 250.341 364.404 227.847 376.553C221.992 379.677 215.683 382.013 209.054 383.439C204.17 384.486 199.165 385.062 194.038 385.062C178.567 385.062 164.188 380.057 152.418 371.669V255.014C157.226 251.571 162.429 248.705 168.026 246.49V303.976H181.813V242.653C185.787 242.001 189.882 241.606 194.038 241.606C198.194 241.606 202.289 242.001 206.263 242.653V352.543H220.051V246.49C222.72 247.597 225.314 248.765 227.847 250.13C230.577 251.632 233.186 253.255 235.643 255.014V304.309H249.431V267.831C259.638 280.253 265.751 296.058 265.751 313.289Z\" fill=\"#FFE200\"><\/path><path d=\"M54.2377 416.277C54.8899 418.75 55.8606 420.888 57.165 422.708C58.4694 424.468 60.153 425.894 62.231 426.864C63.9146 427.259 65.6134 427.774 67.2363 428.366C71.9232 430.247 76.2763 433.174 80.8873 437.072C79.3857 435.191 77.8992 433.371 76.337 431.612C73.7433 428.624 70.9373 425.696 68.2677 422.83C67.9492 422.511 67.6762 422.178 67.4184 421.859C65.9926 421.601 64.6882 421.085 63.3231 420.433C61.958 419.72 60.5929 418.871 59.1671 417.9C58.4543 417.385 59.1671 416.338 59.88 416.854C61.2451 417.764 62.5495 418.613 63.9146 419.265C64.5668 419.584 65.219 419.918 65.9319 420.115C65.3404 419.523 64.8854 418.886 64.3697 418.295C63.2017 416.732 62.1552 415.307 61.1844 413.805C60.6687 413.092 61.7001 412.379 62.231 413.092C63.2017 414.518 64.2483 416.019 65.4162 417.521C66.5841 419.023 67.8886 420.509 69.193 421.95C71.8625 424.817 74.532 427.668 77.2622 430.793C79.0216 432.81 80.7659 434.827 82.404 436.966C81.0996 433.72 80.1289 430.262 79.3402 426.622C78.6273 424.544 77.4594 422.329 76.0184 420.115C71.6653 413.229 67.0392 407.571 59.8345 403.794C55.7392 401.58 50.9918 400.154 45.3949 399.562C47.215 401.777 48.838 404.173 50.2789 406.782C51.9625 409.831 53.3428 413.092 54.2528 416.277H54.2377Z\" fill=\"#00844B\"><\/path><path d=\"M38.8879 243.517C38.7514 244.29 38.5694 245.018 38.175 245.792C38.7666 245.534 39.2823 245.473 39.798 245.473C39.4795 244.821 39.1458 244.169 38.8879 243.517Z\" fill=\"#00844B\"><\/path><path d=\"M36.6128 258.669C35.5055 259.579 34.6561 260.626 34.0039 261.794C33.291 262.962 32.836 264.266 32.5023 265.631C33.3517 269.332 33.8067 273.109 33.9281 276.886C34.4438 274.474 35.1567 272.199 35.9454 269.924C36.2639 269.074 37.5077 269.469 37.174 270.379C36.2639 272.851 35.4903 275.521 34.9595 278.114C36.3246 275.521 37.9475 273.367 39.5705 271.486C40.2833 270.713 41.0721 269.924 41.7849 269.211C43.7416 267.33 45.7589 265.829 47.761 264.463C46.1381 260.11 44.3786 255.879 42.5585 251.723C42.3006 252.117 42.0428 252.496 41.7849 252.83C40.4198 254.908 38.7969 256.864 36.5824 258.685L36.6128 258.669ZM40.9659 262.234C41.2844 262.097 41.5574 261.915 41.8153 261.779C42.331 261.324 42.7253 260.808 43.1804 260.217C43.4989 260.535 43.6354 261.187 43.6354 261.9C43.6354 264.115 42.9832 264.433 41.8153 264.949C41.3602 265.146 40.7687 265.404 40.1317 265.798C40.071 264.297 39.6766 262.674 40.981 262.219L40.9659 262.234Z\" fill=\"#00844B\"><\/path><path d=\"M45.9105 428.123C46.9571 429.033 47.9278 429.943 48.8986 430.914C50.203 432.142 51.5681 433.583 52.9938 435.267C56.4976 439.498 62.1551 444.307 68.9199 445.611C73.1517 446.385 77.7626 445.869 82.5708 443.017C82.4343 442.76 82.2523 442.502 82.1158 442.244C82.0551 442.244 81.9186 442.183 81.8579 442.183C78.612 440.682 75.6847 439.392 72.6966 439.316H72.4995C71.8472 439.316 71.1344 439.377 70.4822 439.514C69.1171 439.771 67.9492 439.969 66.9026 440.105C65.856 440.166 64.946 440.166 64.1724 440.045C63.8539 439.984 63.5202 439.908 63.6567 439.271C63.7932 438.679 64.1117 438.679 64.3696 438.755C65.0825 438.892 65.8712 438.892 66.8419 438.816C67.6913 438.755 68.662 438.619 69.7693 438.361C69.0564 438.103 68.3435 437.845 67.6306 437.451C66.0684 436.738 64.3847 435.828 62.5646 434.66C62.3068 434.463 62.0489 434.266 62.3675 433.75C62.7618 433.234 63.0197 433.431 63.2775 433.553C65.037 434.721 66.6599 435.631 68.2222 436.344C69.7238 437.056 71.2102 437.572 72.6511 438.027C75.897 438.088 78.9609 439.453 82.4039 441.015C82.5405 441.076 82.6618 441.152 82.7983 441.152L83.1168 440.757C77.3986 435.555 72.3174 431.778 66.7357 429.639C60.1075 426.97 52.9483 426.97 45.9257 428.138L45.9105 428.123Z\" fill=\"#00844B\"><\/path><path d=\"M48.0492 394.299C46.7448 392.995 45.2584 391.705 43.6202 390.462C42.1186 390.204 40.6929 390.067 39.1913 390.265C38.3419 390.401 38.1447 389.157 39.0548 389.036C39.9648 388.899 40.8142 388.839 41.5271 388.899C41.2086 388.642 40.8749 388.384 40.5564 388.187C39.7828 387.595 38.9941 387.019 38.2206 386.503C36.719 386.184 35.1718 385.593 33.4731 384.88C31.8501 384.167 30.0907 383.318 28.2099 382.286C27.3605 381.892 27.952 380.785 28.8014 381.179C30.6822 382.15 32.381 383.06 34.0039 383.712C34.459 383.97 34.9747 384.167 35.4297 384.304C35.0353 384.046 34.6561 383.712 34.3225 383.394C32.2445 381.771 30.2879 380.148 28.2706 378.388C27.5577 377.797 28.4071 376.826 29.0441 377.418C31.1221 379.177 33.0787 380.8 35.096 382.423C37.1133 384.046 39.1913 385.669 41.2693 387.17C43.9994 389.051 46.5324 391.068 48.9441 393.344C50.6277 394.967 52.0686 396.665 53.1759 398.288C52.9787 395.695 52.1293 393.086 50.5822 390.492C48.3071 386.594 44.9853 383.272 41.5423 380.345C36.8555 376.31 31.7288 373.519 26.1319 371.502C21.2479 369.743 16.0606 368.711 10.6609 368.059L10.7216 368.12C13.4517 370.137 16.0606 372.018 18.2599 374.687C22.158 379.374 26.2533 383.727 30.5457 387.686C34.7775 391.584 39.252 395.103 43.9994 398.212C47.0481 398.41 49.8542 398.865 52.4478 399.578C51.3406 397.757 49.8542 395.998 48.0189 394.314L48.0492 394.299Z\" fill=\"#00844B\"><\/path><path d=\"M38.5544 412.06C37.8415 412.257 37.5078 412.773 37.8415 413.425C38.2965 414.199 39.4037 414.593 40.1773 414.396C40.8902 414.259 41.2239 413.683 40.8902 413.031C40.4958 412.257 39.3886 411.863 38.5544 412.06Z\" fill=\"#00844B\"><\/path><path d=\"M68.6016 398.925C69.6481 397.423 67.7522 395.224 66.6449 396.71C66.1899 397.363 66.2506 398.394 66.8421 398.986C67.3578 399.501 68.1465 399.501 68.6016 398.925Z\" fill=\"#00844B\"><\/path><path d=\"M33.0333 357.305C34.2012 358.989 35.3084 360.809 36.2792 362.826C37.0527 364.389 37.7049 366.012 38.3571 367.771C39.5857 364.252 40.7688 361.856 39.0094 358.079C37.3257 354.378 34.9747 350.859 31.926 348.068C28.8015 345.277 25.0399 343.184 20.611 341.956C21.8395 344.231 22.9468 346.506 23.9327 348.918C25.1006 351.784 26.0107 354.712 26.86 357.897C27.5123 360.627 27.8308 363.691 28.0886 366.74C28.2858 368.165 28.4071 369.606 28.6043 371.032C31.471 372.2 34.2619 373.626 36.8555 375.324C36.992 373.959 37.1134 372.655 37.3712 371.426C37.5078 370.577 37.7656 370.198 37.5078 369.348C36.7949 367.21 36.0062 365.253 35.0961 363.372C34.186 361.492 33.1395 359.671 31.9716 358.033C31.4558 357.32 32.4266 356.608 33.0181 357.32L33.0333 357.305Z\" fill=\"#00844B\"><\/path><path d=\"M50.203 387.61C50.4002 384.288 50.1423 381.179 49.5508 378.054C48.7773 374.353 47.4728 370.713 45.7134 366.936C44.409 364.145 42.9225 361.415 41.4816 358.685C41.2844 361.415 41.0266 364.343 39.8587 367.391C39.343 368.756 38.8879 370.182 38.6301 371.684C38.3722 373.11 38.175 374.55 38.175 376.113C39.6008 377.083 41.0417 378.191 42.4068 379.359C43.2562 380.071 44.0298 380.784 44.8185 381.497C44.8792 379.874 44.682 378.373 44.3028 376.947C43.8478 375.188 43.1349 373.504 42.1641 371.805C41.7091 371.032 42.8164 370.379 43.2714 371.214C44.2421 372.973 45.0915 374.732 45.5465 376.613C46.0622 378.494 46.1987 380.451 46.0016 382.665C47.6245 384.288 49.0654 385.911 50.2334 387.61H50.203Z\" fill=\"#00844B\"><\/path><path d=\"M45.1219 362.826C45.7135 363.994 46.2899 365.162 46.8814 366.406C48.565 370.107 49.8694 373.626 50.6581 377.205C50.7947 375.249 50.916 373.231 51.0525 371.35C51.2497 367.847 51.371 364.464 51.4469 361.143C51.4469 360.233 52.7513 360.233 52.7513 361.143C52.6906 364.525 52.5541 367.968 52.2963 371.411C52.1598 374.536 51.9019 377.721 51.6441 380.845C51.3862 383.636 51.644 386.503 51.3862 389.294C52.2356 390.659 53.0091 392.16 53.5248 393.723C54.4956 392.752 55.2084 391.25 55.7393 389.233C56.3915 386.821 56.7859 383.773 56.9072 380.33C57.1651 373.049 56.5129 366.284 55.345 359.52C53.6613 354.454 52.2204 349.251 51.1132 343.912C49.9453 345.535 48.9745 347.492 48.0645 349.888C46.7601 353.331 45.7893 357.684 45.1371 362.826H45.1219Z\" fill=\"#00844B\"><\/path><path d=\"M15.4084 331.232C18.3965 334.159 21.3845 337.147 23.4018 341.439C23.4018 341.5 23.4625 341.5 23.4625 341.576C26.1927 342.547 28.6043 343.912 30.743 345.474C29.3779 342.744 27.7549 339.953 25.9955 337.223C23.781 333.704 21.4452 330.261 19.1094 326.878C19.1094 326.878 19.1094 326.818 19.0487 326.818C17.5471 326.302 16.0607 325.513 14.5591 324.603C12.9968 323.633 11.4345 322.389 9.87224 321.024C9.22003 320.432 10.0088 319.461 10.7216 320.114C12.2232 321.342 13.7097 322.525 15.2719 323.496C16.182 324.088 17.0921 324.603 18.0021 324.998C17.4864 324.224 16.9555 323.375 16.3792 322.586C15.4691 321.282 14.4984 319.992 13.3911 318.749C12.7996 318.096 13.7097 317.247 14.3619 317.899C15.4691 319.204 16.5005 320.508 17.4106 321.797C20.7323 326.348 24.0389 331.747 27.1027 336.555C29.3779 340.196 31.4558 343.836 33.1546 347.476C33.6703 347.931 34.1254 348.447 34.5804 348.978C35.3539 348.068 35.0961 346.05 33.9282 342.926C31.9109 337.405 28.7257 331.808 25.859 326.666C23.326 322.176 19.5492 317.763 15.0596 313.925C10.9036 310.346 6.15616 307.358 1.40868 305.34C1.27217 308.328 2.06089 311.316 3.42598 314.38C4.92758 317.763 7.06622 321.145 9.53855 324.725C11.2222 327.197 13.3153 329.214 15.3933 331.232H15.4084Z\" fill=\"#00844B\"><\/path><path d=\"M41.6183 345.671C40.4504 345.611 39.7375 346.066 39.4796 346.642C38.7061 348.144 40.1925 349.691 41.6941 349.691C42.5435 349.752 43.1199 349.236 43.3777 348.584C43.6356 348.068 43.6356 347.416 43.4384 346.9C43.2412 346.248 42.589 345.671 41.6183 345.671Z\" fill=\"#00844B\"><\/path><path d=\"M16.7128 355.287C16.4549 355.151 16.1213 355.151 15.8027 355.151C15.287 355.212 14.832 355.348 14.4376 355.667C14.0433 355.924 13.7248 356.319 13.5883 356.713C13.5276 356.971 13.5276 357.168 13.5276 357.426C13.5883 358.533 14.2405 359.504 15.1505 360.156C16.0606 360.808 17.1678 361.127 18.2751 361.066C18.6694 359.641 18.7301 358.336 18.4722 357.365C18.2144 356.258 17.5622 355.545 16.7128 355.287Z\" fill=\"#00844B\"><\/path><path d=\"M20.8687 300.077C23.9933 305.734 26.3898 311.453 28.2099 317.307C29.6357 322.115 30.7429 326.999 31.5923 331.944C31.653 329.472 31.9108 327.136 32.2445 324.861V324.542C31.5923 314.789 30.1059 306.599 27.497 300.228C25.4797 295.087 22.3552 290.157 17.6077 287.093C16.8341 292.356 16.637 297.559 17.3498 302.761C18.0021 307.645 19.3671 312.454 21.5058 317.262C23.0074 320.583 25.2067 322.919 26.9662 326.105C28.1947 328.319 29.3778 330.397 30.3485 332.278C29.575 327.333 28.4678 322.525 26.9662 317.717C25.146 311.923 22.8102 306.265 19.7463 300.744C19.2913 299.971 20.4592 299.318 20.8536 300.092L20.8687 300.077Z\" fill=\"#00844B\"><\/path><path d=\"M47.8521 313.288C47.8521 311.726 47.8521 310.164 47.9128 308.601C47.655 306.645 47.1393 304.825 46.487 303.202C45.4405 300.472 43.954 298.257 42.1946 296.437C41.2845 299.228 40.3138 301.958 39.3279 304.628C38.16 307.873 36.9921 311.134 35.9455 314.244C33.8069 321.069 32.7603 328.031 32.821 335.251C32.8816 338.376 34.7776 341.106 35.6118 344.033C36.0669 339.999 36.6584 335.964 37.2954 332.066C38.069 327.379 38.9791 322.829 40.0256 318.339C39.8284 317.232 39.7071 316.064 39.6313 314.896C39.6313 313.728 39.6919 312.484 39.8284 311.195C39.965 310.285 41.1935 310.422 41.1329 311.332C40.9357 312.56 40.875 313.743 40.9357 314.911C40.9357 315.503 40.9964 316.079 41.0722 316.671C41.3907 316.352 41.7244 315.897 41.9823 315.442C42.4373 314.669 42.8316 313.758 43.1502 312.651C43.2867 312.393 43.3473 312.06 43.9996 312.257C44.5911 312.454 44.5153 312.773 44.3939 313.03C44.0754 314.198 43.6204 315.245 43.0895 316.094C42.5738 316.944 41.9823 317.657 41.33 318.233C40.2835 322.844 39.3127 327.591 38.5392 332.278C37.7656 336.889 37.1741 341.576 36.7191 346.46C37.8263 346.263 37.8263 344.898 38.1448 343.988C39.1156 341.257 40.2835 338.33 41.4666 335.403C44.1361 328.699 46.9269 321.676 47.837 316.352V313.303L47.8521 313.288Z\" fill=\"#00844B\"><\/path><path d=\"M16.0607 283.696C18.1387 286.684 21.0054 287.731 23.4019 290.582C21.9761 286.426 20.4745 282.255 18.5937 278.297C16.2579 273.231 13.4519 268.483 9.81166 264.448C9.61448 264.191 9.35663 263.933 9.87233 263.538C10.3274 263.083 10.5245 263.341 10.7217 263.599C14.4985 267.755 17.35 272.578 19.7617 277.781C20.8082 279.995 21.7183 282.21 22.6283 284.546C21.2633 279.282 20.4139 274.338 19.9588 269.651C18.7303 266.466 16.9101 263.675 14.6198 261.127C12.4053 258.715 9.81166 256.576 6.94497 254.756C6.8843 259.64 7.46067 264.57 9.02294 269.575C10.4487 274.262 12.7239 278.934 16.0456 283.681L16.0607 283.696Z\" fill=\"#00844B\"><\/path><path d=\"M27.315 295.663C27.7093 292.933 27.9065 290.142 28.0279 287.336C28.1644 283.635 28.0279 279.798 27.77 275.96C27.5122 272.578 25.6314 268.619 23.9326 264.964C23.2804 263.735 22.704 262.431 22.1731 261.263C22.0366 260.944 21.9153 260.671 22.4917 260.414C23.068 260.156 23.2045 260.474 23.341 260.732C23.7961 261.9 24.4483 263.144 25.0247 264.433C25.6769 265.798 26.3291 267.163 26.9054 268.528C26.7689 267.36 26.6476 266.253 26.5111 265.085C26.0561 262.355 25.5404 259.564 24.9488 256.758C24.8881 256.44 24.7516 256.106 25.4038 255.985C26.0561 255.924 26.1167 256.182 26.1774 256.5C26.7689 259.367 27.3453 262.158 27.7397 264.888C28.0582 267.3 28.3312 269.635 28.5132 271.971C28.6497 273.336 28.9076 274.58 28.9683 275.869C29.2261 279.707 29.3626 283.605 29.2261 287.382C29.1654 291.083 28.7711 294.799 28.1189 298.378C28.3767 298.894 28.5739 299.485 28.7711 300.001C29.7418 299.349 30.1968 297.21 30.849 293.949C31.0462 293.039 31.2434 291.993 31.4406 290.885C33.3214 282.498 33.0029 273.261 31.0462 264.934C29.3626 257.653 26.2381 250.888 21.5513 245.822C20.6412 252.981 20.3227 260.459 21.0962 268.574C21.9456 277.735 24.1601 286.911 27.2695 295.618L27.315 295.663Z\" fill=\"#00844B\"><\/path><path d=\"M6.4443 297.999C7.03584 297.999 7.49087 297.802 7.87006 297.483C8.18859 297.165 8.4616 296.71 8.4616 296.179C8.4616 295.648 8.20375 295.208 7.87006 294.875C7.4757 294.556 6.96 294.359 6.36846 294.359C5.85276 294.359 5.3219 294.556 4.9427 294.875C4.62418 295.193 4.427 295.648 4.427 296.179C4.427 296.71 4.62418 297.15 5.01854 297.483C5.33706 297.802 5.86793 297.999 6.4443 297.999Z\" fill=\"#00844B\"><\/path><path d=\"M38.4329 247.02C37.0678 247.612 35.6421 248.78 35.1112 249.296C33.3518 251.116 32.0625 252.739 31.2131 254.24C29.7115 256.713 30.1666 257.425 30.9553 259.837C31.4103 258.866 31.7288 257.759 32.0625 256.713C32.9726 253.785 34.5955 252.481 37.1285 250.539C37.3864 250.342 37.6442 250.084 37.8414 249.948C38.5543 249.432 39.343 250.403 38.6149 250.918C38.3571 251.176 38.0992 251.374 37.9021 251.51C35.5662 253.33 34.004 254.498 33.2911 257.031C33.0332 257.88 32.7754 258.791 32.4417 259.503C32.1839 260.277 31.8502 260.929 31.471 261.46C31.6075 261.976 31.7895 262.567 31.926 263.144C32.1839 262.431 32.5175 261.779 32.8967 261.126C33.6096 259.822 34.5804 258.715 35.8241 257.683C38.3571 255.666 40.0559 253.254 41.6182 250.858C41.2996 249.629 41.1025 247.673 40.1166 246.884C39.798 246.565 39.1458 246.687 38.4329 247.02Z\" fill=\"#00844B\"><\/path><path d=\"M40.5717 272.32C38.0387 275.187 35.6877 278.752 33.8676 283.499C33.8676 283.499 33.8069 283.56 33.8069 283.636C33.6097 286.169 33.2912 288.777 32.6997 291.25C32.9575 291.053 33.2154 290.734 33.549 290.476C34.3984 289.505 35.3085 288.398 35.6877 287.609C37.1135 285.334 38.2965 283.711 39.6616 281.755C39.6616 281.694 39.7981 281.497 40.511 280.526C41.0267 279.813 42.0733 280.526 41.5576 281.3C41.4211 281.436 41.2391 281.755 40.7082 282.468C39.3431 284.424 38.1752 286.047 36.8101 288.322C36.3551 289.096 35.3843 290.34 34.4743 291.31C33.3064 292.539 32.457 292.539 32.1385 294.238C31.8199 295.739 31.5469 297.029 31.2891 298.136C34.2771 295.8 36.9466 293.328 39.2824 290.795C42.0733 287.746 44.2878 284.621 45.7135 281.633C47.0179 279.04 47.8522 276.294 48.1859 273.564C48.5044 271.092 48.383 268.62 47.7915 266.026C45.3192 267.709 42.8468 269.727 40.5717 272.336V272.32Z\" fill=\"#00844B\"><\/path><path d=\"M10.661 250.539C11.2526 250.858 11.9654 250.934 12.5418 250.736C13.194 250.479 13.649 250.024 13.9069 249.432C14.1647 248.841 14.1647 248.203 13.9069 247.475C13.649 246.823 13.194 246.308 12.6025 245.974C12.0109 245.716 11.2981 245.579 10.7217 245.837C10.0695 246.035 9.61445 246.49 9.3566 247.066C9.09875 247.657 9.09875 248.37 9.3566 249.023C9.55378 249.735 10.0695 250.251 10.661 250.524V250.539Z\" fill=\"#00844B\"><\/path><path d=\"M30.6974 245.914C31.4103 242.986 32.4569 240.195 33.7613 237.526C34.1556 236.677 35.3236 237.268 34.9292 238.042C33.6248 240.711 32.654 243.441 31.9412 246.232C31.4255 248.31 30.9704 250.464 30.7126 252.603C31.6226 251.298 32.7905 249.872 34.2315 248.371C36.1881 246.414 38.0689 245.246 37.6139 241.803C37.356 240.18 36.6431 237.647 34.8837 235.099C32.745 237.374 30.7884 240.362 29.8784 243.487C29.1655 246.081 28.9683 249.084 29.484 252.466C29.7418 250.252 30.1362 248.037 30.7126 245.898L30.6974 245.914Z\" fill=\"#00844B\"><\/path><path d=\"M83.6934 410.301C83.5569 409.906 83.7541 409.588 84.0877 409.451C82.2069 407.313 80.4475 405.159 78.688 402.884C78.5515 409.846 78.8852 416.474 79.856 422.587C80.766 428.183 82.2676 433.704 84.6034 438.846C85.7714 437.284 86.0292 436.571 86.8786 434.812C87.1971 432.339 87.3336 429.67 87.1364 426.879C86.8786 421.419 85.7107 415.625 83.6934 410.301Z\" fill=\"#00844B\"><\/path><path d=\"M85.2404 410.756C87.0605 415.958 88.1677 421.555 88.4256 426.879C88.4863 428.639 88.4863 430.322 88.4256 432.021C89.1992 430.792 89.4722 429.685 89.6542 428.184C90.1092 425.393 90.1699 421.419 89.9727 416.611C89.9727 416.353 90.0334 416.156 90.1699 416.095C88.4863 414.335 86.8482 412.576 85.2252 410.756H85.2404Z\" fill=\"#00844B\"><\/path><path d=\"M91.0344 427.926C91.9445 426.242 92.718 424.483 93.3702 422.526C93.6281 421.677 93.8253 420.767 94.0831 419.796C93.1124 418.946 92.2023 418.036 91.2923 417.202C91.4895 421.555 91.3529 425.196 91.0344 427.926Z\" fill=\"#00844B\"><\/path><path d=\"M373.244 318.157C368.299 321.342 364.204 326.742 361.474 332.005C361.277 332.4 361.155 332.46 361.155 332.855C361.216 334.675 361.095 336.495 360.761 338.315C362.778 336.176 364.856 334.083 366.934 332.005C367.071 330.959 367.192 329.988 367.45 329.017C367.708 327.971 368.042 326.879 368.497 325.832C368.815 324.861 369.998 325.377 369.665 326.226C369.27 327.334 368.952 328.304 368.694 329.351C368.633 329.745 368.497 330.2 368.436 330.58C371.303 327.849 374.291 325.18 377.279 322.51C377.992 321.919 378.78 322.905 378.128 323.481C375.064 326.151 372.076 328.82 369.149 331.611C369.467 331.611 369.801 331.611 370.12 331.672C370.893 331.672 371.743 331.732 372.531 331.808C373.441 331.869 373.305 333.173 372.395 333.037C371.682 332.976 370.893 332.9 370.059 332.9H367.844C365.236 335.433 362.703 338.042 360.23 340.833C359.457 343.7 358.152 346.551 356.453 349.221C356.969 348.902 357.5 348.629 358.016 348.311C359.244 346.49 360.609 344.61 362.445 343.245C366.934 339.862 370.514 337.132 373.623 333.886C376.809 330.701 379.539 327.061 382.269 321.919C383.695 319.249 384.408 315.67 385.97 313.395C380.964 314.502 377.188 315.609 373.229 318.142L373.244 318.157Z\" fill=\"#00844B\"><\/path><path d=\"M374.473 292.736C369.589 296.71 365.312 300.806 362.187 305.098C358.805 309.785 356.787 314.79 356.984 320.114C358.607 322.647 359.775 325.256 360.428 327.986C360.488 325.969 360.488 324.012 360.625 322.268C360.822 319.674 361.14 317.323 361.671 315.306C362.323 313.228 363.097 311.605 364.007 310.3C364.917 308.996 366.024 308.025 367.132 307.252C367.905 306.736 368.633 307.767 367.905 308.298C366.798 309.011 365.888 309.921 365.038 311.089C364.189 312.257 363.476 313.759 362.9 315.64C362.763 316.095 362.703 316.55 362.581 317.065C363.097 316.474 363.628 315.958 364.144 315.503C365.251 314.532 366.358 313.683 367.587 312.909C368.3 312.454 369.012 313.501 368.239 314.017C367.132 314.729 366.024 315.518 364.993 316.428C364.022 317.399 363.036 318.385 362.202 319.477C362.066 320.387 362.005 321.358 361.944 322.404C361.808 324.422 361.747 326.56 361.747 328.911C364.417 324.361 367.268 321.115 370.332 318.703C371.181 316.747 371.955 314.866 372.41 313.046C372.804 311.226 373.062 309.148 372.668 307.328C371.955 303.354 373.062 298.879 374.033 294.784C374.23 294.071 374.351 293.419 374.488 292.767L374.473 292.736Z\" fill=\"#00844B\"><\/path><path d=\"M353.663 352.815C349.173 356.592 346.246 361.794 344.501 367.316C344.441 367.316 344.441 367.376 344.441 367.376C344.896 375.567 342.621 383.439 340.148 390.856C342.363 387.155 344.501 383.06 346.519 378.828L346.913 378.054H346.852C346.989 377.084 347.049 376.173 347.049 375.263C346.989 374.353 346.852 373.443 346.731 372.594C346.534 371.744 347.778 371.487 347.96 372.336C348.142 373.185 348.217 374.095 348.278 375.006C350.159 370.713 351.979 366.36 353.617 362.189C353.936 361.339 355.119 361.794 354.785 362.644C353.162 366.876 351.342 371.229 349.446 375.521C349.643 375.385 349.765 375.203 349.962 375.066C351.008 374.293 352.04 373.565 353.086 372.928C353.86 372.533 354.391 373.64 353.738 374.035C352.692 374.626 351.721 375.339 350.75 376.052C349.446 377.099 348.339 377.933 347.687 379.374C346.382 382.165 345.017 384.834 343.591 387.367C346.124 384.698 349.052 382.225 352.176 380.087C354.391 378.661 356.666 377.357 359.002 376.249C360.17 372.928 359.396 370.395 358.744 368.256C358.425 367.209 358.152 366.299 358.031 365.329C357.379 359.413 362.126 351.875 365.251 346.93C361.095 348.098 356.924 350.115 353.678 352.846L353.663 352.815Z\" fill=\"#00844B\"><\/path><path d=\"M371.803 262.568C372.319 262.704 372.911 262.507 373.366 262.173C373.957 261.718 374.336 261.127 374.534 260.353C374.731 259.58 374.67 258.851 374.397 258.336C374.139 257.82 373.745 257.426 373.168 257.289C372.653 257.153 372.061 257.289 371.546 257.684C371.03 258.078 370.635 258.654 370.438 259.443C370.241 260.156 370.302 260.945 370.575 261.521C370.833 262.037 371.288 262.431 371.803 262.568Z\" fill=\"#00844B\"><\/path><path d=\"M345.214 272.578C346.64 272.776 348.005 273.488 349.446 274.793C349.507 273.17 349.765 271.471 350.159 269.848C350.296 269.135 350.478 268.483 350.751 267.77C350.356 266.405 349.901 265.101 349.446 263.872C348.93 262.568 348.4 261.4 347.763 260.368C347.247 259.595 348.354 258.943 348.809 259.716C349.522 260.823 350.114 262.052 350.629 263.356C350.948 264.13 351.221 264.979 351.479 265.829C352.252 263.948 353.238 262.189 354.345 260.49C353.83 257.502 352.525 255.682 350.826 254.514C349.264 253.406 347.308 252.951 345.366 252.83C343.091 256.986 342.12 259.458 342.181 261.991C342.242 264.661 343.349 267.452 345.245 272.457V272.594L345.214 272.578Z\" fill=\"#00844B\"><\/path><path d=\"M354.315 288.838C355.089 290.067 355.938 291.311 356.909 292.479C357.045 292.084 357.167 291.705 357.303 291.371C355.999 285.911 355.741 281.224 356.393 275.764C356.651 273.807 357.045 271.79 357.5 269.788C357.106 268.878 356.727 267.968 356.393 267.058C356.135 266.087 355.938 265.04 355.877 263.933C355.817 263.023 357.106 263.023 357.182 263.933C357.182 264.843 357.379 265.814 357.637 266.663C357.773 267.058 357.895 267.513 358.092 267.892C358.805 265.359 359.775 262.826 360.958 260.278C361.353 259.504 362.521 260.02 362.126 260.869C361.019 263.144 360.17 265.419 359.457 267.755C359.518 267.619 359.654 267.497 359.775 267.361C360.367 266.769 360.943 266.193 361.338 265.541C361.853 264.767 362.9 265.48 362.445 266.254C361.929 266.967 361.338 267.619 360.685 268.271C360.094 268.863 359.457 269.378 358.805 269.894C358.289 271.911 357.895 273.929 357.697 275.946C357.561 277.053 357.44 278.16 357.379 279.268C357.697 278.949 358.092 278.555 358.425 278.221C359.017 277.508 359.593 276.856 359.851 276.401C360.306 275.551 361.413 276.143 361.019 276.992C360.625 277.584 360.048 278.297 359.336 279.07C358.623 279.844 357.834 280.693 357.379 281.482C357.379 284.076 357.697 286.685 358.152 289.278C360.23 284.849 362.703 281.088 365.494 277.902C366.146 275.627 366.464 273.413 366.404 271.198C366.343 268.923 365.949 266.648 365.236 264.434C364.462 262.022 364.265 259.489 364.523 256.956C364.659 255.136 365.039 253.179 365.494 251.298C364.189 252.208 362.9 253.118 361.717 254.165C356.833 258.26 352.874 263.857 351.372 270.167C349.871 276.143 350.599 282.65 354.3 288.823L354.315 288.838Z\" fill=\"#00844B\"><\/path><path d=\"M355.422 300.274C355.422 299.759 355.483 299.228 355.483 298.712C353.602 296.498 351.782 294.222 350.022 291.947H348.066C347.414 291.947 346.761 291.887 346.049 291.75C345.139 291.614 345.336 290.385 346.185 290.521C346.837 290.582 347.489 290.658 348.142 290.658C348.46 290.719 348.733 290.719 349.052 290.719C348.4 289.869 347.823 289.035 347.232 288.246C346.185 286.821 345.154 285.455 344.183 284.015C342.56 283.878 340.998 283.559 339.572 282.847C338.723 282.452 339.314 281.284 340.088 281.679C341.058 282.134 342.105 282.452 343.212 282.649C341.908 280.89 340.679 279.07 339.511 277.31C338.996 276.537 340.027 275.809 340.558 276.598C341.726 278.281 342.894 279.98 344.077 281.664C344.016 281.072 343.88 280.435 343.819 279.843C343.622 278.615 343.364 277.432 343.106 276.203C342.909 275.293 344.153 275.035 344.335 275.885C344.592 277.113 344.85 278.418 345.047 279.661C345.305 281.027 345.503 282.452 345.639 283.893C346.488 285.061 347.398 286.305 348.233 287.473C348.748 288.125 349.203 288.838 349.734 289.49C349.734 289.232 349.795 288.974 349.795 288.777C349.856 287.928 349.856 287.094 349.856 286.305C349.856 285.395 351.16 285.395 351.16 286.305C351.16 287.154 351.16 287.988 351.099 288.838C351.039 289.551 350.963 290.203 350.842 290.916C352.464 292.994 354.087 295.011 355.786 297.028C355.983 295.982 356.181 294.95 356.499 293.904H356.438C355.271 292.478 354.163 290.977 353.314 289.475C350.781 285.243 349.537 280.89 349.416 276.598C346.291 272.957 343.364 273.534 339.602 274.262C338.889 274.398 338.177 274.52 337.388 274.656C338.237 281.482 339.86 286.623 342.727 290.658C345.518 294.693 349.613 297.681 355.468 300.274H355.422Z\" fill=\"#00844B\"><\/path><path d=\"M356.651 300.73C356.514 303.854 356.909 306.979 357.879 309.83C358.592 308.329 359.442 306.842 360.473 305.34L360.412 305.28C360.155 303.778 359.957 302.61 360.352 301.124C361.52 296.437 363.218 292.145 365.296 287.989C366.267 286.169 367.253 284.288 368.345 282.528C368.482 281.679 368.603 281.027 368.664 280.39C368.8 279.737 368.8 279.161 368.861 278.372C368.861 277.462 370.089 277.523 370.089 278.433C370.089 278.827 370.089 279.282 370.029 279.662C370.742 278.494 371.53 277.326 372.243 276.219C372.44 275.961 372.562 275.703 373.093 276.021C373.684 276.34 373.487 276.613 373.29 276.931C370.878 280.632 368.482 284.606 366.464 288.565C366.146 289.157 365.873 289.733 365.615 290.325L365.676 290.264C366.388 289.748 367.177 289.217 367.951 288.838C368.724 288.444 369.316 289.551 368.542 290.006C367.769 290.324 367.117 290.78 366.404 291.31C365.751 291.826 365.099 292.418 364.447 293.07C364.386 293.07 364.386 293.131 364.386 293.131C363.218 295.8 362.308 298.53 361.595 301.458C361.338 302.307 361.338 303.081 361.459 303.93C363.082 301.791 364.963 299.698 367.056 297.62C367.056 297.62 367.117 297.559 367.117 297.484C369.194 294.359 370.893 291.113 372.183 287.792C373.608 284.409 374.594 281.027 375.246 277.584C375.701 275.051 376.02 272.442 376.672 269.848C373.35 272.063 370.302 274.535 367.511 277.584C364.128 281.224 361.262 285.577 359.184 290.127C357.682 293.373 356.772 297.089 356.651 300.73Z\" fill=\"#00844B\"><\/path><path d=\"M385.333 299.167C385.591 298.576 386.243 297.15 385.136 297.089C384.62 297.089 383.907 297.347 383.058 297.802C381.753 298.652 381.374 299.759 380.843 301.124C380.843 301.185 380.782 301.26 380.782 301.321C381.95 301.321 382.86 301.124 383.573 300.805C384.347 300.487 384.938 299.895 385.333 299.183V299.167Z\" fill=\"#00844B\"><\/path><path d=\"M354.573 318.946C352.616 316.474 350.872 314.138 349.31 311.863C348.081 310.043 347.035 308.344 346.124 306.721C344.562 310.953 343.455 315.503 343 320.054C342.484 324.862 342.606 329.746 343.455 334.493C344.107 337.739 345.275 340.803 347.095 343.654C348.597 345.99 350.538 348.205 352.95 350.161C352.556 344.898 351.721 339.696 350.538 334.554C349.568 333.962 348.718 333.325 347.808 332.537C346.898 331.687 345.988 330.716 345.139 329.609C344.547 328.896 345.594 328.108 346.109 328.836C346.959 329.882 347.793 330.792 348.703 331.566C349.158 332.021 349.613 332.339 350.068 332.734C349.158 329.23 348.111 325.848 346.944 322.389C346.686 321.54 347.854 321.161 348.172 321.995C349.279 325.241 350.311 328.563 351.16 331.884C351.418 330.777 351.615 329.609 351.676 328.502C351.676 327.592 352.98 327.653 352.904 328.563C352.844 330.443 352.389 332.339 351.676 334.16C352.904 339.423 353.754 344.822 354.148 350.283C361.171 340.727 362.081 328.502 354.543 318.946H354.573Z\" fill=\"#00844B\"><\/path><path d=\"M337.6 398.591C341.18 397.029 344.562 395.406 347.869 393.192C348.066 392.282 348.324 391.372 348.718 390.522C349.112 389.612 349.628 388.702 350.22 387.853C350.417 387.595 350.614 387.337 351.13 387.716C351.645 388.035 351.448 388.308 351.266 388.565C350.675 389.339 350.22 390.188 349.901 391.038C349.704 391.356 349.583 391.69 349.507 392.084C353.739 389.021 357.576 385.577 361.277 381.937C361.929 381.346 362.839 382.195 362.187 382.847C358.349 386.624 354.512 390.006 350.675 392.797C347.156 395.33 343.394 397.605 339.299 399.304C339.102 399.82 338.844 400.275 338.647 400.806C342.878 400.548 347.095 399.183 351.266 396.65C355.877 393.92 360.427 389.824 364.856 384.425C367.905 380.784 371.166 377.341 374.351 373.898C366.874 373.838 359.138 376.947 352.889 381.118C346.003 385.805 340.27 392.115 337.615 398.606L337.6 398.591Z\" fill=\"#00844B\"><\/path><path d=\"M372.91 359.58C371.743 359.383 370.377 360.035 370.044 361.203C369.649 362.31 370.438 363.281 371.545 363.478C372.653 363.675 374.018 363.023 374.412 361.855C374.731 360.748 374.018 359.838 372.91 359.58Z\" fill=\"#00844B\"><\/path><path d=\"M344.365 348.144C343.713 347.37 342.681 347.37 341.953 348.144C341.635 348.538 341.438 349.054 341.438 349.706C341.438 350.297 341.635 350.874 342.029 351.268C342.681 352.042 343.652 352.315 344.365 351.405C344.684 351.01 344.881 350.434 344.881 349.782C344.881 349.13 344.684 348.553 344.365 348.159V348.144Z\" fill=\"#00844B\"><\/path><path d=\"M333.444 399.304C332.595 397.621 332.019 395.406 331.624 392.797C331.169 389.551 331.033 385.714 331.306 381.543C331.503 378.221 331.897 374.914 332.474 371.471C333.065 368.028 333.899 364.509 335.082 361.006C335.34 360.096 336.584 360.49 336.25 361.4C335.143 364.843 334.294 368.286 333.717 371.669C333.126 375.051 332.807 378.373 332.61 381.619V381.679C332.807 381.361 332.929 381.027 333.126 380.769C333.839 379.662 334.552 378.555 335.401 377.523C335.993 376.871 336.963 377.66 336.372 378.373C335.598 379.343 334.87 380.329 334.233 381.437C333.581 382.483 333.004 383.575 332.474 384.758C332.413 387.686 332.534 390.355 332.868 392.691C333.187 395.027 333.839 397.636 335.143 399.714C336.705 399.001 337.873 393.54 338.586 391.523C342.029 381.315 345.214 370.258 341.574 358.822C340.861 356.486 339.815 354.211 338.526 351.996C337.813 350.692 336.963 349.402 335.993 348.159C333.581 357.972 330.198 367.406 325.921 376.386L325.663 376.841C325.603 382.635 326.058 388.277 327.483 392.312C328.651 395.755 330.547 398.227 333.46 399.334L333.444 399.304Z\" fill=\"#00844B\"><\/path><path d=\"M307.765 434.296C311.011 430.398 314.333 428.441 315.501 423.239C315.819 421.677 315.956 420.19 315.895 418.628C315.834 417.657 317.063 417.521 317.124 418.491C317.26 420.175 317.124 421.874 316.729 423.497C316.593 424.149 316.411 424.801 316.214 425.378C317.518 424.012 318.747 422.647 319.915 421.222C321.932 418.749 323.752 416.156 325.254 413.092C325.709 412.318 326.816 412.895 326.421 413.683C324.799 416.808 322.978 419.477 320.961 422.01C320.188 422.92 319.459 423.83 318.625 424.68C319.596 424.164 320.506 423.633 321.416 423.254C322.19 422.86 322.781 423.967 321.932 424.361C320.764 424.953 319.52 425.59 318.352 426.318C314.454 428.654 311.648 431.657 308.736 435.161C307.234 436.981 305.809 438.862 304.504 440.879C309.707 438.998 314.318 436.389 318.413 432.749C322.842 428.851 326.664 423.709 329.925 417.081C331.745 413.243 333.429 409.467 335.128 405.629C335.901 403.748 336.751 401.852 337.6 399.972C320.43 407.449 309.191 419.993 304.899 438.073C305.809 436.768 306.719 435.54 307.765 434.296Z\" fill=\"#00844B\"><\/path><path d=\"M315.562 404.188C316.077 404.188 316.532 404.052 316.866 403.733C317.185 403.415 317.458 402.884 317.579 402.11C317.579 401.853 317.579 401.519 317.518 401.261C317.458 400.806 317.26 400.412 317.063 400.154C316.805 399.896 316.548 399.699 316.214 399.699H315.956C315.501 399.759 315.107 400.017 314.788 400.412C314.47 400.806 314.272 401.382 314.197 402.035C314.197 402.626 314.333 403.202 314.652 403.658C314.849 403.976 315.167 404.173 315.562 404.173V404.188Z\" fill=\"#00844B\"><\/path><path d=\"M347.429 415.504C346.322 414.73 344.638 414.851 343.531 415.64C342.302 416.55 342.424 417.976 343.986 418.507C344.699 418.765 345.548 418.704 346.322 418.507C347.687 418.112 348.794 416.626 347.429 415.519V415.504Z\" fill=\"#00844B\"><\/path><path d=\"M315.88 436.374C312.24 438.968 308.205 440.985 303.852 442.486C302.805 443.397 301.971 444.564 301.319 445.808C300.864 446.718 300.409 447.689 300.015 448.857C303.261 448.72 306.779 447.75 310.617 446.187C313.347 444.109 315.956 441.758 318.231 439.165C318.883 438.452 319.793 439.301 319.202 440.014C317.837 441.576 316.335 443.002 314.773 444.443C317.897 442.941 321.204 441.197 324.783 439.241C325.557 438.786 326.209 439.893 325.375 440.348C321.143 442.684 317.245 444.701 313.605 446.324C315.031 446.46 316.472 446.718 317.958 447.37C318.474 447.568 318.474 447.886 318.155 448.341C319.52 447.75 320.825 447.113 322.053 446.324C328.621 442.486 334.278 436.768 338.829 431.308C331.548 430.14 321.856 432.081 315.88 436.374Z\" fill=\"#00844B\"><\/path><path d=\"M311.785 447.492H310.875C307.098 448.993 303.655 449.903 300.409 450.161C306.582 451.663 312.376 450.813 317.639 448.599C317.579 448.538 317.503 448.538 317.442 448.462C315.622 447.689 313.665 447.613 311.785 447.492Z\" fill=\"#00844B\"><\/path><path d=\"M303.079 440.348C303.473 438.468 303.928 436.648 304.444 434.888C302.942 432.931 301.85 429.291 301.198 426.895C300.94 425.787 299.12 424.559 298.073 424.028C297.3 423.634 297.815 422.526 298.665 422.921C299.636 423.376 300.546 424.028 301.334 424.877C301.592 423.77 301.926 422.663 302.305 421.632C302.821 420.13 303.473 418.704 304.383 417.476C304.975 416.763 306.006 417.536 305.43 418.249C304.58 419.356 304.004 420.661 303.473 422.026C303.018 423.391 302.624 424.817 302.366 426.182C302.821 428.715 303.731 431.126 304.975 433.144C305.945 430.216 307.053 427.426 308.418 424.756C309.009 420.069 308.933 415.974 308.281 412.394C307.963 410.256 307.371 408.238 306.597 406.479C303.215 410.574 299.575 414.472 295.737 418.188C295.995 426.576 298.665 431.642 301.395 437.042C301.987 438.088 302.502 439.181 303.079 440.364V440.348Z\" fill=\"#00844B\"><\/path><path d=\"M200.151 30.8812C198.012 31.852 198.467 34.1271 200.287 35.3102C202.426 36.6753 203.73 41.3621 204.519 46.1703C205.293 50.9177 205.566 55.8624 205.687 58.001C205.945 62.0356 206.005 66.1916 205.823 69.9077C205.687 73.1535 205.368 76.0809 204.853 78.3561C204.595 79.2661 204.337 80.1155 204.003 80.8284C203.29 82.6485 202.835 83.9529 204.853 85.9702C204.989 86.1067 205.171 86.2281 205.308 86.3646C205.763 86.6831 206.218 86.8803 206.733 86.8803C207.188 86.8803 207.704 86.6224 208.235 86.1067C208.432 85.9702 208.554 85.7882 208.69 85.591C209.6 84.4231 210.313 82.4665 210.768 79.8728C211.223 77.2033 211.481 73.8209 211.42 69.8015C211.42 64.3411 211.162 57.8949 210.192 51.661C209.221 45.427 207.659 39.3751 204.989 34.749C204.398 33.7024 203.685 32.4738 202.851 31.6245C202.077 30.9116 201.167 30.5172 200.181 30.9116L200.151 30.8812Z\" fill=\"#FFE200\"><\/path><path d=\"M219.975 113.135C219.125 113.59 217.245 115.092 217.108 115.547C217.108 115.092 215.606 113.408 214.772 112.68C207.81 112.089 200.924 111.831 194.023 111.831C187.122 111.831 180.175 112.089 173.349 112.68C172.5 113.333 170.938 115.092 170.938 115.547C170.801 115.031 168.92 113.59 168.01 113.135C153.51 114.637 139.268 117.428 125.48 121.463C124.707 121.66 123.857 122.828 123.918 123.419C123.918 124.071 125.419 123.419 126.512 123.161C127.937 122.843 127.422 124.132 128.134 124.329C128.59 124.39 129.181 124.329 130.546 123.935C130.607 124.39 129.636 124.648 128.863 125.497C127.952 126.544 127.558 127.772 129.575 127.636C131.138 127.575 131.714 127.12 132.306 127.378C133.352 127.772 132.503 128.349 134.323 127.894C154.026 123.283 174.047 120.932 194.008 120.932C217.214 120.932 240.497 124.117 263.187 130.366C261.367 127.636 265.144 127.241 267.086 127.954C268.056 128.349 272.88 130.821 276.323 130.366C279.766 129.911 278.598 128.485 276.717 127.317C274.381 125.891 271.378 125.436 270.665 125.497C268.906 125.634 261.504 123.677 261.822 122.448C265.205 123.358 268.784 124.466 272.227 124.587C255.513 118.793 237.888 115.031 219.944 113.135H219.975Z\" fill=\"#FFE200\"><\/path><path d=\"M176.671 69.7708C176.61 73.8054 176.868 77.1877 177.323 79.8421C177.839 82.4358 178.491 84.3924 179.401 85.5603C179.538 85.7575 179.72 85.9547 179.856 86.076C180.372 86.5917 180.903 86.8496 181.358 86.8496C181.874 86.8496 182.329 86.6524 182.784 86.3339C182.92 86.1973 183.102 86.076 183.239 85.9395C185.256 83.9222 184.801 82.6178 184.088 80.7977C183.77 80.0848 183.497 79.2354 183.239 78.3253C182.723 76.0502 182.389 73.1228 182.268 69.8769C182.071 66.176 182.131 62.0049 182.405 57.9703C182.541 55.8317 182.799 50.887 183.572 46.1395C184.225 42.3021 185.135 38.6012 186.56 36.5232C187.668 34.9609 190.079 30.2135 185.65 31.5786C185.332 32.0336 184.998 32.5493 184.74 33.1408C183.83 35.2795 183.178 38.3433 182.662 41.0735C182.207 43.2122 181.813 45.1688 181.358 46.276C179.341 50.8263 178.173 54.0722 177.46 57.5304C176.808 60.9128 176.686 64.5531 176.686 69.7556L176.671 69.7708Z\" fill=\"#FFE200\"><\/path><path d=\"M193.128 76.005C190.656 75.5499 188.836 73.4113 188.836 70.8631C188.836 68.0723 191.05 65.7213 193.78 65.6C190.914 65.4634 188.638 63.0669 188.638 60.2003C188.638 57.3336 190.853 54.9978 193.644 54.8006C191.05 54.5427 188.957 52.3889 188.957 49.7346C188.957 47.2622 190.777 45.1843 193.189 44.7292C191.232 44.4107 189.67 42.9091 189.215 41.0283C186.485 42.1356 185.059 44.9264 184.604 47.6566C184.012 51.8884 183.754 56.105 183.633 58.0616C183.436 62.0962 183.375 66.1915 183.497 69.8317C183.633 73.0169 183.952 75.8836 184.467 78.0223C184.664 78.9323 184.983 79.6452 185.241 80.3581C185.954 82.3147 186.545 83.7405 185.104 85.6971C185.817 85.4393 186.606 85.2421 187.379 85.1814C187.698 83.5585 188.487 82.2541 189.518 81.344C189.457 81.0861 189.457 80.8283 189.457 80.5704C189.457 78.356 191.02 76.4752 193.098 76.0201L193.128 76.005Z\" fill=\"#FFE200\"><\/path><path d=\"M203.594 78.0224C204.11 75.8838 204.443 73.0171 204.565 69.8319C204.701 66.1917 204.625 62.0964 204.428 58.0618C204.292 55.9231 203.973 50.9785 203.199 46.3523C203.063 45.3816 202.881 44.3957 202.684 43.4856C202.229 41.2105 200.803 40.0426 198.907 38.7988C199.423 41.529 197.678 44.1985 194.872 44.7142C197.284 45.1693 199.104 47.2472 199.104 49.7196C199.104 52.3891 197.026 54.5277 194.417 54.7856C197.208 54.9827 199.423 57.3186 199.423 60.1853C199.423 63.0519 197.148 65.4484 194.281 65.5849C197.011 65.7215 199.226 68.0573 199.226 70.8481C199.226 73.3811 197.405 75.5349 194.933 75.99C197.011 76.445 198.573 78.3258 198.573 80.5403C198.573 80.7981 198.573 81.056 198.513 81.3138C199.559 82.2239 200.333 83.5283 200.651 85.1512C201.501 85.2119 202.274 85.4091 202.987 85.7428C201.486 83.7862 202.016 82.2997 202.79 80.3431C203.048 79.6302 203.382 78.9173 203.564 78.0073L203.594 78.0224Z\" fill=\"#FFE200\"><\/path><path d=\"M95.3876 112.423C95.1298 112.741 94.5382 112.68 94.3411 112.286C93.2945 110.527 92.0659 109.419 90.7008 108.843C89.3357 108.267 87.91 108.191 86.469 108.585C85.0433 108.904 83.6782 109.692 82.5709 110.8C81.0693 112.165 79.9773 114.121 79.7043 116.26C79.6436 116.851 79.5677 117.428 79.5677 118.141C79.5677 119.187 79.7043 120.279 80.0835 121.189C80.4778 121.963 81.0542 122.555 81.9642 122.691C82.1007 122.691 82.2828 122.752 82.4193 122.752C83.0108 122.752 83.5265 122.555 83.9815 122.236C84.3759 121.978 84.6337 121.644 84.8309 121.265C85.0281 120.871 85.1495 120.416 85.1495 119.961C85.1495 119.445 85.0129 118.914 84.6944 118.459C84.5579 118.323 84.5579 117.944 84.6338 117.807C85.4073 116.123 86.4539 115.138 87.6825 114.758C88.7897 114.364 90.0941 114.44 91.3227 114.956C92.2934 115.274 93.2793 115.926 94.1135 116.639C95.5393 117.807 96.328 119.824 98.2088 118.065C98.8004 117.549 99.2554 116.897 99.5132 116.184C99.9076 115.335 101.076 115.79 100.681 116.639C100.363 117.549 99.7711 118.323 99.1189 118.975C96.5859 120.992 98.6032 120.992 98.6032 124.238C98.6032 124.633 98.6638 124.951 98.8004 125.285C99.5739 127.302 102.896 128.015 104.776 127.241C132.473 116.123 163.233 110.527 193.993 110.527C224.753 110.527 255.437 116.123 283.133 127.241C284.953 128.015 288.336 127.302 289.109 125.285C291.445 120.477 281.176 121.129 277.733 118.778C276.11 118.004 274.548 116.76 273.304 114.88C273.107 114.561 273.244 114.03 273.623 113.97C275.125 113.515 275.959 112.468 276.353 111.376C276.55 110.663 276.611 109.95 276.55 109.237C276.414 108.524 276.156 107.872 275.701 107.281C275.049 106.31 273.881 105.658 272.379 105.658C271.469 105.658 270.696 105.916 270.043 106.31C269.452 106.704 268.997 107.22 268.618 107.872C268.299 108.524 268.102 109.237 268.102 109.95C268.102 110.724 268.36 111.512 268.815 112.225C269.012 112.544 268.815 113.075 268.42 113.135C263.536 114.637 259.441 114.819 255.877 113.727C252.297 112.68 249.249 110.284 246.382 106.446C246.063 105.991 246.64 105.279 247.231 105.536C250.28 107.099 252.889 106.507 254.572 105.081C255.482 104.308 256.135 103.322 256.529 102.215C256.984 101.107 257.121 99.9395 256.923 98.893C256.666 96.9363 255.3 95.192 252.692 94.6005C252.434 94.5398 252.176 94.2061 252.176 93.9483C252.373 91.7338 251.584 90.1109 250.356 89.0036C249.643 88.4121 248.854 88.0329 248.02 87.8357C247.11 87.6385 246.2 87.6385 245.35 87.8357C243.727 88.2908 242.287 89.398 241.513 91.476C241.452 91.7338 241.058 91.931 240.8 91.8703C238.131 91.2181 236.189 92.1888 235.082 93.7511C234.43 94.7218 234.035 95.9656 233.975 97.1942C233.914 98.4228 234.111 99.6665 234.688 100.774C235.658 102.791 237.812 104.277 241.255 104.02C241.847 103.959 242.165 104.869 241.65 105.188C238.07 107.523 233.656 108.691 229.288 108.115C225.511 107.599 221.81 105.703 218.883 102.063C218.564 101.669 218.822 101.016 219.338 101.016C221.219 100.88 222.387 99.7879 222.917 98.4834C223.115 97.8919 223.175 97.2548 223.175 96.6026C223.175 95.9504 222.978 95.3741 222.72 94.7825C222.129 93.4781 220.9 92.5074 219.019 92.5074C217.457 92.5074 216.289 93.2202 215.637 94.191C215.182 94.7825 214.924 95.4196 214.863 96.1476C214.727 96.8605 214.803 97.5734 215 98.2256C215.394 99.3935 216.304 100.44 217.791 100.819C218.306 101.016 218.382 101.729 217.927 101.987C213.377 104.717 209.145 106.082 205.247 105.627C201.349 105.233 197.769 102.958 194.584 98.3469C194.19 97.8312 194.979 97.0425 195.494 97.4369C196.268 98.1497 197.512 98.4834 198.877 98.4834C199.923 98.4834 201.015 98.2862 202.001 97.8312C202.972 97.4369 203.882 96.8605 204.534 96.0111C205.308 95.101 205.763 93.8725 205.763 92.3102C205.763 90.7479 205.111 89.1856 204.079 88.0784C203.033 87.0318 201.668 86.3948 200.045 86.4555C199.787 86.4555 199.453 86.1369 199.453 85.8639C199.256 84.4988 198.74 83.4523 198.027 82.6787C197.254 84.1045 195.813 85.0904 194.053 85.151C195.282 90.217 195.221 89.8379 200.621 91.0664C198.088 91.0058 195.676 91.1271 193.993 93.0837C192.309 91.1271 189.897 91.0058 187.364 91.0664C192.764 89.8379 192.703 90.217 193.932 85.151C192.173 85.0904 190.747 84.1045 189.958 82.6787C189.245 83.4523 188.73 84.4988 188.532 85.8639C188.532 86.1218 188.214 86.4555 187.941 86.4555C186.439 86.3948 184.953 86.9712 183.846 87.8812C182.875 88.7306 182.283 89.8985 182.344 91.2029C182.344 92.113 182.799 92.8866 183.451 93.5388C183.77 93.7966 184.164 94.0545 184.558 94.191C184.953 94.3882 185.332 94.4488 185.726 94.3882C186.242 94.3882 186.834 94.191 187.289 93.6753C187.683 93.2202 188.517 93.6753 188.335 94.2668C188.199 95.0404 188.274 95.7684 188.532 96.3448C188.73 96.8605 189.124 97.3155 189.503 97.6492C189.958 97.9071 190.413 98.1042 190.929 98.1042C191.384 98.1042 191.9 97.9677 192.355 97.5885C192.87 97.1942 193.583 97.9829 193.265 98.4986C190.079 103.049 186.5 105.263 182.602 105.718C178.704 106.113 174.472 104.672 169.982 102.018C169.527 101.76 169.588 101.047 170.119 100.85C171.545 100.455 172.455 99.4238 172.849 98.2559C173.107 97.6037 173.167 96.8908 173.046 96.1779C172.925 95.4651 172.652 94.8129 172.273 94.2213C171.56 93.2506 170.452 92.5377 168.89 92.5377C167.009 92.5377 165.766 93.5084 165.113 94.8128C164.856 95.4044 164.719 95.9808 164.719 96.633C164.658 97.2852 164.78 97.9374 164.977 98.5138C165.493 99.8182 166.661 100.925 168.557 101.047C169.012 101.047 169.33 101.699 169.012 102.093C166.084 105.734 162.383 107.614 158.606 108.145C154.253 108.737 149.824 107.554 146.184 105.218C145.729 104.899 145.987 103.989 146.639 104.05C150.022 104.368 152.16 102.943 153.207 100.925C153.798 99.8182 154.056 98.4531 153.98 97.2245C153.844 95.9201 153.465 94.6915 152.812 93.7056C151.705 92.1433 149.764 91.2333 147.155 91.8855C146.897 91.9462 146.503 91.749 146.442 91.4911C145.668 89.4132 144.228 88.3059 142.605 87.8509C141.755 87.6537 140.845 87.6537 139.935 87.8509C139.086 88.0481 138.312 88.4424 137.599 89.0188C136.371 90.126 135.582 91.749 135.779 93.9635C135.779 94.2213 135.521 94.555 135.263 94.6157C132.67 95.1314 131.365 96.8908 131.032 98.8475C130.834 99.894 130.971 101.062 131.35 102.169C131.745 103.216 132.397 104.247 133.231 105.036C134.915 106.537 137.523 107.114 140.648 105.627C141.164 105.37 141.755 106.082 141.422 106.537C138.555 110.314 135.506 112.711 131.927 113.757C128.347 114.865 124.312 114.667 119.383 113.166C118.989 113.105 118.867 112.574 119.064 112.256C119.519 111.543 119.717 110.754 119.717 109.981C119.717 109.268 119.58 108.555 119.201 107.903C118.882 107.25 118.427 106.735 117.775 106.34C117.184 105.946 116.41 105.688 115.5 105.688C113.998 105.688 112.83 106.34 112.118 107.311C111.723 107.903 111.465 108.54 111.344 109.268C111.283 109.981 111.283 110.693 111.541 111.406C111.936 112.514 112.77 113.545 114.271 114C114.59 114.061 114.787 114.592 114.59 114.91C113.361 116.791 111.799 118.035 110.161 118.808C108.144 119.779 106.005 120.113 104.048 120.037C103.533 120.037 103.199 119.445 103.533 119.066C104.579 117.762 105.156 116.139 105.156 114.576C105.156 113.803 105.019 113.075 104.761 112.438C104.443 111.785 104.048 111.209 103.533 110.754C102.683 110.163 101.652 109.783 100.211 109.783C99.1037 109.723 98.2543 109.981 97.4808 110.436C96.7072 110.891 95.9792 111.603 95.3421 112.453L95.3876 112.423Z\" fill=\"#FFE200\"><\/path><path d=\"M197.739 39.7995C197.739 37.7822 196.055 36.0986 194.038 36.0986C192.021 36.0986 190.337 37.7822 190.337 39.7995C190.337 41.8168 192.021 43.5763 194.038 43.5763C196.055 43.5763 197.739 41.8927 197.739 39.7995Z\" fill=\"#FFE200\"><\/path><path d=\"M160.472 491.387C159.956 492.555 160.214 493.86 161.064 494.77C161.716 495.422 162.565 495.741 163.339 496.074C162.034 498.744 160.153 499.972 157.09 499.654C153.768 499.259 151.174 497.773 149.551 495.68C148.702 494.633 148.126 493.465 147.792 492.237C147.473 491.008 147.337 489.704 147.473 488.399C147.792 485.609 149.293 482.802 152.024 480.664C155.012 478.252 161.003 476.311 166.387 474.491C168.526 473.778 170.619 473.126 172.303 472.473C174.836 471.503 176.08 469.607 176.277 467.862C176.413 466.694 176.019 465.39 174.972 464.677C174.062 464.086 172.697 464.086 170.938 465.132C167.161 467.347 163.657 468.712 160.017 470.077C158.136 470.85 156.119 471.578 154.102 472.488C149.491 474.566 145.653 477.949 143.242 481.923C140.314 486.731 139.146 492.646 141.482 497.849C142.787 500.716 145.001 503.309 148.444 505.387C152.084 507.662 156.513 508.117 160.351 507.147C163.475 506.297 166.524 504.477 168.223 501.686C170.179 498.562 170.301 493.299 167.631 490.508C165.553 488.369 161.716 488.49 160.472 491.418V491.387Z\" fill=\"#FFE200\"><\/path><path d=\"M233.96 472.458C231.942 471.548 229.925 470.835 228.044 470.046C224.404 468.681 220.885 467.316 217.123 465.102C214.651 463.676 211.663 463.6 208.736 463.676C210.692 465.815 211.921 468.165 214.135 470.243C215.045 471.154 215.895 471.866 216.729 472.519C218.231 473.565 219.914 474.02 221.613 474.597C227.073 476.356 233.125 478.298 236.053 480.649C238.783 482.787 240.284 485.593 240.603 488.384C240.861 490.978 240.148 493.587 238.525 495.664C236.902 497.742 234.293 499.244 230.987 499.638C227.923 499.957 226.042 498.728 224.738 496.059C225.511 495.74 226.361 495.407 227.013 494.754C227.862 493.844 228.12 492.54 227.604 491.372C226.376 488.445 222.538 488.323 220.445 490.462C217.776 493.253 217.912 498.531 219.854 501.641C221.537 504.431 224.601 506.251 227.726 507.101C231.563 508.072 235.977 507.617 239.632 505.341C243.075 503.264 245.29 500.655 246.594 497.803C248.93 492.601 247.762 486.685 244.835 481.877C242.423 477.918 238.586 474.536 233.975 472.443L233.96 472.458Z\" fill=\"#FFE200\"><\/path><path d=\"M219.52 489.567C220.369 488.718 221.34 488.202 222.311 487.944C223.357 487.687 224.328 487.687 225.299 487.884C226.148 488.142 226.922 488.597 227.574 489.188C228.09 489.704 228.484 490.295 228.742 490.948C229.06 491.66 229.197 492.51 229.06 493.359C228.924 494.209 228.545 494.982 227.892 495.695C227.498 496.014 227.043 496.408 226.467 496.742C226.861 497.333 227.377 497.712 227.892 497.97C228.742 498.425 229.713 498.486 230.759 498.425C233.747 498.031 236.022 496.742 237.524 494.922C238.237 494.011 238.752 493.041 239.025 491.933C239.344 490.826 239.42 489.719 239.283 488.551C239.025 486.079 237.721 483.606 235.249 481.665C232.519 479.45 226.542 477.57 221.203 475.81C220.43 475.552 219.702 475.355 219.323 475.219C217.958 474.764 216.987 474.248 216.001 473.596C215.091 472.944 214.242 472.17 213.21 471.184C212.164 470.138 211.193 469.106 210.222 467.999L210.161 467.938C209.449 467.741 208.66 467.544 207.947 467.347C207.628 467.286 207.355 467.15 207.037 467.089C208.599 468.06 210.086 469.227 211.39 470.532C215.819 474.885 218.61 480.998 218.61 487.702C218.61 488.87 218.549 490.113 218.352 491.281C218.67 490.629 219.065 490.053 219.52 489.598V489.567Z\" fill=\"#FFE200\"><\/path><path d=\"M210.541 474.612C206.187 473.247 201.759 472.018 197.269 471.29C194.084 470.699 195.646 471.882 194.144 474.475C192.84 476.751 191.475 479.086 189.988 481.498C188.82 483.455 187.577 485.396 186.287 487.353C185.893 488.005 185.772 488.46 186.424 488.854C187.334 489.37 188.563 489.446 189.549 489.507C195.145 490.022 200.469 492.753 205.156 495.816C206.46 496.59 208.796 498.547 210.101 498.683C210.753 498.82 211.329 498.486 212.118 497.576H212.057C212.77 496.529 213.68 495.559 214.272 494.451C215.834 491.66 213.62 489.385 211.284 488.081C205.945 485.093 200.227 482.818 194.372 481.195C193.522 480.937 193.856 479.693 194.69 479.966C199.954 481.468 205.095 483.409 209.904 485.882C212.694 487.307 214.454 484.38 214.97 482.105C215.682 478.722 213.923 475.674 210.541 474.627V474.612Z\" fill=\"#FFE200\"><\/path><path d=\"M194.675 466.679C194.736 467.65 195.07 469.667 196.101 469.804C200.393 470.395 204.625 471.487 208.781 472.731C209.373 472.928 210.01 472.928 210.404 472.337C210.541 472.14 210.662 471.563 210.465 471.366C206.491 467.468 201.167 464.996 195.252 464.662C195.252 464.662 195.231 464.682 195.191 464.723C194.675 465.041 194.599 465.951 194.675 466.679Z\" fill=\"#FFE200\"><\/path><path d=\"M204.625 497.105C199.165 494.769 196.829 499.062 192.597 500.882C189.078 502.383 184.983 503.293 181.221 503.157C181.737 504.325 182.587 505.371 183.633 506.282L184.027 505.766C184.543 504.992 185.59 505.766 185.074 506.479L184.619 507.07C184.938 507.328 185.211 507.525 185.529 507.722C185.787 507.465 185.923 507.07 185.984 506.676C186.181 505.826 187.41 506.084 187.213 506.934C187.152 507.449 186.955 507.98 186.621 508.435C187.076 508.693 187.531 508.951 188.047 509.148C188.305 508.632 188.502 508.102 188.563 507.525C188.699 506.615 189.988 506.812 189.791 507.722C189.731 508.435 189.473 509.088 189.2 509.679C189.913 509.998 190.625 510.271 191.278 510.453C191.535 509.679 191.672 508.951 191.596 508.238C191.535 507.328 192.825 507.267 192.901 508.102C192.901 508.951 192.84 509.785 192.582 510.635C193.037 510.695 193.553 510.695 194.008 510.695H194.523C194.721 509.725 194.781 508.739 194.842 507.768C194.842 506.858 196.071 506.919 196.071 507.829C196.071 508.739 196.01 509.709 195.813 510.619C196.662 510.559 197.496 510.422 198.346 510.301C198.406 509.194 198.406 508.086 198.285 506.979C198.224 506.069 199.453 505.933 199.589 506.843C199.65 507.889 199.65 508.921 199.65 509.967C200.363 509.77 201.152 509.573 201.865 509.315C201.865 508.147 201.804 506.903 201.546 505.735C201.349 504.886 202.653 504.628 202.775 505.538C203.033 506.585 203.093 507.677 203.169 508.784C203.882 508.466 204.671 508.132 205.308 507.738C205.368 506.63 205.505 505.66 205.171 504.613C204.974 503.703 206.218 503.385 206.4 504.295C206.658 505.265 206.658 506.175 206.658 506.964C207.31 506.509 207.826 505.66 207.704 504.886C207.644 504.689 207.568 504.492 207.507 504.234C207.113 503.384 208.281 502.869 208.614 503.718C208.614 503.718 208.634 503.764 208.675 503.855C208.933 503.202 209.13 502.55 209.069 501.898C209.009 499.684 206.476 497.863 204.58 497.09L204.625 497.105Z\" fill=\"#FFE200\"><\/path><path d=\"M186.105 501.458C189.291 500.943 195.145 499.244 196.829 496.119C197.542 494.891 197.026 492.798 195.661 492.282C192.537 491.053 188.32 490.204 184.862 490.598C183.633 490.735 182.526 491.19 181.358 491.372C180.964 491.433 180.584 491.508 180.19 491.508C178.112 491.645 175.958 490.796 174.472 489.37C173.82 488.718 174.669 487.808 175.321 488.46C176.626 489.688 178.446 490.341 180.129 490.28C180.584 490.28 180.979 490.219 181.358 490.083C182.526 489.825 183.633 489.112 184.346 488.005C185.969 485.593 187.471 483.197 188.896 480.846C190.322 478.51 191.763 476.159 193.128 473.823C194.493 471.351 194.69 467.847 192.081 466.209C191.945 466.148 191.884 466.072 191.763 466.072C190.853 465.617 187.865 465.617 188.381 467.301C188.699 468.469 190.064 469.121 190.337 470.486C190.474 471.335 190.277 472.17 189.685 473.535C188.123 476.917 186.242 480.163 184.225 483.288C183.709 484.061 182.662 483.348 183.178 482.575C185.195 479.526 187.015 476.401 188.517 473.019C188.972 471.912 189.169 471.26 189.033 470.744C188.896 469.97 187.926 468.863 187.273 468.332C185.514 467.104 183.299 467.559 181.358 468.59C179.856 469.364 178.491 470.471 177.581 471.381C173.349 475.537 170.756 481.27 170.756 487.641C170.756 491.539 171.726 495.255 173.486 498.44C175.048 500.973 178.233 501.762 181.358 501.822C183.042 501.883 184.74 501.686 186.105 501.428V501.458ZM178.946 479.162C179.598 478.191 180.311 477.281 180.903 476.295C181.039 476.098 181.221 475.84 181.358 475.643C181.813 474.87 182.268 474.141 182.723 473.429C183.178 472.655 184.285 473.292 183.77 474.081C183.178 475.052 182.602 476.037 182.01 477.008C181.752 477.327 181.555 477.6 181.358 477.918C180.903 478.57 180.448 479.223 179.993 479.875C179.401 480.648 178.37 479.875 178.946 479.162Z\" fill=\"#FFE200\"><\/path><path d=\"M174.851 472.534C174.26 472.989 173.547 473.383 172.773 473.641C171.014 474.293 168.936 475.006 166.797 475.719C161.534 477.478 155.618 479.42 152.812 481.634C150.34 483.591 149.036 486.063 148.778 488.52C148.641 489.688 148.717 490.796 149.036 491.903C149.294 493.01 149.809 493.981 150.537 494.891C152.812 497.758 157.818 499.183 159.638 495.027C159.319 494.512 159.122 493.92 158.986 493.344C158.849 492.494 158.986 491.66 159.304 490.932C159.562 490.28 159.956 489.704 160.472 489.173C161.124 488.581 161.898 488.126 162.747 487.868C163.718 487.671 164.704 487.671 165.735 487.929C166.706 488.187 167.692 488.703 168.526 489.552C168.981 490.007 169.376 490.598 169.694 491.236C169.497 490.068 169.436 488.824 169.436 487.656C169.436 481.938 171.454 476.675 174.836 472.503L174.851 472.534Z\" fill=\"#FFE200\"><\/path><path d=\"M199.165 459.459C197.481 459.459 195.722 459.52 194.023 459.52C192.461 459.52 190.838 459.52 189.276 459.459C186.94 459.398 185.12 462.326 187.455 464.267C189.533 463.676 191.748 463.357 194.023 463.357C199.165 463.357 204.428 465.041 209.373 466.421C207.75 463.888 202.35 459.338 199.165 459.459Z\" fill=\"#FFE200\"><\/path><path d=\"M153.586 471.29C155.664 470.38 157.681 469.667 159.638 468.878C163.217 467.513 166.661 466.148 170.361 463.994C170.619 463.858 170.877 463.737 171.135 463.6C171.529 462.751 171.59 461.977 171.332 461.188C169.967 461.249 168.86 461.386 167.95 461.507C165.811 461.765 164.962 461.704 164.765 459.368C164.704 458.853 164.704 458.2 164.628 457.351C163.718 457.745 162.869 458.064 162.216 458.398C161.367 458.853 160.654 459.308 160.078 459.763C159.941 459.899 159.623 459.899 159.426 459.823C157.469 458.974 155.33 458.2 153.176 457.806C151.099 457.351 148.945 457.214 146.867 457.487C146.351 457.624 145.957 456.972 146.275 456.517C146.73 455.804 147.246 455.091 147.837 454.378C148.035 454.12 148.232 453.862 148.49 453.605C148.095 453.665 147.716 453.741 147.322 453.862C146.351 454.06 145.502 454.317 144.592 454.636C144.076 454.772 143.621 454.181 143.879 453.726L145.244 451.254C144.076 451.314 142.908 451.511 141.801 451.769C140.375 452.027 138.873 452.482 137.448 453.074C136.993 453.271 136.401 452.679 136.674 452.224L138.297 448.448L138.16 448.387C136.401 448.705 134.642 449.1 132.897 449.494C132.442 449.555 132.048 449.1 132.184 448.645L132.958 446.112C132.761 445.975 132.564 445.915 132.366 445.793C130.683 446.9 129.121 447.613 127.68 448.008C126.375 448.265 125.147 448.265 124.161 447.81C123.114 447.355 122.341 446.445 121.886 445.08C121.491 443.912 121.37 442.289 121.567 440.196C121.506 440.196 121.431 440.136 121.37 440.136L119.413 441.759C119.019 442.077 118.367 441.759 118.367 441.304L118.169 438.24C118.033 438.103 117.912 438.043 117.775 437.982C117.381 438.3 116.926 438.695 116.471 439.089C116.334 439.226 116.213 439.286 116.152 439.347C115.834 439.665 115.181 439.408 115.106 438.953C115.045 438.103 115.045 437.33 115.106 436.617C114.453 437.072 113.801 437.466 113.028 437.724C112.633 437.86 112.178 437.587 112.178 437.208C112.118 436.238 112.042 435.252 112.118 434.342C111.92 434.144 111.663 434.023 111.465 433.887C110.692 434.281 109.903 434.539 109.13 434.539C108.219 434.599 107.309 434.402 106.521 433.947C105.747 433.492 105.095 432.901 104.64 432.066C104.048 431.02 103.73 429.791 103.927 428.29C100.878 425.878 97.951 423.406 95.0843 420.812C94.9478 421.525 94.7658 422.177 94.4927 422.89C93.5827 425.878 92.2783 428.35 90.5947 430.959C89.1689 433.037 87.9858 435.054 87.0758 437.39C86.3022 439.271 84.8613 442.593 85.5742 444.61C86.1657 446.37 88.3043 446.43 89.6694 445.657C90.261 444.094 90.898 442.608 91.4896 441.106C92.2631 439.347 92.9911 437.724 93.704 436.222C94.0984 435.373 95.2056 435.965 94.8113 436.738C94.0984 438.3 93.3855 439.923 92.6726 441.546C92.0204 443.23 91.3075 444.929 90.6553 446.552C90.3368 447.462 90.4581 449.342 90.9132 450.192C91.3075 451.102 92.0811 451.496 93.0518 451.299C94.1591 451.041 95.0691 450.389 95.4635 449.418C95.9792 448.053 96.51 446.749 97.0864 445.52C97.6021 444.155 98.1937 442.79 98.8459 441.364C99.1644 440.515 100.347 441.046 100.014 441.88C99.4222 443.184 98.8459 444.549 98.2543 445.975C97.6628 447.401 97.0864 448.842 96.4949 450.268C95.9792 451.436 95.782 452.937 96.0399 454.242C96.237 455.288 96.8134 456.198 97.7235 456.835C98.77 457.487 100.256 456.244 100.59 455.334C100.909 454.424 101.182 453.514 101.5 452.603L102.152 450.647C102.471 449.797 103.715 450.192 103.381 451.041L102.668 453.059C102.41 453.908 102.077 454.818 101.758 455.728C101.303 457.093 101.167 458.519 101.364 459.884C101.622 461.113 102.137 462.356 103.047 463.327C103.7 464.101 104.276 464.829 105.262 464.374C105.914 464.116 106.49 463.524 106.688 462.948C107.461 460.809 108.25 458.519 108.963 456.32C109.418 455.015 109.812 453.787 110.131 452.998C110.388 452.148 111.632 452.543 111.299 453.392C110.844 454.757 110.525 455.728 110.191 456.714C109.418 458.928 108.69 461.067 107.916 463.342C107.4 464.768 107.4 466.072 107.719 466.922C108.113 467.892 108.887 468.347 109.858 468.287C111.162 468.15 112.451 467.119 112.588 465.814C112.724 464.586 112.906 463.084 113.24 461.461C113.634 459.505 114.15 457.305 114.742 454.894C114.999 454.044 116.243 454.378 115.97 455.212C115.379 457.548 114.863 459.763 114.469 461.719C114.15 463.539 113.877 465.162 113.816 466.527C113.756 467.498 113.877 468.15 114.211 468.484C114.529 468.939 115.06 469 115.576 468.803C116.622 468.484 117.199 467.437 117.714 466.467C118.488 464.965 119.14 463.281 119.671 461.461C120.263 459.247 120.778 456.911 121.173 454.242C121.309 453.392 122.538 453.589 122.401 454.439C122.007 457.169 121.491 459.581 120.9 461.78C120.308 463.737 119.671 465.481 118.822 467.043C117.851 468.924 118.23 472.898 121.097 470.623C122.978 469.197 125.071 465.481 126.299 463.281C126.618 462.629 126.952 462.114 127.149 461.856C127.604 461.082 128.711 461.719 128.195 462.508C127.998 462.826 127.74 463.281 127.422 463.934C126.315 465.814 124.692 468.818 122.811 470.698C121.643 472.003 119.823 474.217 120.217 476.038C120.414 476.948 121.127 477.463 122.037 477.463C123.721 477.524 124.965 475.901 125.814 474.597C126.982 472.64 128.286 470.896 129.591 469.136C131.017 467.255 132.457 465.435 133.883 463.676C134.475 463.024 135.445 463.812 134.854 464.525C133.352 466.285 131.927 468.105 130.622 469.925C129.318 471.548 128.089 473.307 126.921 475.188C126.148 476.356 124.843 477.403 124.449 478.707C124.055 479.875 124.13 480.785 124.449 481.437C124.707 482.029 125.298 482.347 125.951 482.287C127.058 482.15 128.089 481.119 128.681 480.269C130.501 477.676 132.382 475.203 134.399 472.731C136.356 470.319 138.494 467.983 140.648 465.708C141.3 465.056 142.21 465.966 141.558 466.618C139.419 468.833 137.326 471.169 135.385 473.58C133.368 475.916 131.547 478.464 129.727 480.997C129.212 481.847 128.559 482.423 127.968 482.817C127.194 484.638 127.452 486.716 128.226 488.02C128.544 488.414 128.878 488.733 129.196 488.991C131.077 489.961 132.579 486.579 133.034 485.411C134.202 482.544 135.764 480.072 137.584 477.933C139.465 475.856 141.619 474.035 143.955 472.412C144.212 472.215 144.47 472.018 144.865 472.549C145.183 473.065 144.925 473.262 144.667 473.459C142.453 475.021 140.314 476.781 138.555 478.798C136.795 480.876 135.309 483.151 134.262 485.881C133.61 487.565 131.927 489.203 133.671 490.887C133.989 491.205 134.444 491.478 134.899 491.6C135.354 491.797 135.87 491.797 136.401 491.736C137.448 491.6 138.479 490.826 139.131 489.142C139.526 486.473 140.557 483.743 142.059 481.27C144.652 477.114 148.626 473.535 153.51 471.32L153.586 471.29Z\" fill=\"#FFE200\"><\/path><path d=\"M267.055 453.483C261.595 450.753 255.68 449.054 251.19 447.886H251.129C251.387 448.66 251.19 449.388 251.19 450.222C251.129 450.616 250.674 450.935 250.28 450.738C249.309 450.283 248.521 449.828 247.747 449.373C248.141 450.222 248.399 451.132 248.596 452.239C248.657 452.694 248.278 453.089 247.823 452.952C246.518 452.694 245.229 452.3 243.985 451.906C243.728 451.845 242.939 451.314 242.681 451.253C243.394 451.966 244.638 453.074 245.548 453.923C245.942 454.317 245.411 455.152 244.895 454.97C242.817 454.257 241.255 453.407 239.435 452.437C240.148 453.802 241.195 455.303 242.165 456.532C242.484 457.047 241.771 457.836 241.255 457.442C239.374 456.213 237.554 454.848 235.795 453.407C235.537 453.468 235.279 453.604 235.021 453.665C235.416 454.712 235.871 455.743 236.326 456.729C236.584 457.321 235.673 457.897 235.279 457.442C234.43 456.395 233.596 455.364 232.867 454.257C231.639 454.575 230.395 454.909 229.167 455.227C230.334 456.456 231.578 457.639 232.807 458.746C233.52 459.338 232.67 460.309 231.957 459.717C230.456 458.413 229.091 457.048 227.801 455.561C226.831 455.819 225.845 456.016 224.935 456.213L228.378 459.99C228.969 460.642 228.059 461.492 227.407 460.839L223.433 456.547C222.129 456.805 220.764 457.063 219.399 457.321C219.914 457.715 220.445 458.17 221.022 458.549C222.326 459.52 223.615 460.43 225.056 461.34C225.83 461.795 225.117 462.902 224.343 462.447C222.917 461.537 221.552 460.566 220.248 459.58C219.399 458.928 218.564 458.276 217.776 457.563C216.805 457.76 215.758 457.882 214.788 458.018C215.637 459.58 216.547 460.946 217.654 462.174C219.08 463.797 220.642 465.162 222.462 466.269C222.66 466.406 222.857 466.527 223.054 466.664C224.874 467.513 226.694 468.165 228.514 468.878C230.471 469.652 232.412 470.38 234.49 471.29C239.374 473.504 243.333 477.084 245.942 481.24C247.565 483.909 248.612 486.837 248.991 489.688C249.249 491.963 249.051 494.239 248.475 496.453C249.188 497.166 250.432 496.65 251.205 496.135C252.707 495.088 253.875 492.692 254.527 490.159C255.3 487.17 255.437 483.909 254.785 482.089C253.025 477.478 250.295 473.762 246.716 471.032C243.136 468.241 238.722 466.285 233.58 465.056C232.67 464.859 232.989 463.63 233.838 463.827C239.177 465.056 243.788 467.073 247.489 470.001C251.266 472.928 254.117 476.765 255.938 481.634C256.256 482.484 256.393 483.652 256.453 484.88C256.453 485.593 256.848 486.245 257.56 486.64C258.865 487.489 259.578 485.472 259.775 484.501C260.548 480.209 259.32 476.174 257.045 472.867C254.117 468.438 249.309 465.132 244.88 463.63C243.97 463.372 244.425 462.129 245.275 462.462C249.961 464.025 254.967 467.528 258.152 472.155C260.685 475.992 262.05 480.603 260.822 485.548C260.624 486.321 260.564 486.852 261.019 487.626C261.216 488.081 261.671 488.475 262.187 488.338C264.522 487.883 264.977 483.727 265.175 481.968C265.432 480.148 265.569 478.267 265.569 476.31C265.508 473.838 265.175 471.366 264.007 469.348C262.323 466.163 257.181 463.691 253.086 461.613C251.857 461.021 250.674 460.445 249.704 459.854C248.93 459.459 249.506 458.291 250.295 458.746C251.266 459.338 252.434 459.853 253.678 460.506C257.909 462.584 263.233 465.253 265.19 468.757C266.418 470.971 266.813 473.641 266.873 476.295C266.873 478.252 266.676 480.269 266.418 482.15C266.282 483.652 267.465 484.289 268.633 483.318C270.514 481.756 271.757 478.768 272.273 475.643C272.789 472.2 272.531 468.56 271.363 466.482C269.998 463.949 268.041 461.871 265.645 460.111C263.233 458.428 260.382 456.987 257.257 455.758C256.408 455.44 256.863 454.257 257.712 454.59C260.897 455.819 263.885 457.32 266.358 459.141C268.951 460.961 271.045 463.175 272.531 465.905C273.441 467.589 273.896 470.259 273.76 472.989C273.76 473.702 273.502 474.096 274.215 474.612C274.988 475.203 275.898 475.522 276.748 474.748C277.203 474.293 277.597 473.58 277.915 472.792C278.628 470.714 278.826 467.908 278.568 465.966C277.915 460.566 272.91 456.471 267.055 453.483Z\" fill=\"#FFE200\"><\/path><path d=\"M281.1 455.167C279.22 453.028 276.55 451.072 272.91 449.449C271.09 448.6 269.27 447.432 267.51 446.264C266.54 445.611 265.554 445.035 264.583 444.307C263.612 443.594 262.96 443.139 261.656 443.139C261.003 443.139 260.745 443.336 260.882 443.989C261.079 444.641 261.656 445.414 261.989 446.067C261.14 446.067 260.488 446.006 259.653 445.748C258.607 445.49 257.575 445.156 257.378 445.809C256.923 446.855 259.198 448.857 260.245 449.191C262.717 450.101 265.25 451.148 267.662 452.376C273.835 455.501 279.114 459.915 279.887 465.83C279.948 466.679 280.024 467.65 279.948 468.697C280.918 469.47 281.176 469.804 282.284 468.757C283.785 467.256 285.074 464.662 284.619 462.448C284.028 459.854 282.996 457.382 281.1 455.167Z\" fill=\"#FFE200\"><\/path><path d=\"M298.467 436.117C297.952 433.902 297.163 431.763 295.995 430.065C294.888 428.502 293.386 427.471 291.506 427.334C290.99 427.334 290.459 427.395 289.883 427.532C289.17 427.668 288.517 428.047 288.26 428.76C287.865 429.67 288.396 431.172 289.109 431.748C290.671 432.977 292.097 434.615 293.401 436.359C294.964 438.498 296.329 440.712 297.102 442.472C297.3 442.866 297.497 443.321 297.694 443.837C299.12 444.231 298.998 443.973 298.998 442.669C298.998 442.472 298.998 442.214 299.059 441.956C299.12 440.333 298.922 438.179 298.467 436.101V436.117Z\" fill=\"#FFE200\"><\/path><path d=\"M292.355 437.163C291.187 435.479 289.761 433.917 288.32 432.81C287.471 432.097 286.44 431.702 285.454 431.763C284.604 431.899 283.77 432.279 283.042 433.189C282.648 433.644 282.451 434.159 282.526 434.69C282.587 435.919 284.286 437.36 285.059 438.133C287.85 441.061 290.717 444.049 293.189 447.689C293.902 448.796 294.691 450.359 295.009 451.921C295.859 452.239 296.966 452.573 297.421 451.526C297.618 451.011 297.679 450.298 297.679 449.509C297.542 447.295 296.632 444.564 295.919 443.078C295.146 441.319 293.902 439.18 292.34 437.163H292.355Z\" fill=\"#FFE200\"><\/path><path d=\"M284.149 439.043C283.558 438.391 282.921 437.815 282.648 437.481C282.056 436.829 281.146 436.253 280.236 436.055C279.584 435.919 278.932 435.995 278.355 436.51C277.703 437.102 276.732 437.678 276.672 438.725C276.414 440.803 277.976 441.516 279.402 442.82C280.509 443.867 281.616 444.898 282.784 445.884C284.801 447.643 286.561 449.524 287.926 451.799C288.639 453.104 289.23 454.469 289.61 456.031C289.746 456.683 289.867 457.26 290.838 457.396C292.855 457.533 294.023 455.182 293.963 453.438C293.902 451.678 292.992 449.737 292.082 448.432C289.67 444.853 286.879 441.925 284.149 439.074V439.043Z\" fill=\"#FFE200\"><\/path><path d=\"M281.95 446.84C280.782 445.869 279.675 444.762 278.507 443.715C277.4 442.668 276.292 441.576 275.064 440.53C274.093 439.756 272.728 438.968 271.621 438.77C271.166 438.71 270.453 438.573 270.256 439.165C270.059 439.878 270.514 441.121 270.65 441.895C269.543 441.637 266.873 440.075 267.268 442.411C267.723 445.338 271.044 447.158 273.441 448.265C277.278 449.949 280.069 452.042 282.086 454.378C284.104 456.714 285.272 459.383 285.863 462.174C285.924 462.568 286 463.023 286 463.403H286.515C287.107 463.403 287.562 463.205 287.941 462.948C288.336 462.629 288.593 462.174 288.791 461.522C288.851 461.067 288.927 460.612 288.927 460.02C288.791 457.032 288.017 454.499 286.849 452.406C285.621 450.267 283.922 448.432 281.965 446.809L281.95 446.84Z\" fill=\"#FFE200\"><\/path><path d=\"M350.933 230.7C350.28 229.017 348.855 229.138 347.414 229.654C345.396 232.703 343.455 236.024 341.62 239.543C339.739 243.183 337.979 247.021 336.478 250.995C336.159 251.844 334.976 251.389 335.31 250.54C336.811 246.505 338.632 242.607 340.512 238.967C342.393 235.327 344.41 231.944 346.488 228.82C347.717 226.863 348.248 224.785 347.596 222.51C347.277 221.342 346.488 220.235 345.184 220.038C344.926 220.553 344.592 221.084 344.274 221.539C342.196 224.209 340.315 226.939 338.419 229.669C336.599 232.46 334.84 235.266 333.217 238.193C332.762 238.967 331.594 238.39 332.11 237.541C333.732 234.614 335.553 231.747 337.373 228.956C339.253 226.165 341.21 223.435 343.227 220.766C344.077 219.719 344.592 218.551 344.653 217.323C344.79 214.79 341.862 211.347 339.906 214.077C337.494 217.459 335.098 221.039 332.747 224.603C330.214 228.501 327.741 232.475 325.33 236.57C324.875 237.344 323.767 236.707 324.222 235.918C326.695 231.823 329.167 227.788 331.7 223.951C334.172 220.113 336.645 216.413 339.178 212.894C339.633 212.241 339.951 211.589 339.891 210.679C339.891 210.163 339.754 209.708 339.496 209.314C338.723 208.207 337.085 207.949 336.25 208.996C333.52 212.241 331.184 215.502 328.909 218.748C326.573 222.131 324.359 225.634 322.023 229.214C321.568 229.988 320.461 229.275 320.976 228.562C323.312 224.922 325.527 221.479 327.863 218.035C330.274 214.517 332.807 211.149 335.659 207.691C336.372 206.781 336.174 205.552 335.795 204.642C335.598 204.385 335.401 204.127 335.28 203.93C334.051 202.564 332.944 202.428 331.836 203.732C327.544 208.161 322.736 213.227 318.246 220.644C317.791 221.418 316.684 220.781 317.2 219.992C321.75 212.454 326.634 207.373 330.926 202.822C331.836 201.912 332.686 201.321 332.489 199.895C332.352 198.848 331.836 198.014 331.124 197.362C329.698 196.194 329.046 195.997 327.741 197.362C325.527 199.637 323.388 202.307 321.234 205.234C319.096 208.222 316.942 211.407 314.727 214.79C314.591 215.047 314.409 215.305 313.878 214.987C313.362 214.668 313.484 214.395 313.681 214.077C315.895 210.694 318.034 207.448 320.188 204.521C322.402 201.533 324.617 198.803 326.816 196.528C327.923 195.36 328.575 194.45 327.665 192.887C325.982 190.218 324.541 191.917 323.054 193.6C320.84 196.073 318.701 198.606 316.623 201.336C314.545 204.127 312.528 207.054 310.571 210.179C310.374 210.436 310.253 210.694 309.661 210.376C309.146 210.057 309.343 209.784 309.464 209.526C311.481 206.341 313.499 203.353 315.577 200.623C317.715 197.832 319.869 195.223 322.084 192.751C323.13 191.583 323.646 190.734 323.707 190.021C323.843 189.429 323.509 188.853 322.994 188.261C321.765 186.896 318.959 184.03 317.533 187.215C316.168 190.203 314.212 192.554 311.937 194.298C309.404 196.255 306.476 197.544 303.412 198.196C296.132 199.758 288.715 196.634 282.936 192.478C277.021 188.185 271.166 182.134 267.586 175.247C264.462 169.271 262.839 162.309 264.522 155.681C253.526 160.231 243.318 162.507 233.504 162.764C226.224 162.962 217.578 161.991 210.101 159.579C200.151 156.394 187.804 156.394 177.854 159.579C170.377 161.991 161.792 162.962 154.451 162.764C144.637 162.507 134.429 160.231 123.433 155.681C125.116 162.309 123.493 169.271 120.445 175.247C116.804 182.134 110.95 188.185 105.034 192.478C99.2402 196.634 91.8384 199.758 84.5579 198.196C81.5092 197.544 78.5818 196.24 76.0337 194.298C73.7585 192.539 71.8019 190.203 70.4368 187.215C69.011 184.03 66.205 186.896 64.9764 188.261C64.4607 188.853 64.1271 189.429 64.2636 190.021C64.3242 190.734 64.8551 191.583 65.8865 192.751C68.101 195.223 70.2396 197.817 72.3934 200.623C74.4714 203.353 76.4887 206.341 78.506 209.526C78.6425 209.784 78.8245 210.042 78.3088 210.376C77.7173 210.694 77.596 210.436 77.3988 210.179C75.4421 207.054 73.4248 204.127 71.3469 201.336C69.2689 198.606 67.1151 196.073 64.9158 193.6C63.4142 191.917 61.9884 190.218 60.3048 192.887C59.3947 194.45 60.047 195.36 61.1542 196.528C63.3687 198.803 65.5832 201.533 67.7825 204.521C69.9211 207.448 72.1356 210.694 74.2894 214.077C74.4866 214.395 74.6079 214.668 74.0922 214.987C73.5765 215.305 73.3793 215.047 73.2428 214.79C71.0283 211.407 68.8897 208.222 66.7359 205.234C64.5973 202.307 62.4434 199.637 60.229 197.362C58.9245 195.997 58.2723 196.194 56.8466 197.362C56.1337 198.014 55.618 198.864 55.4815 199.895C55.2843 201.321 56.1337 201.912 57.0438 202.822C61.3362 207.373 66.205 212.439 70.7705 219.992C71.2862 220.766 70.179 221.418 69.7239 220.644C65.2343 213.227 60.4261 208.161 56.1337 203.732C55.0265 202.428 53.9192 202.564 52.6906 203.93C52.5541 204.127 52.3721 204.385 52.1749 204.642C51.7806 205.552 51.5834 206.781 52.3114 207.691C55.1781 211.134 57.7111 214.517 60.1076 218.035C62.4434 221.479 64.6579 224.922 66.9937 228.562C67.5094 229.275 66.4022 229.988 65.9472 229.214C63.6114 225.634 61.3969 222.131 59.0611 218.748C56.7859 215.502 54.4501 212.241 51.7199 208.996C50.8705 207.949 49.2476 208.222 48.474 209.314C48.2162 209.708 48.0797 210.163 48.0797 210.679C48.019 211.589 48.3375 212.241 48.7925 212.894C51.3255 216.413 53.7979 220.113 56.2702 223.951C58.8032 227.788 61.2755 231.823 63.7479 235.918C64.2029 236.692 63.0957 237.344 62.6406 236.57C60.229 232.475 57.7566 228.501 55.2236 224.603C52.8878 221.023 50.4762 217.444 48.0645 214.077C46.1079 211.347 43.1805 214.79 43.317 217.323C43.3777 218.551 43.9692 219.734 44.7428 220.766C46.7601 223.435 48.7167 226.165 50.5975 228.956C52.4783 231.747 54.2377 234.614 55.8607 237.541C56.3764 238.39 55.2085 238.967 54.7534 238.193C53.1305 235.266 51.371 232.475 49.5509 229.669C47.6701 226.939 45.7742 224.209 43.6962 221.539C43.3777 221.084 43.044 220.568 42.7861 220.038C41.4817 220.235 40.7082 221.342 40.3745 222.51C39.7223 224.785 40.238 226.863 41.4817 228.82C43.5597 231.944 45.577 235.327 47.4578 238.967C49.3386 242.607 51.1587 246.505 52.6603 250.54C52.9788 251.389 51.8109 251.844 51.4924 250.995C49.9908 247.021 48.2465 243.199 46.3505 239.543C44.5304 236.024 42.5738 232.718 40.5565 229.654C39.1307 229.138 37.6898 229.002 37.0376 230.7C35.7332 234.144 37.2348 237.132 38.6605 240.195C43.8024 251.45 49.0656 262.826 52.7058 275.566C69.4206 213.273 126.512 167.178 193.932 167.178C261.352 167.178 318.459 213.288 335.158 275.566C338.798 262.826 344.062 251.45 349.203 240.195C350.629 237.147 352.131 234.144 350.826 230.7H350.933Z\" fill=\"#FFE200\"><\/path><path d=\"M283.694 191.431C289.155 195.405 296.314 198.454 303.2 196.952C306.067 196.3 308.857 195.132 311.193 193.312C313.332 191.628 315.167 189.474 316.396 186.684C317.366 184.606 317.761 181.936 317.366 179.661C317.169 178.69 316.911 177.78 316.396 177.067C315.622 175.642 313.529 174.337 311.845 174.731C310.48 175.05 309.57 176.294 309.707 177.659C309.843 179.479 311.33 179.676 312.755 179.615C313.013 181.693 313.013 183.65 312.24 185.592C310.677 189.823 306.779 192.296 302.426 192.811C299.696 193.206 296.708 192.872 293.978 192.038C289.685 190.733 285.454 187.882 281.889 184.242C277.991 180.404 274.867 175.596 273.107 171.106C271.803 167.785 271.151 164.342 271.348 160.762C271.606 157.637 272.516 154.452 274.396 151.404C275.625 149.386 277.642 149.326 279.538 149.265C281.04 149.204 282.405 149.128 282.86 147.961C283.254 147.05 282.996 146.08 282.405 145.367C281.631 144.32 280.327 143.744 279.023 143.683C272.713 143.486 267.905 149.144 266.206 154.68C264.189 161.111 265.554 168.664 268.739 174.701C272.243 181.405 277.976 187.321 283.694 191.477V191.431Z\" fill=\"#FFE200\"><\/path><path d=\"M233.565 161.52C242.726 161.262 252.419 159.184 262.702 155.013C264.007 154.498 265.175 153.648 265.766 152.283C266.873 149.75 268.496 147.399 270.574 145.579C253.48 152.147 230.774 155.984 207.113 157.031C215.637 160.216 224.343 161.778 233.58 161.52H233.565Z\" fill=\"#FFE200\"><\/path><path d=\"M76.8527 193.312C79.1885 195.132 81.9945 196.3 84.8461 196.952C91.7322 198.454 98.8913 195.39 104.352 191.431C110.07 187.275 115.803 181.36 119.307 174.656C122.492 168.604 123.918 161.066 121.84 154.635C120.156 149.114 115.333 143.456 109.023 143.638C107.795 143.699 106.414 144.29 105.641 145.322C105.049 146.035 104.792 147.005 105.186 147.915C105.641 149.083 107.006 149.144 108.508 149.22C110.388 149.28 112.406 149.356 113.649 151.358C115.53 154.407 116.44 157.607 116.698 160.717C116.895 164.296 116.243 167.74 114.939 171.061C113.255 175.551 110.055 180.359 106.157 184.196C102.577 187.837 98.3605 190.703 94.068 191.993C91.3378 192.842 88.3498 193.161 85.6196 192.766C81.2665 192.25 77.3684 189.778 75.8061 185.546C75.0933 183.59 75.0326 181.648 75.2904 179.57C76.7162 179.631 78.2178 179.434 78.3391 177.614C78.4756 176.249 77.5656 175.02 76.2005 174.686C74.5169 174.292 72.4237 175.596 71.6502 177.022C71.1345 177.735 70.8766 178.645 70.6795 179.616C70.2851 181.891 70.6795 184.56 71.6502 186.638C72.8788 189.429 74.7141 191.583 76.8527 193.267V193.312Z\" fill=\"#FFE200\"><\/path><path d=\"M125.298 155.014H125.359C135.627 159.17 145.32 161.263 154.496 161.521C155.8 161.657 161.716 161.384 164.643 160.095C167.828 158.73 165.493 155.939 163.02 155.666C146.048 153.846 130.182 150.464 117.502 145.595C119.58 147.415 121.203 149.751 122.31 152.299C122.902 153.603 123.994 154.513 125.298 155.029V155.014Z\" fill=\"#FFE200\"><\/path><path d=\"M287.987 109.753C286.561 109.753 285.257 110.345 284.286 111.255C283.376 112.226 282.724 113.53 282.724 114.956C282.724 117.883 285.135 120.219 287.987 120.219C289.488 120.219 290.778 119.628 291.688 118.718C292.658 117.747 293.25 116.442 293.25 114.941C293.25 112.074 290.914 109.738 287.987 109.738V109.753Z\" fill=\"#FFE200\"><\/path><path d=\"M276.156 141.363C277.46 141.818 278.689 141.423 279.402 140.65C279.66 140.392 279.918 140.058 280.054 139.679C280.115 139.361 280.191 138.966 280.115 138.572C279.978 137.601 279.144 136.615 277.324 136.039C250.204 126.878 222.114 122.251 194.023 122.251C165.933 122.251 137.842 126.862 110.722 136.039C108.902 136.63 108.053 137.601 107.931 138.572C107.871 138.966 107.931 139.345 107.992 139.679C108.129 140.073 108.386 140.392 108.644 140.65C109.357 141.423 110.601 141.818 111.89 141.363C141.346 132.065 167.677 127.378 194.008 127.378C220.339 127.378 246.67 132.065 276.126 141.363H276.156Z\" fill=\"#FFE200\"><\/path><path d=\"M188.957 100.077C188.957 98.5751 187.728 97.4072 186.227 97.4072C184.725 97.4072 183.557 98.5751 183.557 100.077C183.557 101.578 184.725 102.807 186.227 102.807C187.728 102.807 188.957 101.578 188.957 100.077Z\" fill=\"#FFE200\"><\/path><path d=\"M194.038 83.877C195.858 83.877 197.36 82.3754 197.36 80.5552C197.36 78.7351 195.858 77.1729 194.038 77.1729C192.218 77.1729 190.716 78.6745 190.716 80.5552C190.716 82.436 192.218 83.877 194.038 83.877Z\" fill=\"#FFE200\"><\/path><path d=\"M198.133 60.2155C198.133 57.9404 196.313 56.0596 194.038 56.0596C191.763 56.0596 189.943 57.9404 189.943 60.2155C189.943 62.4907 191.763 64.3108 194.038 64.3108C196.313 64.3108 198.133 62.4907 198.133 60.2155Z\" fill=\"#FFE200\"><\/path><path d=\"M197.8 49.75C197.8 47.672 196.116 45.9126 194.023 45.9126C191.93 45.9126 190.246 47.672 190.246 49.75C190.246 51.828 191.93 53.5268 194.023 53.5268C196.116 53.5268 197.8 51.8432 197.8 49.75Z\" fill=\"#FFE200\"><\/path><path d=\"M190.064 70.8784C190.064 73.017 191.884 74.8523 194.038 74.8523C196.192 74.8523 197.997 73.0322 197.997 70.8784C197.997 68.7245 196.177 66.8438 194.038 66.8438C191.899 66.8438 190.064 68.6639 190.064 70.8784Z\" fill=\"#FFE200\"><\/path><path d=\"M194.038 31.6701C198.528 31.6701 202.168 27.9692 202.168 23.4796C202.168 18.99 198.528 15.2891 194.038 15.2891C189.548 15.2891 185.908 18.9293 185.908 23.4796C185.908 28.0299 189.548 31.6701 194.038 31.6701Z\" fill=\"#FFE200\"><\/path><path d=\"M253.92 86.1522C253.92 88.1088 255.482 89.7318 257.424 89.7318C258.395 89.7318 259.305 89.3374 259.957 88.6852C260.609 88.033 261.003 87.1229 261.003 86.1522C261.003 84.1956 259.38 82.6333 257.424 82.6333C255.467 82.6333 253.92 84.1956 253.92 86.1522Z\" fill=\"#FFE200\"><\/path><path d=\"M266.464 72.6985C267.571 72.6985 268.542 72.2435 269.194 71.5913C269.907 70.8784 270.362 69.9077 270.362 68.8004C270.362 66.6618 268.602 64.9023 266.464 64.9023C265.417 64.9023 264.446 65.3574 263.734 66.0703C263.021 66.7831 262.566 67.7539 262.566 68.8004C262.566 70.9391 264.325 72.6985 266.464 72.6985Z\" fill=\"#FFE200\"><\/path><path d=\"M258.925 77.9623C258.925 79.9796 260.609 81.6632 262.702 81.6632C263.749 81.6632 264.659 81.2689 265.296 80.556C266.009 79.9038 266.403 78.9937 266.403 77.9623C266.403 75.8843 264.719 74.1855 262.702 74.1855C261.656 74.1855 260.685 74.5799 260.033 75.2928C259.32 75.945 258.925 76.9157 258.925 77.9623Z\" fill=\"#FFE200\"><\/path><path d=\"M267.177 63.3405C268.284 63.3405 269.255 62.8855 269.968 62.2333C270.681 61.5204 271.075 60.5496 271.075 59.4424C271.075 57.3038 269.315 55.605 267.177 55.605C266.13 55.605 265.159 55.9993 264.447 56.7122C263.734 57.4251 263.339 58.3958 263.339 59.4424C263.339 61.581 265.099 63.3405 267.177 63.3405Z\" fill=\"#FFE200\"><\/path><path d=\"M266.464 53.5113C267.571 53.5113 268.542 53.0563 269.255 52.3434C270.028 51.6305 270.423 50.6598 270.423 49.5525C270.423 47.3381 268.663 45.5786 266.464 45.5786C265.357 45.5786 264.386 46.0336 263.673 46.7465C262.96 47.4594 262.505 48.4301 262.505 49.5374C262.505 51.7519 264.264 53.5113 266.479 53.5113H266.464Z\" fill=\"#FFE200\"><\/path><path d=\"M267.374 43.3041C269.588 43.3041 271.348 41.5447 271.348 39.3454C271.348 37.146 269.588 35.4473 267.374 35.4473C265.159 35.4473 263.476 37.2067 263.476 39.3454C263.476 41.484 265.235 43.3041 267.374 43.3041Z\" fill=\"#FFE200\"><\/path><path d=\"M257.5 40.5133C259.638 40.5133 261.398 38.6932 261.398 36.5394C261.398 34.3856 259.638 32.5654 257.5 32.5654C255.361 32.5654 253.526 34.3856 253.526 36.5394C253.526 38.6932 255.285 40.5133 257.5 40.5133Z\" fill=\"#FFE200\"><\/path><path d=\"M248.581 36.9938C249.628 36.9938 250.598 36.5388 251.311 35.8259C252.024 35.1737 252.479 34.203 252.479 33.0957C252.479 30.9571 250.72 29.2583 248.581 29.2583C247.534 29.2583 246.564 29.6527 245.851 30.3655C245.138 31.0784 244.683 32.0492 244.683 33.0957C244.683 35.2344 246.442 36.9938 248.581 36.9938Z\" fill=\"#FFE200\"><\/path><path d=\"M238.571 35.4321C239.617 35.4321 240.527 34.9771 241.24 34.3249C241.892 33.612 242.287 32.7019 242.287 31.716C242.287 29.6381 240.664 28.0151 238.586 28.0151C237.615 28.0151 236.629 28.4095 235.992 29.0617C235.34 29.7746 234.885 30.6846 234.885 31.7312C234.885 33.7485 236.568 35.4321 238.586 35.4321H238.571Z\" fill=\"#FFE200\"><\/path><path d=\"M229.212 34.0669C230.259 34.0669 231.169 33.6118 231.821 32.9596C232.534 32.3074 232.928 31.3367 232.928 30.366C232.928 28.288 231.244 26.665 229.227 26.665C228.181 26.665 227.271 27.0594 226.633 27.7116C225.921 28.4245 225.526 29.3346 225.526 30.3811C225.526 32.3984 227.21 34.082 229.227 34.082L229.212 34.0669Z\" fill=\"#FFE200\"><\/path><path d=\"M220.036 32.5803C221.006 32.5803 221.916 32.1859 222.569 31.5337C223.221 30.8208 223.676 29.9108 223.676 28.94C223.676 26.9227 221.992 25.2998 220.036 25.2998C218.989 25.2998 218.079 25.6942 217.442 26.3464C216.79 27.0593 216.335 27.9693 216.335 28.9552C216.335 30.9725 218.018 32.5955 220.036 32.5955V32.5803Z\" fill=\"#FFE200\"><\/path><path d=\"M211.39 31.5336C213.271 31.5336 214.833 29.9713 214.833 28.0905C214.833 26.2097 213.271 24.6475 211.39 24.6475C209.509 24.6475 207.886 26.2097 207.886 28.0905C207.886 29.9713 209.448 31.5336 211.39 31.5336Z\" fill=\"#FFE200\"><\/path><path d=\"M276.747 47.1412C277.855 47.1412 278.886 46.6862 279.614 45.9126H279.675C280.388 45.1998 280.843 44.1532 280.843 43.046C280.843 40.7708 279.023 38.9507 276.747 38.9507C275.64 38.9507 274.609 39.4057 273.881 40.1186C273.107 40.8921 272.652 41.878 272.652 43.046C272.652 45.2604 274.472 47.1412 276.747 47.1412Z\" fill=\"#FFE200\"><\/path><path d=\"M286.106 48.9005C287.213 48.9005 288.245 48.3848 288.973 47.6719C289.746 46.959 290.201 45.9125 290.201 44.8052C290.201 42.5301 288.32 40.71 286.106 40.71C284.938 40.71 283.967 41.165 283.179 41.8779C282.466 42.6514 282.011 43.6373 282.011 44.8052C282.011 47.0197 283.831 48.9005 286.106 48.9005Z\" fill=\"#FFE200\"><\/path><path d=\"M296.056 52.2831C297.36 52.2831 298.589 51.6915 299.438 50.8573C300.288 50.0079 300.803 48.84 300.803 47.5356C300.803 44.9419 298.665 42.7881 296.056 42.7881C294.751 42.7881 293.584 43.3038 292.734 44.1532C291.885 45.0632 291.308 46.2311 291.308 47.5356C291.308 50.1292 293.447 52.2831 296.056 52.2831Z\" fill=\"#FFE200\"><\/path><path d=\"M305.869 57.8642C307.235 57.8642 308.463 57.2726 309.388 56.3626C310.314 55.4525 310.89 54.2239 310.89 52.8588C310.89 50.1287 308.615 47.8535 305.885 47.8535C304.52 47.8535 303.291 48.4451 302.366 49.3551C301.456 50.2652 300.864 51.4938 300.864 52.874C300.864 55.6042 303.139 57.8793 305.869 57.8793V57.8642Z\" fill=\"#FFE200\"><\/path><path d=\"M309.054 62.0354C309.054 64.9021 311.39 67.2379 314.196 67.2379C317.002 67.2379 319.399 64.9021 319.399 62.0354C319.399 59.1687 317.063 56.8936 314.196 56.8936C311.33 56.8936 309.054 59.2294 309.054 62.0354Z\" fill=\"#FFE200\"><\/path><path d=\"M313.878 73.8056C313.878 76.5358 316.092 78.811 318.883 78.811C321.674 78.811 323.828 76.5358 323.828 73.8056C323.828 71.0754 321.613 68.8003 318.883 68.8003C316.153 68.8003 313.878 71.0754 313.878 73.8056Z\" fill=\"#FFE200\"><\/path><path d=\"M322.842 85.4397C322.842 83.028 320.885 81.0107 318.489 81.0107C316.092 81.0107 314.06 83.028 314.06 85.4397C314.06 87.8514 316.077 89.8687 318.489 89.8687C320.901 89.8687 322.842 87.8514 322.842 85.4397Z\" fill=\"#FFE200\"><\/path><path d=\"M319.46 94.9346C319.46 92.8566 317.776 91.0972 315.622 91.0972C313.468 91.0972 311.785 92.8566 311.785 94.9346C311.785 97.0126 313.544 98.772 315.622 98.772C317.7 98.772 319.46 97.0884 319.46 94.9346Z\" fill=\"#FFE200\"><\/path><path d=\"M311.663 107.357C313.802 107.357 315.562 105.598 315.562 103.52C315.562 101.442 313.802 99.6216 311.663 99.6216C309.525 99.6216 307.826 101.381 307.826 103.52C307.826 105.658 309.585 107.357 311.663 107.357Z\" fill=\"#FFE200\"><\/path><path d=\"M272.258 64.7055C271.864 68.4064 270.953 71.986 269.528 75.2319C267.965 78.7356 266.145 82.1938 264.067 85.3032C262.111 88.2912 259.911 91.0214 257.697 93.0994C257.303 93.5544 257.045 93.8729 257.105 94.2673C257.166 94.7223 257.5 95.3139 258.152 96.1481C258.349 96.3453 258.546 96.5425 258.743 96.6638C259.456 97.1188 260.306 96.9823 261.276 96.4059C262.384 95.6931 263.552 94.4493 264.72 92.9629C267.192 89.7777 269.664 85.288 271.484 81.3293C273.82 76.3846 275.064 72.0922 275.64 67.6784C276.232 62.6124 275.959 57.5312 275.64 52.4652C275.443 50.3266 275.322 47.5812 273.107 47.2627C272.516 47.202 272.258 47.7784 272.137 48.5671C272 49.6137 272.137 50.9788 272.273 51.8888C272.728 56.1206 272.789 60.4737 272.273 64.7055H272.258Z\" fill=\"#FFE200\"><\/path><path d=\"M258.152 44.6082C257.56 43.956 256.923 43.501 256.195 43.501C254.633 43.5616 254.436 44.4717 254.314 45.3818C254.117 46.7469 254.967 47.8541 255.361 49.2799C256.468 53.0566 256.923 56.7575 256.787 60.4584C256.59 64.1593 255.877 67.7996 254.572 71.455C253.859 73.533 252.949 75.3531 251.903 77.1125C250.796 78.872 249.628 80.5556 248.46 82.2544C247.352 83.756 247.034 84.666 247.231 85.1211C247.428 85.5761 248.081 85.834 249.051 86.0918C251.842 86.744 252.949 84.8632 254.117 82.8459C254.436 82.3302 254.769 81.7387 255.164 81.1623C258.743 75.8991 260.821 70.4994 261.595 65.0997C262.444 59.3057 261.853 53.5268 260.033 48.0664C259.714 47.0199 259.062 45.5941 258.152 44.6234V44.6082Z\" fill=\"#FFE200\"><\/path><path d=\"M130.637 89.7318C132.594 89.7318 134.156 88.1088 134.156 86.1522C134.156 84.1956 132.594 82.6333 130.637 82.6333C128.681 82.6333 127.058 84.1956 127.058 86.1522C127.058 87.1229 127.452 88.033 128.104 88.6852C128.756 89.3374 129.666 89.7318 130.637 89.7318Z\" fill=\"#FFE200\"><\/path><path d=\"M121.597 72.6985C123.736 72.6985 125.495 70.9391 125.495 68.8004C125.495 67.7539 125.04 66.7831 124.327 66.0703C123.615 65.3574 122.644 64.9023 121.597 64.9023C119.459 64.9023 117.699 66.6618 117.699 68.8004C117.699 69.9077 118.154 70.8784 118.867 71.5913C119.519 72.2435 120.49 72.6985 121.597 72.6985Z\" fill=\"#FFE200\"><\/path><path d=\"M125.374 81.6632C127.452 81.6632 129.151 79.9796 129.151 77.9623C129.151 76.9157 128.757 75.945 128.044 75.2928C127.391 74.5799 126.421 74.1855 125.374 74.1855C123.357 74.1855 121.673 75.8692 121.673 77.9623C121.673 79.0089 122.068 79.9189 122.78 80.556C123.433 81.2689 124.343 81.6632 125.374 81.6632Z\" fill=\"#FFE200\"><\/path><path d=\"M124.722 59.4268C124.722 58.3802 124.328 57.4095 123.615 56.6966C122.902 55.9837 121.931 55.5894 120.885 55.5894C118.746 55.5894 116.986 57.273 116.986 59.4268C116.986 60.534 117.381 61.5047 118.094 62.2176C118.807 62.8698 119.777 63.3249 120.885 63.3249C122.963 63.3249 124.722 61.5654 124.722 59.4268Z\" fill=\"#FFE200\"><\/path><path d=\"M121.597 45.5786C119.383 45.5786 117.623 47.3381 117.623 49.5525C117.623 50.6598 118.018 51.6305 118.791 52.3434C119.504 53.0563 120.475 53.5113 121.582 53.5113C123.797 53.5113 125.541 51.7519 125.541 49.5374C125.541 48.4301 125.086 47.4594 124.373 46.7465C123.66 46.0336 122.689 45.5786 121.582 45.5786H121.597Z\" fill=\"#FFE200\"><\/path><path d=\"M120.687 43.3041C122.826 43.3041 124.585 41.5447 124.585 39.3454C124.585 37.146 122.826 35.4473 120.687 35.4473C118.549 35.4473 116.713 37.2067 116.713 39.3454C116.713 41.484 118.473 43.3041 120.687 43.3041Z\" fill=\"#FFE200\"><\/path><path d=\"M130.562 40.5133C132.776 40.5133 134.52 38.6932 134.52 36.5394C134.52 34.3856 132.761 32.5654 130.562 32.5654C128.362 32.5654 126.663 34.3856 126.663 36.5394C126.663 38.6932 128.423 40.5133 130.562 40.5133Z\" fill=\"#FFE200\"><\/path><path d=\"M139.48 36.9938C141.619 36.9938 143.378 35.2344 143.378 33.0957C143.378 32.0492 142.923 31.0784 142.21 30.3655C141.497 29.6527 140.527 29.2583 139.48 29.2583C137.341 29.2583 135.582 30.9419 135.582 33.0957C135.582 34.203 136.037 35.1737 136.75 35.8259C137.463 36.5388 138.434 36.9938 139.48 36.9938Z\" fill=\"#FFE200\"><\/path><path d=\"M149.491 35.4321C151.508 35.4321 153.192 33.7485 153.192 31.7312C153.192 30.6846 152.737 29.7746 152.084 29.0617C151.432 28.4095 150.461 28.0151 149.491 28.0151C147.413 28.0151 145.79 29.6381 145.79 31.716C145.79 32.6868 146.184 33.5968 146.897 34.3249C147.549 34.9771 148.459 35.4321 149.491 35.4321Z\" fill=\"#FFE200\"><\/path><path d=\"M158.849 34.0664C160.866 34.0664 162.55 32.3828 162.55 30.3655C162.55 29.3189 162.156 28.4089 161.443 27.696C160.791 27.0438 159.881 26.6494 158.849 26.6494C156.832 26.6494 155.148 28.2724 155.148 30.3503C155.148 31.3211 155.543 32.307 156.255 32.944C156.908 33.5962 157.818 34.0512 158.849 34.0512V34.0664Z\" fill=\"#FFE200\"><\/path><path d=\"M168.026 32.5798C170.043 32.5798 171.727 30.9569 171.727 28.9396C171.727 27.9689 171.272 27.0588 170.619 26.3307C169.967 25.6785 169.057 25.2842 168.01 25.2842C166.054 25.2842 164.37 26.9071 164.37 28.9244C164.37 29.8952 164.825 30.8052 165.477 31.5181C166.13 32.1703 167.04 32.5647 168.01 32.5647L168.026 32.5798Z\" fill=\"#FFE200\"><\/path><path d=\"M176.671 31.5336C178.628 31.5336 180.19 29.9713 180.19 28.0905C180.19 26.2097 178.628 24.6475 176.671 24.6475C174.714 24.6475 173.228 26.2097 173.228 28.0905C173.228 29.9713 174.79 31.5336 176.671 31.5336Z\" fill=\"#FFE200\"><\/path><path d=\"M108.462 45.9126C109.175 46.6862 110.222 47.1412 111.329 47.1412C113.604 47.1412 115.424 45.2604 115.424 43.046C115.424 41.878 114.969 40.9073 114.195 40.1186C113.483 39.4057 112.436 38.9507 111.329 38.9507C109.054 38.9507 107.234 40.7708 107.234 43.046C107.234 44.1532 107.689 45.1846 108.401 45.9126H108.462Z\" fill=\"#FFE200\"><\/path><path d=\"M101.955 48.9005C104.23 48.9005 106.05 47.0197 106.05 44.8052C106.05 43.6373 105.595 42.6666 104.882 41.8779C104.109 41.165 103.123 40.71 101.955 40.71C99.7407 40.71 97.8599 42.5301 97.8599 44.8052C97.8599 45.9125 98.3149 46.9439 99.0884 47.6719C99.8013 48.3848 100.848 48.9005 101.955 48.9005Z\" fill=\"#FFE200\"><\/path><path d=\"M92.0052 52.2831C94.5988 52.2831 96.7527 50.1444 96.7527 47.5356C96.7527 46.2311 96.1611 45.0632 95.3269 44.1532C94.4775 43.3038 93.3096 42.7881 92.0052 42.7881C89.4115 42.7881 87.2577 44.9267 87.2577 47.5356C87.2577 48.84 87.7734 50.0079 88.6228 50.8573C89.4722 51.7067 90.7008 52.2831 92.0052 52.2831Z\" fill=\"#FFE200\"><\/path><path d=\"M82.1918 57.8647C84.9219 57.8647 87.1971 55.5895 87.1971 52.8594C87.1971 51.4943 86.6056 50.2505 85.6955 49.3405C84.7854 48.4304 83.5569 47.8389 82.1766 47.8389C79.4464 47.8389 77.1713 50.114 77.1713 52.8442C77.1713 54.2093 77.7628 55.4379 78.6729 56.3479C79.5829 57.258 80.8115 57.8495 82.1766 57.8495L82.1918 57.8647Z\" fill=\"#FFE200\"><\/path><path d=\"M73.8646 67.2379C76.6555 67.2379 79.0065 64.9021 79.0065 62.0354C79.0065 59.1687 76.6706 56.8936 73.8646 56.8936C71.0586 56.8936 68.6621 59.2294 68.6621 62.0354C68.6621 64.8414 70.9979 67.2379 73.8646 67.2379Z\" fill=\"#FFE200\"><\/path><path d=\"M69.1931 78.811C71.9839 78.811 74.1984 76.5358 74.1984 73.8056C74.1984 71.0754 71.9839 68.8003 69.1931 68.8003C66.4022 68.8003 64.2484 71.0754 64.2484 73.8056C64.2484 76.5358 66.4629 78.811 69.1931 78.811Z\" fill=\"#FFE200\"><\/path><path d=\"M74.0012 85.4397C74.0012 83.028 71.9839 81.0107 69.5722 81.0107C67.1606 81.0107 65.2191 83.028 65.2191 85.4397C65.2191 87.8514 67.1758 89.8687 69.5722 89.8687C71.9687 89.8687 74.0012 87.8514 74.0012 85.4397Z\" fill=\"#FFE200\"><\/path><path d=\"M72.439 98.772C74.517 98.772 76.2764 97.0884 76.2764 94.9346C76.2764 92.7808 74.517 91.0972 72.439 91.0972C70.361 91.0972 68.6016 92.8566 68.6016 94.9346C68.6016 97.0126 70.2852 98.772 72.439 98.772Z\" fill=\"#FFE200\"><\/path><path d=\"M72.4995 103.52C72.4995 105.598 74.259 107.357 76.3976 107.357C78.5362 107.357 80.235 105.598 80.235 103.52C80.235 101.442 78.4756 99.6216 76.3976 99.6216C74.3196 99.6216 72.4995 101.381 72.4995 103.52Z\" fill=\"#FFE200\"><\/path><path d=\"M112.421 52.4797C112.102 57.5457 111.829 62.6269 112.421 67.6929C113.012 72.1219 114.241 76.3992 116.577 81.3438C118.397 85.3026 120.869 89.7922 123.342 92.9774C124.51 94.479 125.677 95.7076 126.785 96.4205C127.755 97.012 128.605 97.1334 129.318 96.6783C129.515 96.5418 129.712 96.3598 129.909 96.1626C130.561 95.3133 130.88 94.7369 130.956 94.2819C131.016 93.8875 130.759 93.569 130.364 93.1139C128.15 91.036 125.935 88.3058 123.994 85.3178C121.916 82.1932 120.096 78.7502 118.533 75.2464C117.108 72.0005 116.198 68.421 115.803 64.7201C115.288 60.4883 115.348 56.1352 115.803 51.9034C115.94 50.9933 116.061 49.6282 115.94 48.5816C115.803 47.8081 115.545 47.2166 114.969 47.2772C112.755 47.5958 112.633 50.3411 112.436 52.4797H112.421Z\" fill=\"#FFE200\"><\/path><path d=\"M132.912 81.1472C133.307 81.7387 133.625 82.3151 133.959 82.8308C135.127 84.8481 136.234 86.7289 139.025 86.0767C139.996 85.8188 140.648 85.561 140.845 85.1059C141.042 84.6509 140.709 83.7409 139.617 82.2393C138.449 80.5556 137.281 78.8569 136.234 77.0974C135.127 75.338 134.217 73.5178 133.504 71.4399C132.2 67.7996 131.487 64.1594 131.29 60.4433C131.153 56.7424 131.608 53.0263 132.715 49.2647C133.11 47.839 133.944 46.7317 133.762 45.3666C133.625 44.4566 133.443 43.5465 131.881 43.4858C131.168 43.4858 130.516 43.9409 129.924 44.5931C129.014 45.5638 128.362 47.0047 128.044 48.0361C126.224 53.4965 125.632 59.2906 126.481 65.0694C127.255 70.4691 129.348 75.8688 132.912 81.132V81.1472Z\" fill=\"#FFE200\"><\/path><path d=\"M78.4149 68.4059C73.8039 74.6549 74.259 82.6483 76.2004 89.7923C77.884 95.7683 80.9479 101.502 84.6488 106.765C85.0432 107.281 85.5589 107.478 86.1504 107.356C87.197 107.099 88.2891 107.038 89.3356 107.159C90.185 107.296 90.3822 106.386 89.9878 105.794C87.652 102.67 85.5589 99.2872 83.9359 95.7835C81.9793 91.6882 80.69 87.3958 80.2957 83.0427C79.6435 75.3072 82.5102 67.8295 87.7734 61.6562C84.5275 63.082 81.0086 64.8415 78.4149 68.421V68.4059Z\" fill=\"#FFE200\"><\/path><path d=\"M298.134 54.9526C297.224 54.4369 296.314 53.9818 295.343 53.5268C293.978 52.8746 292.021 54.4369 293.523 55.4834C294.691 56.3328 295.798 57.2429 296.905 58.2136C298.407 59.5787 301.258 56.7879 298.134 54.9677V54.9526Z\" fill=\"#FFE200\"><\/path><path d=\"M304.11 95.7842C301.896 100.592 298.771 105.082 295.525 109.117C294.297 110.618 293.902 112.241 294.16 113.409C294.357 114.001 294.752 114.516 295.389 114.577C296.299 114.577 297.603 113.925 299.09 112.165C304.747 105.598 309.555 97.9228 311.83 89.7929C313.651 83.0888 313.711 76.2027 310.92 69.4986C309.04 65.009 306.309 61.3687 303.048 58.4413C301.168 56.8791 299.014 60.125 300.318 61.6872C305.581 67.8605 308.387 75.3381 307.735 83.013C307.341 87.3661 306.052 91.6586 304.095 95.7538L304.11 95.7842Z\" fill=\"#FFE200\"><\/path><path d=\"M194.038 459.52C274.533 459.52 340.209 393.844 340.209 313.288C340.209 232.733 274.533 167.178 194.038 167.178C113.543 167.178 47.8521 232.854 47.8521 313.288C47.8521 393.723 113.528 459.52 194.023 459.52H194.038Z\" fill=\"#ED1B24\"><\/path><path d=\"M194.038 113.924C193.977 114.637 191.702 117.504 191.05 117.822H193.067C193.522 117.504 193.841 117.17 194.038 116.715C194.235 117.17 194.554 117.489 195.009 117.822H197.026C196.374 117.504 194.099 114.637 194.038 113.924Z\" fill=\"black\"><\/path><path d=\"M194.038 103.064C193.977 103.717 191.702 106.052 191.05 106.31H193.067C193.522 106.052 193.841 105.795 194.038 105.4C194.235 105.795 194.554 106.052 195.009 106.31H197.026C196.374 106.052 194.099 103.717 194.038 103.064Z\" fill=\"black\"><\/path><path d=\"M156.255 119.127L155.345 119.9C151.189 123.677 146.048 124.587 139.935 122.827L138.706 122.433L139.753 121.72C142.089 119.961 144.561 118.929 147.094 118.535C149.627 118.08 152.297 118.217 155.027 118.854L156.255 119.111V119.127Z\" fill=\"black\"><\/path><path d=\"M169.846 104.884C169.846 105.4 167.828 107.675 167.252 108.009L169.269 107.751C169.664 107.493 169.921 107.235 170.179 106.902C170.437 107.159 170.832 107.417 171.226 107.554L173.243 107.357C172.591 107.22 170.058 105.4 169.861 104.884H169.846Z\" fill=\"black\"><\/path><path d=\"M144.607 107.873C144.667 108.464 142.923 111.118 142.392 111.513L144.349 111.058C144.743 110.739 145.001 110.406 145.123 110.011C145.441 110.269 145.835 110.466 146.29 110.603L148.247 110.148C147.595 110.087 144.804 108.388 144.607 107.873Z\" fill=\"black\"><\/path><path d=\"M117.563 114.956C117.623 115.547 116.137 118.338 115.606 118.732L117.487 118.141C117.805 117.822 118.078 117.489 118.2 117.094C118.518 117.352 118.913 117.489 119.368 117.61L121.324 117.018C120.672 116.958 117.805 115.456 117.548 114.94L117.563 114.956Z\" fill=\"black\"><\/path><path d=\"M153.449 119.839C151.311 119.445 149.293 119.445 147.337 119.779C145.32 120.097 143.439 120.825 141.619 121.993C146.169 123.04 150.143 122.312 153.449 119.855V119.839Z\" fill=\"#ED1B24\"><\/path><path d=\"M231.806 119.127L232.716 119.9C236.948 123.677 242.013 124.587 248.126 122.827L249.355 122.433L248.308 121.72C245.972 119.961 243.5 118.929 240.967 118.535C238.434 118.08 235.764 118.217 233.034 118.854L231.806 119.111V119.127Z\" fill=\"black\"><\/path><path d=\"M218.215 104.884C218.215 105.4 220.233 107.675 220.809 108.009L218.792 107.751C218.397 107.493 218.14 107.235 217.882 106.902C217.624 107.159 217.23 107.417 216.835 107.554L214.818 107.357C215.47 107.22 218.003 105.4 218.2 104.884H218.215Z\" fill=\"black\"><\/path><path d=\"M243.454 107.873C243.394 108.464 245.138 111.118 245.669 111.513L243.712 111.058C243.394 110.739 243.121 110.406 242.939 110.011C242.62 110.269 242.226 110.466 241.771 110.603L239.814 110.148C240.466 110.087 243.257 108.388 243.454 107.873Z\" fill=\"black\"><\/path><path d=\"M270.498 114.956C270.438 115.547 271.924 118.338 272.455 118.732L270.574 118.141C270.256 117.822 269.983 117.489 269.861 117.094C269.543 117.352 269.148 117.489 268.693 117.61L266.737 117.018C267.389 116.958 270.256 115.456 270.514 114.94L270.498 114.956Z\" fill=\"black\"><\/path><path d=\"M234.612 119.839C236.75 119.445 238.768 119.445 240.724 119.779C242.741 120.097 244.622 120.825 246.442 121.993C241.892 123.04 237.918 122.312 234.612 119.855V119.839Z\" fill=\"#ED1B24\"><\/path><path d=\"M247.095 93.4331C246.898 99.1513 247.034 97.6649 252.1 100.319C249.688 99.6064 247.292 99.1513 245.138 100.577C243.97 98.2413 241.695 97.4525 239.223 96.8762C244.941 97.0733 244.365 98.4384 247.095 93.4331Z\" fill=\"black\"><\/path><path d=\"M140.967 93.4331C141.164 99.1513 141.027 97.6649 135.961 100.319C138.373 99.6064 140.769 99.1513 142.923 100.577C144.091 98.2413 146.366 97.4525 148.839 96.8762C143.12 97.0733 143.697 98.4384 140.967 93.4331Z\" fill=\"black\"><\/path><path d=\"M148.581 63.0675C146.048 66.1921 142.074 66.7078 140.845 70.4845C140.254 72.1681 141.695 73.5484 143.06 73.9276C144.622 74.4433 145.396 72.1075 147.094 71.5159C146.381 72.3653 145.866 73.5332 146.321 74.1854C146.836 73.4119 147.291 72.881 148.596 72.5625C146.518 75.5505 147.428 76.0814 148.99 75.8842C149.9 75.8235 150.492 74.9742 151.584 74.4585C151.523 74.7163 148.657 77.3858 150.992 77.583C151.508 77.6437 153.207 76.8701 153.662 76.4151C153.525 77.4617 151.902 77.8408 153.465 78.6902C154.314 79.2059 155.346 78.2352 156.134 77.9167C154.253 80.5104 155.164 81.0412 156.331 80.6469C157.181 80.3283 157.894 79.4183 159.259 79.4183C158.485 80.0705 157.833 80.1918 157.833 81.0412C157.894 83.7714 160.427 83.5742 161.868 83.3164C160.821 84.0899 161.868 87.2145 162.323 87.2903C164.992 87.6088 165.644 86.8353 168.117 86.1224C171.696 85.0151 172.409 80.207 172.348 74.0338C172.288 68.6341 171.636 63.113 170.726 61.4143C169.618 61.0957 167.025 62.5822 167.025 64.1444C166.827 63.4316 166.372 62.84 165.978 62.84C165.129 62.9007 164.294 64.1444 163.566 64.463C160.958 65.6309 163.172 62.1271 163.172 61.93C159.532 61.7934 159.532 66.9353 159.532 61.6114C156.999 61.2171 155.3 66.4196 155.497 61.8693C153.874 60.4435 152.631 61.8086 151.66 62.9765C150.947 63.8866 150.295 64.6601 150.234 64.2809C150.098 63.5074 150.553 62.1423 150.431 61.7479C150.173 61.0351 148.808 62.8552 148.611 63.113L148.581 63.0675Z\" fill=\"#ED1B24\"><\/path><path d=\"M220.233 59.0472C220.551 61.383 220.233 62.4903 219.914 63.734C218.231 69.1337 220.688 74.1997 220.506 79.6601C222.584 80.8887 222.387 78.8107 223.039 77.1271C224.267 71.7274 229.348 85.4541 235.127 79.6601C237.008 77.1878 240.588 74.5182 244.289 74.8519C249.173 77.84 247.019 63.9919 245.654 63.279C245.138 63.0211 244.031 63.6734 244.031 63.4762C243.894 62.3083 243.439 61.5196 242.802 61.5196C241.634 61.2617 241.179 62.1111 240.921 63.3397C240.785 64.1891 239.875 63.5975 239.951 61.7774C239.298 62.3689 238.843 63.5975 238.586 63.7947C238.07 64.1891 238.722 63.7947 238.191 62.2324C237.736 60.7308 237.145 59.8966 236.568 62.4296C236.174 64.0525 234.232 66.7221 231.229 64.9626C229.864 64.1132 229.606 60.0179 227.453 59.5629C226.345 59.3657 227.195 60.7308 226.285 60.6095C226.027 60.5488 225.83 59.8359 225.314 59.4416C224.404 58.7894 225.708 59.7601 223.099 56.3777C220.824 53.5869 219.975 57.5456 220.233 59.0472Z\" fill=\"#ED1B24\"><\/path><path d=\"M273.881 97.6042C272.516 97.7407 271.606 98.3777 271.272 99.6215C270.559 102.488 275.367 101.699 278.234 101.305C282.845 100.714 282.466 104.627 285.12 103.717C286.682 103.201 285.833 97.0127 287.85 95.0712C288.897 94.1005 291.354 93.0539 291.748 92.0073C292.522 89.9293 291.035 88.1092 288.047 87.3205C286.819 87.0627 286.622 85.7582 284.801 85.8947C282.39 86.0313 281.616 87.9727 280.448 89.7928C279.538 91.1579 278.568 92.523 276.929 93.1752C274.912 93.9488 274.715 96.1026 273.881 97.6042Z\" fill=\"#ED1B24\"><\/path><path d=\"M110.934 94.0852C113.801 97.9226 117.639 100.911 120.096 100.713C122.113 100.395 123.16 97.9833 121.977 95.3744C119.504 89.7169 114.817 88.0333 114.696 81.587C110.995 79.9034 106.824 81.1927 102.41 83.4071C97.0105 87.3811 91.808 89.9747 82.6467 89.004C83.8146 93.0993 85.6954 96.9974 87.9099 100.577C90.4429 100.638 92.263 99.5304 92.6574 97.3917C92.9152 96.2845 93.8253 94.2065 95.5848 94.2065C94.3562 95.1166 93.3703 97.4524 94.614 97.9833C96.7527 98.954 97.8599 92.9173 99.8165 92.4622C99.3008 93.6302 97.0864 96.5575 99.4222 96.5575C101.242 96.239 101.106 92.9173 103.002 93.1145C103.26 94.161 102.744 96.6334 104.23 96.5575C106.308 96.0418 105.656 93.0538 106.961 93.0538C106.642 96.0418 110.009 95.5261 110.934 94.1004V94.0852Z\" fill=\"#ED1B24\"><\/path><path d=\"M235.977 135.447C237.539 136.221 240.269 136.357 242.408 136.297C246.443 136.16 244.031 138.83 246.564 138.83C250.72 138.83 253.844 143.714 250.007 145.595C249.097 146.05 247.535 145.989 245.851 145.989C244.349 146.444 248.9 148.325 244.622 148.977C242.999 149.235 238.313 147.87 238.313 150.736C238.313 152.359 233.429 153.33 232.064 153.527C219.899 155.211 206.9 156.06 194.023 156.06C185.635 156.06 177.187 155.666 168.981 155.014C166.19 154.756 166.115 152.541 163.384 151.829C161.883 151.434 159.941 151.631 157.924 151.434C153.434 150.979 153.95 147.657 149.855 148.31C146.215 148.901 142.635 146.489 143.227 144.669C143.621 143.623 145.896 143.046 149.278 142.713C146.867 141.742 147.519 142.121 144.925 142.061C141.877 142 141.088 141.469 141.937 140.559C142.65 139.846 147.276 139.588 144.212 138.997C139.601 138.087 147.731 135.933 148.566 135.554C151.887 134.128 154.739 132.035 158.379 131.458C170.468 129.578 182.238 128.667 194.008 128.667C203.821 128.667 213.65 129.32 223.6 130.624C227.953 131.14 232.124 133.551 235.962 135.432L235.977 135.447Z\" fill=\"#ED1B24\"><\/path><path d=\"M227.847 190.264C221.734 188.58 215.485 187.336 209.054 186.563C208.144 186.426 207.173 186.365 206.263 186.244V229.032C202.305 228.441 198.194 228.122 194.038 228.122C189.882 228.122 185.787 228.441 181.813 229.032V186.244C117.184 192.493 66.3264 247.173 66.3264 313.304C66.3264 379.435 120.035 437.239 187.213 440.879V427.289C127.452 423.709 79.856 373.899 79.856 313.304C79.856 259.398 117.639 214.077 168.026 202.185V232.233C145.077 239.65 126.284 256.486 116.395 278.206L128.484 284.258C131.153 278.342 134.535 272.806 138.631 267.877V358.852C130.956 349.418 125.556 338.103 123.357 325.62L110.161 328.411C117.32 368.211 152.236 398.637 194.038 398.637C199.104 398.637 204.185 398.182 209.054 397.272C215.622 396.104 221.932 394.147 227.847 391.614C258.076 378.419 279.281 348.311 279.281 313.319C279.281 287.504 267.647 264.297 249.431 248.689V213.637C284.407 233.203 308.205 270.531 308.205 313.319C308.205 364.495 274.321 407.935 227.832 422.435C221.78 424.316 215.47 425.681 209.039 426.53C206.309 426.925 203.639 427.183 200.849 427.304V440.894C203.639 440.697 206.309 440.5 209.039 440.181C215.47 439.408 221.719 438.164 227.832 436.48C281.859 421.586 321.72 371.972 321.72 313.319C321.72 254.666 281.859 205.189 227.832 190.294L227.847 190.264ZM220.036 202.155C222.705 202.807 225.299 203.52 227.832 204.294C230.501 205.143 233.095 206.053 235.628 207.085V239.012C233.095 237.587 230.486 236.282 227.832 235.114C225.299 234.007 222.69 233.036 220.036 232.187V202.14V202.155ZM265.751 313.289C265.751 340.606 250.341 364.404 227.847 376.553C221.992 379.677 215.683 382.013 209.054 383.439C204.17 384.486 199.165 385.062 194.038 385.062C178.567 385.062 164.188 380.057 152.418 371.669V255.014C157.226 251.571 162.429 248.705 168.026 246.49V303.976H181.813V242.653C185.787 242.001 189.882 241.606 194.038 241.606C198.194 241.606 202.289 242.001 206.263 242.653V352.543H220.051V246.49C222.72 247.597 225.314 248.765 227.847 250.13C230.577 251.632 233.186 253.255 235.643 255.014V304.309H249.431V267.831C259.638 280.253 265.751 296.058 265.751 313.289Z\" fill=\"#FFE200\"><\/path><path d=\"M54.2377 416.277C54.8899 418.75 55.8606 420.888 57.165 422.708C58.4694 424.468 60.153 425.894 62.231 426.864C63.9146 427.259 65.6134 427.774 67.2363 428.366C71.9232 430.247 76.2763 433.174 80.8873 437.072C79.3857 435.191 77.8992 433.371 76.337 431.612C73.7433 428.624 70.9373 425.696 68.2677 422.83C67.9492 422.511 67.6762 422.178 67.4184 421.859C65.9926 421.601 64.6882 421.085 63.3231 420.433C61.958 419.72 60.5929 418.871 59.1671 417.9C58.4543 417.385 59.1671 416.338 59.88 416.854C61.2451 417.764 62.5495 418.613 63.9146 419.265C64.5668 419.584 65.219 419.918 65.9319 420.115C65.3404 419.523 64.8854 418.886 64.3697 418.295C63.2017 416.732 62.1552 415.307 61.1844 413.805C60.6687 413.092 61.7001 412.379 62.231 413.092C63.2017 414.518 64.2483 416.019 65.4162 417.521C66.5841 419.023 67.8886 420.509 69.193 421.95C71.8625 424.817 74.532 427.668 77.2622 430.793C79.0216 432.81 80.7659 434.827 82.404 436.966C81.0996 433.72 80.1289 430.262 79.3402 426.622C78.6273 424.544 77.4594 422.329 76.0184 420.115C71.6653 413.229 67.0392 407.571 59.8345 403.794C55.7392 401.58 50.9918 400.154 45.3949 399.562C47.215 401.777 48.838 404.173 50.2789 406.782C51.9625 409.831 53.3428 413.092 54.2528 416.277H54.2377Z\" fill=\"#00844B\"><\/path><path d=\"M38.8879 243.517C38.7514 244.29 38.5694 245.018 38.175 245.792C38.7666 245.534 39.2823 245.473 39.798 245.473C39.4795 244.821 39.1458 244.169 38.8879 243.517Z\" fill=\"#00844B\"><\/path><path d=\"M36.6128 258.669C35.5055 259.579 34.6561 260.626 34.0039 261.794C33.291 262.962 32.836 264.266 32.5023 265.631C33.3517 269.332 33.8067 273.109 33.9281 276.886C34.4438 274.474 35.1567 272.199 35.9454 269.924C36.2639 269.074 37.5077 269.469 37.174 270.379C36.2639 272.851 35.4903 275.521 34.9595 278.114C36.3246 275.521 37.9475 273.367 39.5705 271.486C40.2833 270.713 41.0721 269.924 41.7849 269.211C43.7416 267.33 45.7589 265.829 47.761 264.463C46.1381 260.11 44.3786 255.879 42.5585 251.723C42.3006 252.117 42.0428 252.496 41.7849 252.83C40.4198 254.908 38.7969 256.864 36.5824 258.685L36.6128 258.669ZM40.9659 262.234C41.2844 262.097 41.5574 261.915 41.8153 261.779C42.331 261.324 42.7253 260.808 43.1804 260.217C43.4989 260.535 43.6354 261.187 43.6354 261.9C43.6354 264.115 42.9832 264.433 41.8153 264.949C41.3602 265.146 40.7687 265.404 40.1317 265.798C40.071 264.297 39.6766 262.674 40.981 262.219L40.9659 262.234Z\" fill=\"#00844B\"><\/path><path d=\"M45.9105 428.123C46.9571 429.033 47.9278 429.943 48.8986 430.914C50.203 432.142 51.5681 433.583 52.9938 435.267C56.4976 439.498 62.1551 444.307 68.9199 445.611C73.1517 446.385 77.7626 445.869 82.5708 443.017C82.4343 442.76 82.2523 442.502 82.1158 442.244C82.0551 442.244 81.9186 442.183 81.8579 442.183C78.612 440.682 75.6847 439.392 72.6966 439.316H72.4995C71.8472 439.316 71.1344 439.377 70.4822 439.514C69.1171 439.771 67.9492 439.969 66.9026 440.105C65.856 440.166 64.946 440.166 64.1724 440.045C63.8539 439.984 63.5202 439.908 63.6567 439.271C63.7932 438.679 64.1117 438.679 64.3696 438.755C65.0825 438.892 65.8712 438.892 66.8419 438.816C67.6913 438.755 68.662 438.619 69.7693 438.361C69.0564 438.103 68.3435 437.845 67.6306 437.451C66.0684 436.738 64.3847 435.828 62.5646 434.66C62.3068 434.463 62.0489 434.266 62.3675 433.75C62.7618 433.234 63.0197 433.431 63.2775 433.553C65.037 434.721 66.6599 435.631 68.2222 436.344C69.7238 437.056 71.2102 437.572 72.6511 438.027C75.897 438.088 78.9609 439.453 82.4039 441.015C82.5405 441.076 82.6618 441.152 82.7983 441.152L83.1168 440.757C77.3986 435.555 72.3174 431.778 66.7357 429.639C60.1075 426.97 52.9483 426.97 45.9257 428.138L45.9105 428.123Z\" fill=\"#00844B\"><\/path><path d=\"M48.0492 394.299C46.7448 392.995 45.2584 391.705 43.6202 390.462C42.1186 390.204 40.6929 390.067 39.1913 390.265C38.3419 390.401 38.1447 389.157 39.0548 389.036C39.9648 388.899 40.8142 388.839 41.5271 388.899C41.2086 388.642 40.8749 388.384 40.5564 388.187C39.7828 387.595 38.9941 387.019 38.2206 386.503C36.719 386.184 35.1718 385.593 33.4731 384.88C31.8501 384.167 30.0907 383.318 28.2099 382.286C27.3605 381.892 27.952 380.785 28.8014 381.179C30.6822 382.15 32.381 383.06 34.0039 383.712C34.459 383.97 34.9747 384.167 35.4297 384.304C35.0353 384.046 34.6561 383.712 34.3225 383.394C32.2445 381.771 30.2879 380.148 28.2706 378.388C27.5577 377.797 28.4071 376.826 29.0441 377.418C31.1221 379.177 33.0787 380.8 35.096 382.423C37.1133 384.046 39.1913 385.669 41.2693 387.17C43.9994 389.051 46.5324 391.068 48.9441 393.344C50.6277 394.967 52.0686 396.665 53.1759 398.288C52.9787 395.695 52.1293 393.086 50.5822 390.492C48.3071 386.594 44.9853 383.272 41.5423 380.345C36.8555 376.31 31.7288 373.519 26.1319 371.502C21.2479 369.743 16.0606 368.711 10.6609 368.059L10.7216 368.12C13.4517 370.137 16.0606 372.018 18.2599 374.687C22.158 379.374 26.2533 383.727 30.5457 387.686C34.7775 391.584 39.252 395.103 43.9994 398.212C47.0481 398.41 49.8542 398.865 52.4478 399.578C51.3406 397.757 49.8542 395.998 48.0189 394.314L48.0492 394.299Z\" fill=\"#00844B\"><\/path><path d=\"M38.5544 412.06C37.8415 412.257 37.5078 412.773 37.8415 413.425C38.2965 414.199 39.4037 414.593 40.1773 414.396C40.8902 414.259 41.2239 413.683 40.8902 413.031C40.4958 412.257 39.3886 411.863 38.5544 412.06Z\" fill=\"#00844B\"><\/path><path d=\"M68.6016 398.925C69.6481 397.423 67.7522 395.224 66.6449 396.71C66.1899 397.363 66.2506 398.394 66.8421 398.986C67.3578 399.501 68.1465 399.501 68.6016 398.925Z\" fill=\"#00844B\"><\/path><path d=\"M33.0333 357.305C34.2012 358.989 35.3084 360.809 36.2792 362.826C37.0527 364.389 37.7049 366.012 38.3571 367.771C39.5857 364.252 40.7688 361.856 39.0094 358.079C37.3257 354.378 34.9747 350.859 31.926 348.068C28.8015 345.277 25.0399 343.184 20.611 341.956C21.8395 344.231 22.9468 346.506 23.9327 348.918C25.1006 351.784 26.0107 354.712 26.86 357.897C27.5123 360.627 27.8308 363.691 28.0886 366.74C28.2858 368.165 28.4071 369.606 28.6043 371.032C31.471 372.2 34.2619 373.626 36.8555 375.324C36.992 373.959 37.1134 372.655 37.3712 371.426C37.5078 370.577 37.7656 370.198 37.5078 369.348C36.7949 367.21 36.0062 365.253 35.0961 363.372C34.186 361.492 33.1395 359.671 31.9716 358.033C31.4558 357.32 32.4266 356.608 33.0181 357.32L33.0333 357.305Z\" fill=\"#00844B\"><\/path><path d=\"M50.203 387.61C50.4002 384.288 50.1423 381.179 49.5508 378.054C48.7773 374.353 47.4728 370.713 45.7134 366.936C44.409 364.145 42.9225 361.415 41.4816 358.685C41.2844 361.415 41.0266 364.343 39.8587 367.391C39.343 368.756 38.8879 370.182 38.6301 371.684C38.3722 373.11 38.175 374.55 38.175 376.113C39.6008 377.083 41.0417 378.191 42.4068 379.359C43.2562 380.071 44.0298 380.784 44.8185 381.497C44.8792 379.874 44.682 378.373 44.3028 376.947C43.8478 375.188 43.1349 373.504 42.1641 371.805C41.7091 371.032 42.8164 370.379 43.2714 371.214C44.2421 372.973 45.0915 374.732 45.5465 376.613C46.0622 378.494 46.1987 380.451 46.0016 382.665C47.6245 384.288 49.0654 385.911 50.2334 387.61H50.203Z\" fill=\"#00844B\"><\/path><path d=\"M45.1219 362.826C45.7135 363.994 46.2899 365.162 46.8814 366.406C48.565 370.107 49.8694 373.626 50.6581 377.205C50.7947 375.249 50.916 373.231 51.0525 371.35C51.2497 367.847 51.371 364.464 51.4469 361.143C51.4469 360.233 52.7513 360.233 52.7513 361.143C52.6906 364.525 52.5541 367.968 52.2963 371.411C52.1598 374.536 51.9019 377.721 51.6441 380.845C51.3862 383.636 51.644 386.503 51.3862 389.294C52.2356 390.659 53.0091 392.16 53.5248 393.723C54.4956 392.752 55.2084 391.25 55.7393 389.233C56.3915 386.821 56.7859 383.773 56.9072 380.33C57.1651 373.049 56.5129 366.284 55.345 359.52C53.6613 354.454 52.2204 349.251 51.1132 343.912C49.9453 345.535 48.9745 347.492 48.0645 349.888C46.7601 353.331 45.7893 357.684 45.1371 362.826H45.1219Z\" fill=\"#00844B\"><\/path><path d=\"M15.4084 331.232C18.3965 334.159 21.3845 337.147 23.4018 341.439C23.4018 341.5 23.4625 341.5 23.4625 341.576C26.1927 342.547 28.6043 343.912 30.743 345.474C29.3779 342.744 27.7549 339.953 25.9955 337.223C23.781 333.704 21.4452 330.261 19.1094 326.878C19.1094 326.878 19.1094 326.818 19.0487 326.818C17.5471 326.302 16.0607 325.513 14.5591 324.603C12.9968 323.633 11.4345 322.389 9.87224 321.024C9.22003 320.432 10.0088 319.461 10.7216 320.114C12.2232 321.342 13.7097 322.525 15.2719 323.496C16.182 324.088 17.0921 324.603 18.0021 324.998C17.4864 324.224 16.9555 323.375 16.3792 322.586C15.4691 321.282 14.4984 319.992 13.3911 318.749C12.7996 318.096 13.7097 317.247 14.3619 317.899C15.4691 319.204 16.5005 320.508 17.4106 321.797C20.7323 326.348 24.0389 331.747 27.1027 336.555C29.3779 340.196 31.4558 343.836 33.1546 347.476C33.6703 347.931 34.1254 348.447 34.5804 348.978C35.3539 348.068 35.0961 346.05 33.9282 342.926C31.9109 337.405 28.7257 331.808 25.859 326.666C23.326 322.176 19.5492 317.763 15.0596 313.925C10.9036 310.346 6.15616 307.358 1.40868 305.34C1.27217 308.328 2.06089 311.316 3.42598 314.38C4.92758 317.763 7.06622 321.145 9.53855 324.725C11.2222 327.197 13.3153 329.214 15.3933 331.232H15.4084Z\" fill=\"#00844B\"><\/path><path d=\"M41.6183 345.671C40.4504 345.611 39.7375 346.066 39.4796 346.642C38.7061 348.144 40.1925 349.691 41.6941 349.691C42.5435 349.752 43.1199 349.236 43.3777 348.584C43.6356 348.068 43.6356 347.416 43.4384 346.9C43.2412 346.248 42.589 345.671 41.6183 345.671Z\" fill=\"#00844B\"><\/path><path d=\"M16.7128 355.287C16.4549 355.151 16.1213 355.151 15.8027 355.151C15.287 355.212 14.832 355.348 14.4376 355.667C14.0433 355.924 13.7248 356.319 13.5883 356.713C13.5276 356.971 13.5276 357.168 13.5276 357.426C13.5883 358.533 14.2405 359.504 15.1505 360.156C16.0606 360.808 17.1678 361.127 18.2751 361.066C18.6694 359.641 18.7301 358.336 18.4722 357.365C18.2144 356.258 17.5622 355.545 16.7128 355.287Z\" fill=\"#00844B\"><\/path><path d=\"M20.8687 300.077C23.9933 305.734 26.3898 311.453 28.2099 317.307C29.6357 322.115 30.7429 326.999 31.5923 331.944C31.653 329.472 31.9108 327.136 32.2445 324.861V324.542C31.5923 314.789 30.1059 306.599 27.497 300.228C25.4797 295.087 22.3552 290.157 17.6077 287.093C16.8341 292.356 16.637 297.559 17.3498 302.761C18.0021 307.645 19.3671 312.454 21.5058 317.262C23.0074 320.583 25.2067 322.919 26.9662 326.105C28.1947 328.319 29.3778 330.397 30.3485 332.278C29.575 327.333 28.4678 322.525 26.9662 317.717C25.146 311.923 22.8102 306.265 19.7463 300.744C19.2913 299.971 20.4592 299.318 20.8536 300.092L20.8687 300.077Z\" fill=\"#00844B\"><\/path><path d=\"M47.8521 313.288C47.8521 311.726 47.8521 310.164 47.9128 308.601C47.655 306.645 47.1393 304.825 46.487 303.202C45.4405 300.472 43.954 298.257 42.1946 296.437C41.2845 299.228 40.3138 301.958 39.3279 304.628C38.16 307.873 36.9921 311.134 35.9455 314.244C33.8069 321.069 32.7603 328.031 32.821 335.251C32.8816 338.376 34.7776 341.106 35.6118 344.033C36.0669 339.999 36.6584 335.964 37.2954 332.066C38.069 327.379 38.9791 322.829 40.0256 318.339C39.8284 317.232 39.7071 316.064 39.6313 314.896C39.6313 313.728 39.6919 312.484 39.8284 311.195C39.965 310.285 41.1935 310.422 41.1329 311.332C40.9357 312.56 40.875 313.743 40.9357 314.911C40.9357 315.503 40.9964 316.079 41.0722 316.671C41.3907 316.352 41.7244 315.897 41.9823 315.442C42.4373 314.669 42.8316 313.758 43.1502 312.651C43.2867 312.393 43.3473 312.06 43.9996 312.257C44.5911 312.454 44.5153 312.773 44.3939 313.03C44.0754 314.198 43.6204 315.245 43.0895 316.094C42.5738 316.944 41.9823 317.657 41.33 318.233C40.2835 322.844 39.3127 327.591 38.5392 332.278C37.7656 336.889 37.1741 341.576 36.7191 346.46C37.8263 346.263 37.8263 344.898 38.1448 343.988C39.1156 341.257 40.2835 338.33 41.4666 335.403C44.1361 328.699 46.9269 321.676 47.837 316.352V313.303L47.8521 313.288Z\" fill=\"#00844B\"><\/path><path d=\"M16.0607 283.696C18.1387 286.684 21.0054 287.731 23.4019 290.582C21.9761 286.426 20.4745 282.255 18.5937 278.297C16.2579 273.231 13.4519 268.483 9.81166 264.448C9.61448 264.191 9.35663 263.933 9.87233 263.538C10.3274 263.083 10.5245 263.341 10.7217 263.599C14.4985 267.755 17.35 272.578 19.7617 277.781C20.8082 279.995 21.7183 282.21 22.6283 284.546C21.2633 279.282 20.4139 274.338 19.9588 269.651C18.7303 266.466 16.9101 263.675 14.6198 261.127C12.4053 258.715 9.81166 256.576 6.94497 254.756C6.8843 259.64 7.46067 264.57 9.02294 269.575C10.4487 274.262 12.7239 278.934 16.0456 283.681L16.0607 283.696Z\" fill=\"#00844B\"><\/path><path d=\"M27.315 295.663C27.7093 292.933 27.9065 290.142 28.0279 287.336C28.1644 283.635 28.0279 279.798 27.77 275.96C27.5122 272.578 25.6314 268.619 23.9326 264.964C23.2804 263.735 22.704 262.431 22.1731 261.263C22.0366 260.944 21.9153 260.671 22.4917 260.414C23.068 260.156 23.2045 260.474 23.341 260.732C23.7961 261.9 24.4483 263.144 25.0247 264.433C25.6769 265.798 26.3291 267.163 26.9054 268.528C26.7689 267.36 26.6476 266.253 26.5111 265.085C26.0561 262.355 25.5404 259.564 24.9488 256.758C24.8881 256.44 24.7516 256.106 25.4038 255.985C26.0561 255.924 26.1167 256.182 26.1774 256.5C26.7689 259.367 27.3453 262.158 27.7397 264.888C28.0582 267.3 28.3312 269.635 28.5132 271.971C28.6497 273.336 28.9076 274.58 28.9683 275.869C29.2261 279.707 29.3626 283.605 29.2261 287.382C29.1654 291.083 28.7711 294.799 28.1189 298.378C28.3767 298.894 28.5739 299.485 28.7711 300.001C29.7418 299.349 30.1968 297.21 30.849 293.949C31.0462 293.039 31.2434 291.993 31.4406 290.885C33.3214 282.498 33.0029 273.261 31.0462 264.934C29.3626 257.653 26.2381 250.888 21.5513 245.822C20.6412 252.981 20.3227 260.459 21.0962 268.574C21.9456 277.735 24.1601 286.911 27.2695 295.618L27.315 295.663Z\" fill=\"#00844B\"><\/path><path d=\"M6.4443 297.999C7.03584 297.999 7.49087 297.802 7.87006 297.483C8.18859 297.165 8.4616 296.71 8.4616 296.179C8.4616 295.648 8.20375 295.208 7.87006 294.875C7.4757 294.556 6.96 294.359 6.36846 294.359C5.85276 294.359 5.3219 294.556 4.9427 294.875C4.62418 295.193 4.427 295.648 4.427 296.179C4.427 296.71 4.62418 297.15 5.01854 297.483C5.33706 297.802 5.86793 297.999 6.4443 297.999Z\" fill=\"#00844B\"><\/path><path d=\"M38.4329 247.02C37.0678 247.612 35.6421 248.78 35.1112 249.296C33.3518 251.116 32.0625 252.739 31.2131 254.24C29.7115 256.713 30.1666 257.425 30.9553 259.837C31.4103 258.866 31.7288 257.759 32.0625 256.713C32.9726 253.785 34.5955 252.481 37.1285 250.539C37.3864 250.342 37.6442 250.084 37.8414 249.948C38.5543 249.432 39.343 250.403 38.6149 250.918C38.3571 251.176 38.0992 251.374 37.9021 251.51C35.5662 253.33 34.004 254.498 33.2911 257.031C33.0332 257.88 32.7754 258.791 32.4417 259.503C32.1839 260.277 31.8502 260.929 31.471 261.46C31.6075 261.976 31.7895 262.567 31.926 263.144C32.1839 262.431 32.5175 261.779 32.8967 261.126C33.6096 259.822 34.5804 258.715 35.8241 257.683C38.3571 255.666 40.0559 253.254 41.6182 250.858C41.2996 249.629 41.1025 247.673 40.1166 246.884C39.798 246.565 39.1458 246.687 38.4329 247.02Z\" fill=\"#00844B\"><\/path><path d=\"M40.5717 272.32C38.0387 275.187 35.6877 278.752 33.8676 283.499C33.8676 283.499 33.8069 283.56 33.8069 283.636C33.6097 286.169 33.2912 288.777 32.6997 291.25C32.9575 291.053 33.2154 290.734 33.549 290.476C34.3984 289.505 35.3085 288.398 35.6877 287.609C37.1135 285.334 38.2965 283.711 39.6616 281.755C39.6616 281.694 39.7981 281.497 40.511 280.526C41.0267 279.813 42.0733 280.526 41.5576 281.3C41.4211 281.436 41.2391 281.755 40.7082 282.468C39.3431 284.424 38.1752 286.047 36.8101 288.322C36.3551 289.096 35.3843 290.34 34.4743 291.31C33.3064 292.539 32.457 292.539 32.1385 294.238C31.8199 295.739 31.5469 297.029 31.2891 298.136C34.2771 295.8 36.9466 293.328 39.2824 290.795C42.0733 287.746 44.2878 284.621 45.7135 281.633C47.0179 279.04 47.8522 276.294 48.1859 273.564C48.5044 271.092 48.383 268.62 47.7915 266.026C45.3192 267.709 42.8468 269.727 40.5717 272.336V272.32Z\" fill=\"#00844B\"><\/path><path d=\"M10.661 250.539C11.2526 250.858 11.9654 250.934 12.5418 250.736C13.194 250.479 13.649 250.024 13.9069 249.432C14.1647 248.841 14.1647 248.203 13.9069 247.475C13.649 246.823 13.194 246.308 12.6025 245.974C12.0109 245.716 11.2981 245.579 10.7217 245.837C10.0695 246.035 9.61445 246.49 9.3566 247.066C9.09875 247.657 9.09875 248.37 9.3566 249.023C9.55378 249.735 10.0695 250.251 10.661 250.524V250.539Z\" fill=\"#00844B\"><\/path><path d=\"M30.6974 245.914C31.4103 242.986 32.4569 240.195 33.7613 237.526C34.1556 236.677 35.3236 237.268 34.9292 238.042C33.6248 240.711 32.654 243.441 31.9412 246.232C31.4255 248.31 30.9704 250.464 30.7126 252.603C31.6226 251.298 32.7905 249.872 34.2315 248.371C36.1881 246.414 38.0689 245.246 37.6139 241.803C37.356 240.18 36.6431 237.647 34.8837 235.099C32.745 237.374 30.7884 240.362 29.8784 243.487C29.1655 246.081 28.9683 249.084 29.484 252.466C29.7418 250.252 30.1362 248.037 30.7126 245.898L30.6974 245.914Z\" fill=\"#00844B\"><\/path><path d=\"M83.6934 410.301C83.5569 409.906 83.7541 409.588 84.0877 409.451C82.2069 407.313 80.4475 405.159 78.688 402.884C78.5515 409.846 78.8852 416.474 79.856 422.587C80.766 428.183 82.2676 433.704 84.6034 438.846C85.7714 437.284 86.0292 436.571 86.8786 434.812C87.1971 432.339 87.3336 429.67 87.1364 426.879C86.8786 421.419 85.7107 415.625 83.6934 410.301Z\" fill=\"#00844B\"><\/path><path d=\"M85.2404 410.756C87.0605 415.958 88.1677 421.555 88.4256 426.879C88.4863 428.639 88.4863 430.322 88.4256 432.021C89.1992 430.792 89.4722 429.685 89.6542 428.184C90.1092 425.393 90.1699 421.419 89.9727 416.611C89.9727 416.353 90.0334 416.156 90.1699 416.095C88.4863 414.335 86.8482 412.576 85.2252 410.756H85.2404Z\" fill=\"#00844B\"><\/path><path d=\"M91.0344 427.926C91.9445 426.242 92.718 424.483 93.3702 422.526C93.6281 421.677 93.8253 420.767 94.0831 419.796C93.1124 418.946 92.2023 418.036 91.2923 417.202C91.4895 421.555 91.3529 425.196 91.0344 427.926Z\" fill=\"#00844B\"><\/path><path d=\"M373.244 318.157C368.299 321.342 364.204 326.742 361.474 332.005C361.277 332.4 361.155 332.46 361.155 332.855C361.216 334.675 361.095 336.495 360.761 338.315C362.778 336.176 364.856 334.083 366.934 332.005C367.071 330.959 367.192 329.988 367.45 329.017C367.708 327.971 368.042 326.879 368.497 325.832C368.815 324.861 369.998 325.377 369.665 326.226C369.27 327.334 368.952 328.304 368.694 329.351C368.633 329.745 368.497 330.2 368.436 330.58C371.303 327.849 374.291 325.18 377.279 322.51C377.992 321.919 378.78 322.905 378.128 323.481C375.064 326.151 372.076 328.82 369.149 331.611C369.467 331.611 369.801 331.611 370.12 331.672C370.893 331.672 371.743 331.732 372.531 331.808C373.441 331.869 373.305 333.173 372.395 333.037C371.682 332.976 370.893 332.9 370.059 332.9H367.844C365.236 335.433 362.703 338.042 360.23 340.833C359.457 343.7 358.152 346.551 356.453 349.221C356.969 348.902 357.5 348.629 358.016 348.311C359.244 346.49 360.609 344.61 362.445 343.245C366.934 339.862 370.514 337.132 373.623 333.886C376.809 330.701 379.539 327.061 382.269 321.919C383.695 319.249 384.408 315.67 385.97 313.395C380.964 314.502 377.188 315.609 373.229 318.142L373.244 318.157Z\" fill=\"#00844B\"><\/path><path d=\"M374.473 292.736C369.589 296.71 365.312 300.806 362.187 305.098C358.805 309.785 356.787 314.79 356.984 320.114C358.607 322.647 359.775 325.256 360.428 327.986C360.488 325.969 360.488 324.012 360.625 322.268C360.822 319.674 361.14 317.323 361.671 315.306C362.323 313.228 363.097 311.605 364.007 310.3C364.917 308.996 366.024 308.025 367.132 307.252C367.905 306.736 368.633 307.767 367.905 308.298C366.798 309.011 365.888 309.921 365.038 311.089C364.189 312.257 363.476 313.759 362.9 315.64C362.763 316.095 362.703 316.55 362.581 317.065C363.097 316.474 363.628 315.958 364.144 315.503C365.251 314.532 366.358 313.683 367.587 312.909C368.3 312.454 369.012 313.501 368.239 314.017C367.132 314.729 366.024 315.518 364.993 316.428C364.022 317.399 363.036 318.385 362.202 319.477C362.066 320.387 362.005 321.358 361.944 322.404C361.808 324.422 361.747 326.56 361.747 328.911C364.417 324.361 367.268 321.115 370.332 318.703C371.181 316.747 371.955 314.866 372.41 313.046C372.804 311.226 373.062 309.148 372.668 307.328C371.955 303.354 373.062 298.879 374.033 294.784C374.23 294.071 374.351 293.419 374.488 292.767L374.473 292.736Z\" fill=\"#00844B\"><\/path><path d=\"M353.663 352.815C349.173 356.592 346.246 361.794 344.501 367.316C344.441 367.316 344.441 367.376 344.441 367.376C344.896 375.567 342.621 383.439 340.148 390.856C342.363 387.155 344.501 383.06 346.519 378.828L346.913 378.054H346.852C346.989 377.084 347.049 376.173 347.049 375.263C346.989 374.353 346.852 373.443 346.731 372.594C346.534 371.744 347.778 371.487 347.96 372.336C348.142 373.185 348.217 374.095 348.278 375.006C350.159 370.713 351.979 366.36 353.617 362.189C353.936 361.339 355.119 361.794 354.785 362.644C353.162 366.876 351.342 371.229 349.446 375.521C349.643 375.385 349.765 375.203 349.962 375.066C351.008 374.293 352.04 373.565 353.086 372.928C353.86 372.533 354.391 373.64 353.738 374.035C352.692 374.626 351.721 375.339 350.75 376.052C349.446 377.099 348.339 377.933 347.687 379.374C346.382 382.165 345.017 384.834 343.591 387.367C346.124 384.698 349.052 382.225 352.176 380.087C354.391 378.661 356.666 377.357 359.002 376.249C360.17 372.928 359.396 370.395 358.744 368.256C358.425 367.209 358.152 366.299 358.031 365.329C357.379 359.413 362.126 351.875 365.251 346.93C361.095 348.098 356.924 350.115 353.678 352.846L353.663 352.815Z\" fill=\"#00844B\"><\/path><path d=\"M371.803 262.568C372.319 262.704 372.911 262.507 373.366 262.173C373.957 261.718 374.336 261.127 374.534 260.353C374.731 259.58 374.67 258.851 374.397 258.336C374.139 257.82 373.745 257.426 373.168 257.289C372.653 257.153 372.061 257.289 371.546 257.684C371.03 258.078 370.635 258.654 370.438 259.443C370.241 260.156 370.302 260.945 370.575 261.521C370.833 262.037 371.288 262.431 371.803 262.568Z\" fill=\"#00844B\"><\/path><path d=\"M345.214 272.578C346.64 272.776 348.005 273.488 349.446 274.793C349.507 273.17 349.765 271.471 350.159 269.848C350.296 269.135 350.478 268.483 350.751 267.77C350.356 266.405 349.901 265.101 349.446 263.872C348.93 262.568 348.4 261.4 347.763 260.368C347.247 259.595 348.354 258.943 348.809 259.716C349.522 260.823 350.114 262.052 350.629 263.356C350.948 264.13 351.221 264.979 351.479 265.829C352.252 263.948 353.238 262.189 354.345 260.49C353.83 257.502 352.525 255.682 350.826 254.514C349.264 253.406 347.308 252.951 345.366 252.83C343.091 256.986 342.12 259.458 342.181 261.991C342.242 264.661 343.349 267.452 345.245 272.457V272.594L345.214 272.578Z\" fill=\"#00844B\"><\/path><path d=\"M354.315 288.838C355.089 290.067 355.938 291.311 356.909 292.479C357.045 292.084 357.167 291.705 357.303 291.371C355.999 285.911 355.741 281.224 356.393 275.764C356.651 273.807 357.045 271.79 357.5 269.788C357.106 268.878 356.727 267.968 356.393 267.058C356.135 266.087 355.938 265.04 355.877 263.933C355.817 263.023 357.106 263.023 357.182 263.933C357.182 264.843 357.379 265.814 357.637 266.663C357.773 267.058 357.895 267.513 358.092 267.892C358.805 265.359 359.775 262.826 360.958 260.278C361.353 259.504 362.521 260.02 362.126 260.869C361.019 263.144 360.17 265.419 359.457 267.755C359.518 267.619 359.654 267.497 359.775 267.361C360.367 266.769 360.943 266.193 361.338 265.541C361.853 264.767 362.9 265.48 362.445 266.254C361.929 266.967 361.338 267.619 360.685 268.271C360.094 268.863 359.457 269.378 358.805 269.894C358.289 271.911 357.895 273.929 357.697 275.946C357.561 277.053 357.44 278.16 357.379 279.268C357.697 278.949 358.092 278.555 358.425 278.221C359.017 277.508 359.593 276.856 359.851 276.401C360.306 275.551 361.413 276.143 361.019 276.992C360.625 277.584 360.048 278.297 359.336 279.07C358.623 279.844 357.834 280.693 357.379 281.482C357.379 284.076 357.697 286.685 358.152 289.278C360.23 284.849 362.703 281.088 365.494 277.902C366.146 275.627 366.464 273.413 366.404 271.198C366.343 268.923 365.949 266.648 365.236 264.434C364.462 262.022 364.265 259.489 364.523 256.956C364.659 255.136 365.039 253.179 365.494 251.298C364.189 252.208 362.9 253.118 361.717 254.165C356.833 258.26 352.874 263.857 351.372 270.167C349.871 276.143 350.599 282.65 354.3 288.823L354.315 288.838Z\" fill=\"#00844B\"><\/path><path d=\"M355.422 300.274C355.422 299.759 355.483 299.228 355.483 298.712C353.602 296.498 351.782 294.222 350.022 291.947H348.066C347.414 291.947 346.761 291.887 346.049 291.75C345.139 291.614 345.336 290.385 346.185 290.521C346.837 290.582 347.489 290.658 348.142 290.658C348.46 290.719 348.733 290.719 349.052 290.719C348.4 289.869 347.823 289.035 347.232 288.246C346.185 286.821 345.154 285.455 344.183 284.015C342.56 283.878 340.998 283.559 339.572 282.847C338.723 282.452 339.314 281.284 340.088 281.679C341.058 282.134 342.105 282.452 343.212 282.649C341.908 280.89 340.679 279.07 339.511 277.31C338.996 276.537 340.027 275.809 340.558 276.598C341.726 278.281 342.894 279.98 344.077 281.664C344.016 281.072 343.88 280.435 343.819 279.843C343.622 278.615 343.364 277.432 343.106 276.203C342.909 275.293 344.153 275.035 344.335 275.885C344.592 277.113 344.85 278.418 345.047 279.661C345.305 281.027 345.503 282.452 345.639 283.893C346.488 285.061 347.398 286.305 348.233 287.473C348.748 288.125 349.203 288.838 349.734 289.49C349.734 289.232 349.795 288.974 349.795 288.777C349.856 287.928 349.856 287.094 349.856 286.305C349.856 285.395 351.16 285.395 351.16 286.305C351.16 287.154 351.16 287.988 351.099 288.838C351.039 289.551 350.963 290.203 350.842 290.916C352.464 292.994 354.087 295.011 355.786 297.028C355.983 295.982 356.181 294.95 356.499 293.904H356.438C355.271 292.478 354.163 290.977 353.314 289.475C350.781 285.243 349.537 280.89 349.416 276.598C346.291 272.957 343.364 273.534 339.602 274.262C338.889 274.398 338.177 274.52 337.388 274.656C338.237 281.482 339.86 286.623 342.727 290.658C345.518 294.693 349.613 297.681 355.468 300.274H355.422Z\" fill=\"#00844B\"><\/path><path d=\"M356.651 300.73C356.514 303.854 356.909 306.979 357.879 309.83C358.592 308.329 359.442 306.842 360.473 305.34L360.412 305.28C360.155 303.778 359.957 302.61 360.352 301.124C361.52 296.437 363.218 292.145 365.296 287.989C366.267 286.169 367.253 284.288 368.345 282.528C368.482 281.679 368.603 281.027 368.664 280.39C368.8 279.737 368.8 279.161 368.861 278.372C368.861 277.462 370.089 277.523 370.089 278.433C370.089 278.827 370.089 279.282 370.029 279.662C370.742 278.494 371.53 277.326 372.243 276.219C372.44 275.961 372.562 275.703 373.093 276.021C373.684 276.34 373.487 276.613 373.29 276.931C370.878 280.632 368.482 284.606 366.464 288.565C366.146 289.157 365.873 289.733 365.615 290.325L365.676 290.264C366.388 289.748 367.177 289.217 367.951 288.838C368.724 288.444 369.316 289.551 368.542 290.006C367.769 290.324 367.117 290.78 366.404 291.31C365.751 291.826 365.099 292.418 364.447 293.07C364.386 293.07 364.386 293.131 364.386 293.131C363.218 295.8 362.308 298.53 361.595 301.458C361.338 302.307 361.338 303.081 361.459 303.93C363.082 301.791 364.963 299.698 367.056 297.62C367.056 297.62 367.117 297.559 367.117 297.484C369.194 294.359 370.893 291.113 372.183 287.792C373.608 284.409 374.594 281.027 375.246 277.584C375.701 275.051 376.02 272.442 376.672 269.848C373.35 272.063 370.302 274.535 367.511 277.584C364.128 281.224 361.262 285.577 359.184 290.127C357.682 293.373 356.772 297.089 356.651 300.73Z\" fill=\"#00844B\"><\/path><path d=\"M385.333 299.167C385.591 298.576 386.243 297.15 385.136 297.089C384.62 297.089 383.907 297.347 383.058 297.802C381.753 298.652 381.374 299.759 380.843 301.124C380.843 301.185 380.782 301.26 380.782 301.321C381.95 301.321 382.86 301.124 383.573 300.805C384.347 300.487 384.938 299.895 385.333 299.183V299.167Z\" fill=\"#00844B\"><\/path><path d=\"M354.573 318.946C352.616 316.474 350.872 314.138 349.31 311.863C348.081 310.043 347.035 308.344 346.124 306.721C344.562 310.953 343.455 315.503 343 320.054C342.484 324.862 342.606 329.746 343.455 334.493C344.107 337.739 345.275 340.803 347.095 343.654C348.597 345.99 350.538 348.205 352.95 350.161C352.556 344.898 351.721 339.696 350.538 334.554C349.568 333.962 348.718 333.325 347.808 332.537C346.898 331.687 345.988 330.716 345.139 329.609C344.547 328.896 345.594 328.108 346.109 328.836C346.959 329.882 347.793 330.792 348.703 331.566C349.158 332.021 349.613 332.339 350.068 332.734C349.158 329.23 348.111 325.848 346.944 322.389C346.686 321.54 347.854 321.161 348.172 321.995C349.279 325.241 350.311 328.563 351.16 331.884C351.418 330.777 351.615 329.609 351.676 328.502C351.676 327.592 352.98 327.653 352.904 328.563C352.844 330.443 352.389 332.339 351.676 334.16C352.904 339.423 353.754 344.822 354.148 350.283C361.171 340.727 362.081 328.502 354.543 318.946H354.573Z\" fill=\"#00844B\"><\/path><path d=\"M337.6 398.591C341.18 397.029 344.562 395.406 347.869 393.192C348.066 392.282 348.324 391.372 348.718 390.522C349.112 389.612 349.628 388.702 350.22 387.853C350.417 387.595 350.614 387.337 351.13 387.716C351.645 388.035 351.448 388.308 351.266 388.565C350.675 389.339 350.22 390.188 349.901 391.038C349.704 391.356 349.583 391.69 349.507 392.084C353.739 389.021 357.576 385.577 361.277 381.937C361.929 381.346 362.839 382.195 362.187 382.847C358.349 386.624 354.512 390.006 350.675 392.797C347.156 395.33 343.394 397.605 339.299 399.304C339.102 399.82 338.844 400.275 338.647 400.806C342.878 400.548 347.095 399.183 351.266 396.65C355.877 393.92 360.427 389.824 364.856 384.425C367.905 380.784 371.166 377.341 374.351 373.898C366.874 373.838 359.138 376.947 352.889 381.118C346.003 385.805 340.27 392.115 337.615 398.606L337.6 398.591Z\" fill=\"#00844B\"><\/path><path d=\"M372.91 359.58C371.743 359.383 370.377 360.035 370.044 361.203C369.649 362.31 370.438 363.281 371.545 363.478C372.653 363.675 374.018 363.023 374.412 361.855C374.731 360.748 374.018 359.838 372.91 359.58Z\" fill=\"#00844B\"><\/path><path d=\"M344.365 348.144C343.713 347.37 342.681 347.37 341.953 348.144C341.635 348.538 341.438 349.054 341.438 349.706C341.438 350.297 341.635 350.874 342.029 351.268C342.681 352.042 343.652 352.315 344.365 351.405C344.684 351.01 344.881 350.434 344.881 349.782C344.881 349.13 344.684 348.553 344.365 348.159V348.144Z\" fill=\"#00844B\"><\/path><path d=\"M333.444 399.304C332.595 397.621 332.019 395.406 331.624 392.797C331.169 389.551 331.033 385.714 331.306 381.543C331.503 378.221 331.897 374.914 332.474 371.471C333.065 368.028 333.899 364.509 335.082 361.006C335.34 360.096 336.584 360.49 336.25 361.4C335.143 364.843 334.294 368.286 333.717 371.669C333.126 375.051 332.807 378.373 332.61 381.619V381.679C332.807 381.361 332.929 381.027 333.126 380.769C333.839 379.662 334.552 378.555 335.401 377.523C335.993 376.871 336.963 377.66 336.372 378.373C335.598 379.343 334.87 380.329 334.233 381.437C333.581 382.483 333.004 383.575 332.474 384.758C332.413 387.686 332.534 390.355 332.868 392.691C333.187 395.027 333.839 397.636 335.143 399.714C336.705 399.001 337.873 393.54 338.586 391.523C342.029 381.315 345.214 370.258 341.574 358.822C340.861 356.486 339.815 354.211 338.526 351.996C337.813 350.692 336.963 349.402 335.993 348.159C333.581 357.972 330.198 367.406 325.921 376.386L325.663 376.841C325.603 382.635 326.058 388.277 327.483 392.312C328.651 395.755 330.547 398.227 333.46 399.334L333.444 399.304Z\" fill=\"#00844B\"><\/path><path d=\"M307.765 434.296C311.011 430.398 314.333 428.441 315.501 423.239C315.819 421.677 315.956 420.19 315.895 418.628C315.834 417.657 317.063 417.521 317.124 418.491C317.26 420.175 317.124 421.874 316.729 423.497C316.593 424.149 316.411 424.801 316.214 425.378C317.518 424.012 318.747 422.647 319.915 421.222C321.932 418.749 323.752 416.156 325.254 413.092C325.709 412.318 326.816 412.895 326.421 413.683C324.799 416.808 322.978 419.477 320.961 422.01C320.188 422.92 319.459 423.83 318.625 424.68C319.596 424.164 320.506 423.633 321.416 423.254C322.19 422.86 322.781 423.967 321.932 424.361C320.764 424.953 319.52 425.59 318.352 426.318C314.454 428.654 311.648 431.657 308.736 435.161C307.234 436.981 305.809 438.862 304.504 440.879C309.707 438.998 314.318 436.389 318.413 432.749C322.842 428.851 326.664 423.709 329.925 417.081C331.745 413.243 333.429 409.467 335.128 405.629C335.901 403.748 336.751 401.852 337.6 399.972C320.43 407.449 309.191 419.993 304.899 438.073C305.809 436.768 306.719 435.54 307.765 434.296Z\" fill=\"#00844B\"><\/path><path d=\"M315.562 404.188C316.077 404.188 316.532 404.052 316.866 403.733C317.185 403.415 317.458 402.884 317.579 402.11C317.579 401.853 317.579 401.519 317.518 401.261C317.458 400.806 317.26 400.412 317.063 400.154C316.805 399.896 316.548 399.699 316.214 399.699H315.956C315.501 399.759 315.107 400.017 314.788 400.412C314.47 400.806 314.272 401.382 314.197 402.035C314.197 402.626 314.333 403.202 314.652 403.658C314.849 403.976 315.167 404.173 315.562 404.173V404.188Z\" fill=\"#00844B\"><\/path><path d=\"M347.429 415.504C346.322 414.73 344.638 414.851 343.531 415.64C342.302 416.55 342.424 417.976 343.986 418.507C344.699 418.765 345.548 418.704 346.322 418.507C347.687 418.112 348.794 416.626 347.429 415.519V415.504Z\" fill=\"#00844B\"><\/path><path d=\"M315.88 436.374C312.24 438.968 308.205 440.985 303.852 442.486C302.805 443.397 301.971 444.564 301.319 445.808C300.864 446.718 300.409 447.689 300.015 448.857C303.261 448.72 306.779 447.75 310.617 446.187C313.347 444.109 315.956 441.758 318.231 439.165C318.883 438.452 319.793 439.301 319.202 440.014C317.837 441.576 316.335 443.002 314.773 444.443C317.897 442.941 321.204 441.197 324.783 439.241C325.557 438.786 326.209 439.893 325.375 440.348C321.143 442.684 317.245 444.701 313.605 446.324C315.031 446.46 316.472 446.718 317.958 447.37C318.474 447.568 318.474 447.886 318.155 448.341C319.52 447.75 320.825 447.113 322.053 446.324C328.621 442.486 334.278 436.768 338.829 431.308C331.548 430.14 321.856 432.081 315.88 436.374Z\" fill=\"#00844B\"><\/path><path d=\"M311.785 447.492H310.875C307.098 448.993 303.655 449.903 300.409 450.161C306.582 451.663 312.376 450.813 317.639 448.599C317.579 448.538 317.503 448.538 317.442 448.462C315.622 447.689 313.665 447.613 311.785 447.492Z\" fill=\"#00844B\"><\/path><path d=\"M303.079 440.348C303.473 438.468 303.928 436.648 304.444 434.888C302.942 432.931 301.85 429.291 301.198 426.895C300.94 425.787 299.12 424.559 298.073 424.028C297.3 423.634 297.815 422.526 298.665 422.921C299.636 423.376 300.546 424.028 301.334 424.877C301.592 423.77 301.926 422.663 302.305 421.632C302.821 420.13 303.473 418.704 304.383 417.476C304.975 416.763 306.006 417.536 305.43 418.249C304.58 419.356 304.004 420.661 303.473 422.026C303.018 423.391 302.624 424.817 302.366 426.182C302.821 428.715 303.731 431.126 304.975 433.144C305.945 430.216 307.053 427.426 308.418 424.756C309.009 420.069 308.933 415.974 308.281 412.394C307.963 410.256 307.371 408.238 306.597 406.479C303.215 410.574 299.575 414.472 295.737 418.188C295.995 426.576 298.665 431.642 301.395 437.042C301.987 438.088 302.502 439.181 303.079 440.364V440.348Z\" fill=\"#00844B\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">OFFICIAL STORE<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2324325 elementor-widget elementor-widget-text-editor\" data-id=\"2324325\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Take the passion for RCD Mallorca with you with products from our official store, located at Estadi Mallorca Son Moix! In our 200 m\u00b2 space, you\u2019ll find a wide selection of jerseys, accessories, and exclusive items to support the team in every match. Visit us at Cam\u00ed del Reis s\/n and wear Mallorca\u2019s colors with pride.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73c7f6a elementor-widget elementor-widget-button\" data-id=\"73c7f6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/tienda.rcdmallorca.es\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">VISIT THE STORE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-045085e e-flex e-con-boxed e-con e-parent\" data-id=\"045085e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d8810e9 e-con-full e-flex e-con e-child\" data-id=\"d8810e9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cb35b95 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"cb35b95\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">BOOK YOUR SPACE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e2055b elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"2e2055b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Celebrate your event at Estadi Mallorca Son Moix and enjoy an unforgettable experience! Our versatile spaces adapt to any type of event, whether corporate, festive, or formal. Book now and impress your guests with the unique atmosphere and excellent service that only the stadium can offer.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dddb79e elementor-arrows-position-inside elementor-pagination-position-outside elementor-invisible elementor-widget elementor-widget-image-carousel\" data-id=\"dddb79e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel de im\u00e1genes\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 5\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"dddb79e\" data-elementor-lightbox-title=\"Dise\u00f1o sin t\u00edtulo (8)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjA3MiwidXJsIjoiaHR0cHM6XC9cL2VzdGFkaW1hbGxvcmNhc29ubW9peC5lc1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDFcL0Rpc2Vuby1zaW4tdGl0dWxvLTgucG5nIiwic2xpZGVzaG93IjoiZGRkYjc5ZSJ9\" href=\"https:\/\/estadimallorcasonmoix.es\/en\/spaces\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2025\/01\/Diseno-sin-titulo-8.png\" alt=\"Dise\u00f1o sin t\u00edtulo (8)\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 5\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"dddb79e\" data-elementor-lightbox-title=\"Dise\u00f1o sin t\u00edtulo (9)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjA2OSwidXJsIjoiaHR0cHM6XC9cL2VzdGFkaW1hbGxvcmNhc29ubW9peC5lc1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDFcL0Rpc2Vuby1zaW4tdGl0dWxvLTkucG5nIiwic2xpZGVzaG93IjoiZGRkYjc5ZSJ9\" href=\"https:\/\/estadimallorcasonmoix.es\/en\/spaces\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2025\/01\/Diseno-sin-titulo-9.png\" alt=\"Dise\u00f1o sin t\u00edtulo (9)\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 5\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"dddb79e\" data-elementor-lightbox-title=\"Dise\u00f1o sin t\u00edtulo (10)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjA2NiwidXJsIjoiaHR0cHM6XC9cL2VzdGFkaW1hbGxvcmNhc29ubW9peC5lc1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDFcL0Rpc2Vuby1zaW4tdGl0dWxvLTEwLnBuZyIsInNsaWRlc2hvdyI6ImRkZGI3OWUifQ%3D%3D\" href=\"https:\/\/estadimallorcasonmoix.es\/en\/spaces\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2025\/01\/Diseno-sin-titulo-10.png\" alt=\"Dise\u00f1o sin t\u00edtulo (10)\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 5\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"dddb79e\" data-elementor-lightbox-title=\"Dise\u00f1o sin t\u00edtulo (7)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjA3NSwidXJsIjoiaHR0cHM6XC9cL2VzdGFkaW1hbGxvcmNhc29ubW9peC5lc1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDFcL0Rpc2Vuby1zaW4tdGl0dWxvLTcucG5nIiwic2xpZGVzaG93IjoiZGRkYjc5ZSJ9\" href=\"https:\/\/estadimallorcasonmoix.es\/en\/spaces\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2025\/01\/Diseno-sin-titulo-7.png\" alt=\"Dise\u00f1o sin t\u00edtulo (7)\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 5\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"dddb79e\" data-elementor-lightbox-title=\"Dise\u00f1o sin t\u00edtulo (11)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjA2MywidXJsIjoiaHR0cHM6XC9cL2VzdGFkaW1hbGxvcmNhc29ubW9peC5lc1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDFcL0Rpc2Vuby1zaW4tdGl0dWxvLTExLnBuZyIsInNsaWRlc2hvdyI6ImRkZGI3OWUifQ%3D%3D\" href=\"https:\/\/estadimallorcasonmoix.es\/en\/spaces\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2025\/01\/Diseno-sin-titulo-11.png\" alt=\"Dise\u00f1o sin t\u00edtulo (11)\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4393247 elementor-mobile-align-justify elementor-widget-mobile__width-inherit elementor-invisible elementor-widget elementor-widget-button\" data-id=\"4393247\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/estadimallorcasonmoix.es\/en\/spaces\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">BOOK YOUR SPACE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c509e81 elementor-widget__width-initial elementor-absolute img-flotante elementor-widget elementor-widget-image\" data-id=\"c509e81\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;,&quot;motion_fx_mouseTrack_effect&quot;:&quot;yes&quot;,&quot;motion_fx_mouseTrack_direction&quot;:&quot;negative&quot;,&quot;motion_fx_mouseTrack_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"446\" height=\"876\" src=\"https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2025\/05\/forma-izq.png\" class=\"attachment-full size-full wp-image-2423\" alt=\"\" srcset=\"https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2025\/05\/forma-izq.png 446w, https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2025\/05\/forma-izq-153x300.png 153w\" sizes=\"(max-width: 446px) 100vw, 446px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39852a3 elementor-widget__width-initial elementor-absolute img-flotante elementor-widget elementor-widget-image\" data-id=\"39852a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;,&quot;motion_fx_mouseTrack_effect&quot;:&quot;yes&quot;,&quot;motion_fx_mouseTrack_direction&quot;:&quot;negative&quot;,&quot;motion_fx_mouseTrack_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"446\" height=\"876\" src=\"https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2025\/05\/forma-dcha.png\" class=\"attachment-full size-full wp-image-2420\" alt=\"\" srcset=\"https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2025\/05\/forma-dcha.png 446w, https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2025\/05\/forma-dcha-153x300.png 153w\" sizes=\"(max-width: 446px) 100vw, 446px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8822fed e-flex e-con-boxed e-con e-child\" data-id=\"8822fed\" data-element_type=\"container\" data-e-type=\"container\" id=\"donde-estamos\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1acfb33 e-con-full e-flex e-con e-child\" data-id=\"1acfb33\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-d3222c2 e-con-full e-flex e-con e-child\" data-id=\"d3222c2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9c3c5aa elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"9c3c5aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">WHERE WE ARE<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f1a3977 elementor-widget elementor-widget-text-editor\" data-id=\"f1a3977\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Estadi Mallorca Son Moix, located at Cam\u00ed del Reis s\/n, is just a 15-minute drive from Palma city center and the airport. It is accessible by both public and private transport and offers over 2,500 parking spaces, including an exclusive area for buses, to facilitate your event. <\/p><p><strong>\u00b7 +2.500 PARKING SPOTS<\/strong><\/p><p><strong>\u00b7 1.4 KM AWAY FROM THE CITY CENTER<\/strong><\/p><p><strong>\u00b7 11KM AWAY FROM THE AIRPORT<\/strong><\/p><p><strong>\u00b7 ACCES THROUGH P9<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b69e67b e-con-full e-flex e-con e-child\" data-id=\"b69e67b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-e4961b4 e-con-full e-flex e-con e-child\" data-id=\"e4961b4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dd3e311 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"dd3e311\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Address<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e2332e elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"4e2332e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/maps.app.goo.gl\/9kqkW1z8cJK31nyh6\" target=\"_blank\">Cam\u00ed dels Reis, s\/n, 07011 Palma, Balearic Islands<\/a><\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-428797a e-con-full e-flex e-con e-child\" data-id=\"428797a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e6898bd elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"e6898bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_delay&quot;:800}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contact<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a1e985 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"8a1e985\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_delay&quot;:1000}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\"><a href=\"tel:971221221\" target=\"_blank\">971 22 12 21<\/a><\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5396707 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"5396707\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_delay&quot;:1200}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\"><a href=\"mailto:events@rcdmallorca.es\" target=\"_blank\">events@rcdmallorca.es<\/a><\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ce65ca4 e-con-full e-flex e-con e-child\" data-id=\"ce65ca4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cd983fc elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-html\" data-id=\"cd983fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d3074.653626381171!2d2.6274750772496476!3d39.58995610554239!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x1297928feaa22b35%3A0x3ddbee97efbcb063!2sEstadi%20de%20Son%20Moix!5e0!3m2!1ses!2ses!4v1730711770973!5m2!1ses!2ses\" width=\"600\" height=\"100%\" style=\"border:0; border-radius:8px;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29acc43 elementor-widget__width-inherit elementor-invisible elementor-widget elementor-widget-image\" data-id=\"29acc43\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:1400}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1410\" height=\"917\" src=\"https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2024\/11\/mapa-donde-estamos.webp\" class=\"attachment-full size-full wp-image-1104\" alt=\"\" srcset=\"https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2024\/11\/mapa-donde-estamos.webp 1410w, https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2024\/11\/mapa-donde-estamos-300x195.webp 300w, https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2024\/11\/mapa-donde-estamos-1024x666.webp 1024w, https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2024\/11\/mapa-donde-estamos-768x499.webp 768w\" sizes=\"(max-width: 1410px) 100vw, 1410px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cf228e8 e-flex e-con-boxed e-con e-parent\" data-id=\"cf228e8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>UPCOMING EVENTS VIEW ALL EVENTS Football as you&#8217;ve never played it before Discover a unique space where football is experienced in a whole new way. Over 1,500 m\u00b2 of interactive experiences, games, and technology in a covered environment designed for all audiences. A place to enjoy, compete, learn, and share the passion for sport in [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-4576","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.6 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mallorca Son Moix Stadium<\/title>\n<meta name=\"description\" content=\"Estadi Mallorca Son Moix Official Website\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/estadimallorcasonmoix.es\/en\/mallorca-son-moix-stadium\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mallorca Son Moix Stadium\" \/>\n<meta property=\"og:description\" content=\"Estadi Mallorca Son Moix Official Website\" \/>\n<meta property=\"og:url\" content=\"https:\/\/estadimallorcasonmoix.es\/en\/mallorca-son-moix-stadium\/\" \/>\n<meta property=\"og:site_name\" content=\"estadimallorcasonmoix.es\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-06T07:39:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2024\/11\/OG-1024x576.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/estadimallorcasonmoix.es\\\/en\\\/mallorca-son-moix-stadium\\\/\",\"url\":\"https:\\\/\\\/estadimallorcasonmoix.es\\\/en\\\/mallorca-son-moix-stadium\\\/\",\"name\":\"Mallorca Son Moix Stadium\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/estadimallorcasonmoix.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/estadimallorcasonmoix.es\\\/en\\\/mallorca-son-moix-stadium\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/estadimallorcasonmoix.es\\\/en\\\/mallorca-son-moix-stadium\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/estadimallorcasonmoix.es\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/FOOTBALLPARK-COBRANDING-RGB_HORIZONTAL-ROJO-CONESCUDO-1-300x58.png\",\"datePublished\":\"2026-04-27T13:57:09+00:00\",\"dateModified\":\"2026-07-06T07:39:28+00:00\",\"description\":\"Estadi Mallorca Son Moix Official Website\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/estadimallorcasonmoix.es\\\/en\\\/mallorca-son-moix-stadium\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/estadimallorcasonmoix.es\\\/en\\\/mallorca-son-moix-stadium\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/estadimallorcasonmoix.es\\\/en\\\/mallorca-son-moix-stadium\\\/#primaryimage\",\"url\":\"https:\\\/\\\/estadimallorcasonmoix.es\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/FOOTBALLPARK-COBRANDING-RGB_HORIZONTAL-ROJO-CONESCUDO-1-300x58.png\",\"contentUrl\":\"https:\\\/\\\/estadimallorcasonmoix.es\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/FOOTBALLPARK-COBRANDING-RGB_HORIZONTAL-ROJO-CONESCUDO-1-300x58.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/estadimallorcasonmoix.es\\\/en\\\/mallorca-son-moix-stadium\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/estadimallorcasonmoix.es\\\/en\\\/mallorca-son-moix-stadium\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mallorca Son Moix Stadium\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/estadimallorcasonmoix.es\\\/#website\",\"url\":\"https:\\\/\\\/estadimallorcasonmoix.es\\\/\",\"name\":\"estadimallorcasonmoix.es\",\"description\":\"Estadi Mallorca Son Moix Official Website\",\"publisher\":{\"@id\":\"https:\\\/\\\/estadimallorcasonmoix.es\\\/#organization\"},\"alternateName\":\"Estadi Mallorca Son Moix\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/estadimallorcasonmoix.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/estadimallorcasonmoix.es\\\/#organization\",\"name\":\"RCD Mallorca\",\"alternateName\":\"RCD Mallorca\",\"url\":\"https:\\\/\\\/estadimallorcasonmoix.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/estadimallorcasonmoix.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/estadimallorcasonmoix.es\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Logo-Son-Moix.png\",\"contentUrl\":\"https:\\\/\\\/estadimallorcasonmoix.es\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Logo-Son-Moix.png\",\"width\":490,\"height\":284,\"caption\":\"RCD Mallorca\"},\"image\":{\"@id\":\"https:\\\/\\\/estadimallorcasonmoix.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mallorca Son Moix Stadium","description":"Estadi Mallorca Son Moix Official Website","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/estadimallorcasonmoix.es\/en\/mallorca-son-moix-stadium\/","og_locale":"en_US","og_type":"article","og_title":"Mallorca Son Moix Stadium","og_description":"Estadi Mallorca Son Moix Official Website","og_url":"https:\/\/estadimallorcasonmoix.es\/en\/mallorca-son-moix-stadium\/","og_site_name":"estadimallorcasonmoix.es","article_modified_time":"2026-07-06T07:39:28+00:00","og_image":[{"url":"https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2024\/11\/OG-1024x576.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/estadimallorcasonmoix.es\/en\/mallorca-son-moix-stadium\/","url":"https:\/\/estadimallorcasonmoix.es\/en\/mallorca-son-moix-stadium\/","name":"Mallorca Son Moix Stadium","isPartOf":{"@id":"https:\/\/estadimallorcasonmoix.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/estadimallorcasonmoix.es\/en\/mallorca-son-moix-stadium\/#primaryimage"},"image":{"@id":"https:\/\/estadimallorcasonmoix.es\/en\/mallorca-son-moix-stadium\/#primaryimage"},"thumbnailUrl":"https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2026\/03\/FOOTBALLPARK-COBRANDING-RGB_HORIZONTAL-ROJO-CONESCUDO-1-300x58.png","datePublished":"2026-04-27T13:57:09+00:00","dateModified":"2026-07-06T07:39:28+00:00","description":"Estadi Mallorca Son Moix Official Website","breadcrumb":{"@id":"https:\/\/estadimallorcasonmoix.es\/en\/mallorca-son-moix-stadium\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/estadimallorcasonmoix.es\/en\/mallorca-son-moix-stadium\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/estadimallorcasonmoix.es\/en\/mallorca-son-moix-stadium\/#primaryimage","url":"https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2026\/03\/FOOTBALLPARK-COBRANDING-RGB_HORIZONTAL-ROJO-CONESCUDO-1-300x58.png","contentUrl":"https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2026\/03\/FOOTBALLPARK-COBRANDING-RGB_HORIZONTAL-ROJO-CONESCUDO-1-300x58.png"},{"@type":"BreadcrumbList","@id":"https:\/\/estadimallorcasonmoix.es\/en\/mallorca-son-moix-stadium\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/estadimallorcasonmoix.es\/en\/mallorca-son-moix-stadium\/"},{"@type":"ListItem","position":2,"name":"Mallorca Son Moix Stadium"}]},{"@type":"WebSite","@id":"https:\/\/estadimallorcasonmoix.es\/#website","url":"https:\/\/estadimallorcasonmoix.es\/","name":"estadimallorcasonmoix.es","description":"Estadi Mallorca Son Moix Official Website","publisher":{"@id":"https:\/\/estadimallorcasonmoix.es\/#organization"},"alternateName":"Estadi Mallorca Son Moix","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/estadimallorcasonmoix.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/estadimallorcasonmoix.es\/#organization","name":"RCD Mallorca","alternateName":"RCD Mallorca","url":"https:\/\/estadimallorcasonmoix.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/estadimallorcasonmoix.es\/#\/schema\/logo\/image\/","url":"https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2024\/10\/Logo-Son-Moix.png","contentUrl":"https:\/\/estadimallorcasonmoix.es\/wp-content\/uploads\/2024\/10\/Logo-Son-Moix.png","width":490,"height":284,"caption":"RCD Mallorca"},"image":{"@id":"https:\/\/estadimallorcasonmoix.es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/estadimallorcasonmoix.es\/en\/wp-json\/wp\/v2\/pages\/4576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/estadimallorcasonmoix.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/estadimallorcasonmoix.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/estadimallorcasonmoix.es\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/estadimallorcasonmoix.es\/en\/wp-json\/wp\/v2\/comments?post=4576"}],"version-history":[{"count":4,"href":"https:\/\/estadimallorcasonmoix.es\/en\/wp-json\/wp\/v2\/pages\/4576\/revisions"}],"predecessor-version":[{"id":5134,"href":"https:\/\/estadimallorcasonmoix.es\/en\/wp-json\/wp\/v2\/pages\/4576\/revisions\/5134"}],"wp:attachment":[{"href":"https:\/\/estadimallorcasonmoix.es\/en\/wp-json\/wp\/v2\/media?parent=4576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}